{"id":95842,"date":"2013-07-08T06:11:37","date_gmt":"2013-07-08T04:11:37","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=95842"},"modified":"2013-07-08T06:11:37","modified_gmt":"2013-07-08T04:11:37","slug":"revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/","title":{"rendered":"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/07\/espiritualidad7.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-95843\" alt=\"\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/07\/espiritualidad7-300x275.jpg?resize=245%2C224\" width=\"245\" height=\"224\" \/><\/a>A lo largo de este a\u00f1o jubilar por la celebraci\u00f3n de los 350 a\u00f1os de\u00a0 la muerte de San Vicente y de Santa Luisa, todos los vicencianos<\/p>\n<p>estamos sintiendo, fuertemente, una llamada a una profunda renova\u00adci\u00f3n para ser fieles <em>a la gracia de los or\u00edgenes. <\/em>A lo largo de este a\u00f1o, hemos mirado nuestro pasado y nuestro presente. Y, una vez m\u00e1s, nos hemos dado cuenta de que la garant\u00eda de tal renovaci\u00f3n est\u00e1 en la fi\u00addelidad a la herencia recibida y en la b\u00fasqueda de la configuraci\u00f3n cada vez m\u00e1s plena con el Se\u00f1or. S\u00f3lo \u00c9l puede mantener constante la frescura y la autenticidad de los or\u00edgenes y, al mismo tiempo, infundir el coraje de la audacia y de la creatividad para responder a los signos de los tiempos.<\/p>\n<p>Son muchos los estudios de las distintas Congregaciones e Institu\u00adtos en esta l\u00ednea de actualizar el carisma recibido de los fundadores. Tambi\u00e9n entre nosotros. Pero, como dice un experto en vicencianismo, \u00aba quien intente hoy revivir el esp\u00edritu vicenciano original no le basta\u00adr\u00eda con releer la letra para tratar de revivirla; tendr\u00eda que tratar de ex\u00adtraer el esp\u00edritu; es decir, tratar de extraer de la experiencia original los elementos fundamentales que, despu\u00e9s de todos los cambios y revolu\u00adciones que se han dado en la sociedad y en la Iglesia, puedan seguir siendo significativos para que nuestra experiencia espiritual-cristiana pueda seguir consider\u00e1ndonos hoy leg\u00edtimamente como vicencianos\u00bb.<\/p>\n<p>Otro estudioso de San Vicente nos dice \u00abque ning\u00fan tiempo pre\u00adsente es definitivo y nadie entre nosotros es tan sagaz que se invente f\u00f3rmulas valederas para todas las gentes de la tierra y hasta el fin del mundo. Si es cierto que las instituciones corren el peligro del desgas\u00adte espiritual y apost\u00f3lico, ah\u00ed tiene la recurrencia a las fuentes del evan\u00adgelio y de la inspiraci\u00f3n carism\u00e1tica fundacional el remedio para su sa\u00adlud completa\u00bb.<\/p>\n<p>Despu\u00e9s de trescientos cincuenta a\u00f1os de carisma vicenciano, es muy oportuno mirar hacia el futuro asentando bien las bases de la nue\u00adva presencia que tenemos que llevar a cabo, hoy, como Familia Vicen\u00adciana. Por supuesto, no soy tan ingenuo como para pensar que voy a re\u00adsolver esa preocupaci\u00f3n. Y tampoco soy tan atrevido como para pensar que voy a establecer unas bases definitivas e infalibles. No es muy di\u00adficil hacer una lista de propuestas, m\u00e1s o menos generales, para actua\u00adlizar el carisma vicenciano. Lo dificil es bajar a propuestas muy con\u00adcretas.<\/p>\n<p>Ahora bien, siempre hay ciertos elementos que nunca podremos de\u00adjar de lado, que un vicenciano jam\u00e1s podr\u00e1 olvidar en su ser y actuar, si quiere manifestarse como tal. En este escrito quiero enunciar breve\u00admente algunos puntos que, pienso, nos pueden ayudar, hoy, a actuali\u00adzar y revitalizar el carisma recibido de San Vicente hace 350 a\u00f1os: el carisma de la caridad y la misi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>I. FIDELIDAD CREATIVA Y GOZOSA<\/strong><\/p>\n<p>Estamos llamados a testimoniar una gran fidelidad en estos momen\u00adtos delicados y duros, no exentos de tensiones y de pruebas, pero llenos, tambi\u00e9n, de grandes posibilidades. Todo ello es necesario, si queremos re\u00adproducir con audacia y creatividad el carisma vicenciano. S\u00f3lo reencon\u00adt rando <em>el primer amor <\/em>seremos fuertes y audaces, pues s\u00f3lo ese amor pue\u00adde infundir valor y osad\u00eda, en tiempos como los nuestros.<\/p>\n<p>He ah\u00ed, entonces, la llamada m\u00e1s urgente que a todos los vicencia\u00adnos nos viene del Evangelio y de nuestra condici\u00f3n de <em>disc\u00edpulos y mi<\/em><em>sioneros: <\/em>una profunda conversi\u00f3n del coraz\u00f3n y una vuelta constante hacia el Se\u00f1or. No podemos olvidar que es Dios el que hace fecundo y f\u00e9rtil el terreno de la misi\u00f3n evangelizadora. Es El, y s\u00f3lo \u00c9l, quien hace crecer la semilla (cf. Mc 4,27). Caridad-misi\u00f3n es, ante todo, obra e la <em>fuerza de lo alto.<\/em><\/p>\n<p>\u00abAcu\u00e9rdese, padre, de que vivimos en Jesucristo por la muerte en esucristo, y que hemos de morir en Jesucristo por la vida de Jesucris\u00adto, y que nuestra vida tiene que estar oculta en Jesucristo y llena de Je\u00adsucristo, y que, para morir como Jesucristo, hay que vivir como Jesu\u00adcristo\u00bb<sup>3<\/sup>. Estas palabras de una carta de Vicente de Pa\u00fal al P. Portail, nos ponen en la pista de esta primera actitud vicenciana. Porque est\u00e1 meridianamente claro que el esp\u00edritu vicenciano tiene a Cristo como principio, como camino y como meta.<\/p>\n<p>En definitiva, si Cristo no impregna todo nuestro ser humano, cris\u00adtiano y vicenciano, todo lo que hagamos y vivamos no tendr\u00e1 ning\u00fan fundamento ni sentido. No podemos proyectar nuestra vida desde otras instancias, por piadosas que parezcan, sino desde Cristo.<\/p>\n<p>Y es necesario subrayar que el Cristo al que aman y siguen San Vi\u00adcente de Pa\u00fal y Santa Luisa de Marillac, y que nos dejan como legado, es el Cristo que evangeliza y sirve a los pobres. Ellos se fiaron absolu\u00adtamente de este Jesucristo con tanta confianza que no se dejan disua\u00addir por nada ni por nadie.<\/p>\n<p>Todos los vicencianos estamos llamados a acoger el compromiso de nacer de nuevo (cf. Jn 3,3) para acoger, personal e institucional\u00admente, el Evangelio de Jes\u00fas, el mismo que acogi\u00f3 y abraz\u00f3 Vicente de Pa\u00fal como estilo y forma de vida, sin ceder a la constante tentaci\u00f3n de domesticar sus exigencias m\u00e1s radicales para adaptarlas a un c\u00f3modo estilo de vivir.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2. MIRADA POSITIVA Y AGRADECIDA<\/strong><\/p>\n<p>Por todos y cada uno de los seguidores de San Vicente debemos dar gracias a Dios. Su vida y su trabajo son signos de bendici\u00f3n. No esta\u00admos orgullosos de lo que somos, sino agradecidos a los que han hecho posible todo lo bueno que ahora disfrutamos. No formamos una fami\u00adlia de perfectos, sino de mujeres y hombres que caminan hacia la ple\u00adnitud. Todos deber\u00edamos estar en esta direcci\u00f3n, pero, por desgracia, no es as\u00ed.<\/p>\n<p>Al echar una mirada positiva y agradecida a nuestro pasado y a nuestro presente, no tenemos que ocultar las sombras y las infideli\u00addades, el cansancio y las rutinas que a menudo han acompa\u00f1ado nues\u00adtro caminar a lo largo de estos 350 a\u00f1os de historia. No es de extra\u00ad\u00f1ar, entonces, que en esta familia, como en cualquier \u00e1rbol, encontre\u00admos hojas que languidecen y caen o ramas que se secan. Todo esto, a la hora de revitalizar el carisma, nos debe interpelar, nos tiene que ha\u00adcer vigilantes y nos debe ayudar para que no llegue a aplic\u00e1rsenos la palabra del Se\u00f1or: <em>\u00abOs di una tierra por la que no hab\u00edais sudado, ciudades que no hab\u00edais construido, y en las que ahora viv\u00eds; vi\u00f1edos <\/em>y <em>olivares que no hab\u00edais plantado, y de los que ahora com\u00e9is\u00bb <\/em>(Jos 24,13).<\/p>\n<p>Necesitamos una mirada de orfebres para apreciar, amar y dar ca\u00adlor a lo m\u00e1s diminuto de cada jornada, y una mirada larga de centine\u00adlas para ver el horizonte hacia el que nos dirigimos, pero que va ya dentro de lo peque\u00f1o. Hablamos de una mirada contemplativa que arriesga incluso en lo que aparece como p\u00e9rdida, que nos permite in\u00adtuir <sub>.<\/sub>juntos lo que ya es esa nueva vida que est\u00e1 brotando, aunque no lo notemos, y pide ser nombrada y acompa\u00f1ada. La mirada que nos nace caminar juntos y en la misma direcci\u00f3n, aunque nos equivoque- nos o tengamos que rectificar. La par\u00e1bola de la semilla nos recuerda que hemos de aprender a mirar ese dinamismo imparable que atravie\u00adsa todo lo que existe y lo encamina hacia la plenitud. El programa del cristiano, el programa de un vicenciano, es un \u00abcoraz\u00f3n que ve\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>3. ESPIRITUALIDAD PROPIA<\/strong><\/p>\n<p>Bernardo de Claraval sol\u00eda decir que, en materia de espiritualidad, cada uno debe \u00abbeber en su propio pozo\u00bb. <em>Y <\/em>del pozo vicenciano bro\u00adta un agua fresca que no se ha estancado ni se ha agotado con el paso del tiempo.<\/p>\n<p>En todas las \u00d3rdenes y Congregaciones han existido tentaciones de acudir a otras espiritualidades distintas de la suyas propias. Tambi\u00e9n ha podido ocurrir esto en nuestra Congregaci\u00f3n a lo largo de la historia.<\/p>\n<p>Sin embargo, es necesario insistir, una vez m\u00e1s, en que la clave de nuestro \u00abser\u00bb est\u00e1 en la espiritualidad propia, sustentada, desde San Vi\u00adcente, en lo que hemos llamado el \u00abCristo vicenciano\u00bb. Si la Familia Vicenciana quiere ser significativa, tiene que transparentar su existen\u00adcia con el sello peculiar de su propia espiritualidad. San Vicente nos di\u00adr\u00eda a los pa\u00fales que esa espiritualidad propia tiene que ser \u00abel alma de la Compa\u00f1\u00eda\u00bb.<\/p>\n<p>Y esa espiritualidad \u2014sintetizada en las cinco famosas virtudes\u2014 tie\u00adne que vivirse en unas coordenadas de \u00abojos abiertos\u00bb. Porque no se trata de una espiritualidad asc\u00e9tica o de privacidad espiritualista. Es una espiritualidad de encarnaci\u00f3n liberadora en el mundo de los pobres y desheredados, de \u00absacramentalidad del pobre\u00bb, de solidaridad sama\u00adritana, del principio-misericordia. Una espiritualidad misionera y apos\u00adt\u00f3lica. Una espiritualidad que se vive en la historia de cada d\u00eda.<\/p>\n<p>En la espiritualidad vicenciana todo debe estar referido a los pobres y todo debe desembocar en la liberaci\u00f3n integral de los pobres, nada tiene sentido ni raz\u00f3n sin los pobres y todo se hace cre\u00edble y certero desde los pobres, con los pobres, para los pobres y por los pobres.<\/p>\n<p>Para terminar este punto, me viene a la mente aquel cuentecillo ti\u00adtulado <em>Hacer beber al burro que no tiene sed. <\/em>\u00bfQu\u00e9 hay que hacer para que beba un burro que no tiene sed? Salvando las distancias, \u00bfqu\u00e9 ha\u00adcer para devolver la sed y el gusto por lo vicenciano a quien lo ha per\u00addido? \u00bfA bastonazos? El burro es m\u00e1s testarudo que nuestro bast\u00f3n. Adem\u00e1s, este m\u00e9todo no ha funcionado. \u00bfHacerle tragar sal? A\u00fan peor, por lo que tiene de tortura. \u00bfC\u00f3mo hacer beber, pues, a este burro res\u00adpetando su libertad? S\u00f3lo hay una respuesta: encontrar otro burro que tenga sed y que beba mucho delante de su cong\u00e9nere, con alegr\u00eda. Y esto no para darle buen ejemplo, sino ante todo porque tenga sed, por\u00adque de verdad tenga sed, simplemente sed, perpetuamente sed. Un d\u00eda, quiz\u00e1s el otro burro, lleno de envidia, se pregunte si no har\u00eda mejor me\u00adtiendo tambi\u00e9n \u00e9l su hocico en el cubo de agua fresca.<\/p>\n<p>Hoy hacen falta hombres y mujeres con sed de Dios, hacen falta mujeres y hombres dispuestos a meter el hocico en las aguas vicencia\u00adnas. A dar sana envidia a los dem\u00e1s, a contagiar ilusi\u00f3n y esperanza, a invitar a otros, a convocar savia nueva, a decir con convicci\u00f3n: \u00abvenid y ver\u00e9is\u00bb (cf. Jn 1,38-39).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>4. PASI\u00d3N POR LA EVANGELIZACI\u00d3N DE LOS POBRES<\/strong><\/p>\n<p>La misi\u00f3n evangelizadora no es para nosotros una actividad m\u00e1s, sino que es nuestra definici\u00f3n pues, de hecho, los vicencianos tenemos que ser misioneros en el coraz\u00f3n del mundo, con el coraz\u00f3n vuelto ha\u00adcia el Se\u00f1or.<\/p>\n<p>No voy a entrar en todo lo que encierra este enunciado. Voy a su\u00adbrayar solamente el primer t\u00e9rmino: \u00abapasionados\u00bb. Porque estamos hablando de actitudes fundamentales y la \u00abpasi\u00f3n\u00bb por la evangeliza\u00adci\u00f3n de los pobres tiene que ser algo innato en el \u00abser\u00bb de un vicen\u00adciano. Sin esta \u00abpasi\u00f3n\u00bb no puede haber ni presencia cre\u00edble ni signi\u00adficatividad alguna.<\/p>\n<p>Un apasionamiento que significa poner toda nuestra vida al servi\u00adcio de una causa que nos fascina. Nuestro ser, nuestras cualidades, nuestras fuerzas, nuestros recursos, nuestro tiempo, nuestra ilusi\u00f3n, nuestro gozo y nuestro sufrimiento al servicio de la evangelizaci\u00f3n de los pobres. Un apasionamiento que es una mezcla de celo e impulso, de aguij\u00f3n y convicci\u00f3n que nos hace exclamar como a San Pablo: <em>\u00ab\u00a1Ay de m\u00ed si no evangelizare!\u00bb <\/em>Es sentirlo como lo \u00fanico necesario, como nuestra \u00fanica raz\u00f3n de ser. Y, por eso, gozosos e identificados si lo estamos siendo, y frustrados y desidentificados si no lo somos.<\/p>\n<p>Vicente de Pa\u00fal nos transmite su <em>pasi\u00f3n <\/em>por evangelizar a los po\u00adbres (que es una dimensi\u00f3n del celo) cuando nos dice: <em>\u00abHay que acu\u00addir a las necesidades de los pobres como se acude cuando hay fuego, porque no socorrer es matar\u00bb; <\/em>o <em>\u00absi la caridad es el fuego, el celo es <\/em><em>la llama\u00bb; o \u00absi pregunt\u00e1semos a Cristo \u00aba qu\u00e9 viniste al mundo\u00bb, nos responder\u00eda: \u00aba evangelizar a los pobres\u00bb, si volvi\u00e9semos a pregun\u00adtarle \u00aba qu\u00e9 viniste al mundo\u00bb, otra vez nos responder\u00eda: \u00aba evangeli\u00ad<\/em><em>za<\/em><strong><em>r <\/em><\/strong><em>a los pobres\u00bb\u00bb.<\/em><em><\/em><\/p>\n<p><em>El <\/em><em>celo <\/em>o <em>apasionamiento <\/em>por la evangelizaci\u00f3n de los pobres es el fruto o la consecuencia necesaria de una experiencia personal y profunda tutela Cristo, de haberle aceptado cada uno de nosotros como \u00abbue\u00adna noticia\u00bb, como salvaci\u00f3n, y, desde esa experiencia, sentir la necesi\u00addad de que otros la compartan.<\/p>\n<p>El pobre es lugar teol\u00f3gico del encuentro con Dios. Y como todo encuentro con el Salvador salva, as\u00ed cuando llevamos la Buena Noticia a los pobres, son ellos quienes nos dan la Buena Noticia, y al pretender evangelizarlos, son ellos los que nos evangelizar\u00e1. Dios ha deposi\u00adtado la esperanza en el coraz\u00f3n de los pobres. Nuestra tarea ser\u00e1 servir las esperanzas de los pobres y sus posibilidades. Es necesario aprender a descubrir esta esperanza a trav\u00e9s de sus expectativas. La cuesti\u00f3n est\u00e1 en c\u00f3mo servirla y darla a conocer a los mismos pobres, quienes pue\u00adden ignorarla o rechazarla.<\/p>\n<p>Somos bien conscientes de que la misi\u00f3n que nos espera es ardua. El terreno en el que hemos de sembrar la semilla del Evangelio, el co\u00adraz\u00f3n del hombre, est\u00e1 lleno de obst\u00e1culos, como nos recuerda la pa\u00adr\u00e1bola del sembrador (cf. Mt 13,3). Pero somos igualmente conscien\u00adtes de que la fuerza germinativa de la semilla de la Palabra de Dios no ha disminuido. Si hoy las misiones populares no sirven, inventemos otros m\u00e9todos, otros nuevos estilos de evangelizar. Vivimos en un mo\u00admento de crisis, pero, a su vez, lleno de grandes posibilidades.<\/p>\n<p>Si no vivimos ese celo apasionado, tendremos que preguntarnos, con total sinceridad, qu\u00e9 experiencia de Cristo tenemos los vicencianos, c\u00f3mo est\u00e1 el fuego de nuestra caridad que ya no produce esa llama.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>5. NUEVA \u00abIMAGINACI\u00d3N DE LA CARIDAD\u00bb<\/strong><\/p>\n<p>La caridad, nombre de Dios y amor al pr\u00f3jimo, es siempre un cri\u00adterio de discernimiento de la calidad de nuestra acci\u00f3n evangelizadora. La acci\u00f3n evangelizadora tiene hoy un criterio de credibilidad en el ejercicio de la caridad en el nombre del Se\u00f1or. El amor y su expresi\u00f3n sociocaritativa es siempre un signo indicativo de la vitalidad de nues\u00adtra acci\u00f3n social.<\/p>\n<p>El papa Juan Pablo II nos dec\u00eda que la vivencia del amor y la pr\u00e1c\u00adtica de la caridad \u00abhoy requieren mayor creatividad\u00bb<sup>6<\/sup>. Para conocer las nuevas formas de pobreza, para escuchar las voces de los pobres y los d\u00e9biles, de los que nadie se acuerda, para actuar con m\u00e9todos y formas nuevas, rigurosas y eficaces. \u00abLa presencia de obras de caridad, por en\u00adcima de lo normal, tiene que hacer hoy en el proceso de evangelizaci\u00f3n el papel semejante al que hac\u00edan los milagros de Jes\u00fas en el conjunto de su misi\u00f3n evangelizadora\u00bb.<\/p>\n<p>Toda la Familia Vicenciana tendr\u00edamos que convertir en \u00abprofec\u00eda de futuro\u00bb nuestros ministerios de evangelizaci\u00f3n y trabajos sociales. Y siempre alentados por un quehacer comunitario. El hombre de hoy est\u00e1 deseoso de autenticidad y de gestos concretos, siente m\u00e1s fuerte\u00admente la exigencia de ver que la de escuchar, y verificar en lo vivido la autenticidad de las cosas escuchadas. Hoy se aprecia m\u00e1s a los tes\u00adtigos que a los maestros. Nosotros debemos ser las dos cosas: \u00abmaes\u00adtros\u00bb que educamos en la caridad a los seglares, acompa\u00f1ando el vo\u00adluntariado, y, tambi\u00e9n, \u00abtestigos\u00bb implicados en proyectos concretos de atenci\u00f3n y servicio a los m\u00e1s pobres.<\/p>\n<p>Y, juntamente con la creatividad, la organizaci\u00f3n coordinada, siem\u00adpre en las entra\u00f1as mismas de la caridad vicenciana. Y al lado de la or\u00adganizaci\u00f3n siempre ha caminado la preparaci\u00f3n adecuada, la forma\u00adci\u00f3n continua y actualizada. Ojala fu\u00e9semos capaces los vicencianos (le suscitar grupos y abrir foros para estudiar y profundizar las causas que generan las situaciones de miseria y marginaci\u00f3n. El Documento de consulta para la Asamblea General de la Congregaci\u00f3n de la Misi\u00f3n, que se ha celebrado el pasado mes de julio, en Par\u00eds, habla de la posi\u00adbilidad de establecer un \u00abObservatorio de la caridad\u00bb que exprese in\u00adternacionalmente el punto de vista vicenciano actual bajo la mirada y el m\u00e9todo de San Vicente. Ser\u00eda de desear que propuestas de este tipo lleguen a una feliz concreci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>6. MISI\u00d3N COMPARTIDA<\/strong><\/p>\n<p>Federico Ozanam, fiel int\u00e9rprete de San Vicente, dijo en una oca\u00adsi\u00f3n: <em>\u00abMe gustar\u00eda abrazar el mundo entero en una red de caridad\u00bb. Y <\/em>en el Congreso Nacional de la Familia Vicenciana, celebrado el pasa\u00addo mes de marzo en Madrid, nos dec\u00eda uno de los conferenciantes: \u00abLlevamos muchos a\u00f1os, desde el Concilio Vaticano II, hablando de la participaci\u00f3n, de la colaboraci\u00f3n, de la implicaci\u00f3n de los laicos en la misi\u00f3n de la Iglesia. Y llevamos tambi\u00e9n muchos a\u00f1os hablando de la misi\u00f3n de la Familia Vicenciana. Es la hora de tomarse en serio la mi\u00ads\u00bbcompartida\u00bb.<\/p>\n<p>Es verdad. Nos falta pasar a la realidad, es decir, a trabajar m\u00e1s y mejor en equipo, a gestionar proyectos en com\u00fan, de igual a igual. A m\u00ed me gusta recordar a aquel autor que dec\u00eda: \u00abEl reino de Dios se pa\u00adrece a una sinfon\u00eda que est\u00e1 compuesta por muchas notas diferentes. Cada nota es necesaria y tiene su momento, intensidad y duraci\u00f3n. Si suena en exceso, quita vida a las dem\u00e1s. Si se inhibe por temor, la sin\u00adfon\u00eda entera sufre. Cada nota recibe su valor del conjunto armonioso que la precede y del que la sigue. Todas las notas bien orquestadas crean y son la belleza de una sinfon\u00eda original\u00bb.<\/p>\n<p>La \u00abmisi\u00f3n compartida\u00bb por parte de todas las ramas del \u00e1rbol vi\u00adcenciano exige conocimiento mutuo, colaboraci\u00f3n sin prejuicios ni protagonismos, apertura sincera, cambio de esquemas, comuni\u00f3n leal, formaci\u00f3n conjunta, fortalecimiento del carisma vicenciano, uni\u00f3n sin confusi\u00f3n. Podemos decir que todos los esfuerzos que se est\u00e1n reali\u00adzando en la actualidad para llevar a cabo la misi\u00f3n compartida respon\u00adden a la herencia que hemos recibido de Vicente de Pa\u00fal y de Luisa de Marillac. Juan Pablo II nos alent\u00f3 en este camino un 22 de agosto de 1997, en la Catedral de Notre Dame de Par\u00eds, a toda la Familia Vicen\u00adciana, reunida con ocasi\u00f3n de la Beatificaci\u00f3n de Federico Ozanam: \u00abQueridos disc\u00edpulos de San Vicente de Pa\u00fal, \u00a1os encarezco a poner en com\u00fan vuestras fuerzas, para que, como deseaba aquel que os inspira, los pobres sean siempre m\u00e1s amados y mejor servidos!\u00bb<\/p>\n<p>Participar del mismo carisma requiere estrechar la comuni\u00f3n en el conocimiento, la relaci\u00f3n fraternal, la fe compartida y en la gesti\u00f3n de proyectos concretos a favor de los pobres. Qu\u00e9 importante ser\u00e1 seguir potenciando la Coordinadora Nacional de la Familia Vicenciana, as\u00ed como las Coordinadoras provinciales o zonales. Y creo que ha llegado el momento de reconfigurarnos de otra manera. Todo esto con una in\u00adtenci\u00f3n: revitalizar el carisma.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>7. MISERICORDIA FRENTE A LA INSENSIBILIDAD <\/strong><strong>SOCIAL<\/strong><\/p>\n<p>Dios escucha hoy el grito de las gentes sedientas de alegr\u00eda, de paz, de justicia, de amor; necesitadas de gozo y de perd\u00f3n; abandonadas como en pasadas generaciones; escucha a grandes espacios de la humnanidad afectados por la desolaci\u00f3n y la miseria, por la soledad y la violencia, por el maltrato y la injuria despiadada; el subdesarrollo se extiende a gran parte de la tierra; la tristeza del emigrante se encuen\u00adtra bien cerca de nosotros&#8230; \u00bfCu\u00e1l es la mirada de Dios sobre nuestro mundo? \u00bfC\u00f3mo reaccionan nuestras entra\u00f1as de misericordia ante el valle oscuro por el que transitamos?<\/p>\n<p>Jes\u00fas recuerda que la verdadera felicidad est\u00e1 en el ejercicio de la misericordia: <em>felices los misericordiosos porque ellos hallar\u00e1n miseri\u00ad<\/em><em>cordia (Mt 5,7) y <\/em>Pablo exhorta a los cristianos de Colosas: <em>revest\u00edos <\/em><em>de entra\u00f1as de misericordia, de agrado, humildad, sencillez, toleran\u00adcia, conllevaos mutuamente y perdonaos <\/em>(Col 3,12-13).<\/p>\n<p>Si queremos revitalizar, es decir, dar vida al carisma recibido de San Vicente no podemos olvidar esas entra\u00f1as misericordiosas que le caracterizaron siempre. Enuncio ahora algunas actitudes que me pa\u00adrece que nos pueden ayudar a los vicencianos a presentar, hoy, un ros\u00adtro compasivo y misericordioso a los hombres y mujeres de nuestro mundo:<\/p>\n<ol>\n<li>Frente a los criterios habituales del mundo: <em>ruptura <\/em>por parte de aquellos que sin ser inicialmente pobres optan por serlo.<\/li>\n<li>Frente a la divinizaci\u00f3n de la riqueza, la comodidad, la seguri\u00addad: <em>encarnaci\u00f3n, <\/em>entrar en el mundo del pobre y asumirlo como propio.<\/li>\n<li>Frente a la indiferencia y a la pasividad desesperanzada: <em>com\u00adpromiso <\/em>con la <em>liberaci\u00f3n del pobre, <\/em>defensa activa de sus dere\u00adchos y rechazo de toda injusticia y marginaci\u00f3n.<\/li>\n<li>Frente a la idolatr\u00eda del bienestar: <em>austeridad. <\/em>Vivir la pobreza evang\u00e9lica para ser libres frente a las cosas y poder optar por el pobre. Estar disponibles para estar al lado de los que sufren y es\u00adcuchar su dolor, transformar nuestro coraz\u00f3n y descubrir la Vida.<\/li>\n<li>Frente al desarrollo inhumano: <em>defensa de la persona. <\/em>La <em>digni\u00addad <\/em>del ser humano por encima de su utilidad o su eficacia.<\/li>\n<li>Frente a la cultura individualista: <em>solidaridad. <\/em>Crear otra cultu\u00adra, otra sociedad, cambiar las estructuras injustas que generan la pobreza y la marginaci\u00f3n, construir la nueva humanidad, y no desde la filantrop\u00eda sino desde el Evangelio, optando por un compromiso de vida y no por actuaciones pasajeras que tran\u00adquilicen nuestras conciencias, comprometer la persona entera en el servicio a los que sufren. El cambio sist\u00e9mico nos puede ofre\u00adcer un cauce apropiado para actuar hoy como verdaderos vicen\u00adcianos.<\/li>\n<li>Frente a la insensibilidad social: <em>misericordia. <\/em>Ofrecer amistad, escucha, cari\u00f1o, comprensi\u00f3n, ternura, no somos funcionarios del Evangelio que tienen que cumplir una ley o un horario, sino testigos de un Amor que nos roba el coraz\u00f3n y que nos impulsa a Amar como hemos sido amados.<\/li>\n<li>Frente a los \u00eddolos de este mundo: los valores del <em>Reino, <\/em>frente al tener, el <em>compartir, <\/em>frente al valer y al sobresalir por encima de los dem\u00e1s, la <em>fraternidad <\/em>que nos hace uno; y frente al poder, el <em>servicio.<\/em><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>8. CONFIANZA EN EL ESP\u00cdRITU EN TIEMPOS DIF\u00cdCILES<\/strong><\/p>\n<p>Estamos llamados a vivir el presente y el futuro como tiempo del Esp\u00edritu. Continuamente nos tenemos que preguntar: \u00bfqu\u00e9 hemos de hacer, hermanos? (cf. Hch 2,37) De San Vicente surgi\u00f3 el consejo de preguntarse qu\u00e9 es lo que nuestro Se\u00f1or har\u00eda en una circunstancia de\u00adterminada y ante un problema concreto para conformar nuestra con\u00adducta al comportamiento de nuestro Se\u00f1or.<\/p>\n<p>El momento que nos ha tocado vivir es delicado y decisivo. Pero hemos de ser bien conscientes de que este es el tiempo de Dios y, en cuanto tal, revela nuevas oportunidades, purifica, despierta potenciali\u00addades, desvela signos de futuro y de resurrecci\u00f3n. Se hace necesario entrar en una constante actitud de discernimiento, examin\u00e1ndolo todo, para quedarnos con lo bueno (cf. 1 Ts 5,21). De ah\u00ed, la importancia de los encuentros y distintos foros vicencianos. El reciente Congreso Na\u00adcional de la Familia Vicenciana, celebrado en el mes de marzo en Ma\u00addrid, ha sido una verdadera gracia para todos nosotros. Y cu\u00e1nto bien har\u00eda un Centro de Formaci\u00f3n para toda la Familia Vicenciana a nivel nacional.<\/p>\n<p>Hace falta abordar el proceso con el Esp\u00edritu del Cuerpo universal: todos responsables, todos buscando el bien de la Congregaci\u00f3n, de la Compa\u00f1\u00eda, de las distintas Asociaciones. Todos en la misma direcci\u00f3n para que se avive el carisma, para que contin\u00faen la misi\u00f3n, para que se revitalice la vida evang\u00e9lica. Como actitud de base, hemos de creer en el proyecto vicenciano y en la capacidad de cada uno de los grupos- asociaciones. Y, siempre, teniendo muy presente que \u00abquien gobierna el mundo es el Se\u00f1or, no nosotros. Nosotros le ofrecemos nuestro ser\u00advicio en lo que podemos y hasta que \u00e9l nos de fuerzas\u00bb.<\/p>\n<p>Junto a \u00e9sta, otra actitud de discernimiento y elecci\u00f3n: Dios habla en la historia. Hoy nos sigue hablando. Necesitamos estar atentos para des\u00adcubrir los signos de los tiempos. El mismo Jesucristo nos recuerda, de una y mil maneras: \u00abOs lo aseguro: cada vez que lo hicisteis con un her\u00admano m\u00edo, de esos m\u00e1s humildes, lo hicisteis conmigo\u00bb (Mt 25,35). Y haci\u00e9ndose presente, en medio de nosotros, nos repite: \u00abSabed que yo estoy con vosotros, todos los d\u00edas, hasta el fin del mundo\u00bb (Mt 28,20).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CONCLUSI\u00d3N<\/strong><\/p>\n<p>He intentado aproximarme a lo que me parece fundamental, en el presente y en el futuro, para cimentar bien nuestra presencia significativa. Comprendo que es s\u00f3lo un esbozo. Pero sirva lo dicho como ho\u00admenaje a tantos Pa\u00fales, Hijas de la Caridad y seglares de la amplia Familia Vicenciana, muchos de ellos an\u00f3nimos, que dejaron su huella santa y verdaderamente evangelizadora a lo largo y ancho de estos tres\u00adcientos cincuenta a\u00f1os. Y que nos han legado una herencia que no po\u00addemos ni debemos dilapidar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A lo largo de este a\u00f1o jubilar por la celebraci\u00f3n de los 350 a\u00f1os de\u00a0 la muerte de San Vicente y de Santa Luisa, todos los vicencianos estamos sintiendo, fuertemente, una llamada a una profunda &#8230; <a href=\"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":95843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[176,127],"class_list":["post-95842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","tag-misiones-populares","tag-portail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"A lo largo de este a\u00f1o jubilar por la celebraci\u00f3n de los 350 a\u00f1os de\u00a0 la muerte de San Vicente y de Santa Luisa, todos los vicencianos estamos sintiendo, fuertemente, una llamada a una profunda ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-08T04:11:37+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s\",\"datePublished\":\"2013-07-08T04:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/\"},\"wordCount\":4410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Misiones Populares\",\"Portail\"],\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/\",\"name\":\"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2013-07-08T04:11:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/","og_locale":"es_ES","og_type":"article","og_title":"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s - Somos Vicencianos","og_description":"A lo largo de este a\u00f1o jubilar por la celebraci\u00f3n de los 350 a\u00f1os de\u00a0 la muerte de San Vicente y de Santa Luisa, todos los vicencianos estamos sintiendo, fuertemente, una llamada a una profunda ... Read More","og_url":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2013-07-08T04:11:37+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s","datePublished":"2013-07-08T04:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/"},"wordCount":4410,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#primaryimage"},"thumbnailUrl":"","keywords":["Misiones Populares","Portail"],"articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/","url":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/","name":"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#primaryimage"},"thumbnailUrl":"","datePublished":"2013-07-08T04:11:37+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/revitalizar-el-carisma-de-san-vicente-trescientos-cincuenta-anos-despues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Revitalizar el carisma de San Vicente, trescientos cincuenta a\u00f1os despu\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-oVQ","jetpack-related-posts":[{"id":122918,"url":"https:\/\/vincentians.com\/es\/animacion-de-la-formacion\/","url_meta":{"origin":95842,"position":0},"title":"Animaci\u00f3n de la formaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/09\/2022","format":false,"excerpt":"1. Introducci\u00f3n Cuando se me encomend\u00f3 presentar esta Comunicaci\u00f3n se me dijo que lo hiciera desde mi experiencia pastoral en el campo de la Familia Vicenciana. Lo voy a intentar. Quiero empezar afir\u00admando que considero una gracia muy grande el haber podido trabajar como Consiliario o Asesor o simplemente como\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/formacion_permanente.jpg?fit=303%2C303&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":131132,"url":"https:\/\/vincentians.com\/es\/fieles-a-san-vicente\/","url_meta":{"origin":95842,"position":1},"title":"Fieles a San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/08\/2014","format":false,"excerpt":"\"El carisma mismo de los Fundadores se revela como una experiencia del Esp\u00edritu (EN 11), transmitida a los propios disc\u00edpulos para ser por ellos vivida, custodiada, profundizada y desarrollada constantemente en sinton\u00eda con el Cuerpo de Cristo en crecimiento perenne\". (MR 11). \"El fin de la Congregaci\u00f3n de la Misi\u00f3n\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"espiritualidad","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/espiritualidad.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":116383,"url":"https:\/\/vincentians.com\/es\/bibliografia-vicenciana-1960-1970-en-torno-a-la-espiritualidad-de-san-vicente\/","url_meta":{"origin":95842,"position":2},"title":"Bibliograf\u00eda Vicenciana 1960-1970 en torno a la espiritualidad de San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2021","format":false,"excerpt":"Lo que antes se llamaba Asc\u00e9tica y M\u00edstica, hoy se llama com\u00fanmen\u00adte Espiritualidad. Es una palabra tra\u00edda de Francia, como tantas otras, que tambi\u00e9n han hecho fortuna, m\u00e1s por moda que por convencimiento. As\u00ed se bautizan los tratados de Historia, desde Pourrat (1926) hasta Bouyer-Vandenbroucke (1963). El recomendar tan insistentemente\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":399977,"url":"https:\/\/vincentians.com\/es\/espiritu-vicenciano-e-identidad\/","url_meta":{"origin":95842,"position":3},"title":"Esp\u00edritu vicenciano e identidad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/09\/2016","format":false,"excerpt":"Introducci\u00f3n Al comenzar esta reflexi\u00f3n viene a mi mente la memoria de un he\u00adcho notorio en mi vida: la expedici\u00f3n de mi carnet de identidad. Ten\u00eda 16 a\u00f1os. Mi estatura era casi la actual. Los rasgos de mi personalidad, tipo y aspecto exterior estaban ya bastante perfilados... La mayor\u00eda de\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":116979,"url":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-y-renovacion-conciliar\/","url_meta":{"origin":95842,"position":4},"title":"Espiritualidad vicenciana y renovaci\u00f3n conciliar","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/03\/2015","format":false,"excerpt":"En la Iglesia posconciliar se necesita un estudio s\u00f3lido y diverso de la espiritualidad cristiana b\u00e1sica y de las \"espiritualidades\" que han aplicado la Espiritualidad evang\u00e9lica a distintas situa\u00adciones hist\u00f3ricas y a familias religiosas y apost\u00f3licas, para reali\u00adzar la \"adecuada renovaci\u00f3n\" de estas espiritualidades a la au\u00adt\u00e9ntica espiritualidad Cristoc\u00e9ntrica y\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"concilio1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/concilio1-300x113.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25596,"url":"https:\/\/vincentians.com\/es\/la-familia-vicenciana-una-renovacion-incesante\/","url_meta":{"origin":95842,"position":5},"title":"La familia vicenciana, una renovaci\u00f3n incesante","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/03\/2015","format":false,"excerpt":"El primer problema que surge al intentar describir, por brevemente que sea, a la familia vicenciana es la adecuada delimitaci\u00f3n del objeto de ese estudio. \u00bfQu\u00e9 se entiende por familia vicenciana? \u00bfQui\u00e9nes son sus miembros? Esas preguntas pueden ser respondidas en un sentido amplio y en un sentido restringido. El\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"renovacion","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/renovacion-300x191.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/95842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=95842"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/95842\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=95842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=95842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=95842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}