{"id":6785,"date":"2009-02-24T18:00:31","date_gmt":"2009-02-24T17:00:31","guid":{"rendered":"http:\/\/www.vicencianos.org\/web\/2009\/02\/24\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/"},"modified":"2016-07-26T11:00:38","modified_gmt":"2016-07-26T09:00:38","slug":"vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/","title":{"rendered":"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres"},"content":{"rendered":"<p><em>(13.02.46)<br \/>\n<\/em><\/p>\n<p>El padre Vicente, habi\u00e9ndose tomado la molestia de venir a darnos esta conferencia, pregunt\u00f3 cu\u00e1l era el tema, y tras haberlo o\u00eddo, pregunt\u00f3 a una hermana sobre \u00e9l. Despu\u00e9s, quiso informarse por extenso del peligro del que se hab\u00eda visto libre por una gran gracia de Dios, una de las hermanas hac\u00eda tres o cuatro d\u00edas.<\/p>\n<p>Hija m\u00eda, le dijo, \u00bfqu\u00e9 es lo que pas\u00f3? I le o\u00eddo hablar de una casa derrumbada. \u00bfEn qu\u00e9 barrio ha sido?, \u00bfestabais dentro o fuera?, \u00bfqu\u00e9 d\u00eda fue?<\/p>\n<p>La hermana respondi\u00f3 que, el \u00faltimo s\u00e1bado de carnaval, al ir a llevar el puchero a uno de los pobres, cuando sub\u00eda, un pobre aguador que iba delante de ella, exclam\u00f3: \u00abEstamos perdidos\u00bb. Estaba ella entre el primero y segundo piso; y apenas dijo aquel pobre hombre estas palabras, la casa empez\u00f3 a derrumbarse; y nuestra pobre hermana, muy asustada, se acurruc\u00f3 en el rinc\u00f3n de un rellano. Los vecinos, llenos de miedo, corrieron, inmediatamente a buscar el santo sacramento y la extremaunci\u00f3n, para administrarla a los que fueran capaces de ella. Pero m\u00e1s de treinta y cinco o cuarenta personas se vieron desgraciadamente aplastadas por las ruinas de la casa, y solamente hubo un ni\u00f1o de diez u once a\u00f1os que pudo salvarse.<\/p>\n<p>Los espectadores, al ver a nuestra pobre hermana en un peligro que parec\u00eda inevitable, la invitaron a que se echase entre sus brazos. Se pusieron diez o doce para socorrerla. Ella les tendi\u00f3 el puchero, que colgaron de un gancho en el extremo de una vara; luego se arroj\u00f3 sobre los mantos que hab\u00edan extendido fi\u00e1ndose de la providencia de Dios. Sin poder decir c\u00f3mo hab\u00eda sucedido se encontr\u00f3, por una especial providencia de Dios, fuera de peligro, y llena de temblor se fue a servir a los enfermos que le quedaban.<\/p>\n<p>El padre Vicente, despu\u00e9s de haber escuchado atentamente todo lo sucedido, lament\u00f3 el estado de los que hab\u00edan perecido entre los escombros de la casa y observ\u00f3 que el miedo de nuestra hermana hab\u00eda sido leg\u00edtimo al verse amenazada de tal manera, y exclam\u00f3 con las manos elevadas al cielo:<\/p>\n<p>\u00a1Dios m\u00edo! Si la ca\u00edda de una casa es tan terrible, \u00bfqu\u00e9 ser\u00e1, hijas m\u00edas, el d\u00eda del juicio, cuando veamos a una cantidad innumerable de almas precipitarse miserablemente al infierno por toda la eternidad? \u00a1Dios m\u00edo! \u00bfqu\u00e9 ser\u00e1 aquello? \u00a1Bendito sea Dios, hijas m\u00edas!<\/p>\n<p>Luego pregunt\u00f3 los sentimientos de varias hermanas sobre el tema de la conferencia, y, habi\u00e9ndolas escuchado a todas con una paciencia admirable, reanud\u00f3 su pl\u00e1tica poco m\u00e1s o menos en estos t\u00e9rminos<\/p>\n<p>&#8211; Doy gracias a Dios, hijas m\u00edas, por los pensamientos que os ha dado.. Los que yo he tenido ya han sido dichos, y estoy infinitamente consolado por lo que Dios os ha inspirado; \u00bfqu\u00e9 m\u00e1s queda por decir fuera de lo que ya se ha dicho? S\u00ed, hijas m\u00edas, ya hab\u00e9is dicho vosotras todo lo que yo pod\u00eda deciros. \u00a1Bendito sea Dios!<\/p>\n<p>Pero lo que me impresiona sensiblemente y lo que tiene que conmoveros poderosamente para que apreci\u00e9is el servicio de los pobres, es lo que ha dicho una de vosotras: que Dios, desde toda la eternidad, os hab\u00eda escogido y elegido para esto. \u00a1Dios m\u00edo! \u00a1c\u00f3mo nos tiene que impresionar esto! S\u00ed, es verdad, Dios desde toda la eternidad ten\u00eda sus pensamientos y sus designios sobre vosotras y en vosotras, y desde toda la eternidad estabais en la idea de Dios para el estado en que est\u00e1is actualmente; porque, hijas m\u00edas, no solamente todo lo que ha sucedido y sucede ahora, sino todo lo que suceda en el futuro, est\u00e1 presente ante Dios, y millones de a\u00f1os son delante de \u00e9l todav\u00eda menos que un d\u00eda. \u00a1Qu\u00e9 verdad es que desde toda la eternidad ten\u00eda Dios el designio de utilizaros en servicio de los pobres! qu\u00e9 felicidad, hijas m\u00edas, y c\u00f3mo la consideraci\u00f3n de esta misi\u00f3n eterna de Dios sobre vosotras tiene que ayudaros a que sep\u00e1is agradecerle la elecci\u00f3n que de vosotras ha hecho! \u00a1Pensad mucho en ello!<\/p>\n<p>Os he dicho muchas veces, hijas m\u00edas, que ten\u00e9is que estar muy seguras de que es Dios el que os ha fundado, porque os puedo decir delante de \u00e9l que yo nunca hab\u00eda pensado en ello, y que tampoco creo que lo pensase la se\u00f1orita Le Gras. Ya os he dicho c\u00f3mo sucedi\u00f3 esto. Pero, como muchas de las que est\u00e1n aqu\u00ed presentes no estaban entonces, os lo volver\u00e9 a decir una vez m\u00e1s, para se\u00f1alaros la actuaci\u00f3n de Dios en vuestra fundaci\u00f3n.<\/p>\n<p>Sabed, pues, que estando cerca de Lyon en una peque\u00f1a ciudad en donde la Providencia me hab\u00eda llevado para ser p\u00e1rroco, un domingo, como me estuviese preparando para celebrar la santa misa, vinieron a decirme que en una casa separada de las dem\u00e1s, a un cuarto de hora de all\u00ed, estaba todo el mundo enfermo, sin que quedase ni una sola persona para asistir a las otras, y todas en una necesidad que es imposible expresar. Esto me toc\u00f3 sensiblemente el coraz\u00f3n; no dej\u00e9 de decirlo en el serm\u00f3n con gran sentimiento, y Dios, tocando el coraz\u00f3n de los que me escuchaban, hizo que se sintieran todos movidos de compasi\u00f3n por aquellos pobres afligidos.<\/p>\n<p>Despu\u00e9s de comer se celebr\u00f3 una reuni\u00f3n en casa de una buena se\u00f1orita de la ciudad, para ver qu\u00e9 socorros se les podr\u00eda dar, y cada uno se mostr\u00f3 dispuesto a ir a verlos, consolarlos con sus palabras y ayudarles en lo que pudieran. Despu\u00e9s de v\u00edsperas, tom\u00e9 a un hombre honrado, vecino de aquella ciudad, y fuimos juntos hasta all\u00e1. Nos encontramos por el camino con algunas mujeres que iban por delante de nosotros, y un poco m\u00e1s adelante, con otras que volv\u00edan. Y como era en verano y durante los grandes calores, aquellas buenas mujeres se sentaban al lado del camino para descansar y refrescarse. Finalmente, hijas m\u00edas, hab\u00eda tantas, que se podr\u00eda haber dicho que se trataba de una procesi\u00f3n.<\/p>\n<p>Apenas llegu\u00e9, visit\u00e9 a los enfermos y fui a buscar el Sant\u00edsimo Sacramento para los que estaban m\u00e1s graves, no a la parroquia del lugar, porque no hab\u00eda ninguna, sino que depend\u00eda de un cabildo del que yo era prior. As\u00ed pues, despu\u00e9s de haberlos confesado y dado la comuni\u00f3n, hubo que pensar en la manera de atender a sus necesidades. Les propuse a todas aquellas buenas personas, a las que la caridad hab\u00eda animado a acudir all\u00e1, que se pusiesen de acuerdo, cada una un d\u00eda determinado, para hacerles la comida, no solamente a aquellos, sino a todos los que viniesen luego; fue aquel el primer lugar en donde se estableci\u00f3 la Caridad.<\/p>\n<p>Pues bien, ya veis, hijas m\u00edas, c\u00f3mo no es obra de los hombres y como es evidentemente obra de Dios; porque \u00bffueron los hombres los que hicieron enfermar a aquellas personas?, \u00bffueron los hombres los que pusieron fuego en el coraz\u00f3n de tantas personas que se dirigieron all\u00e1 en gran n\u00famero para ir a socorrerlos? \u00bffueron los hombres los que pusieron en los corazones el deseo de prestarles una continua asistencia, no solamente a aquellos sino a los que viniesen despu\u00e9s? No, hijas m\u00edas, no fue obra de los hombres, est\u00e1 claro que Dios actuaba all\u00ed con su poder, porque los hombres no pod\u00edan hacerlo. No, los hombres no pod\u00edan hacer nada de esto.<\/p>\n<p>Yo fui llamado para acudir all\u00e1; y despu\u00e9s de alg\u00fan tiempo, al ir a una misi\u00f3n en Villepreux, que es una aldea a cinco o seis leguas de Par\u00eds, tuvimos la ocasi\u00f3n de establecer all\u00ed la Caridad; era la segunda. Luego pudimos establecerla en Par\u00eds, y San Salvador fue la primera parroquia que la tuvo; siguieron luego todas las principales parroquias. Pero, como hay gran n\u00famero de enfermos en Par\u00eds, estaban mal servidos, porque las damas no pod\u00edan sujetarse a ellos: la esposa por causa de su marido y de su casa, la hija por causa de su padre y de su madre. En fin, que aquello no iba bien, porque Dios quer\u00eda que hubiese una Compa\u00f1\u00eda de hermanas que se dedicase expresamente a servir a los enfermos bajo aquellas damas.<\/p>\n<p>La primera de esas hermanas fue una pobre aldeana; es preciso que os lo diga, hijas m\u00edas, para mostraros la Providencia de Dios, que quiso que vuestra Compa\u00f1\u00eda se compusiese de hermanas pobres, o por nacimiento, o por la elecci\u00f3n que har\u00edan de la pobreza; s\u00ed, hijas m\u00edas, hablo de hermanas pobres, porque es preciso que lo se\u00e1is efectivamente.<\/p>\n<p>Aquella pobre hermana se hab\u00eda entregado a Dios para instruir en su conocimiento a los ni\u00f1os de su aldea, y a pesar de guardar vacas, aprendi\u00f3 a leer ella casi sola, porque ninguno se lo hab\u00eda ense\u00f1ado. Deten\u00eda a los que pasaban por su lado y les preguntaba: \u00abSe\u00f1or, d\u00edgame por favor, lo que son estas letras; qu\u00e9 es lo que quiere decir esta palabra\u00bb; y de esta forma iba aprendiendo para ense\u00f1ar luego a los dem\u00e1s.<\/p>\n<p>Cuando ella supo algunas cosas, ense\u00f1\u00f3 a sus compa\u00f1eras. Fuimos a celebrar una misi\u00f3n en aquel lugar, y Dios demostr\u00f3 en seguida que aquello no le desagradaba. Aquella buena mujer, al o\u00edr que atend\u00edan a los enfermos en Par\u00eds, tuvo deseos de ir a servirles. Hicimos que viniese, y la pusimos bajo la direcci\u00f3n de la se\u00f1orita Le Gras y al servicio de los pobres enfermos de Saint-Nicolas-du-Chardonnet; despu\u00e9s de alg\u00fan tiempo fue atacada por la peste y muri\u00f3 en San Luis, En su lugar se puso a la que serv\u00eda a los enfermos de San Salvador.<\/p>\n<p>He aqu\u00ed, hijas m\u00edas, cu\u00e1l fue el comienzo de vuestra Compa\u00f1\u00eda; como entonces no era lo que es actualmente, hemos de creer que tampoco es ahora lo que ser\u00e1 luego, cuando Dios la haya situado en el puesto en que la quiera; porque, hijas m\u00edas, no es preciso que cre\u00e1is que las comunidades se hacen de un solo golpe. San Benito, san Agust\u00edn, santo Domingo y todos los grandes siervos de Dios, cuyas \u00f3rdenes son tan florecientes, no pensaban ni mucho menos en hacer lo que hicieron. Pero Dios actu\u00f3 por medio de ellos.<\/p>\n<p>Las obras de las que no se pueden indicar los obreros, salen, seg\u00fan se dice, de las manos de Dios. Vuestra instituci\u00f3n no es obra de los hombres; por tanto, pod\u00e9is decir con seguridad que es de Dios; y ciertamente, una Compa\u00f1\u00eda ordenada para una misi\u00f3n tan agradable a Dios, tan excelente en s\u00ed misma y tan \u00fatil para el pr\u00f3jimo, no puede tener por autor m\u00e1s que al propio Dios. \u00bfQui\u00e9n ha o\u00eddo hablar alguna vez de semejante obra antes de hoy? Hab\u00eda ciertamente varias \u00f3rdenes religiosas. Se hab\u00edan fundado hospitales para la asistencia de los enfermos; algunos religiosos se hab\u00edan consagrado a su servicio; pero hasta ahora no se hab\u00eda visto nunca que se cuidase a los enfermos en sus casas. Si en una pobre familia ca\u00eda alg\u00fan enfermo, era preciso separar al marido de su mujer, a la mujer de sus hijos, al padre de su familia. Hasta el presente, Dios m\u00edo, no hab\u00edas establecido ninguna orden para socorrerlos; y parec\u00eda como si tu Providencia adorable, que a nadie falta, no se hubiese cuidado de ellos.<\/p>\n<p>\u00bfY por qu\u00e9 cre\u00e9is, hijas m\u00edas, que Dios estuvo aguardando tanto tiempo para suscitar esta ayuda? \u00a1Es que os lo estaba reservando a vosotras! S\u00ed, vosotras estabais reservadas por Dios desde toda la eternidad, como muy bien ha se\u00f1alado una hermana, para ser las primeras. \u00a1Qu\u00e9 ventaja!; porque las que entran en una Orden en los sesenta a cien primeros a\u00f1os, esto es, en el primer siglo, que es el siglo de oro, esas se llaman las primeras; y por tanto, vosotras sois las primeras. Os ruego, hijas m\u00edas, que atend\u00e1is mucho a lo que esto os obliga.<\/p>\n<p>Si no fuese Dios, hijas m\u00edas, el que realiza lo que se ve en vuestra vocaci\u00f3n, \u00bfpodr\u00eda suceder que una mujer abandonase su pa\u00eds, sus padres, y los placeres del matrimonio, si podemos decir que los tiene, sus peque\u00f1as comodidades, las diversiones que se tienen con las amigas, para venir a un lugar que nunca hab\u00eda visto, con otras mujeres de pa\u00edses lejanos, para entregarse en medio de una pobreza voluntaria al servicio de los condenados, de los ni\u00f1os abandonados por sus parientes, de los pobres enfermos que se pudren en la suciedad y de todos aquellos que viven incluso en los calabozos? No, hijas m\u00edas; s\u00f3lo Dios puede hacer esto. El ha querido que una fuese de Lorena, la otra de Sedan, la otra de Angers, y las otras de otros lugares; por eso se ha dicho: \u00abOs llamar\u00e9 de todas las naciones de la tierra\u00bb 3. Por consiguiente, \u00e9l es el que ha querido esta Compa\u00f1\u00eda de hermanas de diferentes pa\u00edses para que todas ellas no fuesen m\u00e1s que un solo coraz\u00f3n. \u00a1Sea para siempre bendito su santo y adorado nombre!<\/p>\n<p>Otra raz\u00f3n es la protecci\u00f3n especial\u00edsima que Dios tiene de vosotras. \u00bfNo es admirable, hijas m\u00edas? Ten\u00e9is un ejemplo muy reciente en la persona de vuestra buena hermana. \u00bfNo os hace todo esto ver que Dios acepta con muy especial agrado el servicio que le rend\u00eds en la persona de los pobres? Se derrumba una casa nueva; cuarenta personas se ven aplastadas bajo sus ruinas. Esta pobre hermana, que tiene en la mano su puchero, est\u00e1 en un rellano de la escalera que la Providencia conserva expresamente para sostenerla, y sale de este peligro sana y salva. All\u00ed est\u00e1n los \u00e1ngeles, hemos de creerlo; porque \u00bfcre\u00e9is acaso que fueron los hombres? Ellos le tendieron la mano, pero eran los \u00e1ngeles los que la sosten\u00edan. \u00bfCre\u00e9is, hijas m\u00edas, que Dios permiti\u00f3 sin un designio especial que cayese esa casa nueva? \u00bfCre\u00e9is que fue una casualidad que se derrumbase precisamente en el momento en que nuestra hermana estaba all\u00ed; y cre\u00e9is tambi\u00e9n que fue una casualidad que ella escapase sin mal alguno? \u00a1Ni mucho menos, hijas m\u00edas! Todo esto es milagroso. Dios hab\u00eda ordenado todo esto para hacer conocer a vuestra Compa\u00f1\u00eda el cuidado que de ella tiene.<\/p>\n<p>No es solamente a nuestra hermana a la que se concede una gracia tan se\u00f1alada, sino a todas vosotras; ha sido para confirmaros a todas vosotras en la confianza que hab\u00e9is de tener de que vuestros servicios agradan a Dios; ha sido para haceros ver a todas que le sois tan queridas como la ni\u00f1a de sus ojos; ha sido para obligaros a tener una confianza segura en su Providencia, que no os abandonar\u00e1 jam\u00e1s; no, hijas m\u00edas, estad seguras, este ejemplo es una se\u00f1al indudable. Dios os conservar\u00e1 en cualquier sitio adonde vay\u00e1is. Ver\u00e9is muchas veces como la c\u00f3lera de Dios castiga con una muerte repentina y violenta a una muchedumbre de pecadores, sin que tengan ocasi\u00f3n de convertirse a \u00e9l; ver\u00e9is incluso que perecen muchos inocentes. Y vosotras os salvar\u00e9is. S\u00ed, Dios cuida de vosotras y se interesa por vuestra conservaci\u00f3n.<\/p>\n<p>\u00bfNo cre\u00e9is que fue tambi\u00e9n una buena prueba este piso que se cay\u00f3 hace cerca de un a\u00f1o? 5. Es una prueba muy segura. Es maravilloso que se haya roto una viga en un lugar como este, y que no haya ca\u00eddo nadie debajo de ella. La se\u00f1orita Le Gras estaba all\u00ed; una hermana la oy\u00f3 crujir y le dijo que no estaba all\u00ed muy segura. No hizo caso. Se lo repiti\u00f3 otra hermana mayor. Tuvo consideraci\u00f3n de su edad y se retir\u00f3. Apenas se hab\u00eda retirado a la habitaci\u00f3n de al lado (fijaos, hermanas m\u00edas, no hay m\u00e1s que tres pasos), cuando la viga se rompi\u00f3 y cay\u00f3 el piso.<\/p>\n<p>Ved si acaso se hizo esto sin una intervenci\u00f3n especial de Dios. Aquella misma tarde yo ten\u00eda que estar aqu\u00ed; ten\u00edamos que reunirnos para algunos asuntos importantes. En medio del ruido que hay en una reuni\u00f3n, nadie se hubiera dado cuenta de que esta viga cruj\u00eda. No habr\u00eda estado all\u00ed aquella hermana, porque las hermanas no est\u00e1n en esas reuniones, y todos nos hubi\u00e9semos visto aplastados en aquel sitio; y Dios hizo que surgiese otro asunto que me detuvo y que impidi\u00f3 acudir all\u00e1 a todas las damas.<\/p>\n<p>Todo esto no se hace por casualidad, hijas m\u00edas; hay que guardarse de creerlo as\u00ed. Un hombre, para huir de la predicci\u00f3n que se le hab\u00eda hecho de que caer\u00eda una casa sobre su cabeza, se fue al campo. Una tortuga que llevaba un \u00e1guila le cay\u00f3 sobre la cabeza y le mat\u00f3. Ved, hijas m\u00edas, c\u00f3mo en ninguna parte se puede estar seguros. \u00a1Y en unas casas que se derrumban, vosotras os salv\u00e1is! Ten\u00e9is que dar todas juntas muchas gracias a Dios por esta prueba especial de su Providencia que nos ha dado una vez m\u00e1s en la persona de vuestra hermana. S\u00ed, hijas m\u00edas, ten\u00e9is que hacerlo, y os ruego que os preocup\u00e9is de hacerlo. Que vuestra pr\u00f3xima comuni\u00f3n sea, por tanto, por esta intenci\u00f3n. Cuando lo supe, celebr\u00e9 la misa para dar gracias a Dios; y actualmente, que lo s\u00e9 con m\u00e1s detalle todav\u00eda, volver\u00e9 a celebrarla, si Dios quiere. \u00a1Sea por siempre bendito su santo nombre!<\/p>\n<p>He aqu\u00ed pues, mis queridas hijas, unas cuantas razones muy poderosas para incitaros a estimar vuestra vocaci\u00f3n y a aceptarla con agrado, puesto que as\u00ed lo quiere Dios y as\u00ed son socorridos los pr\u00f3jimos; y todo ello sin miedo alguno, puesto que Dios mismo cuida de vosotras.<\/p>\n<p>Un medio para hacerlo como Dios quiere, es hacerlo con caridad, hijas m\u00edas. \u00a1La caridad har\u00e1 excelente vuestro servicio! Pero, \u00bfsab\u00e9is lo que es hacerlo con caridad? Es hacerlo en Dios, porque Dios es caridad, es hacerlo puramente por Dios; es hacerlo en gracia de Dios, porque el pecado nos separa de la caridad de Dios. Yo os he dicho otras veces que no ser\u00e9is verdaderas Hijas de la Caridad mientras no hay\u00e1is purificado todos vuestros motivos, mientras no hay\u00e1is arrancado todas las ra\u00edces de vuestras costumbres viciosas, mientras no os hay\u00e1is separado de vuestros apegos particulares. Lo digo una vez m\u00e1s, hijas m\u00edas, y esto es tan necesario que, si no lo hac\u00e9is, no est\u00e1is en estado de comulgar; ni mucho menos, hijas m\u00edas, no lo est\u00e1is porque a nadie se le permite acercarse a la sagrada comuni\u00f3n con alg\u00fan afecto al pecado, aunque sea simplemente venial. \u00bfQu\u00e9 suceder\u00eda pues, hijas m\u00edas, a una hija de la Caridad que se acercase a comulgar, no digo ya con alg\u00fan afecto al pecado mortal (\u00a1Dios nos guarde! \u00a1qu\u00e9 gran sacrilegio ser\u00eda esto!), sino con alg\u00fan afecto al pecado venial? Pues bien, esto es no querer corregirse. Por ejemplo, una hermana tiene alg\u00fan apego a otra hermana; busca su compa\u00f1\u00eda, le habla al o\u00eddo, le comunica sus descontentos, le cuenta las mortificaciones que ha tenido que sufrir. Este apego es vicioso y, por lo menos, pecado venial. Una hermana que se sintiese con este apego y que comulgase sin proponerse romper con \u00e9l, comulgar\u00eda con afecto al pecado, y en buena conciencia no debe hacerlo hasta que no se haya resuelto a romper con \u00e9l. Ya os he dicho que, apenas os sint\u00e1is apegadas a alguien, ten\u00e9is que avisar de ello a vuestro superior director.<\/p>\n<p>Otra hermana servir\u00e1 a los enfermos de una parroquia; sentir\u00e1 apego a una dama, a una oficial, a un confesor; pues bien, tiene que dar aviso enseguida y aplastar la cabeza de esta serpiente, mientras est\u00e1 todav\u00eda naciendo; porque, si no lo hace, servir\u00e1 a la parroquia, pero no a los pobres; lo har\u00e1 por la satisfacci\u00f3n que siente, y no por el motivo por el que tiene que hacerlo. \u00a1Guard\u00e9monos mucho de estas infidelidades, hijas m\u00edas, en nombre de Dios! Esto nos aparta de los altares. Cuando una hermana vea que siente apego a un lugar o a una dama o confesor, que lo diga cuanto antes. Dios m\u00edo, \u00a1si es tan f\u00e1cil! Si tiene deseos de progresar, lo har\u00e1. Hacedlo, pues, hijas m\u00edas, cuando esto os pase, para que se os pueda enviar a otra parte, donde sirv\u00e1is a Dios por \u00e9l mismo, sin ning\u00fan compromiso ni apego para con nadie.<\/p>\n<p>Otra hermana tendr\u00e1 quiz\u00e1s antipat\u00eda contra alguna compa\u00f1era. Le disgustar\u00e1 todo lo que hace; si se le habla de ella, tragar\u00e1 con dificultad la estima que de ella se tiene; si esa hermana le dice algo, no lo ver\u00e1 bien; y, al no corregirse, comulgar\u00e1 con afecto al pecado en contra de lo que tiene que hacer. \u00a1Y es tan f\u00e1cil poner remedio! Yo tengo antipat\u00eda contra una hermana, pero no quiero fomentarla; le hablar\u00e9 con mansedumbre; si me dice algo la escuchar\u00e9 con docilidad; cuando me hablen de ella, procurar\u00e9 no decir nada que rebaje o disminuya la estima que de ella tienen.<\/p>\n<p>Si hac\u00e9is esto, progresar\u00e9is, hijas m\u00edas, porque os aprovechar\u00e9is de vuestras comuniones y de vuestras conferencias. \u00a1Dios m\u00edo, cu\u00e1nto deseo que comprend\u00e1is bien el esp\u00edritu de Dios en las conferencias que se os hacen, y que os acostumbr\u00e9is a decir vuestros pensamientos, como acab\u00e1is de hacer! Veo con entusiasmo esta disposici\u00f3n en vosotras; porque ya veis cu\u00e1nta materia me proporcionan vuestros pensamientos. No digo nada de mi cosecha, no digo m\u00e1s que lo que vosotras mismas me hab\u00e9is dicho. \u00a1Bendito sea Dios! Lo deseo tanto que os puedo decir de verdad que no creo desear nada m\u00e1s. Porque ya veis, hijas m\u00edas, todos los apegos, todas las aversiones y esos obst\u00e1culos que impiden el fruto de las comuniones y de las instrucciones son obra del diablo, que revienta al ver lo que hac\u00e9is v que hace todo lo que puede para impediros que os aprovech\u00e9is de ellas. Sugerir\u00e1 a las hermanas que est\u00e1n aqu\u00ed: \u00ab\u00bfQu\u00e9 es lo que hago aqu\u00ed? He venido para servir a los enfermos y no me lo mandan\u00bb. A las que est\u00e1n en las parroquias: \u00abSi estuviese con los ni\u00f1os, lo har\u00eda mucho mejor\u00bb. Y todo esto para que, al comulgar con estos apegos o con estas aversiones, no os aproveche. Hijas m\u00edas, cuando sint\u00e1is esto en vosotras, decidlo cuanto antes.<\/p>\n<p>Otro motivo, como ha dicho una hermana (ved, hijas m\u00edas, c\u00f3mo no hablo m\u00e1s que por medio de vosotras) es que, al servir a los pobres, se sirve a Jesucristo. Hijas m\u00edas, \u00a1cu\u00e1nta verdad es esto! Serv\u00eds a Jesucristo en la persona de los pobres. Y esto es tan verdad como que estamos aqu\u00ed. Una hermana ir\u00e1 diez veces cada d\u00eda a ver a los enfermos, y diez veces cada d\u00eda encontrar\u00e1 en ellos a Dios. Como dice san Agust\u00edn, lo que vemos no es tan seguro, porque nuestros sentidos pueden enga\u00f1arse; pero las verdades de Dios no enga\u00f1an jam\u00e1s. Id a ver a los pobres condenados a cadena perpetua, y en ellos encontrar\u00e9is a Dios; servid a esos ni\u00f1os, y en ellos encontrar\u00e9is a Dios. \u00a1Hijas m\u00edas, cu\u00e1n admirable es esto! Vais a unas casas muy pobres, pero all\u00ed encontr\u00e1is a Dios. Hijas m\u00edas, una vez m\u00e1s, \u00a1cu\u00e1n admirable es esto! S\u00ed, Dios acoge con agrado el servicio que hac\u00e9is a esos enfermos y lo considera, como hab\u00e9is dicho, hecho a \u00e9l mismo.<\/p>\n<p>Otro motivo, que tambi\u00e9n ha dado una de las hermanas, es que Dios ha prometido recompensas eternas a los que le ofrezcan a un pobre un vaso de agua; no hay nada tan cierto, y no podemos dudar de ello; y esto es para vosotras, hijas m\u00edas, un gran motivo de confianza, porque si Dios da una eternidad bienaventurada a los que no han ofrecido m\u00e1s que un vaso de agua, \u00bfqu\u00e9 dar\u00e1 a una Hija de la Caridad, que lo deja todo y se entrega a s\u00ed misma para servirle durante toda su vida? \u00bfQu\u00e9 le dar\u00e1? \u00a1No nos lo podemos imaginar! Tiene motivos para esperar ser de aquellos a los que se dir\u00e1: \u00abVenid, benditas de mi Padre, poseed el reino que os est\u00e1 preparado\u00bb.<\/p>\n<p>Otro nuevo motivo es que los pobres asistidos por ella ser\u00e1n sus intercesores delante de Dios; acudir\u00e1n en mont\u00f3n a su encuentro; dir\u00e1n al buen Dios: \u00abDios m\u00edo, \u00e9sta es la que nos asisti\u00f3 por tu amor; Dios m\u00edo, esta es la que nos ense\u00f1\u00f3 a conocerte\u00bb. Porque, ved hijas m\u00edas, hab\u00e9is dicho lo m\u00e1s importante cuando dijisteis que hab\u00eda que asistirles espiritualmente. Ellos dir\u00e1n: \u00abDios m\u00edo, \u00e9sta es la que me ense\u00f1\u00f3 a creer que hab\u00eda un Dios en tres personas; yo no lo sab\u00eda. Dios m\u00edo, \u00e9sta es la que me ense\u00f1\u00f3 a esperar en Ti; \u00e9sta es la que me ense\u00f1\u00f3 tus bondades por medio de las suyas\u00bb. En resumen, hijas m\u00edas, todo esto os valdr\u00e1 el servicio de los pobres.<\/p>\n<p>Por tanto, aficionaos mucho a los pobres, por favor, y tened mucho cuidado de ense\u00f1arles las verdades necesarias para la salvaci\u00f3n. Ya hab\u00e9is visto cu\u00e1nto importa esto. Y es cierto; y tengo muchas ganas de buscar alg\u00fan medio; ya os avisaremos, con la ayuda de Dios. Entre tanto, haced todo lo que est\u00e9 en vuestro poder.<\/p>\n<p>Una hermana ha hecho una observaci\u00f3n muy justa: \u00abEs preciso, ha dicho, hacer que administren los sacramentos a los enfermos antes de nada\u00bb. S\u00ed, hijas m\u00edas, conviene mucho, al atender sus necesidades, procurar averiguar con afabilidad y mansedumbre, con cordialidad y compasi\u00f3n, si se han confesado y, si no lo han hecho, disponerlos para ello.<\/p>\n<p>Una hermana ha objetado anteriormente que a veces los sacerdotes no lo ten\u00edan en cuenta.<\/p>\n<p>Hija m\u00eda, respondi\u00f3 el padre Vicente, no os imagin\u00e9is nunca que ellos descuidan esta obligaci\u00f3n; pero, cuando les hay\u00e1is avisado, vuestra conciencia quedar\u00e1 tranquila delante de Dios. Una de vosotras ha observado muy bien que conven\u00eda ense\u00f1arles a hacer un acto de contrici\u00f3n y fomentar en ellos el deseo de confesarse. Hacedlo as\u00ed hijas m\u00edas; y si empeora su estado, podr\u00e9is advertirlo por segunda vez al se\u00f1or p\u00e1rroco; pero, no lo hag\u00e1is nunca en plan de queja, sino mansamente. Podr\u00e9is decirle: \u00abSe\u00f1or, este pobre enfermo est\u00e1 peor; tengo miedo de que le pase cualquier cosa. Me he cre\u00eddo obligada a advert\u00edrselo\u00bb. Y esto con mansedumbre.<\/p>\n<p>Bien, se est\u00e1 haciendo tarde; ya es hora de acabar. Para terminar, pido a Dios que os d\u00e9 su esp\u00edritu, la perfecci\u00f3n de vuestra vocaci\u00f3n, y que derrame sobre toda la Compa\u00f1\u00eda sus bendiciones, para hacer que cumpla su santa voluntad en este mundo con tal fidelidad que pueda merecer alg\u00fan d\u00eda gozar de su gloria en el otro.<\/p>\n<p>Benedictio Dei Patris&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(13.02.46) El padre Vicente, habi\u00e9ndose tomado la molestia de venir a darnos esta conferencia, pregunt\u00f3 cu\u00e1l era el tema, y tras haberlo o\u00eddo, pregunt\u00f3 a una hermana sobre \u00e9l. Despu\u00e9s, quiso informarse por extenso del &#8230; <a href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":393753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[139,147,135],"class_list":["post-6785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-vicente-de-paul","tag-san-benito","tag-santo-domingo","tag-villepreux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"(13.02.46) El padre Vicente, habi\u00e9ndose tomado la molestia de venir a darnos esta conferencia, pregunt\u00f3 cu\u00e1l era el tema, y tras haberlo o\u00eddo, pregunt\u00f3 a una hermana sobre \u00e9l. Despu\u00e9s, quiso informarse por extenso del ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-24T17:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T09:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres\",\"datePublished\":\"2009-02-24T17:00:31+00:00\",\"dateModified\":\"2016-07-26T09:00:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/\"},\"wordCount\":4765,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"San Benito\",\"Santo Domingo\",\"Villepreux\"],\"articleSection\":[\"Escritos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/\",\"name\":\"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2009-02-24T17:00:31+00:00\",\"dateModified\":\"2016-07-26T09:00:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres - Somos Vicencianos","og_description":"(13.02.46) El padre Vicente, habi\u00e9ndose tomado la molestia de venir a darnos esta conferencia, pregunt\u00f3 cu\u00e1l era el tema, y tras haberlo o\u00eddo, pregunt\u00f3 a una hermana sobre \u00e9l. Despu\u00e9s, quiso informarse por extenso del ... Read More","og_url":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2009-02-24T17:00:31+00:00","article_modified_time":"2016-07-26T09:00:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"24 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres","datePublished":"2009-02-24T17:00:31+00:00","dateModified":"2016-07-26T09:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/"},"wordCount":4765,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","keywords":["San Benito","Santo Domingo","Villepreux"],"articleSection":["Escritos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/","url":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/","name":"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","datePublished":"2009-02-24T17:00:31+00:00","dateModified":"2016-07-26T09:00:38+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-conferencia-024-amor-a-la-vocacion-y-asistencia-a-los-pobres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal, Conferencia 024: Amor a la vocaci\u00f3n y asistencia a los pobres"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1Lr","jetpack-related-posts":[{"id":387673,"url":"https:\/\/vincentians.com\/es\/afianzar-la-compania-2\/","url_meta":{"origin":6785,"position":0},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"17\/04\/2016","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"LOGO HHC","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/03\/LOGO-HHC.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":127035,"url":"https:\/\/vincentians.com\/es\/afianzar-la-compania\/","url_meta":{"origin":6785,"position":1},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"23\/01\/2024","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119413,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-fundador\/","url_meta":{"origin":6785,"position":2},"title":"San Vicente de Pa\u00fal, fundador","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/04\/2013","format":false,"excerpt":"La Comunidad de las Hijas de la Caridad y su estilo emi\u00adnentemente apost\u00f3lico, no han sido creaciones espont\u00e1neas, que podr\u00edan estudiarse y profundizar independientemente de todo con\u00adtexto. Antes de ser una Instituci\u00f3n, fue una etapa en el recorrido de Vicente de Pa\u00fal. Pero, para hacernos una idea justa de la\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/07\/saint-vincent-de-paul-111-197x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":143274,"url":"https:\/\/vincentians.com\/es\/la-hija-de-la-caridad-docente-segun-san-vicente\/","url_meta":{"origin":6785,"position":3},"title":"La Hija de la Caridad docente, seg\u00fan san Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/04\/2015","format":false,"excerpt":"Antes de reflexionar sobre el tema \u201cLa Hija de la Caridad docente\u201d, convendr\u00eda evocar la experiencia de estudiante y de docente de san Vicente, al menos por dos razones: Vicente de Pa\u00fal siempre dio una importancia capital a la experiencia; y todo lo que vivi\u00f3 como estudiante, luego como docente,\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"cochoapa+practica+prof+108","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/04\/cochoapa-practica-prof-108-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130675,"url":"https:\/\/vincentians.com\/es\/el-cristo-de-vicente-de-paul-i\/","url_meta":{"origin":6785,"position":4},"title":"El Cristo de Vicente de Pa\u00fal (I)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/06\/2014","format":false,"excerpt":"Caminemos con confianza por este camino real en el que Jesucristo ser\u00e1 nuestro mentor y nuestro gu\u00eda. (Abelly, BI, 248). En la producci\u00f3n teol\u00f3gica reciente existe una corriente s\u00f3lida que destaca la importancia de los santos como fuente de teolog\u00eda'. Esta corriente se\u00f1ala con fuerza que los santos liberan a\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"dibujo-diaconado","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/11\/dibujo-diaconado.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":114848,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1014-lamberto-aux-couteaux-a-san-vicente\/","url_meta":{"origin":6785,"position":5},"title":"Vicente de Pa\u00fal, Carta 1014: Lamberto Aux Couteaux A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/11\/2012","format":false,"excerpt":"Nantes, 26 julio 1647. Padre: \u00a1Su bendici\u00f3n, por favor! Estamos a punto de partir de Nantes, despu\u00e9s de haber hecho todas las cosas que le voy a explicar. Puedo asegurarle que nuestras hermanas han estado muy agitadas; ciertamente, si han cometido algunas faltillas, la Providencia de Dios las ha puesto\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/6785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=6785"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/6785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/393753"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=6785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=6785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=6785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}