{"id":52974,"date":"2019-02-17T08:35:57","date_gmt":"2019-02-17T07:35:57","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/11\/devociones-a-la-medalla-milagrosa\/"},"modified":"2019-01-27T13:30:08","modified_gmt":"2019-01-27T12:30:08","slug":"devociones-a-la-medalla-milagrosa","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/","title":{"rendered":"Devociones a la Medalla Milagrosa"},"content":{"rendered":"<p>Los cultos m\u00e1s practicados para honrar a la Virgen Mila\u00adgrosa son, aparte del Novenario anual en el mes de noviembre, el de la Visita Domiciliaria, el de la Novena Perpetua u Oraci\u00f3n comunitaria semanal, <em>y <\/em>el del d\u00eda 27 de cada mes. A modo de ejemplo traslado aqu\u00ed dos modelos, uno de la Visita Domicilia\u00adria y otro de la Novena Perpetua.<\/p>\n<h2>1. Oraci\u00f3n de la familia ante la imagen de la visita domiciliaria<\/h2>\n<p>Virgen Mar\u00eda, seas bienvenida a nuestro hogar. Nosotros, que abrimos con gusto las puertas de nuestra casa a los amigos, nos llenamos de especial alegr\u00eda con tu visita: T\u00fa eres nuestra mejor amiga, compa\u00f1era de nuestro camino, nuestra Madre.<\/p>\n<p>Cuando el \u00e1ngel te dijo que tu prima Isabel hab\u00eda concebido un hijo, corriste a su casa para compartir con ella su alegr\u00eda y tu alegr\u00eda, prestarle tus servicios y comunicarle con tu presen\u00adcia la gran noticia: Que el Hijo de Dios se hab\u00eda encarnado en tus entra\u00f1as. Asunta al cielo, no has dejado de seguir visitando a los hombres para traernos a Cristo y llevarnos a El.<\/p>\n<p>Hoy has venido a nuestra casa en esta imagen que nos habla de tu manifestaci\u00f3n a santa Catalina Labour\u00e9. A ella le permitiste apoyar sus manos en tus rodillas, le hablaste como una madre a su hija, la preparaste para cumplir la misi\u00f3n de que se grabara y se difundiera una Medalla tuya, a la que el pueblo llamar\u00eda \u00abmilagrosa\u00bb por los innumerables prodigios que por ella obraste.<\/p>\n<p>Nos complacemos al ver en ella tu concepci\u00f3n inmaculada, tu maternidad espiritual, tu uni\u00f3n con Jes\u00fas en la obra de nuestra redenci\u00f3n, tu intercesi\u00f3n constante por nosotros y, sobre todo, esas manos derramando lluvias de gracia sobre la tierra.<\/p>\n<p>Tu imagen nos habla de tu presencia entre nosotros y de ti queremos aprender mucho. Queremos aprender tu disponibili\u00addad para hacer la voluntad de Dios en lo f\u00e1cil y en lo dificil, queremos vivir los momentos oscuros de la Fe con una fidelidad como la tuya, queremos ser puros y humildes como t\u00fa, quere\u00admos ser serviciales y comprometidos como t\u00fa.<\/p>\n<p>Se\u00f1ora y Madre nuestra: Ya que est\u00e1s con nosotros, que \u00e9sta sea tu casa. Que nosotros vivamos unidos para poder estar juntos a tu lado. Comparte nuestros momentos alegres y nues\u00adtros d\u00edas grises. Ay\u00fadanos a superar nuestros problemas y a salir de nuestros pecados. Te consagramos nuestras personas, nuestros problemas, el trabajo y el estudio de cada d\u00eda. Que nuestro hogar sea como un altar consagrado a ti.<\/p>\n<p><em>(S\u00ed es posible, meditar uno o varios misterios del rosario o leer alg\u00fan pasaje de la Biblia, Y rezar tres veces el Ave Mar\u00eda con la jaculatoria de la Medalla: Oh Mar\u00eda, sin pecado concebida, ruega por nosotros que recurrimos a ti).<\/em><\/p>\n<p><em>Peticiones:<\/em><\/p>\n<p>Y ahora, antes de terminar estos momentos contigo, escu\u00adcha las peticiones que te hacemos <em>(se contesta a cada petici\u00f3n: \u00abMadre de Dios, intercede por nosotros\u00bb).<\/em><\/p>\n<ul>\n<li>Que todos los miembros de esta familia vivamos los compromisos de la Fe, especialmente el amor a Dios y al pr\u00f3jimo, y la participaci\u00f3n plena en la Eucarist\u00eda del d( mingo&#8230;<\/li>\n<li>Que nuestra casa sea un reflejo del hogar de Nazaret al vivir en gracia de Dios y cumplir cada uno sus deberes&#8230;<\/li>\n<li>Que nos esforcemos por vivir unidos, que nos ayudemos en todo, que nos comprendamos y que sepamos perdo\u00adnar las molestias que nos causamos cada d\u00eda&#8230;<\/li>\n<li>Que seamos sensibles a los dem\u00e1s, que nos preocupemos por los ancianos, los ni\u00f1os, los enfermos, los pobres, los alejados de Dios&#8230;<\/li>\n<li>Por nuestro mundo, tan necesitado de paz, de justicia, de fraternidad: que venga a la tierra el Reino de Dios&#8230; <em>(se pueden a\u00f1adir otras peticiones&#8230;).<\/em><\/li>\n<\/ul>\n<p>Oremos:<\/p>\n<p>Se\u00f1ora, Virgen Milagrosa: despu\u00e9s de estos momentos feli\u00adces en torno a ti, volvemos a nuestras ocupaciones habituales. Tu imagen se ir\u00e1 a otra casa, pero t\u00fa quedas en la nuestra y en nuestros corazones. Tu Medalla nos acompa\u00f1a y nos protege. Al igual que te cantamos en los templos, te decimos ahora con el mayor fervor:<\/p>\n<p>\u00abVen con nosotros al caminar, Santa Mar\u00eda, ven\u00bb.<\/p>\n<h2><strong>2. Oraci\u00f3n comunitaria semanal a la Inmaculada de la Medalla Milagrosa<\/strong><\/h2>\n<ul>\n<li><strong>Introducci\u00f3n:<\/strong><\/li>\n<\/ul>\n<p><em>Monici\u00f3n: <\/em>Hermanos, \u00e9sta es la hora de la oraci\u00f3n en com\u00fan. Sabemos que Jesucristo prometi\u00f3 una asistencia espe\u00adcial donde hubiera dos o m\u00e1s reunidos en su nombre. Nosotros nos reunimos como los primeros cristianos para acudir a \u00e9l por mediaci\u00f3n de Mar\u00eda nuestra Madre.<\/p>\n<p><strong>Canto:<\/strong><\/p>\n<p><em>Oh Mar\u00eda sin pecado concebida&#8230; u otro canto breve.<\/em><\/p>\n<p><strong>Oraci\u00f3n:<\/strong><em><\/em><\/p>\n<p>Bajo tu protecci\u00f3n nos acogemos, Santa Madre de Dios. No deseches las s\u00faplicas que te dirigimos en nuestras necesidades; antes bien, l\u00edbranos siempre de todo peligro, oh Virgen gloriosa y bendita.<strong><\/strong><\/p>\n<p><strong>Palabra:<\/strong><\/p>\n<p><em>Lectura de un pasaje de la Biblia<\/em>.<\/p>\n<p><strong>Meditaci\u00f3n<\/strong><\/p>\n<p><em>(el que preside puede comentar brevemente el pasaje le\u00eddo; o bien se guarda silencio para meditar en \u00e9l por unos minutos).<\/em><strong><\/strong><\/p>\n<p><strong>Oraci\u00f3n:<\/strong><\/p>\n<p>Comentario y formulaci\u00f3n de peticiones <em>(si se han presentado peticiones por escrito durante la semana, se pueden notificar y comentar por el que preside, algunas de ellas, resaltando su conteni\u00addo \u00abcristiano\u00bb, su expresi\u00f3n peculiar, etc., todo en orden a educar en la verdadera oraci\u00f3n. Despu\u00e9s se invita a los presentes a expresar en silencio sus plegarias al Se\u00f1or por mediaci\u00f3n de Mar\u00eda: sus necesida\u00addes particulares: las necesidades del mundo, las de la Iglesia, las intenciones del Papa&#8230; Cada uno en silencio, pero todos unidos en esp\u00edritu, y todos con sentido universalista y eclesial).<\/em><\/p>\n<p>Letan\u00eda <em>( se contesta: <\/em>\u00abRuega por nosotros que recurrimos a ti\u00bb).<\/p>\n<ul>\n<li>Mar\u00eda, que por tu Inmaculada Concepci\u00f3n nos ofreces el rostro del hombre nuevo redimido por Cristo&#8230;<\/li>\n<li>Mar\u00eda, que en el \u00abh\u00e1gase\u00bb de la Anunciaci\u00f3n te haces Madre de Dios, del Cristo hist\u00f3rico, cuando el Esp\u00edritu Santo te cubre con su sombra&#8230;<\/li>\n<li>Mar\u00eda, que serviste a Isabel anunci\u00e1ndole el Evangelio con las palabras del Magnificat&#8230;<\/li>\n<li>Mar\u00eda, que en la boda de Can\u00e1 fijaste tu atenci\u00f3n en lo que era necesario para la fiesta&#8230;<\/li>\n<li>Mar\u00eda, perfecta disc\u00edpula que te abres a la palabra y te dejas penetrar por su fuerza&#8230;<\/li>\n<li>Mar\u00eda, que en vez de rechazar o hacer a un lado la palabra cuando no la comprendes y te causa sorpresa, la meditas y la guardas&#8230;<\/li>\n<li>Mar\u00eda, Madre nuestra por haber cooperado con tu amor en el momento en que del Coraz\u00f3n traspasado de Cristo nac\u00eda la familia de los redimidos&#8230;<\/li>\n<li>Mar\u00eda, por quien la vida de Cristo irrumpe, victoriosa, en Pentecost\u00e9s&#8230;<\/li>\n<li>Mar\u00eda, a quien la Iglesia, instruida por el Esp\u00edritu Santo, venera con afecto de piedad filial como a Madre amant\u00ed\u00adsima&#8230;<\/li>\n<li>Mar\u00eda, en cuya Asunci\u00f3n se nos manifiesta el sentido y el destino del cuerpo sanl:acado por la gracia&#8230; Mar\u00eda, que cuidas con amor materno de los hermanos, todav\u00eda peregrinos, de tu Hijo&#8230;<\/li>\n<li>Mar\u00eda, especialmente cuidadosa de que los cristianos tengan vida abundante y lleguen a la madurez de la plenitud de Cristo&#8230;<\/li>\n<li>Mar\u00eda, que constituyes el gran signo del rostro maternal y misterioso de la cercan\u00eda del Padre&#8230;<\/li>\n<li>Mar\u00eda, presencia femenina que crea la voluntad de amor y de acogida&#8230;<\/li>\n<li>Mar\u00eda, que suscitas en los creyentes las plegarias de la ternura, del dolor y de la esperanza&#8230;<\/li>\n<li>Mar\u00eda, que nos has dado en la Medalla Milagrosa un signo de lo que eres, de lo que nos quieres y de lo que quieres para nosotros&#8230;<\/li>\n<\/ul>\n<p><strong>Oraci\u00f3n final:<\/strong><\/p>\n<p>Te rogamos, Se\u00f1or, que venga en nuestra ayuda la interce\u00adsi\u00f3n poderosa de la Virgen Mar\u00eda, para que nos veamos libres de todo peligro y podamos alegrarnos de vivir en paz contigo. Por nuestro Se\u00f1or Jesucristo. Am\u00e9n.<\/p>\n<p><strong>Canto final&#8230;<\/strong><strong><\/strong><\/p>\n<h2><strong><\/strong><strong>3. El d\u00eda 27 de cada mes<\/strong><\/h2>\n<p>Es el aniversario de la Aparici\u00f3n de la Medalla Milagrosa. D\u00eda de recuerdo, de revisi\u00f3n y de renovaci\u00f3n en la fidelidad siguiendo a la Virgen fiel y Madre de los creyentes. \u00abLa fiesta principal de la Asociaci\u00f3n es el d\u00eda 2 7 de noviembre, en el cual se conmemora la Aparici\u00f3n de la Inmaculada Virgen de la Sagrada Medalla\u00bb (art\u00edculo VI de los Estatutos generales de la Asociaci\u00f3n, Breve \u00abDilectus Filius\u00bb).<strong><\/strong><\/p>\n<h2><strong><\/strong><strong>4. Ritual de la bendici\u00f3n e imposici\u00f3n de la Medalla<\/strong><\/h2>\n<ul>\n<li>Nuestro auxilio es el nombre del Se\u00f1or. Que hizo el cielo y la tierra.<\/li>\n<li>El Se\u00f1or est\u00e9 con vosotros. Y con tu esp\u00edritu.<\/li>\n<\/ul>\n<p>Oremos: Dios omnipotente y misericordioso que has obrado continuamente maravillas en la tierra para la salvaci\u00f3n de los hombres por medio de la Inmaculada Virgen Mar\u00eda: concede benigno tu bendici\u00f3n ( + ) a este signo de la Medalla, para que, vener\u00e1ndola con piedad y llev\u00e1ndola con devoci\u00f3n, experimen\u00adtemos el patrocinio de Mar\u00eda y consigamos tu misericordia. Por Jesucristo nuestro Se\u00f1or. Am\u00e9n.<\/p>\n<p><em>(Bendecidas las medallas, se imponen a continuaci\u00f3n, diciendo):<\/em><\/p>\n<p>Recibid la santa Medalla, llevadla con fidelidad y honradla con veneraci\u00f3n, para que la piadosa e inmaculada Reina del cielo os proteja y defienda y, renovando los signos de su bondad, os obtenga lo que supliqu\u00e9is al Se\u00f1or, a fin de que, en la vida y en la hora de la muerte, descans\u00e9is felizmente en su maternal abrazo. Am\u00e9n.<\/p>\n<ul>\n<li>Se\u00f1or, ten piedad&#8230; Cristo, ten piedad&#8230; Se\u00f1or, ten piedad&#8230;<\/li>\n<li>Padre nuestro&#8230;<\/li>\n<li>Se\u00f1or, escucha mi oraci\u00f3n. Y llegue a ti mi clamor.<\/li>\n<\/ul>\n<p>Oremos: Se\u00f1or Jesucristo, que quisiste glorificar con innu\u00admerables milagros a tu Madre, la Sant\u00edsima Virgen Inmacula\u00adda: conc\u00e9denos que, implorando siempre su protecci\u00f3n, consi\u00adgamos los gozos eternos. Que vives y reinas por los siglos de los siglos. Am\u00e9n.<\/p>\n<ul>\n<li>Oh Mar\u00eda, sin pecado concebida: Ruega por nosotros que recurrimos a ti.<\/li>\n<\/ul>\n<h2><strong>5. Ma\u00f1anitas a la Virgen Milagrosa<\/strong><\/h2>\n<ul>\n<li>Estas son las ma\u00f1anitas<br \/>\nque cantaba el rey David;<br \/>\nhoy, por ser d\u00eda de tu santo,<br \/>\nte las cantamos a ti.<\/li>\n<\/ul>\n<p><strong>DESPIERTA, MADRE, DESPIERTA,<\/strong><br \/>\n<strong>MIRA QUE YA AMANECI\u00d3<\/strong><br \/>\n<strong>Y VENIMOS A CANTARTE<\/strong><br \/>\n<strong>PORQUE TU FIESTA LLEG\u00d3.<\/strong><\/p>\n<ul>\n<li>Veintisiete de noviembre fue el d\u00eda en que se mostr\u00f3 tu Medalla Milagrosa para nuestra bendici\u00f3n&#8230;<\/li>\n<li>Los dos brazos hacia el mundo tiendes, Madre, con amor, para derramar la gracia en quien pide tu favor&#8230;<\/li>\n<li>Son tus rayos de las gracias el signo y la mediaci\u00f3n y es tu rostro la alegr\u00eda del santo y del pecador&#8230;<\/li>\n<li>Con tus pies el mal aplastas y tu Santa Concepci\u00f3n nos anuncia la victoria en las luchas del Se\u00f1or.<\/li>\n<li>Junto a la Cruz va tu nombre en estrecha y fuerte uni\u00f3n: con Jes\u00fas caminas siempre en el gozo y el dolor.<\/li>\n<li>Tu coraz\u00f3n con el suyo se enlazan en redenci\u00f3n por la cruz del sufrimiento, por las llamas del amor.<\/li>\n<li>Doce Estrellas te rodean: son la Iglesia que, en fervor, te proclama Sierva y Reina, Madre suya y del Se\u00f1or.<\/li>\n<li>Tu Medalla llevaremos junto a nuestro coraz\u00f3n como el retrato m\u00e1s bello que de ti nos dio el Se\u00f1or.<\/li>\n<li>Oh Mar\u00eda, sin pecado concebida, \u00f3yenos: ruega siempre por nosotros y danos tu bendici\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Los cultos m\u00e1s practicados para honrar a la Virgen Mila\u00adgrosa son, aparte del Novenario anual en el mes de noviembre, el de la Visita Domiciliaria, el de la Novena Perpetua u Oraci\u00f3n comunitaria semanal, y &#8230; <a href=\"https:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":400140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-52974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-virgen-maria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Devociones a la Medalla Milagrosa - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Devociones a la Medalla Milagrosa - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Los cultos m\u00e1s practicados para honrar a la Virgen Mila\u00adgrosa son, aparte del Novenario anual en el mes de noviembre, el de la Visita Domiciliaria, el de la Novena Perpetua u Oraci\u00f3n comunitaria semanal, y ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-17T07:35:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886\" \/>\n\t<meta property=\"og:image:width\" content=\"1771\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Devociones a la Medalla Milagrosa\",\"datePublished\":\"2019-02-17T07:35:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/\"},\"wordCount\":1935,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1\",\"articleSection\":[\"Virgen Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/\",\"name\":\"Devociones a la Medalla Milagrosa - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1\",\"datePublished\":\"2019-02-17T07:35:57+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1\",\"width\":1771,\"height\":886},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/devociones-a-la-medalla-milagrosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devociones a la Medalla Milagrosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Devociones a la Medalla Milagrosa - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/","og_locale":"es_ES","og_type":"article","og_title":"Devociones a la Medalla Milagrosa - Somos Vicencianos","og_description":"Los cultos m\u00e1s practicados para honrar a la Virgen Mila\u00adgrosa son, aparte del Novenario anual en el mes de noviembre, el de la Visita Domiciliaria, el de la Novena Perpetua u Oraci\u00f3n comunitaria semanal, y ... Read More","og_url":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2019-02-17T07:35:57+00:00","og_image":[{"width":1771,"height":886,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Devociones a la Medalla Milagrosa","datePublished":"2019-02-17T07:35:57+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/"},"wordCount":1935,"commentCount":1,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1","articleSection":["Virgen Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/","url":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/","name":"Devociones a la Medalla Milagrosa - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1","datePublished":"2019-02-17T07:35:57+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1","width":1771,"height":886},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/devociones-a-la-medalla-milagrosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Devociones a la Medalla Milagrosa"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-dMq","jetpack-related-posts":[{"id":53073,"url":"https:\/\/vincentians.com\/es\/novena-a-la-medalla-milagrosa-dia-8-la-familia-de-la-medalla-milagrosa\/","url_meta":{"origin":52974,"position":0},"title":"Novena a la Medalla Milagrosa: D\u00eda 8, La familia de la Medalla Milagrosa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/11\/2011","format":false,"excerpt":"Introducci\u00f3n Canto: Oh Mar\u00eda, sin pecado concebida, ruega por nosotros que recurrimos a ti. Saludo: Hijos m\u00edos, mostraos celadores de la ley y dad la vida por la Alianza de vuestros mayores. Acordaos de las haza\u00f1as de vuestros padres en sus d\u00edas y alcanzar\u00e9is gran gloria y nombre eterno (1\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":115978,"url":"https:\/\/vincentians.com\/es\/familia-vicenciana-y-medalla-milagrosa\/","url_meta":{"origin":52974,"position":1},"title":"Familia Vicenciana y Medalla Milagrosa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/11\/2022","format":false,"excerpt":"Lo que ha sido este legado desde 1830 El testimonio de la Historia nos dice que, si bien la Virgen se aparece a Santa Catalina Labour\u00e9, \u00e9sta, cumpliendo los deseos manifestados por la Madre de Dios, permanece oculta, desconocida, en el silencio m\u00e1s incomprensible; un silencio que a veces se\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":53126,"url":"https:\/\/vincentians.com\/es\/la-visita-domiciliaria-de-la-virgen-milagrosa\/","url_meta":{"origin":52974,"position":2},"title":"La visita domiciliaria de la Virgen Milagrosa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/02\/2015","format":false,"excerpt":"Iniciada en Espa\u00f1a por los PP. Pa\u00fales y las Hijas de la Caridad, all\u00e1 por el a\u00f1o 1913. \u00bfQu\u00e9 es la visita domiciliaria? Es un apostolado de la Asociaci\u00f3n de la Me\u00addalla Milagrosa, cuya finalidad es promover el culto a la Inmaculada, buscar la santificaci\u00f3n y formaci\u00f3n de sus miembros\u2026","rel":"","context":"En \u00abAsociaci\u00f3n de la Medalla Milagrosa\u00bb","block_context":{"text":"Asociaci\u00f3n de la Medalla Milagrosa","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/asociacion-de-la-medalla-milagrosa\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/visita_domiciliaria_milagrosa-300x217.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":52972,"url":"https:\/\/vincentians.com\/es\/asociaciones-eclesiales-relativas-a-la-medalla-milagrosa\/","url_meta":{"origin":52974,"position":3},"title":"Asociaciones eclesiales relativas a la Medalla Milagrosa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"15\/02\/2019","format":false,"excerpt":"Dos son las Asociaciones eclesiales relativas a la Medalla Milagrosa: las Hijas e Hijos de Mar\u00eda y la Asociaci\u00f3n de la Inmaculada Concepci\u00f3n de la Sagrada Medalla. Hijas e Hijos de Mar\u00eda Las Hijas e Hijos de Mar\u00eda han dado origen u ocasi\u00f3n a las Juventudes Marianas o Juventudes Marianas\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1200%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1200%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1200%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1200%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":53041,"url":"https:\/\/vincentians.com\/es\/novena-a-la-medalla-milagrosa-dia-1-maria-instrumento-de-salvacion\/","url_meta":{"origin":52974,"position":4},"title":"Novena a la Medalla Milagrosa: D\u00eda 1, Mar\u00eda, instrumento de salvaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/11\/2011","format":false,"excerpt":"Introducci\u00f3n Canto: Oh Mar\u00eda, sin pecado concebida, ruega por nosotros que recurrimos a ti. Saludo: Hermanos: Llenaos del Esp\u00edritu, recitad entre vosotros salmos, himnos y c\u00e1nticos inspirados; cantad y salmodiad en vuestro coraz\u00f3n al Se\u00f1or, dando gracias continuamente y por todo a Dios Padre, en nombre de nuestro Se\u00f1or Jesucristo\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":117065,"url":"https:\/\/vincentians.com\/es\/la-basilica-de-la-milagrosa-madrid-tiene-larga-historia\/","url_meta":{"origin":52974,"position":5},"title":"La Bas\u00edlica de La Milagrosa en Madrid tiene larga historia","author":"Mitxel Olabu\u00e9naga","date":"03\/08\/2021","format":false,"excerpt":"Con motivo de sus Bodas de Oro vocacionales, el P. Eladio Ar\u00adn\u00e1iz hizo un viaje a Roma, y durante su estancia en la ciudad, el Papa P\u00edo X le recibi\u00f3 en audiencia. Luego, a su regreso a Espa\u00f1a, como Director de las Hijas de la Caridad de la entonces enorme\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision-en-espana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/52974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=52974"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/52974\/revisions"}],"predecessor-version":[{"id":402117,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/52974\/revisions\/402117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/400140"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=52974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=52974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=52974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}