{"id":50681,"date":"2016-12-28T12:00:10","date_gmt":"2016-12-28T11:00:10","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/09\/san-vicente-de-paul-biografia-de-roman-08-el-descubrimiento-de-una-vocacion\/"},"modified":"2016-08-20T07:35:08","modified_gmt":"2016-08-20T05:35:08","slug":"san-vicente-paul-biografia-08-descubrimiento-una-vocacion","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/","title":{"rendered":"San Vicente de Pa\u00fal, biograf\u00eda: 08 &#8211; El descubrimiento de una vocaci\u00f3n"},"content":{"rendered":"<h2><strong>Cap\u00edtulo VIII: El descubrimiento de una vocaci\u00f3n<\/strong><\/h2>\n<h3>Raza de capitanes<\/h3>\n<p>Obediente a las \u00f3rdenes de B\u00e9rulle, el Sr. Vicente abandonaba a finales de 1613 su parroquia de Clichy e iba a instalarse, con su parco equipaje, en la residencia parisiense de los se\u00f1ores de Gondi, en la calle de Petits Champs, en la parroquia de San Eustaquio. Por segunda vez iba a vivir en un palacio, quiz\u00e1 algo menos suntuoso que el de la reina Margarita, pero tambi\u00e9n espl\u00e9ndido. Los Gondi eran, al fin y al cabo, una de las principales familias del reino y hab\u00edan heredado, con su sangre florentina, el gusto renacentista por el lujo y el refinamiento.<\/p>\n<p>El primer Gondi establecido en Francia se llamaba Antonio. Era banquero de profesi\u00f3n y sus intereses financieros le hab\u00edan llevado a Ly\u00f3n a principios del siglo XVI. En la ciudad del R\u00f3dano contrajo matrimonio con una noble dama de origen piamont\u00e9s: Mar\u00eda Catalina de Pierre Vive. Los negocios no marchaban bien, pero el matrimonio encontr\u00f3 otros medios de hacer fortuna. Con ocasi\u00f3n de un viaje de Catalina de M\u00e9dicis a Ly\u00f3n, acertaron a granjearse la simpat\u00eda de su regia compatriota. Antonio fue nombrado mayordomo del delf\u00edn, Enrique III, y Mar\u00eda Catalina, gobernante de los infantes. Era un r\u00e1pido ascenso. El de sus dos hijos lo fue m\u00e1s todav\u00eda. El mayor, llamado Alberto, lleg\u00f3 a ser marqu\u00e9s de Belle Isle y de las Islas de Oro, par y mariscal de Francia, general\u00edsimo de los ej\u00e9rcitos reales, general de las galeras, gobernador de Provenza, Metz y Nantes y, por su matrimonio con Catalina de Clermont, duque de Retz. Llevado de su genio florentino para la intriga, fue uno de los principales instigadores de la matanza de San Bartolom\u00e9, de la que, seg\u00fan \u00e9l, no deb\u00eda excluirse ni siquiera al rey de Navarra, el futuro Enrique IV. Ello no le impidi\u00f3 ser luego ferviente partidario del pretendiente hugonote y retener bajo el reinado de \u00e9ste todos sus t\u00edtulos y privilegios. En otro terreno, el eclesi\u00e1stico, la carrera de su hermano Pedro no fue menos mete\u00f3rica. A los treinta y dos a\u00f1os era obispo de Langres, y a los treinta y cinco, de Par\u00eds. Carlos IX le nombr\u00f3 su confesor y jefe de su Consejo. Enrique IV le encomend\u00f3 la espinosa tarea de negociar ante el papa Clemente VIII la absoluci\u00f3n del delito de herej\u00eda y, m\u00e1s tarde, la anulaci\u00f3n de su matrimonio con Margarita de Valois. En recompensa de sus servicios fue elevado al cardenalato.<\/p>\n<p>Del matrimonio de Alberto de Gondi y Catalina de Clermont nacieron cuatro hijos varones. Dos de ellos, Enrique y Juan Francisco, sucedieron, uno tras otro, a su t\u00edo Pedro en la sede episcopal de Par\u00eds. Enrique, coadjutor con derecho a sucesi\u00f3n desde 1596, gobern\u00f3 la di\u00f3cesis durante los \u00faltimos a\u00f1os de su vida de su t\u00edo y le sucedi\u00f3 en 1616. A \u00e9l era a quien Vicente hab\u00eda declarado sentirse en su parroquia de Clichy m\u00e1s feliz que el papa. Muri\u00f3 de la \u00abfiebre del ej\u00e9rcito\u00bb mientras acompa\u00f1aba al rey Luis XIII en el sitio de B\u00e9ziers. Fue tambi\u00e9n cardenal, el primer cardenal de Retz. Juan Francisco, que hab\u00eda sido primero capuchino y luego de\u00e1n de Notre Dame y coadjutor de su hermano fue consagrado en 1623. No lleg\u00f3 a cardenal, pero, en cambio, tuvo la satisfacci\u00f3n de ver su sede, hasta entonces sufrag\u00e1nea de Sens, elevada a la categor\u00eda de arzobispado. Fue, por tanto, el primer arzobispo de Par\u00eds. Su pontificado dur\u00f3 m\u00e1s de treinta a\u00f1os. Con frecuencia tendremos que volver a ocuparnos de \u00e9l en el transcurso de nuestra historia.<\/p>\n<p>Entre las hijas de Alberto de Gondi, dos de las cuales fueron religiosas en la abad\u00eda de Poisy, destaca, como una delicada flor de santidad en esta raza de pol\u00edticos y militares intrigantes y pendencieros, Carlota de Gondi, m\u00e1s conocida como marquesa de Maignalais por su matrimonio con Florimundo d&#8217;Halwin, de quien qued\u00f3 viuda a los veinte a\u00f1os, para pasar el resto de su vida consagrada, en su persona y su fortuna, a toda clase de actividades religiosas y caritativas.<\/p>\n<p>Los otros dos varones de esta tercera generaci\u00f3n de los Gondi franceses se llamaban Carlos y Felipe Manuel. Ambos siguieron la carrera de armas. Carlos sucedi\u00f3 a su padre en el ducado de Retz y otros t\u00edtulos, cas\u00f3 con Antonieta de Orle\u00e1ns, de la casa real de Francia, y llev\u00f3 una existencia relativamente tranquila. Felipe Manuel hered\u00f3 el generalato de las galeras y los t\u00edtulos de marqu\u00e9s de las Islas de Oro, conde de Joigny y bar\u00f3n de Montmirail, Dampierre y Villepreux. Era un caballero galante y distinguido, de esp\u00edritu ameno e ingenioso, valiente hasta la temeridad; pero, en el fondo, recto y sinceramente piadoso. En 1600 contrajo matrimonio con Margarita de Silly, se\u00f1ora de Folleville, \u00e9mula de su cu\u00f1ada Carlota en la piedad y en la abnegaci\u00f3n. La familia, adem\u00e1s del castillo familiar de Montmirail y otras residencias campestres, en las que pasaban largas temporadas, ten\u00eda domicilio en Par\u00eds, primero en la calle de Petits Champs y luego en la calle Pav\u00e9e. En esta casa, entonces en el apogeo de su fortuna, entr\u00f3 Vicente de Pa\u00fal en 1613. El motivo de que los esposos Gondi solicitaran del P. B\u00e9rulle un sacerdote para su servicio fue la necesidad de contar con un preceptor para sus hijos. B\u00e9rulle no pod\u00eda desprenderse de ning\u00fan compa\u00f1ero de su incipiente y reducida comunidad del Oratorio. Pens\u00f3 en Vicente. Seguramente pes\u00f3 en su elecci\u00f3n lo que sab\u00eda de la historia de \u00e9ste como preceptor en su adolescencia de los hijos de Comet y director en su juventud de un pensionado en Toulouse. No le ser\u00eda dif\u00edcil al dichoso p\u00e1rroco de Clichy reanudar su antiguo trabajo. Vicente obedeci\u00f3.<\/p>\n<p>El general de las galeras ten\u00eda dos hijos: Pedro, de once a\u00f1os, y Enrique, de tres. El mayor, heredero de la casa, general de las galeras en sustituci\u00f3n de su padre, intervendr\u00eda en la pol\u00edtica, siempre en la oposici\u00f3n, primero a Richelieu, cuyo asesinato llegar\u00eda a maquinar, y luego a Mazarino. El segundo, destinado a la carrera eclesi\u00e1stica, ver\u00eda tronchada su vida a la temprana edad de doce a\u00f1os, v\u00edctima de un accidente de caballo. Un tercer v\u00e1stago, llamado a ser el m\u00e1s famoso, nac\u00eda ese mismo a\u00f1o de 1613, pocos d\u00edas antes o despu\u00e9s de la entrada de Vicente en la casa, pues fue bautizado el 20 de septiembre. Se le impusieron los nombres de Juan Francisco Pablo. Pero la historia lo conoce como el Cardenal de Retz, el terrible cardenal de Retz de los turbulentos a\u00f1os de la Fronda, cuyas escandalosas memorias constituyen el m\u00e1s c\u00ednico testimonio de las grandezas y miserias de toda una \u00e9poca<span id='easy-footnote-1-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-1-50681' title='Cf. J. Corbinelli, &lt;em&gt;Histoire g\u00e9n\u00e9alogique de la maison des Gondi&lt;\/em&gt; (Par\u00eds, J.-B. Coignard, 1705) 2 vols; R. Chantelauze, &lt;em&gt;Saint Vincent de Paul et les Gondi&lt;\/em&gt; (Par\u00eds 1882) p. 83-89.'><sup>1<\/sup><\/a><\/span>.<\/p>\n<h3>Lluvia de beneficios<\/h3>\n<p>Vicente se dispuso silenciosamente a desempe\u00f1ar sus funciones. Silenciosamente, porque segu\u00eda viviendo su atormentado drama interior. Adem\u00e1s, en 1615 padeci\u00f3 una grave enfermedad de las piernas que le oblig\u00f3 a redoblar su retiro, Y de la que se resentir\u00eda toda la vida<span id='easy-footnote-2-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-2-50681' title='&lt;em&gt;Ristretto cronologico&amp;#8230;&lt;\/em&gt;, p. 20-21; Collet, o.c., t.1 p. 46.'><sup>2<\/sup><\/a><\/span>. Quiz\u00e1 por todo ello viv\u00eda en aquella casa, tan frecuentada por toda clase de personas, \u00abcomo en una cartuja, y en su habitaci\u00f3n, como en la celda de un convento\u00bb<span id='easy-footnote-3-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-3-50681' title='Abelly, o.c., L.1 c.7 p. 28.'><sup>3<\/sup><\/a><\/span>. La gracia continuaba en \u00e9l su misterioso trabajo purificador. Los Gondi apreciaron muy pronto la val\u00eda de aquel discreto hu\u00e9sped y se esforzaron por gan\u00e1rselo definitivamente, acumulando sobre \u00e9l los beneficios: en 1614 hac\u00edan que se le concediera la parroquia de Gamaches, de la di\u00f3cesis de Rouen, cuyo derecho de presentaci\u00f3n correspond\u00eda al conde de Joigny<span id='easy-footnote-4-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-4-50681' title='M. y Ch. 8 (1961) p. 495.'><sup>4<\/sup><\/a><\/span>, y en 1615, el cargo de can\u00f3nigo-tesorero de la iglesia-colegiata de Ecouls, de la que tambi\u00e9n era patr\u00f3n Manuel de Gondi. De este \u00faltimo cargo, seguramente a causa de su enfermedad, Vicente tom\u00f3 posesi\u00f3n por procurador el 27 de mayo. Cuatro meses m\u00e1s tarde, el 18 de septiembre, hac\u00eda acto de presencia en la colegiata para prestar el juramento de fidelidad y recibir el \u00abosculum pacis\u00bb de sus compa\u00f1eros. Al d\u00eda siguiente, conform\u00e1ndose a las costumbres del cabildo, los invitaba a la mesa \u00abpro suo iucundo adventu\u00bb<span id='easy-footnote-5-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-5-50681' title='S.V.P. XIII p. 19-22.'><sup>5<\/sup><\/a><\/span>. Los beneficios, por los que tanto hab\u00eda trabajado en a\u00f1os anteriores, empezaban a acumularse sobre \u00e9l. Al empezar el a\u00f1o 1616, el preceptor de los Gondi era, simult\u00e1neamente, p\u00e1rroco de Clichy, abad de San Leonardo de Chaumes, cura de Gamaches, can\u00f3nigo y tesorero de Ecouis. La carrera so\u00f1ada en los a\u00f1os ya lejanos de Dax y Toulouse estaban alcanzando sus metas. De haberse contentado con ellas, probablemente la vida de Vicente de Pa\u00fal hubiera acabado en estos momentos para la historia. Afortunadamente, el viraje decisivo iniciado en los meses anteriores estaba a punto de consumarse. Acaso sin haberlo le\u00eddo, Vicente se dispon\u00eda a desmentir el ingenioso dicho teresiano: \u00abIban para santos y se quedaron en can\u00f3nigos\u00bb.<\/p>\n<p>De la parroquia de Gamaches no sabemos siquiera si lleg\u00f3 a tomar posesi\u00f3n. El \u00fanico documento que se conserva es el de la colaci\u00f3n del beneficio. De la abad\u00eda de San Leonardo se desprendi\u00f3, como ya vimos, en el curso de ese a\u00f1o de 1616<span id='easy-footnote-6-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-6-50681' title='S.V.P. XIII p. 37-39.'><sup>6<\/sup><\/a><\/span>. De Ecouis se conservan las actas del cabildo, en que le citan para que responda del incumplimiento de la obligaci\u00f3n de residencia, punto que \u00abamenaza con arruinar por completo la fundaci\u00f3n\u00bb<span id='easy-footnote-7-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-7-50681' title='S.V.P. XIII p. 22-24.'><sup>7<\/sup><\/a><\/span>. Sendas cartas de la generala de las galeras y del duque de Retz, hermano del general y copatr\u00f3n de la iglesia, persuadieron a los can\u00f3nigos a ampliar en quince d\u00edas el plazo dado al se\u00f1or \u00abde Paoul\u00bb (es la \u00fanica vez que vemos escrito su apellido con esa ortograf\u00eda) para justificar su ausencia<span id='easy-footnote-8-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-8-50681' title='S.V.P. XIII p. 25.'><sup>8<\/sup><\/a><\/span>. La falta de documentos nos impide conocer el desenlace del conflicto. La carencia de toda menci\u00f3n ulterior del canonicato de Ecouis nos induce a sospechar que Vicente acab\u00f3 por desprenderse de \u00e9l.<\/p>\n<p>El silencioso retiro que se hab\u00eda impuesto no imped\u00eda a Vicente cumplir concienzudamente sus deberes de capell\u00e1n y preceptor. Evidentemente, no se ocupaba para nada del reci\u00e9n nacido Juan Pablo. A los dos ni\u00f1os mayores les iniciaba en los secretos de la lengua latina y se esforzaba por inculcarles criterios de vida cristiana. Pero no estaba satisfecho. Aquellos muchachos de sangre noble y ardiente, como todos sus antepasados italianos y franceses, eran menos maleables que los modestos jovencitos provincianos de Toulouse. Vicente llegar\u00eda a experimentar una dolorosa sensaci\u00f3n de fracaso. En el fondo se sent\u00eda ocioso, como el afamado doctor de la casa de Margarita de Valois. Empez\u00f3 a trabajar por su cuenta. El cargo de capell\u00e1n le obligaba a acompa\u00f1ar a la familia en sus desplazamientos: a Joigny, Montmirail, Villepreux y otros lugares de sus extensos dominios. Vicente se dedicaba, cada vez con mayor intensidad, a la atenci\u00f3n religiosa de los criados y vasallos de sus se\u00f1ores. En la casa instru\u00eda a los dom\u00e9sticos, los visitaba en sus enfermedades, los consolaba en sus penas, y los preparaba, la v\u00edspera de las fiestas solemnes, para la recepci\u00f3n de los sacramentos. En el campo catequizaba a los aldeanos, les predicaba, les exhortaba a la confesi\u00f3n<span id='easy-footnote-9-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-9-50681' title='Abelly, o.c., L.1 c.7 p. 28.'><sup>9<\/sup><\/a><\/span>. Existe una carta suya fechada en 1616 en que solicita del vicario general de Sens licencia para absolver de casos reservados, porque \u00abalgunas veces se encuentran algunas buenas personas que desean hacer confesi\u00f3n general y da pena dejarlos marchar\u00bb por tener pecados reservados<span id='easy-footnote-10-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-10-50681' title='S.V.P. I p. 20: ES p. 90.'><sup>10<\/sup><\/a><\/span>. Poco a poco iba sondeando los abismos de abandono espiritual de aquella pobre gente campesina. Su coraz\u00f3n caritativo empezaba a latir de dolor ante la miseria. No otra cosa significa esa pena suya por los penitentes obligados a retirarse sin absoluci\u00f3n. Insensiblemente, se preparaba para el descubrimiento de su misi\u00f3n. Es l\u00e1stima que las vagas indicaciones de Abelly, seg\u00fan las cuales la tentaci\u00f3n contra la fe dur\u00f3 \u00abtres o cuatro a\u00f1os\u00bb, no nos permitan fijar con exactitud el momento en que Vicente formul\u00f3 la resoluci\u00f3n de entregarse de por vida al servicio de los pobres y se vio libre de su pesadilla. Evidentemente, coincide con la \u00e9poca de esta actividad itinerante por las tierras de los Gondi. No es casualidad que el primer serm\u00f3n suyo que se conserva sea de 1616 y tenga como tema la importancia de conocer bien el catecismo<span id='easy-footnote-11-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-11-50681' title='S.V.P. XIII p. 25-30.'><sup>11<\/sup><\/a><\/span>.<\/p>\n<h3>De capell\u00e1n a director de conciencia<\/h3>\n<p>Casi sin propon\u00e9rselo, la influencia de Vicente fue extendi\u00e9ndose tambi\u00e9n a los se\u00f1ores. Vicente hab\u00eda entrado en aquella casa con una voluntad de transfiguraci\u00f3n sobrenatural de las realidades terrestres. Lo explic\u00f3 \u00e9l mismo en diversas ocasiones:<\/p>\n<p style=\"padding-left: 30px;\">\u00abCuando Dios quiso llamarme a casa de la se\u00f1ora generala de las galeras, yo miraba al se\u00f1or general como a Dios, y a la se\u00f1ora generala como a la Sant\u00edsima Virgen; y no me acuerdo de haber recibido nunca sus \u00f3rdenes m\u00e1s que como venidas de Dios cuando era el se\u00f1or general el que mandaba algo, y de la Sant\u00edsima Virgen cuando era su esposa; no s\u00e9, por la gracia de Dios, que haya obrado nunca en contra de eso. Me atrevo a decir que, si Dios ha querido conceder alguna bendici\u00f3n a la Compa\u00f1\u00eda de la Misi\u00f3n, creo que ha sido por la obediencia que siempre tuve para con el se\u00f1or general y su se\u00f1ora y por el esp\u00edritu de sumisi\u00f3n con que entr\u00e9 en su casa. \u00a1Gloria a Dios por todo ello, y para m\u00ed la confusi\u00f3n!\u00bb<span id='easy-footnote-12-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-12-50681' title='S.V.P. IX p. 9; X p. 387: ES IX p. 27 y 958.'><sup>12<\/sup><\/a><\/span>.<\/p>\n<p>Por una vez, el Sr. Vicente no confesaba pecados, sino virtudes, y nos permit\u00eda con ello hacernos cargo del profundo cambio que se iba operando en su alma.<\/p>\n<p>La situaci\u00f3n no tard\u00f3 en invertirse. Los se\u00f1ores de Gondi empezaron a ver a su capell\u00e1n como un hombre providencial, verdadero enviado de Dios para la salvaci\u00f3n de su familia. La primera en darse cuenta de ello fue la se\u00f1ora. Margarita de Silly era un alma atribulada y compleja. Bella y delicada, con una belleza fr\u00e1gil como de dama de Ghirlandaio, era piadosa hasta el punto de preferir que sus hijos fueran antes santos del cielo que grandes se\u00f1ores de la tierra<span id='easy-footnote-13-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-13-50681' title='R. Chantelauze, o.c., p. 85.'><sup>13<\/sup><\/a><\/span>, como ella misma declar\u00f3 al P. B\u00e9rulle. Ve\u00eda a Dios m\u00e1s como juez que como padre. Se atormentaba a s\u00ed misma y atormentaba a sus confesores con escr\u00fapulos infundados. Antes de que Vicente llevara dos a\u00f1os en su casa, pens\u00f3 hacer de \u00e9l su director de conciencia. Ante la resistencia del capell\u00e1n, recurri\u00f3 a B\u00e9rulle, y Vicente obedeci\u00f3 una vez m\u00e1s. Empez\u00f3 a dirigir aquella alma con una energ\u00eda no exenta de dulzura y respeto. Ella hubiera querido tenerle siempre a su lado, temerosa de que un accidente o una enfermedad se lo arrebatasen. Vicente la obligaba a dirigirse a otros confesores, especialmente a cierto padre recoleto experto en direcci\u00f3n de almas. Suavemente intentaba desprenderla de s\u00ed mismo y ense\u00f1arle a depender s\u00f3lo de Dios<span id='easy-footnote-14-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-14-50681' title='Abelly, o.c., L.1 c.9 p. 36-37.'><sup>14<\/sup><\/a><\/span>. Aplic\u00e1ndole el remedio que hab\u00eda ensayado en s\u00ed mismo, la orient\u00f3 con firmeza hacia las obras de caridad: alentaba su natural desprendido y limosnero, la entrenaba en la visita personal a los pobres, a los que deb\u00eda servir con sus manos; le hac\u00eda preocuparse de que sus funcionarios administraran justicia con rectitud y rapidez<span id='easy-footnote-15-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-15-50681' title='Abelly, o.c., L.1 c.8 p. 31.'><sup>15<\/sup><\/a><\/span>. Aun as\u00ed, llegar\u00eda un momento en que Vicente se creer\u00eda obligado a alejarse para liberarse a s\u00ed mismo y librarla a ella del excesivo apego a su director. Pero antes habr\u00edan hecho juntos el descubrimiento capital de la vida de Vicente.<\/p>\n<p>El se\u00f1or de Gondi, aun apreciando tambi\u00e9n los m\u00e9ritos del preceptor de sus hijos, fue algo m\u00e1s reticente. Vicente se lo gan\u00f3 un d\u00eda en que, con singular libertad de esp\u00edritu, se atrevi\u00f3 a entrometerse en su conducta. Cediendo a los prejuicios de su \u00e9poca, Manuel de Gondi estaba para batirse en duelo. Hab\u00edan matado a un pariente suyo, y \u00e9l se cre\u00eda obligado a vengar el honor de la familia retando al asesino, un noble se\u00f1or de la corte. Antes de dirigirse al lugar del desaf\u00edo quiso cumplir como caballero cristiano oyendo la santa misa. \u00a1Curiosa religiosidad, que intentaba poner a Dios al servicio de las pasiones humanas! All\u00ed estaba Vicente para poner las cosas en su punto. Terminada la misa, y cuando la familia y los servidores se hab\u00edan retirado, Vicente fue a postrarse ante el se\u00f1or de la casa, que hab\u00eda permanecido unos momentos arrodillado en la capilla:<\/p>\n<p style=\"padding-left: 30px;\">\u00abSe\u00f1or &#8211; le dijo -, permita que con toda humildad le diga de parte de Dios, al que acabo de mostrarle y al que usted acaba de adorar, que, si no se aparta usted de ese malvado prop\u00f3sito, \u00e9l descargar\u00e1 su justicia sobre usted y sobre toda su posteridad. Dicho esto, el capell\u00e1n se retir\u00f3\u00bb<span id='easy-footnote-16-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-16-50681' title='S.V.P. XI p. 28: ES p. 720-721.'><sup>16<\/sup><\/a><\/span>.<\/p>\n<p>La valiente reconvenci\u00f3n produjo su efecto. El se\u00f1or Gondi renunci\u00f3 al duelo. Para olvidar su enojo emprendi\u00f3 una gira por sus tierras. El agresor fue condenado al exilio por la justicia<span id='easy-footnote-17-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-17-50681' title='Coste, M.V., t.1 p. 84.'><sup>17<\/sup><\/a><\/span>; Vicente se hab\u00eda ganado la confianza de su se\u00f1or.<\/p>\n<p>En los ocho a\u00f1os transcurridos desde su primera llegada a Par\u00eds, Vicente se hab\u00eda transformado. Era un hombre distinto, en plena posesi\u00f3n de los ricos recursos de naturaleza y gracia con que Dios le hab\u00eda dotado. Pose\u00eda una palabra elocuente y persuasiva, capaz de convencer las inteligencias y conmover los corazones, el arma por excelencia del ap\u00f3stol. Con ella hab\u00eda ahogado en el coraz\u00f3n del general la mala semilla del rencor vengativo y homicida.<\/p>\n<p>Con ella llevaba luz y consuelo a los corazones de los pobres aldeanos, esclavos de las mismas miserias que sus se\u00f1ores. Con ella hab\u00eda encauzado hacia metas caritativas la enfermiza sensibilidad de la se\u00f1ora de Gondi. Se hab\u00eda desprendido del lastre de sus mezquinas ambiciones de dignidades y prebendas bien retribuidas. Hab\u00eda ensanchado hasta l\u00edmites divinos el horizonte de sus aspiraciones. Estaba maduro para hacer el descubrimiento de su vocaci\u00f3n. Dios estaba pronto a revel\u00e1rsela.<\/p>\n<h3>Folleville: \u00abAqu\u00e9l fue el primer serm\u00f3n de misi\u00f3n\u201d<\/h3>\n<p>La revelaci\u00f3n vino por uno de esos acontecimientos imprevistos en los que la espiritualidad de Vicente se complacer\u00e1 en descubrir la voluntad de Dios. La Providencia se disfrazaba de azar.<\/p>\n<p>Un d\u00eda de enero de 1617 se encontraba Vicente acompa\u00f1ando a la se\u00f1ora de Gondi, en el castillo de Folleville, por tierras de Picard\u00eda. Desde la cercana localidad de Gannes, a dos leguas de distancia, lleg\u00f3 el aviso de que un campesino moribundo quer\u00eda ver al Sr. Vicente. Este acudi\u00f3 inmediatamente a la cabecera del enfermo. En el humilde tugurio, Vicente se sent\u00f3 junto al lecho del enfermo para o\u00edr su confesi\u00f3n. Le anim\u00f3 a que la hiciese general de toda su vida. El campesino empez\u00f3 a desgranar el triste rosario de sus pecados. Era m\u00e1s de lo que Vicente hab\u00eda sospechado. Aquel hombre ten\u00eda fama de honrado y virtuoso. Pero en su conciencia guardaba recelosamente miserias que nunca hab\u00eda revelado. A\u00f1o tras a\u00f1o, confesi\u00f3n tras confesi\u00f3n, hab\u00eda callado &#8211; verg\u00fcenza, ignorancia, hipocres\u00eda &#8211; las faltas m\u00e1s graves de su vida. Vicente tuvo el sentimiento de que, en un \u00faltimo momento de gracia, arrancaba un alma de las garras del maligno. El campesino sinti\u00f3 lo mismo. Los remordimientos de toda una vida abandonaron su alma. Respir\u00f3 liberado. De no haber sido por aquella confesi\u00f3n general, se hubiera condenado eternamente. Le invadi\u00f3 un gozo incontenible. Hizo entrar en la pobre estancia a su familia, a sus vecinos, a la misma se\u00f1ora de Gondi. Relat\u00f3 su caso. En los tres d\u00edas que a\u00fan vivi\u00f3 confes\u00f3 p\u00fablicamente pecados que antes no hab\u00eda osado revelar en secreto. Daba gracias a Dios, que le hab\u00eda salvado por medio de aquella confesi\u00f3n general. La se\u00f1ora de Gondi se estremeci\u00f3 de terror:<\/p>\n<p style=\"padding-left: 30px;\">\u00abSe\u00f1or Vicente: \u00bfqu\u00e9 es lo que acabamos de o\u00edr? Esto mismo les pasa, sin duda, a la mayor parte de estas gentes. Si este hombre, que pasaba por hombre de bien, estaba en estado de condenaci\u00f3n, \u00bfqu\u00e9 ocurrir\u00e1 con los dem\u00e1s, que viven tan mal? \u00a1Ay, Sr. Vicente, cu\u00e1ntas almas se pierden! \u00bfQu\u00e9 remedio podemos poner?\u00bb<span id='easy-footnote-18-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-18-50681' title='S.V.P. XI p. 4: ES p. 699.'><sup>18<\/sup><\/a><\/span>\n<p>De com\u00fan acuerdo, Vicente y la se\u00f1ora encontraron uno. La semana siguiente Vicente predicar\u00eda en la iglesia de Folleville un serm\u00f3n sobre la confesi\u00f3n general y la manera de hacerla bien. Se escogi\u00f3 para ello el mi\u00e9rcoles 25 de enero, fiesta de la Conversi\u00f3n de San Pablo. Vicente subi\u00f3 al p\u00falpito. Ten\u00eda ante \u00e9l al humilde pueblo campesino de todos los rincones de Francia: los mismos hombres, embrutecidos por el trabajo, de su lejano Pouy natal; las mismas mujeres ignorantes y piadosas; los mismos j\u00f3venes y los mismos ni\u00f1os, de rostros todav\u00eda intactos, pero cuyos ojos acusaban ya la mordedura secreta de la serpiente. Vicente ten\u00eda s\u00f3lo su palabra. Su palabra y su ardiente compasi\u00f3n por aquellos hermanos suyos abandonados. Predic\u00f3 con claridad y fuerza. Instruy\u00f3, conmovi\u00f3, arrastr\u00f3. \u00abDios bendijo mis palabras\u00bb, dice \u00e9l sobriamente, atribuyendo el m\u00e9rito de ello a la confianza y a la buena fe de la se\u00f1ora, pues sus propios pecados hubieran impedido el fruto de aquella acci\u00f3n. La gente, la pobre y buena gente, acudi\u00f3 en masa a confesarse. Vicente y el sacerdote que le acompa\u00f1aba no daban abasto. Hubo que pedir ayuda a los jesuitas de Ami\u00e9ns, de lo que se encarg\u00f3 la se\u00f1ora. Vino el rector en persona, sustituido luego por otro compa\u00f1ero suyo, el P. Fourch\u00e9. Aun as\u00ed se vieron desbordados por la afluencia de penitentes. Repitieron la predicaci\u00f3n y las exhortaciones en las aldeas vecinas, siempre con el mismo \u00e9xito clamoroso<span id='easy-footnote-19-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-19-50681' title='S.V.P. XI p. 2-5: ES p. 698-700; Abelly, o.c., L. 1 c.8 p. 31-35; Collet, o.c., t.1 p. 46-48.'><sup>19<\/sup><\/a><\/span>.<\/p>\n<p>Fue una revelaci\u00f3n. Vicente sinti\u00f3 que aqu\u00e9lla era su misi\u00f3n, aqu\u00e9lla era para \u00e9l la obra de Dios: llevar el Evangelio al pobre pueblo campesino. No fund\u00f3 nada aquel d\u00eda. Acaso, ni siquiera tuvo la idea de que hiciera falta una fundaci\u00f3n. S\u00f3lo predic\u00f3 un serm\u00f3n, \u00abel primer serm\u00f3n de misi\u00f3n\u00bb<span id='easy-footnote-20-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-20-50681' title='S.V.P. XI p. 5: ES p. 700.'><sup>20<\/sup><\/a><\/span>. Pasar\u00edan ocho a\u00f1os antes de que pusiera en marcha la Congregaci\u00f3n de la Misi\u00f3n. Y, sin embargo, toda su vida har\u00eda que sus misioneros celebraran el 25 de enero como la fiesta del nacimiento de la compa\u00f1\u00eda.<\/p>\n<p>Repetidas veces contar\u00eda, a lo largo de su vida, la historia de aquella primera misi\u00f3n, con variantes de inter\u00e9s. En la segunda versi\u00f3n que se nos conserva, de 25 de enero de 1655, el Sr. Vicente relat\u00f3 otro hecho que antes no se hab\u00eda atrevido a referir por vivir todav\u00eda algunas de las personas interesadas. Dej\u00e9mosle a \u00e9l la palabra:<\/p>\n<p style=\"padding-left: 30px;\">\u00abUn d\u00eda, siendo a\u00fan muchacha, la se\u00f1ora generala de las galeras, al confesarse con su p\u00e1rroco, se dio cuenta de que \u00e9ste no le daba la absoluci\u00f3n, murmuraba algo entre dientes, haciendo lo mismo otras veces que se confes\u00f3 con \u00e9l; aquello le preocup\u00f3 un poco, de modo que le pidi\u00f3 un d\u00eda a un religioso que fue a verla que le entregara por escrito la f\u00f3rmula de la absoluci\u00f3n; as\u00ed lo hizo. Y aquella buena se\u00f1ora, volviendo a confesarse, le rog\u00f3 al mencionado p\u00e1rroco que pronunciase sobre ella las palabras de la absoluci\u00f3n que conten\u00eda aquel papel; \u00e9l las ley\u00f3. Y as\u00ed sigui\u00f3 haci\u00e9ndolo las otras veces que se confes\u00f3 con \u00e9l, entreg\u00e1ndole siempre aquel papel, porque \u00e9l no sab\u00eda las palabras que hab\u00eda de pronunciar, tan ignorante era. Cuando ella me lo dijo, me fij\u00e9 y puse m\u00e1s atenci\u00f3n en aquellos con quienes me confesaba, y vi efectivamente que era verdad todo esto y que algunos no sab\u00edan las palabras de la absoluci\u00f3n\u00bb<span id='easy-footnote-21-50681' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#easy-footnote-bottom-21-50681' title='S.V.P. XI p. 170: ES p. 95.'><sup>21<\/sup><\/a><\/span>.<\/p>\n<p>Ya tenemos a Vicente en posesi\u00f3n de dos de los elementos b\u00e1sicos de su experiencia religiosa fundamental: la miseria espiritual de un pueblo cristiano que ha perdido el Evangelio, la pavorosa impreparaci\u00f3n de un clero que ignoraba las normas elementales del ejercicio de su ministerio. Eran tambi\u00e9n dos males que hab\u00eda denunciado vigorosamente el concilio de Trento, proponiendo para ello la labor catequ\u00e9tica y los centros de formaci\u00f3n sacerdotal. Francia acababa de aceptar por fin, como hemos dicho, los decretos tridentinos en 1615. Vicente estaba en estrecha relaci\u00f3n desde 1609 o 1610 con los ambientes m\u00e1s comprometidos en llevar a cabo la reforma de la Iglesia seg\u00fan las l\u00edneas conciliares. Hab\u00eda acometido con generosa resoluci\u00f3n su propia reforma personal. La Providencia le se\u00f1alaba cu\u00e1l deb\u00eda ser su contribuci\u00f3n a la gran labor colectiva que se avecinaba. \u00c9l la asumi\u00f3 gozosamente. Acontecimientos inmediatos completar\u00edan la revelaci\u00f3n que acababa de hac\u00e9rsele, descubri\u00e9ndole el tercer aspecto &#8211; y, en cierto sentido, el m\u00e1s importante &#8211; de su vocaci\u00f3n propia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cap\u00edtulo VIII: El descubrimiento de una vocaci\u00f3n Raza de capitanes Obediente a las \u00f3rdenes de B\u00e9rulle, el Sr. Vicente abandonaba a finales de 1613 su parroquia de Clichy e iba a instalarse, con su parco &#8230; <a href=\"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":149545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[186,218,148,194,175,193,145,119,125,131,172,117,179,188,120,128,135],"class_list":["post-50681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vicente-de-paul","tag-abadia-de-san-leonardo","tag-abelly","tag-clichy","tag-ecouis","tag-folleville","tag-gamaches","tag-gannes","tag-gondi","tag-joigny","tag-montmirail","tag-pobreza","tag-pouy","tag-reina-margarita","tag-san-leonardo","tag-senora-de-gondi","tag-silly","tag-villepreux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Vicente de Pa\u00fal, biograf\u00eda: 08 - El descubrimiento de una vocaci\u00f3n - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Vicente de Pa\u00fal, biograf\u00eda: 08 - El descubrimiento de una vocaci\u00f3n - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Cap\u00edtulo VIII: El descubrimiento de una vocaci\u00f3n Raza de capitanes Obediente a las \u00f3rdenes de B\u00e9rulle, el Sr. Vicente abandonaba a finales de 1613 su parroquia de Clichy e iba a instalarse, con su parco ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-28T11:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"San Vicente de Pa\u00fal, biograf\u00eda: 08 &#8211; El descubrimiento de una vocaci\u00f3n\",\"datePublished\":\"2016-12-28T11:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/\"},\"wordCount\":4561,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Abad\u00eda de San Leonardo\",\"Abelly\",\"Clichy\",\"Ecouis\",\"Folleville\",\"Gamaches\",\"Gannes\",\"Gondi\",\"Joigny\",\"Montmirail\",\"Pobreza\",\"Pouy\",\"Reina Margarita\",\"San Leonardo\",\"Se\u00f1ora de Gondi\",\"Silly\",\"Villepreux\"],\"articleSection\":[\"Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/\",\"name\":\"San Vicente de Pa\u00fal, biograf\u00eda: 08 - El descubrimiento de una vocaci\u00f3n - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2016-12-28T11:00:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Vicente de Pa\u00fal, biograf\u00eda: 08 &#8211; El descubrimiento de una vocaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Vicente de Pa\u00fal, biograf\u00eda: 08 - El descubrimiento de una vocaci\u00f3n - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/","og_locale":"es_ES","og_type":"article","og_title":"San Vicente de Pa\u00fal, biograf\u00eda: 08 - El descubrimiento de una vocaci\u00f3n - Somos Vicencianos","og_description":"Cap\u00edtulo VIII: El descubrimiento de una vocaci\u00f3n Raza de capitanes Obediente a las \u00f3rdenes de B\u00e9rulle, el Sr. Vicente abandonaba a finales de 1613 su parroquia de Clichy e iba a instalarse, con su parco ... Read More","og_url":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2016-12-28T11:00:10+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"San Vicente de Pa\u00fal, biograf\u00eda: 08 &#8211; El descubrimiento de una vocaci\u00f3n","datePublished":"2016-12-28T11:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/"},"wordCount":4561,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1","keywords":["Abad\u00eda de San Leonardo","Abelly","Clichy","Ecouis","Folleville","Gamaches","Gannes","Gondi","Joigny","Montmirail","Pobreza","Pouy","Reina Margarita","San Leonardo","Se\u00f1ora de Gondi","Silly","Villepreux"],"articleSection":["Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/","url":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/","name":"San Vicente de Pa\u00fal, biograf\u00eda: 08 - El descubrimiento de una vocaci\u00f3n - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1","datePublished":"2016-12-28T11:00:10+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/san-vicente-paul-biografia-08-descubrimiento-una-vocacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"San Vicente de Pa\u00fal, biograf\u00eda: 08 &#8211; El descubrimiento de una vocaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/Saint-Vincent-de-Paul-a-biography.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-dbr","jetpack-related-posts":[{"id":387854,"url":"https:\/\/vincentians.com\/es\/san-vicente-amigo-de-los-pobres-anos-de-busqueda-1613-1617\/","url_meta":{"origin":50681,"position":0},"title":"San Vicente: Amigo de los pobres: a\u00f1os de b\u00fasqueda (1613-1617)","author":"Mitxel Olabu\u00e9naga","date":"12\/10\/2016","format":false,"excerpt":"El se\u00f1or Vicente abandona Clichy El pueblo de Clichy guard\u00f3 siempre un grato recuerdo del mejor de sus p\u00e1rrocos. Pero, cuando m\u00e1s entusiasmado estaba \u00e9ste en sus proyectos, le lleg\u00f3 una carta de Berulle: Deb\u00eda cam\u00adbiar sus actividades. El director espiritual le ped\u00eda que volviera a Par\u00eds. Argumenta\u00adba que ser\u00eda\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119698,"url":"https:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-preceptor\/","url_meta":{"origin":50681,"position":1},"title":"El Se\u00f1or Vicente relee su vida: Preceptor","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/02\/2022","format":false,"excerpt":"Fue en la segunda mitad de 1613 cuando concluy\u00f3 mi b\u00fasqueda que tanto dur\u00f3. Recib\u00eda en efecto \"el cargo de preceptor de los hijos del Se\u00f1or Philippe-Emmanuel de Gondi, Conde de Joigny, General de las Galeras de Francia\". El mayor de los hijos, Pierre, ten\u00eda 11 a\u00f1os, el segundo, Henri,\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":387345,"url":"https:\/\/vincentians.com\/es\/fechas-en-la-vida-de-san-vicente\/","url_meta":{"origin":50681,"position":2},"title":"Fechas en la vida de San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/12\/2017","format":false,"excerpt":"1581: En Pouy (Landas) nace Vicente de Pa\u00fal, tercer hijo de la familia de Pa\u00fal. 1595: Vicente sale de Pouy para ir a Dax, donde vivir\u00e1 en casa del Se\u00f1or de Comet, abogado en Dax y juez en Pouy. Cursa estudios en el colegio de los Franciscanos. 1596: Vicente inicia\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":131357,"url":"https:\/\/vincentians.com\/es\/el-senor-vicente-evolucion-de-un-santo-viii\/","url_meta":{"origin":50681,"position":3},"title":"El se\u00f1or Vicente, evoluci\u00f3n de un santo (VIII)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"02\/10\/2014","format":false,"excerpt":"8. LA C\u00c1NDIDA EVA 1.El se\u00f1or Vicente, p\u00e1rroco de Clichy.- 2.La Hermandad del Rosario.- 3.Restauraci\u00f3n de la iglesia.- 4.Adios a la parroquia.- 5.En la casa de los Gondi.- 6.La familia.- 7.Beneficio.- 8.Las tierra de los Gondi.- 9.Maestro y maestra.- 10.\"El se\u00f1or Vicente\".- 11.Los ni\u00f1os.- 12.El preceptor.- 13.Conducata del capell\u00e1n; proyecto\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"coraz\u00f3n","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/03\/coraz%C3%B3n.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":124193,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-la-fe-del-hombre-maduro\/","url_meta":{"origin":50681,"position":4},"title":"Vicente de Pa\u00fal: La Fe de un hombre maduro","author":"Francisco Javier Fern\u00e1ndez Chento","date":"23\/02\/2023","format":false,"excerpt":"UN NOVICIADO Cuando Vicente lleg\u00f3 a Par\u00eds empez\u00f3 a ocuparse de su vida espiritual. Comprendi\u00f3 que aunque no hab\u00eda sido malo, hab\u00eda v\u00edvido su vida a lo mundano prestando poca atenci\u00f3n a su fe. Al iniciar su peregrinaci\u00f3n a Roma, un a\u00f1o despu\u00e9s de su ordenaci\u00f3n, se hab\u00eda dado cuenta\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":143598,"url":"https:\/\/vincentians.com\/es\/la-experiencia-espiritual-de-san-vicente\/","url_meta":{"origin":50681,"position":5},"title":"La experiencia espiritual de San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"20\/04\/2015","format":false,"excerpt":"La espiritualidad vicenciana no es de ninguna manera una gram\u00e1tica de santidad para estudiar y aplicar. Es una vida, una experiencia, con la que tenemos que comulgar para favorecer el trabajo de la gracia en una vida humana. Es la experiencia espiritual de Vicente de Pa\u00fal la que vamos a\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"san-vicente-de-paul-y-pobres","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/san-vicente-de-paul-y-pobres-300x208.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/50681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=50681"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/50681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/149545"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=50681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=50681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=50681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}