{"id":47509,"date":"2015-02-05T11:11:58","date_gmt":"2015-02-05T10:11:58","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=47509"},"modified":"2015-02-05T11:11:58","modified_gmt":"2015-02-05T10:11:58","slug":"cristo-y-la-pobreza","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/","title":{"rendered":"Cristo y la pobreza"},"content":{"rendered":"<h2><strong>1. Dios se nos revela en la pobreza.<\/strong><\/h2>\n<p><strong><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/07\/pobreespiritu-300x261.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47510 alignright\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/07\/pobreespiritu-300x261.jpg?resize=255%2C221\" alt=\"\" width=\"255\" height=\"221\" \/><\/a><\/strong>En el transcurso de la historia de Israel, vemos que Dios escoge a los peque\u00f1os y humildes. El pueblo escogido no debe su elecci\u00f3n a su poder:<\/p>\n<p><em>\u00abNo porque se\u00e1is el m\u00e1s numeroso de todos los pueblos se ha ligado <\/em><em>Yahv\u00e9h a vosotros y os ha elegido, pues sois el menos numeroso de todos los <\/em><em>pueblos\u00bb <\/em>(Deu. 7,7).<\/p>\n<p>Y, en Israel, los portadores de los designios de Dios, son los menores: Abel, Jacob, David&#8230;; las est\u00e9riles son las que se convierten en madres de los elegidos de Dios: Sara, Ana, Isabel.<\/p>\n<p>Y, en cuanto a Mar\u00eda, todos pueden cantar con Ella:<\/p>\n<p><em>\u00abPorque ha mirado la humildad de su sierva&#8230; Derrib\u00f3 a los potentados <\/em><em>de sus tronos y ensalz\u00f3 a los humildes\u00bb <\/em>(Luc, I, 48-52).<\/p>\n<p>Parece como si existiera en el mundo espiritual una ley que la historia de la Iglesia confirma. A quien se exalta delante de Dios o contra \u00e9l, el Se\u00f1or lo humilla, a quien se reconoce pobre delante de \u00c9l, el Se\u00f1or lo colma.<\/p>\n<p><em>\u00abLos ojos altivos del hombre ser\u00e1n abajados, se humillar\u00e1 la altaner\u00eda <\/em><em>humana. y ser\u00e1 exaltado Yahv\u00e9h solo en aquel d\u00eda\u00bb <\/em>(Isa\u00edas, 2, 11).<\/p>\n<p>En todc ello, no se trata de la pobreza como pura situaci\u00f3n material. Entre el fariseo y el publicano, es el publicano el que se encuentra en situaci\u00f3n de posesi\u00f3n. El ideal no es carecer, sino <em>estar libre o desprendido tanto en la <\/em><em>abundancia como en la privaci\u00f3n, <\/em>a ejemplo de San Pablo.<\/p>\n<p><em>\u00abNo pens\u00e9is que lo digo porque ando escaso, pues yo he aprendido a <\/em><em>arreglarme en toda circunstancia, s\u00e9 vivir con estrechez y s\u00e9 tener en abundan\u00ad<\/em><em>cia, ninguna situaci\u00f3n tiene secretos para m\u00ed, ni estar harto, ni pasar hambre, ni tener sobra, ni pasar falta; para todo me siento con fuerzas, gracias al que <\/em><em>me robustece\u00bb <\/em>(Fil. 4,11-13).<\/p>\n<p>Se trata de una noble independencia y desprendimiento de la<sup>,<\/sup>: realidades terrenas, acompa\u00f1ada de un total y confiada dependencia, que es la actitud de los \u00abPobres de Yahv\u00e9h\u00bb.<\/p>\n<p>La pobreza material, la indigencia, ofrecen condiciones m\u00e1s ventajosas. Naturalmente pueden suscitar reacciones de acritud, de rebeld\u00eda y de odio tan contrarias al Evangelio como la dureza de coraz\u00f3n, la suficiencia y el orgullo del rico, que, por su riqueza, se cree dispensado de confiar en Dios.<\/p>\n<p><em>Pero la pobreza material no est\u00e1 canonizada; necesita, lo mismo que la riqueza, ser evangelizada, para convertirse en una actitud religiosa.<\/em><\/p>\n<p><em>Ahora bien, en los pobres hay unas disposiciones de no-posesi\u00f3n, de <\/em><em>acogida, de participaci\u00f3n, de sentido de la justicia, que, como de forma natu\u00adral sintonizan con el Evangelio.<\/em><\/p>\n<p><em>De ah\u00ed la predilecci\u00f3n de Jes\u00fas por los pobres. \u00abEvangelizar a los pobres\u00bb <\/em><em>es el signo de su misi\u00f3n. <\/em>Jes\u00fas ama a los pobres y a los ni\u00f1os. Unos y otros tienen afinidades con el Hijo del hombre y el Reino de Dios. El hacerse como ni\u00f1os y la pobreza de esp\u00edritu son dos condiciones fundamentales para entrar en el Reino y muy afines una de otra; convergen las dos en la <em>\u00abhumildad\u00bb <\/em>que justifica (Luc. 18,14), que es el estado de alma por excelencia de los hijos del Reino y del propio Jes\u00fas.<\/p>\n<p>Sin duda alguna, Jes\u00fas vino para todos los hombres: pobres y ricos; pero, para entrar en el Reino, los ricos tendr\u00e1n que convertirse, que hacerse como ni\u00f1os y pobres, porque <em>\u00absuyo es el Reino de los Cielos\u00bb.<\/em><\/p>\n<p>De ah\u00ed tambi\u00e9n que Jes\u00fas tenga una actitud diferente con los ricos v con los pobres. Habla siempre de la riqueza desde un punto de vista pol\u00e9mico y se\u00f1alando sus peligros. Jes\u00fas s\u00f3lo se muestra violento con los fuertes y poderosos; pero con los pobres, tiene siempre una delicadeza, una ternura y una suavidad infinitas.<\/p>\n<p>Jes\u00fas ve en los pobres a los primeros oyentes del Evangelio, los que le escuchan fielmente y le siguen hasta el desierto; ovejas abandonadas, por las que no se interesan ni el sumo sacerdote acantonado en su Templo, ni los escribas ni los fariseos.<\/p>\n<p>Jes\u00fas observa que el Evangelio se acepta primero por los pobres, para quienes el dinero no constituye una barrera ni se dejan detener por precau\u00adciones materiales. <em>\u00abBendito seas, Padre, porque has ocultado estas cosas <\/em><em>a los sabios y entendidos y se las has revelado a la gente sencilla\u00bb <\/em>(Luc, 10,21).<\/p>\n<p>San Vicente, por experiencia, comprueba esta verdad del Evangelio: <em>\u00abOs <\/em><em>hablar\u00e9 con gusto de las virtudes de las buenas aldeanas por la experiencia <\/em><em>que tengo&#8230; A esos es a los que Dios quita la penetraci\u00f3n de las verdades <\/em><em>cristianas: a los sabios y a los entendidos del mundo. \u00bfA qui\u00e9nes se las da <\/em><em>entonces? Al pueblo sencillo, a las buenas gentes. Podemos comprobar esto <\/em><em>en la diferencia que se advierte entre la fe de los campesinos y la muestra. Lo <\/em><em>que me queda de la experiencia que tengo, es el juicio que siempre me he <\/em><em>hecho: que la verdadera religi\u00f3n, hermanos m\u00edos, la verdadera religi\u00f3n est\u00e1 entre los pobres. <\/em>(Conf. XII, 14 de marzo de 1959.)<\/p>\n<h2><strong>2. Puesto que Dios se revela en la pobreza, los pobres pueden ser re\u00ad<\/strong><strong>veladores de Dios; un medio y un camino para encontrar a Cristo.<\/strong><\/h2>\n<p>Para muchos hombres, lo que obstaculiza el camino hacia el Reino es el apego a ciertas comodidades, la seguridad de sus costumbres. los falsos pretextos, el miedo a la aventura.<\/p>\n<p>Ante los pobres experimentamos un principio de inquietud espiritual, nos sentimos juzgadas y nos juzgamos a nosotras mismas.<\/p>\n<p>Somos, sin duda \u00abprivilegiadas\u00bb, gozamos de salud y bienestar, y encon\u00adtramos en nuestra vida m\u00e1s dichas que miseria. Eso puede velarnos la realidad. El descubrimiento de la \u00abpobreza\u00bb, en su extensi\u00f3n y en sus innu\u00admerables formas, nos revela la realidad de la humanidad y de cada uno de nosotros. Los pobres nos interpelan y nos obligan a juzgarnos frente al Evangelio. El pobre, es el hombre sencillo, despojado de esa vestidura de pla\u00adcer y de ilusi\u00f3n con que se revisten los ricos y los dichosos de este mundo. El pobre es el signo visible de la situaci\u00f3n humana fundamental.<\/p>\n<p><em>La apertura al Reino y a la salvaci\u00f3n pasa por el reconocimiento y la <\/em><em>aceptaci\u00f3n de nuestra pobreza. <\/em>Dios que vino a \u00abbuscar y salvar lo que estaba perdido\u00bb empieza por hacernos pobres, como lo hizo con Israel. \u00abAntes de haber sido humillado me extravi\u00e9\u00bb lejos del camino de pobreza donde se encuentra al Se\u00f1or.<\/p>\n<p>Adem\u00e1s, la pobreza no es un hecho natural; con frecuencia es fruto de la injusticia y de la malicia de los hombres; no solamente de algunos explo\u00adtadores, sino de las estructuras econ\u00f3micas y sociales que los hombres im\u00adplantan. Es un pecado colectivo del que todos somos solidarios. En el rostro descarnado de los subdesarrollados, de los ni\u00f1os que mueren de hambre, se lee el pecado del mundo.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/pobreza-en-kenya.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-138445\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/pobreza-en-kenya-300x199.jpg?resize=300%2C199\" alt=\"pobreza en kenya\" width=\"300\" height=\"199\" \/><\/a>Los pobres son para nosotros palabra de Dios que nos hace conocernos a nosotros mismos. As\u00ed nos hacen entrar en la <em>\u00abpobreza espiritual\u00bb <\/em>que es el <em>camino del Reino.<\/em><\/p>\n<p>Por eso, hay que proclamar que, en el Evangelio, se exige la pobreza, no de forma perif\u00e9rica, sino central; no como un adorno para almas distin\u00adguidas, ni como un sentimiento del coraz\u00f3n. No se refiere s\u00f3lo al poseer, sino que ata\u00f1e a lo m\u00e1s profundo de nuestro ser, al \u00abcoraz\u00f3n\u00bb en el sentido b\u00edblico. <em>Somos fundamentalmente pobres. <\/em>La pobreza es la puerta y el cami\u00adno, \u00abla puerta estrecha y angosta que conduce a la vida\u00bb (Mt. 7, 14).<\/p>\n<p><em>El pobre es el hombre de la esperanza. <\/em>El rico es el hombre de la pro\u00adpiedad, del haber y del poder. Est\u00e1 satisfecho y no desea ning\u00fan cambio. Las estructuras sociales le parecen naturales y providenciales. Es conser\u00advador.<\/p>\n<p>Por eso, Dios ha puesto su esperanza en los pobres, los \u00abpobres\u00bb de Yav\u00e9h. La pobreza resulta decisiva para el Reino, para el futuro individual y com\u00fan de los hombres. El pobre, que sufre, que es humillado, tiene una conciencia muy viva de su miseria y de la miseria de la humanidad.<\/p>\n<p>Los profetas de Israel denunciaron la miseria como fruto del pecado de la sociedad, del pecado colectivo del pueblo de Dios. Denuncian la idolatr\u00eda\u00a0de una sociedad que a pesar del culto y de los sacrificios, pone su esperanza en el dinero y el poder, y no en el reino de Dios y su justicia.<\/p>\n<p>En el momento de la invasi\u00f3n y del exilio, la esperanza de Israel se \u00abencarn\u00f3\u00bb en el peque\u00f1o \u00abresto\u00bb, en los \u00abpobres de Jav\u00e9h\u00bb, que resistieron a la pol\u00edtica \u00abrealista\u00bb de los vencedores y permanecieron fieles a Jav\u00e9h. Ellos son los que acogieron las Buena Nueva y encontraron no la dicha sino la Bienaventuranza.<\/p>\n<p>Ellos son los Pobres de Jav\u00e9h; su pobreza se define con relaci\u00f3n a Dios, a su venida, a su Reino. No se han encerrado en su haber, en sus pose\u00adsiones, en su poder. Est\u00e1n prontos a arriesgar todo por el Reino. El pobre es el hombre del futuro, de la esperanza.<\/p>\n<p>Es notable c\u00f3mo los revolucionarios han puesto tambi\u00e9n su esperanza en los pobres. \u00abLa direcci\u00f3n de los movimientos revolucionarios debe estar en manos de los pobres.\u00bb \u00abSin pobres, no hay revoluci\u00f3n\u00bb, dec\u00eda Mao-Tse-Tung. A los miserables les han hecho tomar conciencia de su miseria, porque era \u00abinmerecida\u00bb y los han sublevado con la esperanza de un mundo, donde, en las relaciones interhumanas, cesar\u00e1 el dominio de la riqueza, de la posesi\u00f3n. Han transpuesto as\u00ed a este mundo el mesianismo de los profetas.<\/p>\n<p>De esta suerte la pobreza, con todo lo que lleva de miseria, de sufrimien\u00adto, de humillaciones y de explotaci\u00f3n, es signo revelador de un mundo de pecado, de un mundo \u00abroto\u00bb. La pobreza nos invita a liberarnos de todos los falsos \u00ababsolutos\u00bb, como dinero y poder, y a liberar a lo dem\u00e1s de la mise\u00adria. La pobreza nos predispone a acoger a Aquel que vino a liberarnos <em>y <\/em>a traer la Buena Nueva del Reino.<\/p>\n<h2><strong>3. El Evangelio nos da a conocer la predilecci\u00f3n de Jes\u00fas por los Pobres y hasta establece una cierta identidad entre \u00c9l y los pobres.<\/strong><\/h2>\n<p>En el Evangelio de Mateo (25, 31-46), Jes\u00fas se identifica con los pobres en el pasaje del juicio final:<\/p>\n<p><em>\u00abTuve hambre, tuve sed, &#8230; Cuantas veces hicisteis eso a uno de estos mis hermanos menores, a m\u00ed me lo hicisteis.\u00bb<\/em><\/p>\n<p>Los justos no dudaban que, con esas obras de misericordia, atend\u00edan al mismo Cristo. Cristo se oculta, pues, realmente bajo las especies de los que tienen hambre&#8230;<\/p>\n<p>Es evidente que los Padres interpretaron este \u00abmis hermanos menores\u00bb como los cristianos pobres, dado que los cristianos son los miembros del Cuerpo m\u00edstico. San Agust\u00edn nos dice:<\/p>\n<p><em>\u00abAqu\u00ed abajo, Cristo tiene hambre, tiene sed&#8230; porque todo lo que sufre <\/em><em>su Cuerpo aqu\u00ed abajo, el Se\u00f1or dice que lo sufre El mismo&#8230; Veamos nuestro <\/em><em>propio cuerpo&#8230; la cabeza est\u00e1 en la parte superior, los pies en el suelo y, <\/em><em>sin embargo, si alguien nos pisa el pie, es la cabeza la que grita&#8230; As\u00ed, Cristo, nuestra Cabeza, podr\u00e1 decir a alguno de nosotros: \u00abtuve hambre <\/em><em>me disteis de comer\u00bb y a otros: \u00abtuve hambre y no me disteis de comer\u00bb\u2026 Tan grande es la caridad de esta Cabeza con relaci\u00f3n a su cuerpo\u2026\u00bb.<\/em><\/p>\n<p>Hoy d\u00eda se ha dejado de lado esta interpretaci\u00f3n restrictiva. Jes\u00fas se identifica con todo ser que sufre sobre la tierra, cualquiera que sea su fe y sus pr\u00e1cticas religiosas. El Se\u00f1or hace suya la causa de todos los que objetivamente necesitan ayuda, cualesquiera que sean sus disposiciones sub\u00adjetivas. El hijo del hombre ve en todo miserable a su propio hermano. Su amor se solidariza con toda la miseria humana: Cristo vino a buscar y a salvar lo que estaba perdido.<\/p>\n<p>Y la identificaci\u00f3n de Jes\u00fas con los pobres no tiene otro fundamento que su misma pobreza. Esta identificaci\u00f3n se presenta con una fuerza extrema: como una relaci\u00f3n personal entre los pobres y Jes\u00fas. Y esto sinto\u00adniza con todo el Evangelio. Tenemos el mandamiento de amar a los enemi\u00adgos, a ejemplo del Padre Celestial que distribuye sus beneficios sobre los jus\u00adtos e injustos. Est\u00e1 la par\u00e1bola del Buen Samaritano, donde a la pregunta: \u00ab\u00bfQu\u00e9 debo hacer para ganar la vida eterna?\u00bb. Jes\u00fas responde que <em>la poseer\u00e1n <\/em>aquellos que hayan actuado como el Buen Samaritano.<\/p>\n<p><em>El misterio de la presencia \u00abpersonal\u00bb de Cristo en los pobres nos lleva <\/em>al misterio de la pobreza de Cristo en la Encarnaci\u00f3n redentora<\/p>\n<h2><strong>4. \u00bfPor qu\u00e9 escogi\u00f3 Cristo la pobreza?<\/strong><\/h2>\n<p><em>Esta opci\u00f3n que no nace de la necesidad, sino de la gracia; de lo que Dios <\/em><em>libremente decide ser y hacer por nosotros. <\/em>Y hay en ella datos positivos, que nos aportan algo que tenemos que comprender y que debemos imitar.<\/p>\n<p>Por parte de Dios y de Cristo, \u00bfen qu\u00e9 se basa esta predilecci\u00f3n por los pobres? Dios es Amor, Dios es Gracia, La gracia es libertad soberana, su propio movimiento de gracia hace de ella una condescendencia, un don que responde a las exigencias del amor. La naturaleza del amor le inclina a ir hacia lo m\u00e1s bajo, lo m\u00e1s desprovisto. <em>Dios nos ama, no en raz\u00f3n de la <\/em><em>bondad que poseamos, sino al contrario, porque somos pobres.<\/em><\/p>\n<p>As\u00ed, el hecho de que en su Encarnaci\u00f3n Cristo se haya hecho hombre, despos\u00e1ndose con nuestra humanidad, en las condiciones m\u00e1s humildes, para estar plenamente con tantos pobres que, en el correr de los tiempos, han sido humillados, explotados y aplastados, nos revela lo que es Dios en su ser profundo y lo que es Dios para nosotros. Para venir a nosotros, ha escogido el camino del servicio a los hombres, humilde y lleno de amor, el camino del pendiente escabrosa y llena de espinas para buscar a la oveja descarriada, y hasta el polvo del suelo para encontrar la dragma perdida.<\/p>\n<p>Puesto que tal es el camino que ha inaugurado para nosotros, para nos\u00adotros tambi\u00e9n, el camino de la verdad y de la vida es amar como Jes\u00fas am\u00f3, con un amor de predilecci\u00f3n por los humildes, los que sufren, los abando\u00adnados. La novedad del Evangelio es \u00abamar <em>como <\/em>Jes\u00fas am\u00f3\u00bb; amor que es reflejo del mismo amor de Dios. De ello naci\u00f3n el esc\u00e1ndalo de los fariseos aquellos \u00abjustos\u00bb de piedad escrupulosa que cre\u00edan servir mejor a Dios apart\u00e1ndose de los impuros y de los pecadores.<\/p>\n<p>As\u00ed, en Jesucristo, por su pobreza, dependencia y humildad, se descubre para nosotros el ser \u00edntimo de Dios.<\/p>\n<p>Dios es plenitud de vida y de felicidad, pero no una Plenitud orgullosa, satisfecha de s\u00ed misma. Es una vida y una felicidad tan abundante que desborda sobre nosotros. San Pablo habla de la superabundancia de Cristo. Es pobre porque le falta la felicidad de los dem\u00e1s.<\/p>\n<p>Dios es impasible; en El no existe ni la carencia ni la necesidad. Sin embargo, no es insensible. Su felicidad no es una dicha satisfecha y con\u00adfortable. La Sagrada Escritura habla de la compasi\u00f3n y de la ternura de Dios. Cristo quiso sufrir nuestras penas y dolores.<\/p>\n<p>Pero el sufrimiento en s\u00ed no se sacraliza, es el sufrimiento del Redentor, es un sufrimiento que nace del amor.<\/p>\n<p>Cristo vino a buscar lo que estaba perdido; as\u00ed pues, si todo ser que sufre es sagrado en raz\u00f3n de Aquel a quien se asemeja, todo ser que cura, levanta, consuela o sana, est\u00e1 tambi\u00e9n configurado con Cristo.<\/p>\n<p>Cristo ha revelado que el mal puede ser vencido y rescatado, que existe la victoria del amor sobre el sufrimiento y la muerte.<\/p>\n<p>Nuestra dedicaci\u00f3n para con los pecadores y desgraciados son el sacra\u00admento, el anuncio de la Redenci\u00f3n, de la liberaci\u00f3n. El amor y la piedad de Cristo para los enfermos, sus gestos curando a los ciegos, a los sordos, a los paral\u00edticos, leprosos, constitu\u00edan el signo de que se puede ser curado, amado y salvado. A trav\u00e9s de nuestras pobres palabras y obras, a trav\u00e9s de nuestro amor, se manifiesta otro Amor, el amor y la piedad de Cristo.<\/p>\n<p>Por su Encarnaci\u00f3n, Cristo se identific\u00f3 con los pobres. El Hijo de Dios vino a nosotros pobre, a causa de nuestra pobreza. <em>\u00ab\u00c9l se hizo pobre por nos\u00adotros.\u00bb <\/em>Cristo salva a los pobres mediante su pobreza y mediante la nuestra integrada en la suya.<\/p>\n<p>Jes\u00fas, al tomar nuestra pobreza miserable, la cur\u00f3 y la transform\u00f3 en pobreza filial, en oblaci\u00f3n de obediencia y de amor, colm\u00e1ndola de la infinita riqueza de Dios. La pobreza es el crisol donde se realiza la salvaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Dios se nos revela en la pobreza. En el transcurso de la historia de Israel, vemos que Dios escoge a los peque\u00f1os y humildes. El pueblo escogido no debe su elecci\u00f3n a su poder: &#8230; <a href=\"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":138445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[172],"class_list":["post-47509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cristo y la pobreza - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristo y la pobreza - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"1. Dios se nos revela en la pobreza. En el transcurso de la historia de Israel, vemos que Dios escoge a los peque\u00f1os y humildes. El pueblo escogido no debe su elecci\u00f3n a su poder: ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-05T10:11:58+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Cristo y la pobreza\",\"datePublished\":\"2015-02-05T10:11:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/\"},\"wordCount\":2872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/\",\"name\":\"Cristo y la pobreza - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-02-05T10:11:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/cristo-y-la-pobreza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristo y la pobreza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristo y la pobreza - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/","og_locale":"es_ES","og_type":"article","og_title":"Cristo y la pobreza - Somos Vicencianos","og_description":"1. Dios se nos revela en la pobreza. En el transcurso de la historia de Israel, vemos que Dios escoge a los peque\u00f1os y humildes. El pueblo escogido no debe su elecci\u00f3n a su poder: ... Read More","og_url":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-02-05T10:11:58+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Cristo y la pobreza","datePublished":"2015-02-05T10:11:58+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/"},"wordCount":2872,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#primaryimage"},"thumbnailUrl":"","keywords":["Pobreza"],"articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/","url":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/","name":"Cristo y la pobreza - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-02-05T10:11:58+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/cristo-y-la-pobreza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cristo y la pobreza"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-cmh","jetpack-related-posts":[{"id":119429,"url":"https:\/\/vincentians.com\/es\/cantar-el-magnificat-con-maria\/","url_meta":{"origin":47509,"position":0},"title":"Cantar el Magn\u00edficat con Mar\u00eda","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/04\/2013","format":false,"excerpt":"Introducci\u00f3n \"El Magn\u00edficat es un c\u00e1ntico de la Escritura que canta un poema de vida y de acci\u00f3n. Es c\u00e1ntico, oraci\u00f3n, adoraci\u00f3n, exultaci\u00f3n y entusiasmo, acci\u00f3n de gracias, canto de victoria, la de Dios en Jesucristo. Grito de la fe, est\u00e1 impregnado de teolog\u00eda, es meditaci\u00f3n inagotable, es oraci\u00f3n\u2026 En\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"Magnificat","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/Magnificat-244x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":121247,"url":"https:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/","url_meta":{"origin":47509,"position":1},"title":"Escuchar la Palabra de Dios","author":"Francisco Javier Fern\u00e1ndez Chento","date":"04\/05\/2013","format":false,"excerpt":"Cada ma\u00f1ana me despierta para que oiga, para que escuche como disc\u00edpulo. El Se\u00f1or Yahv\u00e9 me ha abierto el o\u00eddo. Is 50,4-5 Ante todo cada uno de nosotros se esforzar\u00e1 por convencerse de esta verdad: que la ense\u00f1anza de Cristo no puede enga\u00f1ar nunca, mientras que la del mundo es\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"leer_la_palabra","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/leer_la_palabra-300x191.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":136440,"url":"https:\/\/vincentians.com\/es\/algunas-virtudes-muy-simples\/","url_meta":{"origin":47509,"position":2},"title":"Algunas virtudes muy simples","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/01\/2016","format":false,"excerpt":"El Se\u00f1or Vicente cre\u00eda m\u00e1s en las virtudes m\u00e1s sencillas que en los grandes sentimientos. Uno de los aspectos m\u00e1s atrayentes de su pensamiento se sit\u00faa justamente en este sabroso equilibrio entre la solidez de un buen sentido que no se paga de palabras, y la acogida humilde y confiada\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"sencillez humildad","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2015\/01\/sencillez-humildad.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2015\/01\/sencillez-humildad.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2015\/01\/sencillez-humildad.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2015\/01\/sencillez-humildad.jpg?resize=700%2C400 2x"},"classes":[]},{"id":120295,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-la-fe-que-dio-sentido-a-su-vida-ix-algunas-virtudes-muy-simples\/","url_meta":{"origin":47509,"position":3},"title":"Vicente de Pa\u00fal: la fe que dio sentido a su vida. IX. Algunas virtudes muy simples","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/01\/2015","format":false,"excerpt":"IX. Algunas virtudes muy simples El Se\u00f1or Vicente cre\u00eda m\u00e1s en las virtudes m\u00e1s sencillas que en los grandes sentimientos. Uno de los aspectos m\u00e1s atrayentes de su pensamiento se sit\u00faa justamente en este sa\u00adbroso equilibrio entre la solidez de un buen sentido que no se paga de palabras, y\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"Vincent-de-Paul-and-bible-alternate","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/Vincent-de-Paul-and-bible-alternate-216x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387135,"url":"https:\/\/vincentians.com\/es\/contemplativos-en-la-accion\/","url_meta":{"origin":47509,"position":4},"title":"Contemplativos en la acci\u00f3n","author":"Mitxel Olabu\u00e9naga","date":"26\/02\/2016","format":false,"excerpt":"\u00abNo descuides el don que posees... Cuida de esas co\u00adsas y ded\u00edcate a ellas, para que todos vean c\u00f3mo adelantas. Preoc\u00fapate de ti y de la ense\u00f1anza; si lo haces te sal\u00advar\u00e1s a ti y a los que te es\u00adcuchan\u00bb. (I Tim 4,14-16). \u00abLa inserci\u00f3n apost\u00f3lica en el mundo, la\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/02\/asd-3-300x214.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":136560,"url":"https:\/\/vincentians.com\/es\/evangelizados-por-los-pobres\/","url_meta":{"origin":47509,"position":5},"title":"Evangelizados por los pobres","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/01\/2015","format":false,"excerpt":"\u00abEscuchad, queridos hermanos \u00bfno fue Dios quien escogi\u00f3 a los que son pobres a los ojos del mundo para que fueran eran ricos de fe y herederos del Reino que \u00e9l prometi\u00f3 a los que lo aman? Vos\u00adotros, en cambio, hab\u00e9is afrentado al pobre\u00bb. Sant 2,5-6). \u00abEn la obra de\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"vicente_pobre","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/vicente_pobre-241x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/47509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=47509"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/47509\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=47509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=47509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=47509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}