{"id":43002,"date":"2014-12-25T06:20:21","date_gmt":"2014-12-25T05:20:21","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=43002"},"modified":"2016-07-27T12:06:35","modified_gmt":"2016-07-27T10:06:35","slug":"rene-almeras-1613-1672","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/","title":{"rendered":"Ren\u00e9 Alm\u00e9ras (1613-1672)"},"content":{"rendered":"<h2>Cap\u00edtulo I: De su vocaci\u00f3n a la Congregaci\u00f3n de la Misi\u00f3n.<\/h2>\n<div id=\"attachment_43008\" style=\"width: 251px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/06\/Almeras.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43008\" class=\"size-medium wp-image-43008\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/06\/Almeras-241x300.jpg?resize=241%2C300\" alt=\"Ren\u00e9 Almer\u00e1s, C.M.\" width=\"241\" height=\"300\" \/><\/a><p id=\"caption-attachment-43008\" class=\"wp-caption-text\">Ren\u00e9 Almer\u00e1s, C.M.<\/p><\/div>\n<p>Para conocer mejor la fuerza de la gracia de Dios en la vocaci\u00f3n del Sr. Alm\u00e9ras, es necesario saber con qu\u00e9 lazos estaba unido a este mundo, y cu\u00e1les fueron los combates que tuvo que sostener para desprenderse de ellos y retirarse a la Congregaci\u00f3n de la Misi\u00f3n. Ren\u00e9 Alm\u00e9ras hab\u00eda nacido en Par\u00eds, el 5 de febrero de 1613. Pod\u00eda pretender a honores, placeres y riquezas considerables. Estando dotado de un esp\u00edritu distinguido que hab\u00eda cultivado por el estudio, y siendo el mayor de una honorable familia, que ten\u00eda como pr\u00f3ximos parientes\u00a0 o aliados a obispos, consejeros de Estado, presidentes y consejeros del Parlamento, y a otras personas de la m\u00e1s alta calidad, tanto eclesi\u00e1sticos como laicos. Su padre era maestro de cuentas, y \u00e9l mismo era consejero en el alto consejo, que era, como se sabe, una justicia soberana cuya jurisdicci\u00f3n se extend\u00eda por todo el mundo.<\/p>\n<p>Su nacimiento, sus cualidades, su cargo, su edad, -no ten\u00eda entonces m\u00e1s que 24 a\u00f1os, -le ofrec\u00edan f\u00e1cil acceso a las m\u00e1s hermosas compa\u00f1\u00edas, y le abr\u00edan la puerta a los partidos m\u00e1s ventajosos, si hubiera querido comprometerse en matrimonio. Pero aunque todas estas ventajas fueran muy poderosas para retirarle del mundo, donde \u00e9l las pod\u00eda poseer con felicidad y vivir a su gusto, Dios le dio la gracia de despreciarlas generosamente, para dedicarse de una manera particular a su servicio; y nada pudo impedirle de ejecutar la elecci\u00f3n que hab\u00eda hecho \u00abde ser abyecto en la casa del Se\u00f1or, antes que habitar en los tabern\u00e1culos de los mundanos\u00bb, que la mayor parte de los hombres buscan con tanto empe\u00f1o.<\/p>\n<p>No se content\u00f3 con huir as\u00ed de todos los se\u00f1uelos enga\u00f1osos del mundo, quiso incluso evitar en su retiro todo cuanto hubiera\u00a0 podido encontrar de esplendoroso. En efecto, en lugar de elegir una de estas santas e ilustres compa\u00f1\u00edas que florec\u00edan entonces en la Iglesia de Dios por la eminencia de su ciencia, de sus talentos y de sus empleos, as\u00ed como unos de sus pr\u00f3ximos, que hab\u00eda sabido su plan, trat\u00f3 de persuad\u00edrselo, \u00e9l hizo ver con claridad cu\u00e1n desprendido estaba de todo cuanto el mundo estima; respondi\u00f3 a\u00a0\u00a0 este amigo que era a causa de su resplandor mismo como no los quer\u00eda elegir, por miedo, dec\u00eda \u00e9l, que al huir el mundo y los vanos honores por una puerta, se los encontrara por otra. Fue con estas miras de un perfecto desprecio del mundo y por amor a su propia abyecci\u00f3n como puso los ojos en la Congregaci\u00f3n de la Misi\u00f3n que estaba como en su cuna, casi desconocida en el mundo, y la m\u00e1s peque\u00f1a de todas, no estaba por entonces compuesta m\u00e1s que de un muy peque\u00f1o n\u00famero de eclesi\u00e1sticos de humilde condici\u00f3n, a los que Vicente, su fundador llamaba sacerdotes de los pueblos y los servidores de los pobres, y que hac\u00edan profesi\u00f3n particular de sencillez, de humildad y de pobreza.<\/p>\n<p>Recibi\u00f3 pues con una perfecta correspondencia de su coraz\u00f3n la inclinaci\u00f3n que Dios le dio a abrazar el estilo de vida de esta Congregaci\u00f3n naciente, que estaba en su primer fervor, y en la que\u00a0 los que la compon\u00edan no eran no ten\u00edan m\u00e1s que un coraz\u00f3n y un alma, por la uni\u00f3n de una perfecta caridad, como los cristianos en la primitiva Iglesia. Despu\u00e9s de examinar bien ante Dios y pensar por espacio de dos a\u00f1os en los medios de hacerle triunfar, se resolvi\u00f3 a hablar a su respetable padre y seguir sin descanso su ejecuci\u00f3n. Le empujaba un deseo tan ardiente de cumplirlo, para obedecer a la vocaci\u00f3n divina\u00a0 de la que estaba plenamente persuadido, que el menor retraso le parec\u00eda insoportable, como se lo declar\u00f3 despu\u00e9s a una persona de confianza.<\/p>\n<p>Su padre, aunque muy hombre de bien, se sorprendi\u00f3 en extremo por esta propuesta y vivamente afectado por esta resoluci\u00f3n, no s\u00f3lo a causa de la privaci\u00f3n de una persona que le era tan querida, sino tambi\u00e9n a causa del inter\u00e9s de su familia, cuyo hijo deb\u00eda ser su principal apoyo; de manera que despu\u00e9s de manifestarle todo lo que el amor paterno y el sentimiento de una p\u00e9rdida tal le pudieron sugerir para hacerle cambiar de resoluci\u00f3n, le dijo por fin, al verle inflexible, que puesto que hab\u00eda gastado dos a\u00f1os en formar y preparar este proyecto, \u00e9l necesitaba tambi\u00e9n al menos otro tanto para ver si deb\u00eda dar su consentimiento.<\/p>\n<p>Si el Sr. Alm\u00e9ras hall\u00f3 tanta resistencia por parte de su padre en la ejecuci\u00f3n de su piadoso proyecto, no la encontr\u00f3 menos por parte del Sr. Vicente cuando se lo hubo declarado; puesto que, si bien este prudente superior reconoci\u00f3 en \u00e9l excelentes disposiciones, tem\u00eda todav\u00eda que al recibir en su Congregaci\u00f3n incipiente a un joven de condici\u00f3n, alimentado delicadamente y que estaba ya educado en un cargo considerable, \u00e9l no abri\u00f3 la puerta\u00a0 al menor relajo del esp\u00edritu de sencillez, de humildad y de mortificaci\u00f3n de lo que hac\u00eda con todos los suyos una particular\u00a0 profesi\u00f3n. Por eso hizo todo lo posible para apartarle de su resoluci\u00f3n cuando le habl\u00f3. El Sr. Alm\u00e9ras le cont\u00f3 un d\u00eda a un sacerdote de la Compa\u00f1\u00eda: \u00bb\u00a0El Sr. Vicente, dijo, adivinando la vanidad de la que yo estaba lleno, me habl\u00f3 de la Congregaci\u00f3n de la manera m\u00e1s humillante que se pueda imaginar; me dijo entre otras cosas: Se\u00f1or, somos unas pobres gentes, mal acomodadas\u00a0 y sin ning\u00fan lugar seguro, vi\u00e9ndonos obligados a ir por todas partes adonde la obediencia nos env\u00eda. Me explic\u00f3 despu\u00e9s la pobreza del vivir, de los vestidos, del lecho y de todo lo dem\u00e1s, de una manera sorprendente, hasta decirme que si yo hubiera visto la\u00a0 pobreza de los seminaristas y la abyecci\u00f3n de sus de sus ejercicios, esto me repeler\u00eda: de suerte que me imaginaba que el seminario era como un lugar lleno de todas las clases de miserias. Pero, no obstante eso, yo estaba resuelto a entrar en \u00e9l, porque Dios ya me hab\u00eda avisado sobre este pensamiento, que un hombre que dejaba el mundo no deb\u00eda ya amar y estimar otra cosa que la pobreza, los sufrimientos y las humillaciones; y yo pod\u00eda comprender que una persona que se revest\u00eda con saco en una religi\u00f3n o con una sotana en una congregaci\u00f3n eclesi\u00e1stica pudiera desear ni buscar otra cosa; y as\u00ed todo lo que me dec\u00eda el Sr. Vicente para desaconsejarme era lo que m\u00e1s me fortalec\u00eda para abrazarla\u00bb.<\/p>\n<p>Esto es lo que el Sr. Alm\u00e9ras ha contado \u00e9l mismo de lo que hab\u00eda pasado entre \u00e9l y el Sr. Vicente en muchas conversaciones que tuvieron\u00a0 sobre su vocaci\u00f3n a la Misi\u00f3n. Este sabio Superior no se qued\u00f3 all\u00ed pues, viendo que no pod\u00eda con todas estas razones hacer cambiar de resoluci\u00f3n al postulante, emple\u00f3 las advertencias de la Sra. presidenta Goussault, a quien su piedad singular, as\u00ed como su parentesco daba mucho cr\u00e9dito sobre el esp\u00edritu del Sr. Alm\u00e9ras, que era su sobrino; pero todo lo que pudo decir sobre la vida oculta y laboriosa de los misioneros que ella conoc\u00eda particularmente aument\u00f3 su ardor\u00a0 su ardor en lugar de disminuirlo; habiendo reconocido sensiblemente que Dios la llamaba\u00a0 a este g\u00e9nero de vida humilde y penoso, se hab\u00eda de tal manera resuelto a ello desde el comienzo que no se esperaba otra cosa en la Misi\u00f3n que privaciones y humillaciones; y \u00e9l ha conservado tan bien siempre los mismos\u00a0 sentimientos que, como lo confes\u00f3 despu\u00e9s,\u00a0 estaba sorprendido de que le hicieran alg\u00fan honor y le dieran alg\u00fan descanso, no creyendo que se le debiera tratar de otra forma que como al \u00faltimo de la casa.<\/p>\n<p>Por \u00faltimo, tras diversas pruebas, la constancia perseverante del Sr. Alm\u00e9ras sobrellev\u00f3 la resistencia de su padre; y pronto uno y otro, uniendo sus peticiones ante el Sr. Vicente le hicieron aceptar su demanda. No se debe omitir aqu\u00ed una circunstancia digna de notar, que su padre que hab\u00eda sido al comienzo tan contrario al plan de su hijo, estuvo con el tiempo tan persuadido que su vocaci\u00f3n ven\u00eda de Dios que no se content\u00f3 con darle su consentimiento y su bendici\u00f3n; cual otro Abrah\u00e1n, quiso \u00e9l mismo contribuir a la ejecuci\u00f3n de su sacrificio, llev\u00e1ndole a San L\u00e1zaro y present\u00e1ndosele a san Vicente, al que dijo con una generosidad verdaderamente cristiana que \u00e9l dejaba en sus manos toda la autoridad que Dios le hab\u00eda dado sobre su hijo, para disponer de \u00e9l a su voluntad,\u00a0 seg\u00fan los designios de la divina Providencia. El Sr. Vicente, por su parte, le recibi\u00f3 como un regalo del cielo y como una persona cuya vocaci\u00f3n extraordinaria y las ventajas de naturaleza y de gracia que hab\u00eda recibido de Dios le eran un presagio que pronto ser\u00eda una de las principales columnas de la Congregaci\u00f3n. \u00c9l lo fue, en efecto, durante toda su vida, por el ejemplo de sus virtudes y por su prudente conducta en los primeros cargos de la Compa\u00f1\u00eda.<\/p>\n<p>La gracia que Dios hizo en esta ocasi\u00f3n al Sr. Alm\u00e9ras se extendi\u00f3 hasta la persona de su padre, quien aprovech\u00f3 mucho, en su estado secular, del ejemplo de virtud que ve\u00eda en su hijo. Se puede constatar por los sentimientos de heroico desprendimiento del que hizo gala en la carta siguiente. Escribi\u00f3 en 1647 al Sr. Vicente para responder a las excusas que \u00e9ste le hab\u00eda presentado porque su hijo hab\u00eda ido a Roma sin darle a saber ni despedirse de \u00e9l: \u00abCuando considero, dice, de qu\u00e9 manera y con qu\u00e9 conformidad consent\u00ed en la vocaci\u00f3n de mi hijo, sin que las ternuras naturales me hayan impedido consignarle en vuestras manos, que desde hace casi diez a\u00f1os no he exigido ninguno de los cuidados que los hijos prestan a su padre, que nunca le he hablado de su vocaci\u00f3n sino para aprobarla y congratularme de verle all\u00ed, tan bien seguro, os manifiesto delante de Dios, que es el \u00fanico escrutador de los corazones, que no tengo nada que decir sobre los designios que teng\u00e1is con la persona de mi hijo, en las comisiones ni en los empleos que le dais ni en los viajes que le encarg\u00e1is hacer, aunque fueran\u00a0 hasta las Indias. Habiendo puesto, cuando os le llev\u00e9 por primera vez, en las manos de Dios y en las vuestras la autoridad paterna que ten\u00eda sobre \u00e9l, para haceros su due\u00f1o absoluto, yo no puedo ni debo revocar la ofrenda que tan voluntariamente hice de \u00e9l: de modo que lo que me queda es pedir a Dios que bendiga sus acciones, que haga prosperar sus viajes, y a vos, Se\u00f1or, que me hag\u00e1is un huequecito en vuestras oraciones\u00bb.<\/p>\n<p>Los t\u00e9rminos de esta carta son todo un testimonio de una virtud poco com\u00fan en un padre que sent\u00eda con toda seguridad por un hijo tan digno un afecto igual a su m\u00e9rito; pero fue m\u00e1s adelante todav\u00eda, en el ejercicio de esta virtud, cuando a imitaci\u00f3n suya hizo un sacrificio de s\u00ed mismo a Dios en la misma Congregaci\u00f3n, donde fue recibido el 2 de marzo de 1657. En ella dio una edificaci\u00f3n muy grande hasta su muerte. Y ahora el testimonio que de \u00e9l ha dado el Sr. Vicente, escribiendo a un superior de la Compa\u00f1\u00eda: \u00abEl padre del Sr. Alm\u00e9ras honra desde hace alg\u00fan tiempo al seminario con su presencia, habiendo tenido la devoci\u00f3n de tomar el h\u00e1bito y la calidad de seminarista, y de asistir a los ejercicios como lo hace, en la medida que se lo permite sus ochenta y dos a\u00f1os. Es una gran humildad para un contable, cabeza de una muy honorable familia, y un venerable anciano; pero as\u00ed ha encontrado de esta manera el secreto de ser grande en la otra vida, despu\u00e9s de haberlo sido en \u00e9sta, que es de hacerse peque\u00f1o como un ni\u00f1o por el amor de Nuestro Se\u00f1or\u00bb.<\/p>\n<p>Despu\u00e9s de su muerte, que tuvo lugar al cabo de seis meses, el Sr. Vicente escribi\u00f3 sobre \u00e9l a las casas de la Congregaci\u00f3n en estos t\u00e9rminos: \u00abEl Sr. Alm\u00e9ras padre ha encontrado el fin de sus d\u00edas tras ochenta y tres a\u00f1os que ha vivido en la tierra; cay\u00f3 enfermo el primer d\u00eda del a\u00f1o, y el cuarto se fue al cielo, tenemos motivos de creerlo as\u00ed, a la vista de los actos de virtud que le hemos visto practicar a partir de su entrada en la Congregaci\u00f3n, que han edificado a toda la casa y que le han dispuesto a una buena muerte,\u00a0 como premio de una larga vida\u00bb.<\/p>\n<p>Estas son\u00a0 en pocas palabras las bendiciones con las que Dios colm\u00f3 a este digno padre por los m\u00e9ritos de su hijo.<\/p>\n<h2>Cap\u00edtulo II: Entrada del Sr. Almer\u00e1s en la Congregaci\u00f3n; de las virtudes que se practican en el Seminario, en especial la devoci\u00f3n que tuvo hacia sus padres<\/h2>\n<p>El Sr. Alm\u00e9ras una vez obtenida del Sr. Vicente la gracia que ped\u00eda despu\u00e9s de todas las pruebas que hemos referido ya, comenz\u00f3 primeramente por el retiro que se hace antes de ser recibido en el seminario de la Congregaci\u00f3n de la Misi\u00f3n. A prop\u00f3sito de su situaci\u00f3n, hablando confidencialmente a un sacerdote de la misma Compa\u00f1\u00eda, le dijo entre otras cosas, que habiendo pasado seis d\u00edas\u00a0 en el retiro, seg\u00fan el uso de aquel tiempo, esperaba que le hablaran enseguida de recibirle en el seminario, pero el director del seminario, que le dirig\u00eda en sus ejercicios, esperando que pidiera ser recibido, le dej\u00f3 continuar hasta doce d\u00edas sin decirle nada sobre el asunto y sin darle a conocer la causa de este retraso. Esto dur\u00f3 hasta que el Sr. Vicente fue verle y le pregunt\u00f3 qu\u00e9 tal encontraba los ejercicios, \u00e9l le dijo que los encontraba bien y que esperaba la orden de recibirle en el seminario. El Sr.Vicente respondiendo que \u00e9l esperaba tambi\u00e9n que se la pidiera de nuevo; y viendo que persist\u00eda a\u00fan en su primera resoluci\u00f3n, le dio a leer el reglamento de la Congregaci\u00f3n, para probar todav\u00eda m\u00e1s la firmeza de su vocaci\u00f3n, antes de admitirle en el seminario con los principiantes.<\/p>\n<p>Durante el tiempo que el Sr. Alm\u00e9ras permaneci\u00f3 as\u00ed en el retiro, un hermano de la casa que ten\u00eda orden de encenderle fuego y hacerle algunos servicios, ha contado lo que sigue: \u00abComo yo iba, dec\u00eda \u00e9l, de vez en cuando a la habitaci\u00f3n donde el Sr. Alm\u00e9ras hac\u00eda su retiro, aprovechaba la ocasi\u00f3n\u00a0 para preguntarme qu\u00e9 se hac\u00eda en la Misi\u00f3n, c\u00f3mo se portaban, lo que se propon\u00eda, c\u00f3mo se viv\u00eda, y cosas semejantes de las que se enteraba con diligencia; y yo le respond\u00eda sencillamente lo que sab\u00eda; los daba se\u00f1ales de interesarle mucho, encendi\u00e9ndose m\u00e1s y m\u00e1s en su resoluci\u00f3n. Y yo le o\u00eda decir; \u00abAqu\u00ed es donde Dios me llama, aqu\u00ed es donde me ha llamado siempre. He buscado muchas cosas, no sab\u00eda lo que buscaba; pero por fin he encontrado lo que Dios pide de m\u00ed\u00bb.<\/p>\n<p>Fue pues al fin recibido en el seminario el 24 de diciembre de 1638. Desde un principio dio muestras de estar tan muerto a todas las cosas del mundo y a las inclinaciones de la naturaleza, en particular respecto de sus padres que se puede decir con verdad que Nuestro Se\u00f1or le dio ese d\u00eda una abundante participaci\u00f3n de la gracia de su nacimiento despoj\u00e1ndole del hombre viejo y revisti\u00e9ndole del nuevo de una manera extraordinaria. En este esp\u00edritu y en esta disposici\u00f3n de una vida nueva, envi\u00f3 a su casa toda su ropa delicada, su sotana de seda y los dem\u00e1s h\u00e1bitos, como los restos del hombre viejo, de los que se hab\u00eda despojado de manera que no quer\u00eda ver ni rastro de ello en la casa; pero lo que es mucho m\u00e1s dif\u00edcil y digno de admiraci\u00f3n, es que se despoj\u00f3 de las m\u00e1ximas del siglo y de las maneras de actuar y de hablar que son ordinarias en los hombres del mundo, y en particular en las personas de condici\u00f3n, que parec\u00eda otro distinto a los que le hab\u00edan conocido antes. En efecto, se entreg\u00f3 en primer lugar, en una continua atenci\u00f3n a s\u00ed mismo,\u00a0 a imitar a nuestro Se\u00f1or en sus virtudes que son las m\u00e1s opuestas al orgullo, al fasto y a la vana moda del mundo, por la pr\u00e1ctica de la sencillez y de la humildad cristiana que ve\u00eda brillar en la Congregaci\u00f3n de la Misi\u00f3n, y particularmente en la persona de su fundador, el Sr. Vicente, y en la del Sr. de La Salle, director del seminario que eran dos copias fieles de este divino original; en lo que hizo tales progresos que parec\u00eda transformado en otro hombre, de manera que muchos que fueron recibidos en la Congregaci\u00f3n\u00a0 y que no sab\u00edan lo que hab\u00eda sido en el mundo, al verle actuar en particular de una manera tan sencilla y tan humilde le tomaban por un hombre de pueblo o de baja condici\u00f3n. Se entregaba con el mismo fervor a la pr\u00e1ctica de todas las virtudes, y en particular de las que son m\u00e1s propias a los misioneros y que componen el esp\u00edritu de su vocaci\u00f3n. Fue en aquel tiempo cuando el Sr. de La Salle tuvo sobre este asunto varias conferencias en el seminario para descubrir con mayor certeza en qu\u00e9 consist\u00eda principalmente este esp\u00edritu. Una vez reconocido como un sentimiento un\u00e1nime, que fue aprobado y confirmado por el Sr. Vicente, que este esp\u00edritu consist\u00eda en la sencillez, humildad, mansedumbre, mortificaci\u00f3n, celo por la salvaci\u00f3n delas almas, el Sr. Alm\u00e9ras, a quien Dios hab\u00eda dado sobre ello muchas luces, no tuvo menos ardor en enriquecerse en este tesoro que hab\u00eda mostrado c\u00f3mo descubrir, haciendo un provisi\u00f3n tan buena de este esp\u00edritu que la ha conservado y aumentado con una fidelidad sin igual hasta su muerte. Esto es lo que le hac\u00eda destacar entre los dem\u00e1s, incluso por los externos, que mostraban en los encuentros una estima particular de su virtud. Un sacerdote de la Congregaci\u00f3n ha dicho a este prop\u00f3sito que, hall\u00e1ndose por aquel tiempo en una asamblea de muchos abates y de otras personas de condici\u00f3n y de piedad, les oy\u00f3 hablar con elogio de las virtudes del Sr. Alm\u00e9ras; le compararon con el devoto Berchmans, quien ha sido en su tiempo un excelente modelo de perfecci\u00f3n en la Compa\u00f1\u00eda de Jes\u00fas; a\u00f1adieron incluso que ve\u00edan tambi\u00e9n varias cosas notables en la vida del Sr. Alm\u00e9ras que no encontraban en la de Berchmans, en tanta estima era considerado ya entonces en virtud y en santidad en el mundo.<\/p>\n<p>Sin embargo \u00e9l ten\u00eda tan bajos sentimientos de s\u00ed mismo, que despu\u00e9s de acabar, con su fervor ordinario el a\u00f1o de su seminario, pidi\u00f3 y obtuvo del Sr. Vicente quedarse a\u00fan\u00a0 un segundo a\u00f1o con los principiantes; y habiendo reconocido\u00a0 por su propia experiencia los grandes frutos que se obtienen de estos dos a\u00f1os de seminario, logr\u00f3 de san Vicente que esta santa pr\u00e1ctica\u00a0 fuera observada universalmente en la Congregaci\u00f3n, como lo ha sido en adelante con gran provecho de los principiantes que hasta entonces no hab\u00eda permanecido m\u00e1s que un a\u00f1o en el seminario. Pero uno de los m\u00e1s raros ejemplos de virtud que ha dado es el desprendimiento de sus padres,\u00a0 que \u00e9l practic\u00f3 desde el comienzo y que lo ha continuado durante toda su vida en un grado muy alto de perfecci\u00f3n. Una vez recibido en el seminario, su padre y sus hermanos y dem\u00e1s parientes pr\u00f3ximos ven\u00edan algunas veces las fiestas y los domingos a o\u00edr las v\u00edsperas a San L\u00e1zaro para hablarle a la salida de la iglesia, donde le esperaban al paso; pero \u00e9l se contentaba con saludarlos de paso sin decir nada, se retiraba con los dem\u00e1s al seminario, y segu\u00eda all\u00ed hasta que le ordenaran por parte de su director que fuera a hablarles, cosa que ha observado por el resto de su vida con una maravillosa exactitud, no habiendo hecho nunca en tales encuentros mientras ha sido inferior en la Congregaci\u00f3n, que por la orden expresa de sus superiores. Desde el d\u00eda de su entrada, no fue a ver a su padre durante veinte a\u00f1os que permaneci\u00f3 en el mundo, m\u00e1s que unas o dos veces lo m\u00e1s, cuando estaba enfermo; y a\u00fan no fue cosa suya, sino por obediencia, que le envi\u00f3 el Sr. Vicente, y aunque haya pasado m\u00e1s de una vez por delante de la casa, saliendo por la ciudad para los asuntos de la Congregaci\u00f3n, no entr\u00f3 nunca en ella, como \u00e9l mismo se lo declar\u00f3 a un sacerdote de la Compa\u00f1\u00eda, cuando le escribi\u00f3 para disuadirle del pensamiento que ten\u00eda de ir a ver a sus padres. Pero lo que parece m\u00e1s sorprendente todav\u00eda, es que habiendo sido enviado a\u00a0 a diversos lugares muy alejados, incluso a Roma, donde pas\u00f3 varios a\u00f1os no s\u00f3lo no fue a ver a su padre antes de marchar, aunque no supiera si le volver\u00eda a ver jam\u00e1s, ni tampoco al regresar de los viajes, ni siquiera se lo dec\u00eda, tan muerto estaba al mundo y a las m\u00e1s tiernas inclinaciones de la naturaleza.<\/p>\n<p>Si era tan comedido en este punto para con su padre, no es de extra\u00f1ar que lo fuese con sus hermanos y sus hermanas: no los fue a visitar nunca, ni siquiera a dos de sus hermanas, religiosas muy virtuosas y que le pidieron varias veces por carta que las consolara con sus palabras, para su edificaci\u00f3n\u00a0 espiritual.\u00a0 Sucedi\u00f3 incluso que habiendo sido enviado por el Sr. Vicente al monasterio de Longchamp, donde estaba una de sus hermanas, para tratar de alg\u00fan asunto importante para la gloria de Dioscon una de las principales religiosas, cumpli\u00f3 su comisi\u00f3n y regres\u00f3 sin ver ni preguntar por su hermana, siguiendo firme en esta m\u00e1xima cristiana que ha observado siempre fielmente, de no conceder nada nunca al amor natural para con sus pr\u00f3jimos sino por fuerza de la obediencia; es lo que ha hecho ver en muchas otras ocasiones que se han presentado.<\/p>\n<p>Mientras estaba empleado en las misiones cuya direcci\u00f3n ten\u00eda \u00e9l, su padre le ped\u00eda con frecuencia que fuera a dar una en la tierra de un se\u00f1or que era de sus parientes, y donde \u00e9l habr\u00eda sido recibido con honor y con todas las clases de satisfacciones, pero \u00e9sta sola consideraci\u00f3n fue suficiente para disuadirle, y logr\u00f3 del Sr. Vicente no ser enviado all\u00e1.<\/p>\n<p>\u00c9l neg\u00f3, con el mismo esp\u00edritu, al Sr. abate Alm\u00e9ras, su hermano la gracia que le pidi\u00f3 de habitar en San L\u00e1zaro, aunque fuera por alg\u00fan tiempo; ya que, aunque fuera por entonces Superior general de la Congregaci\u00f3n y tuviera motivos para creer que nadie podr\u00eda decir nada por haberle concedido este privilegio particular a una persona que tan allegada a \u00e9l, \u00e9l no quiso dispensarse a favor suyo de la costumbre ordinaria de la casa, no deseando usar de su poder m\u00e1s que para mantener las reglas\u00a0 y las pr\u00e1cticas de la Congregaci\u00f3n. Se excus\u00f3 por el mismo principio con su hermana, religiosa de Longchamp, por no satisfacer la petici\u00f3n que le hab\u00eda hecho de parte de la abadesa de enviar a alguno de los sacerdotes de su Congregaci\u00f3n, de la que era entonces Superior general, para hacer alguna exhortaci\u00f3n o conferencia espiritual a las religiosas de este monasterio; le expuso sencillamente la costumbre contraria de la Congregaci\u00f3n, alegando su deseo de no dispensarse de las reglas y laudables costumbres que est\u00e1n en uso, sobre todo a favor de la carne y de la sangre, aunque sea por motivos que parecen muy espirituales y no tener otra finalidad que la gloria de Dios.<\/p>\n<h2>Cap\u00edtulo III<\/h2>\n<p><strong>Empleos que ha tenido en la Congregaci\u00f3n antes de ser elegido Superior general: director del seminario interno (1641); asistente de la casa de San L\u00e1zaro; director de los ejercitantes, etc.<\/strong><\/p>\n<p>El progreso que el Sr. Alm\u00e9ras hizo en la perfecci\u00f3n durante los dos a\u00f1os de su seminario fue tan considerable que el Sr. Vicente pens\u00f3 con justa raz\u00f3n que no era necesario ya tenerle por m\u00e1s tiempo oculto en el retiro y el silencio, sino ponerle en el estado de emplear \u00fatilmente en la salvaci\u00f3n de las almas las gracias y los talentos con que Dios le hab\u00eda enriquecido. En este plan, le hizo recibir las sagradas \u00f3rdenes, a las que llev\u00f3 todas las disposiciones que se pod\u00edan esperar de su piedad; por ello, recibi\u00f3 el esp\u00edritu con plenitud como se ha visto claramente en la continuaci\u00f3n de su vida por las bendiciones particulares que Dios ha dado a los diversos empleos a los que se le ha dedicado. El Sr. Vicente comenz\u00f3 al mismo tiempo a disponerle a las principales funciones de la Congregaci\u00f3n, en las que trabaj\u00f3 despu\u00e9s bajo la direcci\u00f3n de los m\u00e1s antiguos de la Congregaci\u00f3n. Habiendo adquirido pronto en ellas un perfecto conocimiento, lleg\u00f3 a ser en escaso a\u00f1os capaz de guiar y dirigir a los dem\u00e1s. As\u00ed, desde el a\u00f1o 1641, el Sr. Vicente le nombr\u00f3 director del seminario interno en el que, con el ejemplo de sus virtudes, sus fervientes y frecuentes exhortaciones, y con su vigilancia y su exactitud elev\u00f3 a la perfecci\u00f3n cristiana y al esp\u00edritu de la Misi\u00f3n a gran n\u00famero de buenos s\u00fabditos, quienes han conservado siempre despu\u00e9s a \u00e9l un afecto muy particular.<\/p>\n<p>Se comportaba de tal manera con todos, que cre\u00edan ser queridos de manera singular por \u00e9l, lo que es un maravilloso secreto para ganarse el coraz\u00f3n de los inferiores y llevarlos a hacer todo lo que se les proponga.<\/p>\n<p>Todos los domingos y d\u00edas de fiesta, hac\u00eda exhortaciones p\u00fablicas en el seminario, a las que, no s\u00f3lo los seminaristas sino tambi\u00e9n las dem\u00e1s personas de la casa que pod\u00edan asistir no dejaban de acudir; y tomando por texto durante dieciocho meses o dos a\u00f1os estas palabras de Nuestro Se\u00f1or: \u00abSed perfectos como vuestro Padre celestial es perfecto\u00bb, trat\u00f3 de las virtudes cristianas y propias de los misioneros con tanta gracia y energ\u00eda que sus discursos eran recibidos por sus oyentes, seg\u00fan nos lo ha contado uno de ellos, como un celeste man\u00e1 y como un fest\u00edn delicioso.<\/p>\n<p>Una de las cosas que \u00e9l inculcaba muy a menudo a los seminaristas, en particular y en p\u00fablico, era no pararse en el aspecto exterior de la virtud, sino pasar al interior y entregarse a una virtud s\u00f3lida, fundada en una entera abnegaci\u00f3n de s\u00ed mismo, que dec\u00eda muy raro, aun entre los que aspiran a la perfecci\u00f3n; usaba de diversas ideas para convencerles de esta verdad, y no omit\u00eda ninguna ocasi\u00f3n para hac\u00e9rsela practicar.<\/p>\n<p>Un d\u00eda entre otros, les orden\u00f3 entregarse a la oraci\u00f3n a pensar ante Dios cu\u00e1l era la virtud m\u00e1s necesaria en un seminarista, con el fin de dedicarse a ella y de tomar resoluciones eficaces; y al d\u00eda siguiente, charlando con ellos sobre el tema, les pidi\u00f3 a todos, a uno tras otro, hasta los hermanos, sus sentimientos; \u00e9l escribi\u00f3 al mismo tiempo sobre un papel las virtudes que cada uno le mostr\u00f3.<\/p>\n<p>Despu\u00e9s de lo cual, habiendo constatado qu\u00e9 virtud hab\u00eda tenido m\u00e1s votos, vio que era la mortificaci\u00f3n de donde tom\u00f3 pie para para exhortarles a la pr\u00e1ctica de esta de esta virtud fundamental del cristianismo y convencerse por el sentimiento de la mayor parte de entre ellos y por otros poderosos motivos a entregarse a ella con fervor y perseverancia.<\/p>\n<p>Empleaba as\u00ed diversos medios para instruir y animar a mortificarse en todo; es lo que \u00e9l ha recomendado tanto a los directores que, despu\u00e9s de \u00e9l, han sido dedicados a este empleo, ense\u00f1\u00e1ndoles los medios de hacer adelantar a los seminaristas por el ejercicio de la mortificaci\u00f3n en la virtud s\u00f3lida y en el verdadero esp\u00edritu del cristianismo, del que pose\u00eda una idea muy alta y un afecto muy ardiente.<\/p>\n<p>Aunque este solo empleo de la direcci\u00f3n de seminario fuera suficiente para ocupar por completo a un director, sobre todo en aquel momento en que hab\u00eda que redactar los estatutos y reglamentos de todos los oficios del seminario y ponerlos en el buen orden en que se los ve hoy todav\u00eda, aparte de las exhortaciones m\u00e1s frecuentes, su asiduidad al oficio en el coro y otros ejercicios que a\u00f1ad\u00eda a las funciones ordinarias del director, no obstante todo ello era como nada en comparaci\u00f3n de su celo: estaba siempre listo para correr con todos los trabajos que la obediencia le propon\u00eda a menudo por encima de esta carga pesada.<\/p>\n<p>El Sr. Vicente conoc\u00eda el alcance y la capacidad de su esp\u00edritu, y los grandes dones que Dios hab\u00eda puesto en \u00e9l para todos los empleos de la Congregaci\u00f3n, le confiaba de ordinario los m\u00e1s importantes y los m\u00e1s dif\u00edciles: as\u00ed que le hizo tambi\u00e9n asistente de la casa de San L\u00e1zaro, empleo que por s\u00ed solo, como es sabido, ocupa a un hombre por completo; le llamaba tambi\u00e9n a su consejo para todas las cosas que se presentaban para resolver y le enviaba muchas veces a tratar con las personas del exterior asuntos principales que requer\u00edan a un hombre ilustrado como \u00e9l. El Sr. Vicente dec\u00eda a veces que estaba seguro de que el Sr. Alm\u00e9ras no se olvidar\u00eda nada de lo que se le confiara, tan seguro estaba de su prudente gesti\u00f3n en todo.<\/p>\n<p>Se dedicaba tambi\u00e9n por aquel entonces a dirigir las misiones de mayor envergadura, y sal\u00eda a flote siempre con una gracia singular. Por un lado manten\u00eda a los obreros que trabajaban bajo su direcci\u00f3n en una observancia exacta del reglamento, y esto m\u00e1s con el ejemplo que con las palabras; y en cuanto lo que se refiere al pueblo, sab\u00eda muy bien, a imitaci\u00f3n de san Pablo, hacerse todo a todos para ganarlos a todos a Dios, predicaba seg\u00fan el esp\u00edritu de la Misi\u00f3n, de una manera sencilla, clara e inteligible a todos, pero s\u00f3lida y docta, y propia para persuadir a sus oyentes. No era menor la gracia que ten\u00eda para tocar los corazones y llevarlos a una perfecta contricci\u00f3n en el tribunal de la penitencia, para reconciliar a los enemigos, poner de acuerdo a los que estaban en proceso y cumplir con todos los ejercicios que se practican en misi\u00f3n, porque todas sus palabras y todas sus acciones estaban no s\u00f3lo animadas de un gran celo, sino tambi\u00e9n acompa\u00f1adas de una rara prudencia y de una dulzura y paciencia inalterables; traeremos en seguida a colaci\u00f3n algunos actos particulares al hablar de estas virtudes.<\/p>\n<p>Fue tambi\u00e9n dedicado con frecuencia en esta misma \u00e9poca la direcci\u00f3n de personas de la m\u00e1s alta calidad, tanto eclesi\u00e1sticos como laicos que ven\u00edan a hacer el retiro espiritual a San L\u00e1zaro, como tambi\u00e9n a la direcci\u00f3n de los ordenandos durante sus ejercicios. Pose\u00eda tan bien el orden de estos ejercicios y todo lo requerido para que fueran un \u00e9xito para gloria de Dios, que ha redactado la mayor parte de sus reglamentos; de ah\u00ed viene que se daba cuenta de las menores faltas que los oficiales subalternos comet\u00edan, y no dejaba de advertirles al punto, lo que obligaba a todo el mundo a ser muy cuidadosos en cumplirlos. Lo que, por \u00faltimo, es m\u00e1s digno de admiraci\u00f3n respecto de su exactitud en este punto, es que \u00e9l lo ha practicado hasta el fin de su vida, incluso en lo m\u00e1s fuerte de sus ocupaciones y de sus sufrimientos.<\/p>\n<p>Habiendo continuado as\u00ed por algunos a\u00f1os ejerciendo el oficio de director del seminario con el cuidado, de toda la casa en calidad de asistente, y todos los dem\u00e1s empleos que acabamos de citar, sucumbi\u00f3 al fin agotado de fuerzas, bajo el peso de tantos trabajos y de las penitencias extraordinarias que hac\u00eda al mismo tiempo. Es lo que oblig\u00f3 a san Vicente, en 1646, a darle por sucesor en la direcci\u00f3n del seminario al Sr Lambert, uno de los m\u00e1s antiguos sacerdotes de la Compa\u00f1\u00eda y uno de los m\u00e1s virtuosos de su tiempo, a fin de compensar la privaci\u00f3n de un director tan excelente por la elecci\u00f3n del m\u00e1s digno sucesor que le pod\u00eda dar.<\/p>\n<p>A partir de ese tiempo, el Sr. Alm\u00e9ras no pudo recuperarse nunca y estuvo siempre hasta los \u00faltimos momentos de su vida en continuos sufrimientos, como se lo declar\u00f3 a algunas personas de confianza. Pero lo que nos debe hacer admirar m\u00e1s aqu\u00ed el plan de Dios sobre su fiel servidor, es que habiendo querido santificarle, con esta larga cruz de las debilidades corporales, cuya duraci\u00f3n ha sido de m\u00e1s de veintisiete a\u00f1os, \u00e9l ha suplido de tal manera las fuerzas del cuerpo con las del esp\u00edritu, animadas de la gracia, que no ha dejado en toda su vida de trabajar para procurar la gloria de Dios y la salvaci\u00f3n de las almas en los mayores y m\u00e1s importantes empleos de la Congregaci\u00f3n.<\/p>\n<p>En efecto, se recuper\u00f3 un poco de su agotamiento, cuando el Sr. Vicente le emple\u00f3 en hacer la visita a algunas casas de las provincias alejadas, y desempe\u00f1\u00f3 esta comisi\u00f3n con un fruto muy grande y una singular satisfacci\u00f3n de todos, lo que ha hecho despu\u00e9s en diversas provincias, con la misma bendici\u00f3n. Y el Sr. Vicente estaba de tal manera persuadido de la gracia que hab\u00eda tenido para llevar a cabo su empleo, que dijo alguna vez que para restablecer una casa en decadencia de la observancia exacta de las reglas, no hab\u00eda m\u00e1s que enviar al Sr. Alm\u00e9ras, y que \u00e9l la devolver\u00eda pronto a su primer estado.<\/p>\n<p>Despu\u00e9s de las primeras visitas que hizo, en especial en G\u00e9nova, el Sr. Vicente le envi\u00f3 a Roma, y le nombr\u00f3 alg\u00fan tiempo despu\u00e9s superior de la casa, adonde su presencia llev\u00f3 muchas bendiciones tanto espirituales como temporales. Era un nuevo establecimiento que hab\u00eda comenzado hac\u00eda dos a\u00f1os, en el que no hab\u00eda a\u00fan m\u00e1s que una casa de alquiler; esta situaci\u00f3n era un gran obst\u00e1culo al progreso de la Congregaci\u00f3n y de sus funciones en aqu\u00e9l pa\u00eds, y una ocasi\u00f3n de muchos l\u00edos, a causa de los cambios de residencia en los que hab\u00eda que estar sometidos a la voluntad de los propietarios. El Sr. Alm\u00e9ras a la vista de la gran necesidad de una casa estable y segura, se lo comunic\u00f3 al Sr. Vicente por cartas para que viera los medios de remediar el asunto cuanto antes. Aunque este prudente superior alabara el celo que le conced\u00eda en esto para la gloria de Dios y del adelanto de la Congregaci\u00f3n, no obstante teniendo por m\u00e1xima inviolable de su conducta seguir paso a paso, como \u00e9l dec\u00eda, la adorable providencia de Dios, sin adelantarse a ella nunca, y no viendo todav\u00eda entonces que le abriera el camino y presentara los medios de ejecutar este plan, se content\u00f3 con responder al Sr. Alm\u00e9ras que la hora no hab\u00eda llegado a\u00fan; que las obras de Dios no se hacen cuando nosotros las deseamos, sino cuando a \u00e9l le place, y que era una bondad particular de su parte sobre nosotros darnos esta ocasi\u00f3n de honrar la pobreza de Nuestro Se\u00f1or, que no hab\u00eda tenido asilo propio en la tierra.<\/p>\n<p>El Sr. Alm\u00e9ras no perdi\u00f3 los \u00e1nimos por estas dificultades; al contrario, adivinando los grandes bienes que la Congregaci\u00f3n producir\u00eda por el servicio de Dios en esta primera ciudad de la cristiandad, si hubiera una casa segura, crey\u00f3 que no deb\u00eda omitir nada de lo que depend\u00eda de \u00e9l para hacer realidad este piadoso proyecto. \u00c9l se resolvi\u00f3 pues, con el consentimiento del Sr.Vicente, a emplear en la compra de esta casa una suma considerable de la herencia de la Sra. Fayet, su abuela; y cuando la hubo recibido, us\u00f3 de todos sus cuidados y de toda su diligencia para encontrar una casa propia para las funciones de la Compa\u00f1\u00eda.<\/p>\n<p>Esto fue sin embargo sin poder encontrar ninguna proporcionada a los medios de que se dispon\u00eda. Se reconoci\u00f3 visiblemente en lo sucesivo que los diversos obst\u00e1culos que se encontraron a partir de entonces en la ejecuci\u00f3n de esta obra eran un efecto particular de la divina Providencia sobre esta casa naciente.<\/p>\n<p>En efecto, habi\u00e9ndose visto privada de su renta alg\u00fan tiempo despu\u00e9s por las guerras civiles que sucedieron en Francia, no subsisti\u00f3 durante dos o tres a\u00f1os m\u00e1s que por el socorro de este dinero, del que consumi\u00f3 una parte durante su extrema necesidad; y a pesar de la disminuci\u00f3n notable de esta suma destinada a la compra de un inmueble, Dios dispuso tan bien las cosas, algunos a\u00f1os despu\u00e9s, que se encontr\u00f3 una casa c\u00f3moda, de un precio razonable, que se compr\u00f3 con el resto de este dinero y la ayuda de algunos bienhechores que la divina Providencia suscit\u00f3 oportunamente para llevar a cabo esta obra importante a su gloria.<\/p>\n<p>Sin embargo, como todas las cosas se logran para el bien de todos los que aman a Dios perfectamente, el Sr. Alm\u00e9ras, que estaba animado en extremo por este amor, sac\u00f3 un gran provecho de todos estos retrasos y accidentes molestos con muchos actos excelentes de una entera sumisi\u00f3n a la voluntad de Dios.<\/p>\n<p>Los practic\u00f3 con tal perfecci\u00f3n, que habiendo regresado a Francia antes de la compra de una casa, dej\u00f3 el dinero en las manos del que le sucedi\u00f3, sin preocuparse y sin dar a conocer que hubiera aportado nunca ning\u00fan bien a la casa de Roma. Pero no debe sorprender que despu\u00e9s de darse a s\u00ed mismo sin reserva a la Compa\u00f1\u00eda hiciera tan poco caso del presente, si bien muy considerable, que le hab\u00eda hecho de sus bienes.<\/p>\n<p>El Sr. Alm\u00e9ras de regreso pues a Francia en 1651, fue establecido algunos meses despu\u00e9s superior de San Carlos, en un tiempo dif\u00edcil a causa de los estragos y pillajes que los extranjeros hac\u00edan entonces en los alrededores de Par\u00eds, y a los que esta casa, que se halla a las afueras de los barrios de Par\u00eds, se encontraba expuesta.<\/p>\n<p>Como el Sr. Vicente sab\u00eda por experiencia que Dios favorec\u00eda en todas partes de forma especial a este digno Misionero, juzg\u00f3 prudentemente que no pod\u00eda dar a esta casa, destituida de todo auxilio humano, un apoyo m\u00e1s fuerte que el que ella pod\u00eda recibir por los m\u00e9ritos de la prudente direcci\u00f3n de tal superior. En efecto, su esperanza no fue vana. Dios protegi\u00f3 en diversas ocasiones a esta casa en medio de los peligros; se vio en particular en una ocasi\u00f3n a prop\u00f3sito de la cual el Sr. Vicente escribi\u00f3 entonces al superior de G\u00e9nova en los t\u00e9rminos siguientes:<\/p>\n<p>\u00abMe hac\u00e9is pues esperar, Se\u00f1or, vuestras oraciones por la paz de este reino: os lo agradezco; nunca la necesidad de ellas fue mayor, no hace m\u00e1s que tres o cuatro noches que ten\u00edamos un ej\u00e9rcito completo por nuestros alrededores; mas como era perseguido por el del rey levantaron el ala por la ma\u00f1ana a toda prisa, y la retaguardia fue atacada fue atacada tras el seminario de San Carlos. Este seminario corri\u00f3 muchos riesgos de ser saqueado. Los soldados que hab\u00edan entrado con estos prop\u00f3sitos quisieron maltratar al Sr. Alm\u00e9ras, que les ofrec\u00eda la mesa y el dinero, con tal de que no causasen da\u00f1os; pero fueron a las habitaciones y rompieron cofres, y cargaron con lo que les pareci\u00f3 lo mejor; y en el momento que sal\u00edan cargados con el bot\u00edn, un suizo y un cochero del Sr. duque de Bouillon que pasaban por all\u00ed vieron este desorden y echaron mano a la espada contra ellos y, tras hacerles devolver lo que hab\u00edan tomado, los pusieron en la calle y se quedaron el d\u00eda y la noche en la casa para impedir que otros ladrones entrasen. Se trata de hombres que no nos conoc\u00edan y que nos defendieron por compasi\u00f3n. Hay que confesar que Dios es admirable por enviarnos esta defensa tan oportuna. Los hemos recibido y tenido como a dos protectores llegados de su parte; se retiraron al d\u00eda siguiente, mi\u00e9rcoles \u00faltimo, bastante satisfechos de nosotros\u00bb.<\/p>\n<p>La extrema desolaci\u00f3n que causaron las guerras civiles en diversas provincias de Francia, en particular en Picard\u00eda y Champa\u00f1a, encendi\u00f3 la caridad de muchas damas de Par\u00eds para procurar el alivio de los pueblos que se encontraban desprovistos de todo socorro humano.<\/p>\n<p>El Sr Vicente, para corresponder a sus piadosas intenciones, envi\u00f3 el a\u00f1o 1650 a varios Misioneros que fueron empleados en proveer a las necesidades espirituales y corporales de una infinidad de pobres abandonados. Pero como la continuaci\u00f3n de estas guerras, que duraron diez a\u00f1os, renov\u00f3 en diversos lugares miserias semejantes, el Sr. Vicente continu\u00f3 tambi\u00e9n siempre las mismas asistencias, con los auxilios de estas caritativas damas envi\u00f3, entre otros obreros propios para este plan, al Sr. Alm\u00e9ras a la ciudad de Laon y lugares vecinos, en 1654, y \u00e9ste llev\u00f3 a cabo su misi\u00f3n con tanta prudencia, caridad y edificaci\u00f3n, que los sacerdotes y los pueblos le veneraban como a un santo, y muchos le calificaban con este nombre al hablar de \u00e9l<\/p>\n<p>Reuni\u00f3 a los pastores y a los sacerdotes del campo que estaban en las ciudades. Les dio varias conferencias espirituales para hacerles distribuir a sus pueblos los socorros que necesitaban; y como no los hab\u00edan dejado m\u00e1s que porque les faltaban los medios necesarios para subsistir en sus parroquias, \u00e9l les proporcion\u00f3 a todos ropas, ornamentos sagrados y pensiones regladas que les eran entregadas de vez en cuando seg\u00fan la necesidad de cada uno; por este medio restableci\u00f3 el culto divino y la administraci\u00f3n de los sacramentos en un gran n\u00famero de iglesias desiertas y despojadas de toda clase de ornamentos.<\/p>\n<p>Procur\u00f3 con la ayuda de un hermano que le acompa\u00f1aba, la asistencia corporal de un gran n\u00famero de pobres de toda edad y condici\u00f3n, y se ocup\u00f3 de retirar a las pobres j\u00f3venes cuya salvaci\u00f3n peligraba debido a la extrema pobreza. Su caridad le hab\u00eda comprometido en trabajos que sobrepasaban con mucho sus fuerzas, cayendo enfermo en el mismo lugar y muy pronto reducido al extremo. El hermano que trabajaba bajo su direcci\u00f3n en el alivio de los pobres de Laon y sus cercan\u00edas acudiendo entonces a atenderle, el Sr. Alm\u00e9ras no pod\u00eda consentir que por \u00e9l se alejara por poco que fuera de los pobres de quienes deb\u00eda ocuparse; le dec\u00eda a menudo: \u00abHermano, id a vuestros pobres y dejadme a m\u00ed\u00bb. Aunque estuviera en peligro de muerte, no quer\u00eda tampoco permitir que el hermano le vigilara por la noche, por miedo a incomodarle: haci\u00e9ndole m\u00e1s sensible su caridad a las necesidades de los pobres y de sus hermanos que a sus propias necesidades.<\/p>\n<p>Quiso al fin Nuestro Se\u00f1or conceder al piadoso Misionero la salud que tan generosamente hab\u00eda consumido en el servicio de sus miembros; y despu\u00e9s de poner buen orden en el alivio de los pobres que todav\u00eda necesitaban auxilios, fue llamado a Par\u00eds por el Sr. Vicente. \u00c9ste le envi\u00f3 alg\u00fan tiempo despu\u00e9s a Sedan para remediar algunas dificultades que se encontraron entonces en la direcci\u00f3n de la parroquia a consecuencia de la oposici\u00f3n de una persona influyente. Cuando se concluy\u00f3 su misi\u00f3n, lo que hizo con mucha prudencia, volvi\u00f3 a Par\u00eds. All\u00ed ejerci\u00f3 nuevamente el oficio de asistente en la casa de San L\u00e1zaro, no obstante sus debilidades ordinarias que no le imped\u00edan emplearse en la direcci\u00f3n de los ordenandos y de otras personas particulares que ven\u00edan a hacer el retiro espiritual, y dem\u00e1s ocupaciones semejantes.<\/p>\n<p>Sin embargo, como el Sr. Vicente deseaba no omitir nada de cuanto pod\u00eda contribuir a restablecerle en una salud m\u00e1s perfecta, le envi\u00f3, en 1657, por consejo de los m\u00e9dicos, a tomar las aguas de Bourbon. Pero el Sr. Alm\u00e9ras, en lugar de encontrar all\u00ed alg\u00fan alivio a sus debilidades, cay\u00f3 enfermo, debido a una direcci\u00f3n particular de la divina Providencia, y puesto en peligro de muerte. Los m\u00e9dicos perdieron las esperanzas, pero no el Sr. Vicente, quien escribi\u00f3 a un sacerdote de la compa\u00f1\u00eda, por entonces al cuidado del enfermo, esta carta. Hace saber igualmente la estima y el afecto que ten\u00eda por un hijo tan digno: \u00abLa enfermedad del Sr. Alm\u00e9ras, dice, nos ha consternado a todos, y no s\u00e9 si alguna vez me he sentido m\u00e1s afligido que ahora, en el temor de que nos veamos privados de \u00e9l como castigo de mis pecados. Espero no obstante de la bondad divina que con el tiempo y los remedios, se le devuelva la salud. Ya s\u00e9 que emple\u00e1is toda vuestra capacidad, y la de los dem\u00e1s con una gran confianza en Dios. S\u00ed, no hay uno solo que no se tenga por afortunado de asistir a este querido enfermo; pero no estando presentes m\u00e1s que vos y el buen hermano Gauthier, descansamos todos en vuestro afecto y en vuestros cuidados; nos contentamos con compartir vuestra pena com\u00fan y ofrec\u00e9rsela a Dios con vuestras personas\u00bb.<\/p>\n<p>Por \u00faltimo, Dios atendiendo a las oraciones del Sr. Vicente y, de todos sus hijos, devolvi\u00f3 la salud al Sr. Alm\u00e9ras y le concedi\u00f3 adem\u00e1s, contra toda apariencia humana, como en otro tiempo a Ezequ\u00edas, otros quince a\u00f1os y medio de vida m\u00e1s para el bien de toda la Congregaci\u00f3n, como vamos a ver.<\/p>\n<p>El Sr. Alm\u00e9ras regres\u00f3 a Par\u00eds despu\u00e9s de un mes de ausencia; all\u00ed continu\u00f3 el oficio de asistente de la casa hasta el a\u00f1o de 1660. Ese a\u00f1o, el Sr. Vicente le envi\u00f3 a la casa de Richelieu, de la que hab\u00eda sido nombrado visitador unos a\u00f1os antes, lo mismo que de otras casas de la Compa\u00f1\u00eda de la provincia del Poitou. All\u00ed se encontraba a la llegada de la corte que regresaba de Guienne despu\u00e9s de la conclusi\u00f3n de la paz general, y all\u00ed tribut\u00f3 sus cumplidos a sus Majestades.<\/p>\n<p>Hizo la visita de la casa tras la partida de la corte; y se dispuso para regresar a Par\u00eds, siguiendo la orden del Sr.Vicente, cuando cay\u00f3 enfermo hasta temer que ten\u00eda los d\u00edas contados. Dios se complac\u00eda de esta manera en probar la paciencia de su fiel servidor, no s\u00f3lo por sus debilidades ordinarias, que eran continuas, sino tambi\u00e9n por grandes y frecuentes enfermedades, para aumentar sus m\u00e9ritos mediante el buen uso que hac\u00eda de estas rudas pruebas. Esta enfermedad continu\u00f3 por varias semanas, aunque a intervalos sent\u00eda ligeras mejor\u00edas. El Sr. Vicente le escribi\u00f3 durante aquel tiempo varias cartas muy llenas de sentimientos extraordinarios de estima y de amor hacia \u00e9l, como por el m\u00e1s digno de sus hijos y el m\u00e1s firme apoyo de su Congregaci\u00f3n. Traeremos aqu\u00ed a colaci\u00f3n algunos extractos como fieles y muy seguros testimonios de la excelencia de la virtud y del m\u00e9rito del Sr. Alm\u00e9ras.<\/p>\n<p>\u00abToda esta casa, le escrib\u00eda el Sr. Vicente en una de sus cartas, siente vivamente vuestro mal redobla sus instancias ante la divina Bondad por vuestra conservaci\u00f3n, y no puedo expresaros la parte que yo tengo en ello en particular; pero viva la voluntad de Dios y que sea siempre alabado por todas sus disposiciones sobre nosotros! Ciertamente, sentir\u00eda mucho en tenerlas que soportar, si las considerara fuera del plan divino, que ordena todo para lo mejor. No pensaba que un accidente as\u00ed os debiera suceder cuando os envi\u00e9 a Richelieu, pero no lo volver\u00e9 a hacer, aunque vos y yo vivi\u00e9ramos quince o veinte a\u00f1os; la Compa\u00f1\u00eda sufre con la privaci\u00f3n de vuestra presencia, y me sentir\u00e9 m\u00e1s consolado con vuestro regreso de lo que podr\u00eda estar por cualquier otro asunto que pudiera suceder\u00bb.<\/p>\n<p>Las otras cartas est\u00e1n llenas de parecidos sentimientos; mas, para abreviar, a\u00f1adiremos tan s\u00f3lo lo que el Sr. Vicente, un mes antes de su muerte o as\u00ed, le informa en la \u00faltima, despu\u00e9s de enterarse que le iba un poco mejor: \u00ab\u00bfCu\u00e1ndo llegar\u00e1 el d\u00eda, Se\u00f1or, le dice, que tengamos el consuelo completo de vuestra recuperaci\u00f3n? C\u00f3mo lo deseo, ser\u00e1 una grande gracia, as\u00ed se lo pido frecuentemente, no s\u00f3lo po mi inter\u00e9s particular, que no es peque\u00f1o, ya que lleno de estima y de ternura por vos, yo soy el primero que sufre con vuestro mal y vuestra ausencia; pero tambi\u00e9n por la Compa\u00f1\u00eda, la cual, habiendo recibido de vos por la gracia de Dios una gran edificaci\u00f3n, necesita a\u00fan de vuestra ayuda y de vuestros ejemplos. Os digo esto, Se\u00f1or, con un sentimiento de gratitud para con Dios y para con vos, y no digo m\u00e1s, porque ello basta para el fin que yo pretendo, que es mostraros que har\u00e9is una cosa agradable a Dios si os conserv\u00e1is y os cuid\u00e1is por el reposo y los remedios que ten\u00e9is al alcance, y sobre todo por el socorro de Dios. \u00c9l no os negar\u00e1 las fuerzas de cuerpo y esp\u00edritu necesarias para el plan que tiene sobre la Compa\u00f1\u00eda, si se los ped\u00eds por su Hijo Nuestro Se\u00f1or, el cual, habiendo suscitado la Compa\u00f1\u00eda para su servicio, os ha llamado tambi\u00e9n a vos tan \u00fatilmente por su gracia. No ahorr\u00e9is pues nada de lo que puede contribuir a vuestra salud y al adelanto de vuestro regreso, tras el cual estamos suspirando\u00bb.<\/p>\n<p>El Sr. Alm\u00e9ras, habiendo recibido esta \u00faltima carta, parti\u00f3 de Richelieu, todo lo indispuesto que estaba, echado en unas parihuelas, y lleg\u00f3 a Par\u00eds el 24 de septiembre del 1660, tres d\u00edas antes de la muerte del Sr. Vicente. Estaba tan abatido por la fatiga del camino, que hubo que llevarlo en primer lugar a la enfermer\u00eda sin poder hablar entonces al Sr. Vicente; pero este caritativo padre, gozoso en extremo por la llegada de este muy digno hijo, se le adelant\u00f3 al d\u00eda siguiente por la ma\u00f1ana, haci\u00e9ndose llevar a la enfermer\u00eda. Despu\u00e9s de o\u00edr la misa, convers\u00f3 con \u00e9l en particular largo tiempo y, como se puede adivinar, le instruy\u00f3 obre las cosas m\u00e1s importantes para el buen orden de su Congregaci\u00f3n. Despu\u00e9s de lo cual, se hizo llevar a su habitaci\u00f3n, y viendo todos sus deseos cumplidos en la tierra por la presencia del que cre\u00eda deber sucederle, no pens\u00f3 m\u00e1s que en unirse m\u00e1s perfectamente a Dios mediante la separaci\u00f3n de todas las cosas de este mundo, y la liberaci\u00f3n de la larga prisi\u00f3n de su cuerpo. Es lo que Dios le concedi\u00f3 pronto, entrando desde el d\u00eda siguiente en agon\u00eda y habiendo terminado su santa vida con una muerte dichosa, la ma\u00f1ana del d\u00eda siguiente, 27 de septiembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cap\u00edtulo I: De su vocaci\u00f3n a la Congregaci\u00f3n de la Misi\u00f3n. Para conocer mejor la fuerza de la gracia de Dios en la vocaci\u00f3n del Sr. Alm\u00e9ras, es necesario saber con qu\u00e9 lazos estaba unido &#8230; <a href=\"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":391249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19],"tags":[230,144,172,143],"class_list":["post-43002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biografias-de-misioneros-paules","tag-almeras","tag-lambert","tag-pobreza","tag-san-lazaro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ren\u00e9 Alm\u00e9ras (1613-1672) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ren\u00e9 Alm\u00e9ras (1613-1672) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Cap\u00edtulo I: De su vocaci\u00f3n a la Congregaci\u00f3n de la Misi\u00f3n. Para conocer mejor la fuerza de la gracia de Dios en la vocaci\u00f3n del Sr. Alm\u00e9ras, es necesario saber con qu\u00e9 lazos estaba unido ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-25T05:20:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-27T10:06:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"45 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"Ren\u00e9 Alm\u00e9ras (1613-1672)\",\"datePublished\":\"2014-12-25T05:20:21+00:00\",\"dateModified\":\"2016-07-27T10:06:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/\"},\"wordCount\":9090,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Almer\u00e1s\",\"Lambert\",\"Pobreza\",\"San L\u00e1zaro\"],\"articleSection\":[\"Biograf\u00edas de Misioneros Pa\u00fales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/\",\"name\":\"Ren\u00e9 Alm\u00e9ras (1613-1672) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2014-12-25T05:20:21+00:00\",\"dateModified\":\"2016-07-27T10:06:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/rene-almeras-1613-1672\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ren\u00e9 Alm\u00e9ras (1613-1672)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ren\u00e9 Alm\u00e9ras (1613-1672) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/","og_locale":"es_ES","og_type":"article","og_title":"Ren\u00e9 Alm\u00e9ras (1613-1672) - Somos Vicencianos","og_description":"Cap\u00edtulo I: De su vocaci\u00f3n a la Congregaci\u00f3n de la Misi\u00f3n. Para conocer mejor la fuerza de la gracia de Dios en la vocaci\u00f3n del Sr. Alm\u00e9ras, es necesario saber con qu\u00e9 lazos estaba unido ... Read More","og_url":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2014-12-25T05:20:21+00:00","article_modified_time":"2016-07-27T10:06:35+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"45 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"Ren\u00e9 Alm\u00e9ras (1613-1672)","datePublished":"2014-12-25T05:20:21+00:00","dateModified":"2016-07-27T10:06:35+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/"},"wordCount":9090,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","keywords":["Almer\u00e1s","Lambert","Pobreza","San L\u00e1zaro"],"articleSection":["Biograf\u00edas de Misioneros Pa\u00fales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/","url":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/","name":"Ren\u00e9 Alm\u00e9ras (1613-1672) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","datePublished":"2014-12-25T05:20:21+00:00","dateModified":"2016-07-27T10:06:35+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/rene-almeras-1613-1672\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ren\u00e9 Alm\u00e9ras (1613-1672)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-bbA","jetpack-related-posts":[{"id":131832,"url":"https:\/\/vincentians.com\/es\/rene-almeras-c-m-1612-1672-superior-general\/","url_meta":{"origin":43002,"position":0},"title":"Ren\u00e9 Alm\u00e9ras, C.M. (1612-1672) (Superior General)","author":"Mitxel Olabu\u00e9naga","date":"02\/12\/2014","format":false,"excerpt":"Si Vicente de Pa\u00fal quer\u00eda a sus misioneros humildes y sencillos, no se refer\u00eda con ello al origen familiar, sino a la vitudes que uno deb\u00eda adquirir. Esto se puede comprobar en uno de los dos en qi\u00e9n puso su confianza para el gobierno de la CM, Renato Almer\u00e1s. Aunque\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32423,"url":"https:\/\/vincentians.com\/es\/el-senor-rene-almeras-padre-1575-1658\/","url_meta":{"origin":43002,"position":1},"title":"El se\u00f1or Ren\u00e9 Alm\u00e9ras, padre (1575-1658)","author":"Mitxel Olabu\u00e9naga","date":"07\/04\/2014","format":false,"excerpt":"El 2 de marzo de 1657, un seminarista de edad ya bien avanzada \u2013ten\u00eda ochenta y dos a\u00f1os- entraba en el seminario interno. Era el Sr. Alm\u00e9ras, padre del Sr. Ren\u00e9 Alm\u00e9ras, y veamos c\u00f3mo anunci\u00f3 san Vicente este noticia al Sr. Get, superior de la Misi\u00f3n de Marsella \"El\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":38142,"url":"https:\/\/vincentians.com\/es\/historia-general-de-la-c-m-hasta-el-ano-1720-02-eleccion-del-sr-almeras-elegido-2%c2%ba-general-de-la-congregacion-1661\/","url_meta":{"origin":43002,"position":2},"title":"Historia general de la C.M., hasta el a\u00f1o 1720 (02. Elecci\u00f3n del sr. Almer\u00e1s elegido 2\u00ba general de la Congregaci\u00f3n. 1661)","author":"Mitxel Olabu\u00e9naga","date":"10\/08\/2014","format":false,"excerpt":"II. Elecci\u00f3n del sr. Almer\u00e1s elegido 2\u00ba general de la Congregaci\u00f3n. 1661 El sr. Vicente tuvo el consuelo de ver, antes de su muerte, la Congregaci\u00f3n bastante bien asentada y ten\u00eda motivos para esperar que esta Compa\u00f1\u00eda de la que hab\u00eda resultado Fundador, sin pensar al principio en formar ninguna\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"San Vicente de Pa\u00fal","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/05\/vincent_de_paul-205x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":39287,"url":"https:\/\/vincentians.com\/es\/historia-general-de-la-c-m-hasta-el-ano-1720-20-muerte-del-sr-almeras-el-sr-jolly-su-sucesor\/","url_meta":{"origin":43002,"position":3},"title":"Historia general de la C.M., hasta el a\u00f1o 1720 (20. Muerte del sr. Almer\u00e1s. El sr. Jolly su sucesor)","author":"Mitxel Olabu\u00e9naga","date":"24\/10\/2014","format":false,"excerpt":"\u00a0XX. Muerte del sr. Almer\u00e1s. El sr. Jolly su sucesor Dios retir\u00f3 del mundo al sr. Almer\u00e1s despu\u00e9s de probar su paciencia con un largo agotamiento, acompa\u00f1ado de hidropes\u00eda. Su fallecimiento lleg\u00f3 el dos de setiembre, fiesta de San L\u00e1zaro, 1672. Fue enterrado al lado derecho del sr. Vicente en\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"San Vicente de Pa\u00fal","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/05\/vincent_de_paul-205x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":115915,"url":"https:\/\/vincentians.com\/es\/obrero-de-la-primera-hora-padre-portail-en-mosaico-iv\/","url_meta":{"origin":43002,"position":4},"title":"Obrero de la primera hora: Padre Portail en mosaico (IV)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/05\/2021","format":false,"excerpt":"4. Definici\u00f3n del perfil institucional de la Misi\u00f3n La Asamblea General de 1642 se hizo c\u00e9lebre. La Congregaci\u00f3n, 17 a\u00f1os despu\u00e9s de su fundaci\u00f3n, contaba con 10 Casas y estaba a punto de iniciarse el proceso de organizaci\u00f3n de sus primeras Provincias. En esa Asamblea, el Padre Vicente present\u00f3, por\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":131834,"url":"https:\/\/vincentians.com\/es\/edme-jolly-c-m-1622-1697-superior-general\/","url_meta":{"origin":43002,"position":5},"title":"Edm\u00e8 Jolly, C.M. (1622-1697) (Superior General)","author":"Mitxel Olabu\u00e9naga","date":"06\/12\/2014","format":false,"excerpt":"Tambi\u00e9n el segundo sucesor de Vicente de Pa\u00fal era de familia de cierto relieve social. Su padre era fiscal real en la di\u00f3cesis de Meaux, all\u00ed fue donde naci\u00f3 el hijo en 1622. Con 19 a\u00f1os y despu\u00e9s de haber estudiado filosof\u00eda y teolog\u00eda form\u00f3 parte del s\u00e9quito del Embajador\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/43002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=43002"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/43002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/391249"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=43002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=43002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=43002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}