{"id":405137,"date":"2024-03-12T08:18:23","date_gmt":"2024-03-12T07:18:23","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=405137"},"modified":"2023-08-13T20:19:27","modified_gmt":"2023-08-13T18:19:27","slug":"la-palabra-de-dios-en-san-vicente-de-paul-v","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/","title":{"rendered":"La Palabra de Dios en san Vicente de Pa\u00fal (V)"},"content":{"rendered":"<p>UN ACERCAMIENTO A LA BIBLIA QUE SE TEJ\u00cdA EN EL RITMO DE SU PROPIO CAMINAR<\/p>\n<p>Es opini\u00f3n de quienes han profundizado la cercan\u00eda de san Vicente a la Sagrada Escritura s\u00f3lo hacia la edad de sus 36 a\u00f1os, que coincide con sus dos momentos iluminadores de Ch\u00e1tillon et de Folleville, Vicente entre en un proceso no de lectura o cono\u00adcimiento sino de lectura espiritual, iluminadora, transformadora de su mundo interior y creadora de energ\u00eda evangelizadora.<\/p>\n<p>\u00bfPod\u00eda san Vicente disponer de inter\u00e9s, de tiempo y de mate\u00adrial b\u00edblico para que su estudio pudiese desembocar a resultados diferentes de los que constatamos?<\/p>\n<p>Tal vez en los caminos de Dios, ese momento misterioso de la Providencia divina de que habl\u00f3 tanto el Fundador, le faltaba aun, es decir, el <em>\u00abEMAUS DE LOS POBRES\u00bb, que abrieron sus ojos y su coraz\u00f3n a la comprensi\u00f3n exacta de la Escrituras&#8230; la periferia espiritual estaba muy reducida pero por acci\u00f3n de Dios otro paso comienza y un Vicente de Pa\u00fal nace y crece y en su coraz\u00f3n nace de otra forma la Palabra de Dios.<\/em><\/p>\n<p>Vicente no acelera sus pasos, pero Dios parece acelerar los suyos y obligar a Vicente a entrar sencillamente <em>\u00abdentro de los sentimientos de Jes\u00fas desde donde la Biblia se lee diferentemen\u00adte\u00bb, <\/em>que le condujeron como a Pablo a decir <em>\u00abnada me agrada sino es en Jesucristo.<\/em><\/p>\n<p>UNA HERMEN\u00c9UTICA INVENTIVA<\/p>\n<p>El apoyarse en las realidades invisibles proyecta algunas luces sobre la agilidad desconcertante de la hermen\u00e9utica vicenciana. Catequista por naturaleza y por vocaci\u00f3n, el buen se\u00f1or Vicente vive preocupado casi hasta la obsesi\u00f3n de hacer conocer bien a los pobres la buena noticia del Hijo de Dios. El m\u00e9todo m\u00e1s adaptado y tambi\u00e9n el m\u00e1s f\u00e1cil era el ofrecido por Jes\u00fas mismo. El Salvador no solamente utiliz\u00f3 el \u00abpeque\u00f1o m\u00e9to\u00addo\u00bb, sino que tambi\u00e9n ha utilizado las comparacio\u00adnes m\u00e1s comunes. <em>\u00ab\u00a1Que maravillas podr\u00eda \u00e9l haberle ense\u00f1ado al pueblo! \u00a1Qu\u00e9 secretos no habr\u00eda podido descubrir de la divini\u00addad y de sus admirables perfecciones, el que era la sabidur\u00eda eter\u00adna de su Padre! Pero ya ve usted c\u00f3mo hablaba de forma inteligi\u00adble y se serv\u00eda de comparaciones familiares: el labrador, el vi\u00f1ador<\/em>, <em>el campo, la vi\u00f1a<\/em>, <em>de un grano de mostaza<\/em>. <em>As\u00ed es c\u00f3mo tiene usted que hablar, si quiere que le entienda el pue\u00adblo, al que anuncia la palabra de Dios\u00bb<\/em>.<\/p>\n<p>Con una reflexi\u00f3n m\u00e1s atenta descubrimos que el pensamien\u00adto y la expresi\u00f3n de este catequista b\u00edblico explotan y funden su reflexi\u00f3n sobre un doble movimiento interactivo.<\/p>\n<p><em>El primero, <\/em>su certeza de que la gracia viene del Padre, se manifiesta en el Hijo y se difunde en el Esp\u00edritu Santo. Esta gra\u00adcia que el bautismo ha difundido en los corazones invita a unir\u00adse a Jes\u00fas para unirse al Padre.<\/p>\n<p><em>El segundo <\/em>despierta y crea un lenguaje a partir de los pobres. Los pobres constituyen el coraz\u00f3n de la Iglesia. <em>\u00abEs entre ellos donde se conserva la verdadera religi\u00f3n, la fe viva; creen senci\u00adllamente, sin hurgar; sumisi\u00f3n a las \u00f3rdenes, paciencia en las miserias que hay que sufrir mientras Dios quiera, unos por las guerras, otros por trabajar todo el d\u00eda bajo el ardor del sol. Vivi\u00admos del patrimonio de Jesucristo, del sudor de los pobres\u00bb<\/em>. Los pobres son los amos y se\u00f1ores. Nuestro Se\u00f1or no solamente tiene como hecho a \u00e9l mismo lo que se hace a los pobres sino que \u00c9l est\u00e1 en el pobre.<\/p>\n<p>En lo m\u00e1s profundo de su conciencia, el se\u00f1or Vicente con\u00adserva algunas convicciones muy s\u00f3lidas que el formula diversa\u00admente seg\u00fan las ocasiones. Podemos retener tres:<\/p>\n<ul>\n<li><em>La primera es que el hombre no permanece siempre en el mismo estado. <\/em>Es en Job en donde lo ha aprendido, parangon\u00e1n\u00addolo con los justos y de lo cual el hablar\u00e1 con frecuencia.<\/li>\n<li><em>La segunda es la que la Escritura formula en diferentes libros, es que Dios solo da la vida y la muerte. <\/em>El hace morir y vivifica.<\/li>\n<li><em>La tercera es que Dios \u00abha querido que todas las cosas del mundo sean inciertas y perecederas para que nosotros busque\u00admos en \u00c9l solamente la solidez de nuestros deseos y de nuestros asuntos\u00bb<\/em>. Las degradaciones que Dios ha permi\u00adtido son destinadas a instruir nuestra d\u00e9bil conciencia de que solo Dios hace bien todo lo que se hace y que le pertenece a \u00c9l solamente el dar t\u00e9rmino a lo que \u00c9l ha comenzado. El mismo d\u00eda de su muerte, a la una y media de la ma\u00f1ana del 27 de sep\u00adtiembre de 1660, al momento en que se le ped\u00eda una bendici\u00f3n para su familia, \u00e9l respondi\u00f3: <em>Que Dios la bendiga \u00bb <\/em>y levantan\u00addo la mano dijo: <em>\u00abQui coepit opus, perficiet\u00bb \u00abQuien comenz\u00f3 en vosotros esta obra que \u00c9l la lleve a t\u00e9rmino\u00bb<\/em>.<\/li>\n<\/ul>\n<p>Dirigi\u00e9ndose a auditorios muy diferentes: gentes de la parro\u00adquia y ni\u00f1os en Clichy y tal vez en Ch\u00e1tillon-les-Dombes, Damas de la Caridad o Hijas de la Caridad, sacerdotes o herma\u00adnos de la Misi\u00f3n, san Vicente simplifica o actualiza su exposici\u00f3n.<\/p>\n<p>Evoca los personajes, les da vida y los hace hablar. Termina habitualmente sus conferencias a trav\u00e9s de una oraci\u00f3n dirigida direc\u00adtamente a Jes\u00fas o a la Sant\u00edsima Virgen. (Existe una colecci\u00f3n de 84 oraciones en el libro: \u00abEn oraci\u00f3n con san Vicente\u201d). Las personas son arrancadas del pasado como Ad\u00e1n, No\u00e9, Abraham, Mois\u00e9s y a trav\u00e9s de una metodolog\u00eda pro\u00adpia se convierten en seres vivientes. Con vivacidad de lenguaje, san Vicente traduce II Sm 11, 2: <em>\u00abUna mirada (seductora) perdi\u00f3 a David\u00bb <\/em>(SVP, IX, 26). \u00c9l nos sorprende y nos hace sonre\u00ad\u00edr cuando dice a las Hijas de la Caridad que <em>\u00abNuestro Se\u00f1or <\/em>cuando, al ir a visitar a los pobres, pasaba delante de las taber\u00adnas, se re\u00edan de \u00e9l, se burlaban, y ten\u00eda que escuchar las cancio\u00adnes indecentes y las palabras groseras que se dec\u00edan en aquellos lugares\u00bb.<\/p>\n<p>Muy tranquilamente, \u00e9l afirma tambi\u00e9n que san Pedro lloraba continuamente y que Margarita Ch\u00e9tif, que se siente inc\u00f3moda de vestirse en Arras con una cofia del centro de Francia deb\u00eda imitar a Nuestro Se\u00f1or que no cambi\u00f3 nunca su vestido yendo a Egipto.<\/p>\n<p>La raz\u00f3n por la cual las Hijas de la Caridad deben ser sobrias es que Nuestro Se\u00f1or Jesucristo, fuera de la Pascua, en la cual com\u00eda el cordero o en una otra ocasi\u00f3n hab\u00eda comido el pescado, el solo com\u00eda pan.<\/p>\n<p>Cuando su memoria se vuelve perezosa o d\u00e9bil el invierte el orden las palabras o atribuye un texto del Apocalipsis a san Pablo. Citando el salmo 65, 1, \u00e9l escribe tomando el texto masor\u00e9tico: <em>\u00abEl silencio es una alabanza a Dios en Si\u00f3n\u00bb, dice el profeta y san Jer\u00f3nimo lo repite\u00bb<\/em>. M. Ch. Ozenne, al recibir una carta de san Vicente, pod\u00eda sorprenderse de una traducci\u00f3n de ese g\u00e9nero, pero M. B. Codoing, superior de la casa de Roma habr\u00eda buscado en vano el pasaje del Nuevo Testamento a\u00f1adido por san Vicente en su carta: <em>\u00abO que bien sab\u00eda el Se\u00f1or lo que el afirmaba al decir malum pecus inficit omne pecus\u201d<\/em>. Esta afirmaci\u00f3n esta entresacada de las s\u00e1tiras de Juvenal. Es verdad que la frase se volvi\u00f3 \u00abpro\u00adverbial\u00bb y que la regla de san Benito pide \u00abque la oveja enferma debe ser descartada para que no infecte todo el reba\u00f1o\u00bb. Y el se\u00f1or Vicente sin duda no ignoraba la regla benedicti\u00adna.<\/p>\n<p>CEME<\/p>\n<p>\u00c1lvaro Restrepo \u00c1lzate<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN ACERCAMIENTO A LA BIBLIA QUE SE TEJ\u00cdA EN EL RITMO DE SU PROPIO CAMINAR Es opini\u00f3n de quienes han profundizado la cercan\u00eda de san Vicente a la Sagrada Escritura s\u00f3lo hacia la edad de &#8230; <a href=\"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":405111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[374,226],"tags":[],"class_list":["post-405137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Palabra de Dios en san Vicente de Pa\u00fal (V) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Palabra de Dios en san Vicente de Pa\u00fal (V) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"UN ACERCAMIENTO A LA BIBLIA QUE SE TEJ\u00cdA EN EL RITMO DE SU PROPIO CAMINAR Es opini\u00f3n de quienes han profundizado la cercan\u00eda de san Vicente a la Sagrada Escritura s\u00f3lo hacia la edad de ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T07:18:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"La Palabra de Dios en san Vicente de Pa\u00fal (V)\",\"datePublished\":\"2024-03-12T07:18:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/\"},\"wordCount\":1348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aa.jpeg?fit=1152%2C648&ssl=1\",\"articleSection\":[\"Espiritualidad\",\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/\",\"name\":\"La Palabra de Dios en san Vicente de Pa\u00fal (V) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aa.jpeg?fit=1152%2C648&ssl=1\",\"datePublished\":\"2024-03-12T07:18:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aa.jpeg?fit=1152%2C648&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aa.jpeg?fit=1152%2C648&ssl=1\",\"width\":1152,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-palabra-de-dios-en-san-vicente-de-paul-v\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Palabra de Dios en san Vicente de Pa\u00fal (V)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Palabra de Dios en san Vicente de Pa\u00fal (V) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/","og_locale":"es_ES","og_type":"article","og_title":"La Palabra de Dios en san Vicente de Pa\u00fal (V) - Somos Vicencianos","og_description":"UN ACERCAMIENTO A LA BIBLIA QUE SE TEJ\u00cdA EN EL RITMO DE SU PROPIO CAMINAR Es opini\u00f3n de quienes han profundizado la cercan\u00eda de san Vicente a la Sagrada Escritura s\u00f3lo hacia la edad de ... Read More","og_url":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2024-03-12T07:18:23+00:00","og_image":[{"width":1152,"height":648,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"La Palabra de Dios en san Vicente de Pa\u00fal (V)","datePublished":"2024-03-12T07:18:23+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/"},"wordCount":1348,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1","articleSection":["Espiritualidad","Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/","url":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/","name":"La Palabra de Dios en san Vicente de Pa\u00fal (V) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1","datePublished":"2024-03-12T07:18:23+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1","width":1152,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/la-palabra-de-dios-en-san-vicente-de-paul-v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Palabra de Dios en san Vicente de Pa\u00fal (V)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1Hot","jetpack-related-posts":[{"id":386810,"url":"https:\/\/vincentians.com\/es\/santa-virgen-maria-madre-de-dios-reflexion-de-la-s-s-v-p-en-estados-unidos\/","url_meta":{"origin":405137,"position":0},"title":"Santa Virgen Mar\u00eda, Madre de Dios (reflexi\u00f3n de la S.S.V.P. en Estados Unidos)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/01\/2016","format":false,"excerpt":"Evangelio: (San Lucas 2:16-21) Fueron apresuradamente y hallaron a Mar\u00eda y a Jos\u00e9 con el reci\u00e9n nacido acostado en el pesebre. Entonces contaron lo que los \u00e1ngeles les hab\u00edan dicho del ni\u00f1o. Todos los que escucharon a los pastores quedaron maravillados de lo que dec\u00edan. Mar\u00eda, por su parte, guardaba\u2026","rel":"","context":"En \u00abHomil\u00edas y reflexiones, A\u00f1o C\u00bb","block_context":{"text":"Homil\u00edas y reflexiones, A\u00f1o C","link":"https:\/\/vincentians.com\/es\/category\/homilias-y-reflexiones-a-la-palabra-de-dios\/homilias-y-reflexiones-ano-c\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/reflexiones-palabra-de-dios.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/reflexiones-palabra-de-dios.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/reflexiones-palabra-de-dios.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/reflexiones-palabra-de-dios.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/reflexiones-palabra-de-dios.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119421,"url":"https:\/\/vincentians.com\/es\/la-espiritualidad-de-san-vicente\/","url_meta":{"origin":405137,"position":1},"title":"La espiritualidad de san Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/02\/2015","format":false,"excerpt":"Introducci\u00f3n En \"San Vicente y la Caridad\", Andr\u00e9 Dodin muestra bien la inutilidad de la empresa, que consistir\u00eda en intentar definir la doctrina espiritual de san Vicente, y demuestra que no pod\u00eda tratarse m\u00e1s que de una doctrina en una vida. Es pues, siguiendo la vida de san Vicente, analizando\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"nddm_vincent1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/03\/nddm_vincent1-300x242.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130881,"url":"https:\/\/vincentians.com\/es\/el-camino-de-san-vicente-actos-de-piedad\/","url_meta":{"origin":405137,"position":2},"title":"El camino de San Vicente: Actos de piedad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/02\/2015","format":false,"excerpt":"Escucha, hermano, lo que dice san Vicente acerca de la vida de piedad: Cristo el Se\u00f1or y sus disc\u00edpulos ten\u00edan sus ejercicios de piedad, como por ejemplo subir al templo, retirarse de vez en cuando a la soledad, dedicarse a la oraci\u00f3n, y cosas semejantes. Por ello parece muy justo\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"oracion-en-capilla","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/oracion-en-capilla-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":119618,"url":"https:\/\/vincentians.com\/es\/relectura-de-los-acontecimientos-desde-la-fe-para-reconocer-en-ellos-la-presencia-de-dios\/","url_meta":{"origin":405137,"position":3},"title":"Relectura de los acontecimientos desde la Fe para reconocer en ellos la presencia de Dios","author":"Francisco Javier Fern\u00e1ndez Chento","date":"20\/06\/2015","format":false,"excerpt":"Introducci\u00f3n En su carta de Adviento 2010, nuestro Superior general, el Padre Gregory nos invit\u00f3 a reconocer y dejarnos interpelar por la presencia activa de Dios en el coraz\u00f3n y en la vida de los pobres. Nos dice: \"\u2026 han acabado por reconocer que Dios es el don de la\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"manos","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/manos-300x284.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":118401,"url":"https:\/\/vincentians.com\/es\/el-puro-amor-en-san-vicente-y-santa-luisa\/","url_meta":{"origin":405137,"position":4},"title":"El &quot;puro amor&quot; en san Vicente y santa Luisa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/10\/2021","format":false,"excerpt":"Introducci\u00f3n hist\u00f3rica No es f\u00e1cil saber de qui\u00e9n hab\u00edan tomado esta doctrina y este t\u00e9rmino el se\u00f1or Vicente y la se\u00f1orita Legras, Luisa de Marillac. Muchos autores de su \u00e9poca hab\u00edan publicado libros en los que aparec\u00eda esta doctrina del amor desinteresado de Dios, pero sin duda el t\u00e9rmino proced\u00eda\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":116854,"url":"https:\/\/vincentians.com\/es\/cristo-regla-de-la-mision-xi-429\/","url_meta":{"origin":405137,"position":5},"title":"Cristo, Regla de la Misi\u00f3n (XI, 429)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/05\/2015","format":false,"excerpt":"Fundamento cristol\u00f3gico del carisma Mi vivir es Cristo (FIp 1, 21) 1) Todo cristiano, como san Pablo, debe tener su propia cristolog\u00eda, mi vivir es Cristo (Flp 1, 21), que consiste en el modo c\u00f3mo responde a la interpelaci\u00f3n que Cristo le hace para seguirlo e imitarlo: Ven y s\u00edgueme\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"ESCUDOCM","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/09\/ESCUDOCM8.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/405137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=405137"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/405137\/revisions"}],"predecessor-version":[{"id":405138,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/405137\/revisions\/405138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/405111"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=405137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=405137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=405137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}