{"id":404665,"date":"2023-05-10T08:08:29","date_gmt":"2023-05-10T06:08:29","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=404665"},"modified":"2023-01-16T10:10:07","modified_gmt":"2023-01-16T09:10:07","slug":"el-valor-del-catecismo-en-san-vicente-de-paul-viii","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/","title":{"rendered":"El valor del catecismo en san Vicente de Pa\u00fal (VIII)"},"content":{"rendered":"<p>3.1. ALGUNAS <em>LUCES <\/em>EN LA ENSE\u00d1ANZA DEL CATECISMO<\/p>\n<p>Comencemos por las <em>luces, <\/em>que existieron, y que conviene reconocer. En primer lugar, conviene se\u00f1alar que el concilio de Trento y el impulso misionero y catequ\u00e9tico que origin\u00f3 en el seno del pueblo cristiano cat\u00f3lico supuso un <em>extraordinario renacimiento espiritual <\/em>que nos hace evocar otras etapas glorio\u00adsas de la historia en la Iglesia<sup>135<\/sup>. Las misiones y el catecismo sir\u00advieron para atajar la ignorancia religiosa de los cat\u00f3licos de los siglos XVI y XVII. Fueron muchos los que trabajaron en esa direcci\u00f3n. De entre ellos, nosotros destacamos a Vicente de Pa\u00fal, pues \u00abdebe pon\u00e9rsele entre los protagonistas m\u00e1ximos del des\u00adpertar moral y religioso del per\u00edodo postridentino\u00bb.<\/p>\n<p>Algunas luces m\u00e1s en aquellos tiempos tan problem\u00e1ticos y dif\u00edciles, saturados de confrontaciones pol\u00edticas y religiosas, fue\u00adron las <em>misiones populares <\/em>y la ense\u00f1anza de la doctrina cristia\u00adna o <em>catecismo. <\/em>Jos\u00e9 Mar\u00eda Rom\u00e1n, historiador, nos ofrece este balance sobre las misiones en tiempo de Vicente de Pa\u00fal:<\/p>\n<p>\u00abTomada en su conjunto, y al margen de an\u00e9cdotas f\u00e1ciles, la acci\u00f3n misional del siglo XVII result\u00f3 mucho menos ef\u00edmera de lo que sus cr\u00edti\u00adcos daban a entender. Una parte muy considerable del campo franc\u00e9s fue transformada en profundidad. Las misiones cambiaron costumbres, disi\u00adparon abusos, arraigaron la fe, purificaron el sentimiento religioso, educa\u00adron al pueblo.<\/p>\n<p>Un historiador contempor\u00e1neo ha escrito que \u00ablos estudios sociol\u00f3\u00adgicos llevados a cabo en nuestros d\u00edas han demostrado que han perma\u00adnecido cristianas en la Francia del siglo XX aquellas zonas en que hace m\u00e1s de trescientos a\u00f1os trabajaron con m\u00e1s intensidad los misioneros, y que aquellas tierras donde no penetraron son las regiones tristemente c\u00e9lebres, se\u00f1aladas de rojo por el can\u00f3nigo Boulard en su c\u00e9lebre mapa de la pr\u00e1ctica religiosa en la Francia de nuestra \u00e9poca\u00bb. No puede ren\u00addirse m\u00e1s exacto homenaje a las misiones del siglo XVII y a los admi\u00adrables hombres que tan acertadamente las condujeron. Uno de estos hombres, el m\u00e1s ilustre de todos, fue Vicente de Pa\u00fal\u00bb.<\/p>\n<p>La acci\u00f3n misionera ofreci\u00f3 frutos buenos y, parece ser, dura\u00adderos; al menos han llegado a los umbrales de nuestro tiempo, de nuestra \u00e9poca. Lleg\u00f3 a cambiar el rostro del catolicismo. Llev\u00f3 a profundizar en el modo de ser cristiano y consigui\u00f3 que los cris\u00adtianos lo vivieran de una manera nueva y, con respecto a los siglos anteriores, m\u00e1s sincera y aut\u00e9ntica. Las misiones populares transformaron los corazones de las personas, desarraigaron cos\u00adtumbres y abusos negativos, fortalecieron la fe, educaron al pueblo, purificaron el sentimiento religioso. Y la prueba de todo esto que decimos la encontramos en que, en pleno siglo XX, la fe segu\u00eda arraigada en aquellas tierras en que hab\u00edan trabajado los misioneros y, en cambio, hab\u00eda desaparecido en las que no hab\u00ed\u00adan estado misionando. Vicente de Pa\u00fal, y otros buenos esp\u00edri\u00adtus como \u00e9l en Francia, en Espa\u00f1a, en Italia y en otras muchas partes, fueron capaces de transformar el cristianismo anquilosado recibido en una religi\u00f3n viva, ilustrada y operante.<\/p>\n<p>Las misiones, pues, incidieron en la vida de las gentes. Incidie\u00adron, sustancialmente, en dos aspectos, el de la <em>reconciliaci\u00f3n <\/em>y el de la <em>caridad. <\/em>Se reconciliaron familias entre s\u00ed y pueblos entre s\u00ed. El odio entre personas fue depuesto. Se perdonaron homicidios y muertes por venganza. Se subsanaron uniones ileg\u00edtimas y esc\u00e1ndalos. Estas reconciliaciones no fueron meramente superfi\u00adciales y pasajeras, se realizaron, incluso, ante notario. El segun\u00addo pilar de la obra misionera fue la caridad. Los misioneros vicencianos ten\u00edan la obligaci\u00f3n de establecer, al final de las misiones dadas, las <em>cofrad\u00edas de la caridad. <\/em>\u00c9stas configuraron un nuevo rostro de la Iglesia. Las caridades y el catecismo lleva\u00adron a pensar en la creaci\u00f3n de algunas escuelas para educar a los ni\u00f1os. Las caridades mostraron el rostro de la compasi\u00f3n y de la misericordia, el verdadero rostro de los cristianos, el rostro m\u00e1s aut\u00e9ntico de Dios. Hicieron posible un nuevo contacto con los pobres y, c\u00f3mo no, con el Dios de los pobres. Los catecismos, del signo que fueran, promocionaron una nueva forma de educar y de vivir la fe. Hasta ese momento, la educaci\u00f3n de la fe se hab\u00eda tenido en el seno de las familias y se realizaba oralmente. Desde la aparici\u00f3n de los catecismos \u00abla transmisi\u00f3n de la fe pasa por el libro y se verificar\u00e1 en las conciencias individ\u00aduales\u00bb. Un buen bot\u00f3n de muestra de todo esto nos lo muestra el mismo Vicente de Pa\u00fal al contar a los suyos su experiencia con el hugonote, al comienzo de sus a\u00f1os fecundos. El hugo\u00adnote objetaba que el Esp\u00edritu Santo no pod\u00eda estar guiando a la Iglesia cat\u00f3lica porque \u00e9sta abandonaba la instrucci\u00f3n religiosa y el ejercicio de la predicaci\u00f3n en los campos, y dejaba a los campesinos sumidos en la ignorancia y en la superstici\u00f3n. Pero, viendo el trabajo que estaban realizando aquellos misioneros, tanto en la predicaci\u00f3n como en la ense\u00f1anza del catecismo y en la atenci\u00f3n caritativa, termin\u00f3 confesando: \u00abAhora es cuando he visto que el Esp\u00edritu Santo gu\u00eda a la Iglesia romana, ya que se preocupa de la instrucci\u00f3n y la salvaci\u00f3n de estos aldeanos\u00bb. Y, a\u00f1ade, \u00abEstoy dispuesto a entrar en ella, cuando quiera usted recibirme\u00bb. Un ejemplo, un testimonio, s\u00ed, pero entre otros muchos que podr\u00edamos traer a colaci\u00f3n.<\/p>\n<p>As\u00ed pues, las misiones y el catecismo tuvieron como objeti\u00advos prioritarios evangelizar e instruir a los pobres y, a su vez, desarrollar la caridad organizada entre esos mismos pobres\u00bb&#8217;. Evangelizar e instruir a los pobres fue la gran apuesta de Vicen\u00adte de Pa\u00fal, su proyecto prioritario. Engloba, pues, anuncio, ense\u00f1anza y atenci\u00f3n material a los necesitados. Era, para \u00e9l, la mejor manera de \u00abhacer efectivo el evangelio\u00bb. La catequesis ser\u00e1 uno de sus m\u00e9todos preferidos para instruir a las gentes, y el ejercicio de la caridad su colof\u00f3n. La catequesis deber\u00eda llevar a la celebraci\u00f3n sacramental, principalmente de la confesi\u00f3n y de la eucarist\u00eda; las misiones, a renovar las parroquias y, la caridad, a ser expresi\u00f3n de un amor afectivo y efectivo tanto para con Dios como para con los hermanos. Y, gracias al \u00abpeque\u00f1o m\u00e9to\u00addo\u00bb, la predicaci\u00f3n y el catecismo ofrecieron sus mejores frutos, la conversi\u00f3n de las gentes, la reconciliaci\u00f3n de los enfrentados, la atenci\u00f3n y salvaci\u00f3n de los enfermos, pobres y menesterosos.<\/p>\n<p>CEME<\/p>\n<p>Santiago Barqu\u00edn<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3.1. ALGUNAS LUCES EN LA ENSE\u00d1ANZA DEL CATECISMO Comencemos por las luces, que existieron, y que conviene reconocer. En primer lugar, conviene se\u00f1alar que el concilio de Trento y el impulso misionero y catequ\u00e9tico que &#8230; <a href=\"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":404148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-404665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El valor del catecismo en san Vicente de Pa\u00fal (VIII) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El valor del catecismo en san Vicente de Pa\u00fal (VIII) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"3.1. ALGUNAS LUCES EN LA ENSE\u00d1ANZA DEL CATECISMO Comencemos por las luces, que existieron, y que conviene reconocer. En primer lugar, conviene se\u00f1alar que el concilio de Trento y el impulso misionero y catequ\u00e9tico que ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-10T06:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"289\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"El valor del catecismo en san Vicente de Pa\u00fal (VIII)\",\"datePublished\":\"2023-05-10T06:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/\"},\"wordCount\":1167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/p.jpg?fit=550%2C289&ssl=1\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/\",\"name\":\"El valor del catecismo en san Vicente de Pa\u00fal (VIII) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/p.jpg?fit=550%2C289&ssl=1\",\"datePublished\":\"2023-05-10T06:08:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/p.jpg?fit=550%2C289&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/p.jpg?fit=550%2C289&ssl=1\",\"width\":550,\"height\":289},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El valor del catecismo en san Vicente de Pa\u00fal (VIII)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El valor del catecismo en san Vicente de Pa\u00fal (VIII) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/","og_locale":"es_ES","og_type":"article","og_title":"El valor del catecismo en san Vicente de Pa\u00fal (VIII) - Somos Vicencianos","og_description":"3.1. ALGUNAS LUCES EN LA ENSE\u00d1ANZA DEL CATECISMO Comencemos por las luces, que existieron, y que conviene reconocer. En primer lugar, conviene se\u00f1alar que el concilio de Trento y el impulso misionero y catequ\u00e9tico que ... Read More","og_url":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2023-05-10T06:08:29+00:00","og_image":[{"width":550,"height":289,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"El valor del catecismo en san Vicente de Pa\u00fal (VIII)","datePublished":"2023-05-10T06:08:29+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/"},"wordCount":1167,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/","url":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/","name":"El valor del catecismo en san Vicente de Pa\u00fal (VIII) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1","datePublished":"2023-05-10T06:08:29+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1","width":550,"height":289},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-viii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"El valor del catecismo en san Vicente de Pa\u00fal (VIII)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1HgR","jetpack-related-posts":[{"id":404663,"url":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-vii\/","url_meta":{"origin":404665,"position":0},"title":"El valor del catecismo en san Vicente de Pa\u00fal (VII)","author":"Mitxel Olabu\u00e9naga","date":"08\/05\/2023","format":false,"excerpt":"LUCES Y SOMBRAS EN LA ENSE\u00d1ANZA DEL CATECISMO Necesitamos volver al motivo de nuestra exposici\u00f3n, la cita sobre el valor del catecismo seg\u00fan Vicente de Pa\u00fal. Todos segui\u00admos recordando la frase que plasm\u00f3 en una de sus cartas Vicen\u00adte de Pa\u00fal: \"Todo el mundo est\u00e1 de acuerdo en que el\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":119278,"url":"https:\/\/vincentians.com\/es\/historia-de-los-paules-en-cuba-capitulo-vi-c\/","url_meta":{"origin":404665,"position":1},"title":"Historia de los Pa\u00fales en Cuba: cap\u00edtulo VI (C)","author":"Mitxel Olabu\u00e9naga","date":"05\/02\/2022","format":false,"excerpt":"3. Labor misionera y social de los Pa\u00fales en la Iglesia de la Merced. Las \"Sabatinas\". Las Asociaciones Cat\u00f3licas: Las Damas de la Caridad. Las Cat\u00f3licas Cubanas. El Sanatorio de la Milagrosa. Las Conferencias de San Vicente de Pa\u00fal. El Ropero de San Vicente de Pa\u00fal. Mientras ocurr\u00edan y se\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/d.jpg?fit=1200%2C799&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/d.jpg?fit=1200%2C799&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/d.jpg?fit=1200%2C799&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/d.jpg?fit=1200%2C799&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/d.jpg?fit=1200%2C799&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":404655,"url":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-iii\/","url_meta":{"origin":404665,"position":2},"title":"El valor del catecismo en san Vicente de Pa\u00fal (III)","author":"Mitxel Olabu\u00e9naga","date":"30\/04\/2023","format":false,"excerpt":"2.2. EVANGELIZAR E INSTRUIR A LOS POBRES: MISIONES Y CATECISMO En el serm\u00f3n sobre el Catecismo, Vicente de Pa\u00fal nos ha dejado plasmado el hallazgo de una necesidad en el pueblo de Dios y el proyecto para remediarla. All\u00ed hemos descubierto sus intenciones; hemos de ver y analizar, tambi\u00e9n, los\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":118187,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1076-a-antonio-portail-sacerdote-de-la-mision-en-marsella\/","url_meta":{"origin":404665,"position":3},"title":"Vicente de Pa\u00fal, Carta 1076: A  Antonio Portail, Sacerdote De La Misi\u00f3n, En Marsella","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/02\/2013","format":false,"excerpt":"8 mayo 1648. Estoy de acuerdo con usted en que el superior de la casa de Marsella no tiene por qu\u00e9 consultar a los se\u00f1ores administradores cuando se trate de poner o de cambiar los sacerdotes externos en el hospital; quiero decir que no conviene que sea esto obligatorio. Tendr\u00e1\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":404667,"url":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-ix\/","url_meta":{"origin":404665,"position":4},"title":"El valor del catecismo en san Vicente de Pa\u00fal (IX)","author":"Mitxel Olabu\u00e9naga","date":"12\/05\/2023","format":false,"excerpt":"3.2. ALGUNAS SOMBRAS EN LA ENSE\u00d1ANZA DEL CATECISMO Pero, en esta vida, no hay luz sin sombras. Y as\u00ed sucedi\u00f3 en la gran apuesta y trabajo por evangelizar e instruir a los pobres. Esto lo podemos decir tanto de los catecismos surgidos a la luz del concilio de Trento, como\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":404651,"url":"https:\/\/vincentians.com\/es\/el-valor-del-catecismo-en-san-vicente-de-paul-ii\/","url_meta":{"origin":404665,"position":5},"title":"El valor del catecismo en san Vicente de Pa\u00fal (II)","author":"Mitxel Olabu\u00e9naga","date":"28\/04\/2023","format":false,"excerpt":"2.1 . EL SERM\u00d3N SOBRE EL CATECISMO El escrito acerca del Serm\u00f3n sobre el Catecismo es un texto aut\u00f3grafo. Por eso mismo tiene un doble valor para nosotros: el de ser un texto salido de la mente y de la pluma de Vicente de Pa\u00fal y el de ofrecernos su\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/p.jpg?fit=550%2C289&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/404665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=404665"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/404665\/revisions"}],"predecessor-version":[{"id":404666,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/404665\/revisions\/404666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/404148"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=404665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=404665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=404665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}