{"id":404581,"date":"2023-02-16T08:44:14","date_gmt":"2023-02-16T07:44:14","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=404581"},"modified":"2022-12-29T17:45:30","modified_gmt":"2022-12-29T16:45:30","slug":"san-vicente-de-paul-un-hombre-evangelico-v","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/","title":{"rendered":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V)"},"content":{"rendered":"<p>VICENTE DE PA\u00daL EXPRESA AL VIVO LAS BIENAVENTURANZAS DE JES\u00daS<\/p>\n<p>Las bienaventuranzas est\u00e1n en el centro de la predicaci\u00f3n de Jes\u00fas. Son el coraz\u00f3n del Evangelio. Con ellas Jes\u00fas recoge las promesas hechas al pueblo elegido desde Abraham; pero las per\u00adfecciona orden\u00e1ndolas no s\u00f3lo a la posesi\u00f3n de una tierra, sino al Reino de los cielos. El texto de Mateo lo deja bien claro: <em>\u00abBien\u00adaventurados los pobres en el esp\u00edritu porque de ellos es el Reino de los Cielos\u00bb (Mt <\/em>5, 3). Las bienaventuranzas revelan un orden de felicidad <em>y <\/em>de gracia, de belleza y de paz que expresan el nuevo orden del amor en plenitud que Cristo nos ha revelado en su Evangelio. En las Bienaventuranzas Jes\u00fas celebra la alegr\u00eda de los pobres de quienes es ya el Reino (Lc 6,20). Por eso Vicen\u00adte de Pa\u00fal hizo de estas santas m\u00e1ximas de Jesucristo la norma de su vida. As\u00ed lo confiesa en las Conferencias que sobre ellas dirigi\u00f3 a los misioneros y a las hijas de la Caridad<sup>59<\/sup>.<\/p>\n<p>Vicente encuentra libertad interior, paz, felicidad y seguridad plena en la vivencia de las Bienaventuranzas. As\u00ed lo expresa en 1642 cuando escribe al P. Bernardo Codoing, superior en Roma, rechazando la propuesta de dar misiones en los pueblos de los Cardenales de la Curia. No es evang\u00e9lico ganarse la simpat\u00eda de los Cardenales. Por eso rechaza el proyecto con energ\u00eda, porque no se ajusta al esp\u00edritu de las Bienaventuranzas: <em>\u00abEst\u00e9 seguro de que los principios de Jesucristo y los ejemplos de su vida nunca nos llevan al desastre, sino que dan su fruto a su debido tiempo, que todo lo que no es conforme con ellos es vano, y que al que sigue las m\u00e1ximas contrarias todo le saldr\u00e1 mal. <\/em>Tal es mi fe y tal es tambi\u00e9n mi experiencia. <em>En nombre de Dios, padre, tenga esto por infalible y oc\u00faltese bien\u00bb. <\/em>San Vicente expresa la dicha que siente por haber sido elegido para expresar <em>al vivo las Bienaventuranzas. <\/em>En 1643, hablando del celo misionero, expre\u00adsa en tono interrogativo lo que \u00e9l estaba viviendo: \u00ab\u00bf<em>Verdad que nos sentimos dichosos, hermanos m\u00edos, de expresar al vivo la vocaci\u00f3n de Jesucristo? \u00bfQui\u00e9n manifiesta mejor la forma de vivir que Jesucristo tuvo en la tierra, sino los misioneros?\u201d.<\/em><\/p>\n<p>Al explicar las Bienaventuranzas como m\u00e1ximas esenciales de Jesucristo, Vicente proyecta lo que vive. El mundo llama bienaventurados a los que abundan en riquezas y honores, que viven regocijadamente y no tienen ocasi\u00f3n alguna de padecer. Los pobres de esp\u00edritu que Jesucristo llama bienaventurados son los que tienen el coraz\u00f3n desprendido de las riquezas, hacen buen uso de ellas si las poseen, no las buscan con solicitud si no \u00a0las tienen, y sufren con resignaci\u00f3n su p\u00e9rdida si se las quitan. As\u00ed lo expresa \u00e9l atribuyendo s\u00f3lo a Dios todo el bien que reali\u00adza y la fundaci\u00f3n de sus obras; al rechazar los honores, se mani\u00adfiesta totalmente desprendido de las alabanzas y reconocimien\u00adtos, vive desprendido de los bienes materiales y s\u00f3lo los utiliza a favor de los pobres. El Hermano Luis Robineau nos aporta m\u00fal\u00adtiples detalles que lo ponen de manifiesto.<\/p>\n<p>San Vicente est\u00e1 convencido de que los mansos tratan al pr\u00f3\u00adjimo con dulzura y sufren con paciencia sus defectos y agravios sin quejas, resentimientos ni venganzas. En la Conferencia a los misioneros del 28 de marzo de 1659 expresa sus convicciones y vivencias sobre la virtud y bienaventuranza de la mansedumbre, una de las cinco virtudes fundamentales del misionero. Afirma, adem\u00e1s, que los misioneros, m\u00e1s que todos los dem\u00e1s sacerdo\u00adtes, deben estar llenos de mansedumbre ya que su vocaci\u00f3n les llama a servir a los m\u00e1s miserables y abandonados de la socie\u00addad. Se\u00f1ala que su pr\u00e1ctica conlleva varias fases. La primera fase tiene dos etapas: en la primera, la persona reprime el movi\u00admiento espont\u00e1neo de c\u00f3lera que siente, esforz\u00e1ndose en perma\u00adnecer sereno y razonable. Esto es dif\u00edcil, dice el santo a sus oyen\u00adtes, pero es posible, pues aunque los movimientos de la naturaleza preceden a los de la gracia, la gracia puede dominar\u00adlos. La segunda etapa consiste en orientar la c\u00f3lera de forma apropiada. A veces puede ser importante corregir, castigar, reprender, como lo hizo Jes\u00fas con sus disc\u00edpulos. En estos casos el misionero deber\u00e1 actuar, no porque se haya dejado dominar por la ira, sino porque \u00e9l la ha dominado. Afirma con energ\u00eda que las personas mansas son constantes y firmes. Son capaces de juz\u00adgar rectamente. Por el contrario, los que se dejan llevar por la c\u00f3lera y la pasi\u00f3n son ordinariamente inconstantes.<\/p>\n<p>San Vicente relaciona con frecuencia la mansedumbre y el\u00a0respeto\u00bb. Dice a las Hijas de la Caridad que no hay caridad sin mansedumbre y respeto mutuo. Exhorta a Roberto de Sergis a tratar a los criados con mansedumbre, cordialidad y profundo respeto. Adem\u00e1s, a\u00f1ade: <em>\u00abCreo que s\u00f3lo a las almas que tienen mansedumbre se les concede poder discernir las cosas\u00bb. <\/em>Con gran expresividad manifiesta a lo largo de su vida y sus ense\u00f1an\u00adzas su fe y experiencia en torno a esta bienaventuranza.<\/p>\n<p>Vicente de Pa\u00fal explica que los que lloran y no obstante se llaman bienaventurados, son los que sufren con resignaci\u00f3n las tribulaciones, los que se afligen por los pecados cometidos, por los males y esc\u00e1ndalos del mundo, por verse lejos del cielo y por el peligro de perderlo. \u00c9l sufri\u00f3 con resignaci\u00f3n la acusaci\u00f3n de robo en su juventud; mirando a Jes\u00fas, que aguant\u00f3 calumnias y persecuci\u00f3n, decidi\u00f3 callar y no excusarse. En su madurez se afligi\u00f3 por los pecados de su juventud, sent\u00eda los pecados del mundo como ofensa a Dios y trat\u00f3 de remediarlos instruyendo al pueblo a trav\u00e9s de las misiones populares. Le pesaban en el alma los pecados propios y los del clero de su tiempo, por eso empren\u00addi\u00f3 un trabajo serio y responsable a favor de la reforma del clero. Le dol\u00edan las profanaciones y desmanes contra la religi\u00f3n por ello mand\u00f3 hacer actos de reparaci\u00f3n en las aldeas de Clamart, Chatillon y Limetz y pidi\u00f3 a sus misioneros que fuesen en peregrinaci\u00f3n a estas iglesias para reparar las profanaciones cometidas durante la primera guerra de la Fronda.<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"996\">\n<table width=\"100%\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Y al final de su vida sinti\u00f3 con fuerza el peso de verse lejos del Cielo y se prepar\u00f3 para la muerte pidiendo perd\u00f3n a todos y en particular a sus bienhechores. As\u00ed escribe al Sr. de Gondi, antiguo general de las galeras, un a\u00f1o antes de morir: <em>\u00abEl estado tan achacoso en que me encuentro y una fiebrecilla que sufro, me obligan, ante la duda de lo que pueda ocurrir, d usar la pre\u00adcauci\u00f3n de postrarme en esp\u00edritu a sus pies para pedirle perd\u00f3n por los disgustos que le he dado con mi rusticidad y para agra\u00addecerle con toda humildad, como lo hago, esa paciencia tan caritativa que ha tenido conmigo y los innumerables beneficios que nuestra Congregaci\u00f3n y yo en particular hemos recibido de su bondad. Est\u00e9 seguro, se\u00f1or, que si Dios quiere seguir d\u00e1ndo\u00adme fuerzas para rezar, las emplear\u00e9 en este mundo y en el otro para pedir por usted y por todos los suyos\u00bb.<\/em><\/p>\n<p>Para Vicente tienen hambre y sed de justicia los que ardiente\u00admente desean crecer de continuo en la divina gracia y en el ejer\u00adcicio de las buenas obras. El hambre y sed de justicia es palpa\u00adble en el coraz\u00f3n de Vicente. De ellas brotan sus obras e instituciones de caridad. La expresi\u00f3n m\u00e1s radical de su hambre y sed de justicia es su celo misionero y su ardiente deseo de bus\u00adcar en todo la gloria de Dios y la extensi\u00f3n de su Reino. Afirma Abelly que es imposible conocer todo lo que hizo Vicente de Pa\u00fal para hacer brillar la justicia y la santidad de Dios en su Igle\u00adsia: <em>\u00abMe parece que su Providencia misericordiosa ha querido usar las misiones para cooperar eficazmente a los principales efectos que hab\u00eda determinado producir por medio de la Encar\u00adnaci\u00f3n de su Hijo, y que hab\u00eda hecho predecir por su profeta, a saber: \u00abBorrar la iniquidad, abolir y exterminar el pecado, y restablecer la santidad y la justicia\u00bb.<\/em><\/p>\n<p>El mismo Vicente reconoce que lo vivi\u00f3 as\u00ed y lo dese\u00f3 para los suyos. Lo manifiesta con ardor y celo en la conferencia a los misioneros sobre la b\u00fasqueda del Reino de Dios: <em>\u00abBuscar el reino de Dios&#8230; me parece que dice muchas cosas; quiere decir que<\/em> <em>hemos de obrar de tal forma que aspiremos siempre a lo que se nos recomienda, que trabajemos incesantemente por el reino de Dios, sin quedarnos en una situaci\u00f3n c\u00f3moda y parados, prestar atenci\u00f3n a nuestro interior para arreglarlo bien, pero no al exterior para dedicarnos a \u00e9l. Buscad, buscad, esto dice, preocupaci\u00f3n, esto dice acci\u00f3n&#8230; \u00a1Pobre hombre! Tengo mucha obligaci\u00f3n de ser un hombre interior y no hago m\u00e1s que caer y volver a caer. \u00a1Que Dios me perdone! &#8230; Procuremos, hermanos m\u00edos, hacernos interiores, hacer que Jesucristo reine en nosotros; busquemos, salgamos de ese estado de tibieza y de disipaci\u00f3n, de esa situaci\u00f3n secular y profana, que hace que nos ocupemos de los objetos que nos muestran los sentidos, sin pensar en el creador que los ha hecho, sin hacer oraci\u00f3n para desprendernos de los bienes de la tierra y sin buscar el soberano bien&#8230; Busque\u00admos la gloria de Dios, busquemos el reino de Jesucristo\u00bb.<\/em><\/p>\n<p>Para Vicente de Pa\u00fal, misericordiosos son los que aman en Dios y por amor de Dios a su pr\u00f3jimo, se compadecen de sus miserias as\u00ed espirituales como corporales y procuran aliviarlas seg\u00fan su fuerza y estado, con un amor afectivo y efectivo. Toda la vida y obras de Vicente de Pa\u00fal son expresi\u00f3n de misericordia. El Hermano Luis Robineau nos habla de su misericordia y com\u00adpasi\u00f3n con los pobres, detallando algunas facetas que han omiti\u00addo los dem\u00e1s bi\u00f3grafos, incluso Abelly. Nos relata que el Sr. Vicente movido por la misericordia de su coraz\u00f3n iba en busca de los pobres a sus casas, distribuye limosnas a 2000 pobres en el a\u00f1o 1649, con frecuencia da limosnas de su dinero personal, besa los pies de los pobres porque representan a Jesucristo y se quitaba el sombrero o bonete para hablar con ellos, hace llevar a una mujer enferma con \u00falceras en las piernas que se encontraba\u00a0 tirada en la calle al H\u00f3tel Dieu, hace subir a otras dos se\u00f1oras ancianas a su carroza, a los enfermos que ve tumbados en la calle, a un ni\u00f1o herido. Es el buen samaritano que no pasa de largo por los caminos de la vida y deja a los pobres en la cuneta. Se deja mover por la compasi\u00f3n, llora con los que lloran y sufre con los que sufren, afirmando al hablar del coraz\u00f3n compasivo: <em>\u00ab\u00a1C\u00f3mo! \u00a1ser cristiano y ver afligido a un hermano, sin llorar con \u00e9l ni sentirse enfermo con \u00e9l! Eso es no tener caridad; es ser cristiano en pintura; es carecer de humanidad; es ser peor que las bestias\u00bb.<\/em><\/p>\n<p>Una faceta de la misericordia de Vicente que tambi\u00e9n ponen de relieve Abelly y el Hermano Robineau es su capacidad de per\u00addonar. Estaba convencido de que quien no sabe perdonar no tiene misericordia en el coraz\u00f3n. Abelly refiere algunos hechos: <em>\u00abUn d\u00eda el se\u00f1or Vicente se enter\u00f3 que cierto Superior de una Comu\u00adnidad Religiosa importante de Par\u00eds hab\u00eda manifestado alguna contrariedad por su forma de actuar en alg\u00fan asunto. Inmedia\u00adtamente fue a buscarlo, se ech\u00f3 a sus pies y le pidi\u00f3 perd\u00f3n, como si lo hubiera ofendido. No recibi\u00f3 de \u00e9l m\u00e1s que despre\u00adcios y palabras \u00e1speras; y sin poder calmarlo, se vio obligado a retirarse, muy contento por haber sufrido aquel rechazo por el amor de su buen Maestro\u00bb. <\/em>Pasados algunos meses el Sr. Vicente envi\u00f3 a un hermano a pedir ornamentos para una cele\u00adbraci\u00f3n. El citado Superior los cedi\u00f3 afirmando que el Sr Vicen\u00adte estaba guiado por el esp\u00edritu de Dios y no entend\u00eda de resenti\u00admientos. El Hermano Robineau se\u00f1ala que el se\u00f1or Vicente hace poner en libertad a un joven fracasado en su vocaci\u00f3n, converti\u00addo en ladr\u00f3n que se hab\u00eda refugiado en la casa del ministro Drelincourt; afirma tambi\u00e9n rez\u00f3 e hizo rezar por un burgu\u00e9s que le hab\u00eda injuriado y calumniado. Estos y otros hechos semejantes prueban como viv\u00eda la bienaventuranza de la misericordia.<\/p>\n<p>La limpieza del coraz\u00f3n en el pensamiento de Jes\u00fas y de Vicente de Pa\u00fal, m\u00e1s que una virtud particular es la envolvente que acompa\u00f1a a todas las virtudes, a fin de que sean verdaderas virtudes. Seg\u00fan el Evangelio lo que decide la pureza o impureza de una acci\u00f3n \u2014sea \u00e9sta la limosna, el ayuno o la oraci\u00f3n\u2014 es la intenci\u00f3n: esto es, si se realiza para ser vistos por los hombres o por agradar a Dios (Mt 6, 2-6). Es la transparencia de la inten\u00adci\u00f3n que solo busca la gloria de Dios y nada m\u00e1s. En este senti\u00addo san Vicente nos confiesa su atracci\u00f3n por la virtud de la sen\u00adcillez: <em>\u00abPor lo que a m\u00ed se refiere, me parece que Dios me ha dado un aprecio tan grande de la sencillez, que la llamo mi Evangelio. <\/em>Siento una especial devoci\u00f3n <em>y consuelo al decir las cosas como son\u00bb. <\/em>Y porque busca solo la verdad y la gloria de Dios, se siente mero instrumento en manos de la divina Provi\u00addencia y se deja conducir por ella. As\u00ed lo confiesa en sus escri\u00adtos: <em>\u00abSiento una devoci\u00f3n especial en ir siguiendo, paso a paso, la adorable Providencia de Dios. Y el \u00fanico consuelo que tengo es que me parece que ha sido solo nuestro Se\u00f1or el que ha hecho y hace continuamente las cosas de esta peque\u00f1a Compa\u00f1\u00eda\u00bb. <\/em>La hipocres\u00eda es el pecado denunciado con m\u00e1s fuerza por Dios a lo largo de toda la Biblia y tambi\u00e9n por Vicente de Pa\u00fal. Con ella el hombre rebaja a Dios, le pone en el segundo lugar, situan\u00addo en el primero a las criaturas. Cultivar la apariencia m\u00e1s que el coraz\u00f3n significa para Vicente de Pa\u00fal dar m\u00e1s importancia al hombre que a Dios. \u00c9l est\u00e1 convencido de que \u00abEl hombre mira las apariencias pero el Se\u00f1or mira el coraz\u00f3n\u00bb (1 Sam 16, 7).<\/p>\n<p>La bienaventuranza de los pac\u00edficos se refiere a los que con\u00adservan la paz con el pr\u00f3jimo y consigo mismos y procuran poner en paz a los enemistados. En las guerras que afligieron a Francia a mediados del siglo XVII, Vicente trabaj\u00f3 activamente como pacificador. Fue testigo de primera mano de los saqueos de vio\u00adlencia y vio el dolor que la guerra tra\u00eda especialmente a los pobres. Alrededor de 1640, durante la lucha civil en Lorena, se present\u00f3 ante el Cardenal Richelieu, se arrodill\u00f3 ante \u00e9l y le suplic\u00f3 la paz. Richelieu se neg\u00f3 respondiendo que la paz no depend\u00eda s\u00f3lo de \u00e9l. En 1649, durante la guerra civil, abandon\u00f3 silenciosamente Par\u00eds, cruz\u00f3 las l\u00edneas de batalla y vade\u00f3 un r\u00edo desbordado (casi a los 70 a\u00f1os de edad) para ver a la Reina y pedir que depusiera a Mazarino, al que consideraba responsable de la guerra. Tambi\u00e9n habl\u00f3 directamente a Mazarino. Pero de nuevo sus s\u00faplicas fueron desatendidas. Mazarino, por el contra\u00adrio, escribi\u00f3 en su diario secreto que Vicente era su \u00abenemigo\u00bb.<\/p>\n<p>San Vicente anim\u00f3 a los miembros de la Congregaci\u00f3n de la Misi\u00f3n a trabajar en curar las relaciones rotas. Uno de los obje\u00adtivos de \u00abla misi\u00f3n\u00bb era la reconciliaci\u00f3n (RC, XI, 8). De hecho, los misioneros a menudo contaban a san Vicente sus \u00e9xitos en apaciguar las rencillas. Es claro, a partir de sus cartas, que \u00e9l mismo a lo largo de su vida intent\u00f3 mediar en muchas disputas entre los miembros de la Congregaci\u00f3n, las Hijas de la Caridad y otras personas a quienes \u00e9l aconsejaba. Insiste en que la paz personal es esencial para juzgar bien. <em>\u00abCreo\u00bb, <\/em>escribe casi al final de su vida, <em>\u00abque s\u00f3lo a las almas que tienen mansedumbre se les concede poder discernir las cosas\u00bb<sup>8<\/sup>\u00b0 <\/em>La vida de Vicente se correspondi\u00f3 con sus palabras. Abelly nos dice que muchos lo consideraron el hombre m\u00e1s pac\u00edfico y manso de su tiempo.<\/p>\n<p>La \u00faltima bienaventuranza tambi\u00e9n fue expresada al vivo por san Vicente. Padecen persecuci\u00f3n a causa de la justicia los que sufren con paciencia las burlas, improperios y persecuciones por la fe y la ley de la caridad que Jesucristo nos ha regalado con su Encarnaci\u00f3n, vida, muerte y resurrecci\u00f3n. Vicente sufri\u00f3 burlas, improperios y persecuciones por la fe y la caridad en Argel durante su esclavitud, en M\u00e1con cuando organiz\u00f3 las Cofrad\u00edas de la Caridad a favor de los mendigos. As\u00ed lo refiere \u00e9l mismo: <em>\u00abCuando fund\u00e9 la Caridad en M\u00e1con, todos se re\u00edan de m\u00ed, se me se\u00f1alaba con el dedo por las calles, pues pensaban que nunca podr\u00eda tener \u00e9xito. Y cuando se hizo la cosa, todos derra\u00admaban l\u00e1grimas de alegr\u00eda. Y los regidores municipales, cuando (\u203a,vtaba ya para marcharme, me colmaron de honores, de tal manera que no pudi\u00e9ndolo aguantar, me vi obligado a salir de inc\u00f3gnito para evitar los aplausos. Y ahora hay all\u00ed una de las Caridades que mejor marcha\u00bb.<\/em><\/p>\n<p>Experiment\u00f3 la oposici\u00f3n y persecuci\u00f3n solapada de algunos frailes el Oratorio que le hicieron la contra en Roma para que el Papa no aprobase la Congregaci\u00f3n de la Misi\u00f3n, de algunos can\u00f3nigos y sacerdotes de Par\u00eds cuando le ofrecieron el priorato de San L\u00e1zaro; el Cardenal Mazarino le expuls\u00f3 del Consejo de Conciencia&#8230; Durante la guerra de la Fronda sufri\u00f3 fuertes con\u00adtratiempos y persecuciones. Su actitud siempre es la del perd\u00f3n, de bendici\u00f3n: <em>\u00abEn 1649, los soldados nos causaron da\u00f1os por valor de 42.000 libras, seg\u00fan evaluaci\u00f3n, pero no se trat\u00f3 de una p\u00e9rdida particular, ya que todo el mundo se resinti\u00f3 de las cala\u00admidades p\u00fablicas: el mal fue com\u00fan, y nosotros fuimos tratados del mismo modo que los dem\u00e1s. Pero, \u00a1bendito sea Dios!, Her\u00admanos m\u00edos, porque ahora ha querido su Providencia adorable despojarnos de una tierra, que nos acaban de quitar (la finca de Orsigny). Se trata de una p\u00e9rdida considerable para la Compa\u00ad\u00f1\u00eda, pero que muy considerable. Hagamos nuestros los senti\u00admientos de Job cuando dec\u00eda: \u00abDios me dio estos bienes, El me los quit\u00f3. \u00a1Bendito sea su Santo Nombre!\u00a0 <\/em>Es verdad que defiende sus derechos a favor de su Comunidad y de los pobres, pero ruega a los abogados que no usen palabras ofensivas sino respetuosas con todos.<\/p>\n<p>A lo largo de este recorrido hemos visto que Vicente de Pa\u00fal es un hombre evang\u00e9lico y quiere que lo sean sus seguidores. Terminamos con una bella oraci\u00f3n en la que san Vicente expre\u00adsa el deseo de que todos sus seguidores, todos los que hemos sido llamados a continuar la misi\u00f3n de Jesucristo, seamos perso\u00adnas evang\u00e9licas: <em>\u00ab\u00a1Oh, Salvador! \u00a1Mi buen Salvador! \u00a1Quiera tu divina bondad librar a la Misi\u00f3n del esp\u00edritu de ociosidad, de la b\u00fasqueda de la comodidad, y darle un celo ardiente de tu gloria, que la haga abrazarlo todo con alegr\u00eda, sin rechazar nunca la ocasi\u00f3n de servirte! &#8230; Estamos hechos para esto; a un misione\u00adro, un verdadero misionero, un hombre de Dios, un hombre que tiene el esp\u00edritu de Dios, todo le tiene que parecer bien e indife\u00adrente; lo abraza todo, lo puede todo; con mayor raz\u00f3n ha de hacerlo una Compa\u00f1\u00eda; una congregaci\u00f3n, una asociaci\u00f3n, lo puede todo cuando est\u00e1 animada y llevada por el esp\u00edritu de Dios&#8230; Si nada podemos por nosotros mismos, lo podemos todo con Dios. S\u00ed, la Misi\u00f3n lo puede todo, porque tenemos en nos\u00adotros el germen de la omnipotencia de Jesucristo\u00bb.<\/em><\/p>\n<p>San Vicente de Pa\u00fal, un hombre evang\u00e9lico<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VICENTE DE PA\u00daL EXPRESA AL VIVO LAS BIENAVENTURANZAS DE JES\u00daS Las bienaventuranzas est\u00e1n en el centro de la predicaci\u00f3n de Jes\u00fas. Son el coraz\u00f3n del Evangelio. Con ellas Jes\u00fas recoge las promesas hechas al pueblo &#8230; <a href=\"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":404161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-404581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"VICENTE DE PA\u00daL EXPRESA AL VIVO LAS BIENAVENTURANZAS DE JES\u00daS Las bienaventuranzas est\u00e1n en el centro de la predicaci\u00f3n de Jes\u00fas. Son el coraz\u00f3n del Evangelio. Con ellas Jes\u00fas recoge las promesas hechas al pueblo ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T07:44:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V)\",\"datePublished\":\"2023-02-16T07:44:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/\"},\"wordCount\":3506,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/05\\\/d.jpg?fit=1200%2C799&ssl=1\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/\",\"name\":\"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/05\\\/d.jpg?fit=1200%2C799&ssl=1\",\"datePublished\":\"2023-02-16T07:44:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/05\\\/d.jpg?fit=1200%2C799&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/05\\\/d.jpg?fit=1200%2C799&ssl=1\",\"width\":1200,\"height\":799,\"caption\":\"- 49 TAB. On ignore actuellement l\u2019auteurs et la date de ce tableau. L\u2019origine est probablement espagnole vue la forme des cornettes et sans doute du 19e si\u00e8cle. Il a \u00e9t\u00e9 enregistr\u00e9 \u00e0 partir d\u2019une reproduction conserv\u00e9e aux Archives de la Congr\u00e9gation \u00e0 Paris.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-un-hombre-evangelico-v\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/","og_locale":"es_ES","og_type":"article","og_title":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V) - Somos Vicencianos","og_description":"VICENTE DE PA\u00daL EXPRESA AL VIVO LAS BIENAVENTURANZAS DE JES\u00daS Las bienaventuranzas est\u00e1n en el centro de la predicaci\u00f3n de Jes\u00fas. Son el coraz\u00f3n del Evangelio. Con ellas Jes\u00fas recoge las promesas hechas al pueblo ... Read More","og_url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2023-02-16T07:44:14+00:00","og_image":[{"width":1200,"height":799,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V)","datePublished":"2023-02-16T07:44:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/"},"wordCount":3506,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/","url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/","name":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1","datePublished":"2023-02-16T07:44:14+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1","width":1200,"height":799,"caption":"- 49 TAB. On ignore actuellement l\u2019auteurs et la date de ce tableau. L\u2019origine est probablement espagnole vue la forme des cornettes et sans doute du 19e si\u00e8cle. Il a \u00e9t\u00e9 enregistr\u00e9 \u00e0 partir d\u2019une reproduction conserv\u00e9e aux Archives de la Congr\u00e9gation \u00e0 Paris."},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (V)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1Hfv","jetpack-related-posts":[{"id":122224,"url":"https:\/\/vincentians.com\/es\/el-evangelio-y-los-pobres\/","url_meta":{"origin":404581,"position":0},"title":"El Evangelio y los Pobres","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/05\/2013","format":false,"excerpt":"1. La prioridad de los pobres en el Evangelio La escena evang\u00e9lica lucana se sit\u00faa en Nazaret, en el marco de la sinagoga y en el d\u00eda del s\u00e1bado (Lc 4,16-30). All\u00ed Jes\u00fas abre la Escritura en el pasaje que proclama la misi\u00f3n prof\u00e9tica de Isa\u00edas por encargo divino (Is\u2026","rel":"","context":"En \u00abDoctrina Social de la Iglesia\u00bb","block_context":{"text":"Doctrina Social de la Iglesia","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/doctrina-social-de-la-iglesia\/"},"img":{"alt_text":"Jes\u00fas le da la vuelta a la tortilla: felices los que lloran, los que sufren, los perseguidos, los pobres.","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/05\/tortilla-300x269.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387816,"url":"https:\/\/vincentians.com\/es\/espiritu-de-jesus-espiritu-de-la-familia-vicenciana\/","url_meta":{"origin":404581,"position":1},"title":"Esp\u00edritu de Jes\u00fas, esp\u00edritu de la Familia Vicenciana","author":"Mitxel Olabu\u00e9naga","date":"14\/09\/2016","format":false,"excerpt":"El Esp\u00edritu de Jes\u00fas es el Esp\u00ed\u00adritu Santo, Se\u00f1or y dador de vida, trasmitido a los cristianos por la participaci\u00f3n en la misi\u00f3n sacerdotal de Jesucristo. Pero se en\u00adtiende tambi\u00e9n por esp\u00edritu de Jes\u00fas un talante o estilo de vida que le distingue de los maestros de la Ley. Jes\u00fas\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":127307,"url":"https:\/\/vincentians.com\/es\/la-prioridad-de-los-pobres-en-el-nuevo-testamento-principio-de-otro-mundo-posible-ii-mateo-y-lucas\/","url_meta":{"origin":404581,"position":2},"title":"La prioridad de los pobres en el Nuevo Testamento, principio de otro mundo posible II: Mateo y Lucas","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2024","format":false,"excerpt":"1. La terminolog\u00eda de la pobreza en el Nuevo Testamento Continuando el estudio de la prioridad de los pobres en el Nuevo Testamento, iniciado en el anterior cuaderno de estudio de Contraste, en el que desarrollamos particularmente el profundo sentido cristol\u00f3gico del pensamiento paulino sobre la pobreza, bas\u00e1ndonos en la\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":143163,"url":"https:\/\/vincentians.com\/es\/vidas-que-cambian-vidas-los-martires-de-espana\/","url_meta":{"origin":404581,"position":3},"title":"Vidas que cambian vidas: los m\u00e1rtires de Espa\u00f1a","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/04\/2015","format":false,"excerpt":"Introducci\u00f3n \u201cDefender y custodiar la vida\u201d es el tema del a\u00f1o elegido para los Colegios de las Hijas de la Caridad en Espa\u00f1a. El lema que lo ilustra \u00a1Todo por la vida! La Comisi\u00f3n interprovincial de Hermanas ha elaborado para los alumnos y los profesores un material educativo, pedag\u00f3gico y\u2026","rel":"","context":"En \u00abTestigos vicencianos\u00bb","block_context":{"text":"Testigos vicencianos","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/testigos-vicencianos\/"},"img":{"alt_text":"martires hijas de la caridad 2013","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/04\/martires-hijas-de-la-caridad-2013-456x1024.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387697,"url":"https:\/\/vincentians.com\/es\/jesucristo-evangelizador-de-los-pobres\/","url_meta":{"origin":404581,"position":4},"title":"Jesucristo evangelizador de los pobres","author":"Mitxel Olabu\u00e9naga","date":"20\/08\/2016","format":false,"excerpt":"El Jes\u00fas descubierto por Vicente de Pa\u00fal no es otro que Jes\u00fas de Nazaret, \u00abnacido de mujer, sometido a la Ley\u00bb (Gal 4,4), con lengua y patria propia; pero es, a la vez, el Jes\u00fas coronado con las funciones gloriosas de Se\u00f1or y Cristo (Hch 2,36) \u2014Kyr\u00edos kai Chr\u00edstos, Salvador\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/jesus-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/jesus-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/jesus-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/jesus-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/jesus-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":136623,"url":"https:\/\/vincentians.com\/es\/399-anos-de-andadura-evangelizando-a-los-pobres\/","url_meta":{"origin":404581,"position":5},"title":"399 a\u00f1os de andadura evangelizando a los pobres","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/01\/2016","format":false,"excerpt":"El d\u00eda 25 de enero el peque\u00f1o grupo de misioneros que logr\u00f3 reunir San Vicente cumple 399 a\u00f1os de andadura evangelizando a los pobres por todos los rincones de la tierra, hasta por los impensables e imposibles, como Madagascar, mientras el mismo Vicente dirig\u00eda la compa\u00f1\u00eda. As\u00ed pues, padres y\u2026","rel":"","context":"En \u00abCongregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Congregaci\u00f3n de la Misi\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/congregacion-de-la-mision\/"},"img":{"alt_text":"cm","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/01\/cm-1024x700.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/01\/cm-1024x700.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/01\/cm-1024x700.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/01\/cm-1024x700.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/404581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=404581"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/404581\/revisions"}],"predecessor-version":[{"id":404582,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/404581\/revisions\/404582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/404161"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=404581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=404581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=404581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}