{"id":403837,"date":"2021-11-20T07:41:20","date_gmt":"2021-11-20T06:41:20","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=403837"},"modified":"2021-07-22T10:42:33","modified_gmt":"2021-07-22T08:42:33","slug":"santa-luisa-de-marillac-mistica-v","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/","title":{"rendered":"Santa Luisa de Marillac, \u00bfm\u00edstica? (V)"},"content":{"rendered":"<p>LA M\u00cdSTICA ES OBRA DEL ESP\u00cdRITU SANTO<\/p>\n<p>La vida espiritual de los hombres consiste en la respuesta que damos a la acci\u00f3n del Esp\u00edritu Santo en nosotros para que siga\u00admos a Jesucristo en la salvaci\u00f3n de los pobres. Si comparamos la vida humana normal que solemos llamar asc\u00e9tica con la vida sobrehumana que la tradici\u00f3n ha llamado m\u00edstica, notamos que la diferencia est\u00e1 en la manera de actuar el Esp\u00edritu Santo.<\/p>\n<p>La actividad del Esp\u00edritu divino en nosotros puede realizarse en dos maneras (generalmente de acuerdo con las etapas en el camino del seguimiento): una a trav\u00e9s de la inteligencia y la voluntad que activan las virtudes de fe, esperanza y caridad y las dem\u00e1s virtudes. Es el hombre, por lo tanto, guiado y ayudado por el Esp\u00edritu de Jes\u00fas, el que realiza activamente con su <em>esfuerzo <\/em>(en griego <em>ascesis) <\/em>la vida espiritual. A esta etapa la tradici\u00f3n la conoce por <em>asc\u00e9tica. <\/em>Es la m\u00e1s corriente, y al ser \u00e9ste el modo humano y normal de obrar, en la asc\u00e9tica el hombre no siente, no experimenta ni la presencia ni la actuaci\u00f3n del Esp\u00edritu.<\/p>\n<p>Pero tambi\u00e9n el Esp\u00edritu Santo puede apoderarse de tal mane\u00adra de las potencias del hombre, de la inteligencia y de la volun\u00adtad, que sea \u00c9l quien active las virtudes, a trav\u00e9s de gracias y carismas que, tradicionalmente y seg\u00fan los diferentes autores de teolog\u00eda, son llamadas los siete famosos <em>dones <\/em>del Esp\u00edritu Santo. El hombre es pasivo y siente que en su mente, sin que \u00e9l pueda producirlos ni pueda impedirlo, le brotan pensamientos y en la voluntad afectos producidos por Otro, el Esp\u00edritu Santo. Por eso esta acci\u00f3n del Esp\u00edritu divino \u2014fuera de lo normal\u2014 se consi\u00addera sobrehumana, y, al no ser la forma natural de actuar las potencias humanas, el hombre experimenta la presencia divina y su acci\u00f3n. Se conoce por <em>m\u00edstica. <\/em>Durante la oraci\u00f3n m\u00edstica gene\u00adralmente el Esp\u00edritu divino act\u00faa por medio de los dones de inte\u00adligencia y sabidur\u00eda, y se conoce como <em>oraci\u00f3n contemplativa.<\/em><\/p>\n<p>Conviene aclarar que no todos los autores de espiritualidad dan el mismo significado a la <em>experiencia de la presencia del Esp\u00edritu divino. <\/em>Admitiendo todos que no se trata de una expe\u00adriencia sensible, a pesar que frecuentemente los m\u00edsticos emple\u00adan el verbo <em>sentir, <\/em>algunos autores retratan la experiencia como un acto de la consciencia m\u00e1s o menos firme, pero ordinario y com\u00fan dentro del conocimiento, otros autores la igualan simple\u00admente a una experiencia de fe. La experiencia m\u00edstica es un con\u00advencimiento m\u00e1s profundo y seguro de la presencia divina en el interior \u00edntimo de la persona. Segundo Galilea lo explica as\u00ed: \u00abEs la convicci\u00f3n, experimentada \u00abimprecisamente (san Juan de la Cruz) en el fondo del esp\u00edritu, m\u00e1s all\u00e1 de la sensibilidad y del razonamiento, de que el Dios de Jes\u00fas est\u00e1 presente en nosotros, en los dem\u00e1s y en la historia as\u00ed como en la naturaleza&#8230; Contem\u00adplar a Dios es saber vivencialmente que estamos en sus manos\u00bb. Aunque a veces, al explicarlo, no sabemos si la considera como un convencimiento humano y natural m\u00e1s que sobrehumano operado por el Esp\u00edritu Santo. Y Jos\u00e9 Mar\u00eda Vigil y Pedro Casald\u00e1liga confiesan: \u00abSin negar lo que haya de intuici\u00f3n correcta en lo que los grandes m\u00edsticos y te\u00f3logos quer\u00edan decir con esas expresiones, nosotros&#8230; realizamos nuestra experiencia de Dios desde unos planteamientos y unas categor\u00edas diversos. Nosotros testimoniamos nuestra experiencia de Dios cuando decimos que sentimos estar colaborando con el Se\u00f1or en la cre\u00adaci\u00f3n inacabada, tratando de continuarla\u00bb.<\/p>\n<p>No cabe duda que santa Luisa conoc\u00eda lo que era <em>experiencia m\u00edstica, <\/em>pero no s\u00f3lo porque lo hubiera le\u00eddo o se lo hubiesen explicado, sino porque lo viv\u00eda y lo experimentaba frecuente\u00admente en la vida y en la contemplaci\u00f3n. Es clarificadora e impre\u00adsionante una p\u00e1gina que dej\u00f3 escrita de su mano, no se sabe si para ella misma, para su director y superior, Vicente de Pa\u00fal, o para sus hijas, las Hermanas:<\/p>\n<p>\u00abLas almas verdaderamente pobres y deseosas de servir a Dios deben tener gran confianza en que al venir a ellas el Esp\u00edritu Santo y no encontrar resistencia alguna, las dispondr\u00e1 conve\u00adnientemente para cumplir la sant\u00edsima voluntad de Dios&#8230;<\/p>\n<p>Y para llegar a ese estado de no-resistencia, es preciso estable\u00adcerse en obediencia, como los Ap\u00f3stoles, y en el reconocimien\u00adto sincero de nuestra impotencia, desprendi\u00e9ndonos por com\u00adpleto de todas las creaturas y hasta de Dios mismo en cuanto a los sentidos&#8230; Y al venir el Esp\u00edritu Santo a las almas as\u00ed dis\u00adpuestas, el ardor de su amor consumir\u00e1 todos los obst\u00e1culos a las operaciones divinas, establecer\u00e1 en ellas las leyes de la santa Caridad y les dar\u00e1 fortaleza para obrar por encima de la potencia humana&#8230;<\/p>\n<p>El amor que debemos tener a Dios ha de ser tan puro que no pre\u00adtendamos en la recepci\u00f3n de sus gracias m\u00e1s especiales otra cosa que la gloria de su Hijo\u00bb.<\/p>\n<p>Al final de su vida comprendi\u00f3 que su oraci\u00f3n contemplativa era obra del Esp\u00edritu Santo y es cuando la Tercera Persona de la Trinidad se convirti\u00f3 en el eje de su vida. No es extra\u00f1o, enton\u00adces, que en 1657, tres a\u00f1os antes de morir, hiciera los Ejercicios anuales \u00fanicamente sobre las <em>Razones de darse a Dios para par\u00adticipar en la recepci\u00f3n del Esp\u00edritu Santo el d\u00eda de Pentecost\u00e9s<\/em>.<\/p>\n<p>Ella misma dice que durante los Ejercicios muchas oraciones fueron de pura contemplaci\u00f3n. Es la divinizaci\u00f3n de la mujer pose\u00edda totalmente por la fuerza del Esp\u00edritu Santo y que segura\u00admente hab\u00eda le\u00eddo en B\u00e9rulle:<\/p>\n<p>\u00abNo es, pues, bastante que me ense\u00f1es, oh Salvador m\u00edo, los medios para prepararme a la venida del Esp\u00edritu Santo, sino que hace falta, alma m\u00eda, tratar de verdad en vaciarse de todos los impedimentos, y actuar, o mejor dicho dejar actuar plenamente a la gracia que el Esp\u00edritu Santo quiere derramar en todas las potencias de nuestro ser; y esto no puede ser sino por una des\u00adtrucci\u00f3n de mis malos h\u00e1bitos que en ocasiones se oponen a ello. \u00a1Quita mi ceguera, Luz eterna! \u00a1Da sencillez a mi alma, Unidad perfecta! \u00a1Humilla mi coraz\u00f3n para asentar el funda\u00admento de tus gracias! y que la capacidad de amar que has pues\u00adto en mi alma no se detenga ya nunca m\u00e1s en el desarreglo de mi propia suficiencia que no es, en efecto, m\u00e1s que un obst\u00e1cu\u00adlo y un impedimento al puro Amor que he de tener con la efu\u00adsi\u00f3n del Esp\u00edritu Santo. Confusi\u00f3n, pues, para m\u00ed a causa de mis enga\u00f1os que tantas veces me han atado a la falsedad, apart\u00e1ndo\u00adme de la Verdad eterna \u00a1Consume todo esto, fuego del Amor divino, aunque yo no merezca tal gracia!\u00bb.<\/p>\n<p>Y convertida ya en una posesa divina, durante la oraci\u00f3n con\u00adtemplativa no puede menos que continuar exclamando en forma de interrogantes:<\/p>\n<p>\u00ab\u00bfHay algo m\u00e1s excelente, en el cielo y en la tierra, que este tesoro? \u00bfC\u00f3mo vivir fuera de raz\u00f3n despu\u00e9s de haberse entrega\u00addo totalmente para prepararse a este bien infinito? \u00bfNo deber\u00eda yo desear morir, \u00a1oh Dios m\u00edo! tan pronto como lo hubiera reci\u00adbido? Vivir tanto como a \u00c9l le agrade, pero de tu vida que es toda de Amor. \u00a1Que no pueda yo desde este mundo derramarme en el oc\u00e9ano de tu Ser divino!\u00bb<\/p>\n<p>CONCLUSI\u00d3N<\/p>\n<p>Al finalizar esta charla, quisiera sacar dos conclusiones. Pri\u00admera, la m\u00edstica se puede alcanzar viviendo cualquier espirituali\u00addad racional y afectiva, siempre que se viva en la fe, la esperanza y el amor. Y, por lo tanto, desde cualquiera de las llamadas escue\u00adlas de espiritualidad cat\u00f3lica, tambi\u00e9n desde el vicencianismo.<\/p>\n<p>Santa Luisa hab\u00eda comenzado el camino espiritual por la senda trazada por B\u00e9rulle y dem\u00e1s espirituales de la llamada <em>Escuela abstracta francesa. <\/em>Luego, de la mano de su director Vicente, pas\u00f3 a lo que hoy llamamos <em>vicencianismo, <\/em>pero nunca pudo olvi\u00addar la formaci\u00f3n espiritual que le dieron los primeros directores capuchinos. Es la marca que le dejaron su ni\u00f1ez y juventud. As\u00ed, naci\u00f3 su espiritualidad, la propia, la que vivi\u00f3 los \u00faltimos a\u00f1os de su vida y que hoy podemos denominarla <em>luisiana: <\/em>una mezcla admirable de vicencianismo y de Escuela Abstracta.<\/p>\n<p>Brota entonces una pregunta \u00bfpor qu\u00e9 no se ha considerado m\u00edstica a santa Luisa de Marillac hasta ahora? Porque hasta el siglo XX solamente estaba al alcance de los estudiosos sus car\u00adtas, que por lo general son cartas para el servicio y para la vida comunitaria, mientras que sus escritos espirituales hab\u00edan sido falsificados en cierto modo por Gobillon. Me explico: sus escri\u00adtos publicados por Gobillon con el nombre de Meditaciones, no eran nada m\u00e1s que unas composiciones rehechas por \u00e9l a base de algunos trozos escritos por la santa. Pero tanto en estas Medita\u00adciones como en la Vida de la Se\u00f1orita Le Gras que escribi\u00f3, Gobillon hab\u00eda quitado todo trazo de m\u00edstica. \u00bfPor qu\u00e9? Porque debido al quietismo la m\u00edstica hab\u00eda quedado en entredicho, y era sospechosa de herej\u00eda quietista o semiquietista toda persona que experimentara fen\u00f3menos m\u00edsticos o hablara de m\u00edstica.<\/p>\n<p>\u00abTanto entre eclesi\u00e1sticos como entre civiles, se toleraban cada vez menos las manifestaciones p\u00fablicas de misticismo, y especialmente cuando se trataba de mujeres. Esto cort\u00f3 las alas a las m\u00edsticas, quienes en much\u00edsimos casos y sobre todo duran\u00adte los periodos m\u00e1s creadores de su existencia sol\u00edan llevar una vida semirreligiosa en la que la compasi\u00f3n hacia el pr\u00f3jimo se fund\u00eda con la apasionada autodisoluci\u00f3n en el Amante divino. Por tanto, hubo que aislarlas de manera m\u00e1s eficaz, pero tambi\u00e9n controlarlas m\u00e1s severamente a trav\u00e9s de sus confesores y gu\u00edas espirituales. Sin embargo, a menudo ocurr\u00eda, como tantas veces en el pasado, que el gu\u00eda se volv\u00eda poco a poco un igual y un amigo, o incluso un disc\u00edpulo, lo que planteaba problemas cada vez m\u00e1s delicados\u00bb.<\/p>\n<p>La segunda conclusi\u00f3n responde al planteamiento que he pre\u00adsentado al comienzo: la m\u00edstica, si es verdadera, nos lleva a sal\u00advar a los pobres, en oposici\u00f3n al quietismo que propagaba una espiritualidad personal del recogimiento y la interioridad hasta una uni\u00f3n del hombre con Dios en identidad total, sin necesitar ya mediaciones ni sacramentos ni Jesucristo ni barreras morales. La m\u00edstica llev\u00f3 a Luisa de Marillac a servir a los pobres.<\/p>\n<p>Desde 1629, la nueva mujer en que se hab\u00eda convertido la se\u00f1orita Le Gras al lado de Vicente de Pa\u00fal, hab\u00eda entrado de una manera natural y, al mismo tiempo, misteriosa, en un mundo hasta hac\u00eda poco extra\u00f1o para ella: el mundo de los pobres. Y esta mujer dirigida por san Vicente no pudo ya prescindir de los pobres. El pobre pasa a ser el centro de su vida y hasta aparece en su oraci\u00f3n, a\u00fan la contemplativa. Aparece como algo l\u00f3gico, y por ello aparece unido a Jes\u00fas, pero el pobre no fue el centro de su oraci\u00f3n, el centro siempre fue Dios. Su oraci\u00f3n es para unirse con Dios y Dios es su objeto y su fin. El pobre no es el objeto de su oraci\u00f3n, es el fruto; como objetivo ser\u00e1 el centro de su acci\u00f3n, de sus conferencias, de sus cartas.<\/p>\n<p>Y en la oraci\u00f3n contemplativa descubri\u00f3 que lo m\u00e1s importa no era ver a Dios en los pobres, que lo m\u00e1s importante era que los pobres vieran a Cristo en ella, cuando se les acercaba a soco\u00adrrerlos, porque vaciada de ella se hab\u00eda revestido del Esp\u00edritu de Cristo. De este modo lleg\u00f3 a ser una santa tan activa como con\u00adtemplativa.<\/p>\n<p>Benito Mart\u00ednez<\/p>\n<p>CEME 2010<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA M\u00cdSTICA ES OBRA DEL ESP\u00cdRITU SANTO La vida espiritual de los hombres consiste en la respuesta que damos a la acci\u00f3n del Esp\u00edritu Santo en nosotros para que siga\u00admos a Jesucristo en la salvaci\u00f3n &#8230; <a href=\"https:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":399750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-403837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Luisa de Marillac, \u00bfm\u00edstica? (V) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Luisa de Marillac, \u00bfm\u00edstica? (V) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"LA M\u00cdSTICA ES OBRA DEL ESP\u00cdRITU SANTO La vida espiritual de los hombres consiste en la respuesta que damos a la acci\u00f3n del Esp\u00edritu Santo en nosotros para que siga\u00admos a Jesucristo en la salvaci\u00f3n ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T06:41:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"Santa Luisa de Marillac, \u00bfm\u00edstica? (V)\",\"datePublished\":\"2021-11-20T06:41:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/\"},\"wordCount\":2107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/\",\"name\":\"Santa Luisa de Marillac, \u00bfm\u00edstica? (V) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2021-11-20T06:41:20+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/santa-luisa-de-marillac-mistica-v\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Luisa de Marillac, \u00bfm\u00edstica? (V)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Luisa de Marillac, \u00bfm\u00edstica? (V) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/","og_locale":"es_ES","og_type":"article","og_title":"Santa Luisa de Marillac, \u00bfm\u00edstica? (V) - Somos Vicencianos","og_description":"LA M\u00cdSTICA ES OBRA DEL ESP\u00cdRITU SANTO La vida espiritual de los hombres consiste en la respuesta que damos a la acci\u00f3n del Esp\u00edritu Santo en nosotros para que siga\u00admos a Jesucristo en la salvaci\u00f3n ... Read More","og_url":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2021-11-20T06:41:20+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"Santa Luisa de Marillac, \u00bfm\u00edstica? (V)","datePublished":"2021-11-20T06:41:20+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/"},"wordCount":2107,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/","url":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/","name":"Santa Luisa de Marillac, \u00bfm\u00edstica? (V) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","datePublished":"2021-11-20T06:41:20+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-v\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Santa Luisa de Marillac, \u00bfm\u00edstica? (V)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1H3v","jetpack-related-posts":[{"id":129151,"url":"https:\/\/vincentians.com\/es\/vida-contemplativa\/","url_meta":{"origin":403837,"position":0},"title":"Vida contemplativa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"02\/03\/2014","format":false,"excerpt":"Aunque parezca extra\u00f1o, la exorbitante actividad de Luisa no destruy\u00f3 su experiencia de Dios, al contrario, la complet\u00f3. Luisa aparece en la historia de la espiritualidad como una de las mujeres m\u00e1s contemplativas; tan contemplativa como San Pablo, Santa Teresa o San Vicente de Pa\u00fal y tan activa como ellos.\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"cartel","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/01\/cartel.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":405252,"url":"https:\/\/vincentians.com\/es\/el-cristo-de-las-hijas-de-la-caridad-iv\/","url_meta":{"origin":403837,"position":1},"title":"El Cristo de las Hijas de la Caridad (IV)","author":"Mitxel Olabu\u00e9naga","date":"30\/06\/2024","format":false,"excerpt":"Cap\u00edtulo IV: etapas del seguimiento Segunda conversi\u00f3n De santa Luisa de Marillac s\u00f3lo conserva\u00admos unos papeles generalmente sin fecha, a veces notas peque\u00f1as, que escribe mientras hace oraci\u00f3n, o quiere recordar cuando vaya a su habitaci\u00f3n. El a\u00f1o 1645, cuando tiene 54 a\u00f1os, se propone ir escribiendo su oraci\u00f3n m\u00eds\u00adtica\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaa1.jpg?fit=500%2C262&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":119558,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-su-entronque-hispanico-vii\/","url_meta":{"origin":403837,"position":2},"title":"San Vicente de Pa\u00fal y su entronque hisp\u00e1nico (VII)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/08\/2022","format":false,"excerpt":"Art\u00edculo II: Emparentamiento teol\u00f3gico y asc\u00e9tico. No s\u00f3lo depende su formaci\u00f3n teol\u00f3gica, en gran parte, de la Universidad de Zaragoza, en la que bebi\u00f3 aquella doctrina 's\u00f3lida y sana\", que no s\u00f3lo le dio el sentido de la ortodoxia cat\u00f3lica, que le libr\u00f3 y con la que combati\u00f3 victoriosamente las\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/msoF811D.jpg?fit=612%2C490&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/msoF811D.jpg?fit=612%2C490&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/msoF811D.jpg?fit=612%2C490&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":387816,"url":"https:\/\/vincentians.com\/es\/espiritu-de-jesus-espiritu-de-la-familia-vicenciana\/","url_meta":{"origin":403837,"position":3},"title":"Esp\u00edritu de Jes\u00fas, esp\u00edritu de la Familia Vicenciana","author":"Mitxel Olabu\u00e9naga","date":"14\/09\/2016","format":false,"excerpt":"El Esp\u00edritu de Jes\u00fas es el Esp\u00ed\u00adritu Santo, Se\u00f1or y dador de vida, trasmitido a los cristianos por la participaci\u00f3n en la misi\u00f3n sacerdotal de Jesucristo. Pero se en\u00adtiende tambi\u00e9n por esp\u00edritu de Jes\u00fas un talante o estilo de vida que le distingue de los maestros de la Ley. Jes\u00fas\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":116383,"url":"https:\/\/vincentians.com\/es\/bibliografia-vicenciana-1960-1970-en-torno-a-la-espiritualidad-de-san-vicente\/","url_meta":{"origin":403837,"position":4},"title":"Bibliograf\u00eda Vicenciana 1960-1970 en torno a la espiritualidad de San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2021","format":false,"excerpt":"Lo que antes se llamaba Asc\u00e9tica y M\u00edstica, hoy se llama com\u00fanmen\u00adte Espiritualidad. Es una palabra tra\u00edda de Francia, como tantas otras, que tambi\u00e9n han hecho fortuna, m\u00e1s por moda que por convencimiento. As\u00ed se bautizan los tratados de Historia, desde Pourrat (1926) hasta Bouyer-Vandenbroucke (1963). El recomendar tan insistentemente\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":403829,"url":"https:\/\/vincentians.com\/es\/santa-luisa-de-marillac-mistica-i\/","url_meta":{"origin":403837,"position":5},"title":"Santa Luisa de Marillac, \u00bfm\u00edstica? (I)","author":"Mitxel Olabu\u00e9naga","date":"12\/11\/2021","format":false,"excerpt":"EL PORQU\u00c9 DE ESTA CHARLA Cuando me pidieron que hablara sobre la m\u00edstica de santa Luisa de Marillac, por imposibilidad de Sor Elisabeth Charpy, pens\u00e9 si el hablar de m\u00edstica tendr\u00eda inter\u00e9s para la gente de hoy d\u00eda, inmersa en una crisis social, econ\u00f3mica y laboral. \u00bfQu\u00e9 solu\u00adci\u00f3n puede dar\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=403837"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403837\/revisions"}],"predecessor-version":[{"id":403838,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403837\/revisions\/403838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/399750"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=403837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=403837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=403837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}