{"id":403816,"date":"2021-10-30T07:44:51","date_gmt":"2021-10-30T05:44:51","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=403816"},"modified":"2021-07-21T12:45:48","modified_gmt":"2021-07-21T10:45:48","slug":"vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/","title":{"rendered":"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II)"},"content":{"rendered":"<ol>\n<li>VICENTE DE PA\u00daL, EL HOMBRE<\/li>\n<\/ol>\n<p>Podr\u00eda parecer innecesario y hasta superfluo partir del supuesto \u00abhombre\u00bb para valorar al \u00abcristiano\u00bb, elevado a la cate\u00adgor\u00eda de hijo de Dios por la gracia del Esp\u00edritu. Pero no, porque sin el conocimiento previo de tal o cual naturaleza humana nos resultar\u00eda m\u00e1s dif\u00edcil todav\u00eda seguir la evoluci\u00f3n y transforma\u00adci\u00f3n de esa criatura racional en un cristiano aut\u00e9ntico. El hombre Vicente de Pa\u00fal comienza a destellar la luz de Cristo desde que tomara conciencia de Dios, de s\u00ed mismo y del mundo que le rodeaba.<\/p>\n<p>Si algo habr\u00eda que destacar en \u00e9l como hombre son sus ra\u00edces campesinas y las virtudes dom\u00e9sticas de la honradez, el trabajo y el agradecimiento. Estaba convencido de que \u00abun hombre que no tiene palabra no es hombre: s\u00f3lo tiene las apariencias, es un animal, un animal feroz que merece ser echado de la sociedad&#8217;. Veinte a\u00f1os antes de emitir este juicio el 13 de agosto de 1655, hab\u00eda mani\u00adfestado al P. Antonio Portail, el 1 de mayo de 1635: \u00abNo se le cree a un hombre porque sea muy sabio, sino porque lo juzgamos bueno y lo apreciamos. El diablo es muy sabio, pero no creemos en nada de cuanto \u00e9l nos dice, porque no lo estimamos&#8230;\u00bb<\/p>\n<p>Todos sus bi\u00f3grafos est\u00e1n de acuerdo en que era un trabaja\u00addor infatigable y que evitaba a todo trance ser carga a la socie\u00addad y comer de balde, seg\u00fan la ense\u00f1anza de san Pablo: \u00abEl que no trabaje, que no coma\u00bb (2 Ts 3, 10). Sin embargo, hasta llegar a esa entrega desinteresada y fiel al trabajo, en beneficio de los pobres y necesitados, hubo de superar serias dificultades que le pusieron a prueba<sup>s<\/sup>. Despu\u00e9s de los sacramentos, el trabajo ser\u00e1 su principal fuente de santificaci\u00f3n, convencido de que \u00abla Igle\u00adsia es como una gran mies que requiere obreros, pero obreros que trabajen\u00bb.<\/p>\n<p>En cuanto al agradecimiento lo lleva tan grabado en el alma que llama a \u00abla ingratitud el crimen de los cr\u00edmenes&#8230; A\u00fan m\u00e1s, hemos de tener cuidado de no caer en ese miserable pecado de la ingratitud para con los que nos alimentan y sostienen. Hemos de mostrarles mucho agradecimiento por el bien que nos han hecho\u00bb.<\/p>\n<p>He aqu\u00ed al hombre sobre el que se sustenta, en buena parte, su experiencia humana. No exageramos al asegurar que la mentira, la vagancia y la ingratitud eran superiores a su modo de ser; no toleraba de ninguna manera un comportamiento doble e indolen\u00adte. Pero estas virtudes humanas no eran suficientes, aunque s\u00ed b\u00e1sicas, para actuar siempre como aut\u00e9ntico cristiano, sellado por el Esp\u00edritu. Le faltaba todav\u00eda el esp\u00edritu de fe necesario, para volcarse sobre los m\u00e1s infelices, ya que negarse a echarles una mano ser\u00eda \u00abcarecer de humanidad; ser peor que las bestias&#8217;.<\/p>\n<p>El conocimiento que ten\u00eda de s\u00ed mismo y el esp\u00edritu de realis\u00admo que le acompa\u00f1aba le ayud\u00f3 a constatar que \u00abel hombre no est\u00e1 nunca en el mismo estado\u00bb y que \u00abel hast\u00edo y el des\u00e1nimo son productos de la pobre naturaleza que se llevan a todas partes por donde uno va; hay que abandonarse al esp\u00edritu de nuestro Se\u00f1or para poder soportarse a s\u00ed mismo y para vencer la timidez, pereza y dem\u00e1s enfermedades\u00bb, pues \u00abla naturaleza corrompida nos sujeta a estas miserias\u00bb.<\/p>\n<p>Vicente de Pa\u00fal, en determinadas circunstancias, al hablar de la Iglesia y de la sociedad, puede dar la impresi\u00f3n de estar tizna\u00addo de pesimismo o de ser un campesino desconfiado; pero no, a no ser que llamemos pesimista al optimista que describe la cruda y dura realidad de un pueblo desangrado por las guerras, el ham\u00adbre y las epidemias y en el que, para colmo de males, \u00abse han impuesto los herejes y reinan los vicios y la ignorancia; y esto por culpa de los des\u00f3rdenes de los propios sacerdotes y por no haberse opuesto con todas sus fuerzas, como ten\u00edan obligaci\u00f3n, a esos tres torrentes que han inundado la tierra. Si no hubiera sido por el optimismo evang\u00e9lico que le animaba, jam\u00e1s se hubiera comprometido, con otros contempor\u00e1neos suyos, a mejorar la situaci\u00f3n de aquella sociedad civil y eclesi\u00e1stica.<\/p>\n<p>El cambio de Vicente de Pa\u00fal fue debido al encuentro con Jesucristo, encarnado en los pobres de modo particular, encuen\u00adtro que le oblig\u00f3 a replantear sus actitudes religiosas y sacerdo\u00adtales, coincidiendo con la etapa de la \u00abconversi\u00f3n\u00bb. Ten\u00eda a la saz\u00f3n treinta y seis a\u00f1os de edad, si damos el a\u00f1o 1617 como bisagra sobre la que hace girar su nueva vida de cristiano com\u00adprometido. A ese a\u00f1o clave le precedi\u00f3 una tentaci\u00f3n contra la fe que pudo durarle aproximadamente unos cuatro a\u00f1os; de ella sali\u00f3 m\u00e1s iluminado, robustecido y decidido a vivir con gozo y esperanza la vocaci\u00f3n humana y cristiana.<\/p>\n<p>Tal tentaci\u00f3n o \u00abcrisis\u00bb, entendida \u00e9sta en su sentido etimol\u00f3\u00adgico, es decir de juicio y decisi\u00f3n, de donde vino a significar \u00abmomento decisivo\u00bb, le sirvi\u00f3 de luz y de fortaleza para empren\u00adder el camino de la caridad o del amor: carisma que recibi\u00f3 gra\u00adtuitamente del Esp\u00edritu de Dios. En esto consiste, a mi parecer, la llamada \u00abconversi\u00f3n\u00bb de Vicente de Pa\u00fal: en vaciarse de sus ego\u00edsmos, de sus antiguas ambiciones y aspiraciones a ascender en la escala social, someti\u00e9ndose a una purificaci\u00f3n de la fe y a entablar una lucha constante consigo mismo, por amor a Dios y al hombre.<\/p>\n<p>Afirmamos esto porque tras algunos a\u00f1os de experiencia cris\u00adtiana, dir\u00e1 a los misioneros: \u00abCuando un coraz\u00f3n se vac\u00eda de s\u00ed mismo, Dios lo llena. Dios es el que entonces mora y act\u00faa en \u00e9l. No somos nosotros los que obramos, sino Dios en nosotros\u00bb<sup>11<\/sup>. Y a las Hermanas: \u00ab\u00bfQu\u00e9 no har\u00e1 una persona que tiene a Dios en s\u00ed, que est\u00e1 llena de Dios? No har\u00e1 ya ciertamente sus acciones, sino que har\u00e1 las acciones de Jesucristo; servir\u00e1 a los enfermos con la caridad de Jesucristo; tendr\u00e1 en su conversaci\u00f3n la man\u00adsedumbre de Jesucristo&#8230; En una palabra, todas sus acciones no ser\u00e1n ya acciones de una mera criatura, sino acciones de Jesucristo\u00bb. En fin, \u00ab\u00bfqu\u00e9 hacemos cuando nos situamos en la mor\u00adtificaci\u00f3n, en la paciencia, en la humildad y en las dem\u00e1s virtu\u00addes? Situamos en nosotros a Jesucristo y podemos decir con san Pablo: &#8216;Vivo yo, pero no yo, sino Jesucristo quien vive en m\u00ed (Ga 2, 20)\u00bb.<\/p>\n<p>Es probable que la aludida \u00abtentaci\u00f3n\u00bb tuviera mucho que ver con la lucha entre la raz\u00f3n y la fe, la naturaleza y la gracia. Robustecido por un car\u00e1cter firme y temperamento activo, reac\u00adcionaba consecuentemente, de acuerdo con su psicolog\u00eda. Es cierto que la raz\u00f3n no siempre le aclaraba las razones del cora\u00adz\u00f3n con el que creemos y amamos a Dios y al pr\u00f3jimo, pero al final la fe terminaba prevaleciendo. Si partimos de esta realidad, podemos aplicarle lo que el Papa Juan Pablo II comentaba al comienzo de la enc\u00edclica <em>Fides et Ratio: <\/em>\u00abLa fe y la raz\u00f3n son como las dos alas con las cuales el esp\u00edritu humano se eleva hacia la contemplaci\u00f3n de la verdad. Dios ha puesto en el cora\u00adz\u00f3n del hombre el deseo de conocer la verdad y, en definitiva, de conocerle a \u00c9l, para que conoci\u00e9ndolo y am\u00e1ndolo, pueda alcan\u00adzar tambi\u00e9n la plena verdad sobre s\u00ed mismo\u00bb.<\/p>\n<p>A nuestro joven Vicente le cost\u00f3 l\u00e1grimas a tragos el despren\u00addimiento de sus familiares, pero as\u00ed fue c\u00f3mo, al soplo del Esp\u00edritu, creci\u00f3 su experiencia humana y espiritual desde que tuvo conciencia de ser instrumento de la caridad de Cristo y heraldo del evangelio de los pobres.<\/p>\n<p>Antonino Orcajo<\/p>\n<p>CEME 2011<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VICENTE DE PA\u00daL, EL HOMBRE Podr\u00eda parecer innecesario y hasta superfluo partir del supuesto \u00abhombre\u00bb para valorar al \u00abcristiano\u00bb, elevado a la cate\u00adgor\u00eda de hijo de Dios por la gracia del Esp\u00edritu. Pero no, porque &#8230; <a href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":402733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-403816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"VICENTE DE PA\u00daL, EL HOMBRE Podr\u00eda parecer innecesario y hasta superfluo partir del supuesto \u00abhombre\u00bb para valorar al \u00abcristiano\u00bb, elevado a la cate\u00adgor\u00eda de hijo de Dios por la gracia del Esp\u00edritu. Pero no, porque ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-30T05:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II)\",\"datePublished\":\"2021-10-30T05:44:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/\"},\"wordCount\":1373,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/\",\"name\":\"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2021-10-30T05:44:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II) - Somos Vicencianos","og_description":"VICENTE DE PA\u00daL, EL HOMBRE Podr\u00eda parecer innecesario y hasta superfluo partir del supuesto \u00abhombre\u00bb para valorar al \u00abcristiano\u00bb, elevado a la cate\u00adgor\u00eda de hijo de Dios por la gracia del Esp\u00edritu. Pero no, porque ... Read More","og_url":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2021-10-30T05:44:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II)","datePublished":"2021-10-30T05:44:51+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/"},"wordCount":1373,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/","url":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/","name":"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1","datePublished":"2021-10-30T05:44:51+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-un-cristiano-revestido-del-espiritu-de-cristo-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal, un cristiano revestido del esp\u00edritu de Cristo (II)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1H3a","jetpack-related-posts":[{"id":387700,"url":"https:\/\/vincentians.com\/es\/la-iglesia-de-jesus\/","url_meta":{"origin":403816,"position":0},"title":"La Iglesia de Jes\u00fas","author":"Mitxel Olabu\u00e9naga","date":"23\/08\/2016","format":false,"excerpt":"Grandes y profundos cambios cient\u00edfico-t\u00e9cnicos, pol\u00edticos, econ\u00f3micos, sociales y religiosos se han producido desde el siglo XVII hasta nuestros d\u00edas, cambios semejantes y a\u00fan mayores que los originados por el paso de la Edad Media a la Moderna. Sin embargo, entre las nuevas orientaciones doctrinales y las vividas ya entonces\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/iglesia-de-los-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/iglesia-de-los-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/iglesia-de-los-pobres.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/iglesia-de-los-pobres.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/iglesia-de-los-pobres.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":116700,"url":"https:\/\/vincentians.com\/es\/caridad-en-san-vicente-de-paul\/","url_meta":{"origin":403816,"position":1},"title":"Caridad en San Vicente de Pa\u00fal","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/10\/2018","format":false,"excerpt":"Introducci\u00f3n Hablar de la caridad en Vicente de Pa\u00fal en esta semana de Estudios Vicencianos significa hacer una \"relectura\" de la misma. Esta relectura implica no una simple exposici\u00f3n de lo que dijo e hizo Vicente de Pa\u00fal referente a la caridad, sino un volver a leer su ense\u00f1anza y\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":387692,"url":"https:\/\/vincentians.com\/es\/fuentes-de-doctrina-vicenciana-y-criterios-de-lectura\/","url_meta":{"origin":403816,"position":2},"title":"Fuentes de doctrina vicenciana y criterios de lectura","author":"Mitxel Olabu\u00e9naga","date":"14\/08\/2016","format":false,"excerpt":"La vocaci\u00f3n del cristiano consiste en seguir a Jes\u00fas. Cristianos, precisamente, llamaron por primera vez en Antioqu\u00eda a los disc\u00edpulos del Se\u00f1or (cf. Hch 11,26). Desde entonces los seguidores de Cristo expresan su fe viviendo el ideal de la Buena Nueva encarnada y predicada por Jes\u00fas de Nazaret, el Cristo\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/Fuentes-de-doctrina-vicenciana.jpg?fit=1199%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/Fuentes-de-doctrina-vicenciana.jpg?fit=1199%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/Fuentes-de-doctrina-vicenciana.jpg?fit=1199%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/Fuentes-de-doctrina-vicenciana.jpg?fit=1199%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/Fuentes-de-doctrina-vicenciana.jpg?fit=1199%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":130259,"url":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-06\/","url_meta":{"origin":403816,"position":3},"title":"Un perfil heroico: santa Luisa de Marillac (06)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/02\/2015","format":false,"excerpt":"ESOS que est\u00e1n cubiertos de blancas vestiduras, \u00bfqui\u00e9nes son y de d\u00f3nde han venido? (Apocalipsis, VII.) VICENTE de Pa\u00fal ha sido uno de los mayores dones que la ca\u00adridad y la misericordiosa de Dios han concedido al mundo. Su santidad personal es tan atrayente, tan humana, tan digna de imitaci\u00f3n\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387799,"url":"https:\/\/vincentians.com\/es\/jesus-trabaja-como-el-padre\/","url_meta":{"origin":403816,"position":4},"title":"Jes\u00fas trabaja como el Padre","author":"Mitxel Olabu\u00e9naga","date":"05\/09\/2016","format":false,"excerpt":"El designio de Dios se realiza en la acci\u00f3n. Tal modo de concebir la voluntad divina ha de entenderse bajo la triple perspectiva, trinitaria, cristol\u00f3gica y antropol\u00f3gica. El hombre es objeto preferencial de la obra de Dios y de Jes\u00fas, revelada en la creaci\u00f3n y en la encarnaci\u00f3n del Verbo.\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":117335,"url":"https:\/\/vincentians.com\/es\/evangelizar-siguiendo-a-san-vicente\/","url_meta":{"origin":403816,"position":5},"title":"Evangelizar siguiendo a san Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/11\/2018","format":false,"excerpt":"Una de las opciones en Misiones Populares, tal y como lo hacemos los vicencianos, es el trabajo en equipo, que se compone de Consagrados (Pa\u00fales, Hijas de la Caridad, sacerdotes diocesanos\u2026) y Seglares Vicencianos. No lo hacemos as\u00ed por \"moda\", sino que es una de las urgencias en nuestra sociedad\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=403816"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403816\/revisions"}],"predecessor-version":[{"id":403817,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403816\/revisions\/403817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/402733"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=403816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=403816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=403816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}