{"id":403776,"date":"2021-09-22T07:46:27","date_gmt":"2021-09-22T05:46:27","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=403776"},"modified":"2021-07-17T11:47:22","modified_gmt":"2021-07-17T09:47:22","slug":"vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/","title":{"rendered":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV)"},"content":{"rendered":"<ol start=\"4\">\n<li>UN PER\u00cdODO DIF\u00cdCIL (1640-1642)<\/li>\n<\/ol>\n<p>Y sobreviene un per\u00edodo dif\u00edcil, en el que van a modificarse las relaciones. Ya en los a\u00f1os que preceden, algunas actitudes revelan la gran desemejanza entre una y otra personalidad. Toda amistad sufre crisis: la de Vicente y Luisa sigue esta precisa ley.<\/p>\n<p>Entre marzo de 1640 y junio de 1642, su amistad que estriba\u00adba sobre la verdad, la confianza, la sencillez, va afrontar tensio\u00adnes. La diferencia, hasta entonces pac\u00edficamente aceptada, se hace fuente de impaciencia, no se reconoce como complementariedad, sino que m\u00e1s bien se torna incomprensi\u00f3n.<\/p>\n<p>En diciembre de 1639 Luisa de Marillac llevaba al hospital de Angers las Hijas de la Caridad. Los administradores piden un contrato bien escrito, seg\u00fan la forma debida. Pensaba el se\u00f1or Vicente que todo habr\u00eda sido de viva voz. Por carta, pregunta<\/p>\n<p>Luisa al se\u00f1or Vicente, \u00bfqui\u00e9n firmar\u00e1 el contrato, pues las Hijas de la Caridad no tienen entidad legal? No se hace declaraci\u00f3n alguna. Es muy probable que Luisa haya sentido los \u00abefectos noci\u00advos\u00bb de la prudente lentitud del se\u00f1or Vicente, quien responde:<\/p>\n<p><em>Dado que esos se\u00f1ores quieren tratar por escrito, h\u00e1galo in nomine Domini, y mande que hagan el contrato a su nombre como directora de las Hijas de la Caridad [siervas de los pobres enfer\u00admos de los hospitales y de las parroquias, con el benepl\u00e1cito del superior general de la congregaci\u00f3n de los sacerdotes de la Misi\u00f3n, director de dichas Hijas de la Caridad (SVP, II, 7).<\/em><\/p>\n<p>La carta prosigue luego, con explicaciones algo complicadas, al estilo gasc\u00f3n<\/p>\n<p><em>Y si le piden el documento de erecci\u00f3n de esta congregaci\u00f3n, d\u00edgales que no tiene m\u00e1s que los poderes que se le han dado a dicho superior, director de las cofrad\u00edas de la Caridad, como se hace en todas partes, especialmente en esa di\u00f3cesis, en Bourg-neuf , en las tierras de la se\u00f1ora Goussault, seg\u00fan creo, aunque no estoy muy seguro, [y] en Richelieu, en la di\u00f3cesis de Poitiers (SVP, II, 7-8).<\/em><\/p>\n<p>\u00c9sta no pareci\u00f3 a Luisa una respuesta satisfactoria. Tuvo que manifestar su extra\u00f1eza, pues una cuarta misiva de Vicente, el 28 de febrero de 1640, concurre a confirmar la primera:<\/p>\n<p><em>Ya le he dicho mi opini\u00f3n sobre las cl\u00e1usulas y condiciones que tiene que estipular ah\u00ed (SVP, 11, 13).<\/em><\/p>\n<p>Luisa obedece: el 1 de febrero de 1640 firma ella el contrato que establece a las Hijas de la Caridad en el hospital de Angers.<\/p>\n<p>Al a\u00f1o siguiente, la elecci\u00f3n del emplazamiento de una nueva casa-madre para las Hijas de la Caridad, se convierte en nueva fuente de tensiones entre Vicente de Pa\u00fal y Luisa de Marillac. En 1636 se hab\u00edan establecido las Hijas de la Caridad en una casa de la aldehuela de La Chapelle, al norte de Par\u00eds. Sin embargo, con la afluencia de candidatas, la casa se qued\u00f3 peque\u00f1a. Era preci\u00adsa otra m\u00e1s grande. Luisa aprovecha la ocasi\u00f3n y reitera el deseo que expresaba en 1636 y hab\u00eda rechazado el se\u00f1or Vicente: morar no lejos de San L\u00e1zaro.<\/p>\n<p>El se\u00f1or Vicente comienza rehusando: que no es prudente. Cuando el pueblo de la barriada vea a un sacerdote de la Misi\u00f3n entrar en la casa de las Hermanas, o a una Hermana entrar en San L\u00e1zaro, habr\u00e1 cotilleo, habladur\u00edas. Luisa rechaza las diversas propuestas que le son hechas, pues ninguna de ellas acerca a las Hermanas a San L\u00e1zaro. Ante la insistencia de Luisa, el se\u00f1or Vicente termina por ceder. Luisa empero se impacienta, las pes\u00adquisas no le parecen ir lo bastante veloces. En febrero de 1641, postrado por la enfermedad, Vicente escribe con bastante dureza:<\/p>\n<p><em>La encuentro siempre a usted con sentimientos un poco humanos desde que me ve usted enfermo, al pensar que se ha perdido todo, si no se encuentra casa. \u00a1Oh, mujer de poca fe y poco aficionada al ejemplo y a la conducta de Jesucristo! El Salvador del mundo, al pensar en toda su Iglesia, conf\u00eda en el Padre para sus reglas y su direcci\u00f3n; y para un pu\u00f1ado de muje\u00adres, que tan claramente ha suscitado y reunido su Providencia, \u00a1le parece a usted que nos fallar\u00e1! (SVP, II, 130).<\/em><\/p>\n<p>La impaciencia de Luisa se manifiesta asimismo en relaci\u00f3n con las j\u00f3venes que llegan a la Compa\u00f1\u00eda de las Hijas de la Cari\u00addad: querr\u00eda ella que estuviesen de inmediato preparadas para ir a prestar sus servicios. Vicente le reprocha su severidad y le pre\u00addica la paciencia:<\/p>\n<p><em>Me parece&#8230; que sor Vicenta de Richelieu&#8230; es una herma\u00adna muy buena, que goza de excelente reputaci\u00f3n en su pa\u00eds, que ha servido con constancia a su due\u00f1a durante siete u ocho a\u00f1os. Aquella pobre mujer ha sentido tanto su ausencia, que es imposible de decir. Hay esp\u00edritus que no se ajustan de golpe a todas las peque\u00f1as normas. El tiempo va remediando las cosas. Entre nosotros lo estoy experimentando continuamente (SVP, II, 121).<\/em><\/p>\n<p>Desde los comienzos de la Compa\u00f1\u00eda de las Hijas de la Cari\u00addad el se\u00f1or Vicente tiene por h\u00e1bito de acudir con regularidad y hablar a las Hermanas, las cuales aprecian mucho sus conferen\u00adcias. De pronto observa Luisa c\u00f3mo pasan los meses, y el se\u00f1or Vicente siempre ha de hallar alg\u00fan pretexto para no acudir: est\u00e1 abrumado de trabajo, o promete ir y no va, pues antes que las Hermanas est\u00e1n las Damas, los Padres, la Reina&#8230; Luisa lo lleva muy mal. Adjunta breves apostillas a la relaci\u00f3n de algunas con\u00adferencias que da el se\u00f1or Vicente. El 16 de agosto de 1640 pone que el se\u00f1or Vicente anda con prisas:<\/p>\n<p><em>Ha faltado poco para que no pudiese venir hoy, ya que he tenido que irme lejos dentro de la ciudad; por eso, dispongo de poco tiempo para hablaros (SVP, IX, 51).<\/em><\/p>\n<p>El 16 de agosto de 1641 hace constar Luisa las excusas del se\u00f1or Vicente:<\/p>\n<p><em>Hace tiempo que deber\u00eda haberos reunido (hac\u00eda un a\u00f1o que no hab\u00eda venido), pero me lo han impedido especialmente mi miseria y mis quehaceres. Adem\u00e1s, hijas m\u00edas, espero que la bondad de Dios habr\u00e1 suplido ella misma todo lo que yo os debo (SVP, IX, 55-56).<\/em><\/p>\n<p>El 9 de marzo de 1642, registra Luisa, con severidad tanto mayor:<\/p>\n<p><em>El d\u00eda 9 de marzo, el Padre Vicente no pudo, por alg\u00fan asun\u00adto urgente, estar al comienzo de la conferencia que su caridad hab\u00eda decidido darnos&#8230;El Padre Portail empez\u00f3 la conferencia (SVP, IX, 71-72).<\/em><\/p>\n<p>Luego, a mitad de la relaci\u00f3n, intercala:<\/p>\n<p><em>El Padre Vicente lleg\u00f3 a las cinco, y, despu\u00e9s de haber escu\u00adchado los pensamientos de algunas de nuestras hermanas, con\u00adtinu\u00f3: \u2014 Hermanas m\u00edas, se est\u00e1 haciendo ya muy tarde&#8230; hay que dejarlo para el domingo pr\u00f3ximo (SVP, IX, 72).<\/em><\/p>\n<p>S\u00f3lo las escasas conferencias de entre 1640 y 1642 ostentan tales observaciones. Pese a la ligera tensi\u00f3n en las relaciones, a los puntos de vista divergentes, la vida de la Compa\u00f1\u00eda prosigue: recepci\u00f3n de numerosas postulantes, respuesta a los llamamien\u00adtos, nuevas implantaciones (Nanteuil, Fontenay aux Roses, Sedan &#8230;), y asimismo la preparaci\u00f3n de los primeros votos en la Compa\u00f1\u00eda, el 25 de marzo de 1642.<\/p>\n<p>Un acontecimiento exterior, m\u00ednimo en apariencia, sacude bruscamente a ambos fundadores. El 7 de junio de 1642, vigilia de Pentecost\u00e9s, se hunde una planta en la casa-madre de las Hijas de la Caridad: era la sala donde las Hermanas ten\u00edan habitualmen\u00adte la conferencia. Estaba prevista para aquel d\u00eda una reuni\u00f3n, pero el se\u00f1or Vicente estaba comprometido, y hab\u00eda anunciado a las Hermanas que no acudir\u00eda. Ello explica por qu\u00e9 no hubo v\u00edctimas.<\/p>\n<p>Vicente de Pa\u00fal, siempre muy atento a los acontecimientos, deja que \u00e9ste le interpele hondamente. La ma\u00f1ana de Pentecos\u00adt\u00e9s comunica sus reflexiones a Luisa.<\/p>\n<p><em>\u00a1Dios m\u00edo, se\u00f1orita! \u00a1Cu\u00e1nto me he asustado esta ma\u00f1ana, cuando el padre Portail me ha dicho el accidente que ocurri\u00f3 ayer en su casa, y que le he comunicado a toda la compa\u00f1\u00eda!; le he dicho lo que nuestro Se\u00f1or les dijo a los que le preguntaban por el motivo de que hubieran muerto bajo las ruinas aquellos jud\u00edos, cuando la ca\u00edda de la torre de Jeric\u00f3: que esto no se deb\u00eda a los pecados de aquellas personas, ni a los de sus padres o sus madres, sino para manifestar la gloria de Dios. A usted le digo ciertamente lo mismo, se\u00f1orita, un nuevo motivo para amar a Dios m\u00e1s que nunca, ya que \u00c9l la ha preservado como a la <\/em><em>ni\u00f1a de sus ojos, en un accidente en el que deber\u00eda haber muer\u00adto usted bajo las ruinas, si Dios no hubiese detenido ese golpe con su amable Providencia. Todos le hemos dado gracias a Dios; entretanto, con la ayuda de Dios, espero tener la dicha de verla por aqu\u00ed, si viene usted a v\u00edsperas, o bien en su casa; le mando estas l\u00edneas para saludarle y darle de antemano los buenos d\u00edas (SVP, II, 215-216).<\/em><\/p>\n<p>Luisa de Marillac est\u00e1 tambi\u00e9n muy cambiada ante el suceso. Se ha conservado apenas su reflexi\u00f3n escrita de algunas a\u00f1os despu\u00e9s, en el aniversario del accidente:<\/p>\n<p><em>El d\u00eda y tiempo en que nuestro buen Dios nos permiti\u00f3 reco\u00adnocer su divina Providencia por acontecimientos tan se\u00f1alados como el de la ca\u00edda de nuestro piso, me ha vuelto a poner ante los ojos, la gran transformaci\u00f3n interior que tuve cuando su bondad me otorg\u00f3 luz y esclarecimiento sobre las grandes inquietudes y dificultades que (entonces) experimentaba&#8230; pareci\u00e9ndome que al mismo tiempo se operaba interiormente en nuestro muy Honorable Padre y en el alma de algunas de nues\u00adtras Hermanas algo grande para el establecimiento s\u00f3lido de esta peque\u00f1a familia&#8230; Y aunque siendo tan miserable como soy, ten\u00eda que haber pensado que lo ocurrido se deb\u00eda a mis pecados, nunca me ha venido tal pensamiento, ni en ese momen\u00adto ni despu\u00e9s, sino siempre en mis labios y m\u00e1s a\u00fan en mi cora\u00adz\u00f3n (el convencimiento de) que era una gracia de Dios, opera\u00adda con un fin que no conoc\u00edamos, y que por medio de ella Dios nos ped\u00eda algo a los unos y a los otros (SLM, 756).<\/em><\/p>\n<p>Vicente y Luisa se dejan interpelar por esta luz de Dios. Toman conciencia m\u00e1s aguda de que el autor de esta Compa\u00f1\u00eda es Dios, que tiene de ella un cuidado especial, que les invita a proseguir juntos la obra comenzada para su gloria y el bien de los pobres.<\/p>\n<p>En este d\u00eda de Pentecost\u00e9s de 1642, el esp\u00edritu de Dios les urge a superar la crisis que estaban viviendo y a convertirse.<\/p>\n<p>Han rebasado una etapa dif\u00edcil. Ante ellos se abre un largo per\u00edo\u00addo de amistad honda y f\u00e9rtil.<\/p>\n<p>Elisabeth Charpy<\/p>\n<p>CEME 2010<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN PER\u00cdODO DIF\u00cdCIL (1640-1642) Y sobreviene un per\u00edodo dif\u00edcil, en el que van a modificarse las relaciones. Ya en los a\u00f1os que preceden, algunas actitudes revelan la gran desemejanza entre una y otra personalidad. Toda &#8230; <a href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":402667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-403776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"UN PER\u00cdODO DIF\u00cdCIL (1640-1642) Y sobreviene un per\u00edodo dif\u00edcil, en el que van a modificarse las relaciones. Ya en los a\u00f1os que preceden, algunas actitudes revelan la gran desemejanza entre una y otra personalidad. Toda ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T05:46:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV)\",\"datePublished\":\"2021-09-22T05:46:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/\"},\"wordCount\":1891,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2019\\\/11\\\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/\",\"name\":\"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2019\\\/11\\\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2021-09-22T05:46:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2019\\\/11\\\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2019\\\/11\\\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV) - Somos Vicencianos","og_description":"UN PER\u00cdODO DIF\u00cdCIL (1640-1642) Y sobreviene un per\u00edodo dif\u00edcil, en el que van a modificarse las relaciones. Ya en los a\u00f1os que preceden, algunas actitudes revelan la gran desemejanza entre una y otra personalidad. Toda ... Read More","og_url":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2021-09-22T05:46:27+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV)","datePublished":"2021-09-22T05:46:27+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/"},"wordCount":1891,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/","url":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/","name":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1","datePublished":"2021-09-22T05:46:27+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-iv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (IV)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1280%2C720&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1H2w","jetpack-related-posts":[{"id":103885,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0977-a-luisa-de-marillac\/","url_meta":{"origin":403776,"position":0},"title":"Vicente de Pa\u00fal, Carta 0977: A Luisa De Marillac","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/09\/2012","format":false,"excerpt":"[Entre 1642 y 1649] Haga el favor de avisar para la reuni\u00f3n de ma\u00f1ana, despu\u00e9s de comer, si le parece bien, y a la se\u00f1orita de Lamoignon av\u00edsele para esta tarde a las seis; pero me ser\u00eda m\u00e1s c\u00f3modo que fuese para la una del mediod\u00eda de hoy.","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":403770,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-luisa-de-marillac-cual-fue-su-relacion-i\/","url_meta":{"origin":403776,"position":1},"title":"Vicente de Pa\u00fal y Luisa de Marillac. Cu\u00e1l fue su relaci\u00f3n (I)","author":"Mitxel Olabu\u00e9naga","date":"16\/09\/2021","format":false,"excerpt":"Numerosas son las cartas cruzadas entre Vicente de Pa\u00fal y Luisa de Marillac. Los archivos poseen 400 cartas de Vicente a Luisa: de \u00e9stas el 75% es anterior a 1642; y 200 de Luisa a Vicente, de las que el 80% es posterior a 1645. Recorri\u00e9ndolas se comprueba cu\u00e1nto evolucion\u00f3,\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2019\/11\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29843,"url":"https:\/\/vincentians.com\/es\/vida-de-santa-luisa-de-marillac-12-hacia-una-relacion-de-comunion\/","url_meta":{"origin":403776,"position":2},"title":"Vida de santa Luisa de Marillac. 12. Hacia una relaci\u00f3n de comuni\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/10\/2016","format":false,"excerpt":"Hacia una relaci\u00f3n de comuni\u00f3n TREINTA y cinco a\u00f1os de trabajo en com\u00fan, treinta y cinco a\u00f1os de intensa actividad. \u00bfSe trata para Vicente de Pa\u00fal y Luisa de Marillac de una simple colaboraci\u00f3n impuesta por las circuns\u00adtancias? \u00bfFue m\u00e1s lejos esa cooperaci\u00f3n que la simple ayuda mutua necesaria en\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/sata-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/sata-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/sata-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/sata-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/sata-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":387673,"url":"https:\/\/vincentians.com\/es\/afianzar-la-compania-2\/","url_meta":{"origin":403776,"position":3},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"17\/04\/2016","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"LOGO HHC","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/03\/LOGO-HHC.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":127035,"url":"https:\/\/vincentians.com\/es\/afianzar-la-compania\/","url_meta":{"origin":403776,"position":4},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"23\/01\/2024","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":103886,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0976-luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":403776,"position":5},"title":"Vicente de Pa\u00fal, Carta 0976: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"23\/09\/2012","format":false,"excerpt":"[Entre 1642 y 1649] Padre: Le suplico muy humildemente que haga el favor de decirme si se podr\u00e1 tener ma\u00f1ana mi\u00e9rcoles la reuni\u00f3n de las hermanas, para que pueda avisarlas, lo mismo que a las de Issy y Fontenay. La se\u00f1orita de Lamoignon desea que le pregunte cu\u00e1ndo podr\u00e1 descargar\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=403776"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403776\/revisions"}],"predecessor-version":[{"id":403777,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403776\/revisions\/403777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/402667"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=403776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=403776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=403776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}