{"id":403753,"date":"2021-08-30T08:25:45","date_gmt":"2021-08-30T06:25:45","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=403753"},"modified":"2021-07-17T11:27:11","modified_gmt":"2021-07-17T09:27:11","slug":"experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/","title":{"rendered":"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II)"},"content":{"rendered":"<ol>\n<li>LUISA DE MARILLAC EN LAS FUENTES DE LA ESPI\u00adRITUALIDAD VICENCIANA<\/li>\n<\/ol>\n<p>El Concilio Vaticano II urgi\u00f3 a todas las comunidades a encontrar en el seguimiento de Jesucristo y en las fuentes propias de su espiritualidad el dinamismo de renovaci\u00f3n que la Iglesia y los nuevos tiempos precisaban.<\/p>\n<p>Esta urgencia ha sido concretada y precisada en documentos de la Iglesia dirigidos a los diversos institutos y comunidades en los a\u00f1os posteriores al Concilio Vaticano II hasta nuestros d\u00edas:<\/p>\n<p>As\u00ed la Instrucci\u00f3n <em>\u00abMutuae Relationes\u00bb: \u00abEl carisma mismo de los Fundadores se revela como una experiencia del Esp\u00edritu transmitida a sus disc\u00edpulos para ser por ellos vivida, custodia\u00adda, profundizada y desarrollada constantemente en sinton\u00eda con el cuerpo de Cristo en crecimiento perenne&#8230; El car\u00e1cter caris\u00adm\u00e1tico de todo instituto requiere tanto por parte del Fundador, cuanto por parte de los disc\u00edpulos, el verificar continuamente la propia fidelidad al Se\u00f1or, la docilidad a su Esp\u00edritu, la atenci\u00f3n inteligente a las circunstancias y a los signos de los tiempos&#8230; nuestro tiempo exige de una manera especial esta autenticidad carism\u00e1tica, viva e ingeniosa en sus invenciones&#8217;.<\/em><\/p>\n<p>Y la Exhortaci\u00f3n Apost\u00f3lica <em>\u00abVita Consecrata\u00bb: \u00abSe invita a los Institutos a reproducir con valor la audacia, la creatividad y la santidad de sus fundadores y fundadoras como respuesta a los signos de los tiempos que surgen en el mundo de hoy&#8230; en plena docilidad a la inspiraci\u00f3n divina y al discernimiento eclesial. &#8230;la garant\u00eda de toda renovaci\u00f3n que pretenda ser fiel a la ins\u00adpiraci\u00f3n originaria est\u00e1 en la b\u00fasqueda de la conformaci\u00f3n cada vez m\u00e1s plena con el Se\u00f1or&#8230; En la dimensi\u00f3n del carisma convergen todos los dem\u00e1s aspectos de la formaci\u00f3n, como en un una s\u00edntesis que requiere una reflexi\u00f3n continua sobre la propia consagraci\u00f3n en sus diversas vertientes, tanto la apost\u00f3lica, como la asc\u00e9tica y m\u00edstica. Esto exige de cada miembro el estu\u00addio asiduo del esp\u00edritu del Instituto al que pertenece, de su his\u00adtoria y su misi\u00f3n\u00bb.<\/em><\/p>\n<p>Cuando hablamos, pues, de la importancia de conocer a santa Luisa y de acercarnos con seriedad y profundidad a sus escritos, no estamos pretendiendo acogernos a una moda, o a un plantea\u00admiento que pueda gozar de cierta simpat\u00eda en nuestras comuni\u00addades. Estamos, m\u00e1s bien, respondiendo a una llamada que <strong>tiene que ver con la identidad, con la fidelidad. <\/strong>Estamos tratando de beber en las <strong>fuentes de la espiritualidad vicenciana.<\/strong><\/p>\n<p>La argumentaci\u00f3n presentada por el Hermano Ducourneau para convencer a sus compa\u00f1eros de la necesidad de recoger y ordenar las palabras del se\u00f1or Vicente, podr\u00edan ayudarnos a nos\u00adotros tambi\u00e9n en relaci\u00f3n con los escritos de santa Luisa: <em>\u00abLa mejor herencia de los padres es la buena instrucci\u00f3n que dejan <\/em><em>a sus hijos&#8230; Si las obras que el Padre Vicente ha hecho son obras de Dios, como parece, es preciso que Dios le haya dado su esp\u00edritu para realizarlas y mantenerlas; por consiguiente, los consejos y ense\u00f1anzas utilizadas para ello hemos de tenerlos como divinos y recogerlos como un man\u00e1 del cielo&#8230; Quiz\u00e1s diga alguno que el Padre Vicente no dice nada que no pueda verse en los libros. Respondo que quiz\u00e1 sea verdad. Pero sabemos que, para alimentar bien a los ni\u00f1os, lo mejor es la leche de su pro\u00adpia madre y que las cari\u00f1osas ense\u00f1anzas de su padre hacen m\u00e1s impresi\u00f3n en sus almas que las de los maestros, debido al cari\u00ad\u00f1o y al afecto natural que Dios ha impreso en toda clase de per\u00adsonas hacia aquellos que los engendraron. Adem\u00e1s, es dif\u00edcil encontrar en los libros las hermosas ideas y los buenos senti\u00admientos que recibimos de las charlas de este caritativo padre, ya que nos las da seg\u00fan nuestras necesidades y nuestras obligacio\u00adnes, que son muy diferentes de las otras compa\u00f1\u00edas que han escrito lo que les corresponde a ellas\u2026\u201d.<\/em><\/p>\n<p>La Iglesia, al aprobar un carisma, est\u00e1 garantiz\u00e1ndonos que es <em>\u00abdon del Esp\u00edritu para la construcci\u00f3n del Cuerpo de Cristo\u201d. <\/em>La Iglesia aprueba el carisma vicenciano y las instituciones en que se hace visible.<\/p>\n<p>La Iglesia, al reconocer la santidad de quienes han sido elegi\u00addos por el Esp\u00edritu Santo para dar forma a una nueva familia espiritual, nos los propone como referencia fundacional y nos invita a recurrir a ellos como <strong>fuente permanente de inspiraci\u00f3n y renovaci\u00f3n.<\/strong><\/p>\n<p>San Vicente y santa Luisa son as\u00ed <strong>fuente de esta familia espi\u00adritual, <\/strong>y su experiencia est\u00e1 llamada a ser por nosotros <em>profundi\u00adzada, actualizada, recreada.<\/em><\/p>\n<p>Como anotara Jos\u00e9 Mar\u00eda Rom\u00e1n, cuando Vicente y Luisa <em>se <\/em>conocen y comienzan a colaborar, <em>\u00abla espiritualidad vicenciana no estaba a\u00fan completamente elaborada. Pero el descubrimien\u00adto esencial s\u00ed estaba hecho. La visi\u00f3n de Cristo en el pobre, la comprensi\u00f3n de la misi\u00f3n mesi\u00e1nica como evangelizaci\u00f3n de los pobres de palabra y de obra y la necesaria reforma de la Iglesia por la formaci\u00f3n de los sacerdotes eran convicciones o, mejor, ideas fuerza irreversiblemente adquiridas por Vicente desde las experiencias de Folleville y Ch\u00e1tillon en 1617 y la de Montmi-rail-Marchais en 1621. Hab\u00eda encontrado adem\u00e1s o estaba a punto de encontrar los cauces concretos por que deber\u00eda discu\u00adrrir su esfuerzo transformador: las caridades, fundadas en 1617 y la Congregaci\u00f3n de la Misi\u00f3n, en avanzado trance de gesta\u00adci\u00f3n y a punto de nacer como instituci\u00f3n en el pr\u00f3ximo de 1625\u00bb.<\/em><\/p>\n<p>Me atrevo a decir que hoy estamos en condiciones de asegu\u00adrar (hasta donde alcanzan nuestras investigaciones) que lo que llamamos <strong>espiritualidad vicenciana se ha ido consolidando en la mutua comprensi\u00f3n y colaboraci\u00f3n de Vicente de Pa\u00fal y de Luisa de Marillac.<\/strong><\/p>\n<p>En la presentaci\u00f3n de la biograf\u00eda de santa Luisa escrita por el P. Dirvin, escrib\u00eda el Cardenal Terence Cook: <em>\u00abEl gran coraz\u00f3n y original genio de esta mujer quedan eclipsados por la figura de quien fue su amigo, gu\u00eda y colaborador: es lamentable. Cierto, ella no lo juzgar\u00eda as\u00ed. La historia, en todo caso, no tolera bien el propio ocultamiento, cuando ata\u00f1e a logros excepcionales\u201d.<\/em><\/p>\n<p>\u00bfNo estaremos exagerando? \u00bfNo querremos ahora pasar al extremo opuesto y, por reacci\u00f3n, atribuir a santa Luisa lo que corresponde a san Vicente?<\/p>\n<p>Las Hijas de la Caridad han sabido encontrar, a mi modo de ver, el camino justo en ocasi\u00f3n de la revisi\u00f3n de sus Constitucio\u00adnes en la Asamblea general de 2003. Algunos postulados llega\u00addos a la Asamblea planteaban hasta el cambio de nombre de la Compa\u00f1\u00eda, para que reflejara mejor el papel de santa Luisa de Marillac y no figurara \u00fanicamente como la <em>Compa\u00f1\u00eda de las Hijas de la Caridad de San Vicente de Pa\u00fal. <\/em>La Compa\u00f1\u00eda, sin embargo, entendi\u00f3 que <strong>no se trataba de escribir el nombre de Luisa de Marillac donde figuraba el de Vicente de Pa\u00fal; <\/strong>lo verdaderamente importante era recuperar la frescura y vitalidad de las intuiciones de Luisa de Marillac en la vida de la Compa\u00ad\u00f1\u00eda. Todo lo dem\u00e1s podr\u00eda ser s\u00f3lo un brindis al sol.<\/p>\n<p>En esa misma direcci\u00f3n, no me gustar\u00eda dejar la impresi\u00f3n de estar proponiendo que la <strong>Familia Vicenciana <\/strong>dejara de llamarse Vicenciana para <strong>introducir un t\u00e9rmino que hiciera referencia tambi\u00e9n a Luisa de Marillac.<\/strong><\/p>\n<p>No se trata de cambiar de nombre, se trata de descubrir, de poner de relieve, de <strong>tomar en consideraci\u00f3n la fuente que para la Familia Vicenciana representa la experiencia de Luisa de Marillac como verdadera fundadora.<\/strong><\/p>\n<p>Jaime Corera, recogiendo una feliz expresi\u00f3n de san Ireneo, habla de las dos manos del Padre: Vicente y Luisa, las dos manos del \u00fanico carisma que estamos llamados a profundizar, actuali\u00adzar, expresar.<\/p>\n<p>Seguramente, las Hermanas admitir\u00e1n con benevolencia esta propuesta. Pero, \u00bfpodr\u00e1n admitirla tambi\u00e9n los dem\u00e1s miembros de la Familia Vicenciana? Conf\u00edo en que \u00e9ste pueda ser uno de los frutos de las celebraciones de este 350 aniversario de la muerte de san Vicente de Pa\u00fal y de santa Luisa de Marillac, <strong>fundadores los dos de la Familia Vicenciana.<\/strong><\/p>\n<p>Perm\u00edtanme, pues, formular sencillamente mi reflexi\u00f3n <em>y <\/em>sin\u00adtetizar mi aportaci\u00f3n a este tema:<\/p>\n<p>Entiendo por <strong>carisma vicenciano <\/strong>el don del Esp\u00edritu sus\u00adcitado por Dios en su Iglesia en las personas de Vicente de Pa\u00fal y de Luisa de Marillac; don del Esp\u00edritu compartido por sus seguidores y seguidoras que en las diversas insti\u00adtuciones y asociaciones surgidas bajo su inspiraci\u00f3n, se esfuerzan por vivir, custodiar, profundizar y desarrollar constantemente en sinton\u00eda con el Cuerpo de Cristo en crecimiento perenne.<\/p>\n<p>Aunque la palabra <strong>vicenciano <\/strong>procede etimol\u00f3gicamente del nombre propio Vicente (Vincentius), no creo que pueda referirse a la \u00fanica personalidad de Vicente de Pa\u00fal la peculiaridad del carisma vicenciano. \u00c9ste no se entien\u00adde sin la original aportaci\u00f3n de Luisa de Marillac. Cuanto m\u00e1s estudiamos la relaci\u00f3n entre <strong>Vicente de Pa\u00fal y Luisa de Marillac, <\/strong>m\u00e1s dif\u00edcil resulta atribuir a uno solo las ins\u00adpiraciones del que conocemos como carisma vicenciano.<\/p>\n<p>La configuraci\u00f3n del carisma vicenciano no corresponde en exclusiva a la \u00e9poca de los Fundadores. El carisma es una <strong>realidad din\u00e1mica, <\/strong>que va recre\u00e1ndose en cada \u00e9poca, que va profundiz\u00e1ndose y enriqueci\u00e9ndose perma\u00adnentemente con la vitalidad de las respuestas de cada una de las personas, comunidades y asociaciones en fidelidad al Esp\u00edritu. Por lo que, en seguimiento de Jesucristo, a par\u00adtir de las fuentes fundacionales, deber\u00e1 ser constantemente recreado, actualizado y en nuevas formas expresado y vivenciado.<\/p>\n<p>Corpus Delgado<\/p>\n<p>CEME 2010<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LUISA DE MARILLAC EN LAS FUENTES DE LA ESPI\u00adRITUALIDAD VICENCIANA El Concilio Vaticano II urgi\u00f3 a todas las comunidades a encontrar en el seguimiento de Jesucristo y en las fuentes propias de su espiritualidad el &#8230; <a href=\"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":399750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-403753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"LUISA DE MARILLAC EN LAS FUENTES DE LA ESPI\u00adRITUALIDAD VICENCIANA El Concilio Vaticano II urgi\u00f3 a todas las comunidades a encontrar en el seguimiento de Jesucristo y en las fuentes propias de su espiritualidad el ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-30T06:25:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II)\",\"datePublished\":\"2021-08-30T06:25:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/\"},\"wordCount\":1674,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/\",\"name\":\"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2021-08-30T06:25:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/","og_locale":"es_ES","og_type":"article","og_title":"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II) - Somos Vicencianos","og_description":"LUISA DE MARILLAC EN LAS FUENTES DE LA ESPI\u00adRITUALIDAD VICENCIANA El Concilio Vaticano II urgi\u00f3 a todas las comunidades a encontrar en el seguimiento de Jesucristo y en las fuentes propias de su espiritualidad el ... Read More","og_url":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2021-08-30T06:25:45+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II)","datePublished":"2021-08-30T06:25:45+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/"},"wordCount":1674,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/","url":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/","name":"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","datePublished":"2021-08-30T06:25:45+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/experiencia-espiritual-de-santa-luisa-y-espiritualidad-vicenciana-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Experiencia espiritual de santa Luisa y espiritualidad vicenciana (II)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"https:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/luisa-y-vicente-con-ninyos.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1H29","jetpack-related-posts":[{"id":126479,"url":"https:\/\/vincentians.com\/es\/el-laicado-vicenciano-a-la-luz-del-vaticano-ii\/","url_meta":{"origin":403753,"position":0},"title":"El Laicado Vicenciano a la luz del Vaticano II","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/08\/2019","format":false,"excerpt":"De entrada, confieso mi rubor y mi atrevimiento. Porque soy consciente de que puedo caer en la sempiterna tentaci\u00f3n del t\u00edpico cl\u00e9rigo que, desde las alambradas del dogmatismo, se permite adoctrinar a los \"pobrecitos\" laicos, como si ellos no fueran mayores de edad y protagonis\u00adtas de su compromiso vital. Sin\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/vincentian-missionarie.jpg?fit=846%2C444&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/vincentian-missionarie.jpg?fit=846%2C444&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/vincentian-missionarie.jpg?fit=846%2C444&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/vincentian-missionarie.jpg?fit=846%2C444&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":109293,"url":"https:\/\/vincentians.com\/es\/secularidad-y-exencion-de-la-congregacion-distincion-con-los-religiosos\/","url_meta":{"origin":403753,"position":1},"title":"Secularidad y exenci\u00f3n de la Congregaci\u00f3n. Distinci\u00f3n con los religiosos.","author":"Francisco Javier Fern\u00e1ndez Chento","date":"04\/05\/2016","format":false,"excerpt":"A trav\u00e9s de los tiempos, la vida y la profesi\u00f3n de los \"Conse\u00adjos evang\u00e9licos\" han tomado diversas formas can\u00f3nicas. Sobre este tema se est\u00e1n editando buenos libros y s\u00edntesis luminosas. I En tiempo de San Vicente eran considerados jur\u00eddicamente Religiosos los que hac\u00edan profesi\u00f3n de los consejos evang\u00e9licos mediante votos\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"LOGO CM","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2012\/06\/LOGO-CM-237x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":116383,"url":"https:\/\/vincentians.com\/es\/bibliografia-vicenciana-1960-1970-en-torno-a-la-espiritualidad-de-san-vicente\/","url_meta":{"origin":403753,"position":2},"title":"Bibliograf\u00eda Vicenciana 1960-1970 en torno a la espiritualidad de San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2021","format":false,"excerpt":"Lo que antes se llamaba Asc\u00e9tica y M\u00edstica, hoy se llama com\u00fanmen\u00adte Espiritualidad. Es una palabra tra\u00edda de Francia, como tantas otras, que tambi\u00e9n han hecho fortuna, m\u00e1s por moda que por convencimiento. As\u00ed se bautizan los tratados de Historia, desde Pourrat (1926) hasta Bouyer-Vandenbroucke (1963). El recomendar tan insistentemente\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":116979,"url":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-y-renovacion-conciliar\/","url_meta":{"origin":403753,"position":3},"title":"Espiritualidad vicenciana y renovaci\u00f3n conciliar","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/03\/2015","format":false,"excerpt":"En la Iglesia posconciliar se necesita un estudio s\u00f3lido y diverso de la espiritualidad cristiana b\u00e1sica y de las \"espiritualidades\" que han aplicado la Espiritualidad evang\u00e9lica a distintas situa\u00adciones hist\u00f3ricas y a familias religiosas y apost\u00f3licas, para reali\u00adzar la \"adecuada renovaci\u00f3n\" de estas espiritualidades a la au\u00adt\u00e9ntica espiritualidad Cristoc\u00e9ntrica y\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"concilio1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/concilio1-300x113.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":131132,"url":"https:\/\/vincentians.com\/es\/fieles-a-san-vicente\/","url_meta":{"origin":403753,"position":4},"title":"Fieles a San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/08\/2014","format":false,"excerpt":"\"El carisma mismo de los Fundadores se revela como una experiencia del Esp\u00edritu (EN 11), transmitida a los propios disc\u00edpulos para ser por ellos vivida, custodiada, profundizada y desarrollada constantemente en sinton\u00eda con el Cuerpo de Cristo en crecimiento perenne\". (MR 11). \"El fin de la Congregaci\u00f3n de la Misi\u00f3n\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"espiritualidad","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/espiritualidad.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":134512,"url":"https:\/\/vincentians.com\/es\/dos-papas-santos-simpatizantes-del-carisma-vicentino\/","url_meta":{"origin":403753,"position":5},"title":"Dos papas santos simpatizantes del carisma vicentino","author":"Francisco Javier Fern\u00e1ndez Chento","date":"31\/12\/2014","format":false,"excerpt":"El Papa Francisco canoniz\u00f3 a los papas Juan XXIII (1881\u20131963) y Juan Pablo II (1929\u20132005) el 27 de abril de 2014 en Roma, en el contexto del 50 aniversario de la apertura del Concilio Vaticano II convocado por el papa Roncalli, convirti\u00e9ndose as\u00ed en los otros pont\u00edfices proclamados santos en\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"juan23_y_juanpablo2","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/12\/juan23_y_juanpablo2.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=403753"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403753\/revisions"}],"predecessor-version":[{"id":403754,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403753\/revisions\/403754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/399750"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=403753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=403753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=403753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}