{"id":39070,"date":"2020-10-14T08:55:29","date_gmt":"2020-10-14T06:55:29","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/05\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/"},"modified":"2020-10-03T19:27:41","modified_gmt":"2020-10-03T17:27:41","slug":"vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/","title":{"rendered":"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey"},"content":{"rendered":"<p>Por gracia y privilegio del Rey se autoriza a Florentino Lambert, comerciante librero de Par\u00eds, a imprimir o hacer imprimir, vender y distribuir en todo el Reino un libro titulado: \u00ab<strong>La Vie du V\u00e9n\u00e9rable Serviteur de Dieu, Vincent de Paul, Instituteur et premier Sup\u00e9rieur G\u00e9n\u00e9ral de la Congregation de la Mission\u00bb. Par Messire Louis Abelly, \u00abEvesque de Rodez<\/strong>\u00ab; y con el tama\u00f1o, el tipo de letra y tantas veces como le parezca bien durante veinte a\u00f1os consecutivos. Con prohibici\u00f3n a todos los impresores, libreros y dem\u00e1s, de imprimir, hacer imprimir, vender y distribuir dicho libro, de la forma y manera y con el pretexto que sea, sin el consentimiento de dicho Lambert, o de los que ostenten sus derechos, bajo la pena de confiscaci\u00f3n de los ejemplares, de una multa arbitraria, de costas, perjuicios e intereses, como se ha hecho notar a lo largo de dicho privilegio, dado en Par\u00eds, el d\u00eda 19 de mayo de 1664.<\/p>\n<p>Y el 22 de nuestro reinado. Firmado BARDON.<\/p>\n<p>\u00abRegistrado en el Libro del Gremio de Impresores y Comerciantes Libreros de esta ciudad el 19 de agosto de 1664\u00bb<\/p>\n<p>E. MARTIN, s\u00edndico Se acab\u00f3 de imprimir por primera vez el 10 de septiembre de 1664<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por gracia y privilegio del Rey se autoriza a Florentino Lambert, comerciante librero de Par\u00eds, a imprimir o hacer imprimir, vender y distribuir en todo el Reino un libro titulado: \u00abLa Vie du V\u00e9n\u00e9rable Serviteur &#8230; <a href=\"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":149583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"#ffffff","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[266,5],"tags":[218,144],"class_list":["post-39070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-luis-abelly","category-vicente-de-paul","tag-abelly","tag-lambert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Por gracia y privilegio del Rey se autoriza a Florentino Lambert, comerciante librero de Par\u00eds, a imprimir o hacer imprimir, vender y distribuir en todo el Reino un libro titulado: \u00abLa Vie du V\u00e9n\u00e9rable Serviteur ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T06:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey\",\"datePublished\":\"2020-10-14T06:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/\"},\"wordCount\":222,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/abelly-feat.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Abelly\",\"Lambert\"],\"articleSection\":[\"Escritos de Luis Abelly\",\"Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/\",\"name\":\"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/abelly-feat.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2020-10-14T06:55:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/abelly-feat.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/abelly-feat.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/","og_locale":"es_ES","og_type":"article","og_title":"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey - Somos Vicencianos","og_description":"Por gracia y privilegio del Rey se autoriza a Florentino Lambert, comerciante librero de Par\u00eds, a imprimir o hacer imprimir, vender y distribuir en todo el Reino un libro titulado: \u00abLa Vie du V\u00e9n\u00e9rable Serviteur ... Read More","og_url":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2020-10-14T06:55:29+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey","datePublished":"2020-10-14T06:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/"},"wordCount":222,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1","keywords":["Abelly","Lambert"],"articleSection":["Escritos de Luis Abelly","Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/","url":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/","name":"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1","datePublished":"2020-10-14T06:55:29+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-tercero-extracto-del-privilegio-del-rey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vida de san Vicente de Pa\u00fal: Libro Tercero, Extracto del privilegio del Rey"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-aaa","jetpack-related-posts":[{"id":30481,"url":"https:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-primero-extracto-del-privilegio-del-rey\/","url_meta":{"origin":39070,"position":0},"title":"Vida de san Vicente de Pa\u00fal: Libro Primero, Extracto del privilegio del Rey","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/04\/2020","format":false,"excerpt":"Por gracia y privilegio del Rey se autoriza a Florentino Lambert, comerciante librero de Par\u00eds, a imprimir o hacer imprimir, vender y distribuir en todo el Reino un libro titulado: \"La vie du V\u00e9n\u00e9rable Serviteur de Dieu, Vincent de Paul, Instituteur et premier Sup\u00e9rieur G\u00e9n\u00e9ral de la Congr\u00e9gation de la\u2026","rel":"","context":"En \u00abEscritos de Luis Abelly\u00bb","block_context":{"text":"Escritos de Luis Abelly","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luis-abelly\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":402198,"url":"https:\/\/vincentians.com\/es\/san-vicente-collet-3\/","url_meta":{"origin":39070,"position":1},"title":"San Vicente (Collet) 3","author":"Mitxel Olabu\u00e9naga","date":"21\/03\/2019","format":false,"excerpt":"APROBACI\u00d3N \u00a0 He le\u00eddo de parte de la Orden de Monse\u00f1or Canciller, la Nueva Vida de S. Vicente de Pa\u00fal, ese gran Modelo de todas las Virtudes Cristianas y Eclesi\u00e1sticas, Padre y Fundador de una Congregaci\u00f3n, que se distingue por su celo por la Predicaci\u00f3n del Evangelio, y de quien\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":101815,"url":"https:\/\/vincentians.com\/es\/vida-del-senor-vicente-de-paul-nota-bibliografica-2\/","url_meta":{"origin":39070,"position":2},"title":"Vida del Se\u00f1or Vicente de Pa\u00fal: Nota bibliogr\u00e1fica","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/05\/2015","format":false,"excerpt":"Nota bibliogr\u00e1fica Esta biograf\u00eda de san Vicente de Pa\u00fal se dedica a la memoria de Pierre Coste, C.M. (1873-1935), sin cuyo trabajo previo no hubiera podido ser escrita. Coste recogi\u00f3 pacientemente y public\u00f3 en trece vol\u00famenes pr\u00e1cticamente todos los es\u00adcritos procedentes de Vicente de Pa\u00fal o que se refieren a\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"sanvibiblia","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/08\/sanvibiblia-300x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":122034,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1137-a-lamberto-aux-couteaux-sacerdote-de-la-mision-en-san-lazaro\/","url_meta":{"origin":39070,"position":3},"title":"Vicente de Pa\u00fal, Carta 1137: A Lamberto Aux Couteaux, Sacerdote De La Misi\u00f3n, En San L\u00e1zaro","author":"Francisco Javier Fern\u00e1ndez Chento","date":"04\/05\/2013","format":false,"excerpt":"Fr\u00e9neville, 18 enero 1649 San Vicente le dice que no es conveniente vender el grano almacenado en los graneros de San L\u00e1zaro; m\u00e1s vale prest\u00e1rselos a Dios d\u00e1ndoselo en limosna a los pobres. Si no basta la limosna de medio saco, que se les d\u00e9 uno entero.","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":130531,"url":"https:\/\/vincentians.com\/es\/santa-luisa-ane-la-infancia-abandonada-iv\/","url_meta":{"origin":39070,"position":4},"title":"Santa Luisa: ante la infancia abandonada (IV)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/05\/2014","format":false,"excerpt":"Dedicaci\u00f3n de las hermanas Bajo la direcci\u00f3n conjunta de los dos santos, no es sorprendente que sus hijas hayan comprendido tan bien las lecciones recibidas. Su aplicaci\u00f3n no estaba falta de fatiga, pero este cansancio incluso les era tanto m\u00e1s dulce en cuanto que estaba acompa\u00f1ado de grandes consuelos que\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"Hijas-de-la-Caridad-18-Luisa","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/05\/Hijas-de-la-Caridad-18-Luisa.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":399431,"url":"https:\/\/vincentians.com\/es\/vicente-paul-carta-1373-lamberto-aux-couteaux-superior-richelieu\/","url_meta":{"origin":39070,"position":5},"title":"Vicente de Pa\u00fal, Carta 1373: A Lamberto Aux Couteaux, Superior de Richelieu","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/01\/2017","format":false,"excerpt":"15 de enero de 1651 Le rogu\u00e9 que fuera a hacer la visita a Lu\u00e7on, donde actualmente est\u00e1 de superior el padre Lucas y el padre Chiroye no es m\u00e1s que asistente. Le hab\u00eda rogado al primero que enviase a alguien a las aldeas del se\u00f1or de la Marguerie, en\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/39070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=39070"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/39070\/revisions"}],"predecessor-version":[{"id":403087,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/39070\/revisions\/403087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/149583"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=39070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=39070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=39070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}