{"id":35823,"date":"2014-06-28T08:35:07","date_gmt":"2014-06-28T06:35:07","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/04\/espiritualidad-vicenciana-dementes\/"},"modified":"2014-06-28T08:35:07","modified_gmt":"2014-06-28T06:35:07","slug":"espiritualidad-vicenciana-dementes","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/","title":{"rendered":"Espiritualidad vicenciana: Dementes"},"content":{"rendered":"<h2 style=\"text-align: justify\">I. Los dementes en el siglo XVII en Francia<\/h2>\n<p style=\"text-align: justify\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/dementes.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-35824\" title=\"dementes\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/dementes-219x300.jpg?resize=219%2C300\" alt=\"\" width=\"219\" height=\"300\" \/><\/a>Para comprender y valorar la evangelizaci\u00f3n vicenciana con los dementes, conviene recordar que hasta la \u00faltima parte del siglo XVIII, con Pi\u00adnel (1745-1826), no hubo en Francia ni psiqui\u00e1\u00adtricos ni actuaci\u00f3n psiqui\u00e1trica cient\u00edfica, tal como se concibe actualmente.<\/p>\n<p style=\"text-align: justify\">Para las gentes del siglo XVII, \u00abque basaba la grandeza del hombre en su raz\u00f3n y voluntad\u00bb, un loco es \u00abun ser ausente de s\u00ed mismo\u00bb. El loco es un enfermo del alma y su locura es una enfer\u00admedad, ocasionada por una determinada pertur\u00adbaci\u00f3n, ante todo f\u00edsica. Esta perturbaci\u00f3n es la que impide al alma ejercer sus funciones de ra\u00adzonamiento, memoria e imaginaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Las enfermedades mentales son consecuen\u00adcia de una \u00abcocci\u00f3n\u00bb de alguno de los cuatro hu\u00admores (sangre, bilis, linfa y humor negro). Al ca\u00adlentarse excesivamente, estos humores producen substancias nocivas que da\u00f1an al cerebro. Las principales enfermedades mentales son el fre\u00adnes\u00ed, las man\u00edas y la melancol\u00eda.<\/p>\n<p style=\"text-align: justify\">Si la grandeza del hombre requiere el domi\u00adnio de s\u00ed mismo, el loco, el ausente de s\u00ed mis\u00admo, es adem\u00e1s considerado como una presa f\u00e1\u00adcil del genio, la c\u00f3lera, y del demonio u otros es\u00adp\u00edritus.<\/p>\n<p style=\"text-align: justify\">Con este cuadro delante, no es de extra\u00f1ar, que los medios de curaci\u00f3n se busquen entre los que calman y tonifican, sobre todo, el opio; los que eliminan los humores da\u00f1ados: purgas, sangr\u00edas y toda clase de evacuantes; es tambi\u00e9n el mis\u00admo hombre normal el que proporciona los ele\u00admentos que pueden combatir, por eso se utilizan p\u00f3cimas humanas a base de excrementos, pol\u00advos de cr\u00e1neo, cabellos quemados\u2026 La magia, los exorcismos, junto con pr\u00e1cticas religiosas y pe\u00adregrinaciones a Santos determinados, con pode\u00adres extraordinarios, ser\u00e1n tambi\u00e9n medios ade\u00adcuados de curaci\u00f3n, sobre todo cuando al loco, perdido el dominio de s\u00ed mismo, se le considera que ha pasado a depender de \u00abotros\u00bb.<\/p>\n<p style=\"text-align: justify\">En una sociedad que predica la norma y el or\u00adden como ideal humano y que tiene s\u00f3lo un co\u00adnocimiento m\u00e9dico del comportamiento humano, anclado en siglos pasados, no puede tener cabida la enfermedad mental en sentido moderno.<\/p>\n<p style=\"text-align: justify\">Esta sociedad del siglo XVII, que define a los locos, como desequilibrados en el orden perso\u00adnal y los considera tambi\u00e9n como marginados del orden social existente, los coloca entre los men\u00addigos, vagabundos, rebeldes y \u00abmonstruos\u00bb de la naturaleza. Por eso, su tarea principal consiste en defenderse de todos \u00e9stos, creando lugares de \u00abencerramiento\u00bb. La asistencia, que presta a este grupo de marginados, se reduce propiamente a apartarlos de la vida social.<\/p>\n<p style=\"text-align: justify\">Desde 1611, hay en Par\u00eds tres lugares llama\u00addos hospitales de pobres \u00abenfermes\u00bb. En ellos, se encierra tanto a locos e insensatos, como a j\u00f3\u00advenes y mujeres desvergonzadas, incorregibles, ni\u00f1os dif\u00edciles y a mendigos ociosos y vagabun\u00addos\u2026 Estas casas funcionar\u00e1n hasta 1656, a\u00f1o en que se cre\u00f3 para todos ellos el gran Hospital Ge\u00adneral. Entre el 5 el 10 por ciento de todos los \u00abencerrados\u00bb en esta nueva instituci\u00f3n ser\u00e1n los propiamente dementes.<\/p>\n<p style=\"text-align: justify\">La apertura y la organizaci\u00f3n de estas institu\u00adciones sociales es el resultado de una asistencia p\u00fablica, motivada por las m\u00faltiples visiones que la sociedad de entonces ten\u00eda sobre los margi\u00adnados; visiones que van desde considerarlos s\u00f3\u00adlo como un peligro social y sanitario, hasta tener de ellos la visi\u00f3n cristiana del pobre, e incluso ver en ellos la imagen de Cristo crucificado. Ser\u00e1n es\u00adtas distintas visiones las que proporcionar\u00e1n los diversos medios de atenci\u00f3n para con ellos.<\/p>\n<div style=\"text-align: justify\">\n<h2>II. Visi\u00f3n vicenciana o el amor a los dementes<\/h2>\n<\/div>\n<p style=\"text-align: justify\">Cuando a Vicente le ofrecieron el Priorato de S. L\u00e1zaro, dud\u00f3 mucho en aceptarlo. En S. L\u00e1za\u00adro, hab\u00eda mucha cosas; entre ellas, un \u00abencerra\u00admiento de locos\u00bb, sobre las que hab\u00eda que hacer un profundo discernimiento. Discernimiento que a Vicente le llev\u00f3 m\u00e1s de un a\u00f1o.<\/p>\n<p style=\"text-align: justify\">Vicente comenz\u00f3 por aceptar el servicio a los locos, para pasar muy pronto a tener una gran predilecci\u00f3n por ellos. <em>\u00abEn aquel <\/em><em>tiempo<\/em> \u2013dec\u00eda Vi\u00adcente\u2013 <em>tuvimos un juicio, en el que se ventilaba si nos echaban o nos dejaban en la casa de S. L\u00e1\u00adzaro; me acuerdo que entonces me plante\u00e9 a m\u00ed mismo esta pregunta: Si hubiera que dejar ahora esta casa \u00bfqu\u00e9 es lo que te cuesta o te cos\u00adtar\u00eda m\u00e1s? \u00bfqu\u00e9 es lo que te causar\u00eda mayor disgusto y pena? Y me pareci\u00f3 entonces que lo peor ser\u00eda tener que dejar de ver a esas pobres gentes <\/em>(locos), <em>verme obligado a dejar su cuida\u00addo y servicio\u00bb <\/em>(XI, 715). Vicente, en este peque\u00ad\u00f1o espacio de tiempo (el 8 de enero de 1632 to\u00adm\u00f3 posesi\u00f3n de S. L\u00e1zaro y el 21 de agosto se tuvo el juicio), ha pasado del <em>\u00abtuvimos que asu\u00admir su cuidado\u00bb <\/em>a quererlos, y adem\u00e1s con pre\u00addilecci\u00f3n. Ha mirado a esos dementes y los ha vis\u00adto a la luz del Evangelio. Este paso, del <em>\u00abtuvimos que asumir su cuidado\u00bb <\/em>hasta <em>\u00ablo peor ser\u00eda te\u00adner que dejarlos\u00bb, <\/em>es lo que trata de explicar en sus conferencias a todos los misioneros, sobre todo a los que se dedican principalmente a ellos en S. L\u00e1zaro. Sus razonamientos son claros y los podemos resumir as\u00ed:<\/p>\n<ul style=\"text-align: justify\">\n<li>Dios los quiere: es una cosa agradable a Dios el dedicarse al alivio de estos afligidos. Es una de las obras que m\u00e1s le agradan (XI, 716).<\/li>\n<li>Es una obra mucho m\u00e1s meritoria que otras, porque la naturaleza no encuentra en ella, ningu\u00adna satisfacci\u00f3n (Xl, 716).<\/li>\n<li>Dios nos ha llamado a la imitaci\u00f3n y segui\u00admiento de Cristo, es Nuestro Se\u00f1or la regla de la Misi\u00f3n, y \u00e9l quiso verse rodeado de lun\u00e1ticos, endemoniados, locos, tentados y posesos. Estos dementes pertenecen al lote de los pobres, lote que nos ha tocado a nosotros. Algunos dir\u00e1n \u00bfpor qu\u00e9 perder el tiempo con los locos? No importa; nuestra vocaci\u00f3n es Evangelizare pauperibus. (X, 129; XI, 387, 394-95, 429).<\/li>\n<li>La solidaridad de Cristo con estos hombres le llev\u00f3 a ser tomado por uno de ellos. (Mc. 2, 21; XI, 394).<\/li>\n<li>El sufrimiento es la escuela de la santidad personal y del servicio a los dem\u00e1s. La enferme\u00addad es siempre para el bien y la salvacion de los hombres. Los enfermos son una bendici\u00f3n de la Compa\u00f1\u00eda. El compartir, dar remedio y mirar a Cristo en los enfermos tiene la m\u00e1s pura realiza\u00adci\u00f3n, cuando se trata de los locos, de los que no se puede esperar una m\u00ednima recompensa (XI, 716-17).<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Vicente termina su alocuci\u00f3n con un profun\u00addo deseo: \u00ab\u00a1Oh, Salvador m\u00edo y Dios m\u00edo! \u00a1Con\u00adc\u00e9denos la gracia de mirar estas cosas con los mismos ojos con que t\u00fa las miras!\u00bb (XI, 716).<\/p>\n<p style=\"text-align: justify\">Ferr\u00fas, representante en 1784 del que es con\u00adsiderado fundador de la psiquiatr\u00eda en Francia, el psiquiatra Pinel, escrib\u00eda: \u00abVicente de Pa\u00fal, este digno ap\u00f3stol del Evangelio, fue el primero que predic\u00f3 con entusiasmo a favor de estos infelices. \u00a1Es un hecho cierto! \u00a1Y adem\u00e1s, sobre todo, siem\u00adpre los defend\u00eda!\u00bb.<\/p>\n<p style=\"text-align: justify\">Esta visi\u00f3n vicenciana es, sin duda, la base y el fundamento de la obra con los locos, pero no es todo. Este amor afectivo, interno, debe ter\u00adminar en una realizaci\u00f3n externa, en un amor efectivo para comprender toda tarea vicenciana.<\/p>\n<p style=\"text-align: justify\">El Doctor Werner Leibrand, que escribi\u00f3 una vida de san Vicente desde el punto de vista de su profesi\u00f3n m\u00e9dica, enjuicia la obra de Vicente con los locos diciendo: \u00abTodos los intentos para relacionar a Vicente con las ideas racionalistas del siglo XVIII han de fracasar, porque no tienen en cuenta las caracter\u00edsticas de su personalidad evang\u00e9lica. Pero ser\u00eda igualmente desacertado, co\u00admo lo hace Jacques Vi\u00e9, pensar que su misticis\u00admo es la \u00fanica base teor\u00e9tica de la posici\u00f3n prag\u00adm\u00e1tica de Vicente\u00bb (pg. 168-69).<\/p>\n<div style=\"text-align: justify\">\n<h2>III. Acci\u00f3n vicenciana o el amor efectivo a los de\u00admentes<\/h2>\n<\/div>\n<h3 style=\"text-align: justify\"><strong>1. Los pensionistas de S. L\u00e1zaro<\/strong><\/h3>\n<p style=\"text-align: justify\">Cuando Vicente lleg\u00f3 a San L\u00e1zaro el 8 de enero de 1632 con alrededor de veinticinco mi\u00adsioneros, hab\u00eda en el Priorato dos o tres locos y probablemente (o vinieron muy pronto) algunos otros d\u00e9biles de esp\u00edritu o mentecatos y algunas personas de mala conducta. Tambi\u00e9n desde 1637, se internaban en S. L\u00e1zaro sacerdotes vagabun\u00addos o mendigos, que hab\u00edan roto con sus di\u00f3ce\u00adsis y que en Par\u00eds causaban alg\u00fan esc\u00e1ndalo.<\/p>\n<p style=\"text-align: justify\">Todos estos forman el grupo de los \u00abpensio\u00adnistas\u00bb. De estos pensionistas, dice Vicente que unos son enfermos de cuerpo y otros de esp\u00edri\u00adtu, unos dementes y otros ligeros, unos sin raz\u00f3n y otros viciosos, en una palabra, alienados de es\u00adp\u00edritu, pero unos por enfermedad y otros por ma\u00adlicia, aqu\u00e9llos est\u00e1n aqu\u00ed para recobrar su salud y \u00e9stos para corregirse de su mala vida (XI, 716).<\/p>\n<p style=\"text-align: justify\">Estas dos clases de hombres son los que ocu\u00adpaban el correccional de S. L\u00e1zaro, un edificio de varias plantas, con habitaciones particulares, al\u00adgunas con rejas y a los que se les vigilaba estre\u00adchamente, incluso con varios perros.<\/p>\n<p style=\"text-align: justify\">Para un encerramiento prolongado, era nece\u00adsario la autorizaci\u00f3n de un magistrado. S\u00f3lo cuan\u00addo el encerramiento era de algunas semanas, nunca superior a tres meses, pod\u00eda hacerlo la fa\u00admilia. Eran en general familias de \u00abqualit\u00e9\u00bb que se compromet\u00edan a pagar una pensi\u00f3n. A veces, el Parlamento ordenaba el encerramiento de un individuo y entonces era el Tesoro P\u00fablico el que pagaba.<\/p>\n<p style=\"text-align: justify\">Hab\u00eda distintos tipos de pensi\u00f3n, que obliga\u00adban tambi\u00e9n a distintas clases de servicios. Se cal\u00adcula entre 50 y 60 el n\u00famero de los que pasaron por San L\u00e1zaro en tiempos de Vicente.<\/p>\n<p style=\"text-align: justify\">Tanto las familias, como los mismos pensio\u00adnistas, trataban de ocultar su paso por el correc\u00adcional de S. L\u00e1zaro, sin embargo desde finales del siglo XVII hasta el 13 de julio de 1789, d\u00eda del asalto a S. L\u00e1zaro, se conservan algunas listas de los encerrados, y los procesos oficiales de las vi\u00adsitas ordenadas por el Parlamento.<\/p>\n<p style=\"text-align: justify\">Sabemos que desde diciembre de 1634 es\u00adtuvo all\u00ed Juan de Montholon, de 21 a\u00f1os, herma\u00adno de Guido-Francisco, abogado del Parlamento. Estaba all\u00ed a petici\u00f3n del abogado, que era su tu\u00adtor, por haberse casado con una menor, y estu\u00advo al borde de la locura antes de escaparse, en\u00adtre marzo y abril de 1635 (I, 313. 317).<\/p>\n<p style=\"text-align: justify\">En 1646, estuvo de pensionista el poeta Chapelle, amigo de Moliere, La Fontaine y Boileau. Despu\u00e9s de la muerte de Vicente, encontramos nobles, como el hermano del Cardenal Estr\u00e9es, dos caballeros de Haye-Montbault, Enrique-Luis de Lomenie, conde de Friesne, que estuvo 18 a\u00f1os. Tambi\u00e9n pol\u00edticos, como Caron de Beau\u00admarchais, el caballero de Grieux, del que nos ha\u00adbla Pr\u00e9vost. Entre los eclesi\u00e1sticos, estuvieron el abb\u00e9 Longu\u00e9 y el abb\u00e9 Blanch, junto con el su\u00adperior general de la Orden del Esp\u00edritu Santo.<\/p>\n<p style=\"text-align: justify\">Los relatos que algunos de ellos escribieron, contando su estancia en S. L\u00e1zaro, pecan de par\u00adcialidad por exagerados elogios o reproches. Cier\u00adtamente, hubo en siglo XVII coplas populares en las que se ridiculizaba a los lazaristas guardianes, pero tambi\u00e9n hay informes de los inspectores de prisiones en los que se coloca al correccional de S. L\u00e1zaro entre las casas modelo, mucho mejor que otros establecimientos de este g\u00e9nero que hab\u00eda en Par\u00eds.<\/p>\n<h3 style=\"text-align: justify\"><strong>2. El cuidado y el servicio a los dementes<\/strong><\/h3>\n<p style=\"text-align: justify\">El m\u00e9dico antes citado, Werner Leibrand, es\u00adcrib\u00eda: \u00abEstarnos cansados de saber que fue Pi\u00adnel, en el siglo XVIII, quien libert\u00f3 a los locos de sus cadenas\u2026, pero fue en realidad san Vicente el gran psiqu\u00edatra de su siglo, y en el cuidado de los locos, tienen una gran participaci\u00f3n los reli\u00adgiosos de la Misi\u00f3n\u00bb (pg. 158).<\/p>\n<p style=\"text-align: justify\">Vicente, antes de llegar a S. L\u00e1zaro, ya habla intervenido en varios casos de psic\u00f3patas, don\u00adde pone en pr\u00e1ctica su amor y su ciencia.<\/p>\n<p style=\"text-align: justify\">Conocemos, hacia 1610, el caso de Co\u00e9ffe\u00adtean, el doctor capell\u00e1n de la corte de la reina Margot, al que Vicente le receta reposo y no ejer\u00adcicios piadosos (XI, 725-26).<\/p>\n<p style=\"text-align: justify\">En 1618, intervino en la enfermedad de Mar\u00eda Ang\u00e9lica de Atri. Caso que califica no de posesi\u00f3n, a la que haya que darle los exorcismos, sino de debilitamiento mental por humores melanc\u00f3licos y a la que recomienda <em>\u00abestar con su t\u00eda y que \u00e9s\u00adta la lleve a tomar el aire de los campos\u00bb, <\/em>en lu\u00adgar del trato con Saint-Cyran, que la empujaba de una manera obsesiva a la vida religiosa (I, 431. 473-75).<\/p>\n<p style=\"text-align: justify\">Entre 1622-23, Vicente conoce a la salesa Ma\u00adr\u00eda Amaury, perturbada mental con tendencia al sacrilegio. Vicente ha visto el tratamiento m\u00e9di\u00adco que se le ha aplicado, pero \u00e9l cree en la cura\u00adci\u00f3n milagrosa que se ha producido (X, 79-80).<\/p>\n<p style=\"text-align: justify\">En el consejo del 25 de octubre de 1646, que tiene con las Hijas de la Caridad, se plantea el ca\u00adso de una muchacha de Angers, que estuvo en la Compa\u00f1\u00eda, tuvo que salir <em>\u00abpor una grave en\u00adfermedad, que le dej\u00f3 la imaginaci\u00f3n herida\u00bb y <\/em>ahora quiere volver. Vicente es claro partidario de no readmitirla, siguiendo su experiencia de que las readmisiones nunca resultan; pero, ante las ob\u00adservaciones que hace el P. Portail y sobre todo Luisa, que juzga la salida por causa solamente de la enfermedad y la enfermedad <em>\u00abpor haberse de\u00addicado a la oraci\u00f3n con m\u00e1s intensidad de lo que sus fuerzas le permit\u00edan\u00bb, <\/em>forzada sin duda por un padre que la dirig\u00eda, Vicente cambia de opini\u00f3n y acepta su vuelta (X, 754-758).<\/p>\n<p style=\"text-align: justify\">Abelly nos trae parte de una conferencia, en la que Vicente nos describe el caso de un sacer\u00addote, pensionista de S. L\u00e1zaro, \u00abque ca\u00eda en fre\u00adcuentes delirios, fruto del exceso de humor de melancol\u00eda que le hace perder el dominio de su voluntad, perdiendo el juicio y la libertad\u00bb. Vicente diagnostica que en estos casos el enfermo no tiene en s\u00ed suficientes fuerzas para detener el ac\u00adceso, y pide a la comunidad, oraciones y compa\u00adsi\u00f3n (XI, 714-715).<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s de estas acertadas actuaciones per\u00adsonales, Vicente organiz\u00f3 y fue siempre el res\u00adponsable \u00faltimo del Correccional de S. L\u00e1zaro. Coloc\u00f3 a un grupo de Padres y Hermanos, cuya actuaci\u00f3n nos describe Abelly: \u00abHay un grupo de hermanos que cuidan de sus exigencias f\u00edsicas y sacerdotes para la atenci\u00f3n del alma. Los unos se ocupan de la alimentaci\u00f3n y otras cosas mate\u00adriales; los otros consuelan y animan a los enfer\u00admos para que cambien moralmente y se des\u00adprendan de sus culpas, prepar\u00e1ndose a seguir una vida sana y virtuosa\u00bb (Abelly, II, 306).<\/p>\n<p style=\"text-align: justify\">Tambi\u00e9n en 1657, las Hijas de la Caridad par\u00adticipar\u00e1n en esta tarea de cuidar a los locos, cuan\u00addo el Ayuntamiento, al comprar la antigua lepro\u00adser\u00eda de S. Germ\u00e1n, levante el hospital de las Pe\u00adtites-Maisons, destinado a los dementes.<\/p>\n<p style=\"text-align: justify\">Vicente trat\u00f3 de transmitir a estos servidores de los pensionistas, padres y hermanos, toda su visi\u00f3n evang\u00e9lica, para que fueran capaces de ejercer un amor afectivo en ellos. Esta tarea de cuidar a los locos es el medio que la Providencia ha puesto en sus manos. Tarea vicenciana que les permite y les posibilita para seguir a Jesucristo, evangelizador de los pobres, siendo solidarios del sufrimiento, principal instrumento de amor y de evangelizaci\u00f3n cristiana ( XI, 716 ). Pero no tra\u00adt\u00f3 s\u00f3lo de comunicarles el amor afectivo, base y fundamento de toda evangelizaci\u00f3n, sino tam\u2011<br \/>\nbi\u00e9n de capacitarles y exigirles el amor efectivo.<\/p>\n<p style=\"text-align: justify\">Les exige primero justicia y respeto para el pensionista: No deben admitir nunca un pensio\u00adnista con la \u00fanica finalidad de librar a la familia y a la sociedad de un estorbo. Exige el juicio y la determinaci\u00f3n de los magistrados para el ingre\u00adso en la casa; no basta el capricho de la familia como sucedi\u00f3 con el joven Demourard, hijo de un tesorero de Lyon, que por no querer ser sacer\u00addote fue ingresado en S. L\u00e1zaro por orden de su hermano. Vicente se disgust\u00f3, se opuso y final\u00admente logr\u00f3 reconciliar a los dos hermanos. Si el pensionista es aceptado, el deber de justicia les tiene que llevar a un servicio que sea el cumpli\u00admiento de lo estipulado en la pensi\u00f3n \u00abya <em>que no est\u00e1n en situaci\u00f3n de pod\u00e9roslo exigir y por otra parte los que podr\u00edan exig\u00edroslo no ven lo que hac\u00e9is\u00bb (XI, <\/em>225).<\/p>\n<p style=\"text-align: justify\">Les exige capacitaci\u00f3n. En la biblioteca de S. L\u00e1zaro, no s\u00f3lo hay teolog\u00eda y sermones; all\u00ed, po\u00addemos encontrar las obras antiguas de medicina de Hip\u00f3crates y Galeno, y las recientes de Juan Basilio, Campanella, Sylvio, Teruel, Fallopio, Lau\u00adrens, Lamart\u2026<\/p>\n<p style=\"text-align: justify\">Guy Patin es un m\u00e9dico, que vive cerca de S. L\u00e1zaro, y al que Vicente trata y consulta. Estos ser\u00advidores deben conocer los remedios de la \u00e9poca, determinar el diagn\u00f3stico no s\u00f3lo con una visi\u00f3n religiosa sino cient\u00edfica y racional.<\/p>\n<p style=\"text-align: justify\">El evangelio de Vicente es el Evangelio de Je\u00adsucristo: Buena Noticia para los hombres de la tie\u00adrra. Jesucristo es el Hijo de Dios y el Hijo del Hombre, Salvador de almas y de cuerpos, de hombres.<\/p>\n<p style=\"text-align: justify\">La solidaridad vicenciana con estos enfermos del alma debe llevarles a realizar ante Dios las funciones del alma de estos enfermos incapaci\u00adtados para ellas, pero tambi\u00e9n a trabajar para que desaparezcan las causas de esta incapacidad.<\/p>\n<h2 style=\"text-align: justify\"><strong>BIBLIOGRAF\u00cdA:<\/strong><\/h2>\n<p style=\"text-align: justify\">L. BIZARD-CHAPOLA, Histoire de la prison de Saint Lazare du Moyen-Age \u00e1 nos jours. Paris, de Boc\u00adcard, 1925.- F. BLUCHE, Dictionnaire du Grand Si\u00e9\u00adcle. Par\u00eds: Fayard, 1990. Art\u00edculos: Assistance, Folie, H\u00f3pital-General, Humeurs.- Dr. W. LEIBRAND, Vicente de Pa\u00fal, el Santo de la Medicina (Taduc\u00adci\u00f3n del alem\u00e1n por Margarita Gonz\u00e1lez). Madrid, 1944.- J. L. PEsET, Medicina y Sociedad en la Fran\u00adcia del Barroco.- J. MELOT, Les Pensionnaires de Saint Lazare, en Mission et Chant\u00e9, 1964, 49-55.- J. vi \u00c9, Les alienes et les correctionnaires \u00e1 Saint\u00adLazare au XVIIe et au Malle si\u00e9cles. Paris, Alean, 1930.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I. Los dementes en el siglo XVII en Francia Para comprender y valorar la evangelizaci\u00f3n vicenciana con los dementes, conviene recordar que hasta la \u00faltima parte del siglo XVIII, con Pi\u00adnel (1745-1826), no hubo en &#8230; <a href=\"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":388395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[218,127,143],"class_list":["post-35823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","tag-abelly","tag-portail","tag-san-lazaro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espiritualidad vicenciana: Dementes - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espiritualidad vicenciana: Dementes - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"I. Los dementes en el siglo XVII en Francia Para comprender y valorar la evangelizaci\u00f3n vicenciana con los dementes, conviene recordar que hasta la \u00faltima parte del siglo XVIII, con Pi\u00adnel (1745-1826), no hubo en ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-28T06:35:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Espiritualidad vicenciana: Dementes\",\"datePublished\":\"2014-06-28T06:35:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/\"},\"wordCount\":3137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Abelly\",\"Portail\",\"San L\u00e1zaro\"],\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/\",\"name\":\"Espiritualidad vicenciana: Dementes - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2014-06-28T06:35:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/espiritualidad-vicenciana-dementes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espiritualidad vicenciana: Dementes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espiritualidad vicenciana: Dementes - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/","og_locale":"es_ES","og_type":"article","og_title":"Espiritualidad vicenciana: Dementes - Somos Vicencianos","og_description":"I. Los dementes en el siglo XVII en Francia Para comprender y valorar la evangelizaci\u00f3n vicenciana con los dementes, conviene recordar que hasta la \u00faltima parte del siglo XVIII, con Pi\u00adnel (1745-1826), no hubo en ... Read More","og_url":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2014-06-28T06:35:07+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Espiritualidad vicenciana: Dementes","datePublished":"2014-06-28T06:35:07+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/"},"wordCount":3137,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1","keywords":["Abelly","Portail","San L\u00e1zaro"],"articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/","url":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/","name":"Espiritualidad vicenciana: Dementes - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1","datePublished":"2014-06-28T06:35:07+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-dementes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Espiritualidad vicenciana: Dementes"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-9jN","jetpack-related-posts":[{"id":130374,"url":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-18\/","url_meta":{"origin":35823,"position":0},"title":"Un perfil heroico: santa Luisa de Marillac (18)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/03\/2015","format":false,"excerpt":"Soy un gusano, y no un hombre; el oprobio de los hombres y el desecho de la plebe. (Salmo 21.) El 29 de septiembre de 1655, en una reuni\u00f3n familiar con las Hijas de la Caridad, San Vicente, en uni\u00f3n con la se\u00f1orita Legras, les hablaba de las gracias que\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":21509,"url":"https:\/\/vincentians.com\/es\/al-servicio-de-los-dementes\/","url_meta":{"origin":35823,"position":1},"title":"Al Servicio de los dementes","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/09\/2018","format":false,"excerpt":"En su prefacio para la traducci\u00f3n inglesa de la biograf\u00eda del Sr. Vicente por Abelly, el P. Stafford Poole, a pesar de algunas reservas, dice que ese trabajo es para nosotros fundamental, \u00fanico e indispensable, la \u00fanica fuente importante. Gracias a Abelly sabemos lo que el Sr. Vicente hizo en\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/04\/vicente-y-eucaristia.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/04\/vicente-y-eucaristia.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/04\/vicente-y-eucaristia.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/04\/vicente-y-eucaristia.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/04\/vicente-y-eucaristia.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":127445,"url":"https:\/\/vincentians.com\/es\/la-afliccion-de-los-locos-i\/","url_meta":{"origin":35823,"position":2},"title":"La aflicci\u00f3n de los locos (I)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/06\/2024","format":false,"excerpt":"\"S\u00ed, hermanas m\u00edas, es Dios mismo quien ha querido servirse de las hijas de la caridad para cuidar a estos pobres enajenados. \u00a1Oh!, vos\u00adotras todas. Pero qu\u00e9 gran favor es para aque\u00adllas que se dedican a ello el tener un medio tan bueno de servir a Dios y a Nuestro\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/n-1.jpg?fit=823%2C564&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/n-1.jpg?fit=823%2C564&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/n-1.jpg?fit=823%2C564&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/n-1.jpg?fit=823%2C564&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":109299,"url":"https:\/\/vincentians.com\/es\/aspectos-del-siglo-xvii-frances-i\/","url_meta":{"origin":35823,"position":3},"title":"Aspectos del siglo XVII franc\u00e9s (I)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/08\/2019","format":false,"excerpt":"A la hora de presentar este trabajo quiero dejar constancia de los m\u00f3viles que me han guiado a llevarlo a cabo: un deseo de aportar conoci\u00admientos fuera del alcance de muchos miembros de la familia vicenciana, y sobre todo estimular a estos miembros a que la lectura de estas l\u00edneas\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/revolucion-francesa.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/revolucion-francesa.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/revolucion-francesa.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/revolucion-francesa.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/revolucion-francesa.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":149456,"url":"https:\/\/vincentians.com\/es\/las-corrientes-espirituales-del-siglo-xvii-frances\/","url_meta":{"origin":35823,"position":4},"title":"Las corrientes espirituales del siglo XVII franc\u00e9s","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/05\/2015","format":false,"excerpt":"I- El contexto espiritual general: de San Agust\u00edn a la Ilustraci\u00f3n Introducci\u00f3n Se trata de presentar el mundo espiritual en el que Juan Bautista De La Salle ha vivido, aclarar sus actitudes y sus opciones, con el fin de comprender mejor lo que nos dice, en particular lo que se\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"clero_siglo_xvii","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/02\/clero_siglo_xvii-300x280.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":116979,"url":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-y-renovacion-conciliar\/","url_meta":{"origin":35823,"position":5},"title":"Espiritualidad vicenciana y renovaci\u00f3n conciliar","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/03\/2015","format":false,"excerpt":"En la Iglesia posconciliar se necesita un estudio s\u00f3lido y diverso de la espiritualidad cristiana b\u00e1sica y de las \"espiritualidades\" que han aplicado la Espiritualidad evang\u00e9lica a distintas situa\u00adciones hist\u00f3ricas y a familias religiosas y apost\u00f3licas, para reali\u00adzar la \"adecuada renovaci\u00f3n\" de estas espiritualidades a la au\u00adt\u00e9ntica espiritualidad Cristoc\u00e9ntrica y\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"concilio1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/concilio1-300x113.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=35823"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/388395"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=35823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=35823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=35823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}