{"id":35367,"date":"2011-09-26T03:45:23","date_gmt":"2011-09-26T01:45:23","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/09\/novena-a-san-vicente-de-paul-dia-octavo\/"},"modified":"2016-07-26T17:23:38","modified_gmt":"2016-07-26T15:23:38","slug":"novena-a-san-vicente-de-paul-dia-octavo","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/","title":{"rendered":"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo"},"content":{"rendered":"<h3><strong><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/03\/San-Vicente-8.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-32314\" title=\"San Vicente (8)\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/03\/San-Vicente-8-202x300.jpg?resize=202%2C300\" alt=\"\" width=\"202\" height=\"300\" \/><\/a><\/strong><\/h3>\n<h2>Sobre la necesidad de soportar a los dem\u00e1s<\/h2>\n<h3><strong>Oraci\u00f3n preparatoria.<\/strong><\/h3>\n<p><strong> <\/strong>Dios todopoderoso y eterno, que llenaste de caridad el coraz\u00f3n de san Vicente de Pa\u00fal, escucha nuestra oraci\u00f3n y danos tu amor. A ejemplo suyo, haznos descubrir y servir a Jesucristo, tu Hijo, en nuestros hermanos pobres y desdichados. Que en su escuela aprendamos a amarte a Ti con el sudor de nuestro rostro y la fuerza de nuestros brazos. Por sus oraciones, libra nuestras almas del odio y del ego\u00edsmo; haz que todos recordemos que un d\u00eda seremos juzgados sobre el amor. Oh Dios, que quieres la salvaci\u00f3n de todos, danos los sacerdotes, las religiosas y los ap\u00f3stoles seglares que tanto necesitamos. Que sean entre nosotros los primeros testigos de tu amor. Virgen de los pobres y Reina de la Paz, obt\u00e9n para nuestro mundo dividido y angustiado, el amor y la paz. AS\u00cd SEA.<\/p>\n<h3>Reflexi\u00f3n del d\u00eda 8\u00ba.<\/h3>\n<p>Despu\u00e9s de haber hablado varios de la compa\u00f1\u00eda, el padre Vicente concluy\u00f3 diciendo que hab\u00eda quedado muy edificado por lo que acababan de decir los que hab\u00edan hablado sobre este tema. Se ha dicho muy bien que esta paciencia es en una congregaci\u00f3n algo as\u00ed como los nervios en el cuerpo humano.<\/p>\n<p>En efecto, donde no se soportan los individuos de una casa o de una comunidad, \u00bfverdad que s\u00f3lo se aprecia un gran desorden?. Nuestro Se\u00f1or supo soportar a san Pedro, a pesar de haber cometido aquel pecado tan infame de renegar de su Maestro. Y a san Pablo, \u00bfno lo soport\u00f3 tambi\u00e9n nuestro Se\u00f1or? \u00bfSe encontrar\u00e1 en alguna parte a un hombre que sea perfecto y sin defecto alguno, y al que no tengan que soportar los dem\u00e1s? \u00bfSe encontrar\u00e1 en alguna parte alg\u00fan superior que carezca de defectos, y al que nunca tengan necesidad de soportar sus s\u00fabditos? \u00a1Ojal\u00e1 hubiera alguno! Pero me atrever\u00e9 a decir m\u00e1s: el hombre est\u00e1 hecho de tal manera que muchas veces no tiene m\u00e1s remedio que soportarse a s\u00ed mismo, ya que es cierto que esta virtud de saber soportar es necesaria a todos los hombres, incluso para ejercerla con uno mismo, a quien a veces cuesta tanto soportar.<\/p>\n<p>\u00bfEn qu\u00e9 hemos de soportar a nuestros hermanos? En todas las cosas: soportar su mal humor, su manera de obrar, de actuar, etc., que no nos gusta, que nos desagrada. Hay personas de tan mal car\u00e1cter que todo les disgusta y que no pueden soportar la m\u00e1s m\u00ednima cosa que vaya en contra de su humor o de su capricho.<\/p>\n<p>El bienaventurado obispo de Ginebra dec\u00eda que le hab\u00eda sido m\u00e1s f\u00e1cil sujetarse a la voluntad de cien personas que sujetar a una sola de ellas a la propia voluntad. (Cf. Op. cit., nn. 552-554).<\/p>\n<h3>Oraci\u00f3n final.<\/h3>\n<p>Salvador nuestro: \u00bfte veremos practicar la mansedumbre tan incomparablemente con los criminales, sin hacernos mansos nosotros? \u00bfNo nos sentiremos impresionados por los ejemplos y ense\u00f1anzas que encontramos en tu escuela?<\/p>\n<p>Cordero de Dios, que quitas el pecado del mundo, haznos en esto semejantes a ti. Am\u00e9n.<\/p>\n<p><strong>Gozos.<br \/>\n<\/strong> <strong><\/strong><\/p>\n<p style=\"text-align: center\"><strong> HIMNO A SAN VICENTE<\/strong><\/p>\n<p style=\"text-align: center\">(Melod\u00eda del \u00abQuis novus caelis\u00bb)<\/p>\n<p style=\"text-align: center\">\u00bfQu\u00e9 nuevo triunfo cantan hoy, los cielos?<br \/>\n\u00bfQu\u00e9 nuevo aplauso los santos tributan?<br \/>\n\u00a1La luz del Clero, el Padre de los Pobres<br \/>\nbrilla en la Gloria!<\/p>\n<p style=\"text-align: center\"><em>Ay\u00fadanos, San Vicente,<\/em><br \/>\n<em> a renovarnos en el Evangelio.<\/em><\/p>\n<p style=\"text-align: center\">Obras ingentes loan tus proezas<br \/>\ny el Amor ci\u00f1e de laurel tu frente;<br \/>\ncuanto le diste al Pobre con largueza<br \/>\nte vuelve el Cielo.<\/p>\n<p style=\"text-align: center\"><em>Ay\u00fadanos, San Vicente,<\/em><br \/>\n<em> a renovarnos en el Evangelio.<\/em><\/p>\n<p style=\"text-align: center\">Los sacerdotes, siendo t\u00fa su Gu\u00eda,<br \/>\nllevan al Pobre la verdad de Cristo:<br \/>\nla madre Iglesia vive y canoniza<br \/>\ntu Magisterio.<\/p>\n<p style=\"text-align: center\"><em>Ay\u00fadanos, San Vicente,<\/em><br \/>\n<em> a renovarnos en el Evangelio.<\/em><\/p>\n<p style=\"text-align: center\">Pero te honran de manera insigne<br \/>\nv\u00edrgenes castas que, a la vez, son Madres:<br \/>\nlos Pobres gozan, bajo tu mirada,<br \/>\nde su ternura.<\/p>\n<p style=\"text-align: center\"><em>Ay\u00fadanos, San Vicente,<\/em><br \/>\n<em> a renovarnos en el Evangelio.<\/em><\/p>\n<p style=\"text-align: center\">Como aliviaste el dolor del m\u00edsero,<br \/>\noye hoy, benigno, el clamor del Pueblo:<br \/>\ntodos los pobres, juntos te proclaman<br \/>\nPadre y Amigo.<\/p>\n<p style=\"text-align: center\"><em>Ay\u00fadanos, San Vicente,<\/em><br \/>\n<em> a renovarnos en el Evangelio.<\/em><\/p>\n<p style=\"text-align: center\">Demos hoy, todos, gloria al Padre Eterno<br \/>\ny al Hijo Ungido Salvador del hombre<br \/>\ny al Amor mismo, Llama de Dios vivo<br \/>\nque arde en Vicente. Am\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sobre la necesidad de soportar a los dem\u00e1s Oraci\u00f3n preparatoria. Dios todopoderoso y eterno, que llenaste de caridad el coraz\u00f3n de san Vicente de Pa\u00fal, escucha nuestra oraci\u00f3n y danos tu amor. A ejemplo suyo, &#8230; <a href=\"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":32314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[205,5],"tags":[],"class_list":["post-35367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oracion","category-vicente-de-paul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novena a san Vicente de Pa\u00fal: D\u00eda Octavo - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Sobre la necesidad de soportar a los dem\u00e1s Oraci\u00f3n preparatoria. Dios todopoderoso y eterno, que llenaste de caridad el coraz\u00f3n de san Vicente de Pa\u00fal, escucha nuestra oraci\u00f3n y danos tu amor. A ejemplo suyo, ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-26T01:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T15:23:38+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo\",\"datePublished\":\"2011-09-26T01:45:23+00:00\",\"dateModified\":\"2016-07-26T15:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/\"},\"wordCount\":750,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Oraci\u00f3n\",\"Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/\",\"name\":\"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2011-09-26T01:45:23+00:00\",\"dateModified\":\"2016-07-26T15:23:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/novena-a-san-vicente-de-paul-dia-octavo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/","og_locale":"es_ES","og_type":"article","og_title":"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo - Somos Vicencianos","og_description":"Sobre la necesidad de soportar a los dem\u00e1s Oraci\u00f3n preparatoria. Dios todopoderoso y eterno, que llenaste de caridad el coraz\u00f3n de san Vicente de Pa\u00fal, escucha nuestra oraci\u00f3n y danos tu amor. A ejemplo suyo, ... Read More","og_url":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2011-09-26T01:45:23+00:00","article_modified_time":"2016-07-26T15:23:38+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo","datePublished":"2011-09-26T01:45:23+00:00","dateModified":"2016-07-26T15:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/"},"wordCount":750,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#primaryimage"},"thumbnailUrl":"","articleSection":["Oraci\u00f3n","Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/","url":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/","name":"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2011-09-26T01:45:23+00:00","dateModified":"2016-07-26T15:23:38+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/novena-a-san-vicente-de-paul-dia-octavo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Novena a san Vicente de Pa\u00fal: D\u00eda Octavo"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-9cr","jetpack-related-posts":[{"id":129151,"url":"https:\/\/vincentians.com\/es\/vida-contemplativa\/","url_meta":{"origin":35367,"position":0},"title":"Vida contemplativa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"02\/03\/2014","format":false,"excerpt":"Aunque parezca extra\u00f1o, la exorbitante actividad de Luisa no destruy\u00f3 su experiencia de Dios, al contrario, la complet\u00f3. Luisa aparece en la historia de la espiritualidad como una de las mujeres m\u00e1s contemplativas; tan contemplativa como San Pablo, Santa Teresa o San Vicente de Pa\u00fal y tan activa como ellos.\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"cartel","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/01\/cartel.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":120300,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-la-fe-que-dio-sentido-a-su-vida-iv-amemos-a-dios-hermanos-mios-amemos-a-dios\/","url_meta":{"origin":35367,"position":1},"title":"Vicente de Pa\u00fal: la fe que dio sentido a su vida. IV. \u00a1Amemos a Dios, hermanos m\u00edos, amemos a Dios!","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/01\/2015","format":false,"excerpt":"IV. \u00a1Amemos a Dios, hermanos m\u00edos, amemos a Dios! El descubrimiento de la bondad de Dios no deja a Vi\u00adcente maravillado e inactivo; est\u00e1 en el origen de un dina\u00admismo asombroso que da impulso a toda su vida. Vi\u00e9ndole recomendar la disponibilidad para con la divina Providen\u00adcia, podr\u00edan imaginarse algunos\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"Vincent-de-Paul-and-bible-alternate","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/Vincent-de-Paul-and-bible-alternate-216x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":114809,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0994-luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":35367,"position":2},"title":"Vicente de Pa\u00fal, Carta 0994: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/11\/2012","format":false,"excerpt":"[Junio 1647] Padre: Si quisiera su caridad proponerle al due\u00f1o de la casa pr\u00f3xima a San Lorenzo que se alojase en los locales que tiene arrendados al cervecero, con la debida indemnizaci\u00f3n que la har\u00edan las damas, podr\u00edamos acomodar bien las cosas para los ni\u00f1os. No tengo m\u00e1s remedio que\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":387803,"url":"https:\/\/vincentians.com\/es\/jesus-ora-al-padre-movido-por-el-espiritu\/","url_meta":{"origin":35367,"position":3},"title":"Jes\u00fas ora al Padre, movido por el Esp\u00edritu","author":"Mitxel Olabu\u00e9naga","date":"08\/09\/2016","format":false,"excerpt":"Jes\u00fas de Nazaret es un trabajador fiel que hace de su vida oraci\u00f3n, y de la oraci\u00f3n compromiso de salvaci\u00f3n para los hombres. Trabajo y oraci\u00f3n se funden indisolublemente en su persona. Es inconcebible un Jes\u00fas que no ora expresamente al Padre y que no ense\u00f1a a sus disc\u00edpulos a\u2026","rel":"","context":"En \u00abOraci\u00f3n\u00bb","block_context":{"text":"Oraci\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/oracion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":103887,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0975-julian-guerin-sacerdote-de-la-mision-a-san-vicente\/","url_meta":{"origin":35367,"position":4},"title":"Vicente de Pa\u00fal, Carta 0975: Julian Guerin, Sacerdote De La Misi\u00f3n, A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"22\/09\/2012","format":false,"excerpt":"[T\u00fanez, entre 1645 y mayo de 1648] Se sentir\u00eda usted entusiasmado al escuchar, los domingos y d\u00edas de fiesta, cantar en nuestras iglesias y capillas el Exaudiat y las dem\u00e1s oraciones por el rey de Francia, por el que los mismos extranjeros demuestran mucho respeto y afecto; as\u00ed como tambi\u00e9n\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119354,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1118-luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":35367,"position":5},"title":"Vicente de Pa\u00fal, Carta 1118: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/04\/2013","format":false,"excerpt":"[Octubre 1648] Padre. No me acuerdo muy bien del asunto de que le escrib\u00eda el se\u00f1or p\u00e1rroco de Serqueux, pero me parece que se trataba de algo de las religiosas de cerca de Forges, a las que se acusa de una gran falta, por la que me parece que le\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=35367"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35367\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=35367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=35367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=35367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}