{"id":29258,"date":"2015-03-15T02:03:49","date_gmt":"2015-03-15T01:03:49","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=29258"},"modified":"2016-07-26T17:27:17","modified_gmt":"2016-07-26T15:27:17","slug":"oracion-a-santa-luisa-de-marillac","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/","title":{"rendered":"Oraci\u00f3n a santa Luisa de Marillac"},"content":{"rendered":"<p>Oh, Santa Luisa de Marillac; vos sois, la hija del Dios de la vida y aquella sierva humilde que lo amasteis de tal manera que quisisteis vuestro amor dejar en las \u00abVicentinas\u00bb, Hijas de la Caridad reflejado.<\/p>\n<p>San Vicente sus normas redact\u00f3, y os dej\u00f3 por los tiempos, vuestra forma de vivir: \u00ab<em>Por Monasterio, tendr\u00e1n las casas de los enfermos. Por habitaci\u00f3n una pieza arrendada. Por claustro tendr\u00e1n las calles donde hay pobres que socorrer. Su l\u00edmite de acci\u00f3n ser\u00e1 la obediencia. Puerta y muro de defensa ser\u00e1 el temor de ofender a Dios. El velo protector ser\u00e1 la modestia o castidad<\/em>\u00ab.<\/p>\n<p>As\u00ed, hasta hoy en vos, siguen vuestros pasos, las hijas vuestras que, en cuerpo y alma, a las obras de la caridad y del apostolado se dedican. Vuestra tarea inmensa cumplida, volasteis al cielo, para coronada ser de luz eterna.<\/p>\n<p>De los Asistentes Sociales Patrona Santa; oh, Santa Luisa de Marillac, \u00abluz\u00bb.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/02\/USA-IN-Indianapolis.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-141524\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/02\/USA-IN-Indianapolis-594x1024.jpg?resize=594%2C1024\" alt=\"Louise de Marillac with book\" width=\"594\" height=\"1024\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oh, Santa Luisa de Marillac; vos sois, la hija del Dios de la vida y aquella sierva humilde que lo amasteis de tal manera que quisisteis vuestro amor dejar en las \u00abVicentinas\u00bb, Hijas de la &#8230; <a href=\"https:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":141524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18,205],"tags":[],"class_list":["post-29258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luisa-de-marillac","category-oracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oraci\u00f3n a santa Luisa de Marillac - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oraci\u00f3n a santa Luisa de Marillac - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Oh, Santa Luisa de Marillac; vos sois, la hija del Dios de la vida y aquella sierva humilde que lo amasteis de tal manera que quisisteis vuestro amor dejar en las \u00abVicentinas\u00bb, Hijas de la ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-15T01:03:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T15:27:17+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Oraci\u00f3n a santa Luisa de Marillac\",\"datePublished\":\"2015-03-15T01:03:49+00:00\",\"dateModified\":\"2016-07-26T15:27:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/\"},\"wordCount\":166,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Luisa de Marillac\",\"Oraci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/\",\"name\":\"Oraci\u00f3n a santa Luisa de Marillac - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-15T01:03:49+00:00\",\"dateModified\":\"2016-07-26T15:27:17+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/oracion-a-santa-luisa-de-marillac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oraci\u00f3n a santa Luisa de Marillac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oraci\u00f3n a santa Luisa de Marillac - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/","og_locale":"es_ES","og_type":"article","og_title":"Oraci\u00f3n a santa Luisa de Marillac - Somos Vicencianos","og_description":"Oh, Santa Luisa de Marillac; vos sois, la hija del Dios de la vida y aquella sierva humilde que lo amasteis de tal manera que quisisteis vuestro amor dejar en las \u00abVicentinas\u00bb, Hijas de la ... Read More","og_url":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-15T01:03:49+00:00","article_modified_time":"2016-07-26T15:27:17+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Oraci\u00f3n a santa Luisa de Marillac","datePublished":"2015-03-15T01:03:49+00:00","dateModified":"2016-07-26T15:27:17+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/"},"wordCount":166,"commentCount":1,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#primaryimage"},"thumbnailUrl":"","articleSection":["Luisa de Marillac","Oraci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/","url":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/","name":"Oraci\u00f3n a santa Luisa de Marillac - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-15T01:03:49+00:00","dateModified":"2016-07-26T15:27:17+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/oracion-a-santa-luisa-de-marillac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Oraci\u00f3n a santa Luisa de Marillac"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-7BU","jetpack-related-posts":[{"id":101771,"url":"https:\/\/vincentians.com\/es\/orando-con-luisa-de-marillac\/","url_meta":{"origin":29258,"position":0},"title":"Orando con Luisa de Marillac","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/04\/2015","format":false,"excerpt":"Las primeras Hijas de la Caridad quedaron impresiona\u00addos por la actitud orante de Luisa de Marillac. En las conferencias celebradas sobre las virtudes de la Srta. Le Gras, varias Hermanas pusieron de relieve su pro\u00adfunda uni\u00f3n con Dios: \"Siempre ten\u00eda su esp\u00edritu ocupado en Dios.\" \"Ten\u00eda mucha vida Interior y\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/09\/rostros_luisa_09-225x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":144824,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-mujer-discipula-colaboradora-formadora-fundadora-madre\/","url_meta":{"origin":29258,"position":1},"title":"Luisa de Marillac: Mujer, disc\u00edpula, colaboradora, formadora, fundadora, madre","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/05\/2015","format":false,"excerpt":"Introducci\u00f3n En julio de 1660 san Vicente de Pa\u00fal, en una conferencia a las Hermanas sobre las virtudes de la Se\u00f1orita Le Gras afirma convencido: \u201cSi desean ser buenas Hijas de la Caridad, est\u00e1n obligadas a fijarse en sus virtudes.\u201d[1]. \u201c\u2026 Ser buenas Hijas de la Caridad\u201d es la decisi\u00f3n\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"Louise 112","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/Louise-112-297x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130448,"url":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-21-y-ultimo\/","url_meta":{"origin":29258,"position":2},"title":"Un perfil heroico: santa Luisa de Marillac (21 y \u00faltimo)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"15\/03\/2015","format":false,"excerpt":"DADLE el fruto de sus manos, y al\u00e1benla sus obras 3 las puertas de la Ciudad Santa. (Prov., 31.) En esto hemos conocido el amor\u2014dice al Ap\u00f3stol San Juan\u2014, el es, que Cristo ha dado su vida por nosotros, y nosotros del mos darla por nuestros hermanos... No amemos, pues,\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":101790,"url":"https:\/\/vincentians.com\/es\/honrar-al-verbo-encarnado\/","url_meta":{"origin":29258,"position":3},"title":"Honrar al Verbo encarnado","author":"Francisco Javier Fern\u00e1ndez Chento","date":"15\/04\/2016","format":false,"excerpt":"En sus meditaciones, Luisa de Marillac se detiene con mayor frecuencia en el misterio de la Encarnaci\u00f3n y se ex\u00adtas\u00eda en ese Amor inmenso de Dios hecho hombre por amor al hombre. \"Tan pronto como nuestro primer padre hubo peca\u00addo, la bondad de Dios, apiad\u00e1ndose de la naturaleza humana, prometi\u00f3\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"rostros_luisa_09-768x1024","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2012\/08\/rostros_luisa_09-768x1024-225x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":114809,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0994-luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":29258,"position":4},"title":"Vicente de Pa\u00fal, Carta 0994: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/11\/2012","format":false,"excerpt":"[Junio 1647] Padre: Si quisiera su caridad proponerle al due\u00f1o de la casa pr\u00f3xima a San Lorenzo que se alojase en los locales que tiene arrendados al cervecero, con la debida indemnizaci\u00f3n que la har\u00edan las damas, podr\u00edamos acomodar bien las cosas para los ni\u00f1os. No tengo m\u00e1s remedio que\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":130444,"url":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-19\/","url_meta":{"origin":29258,"position":5},"title":"Un perfil heroico: santa Luisa de Marillac (19)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/03\/2015","format":false,"excerpt":"Y pondr\u00e9 mi esp\u00edritu en vosotros, y har\u00e9 que guard\u00e9is mis preceptos. Y vosotros ser\u00e9is el pueblo m\u00edo, y yo ser\u00e9 vuestro Dios. (Ezequiel, XXXVI.) VICENTE de Pa\u00fal, cuyo coraz\u00f3n se regocijaba santamente al contemplar las bellas disposiciones de esp\u00edritu de las Hijas de la Caridad, y los frutos copiosos\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/29258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=29258"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/29258\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=29258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=29258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=29258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}