{"id":28945,"date":"2013-11-22T08:53:04","date_gmt":"2013-11-22T07:53:04","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/28945\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/"},"modified":"2016-07-26T17:29:09","modified_gmt":"2016-07-26T15:29:09","slug":"la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/","title":{"rendered":"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830"},"content":{"rendered":"<h2><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2009\/11\/Guatemala-casa-madre_JPG1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-27264\" title=\"Guatemala-casa-madre_JPG\" alt=\"\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2009\/11\/Guatemala-casa-madre_JPG1-300x225.jpg?resize=300%2C225\" width=\"300\" height=\"225\" \/><\/a>4.\u00a0Las apariciones de 1830<\/h2>\n<p>No poseemos edici\u00f3n cr\u00edtica de los diversos testimonios sobre la aparici\u00f3n y sobre la medalla: todo ha sido envuel\u00adto enseguida por el silencio.<\/p>\n<p>El confesor de Catalina recibi\u00f3 sus confidencias. Al prin\u00adcipio no las acept\u00f3. Los hechos fueron as\u00ed: el 30 de junio de 1832 las primeras medallas que se ajustaban al modelo descrito por la vidente salen del taller del orfebre, M. Va\u00adchette; en 1835, un artista, M. Lecerf, pinta la visi\u00f3n del coraz\u00f3n de san Vicente de Pa\u00fal y la de la Virgen de las ma\u00adnos llenas de rayos luminosos (cuadros que se conservan en el seminario de las Hijas de la Caridad). En 1836 se abre un sumario can\u00f3nico sobre los hechos de la calle Bac por orden del Arzobispo de Par\u00eds.<\/p>\n<p>En 1841 solamente parece que el P. Aladel, confesor de Catalina, le pide una relaci\u00f3n escrita de su pu\u00f1o y letra para confirmar y corregir el relato que \u00e9l mismo hab\u00eda publicado en su carta del 17 de Marzo de 1834 y en la <em>Notice historique <\/em><em>sur l&#8217;origine et les effets de la Nouvelle M\u00e9daille&#8230; g\u00e9n\u00e9rale\u00ad<\/em><em>ment connue sous le nom de M\u00e9daille Miraculeuse- <\/em>En 1841 pues, Sor Catalina escribe tres relaciones algo diferentes: conciernen a la aparici\u00f3n del 27 de noviembre m\u00e1s especial\u00admente consagrada a la Medalla. La de la noche del 18 al 19 de julio que preparaba a la vidente a su visi\u00f3n ser\u00e1 evocada en escritos posteriores a la petici\u00f3n del P. Aladel (1856) y del P. Chevalier, redactor de la \u00faltima edici\u00f3n de la <em>Notice sur la m\u00e9daille, <\/em>y confidente de sor Catalina en los \u00faltimos meses de su vida (1876).<\/p>\n<p>Esperando una edici\u00f3n cr\u00edtica (que creo publicar\u00e1 el padre Laurentin) publicamos las fuentes escritas del re\u00adlato tradicional, cuyo sentido simb\u00f3lico explicaremos en\u00adseguida.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Noche del 18 al 19 de julio<\/em><\/p>\n<p>Sor Catalina es entonces novicia en el seminario de la calle del Bac. Su directora, en la v\u00edspera de la fiesta de san Vicente, da una instrucci\u00f3n a las j\u00f3venes hermanas sobre la devoci\u00f3n a los santos, en particular sobre la devoci\u00f3n a la <em>Virgen \u00ablo que me ha dado un deseo de ver a la Sant\u00edsima Virgen\u00bb <\/em>confiesa Catalina, que prosigue as\u00ed su relato:<\/p>\n<p><em>&#8230;Me dorm\u00ed con el pensamiento de que san Vicente me <\/em><em>alcanzar\u00eda la gracia de ver a la Virgen. En fin, a las once y <\/em><em>media de la noche sent\u00ed que me llamaban por mi nombre: <\/em><em>Sor, Sor, Sor&#8230;. Me despert\u00e9. Mir\u00e9 al lado del pasillo, apart\u00e9 <\/em><em>la cortina, vi a un ni\u00f1o, vestido de blanco, de cuatro a cinco <\/em><em>a\u00f1os aproximadamente, que me dijo: \u00ablev\u00e1ntese pronto y venga a la capilla, la Sant\u00edsima Virgen le espera\u00bb. Pronto <\/em><em>me asalt\u00f3 la idea de que me iban a oir. El ni\u00f1o me respondi\u00f3: \u00abest\u00e9se tranquila, son las once y media, todos duermen pro\u00adfundamente, venga, yo la espero\u00bb. Me vest\u00ed, r\u00e1pidamente y me acerqu\u00e9 al ni\u00f1o que se hab\u00eda quedado de pie sin moverse de la cabecera de mi cama. Me sigui\u00f3, o m\u00e1s bien lo segu\u00ed,<\/em> <em>siempre a mi izquierda, iluminaba con un gran resplandor los <\/em><em>sitios por donde pasaba; las luces estaban encendidas por <\/em><em>todos los lugares por donde pas\u00e1bamos, cosa que me extra\u00ad\u00f1aba mucho, pero a\u00fan me sorprend\u00ed m\u00e1s al entrar en la ca\u00ad<\/em><em>pilla, la puerta se abri\u00f3 apenas tocarla el ni\u00f1o con la punta <\/em><em>de los dedos; pero m\u00e1s aument\u00f3 mi sorpresa cuando v\u00ed los <\/em><em>cirios y las velas encendidas, lo que me record\u00f3 la misa del <\/em><em>Gallo. Sin embargo yo no ve\u00eda a la Virgen. El ni\u00f1o me condujo <\/em><em>por el santuario a lado del sill\u00f3n del P. Director, y all\u00ed me puse de rodillas; el ni\u00f1o permaneci\u00f3 en pie todo el tiempo.<\/em><\/p>\n<p><em>Como el tiempo se me hac\u00eda largo, miraba por si pasaban l<\/em><em>as vigilantas por la tribuna&#8230; Al fin, lleg\u00f3 la hora, el ni\u00f1o me avis\u00f3, me dijo: \u00abHe ah\u00ed a la Virgen, hela ah\u00ed&#8230;\u00bb. O\u00ed como un ruido, como el rumor de un vestido de seda, que ven\u00eda del lado del p\u00falpito, al lado del cuadro de san Jos\u00e9, que ven\u00eda a posarse sobre los escalones del altar del lado del Evangelio, en un sill\u00f3n parecido al de santa Ana. La Virgen s\u00f3lo se diferenciaba de santa Ana en la cara. Dudaba si era la Virgen. Sin embargo el ni\u00f1o me dijo: \u00abHe ah\u00ed a la Virgen\u00bb. Me ser\u00eda imposible decir lo que yo experiment\u00e9 en aquel momento, lo que pas\u00f3 en mi interior, me parec\u00eda que no ve\u00eda a la Virgen&#8230;, fue en\u00adtonces cuando el ni\u00f1o me habl\u00f3, no ya como un ni\u00f1o, sino como un hombre, como el m\u00e1s fuerte, con las palabras m\u00e1s fuertes. Entonces, mirando a la Virgen me limit\u00e9 a dar un paso de rodillas sobre los escalones del altar, apoyando las manos sobre las rodillas de la Virgen&#8230;<\/em><\/p>\n<p><em>All\u00ed, transcurri\u00f3 un momento, el m\u00e1s dulce de mi vida; <\/em><em>me parece imposible decir todo lo que experiment\u00e9. Ella me dijo c\u00f3mo deb\u00eda conducirme con respecto a mi director y a <\/em><em>muchas cosas que no debo decir, la manera de conducirme en mis penas, me mand\u00f3 venir, mostr\u00e1ndome con la mano <\/em><em>izquierda el pie del altar, de arrojarme al pie del altar, expan<\/em><em>sionar mi coraz<\/em><em>\u00f3<\/em><em>n; all<\/em><em>\u00ed<\/em><em> recibir<\/em><em>\u00ed<\/em><em>a todos los consuelos que nece\u00ad<\/em><em>sitara&#8230; All<\/em><em>\u00ed<\/em><em> le ped<\/em><em>\u00ed<\/em><em> que me explicara lo que significaban todas las cosas que hab<\/em><em>\u00ed<\/em><em>a visto y ella me lo explic<\/em><em>\u00f3<\/em><em> todo. Permanec<\/em><em>\u00ed<\/em><em> <\/em><em>all<\/em><em>\u00ed<\/em><em> no s<\/em><em>\u00e9<\/em><em> cu<\/em><em>\u00e1<\/em><em>nto tiempo; todo lo que s<\/em><em>\u00e9<\/em><em> es que cuando ella se <\/em><em>fue s<\/em><em>\u00f3<\/em><em>lo percib<\/em><em>\u00ed<\/em><em> algo que se apagaba, como una sombra que caminaba al lado de la tribuna por el mismo sitio por el que <\/em><em>hab<\/em><em>\u00ed<\/em><em>a llagado.<\/em><\/p>\n<p><em>Me levant<\/em><em>\u00e9<\/em><em> de los pelda<\/em><em>\u00f1<\/em><em>os del altar y vi al ni<\/em><em>\u00f1<\/em><em>o donde lo hab<\/em><em>\u00ed<\/em><em>a dejado, me dijo: Ella se ha ido&#8230; Volvimos a tomar el <\/em><em>mismo camino, siempre iluminado, y el ni<\/em><em>\u00f1<\/em><em>o iba siempre a <\/em><em>mi izquierda. Creo que este ni<\/em><em>\u00f1<\/em><em>o era mi <\/em><em>\u00e1<\/em><em>ngel de la guarda, <\/em><em>que se hab<\/em><em>\u00ed<\/em><em>a hecho visible para hacerme ver a la Virgen, por\u00adque le hab<\/em><em>\u00ed<\/em><em>a rezado mucho para que me alcanzara este favor. <\/em><em>Estaba vestido de blanco, llevaba una luz milagrosa con <\/em><em>\u00e9<\/em><em>l, <\/em><em>es decir, iba resplandeciente de luz, y era de una edad de <\/em><em>4 a 5 a<\/em><em>\u00f1<\/em><em>os.<\/em><\/p>\n<p><em>Cuando volv<\/em><em>\u00ed<\/em><em> a la cama eran las dos de la noche, o<\/em><em>\u00ed<\/em><em> c<\/em><em>\u00f3<\/em><em>mo el reloj daba la hora. No me volv<\/em><em>\u00ed<\/em><em> a dormir.<\/em><em> <\/em><\/p>\n<p>Conversaci\u00f3n de la Virgen desde el 18, a las 11 y media de la noche hasta la una y media de la noche del 19, d\u00eda de san Vicente.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Hija m<\/em><em>\u00ed<\/em><em>a, el buen Dios, te quiere encomendar una misi<\/em><em>\u00f3<\/em><em>n. <\/em><em>Sufrir<\/em><em>\u00e1<\/em><em>s mucho pero podr<\/em><em>\u00e1<\/em><em>s soportarlo, podr<\/em><em>\u00e1<\/em><em>s sobrellevar estas <\/em><em>penas, pensando que lo haces por la gloria de Dios. Conocer<\/em><em>\u00e1<\/em><em>s secretos divinos, y te ver<\/em><em>\u00e1<\/em><em>s atormentada por ello hasta que <\/em><em>se lo digas al que est<\/em><em>\u00e1<\/em><em> encargado de dirigirte. Te contradecir<\/em><em>\u00e1<\/em><em>n, <\/em><em>pero contar<\/em><em>\u00e1<\/em><em>s con la gracia, no temas. Di todo, con confianza, <\/em><em>lo que pasa en ti, dilo con simplicidad, ten confianza, no temas. <\/em><em>Ver<\/em><em>\u00e1<\/em><em>s ciertas cosas, presta atenci<\/em><em>\u00f3<\/em><em>n a lo que veas y oigas. <\/em><em>Ser<\/em><em>\u00e1<\/em><em>s inspirada en tus oraciones. Ten en cuenta lo que te digo<\/em><em> <\/em><em>lo que ver\u00e1s en tus oraciones. Los tiempos son malos, las des\u00ad<\/em><em>gracias se cernir\u00e1n sobre Francia, el trono ser\u00e1 derribado, <\/em><em>el mundo entero se ver\u00e1 amenazado por desgracias de todas clases (la Virgen ten\u00eda cara de pena al decir todo esto) pero <\/em><em>acercaos al pie de este altar, aqu\u00ed las gracias ser\u00e1n concedidas <\/em><em>particularmente a las personas que las pidan.<\/em><\/p>\n<p><em>Hija m\u00eda, me gusta derramar las gracias sobre la comuni\u00addad en particular, la quiero mucho. Estoy apenada, hay mu\u00adchos abusos respecto a las reglas, no se observan. Gran rela\u00adjamiento en las dos comunidades. D\u00edgale al que est\u00e1 encargado de vosotras, aunque no sea superior, se haga cargo de una manera especial de la comunidad, debe hacer todo lo posible para que la regla recupere su vigor. Dile de mi parte que vi\u00adgile las malas lecturas, las p\u00e9rdidas de tiempo y las visitas.<\/em><\/p>\n<p><em>Cuando la regla sea puesta en vigor habr\u00e1 una comunidad que vendr\u00e1 a reunirse a la comunidad, no es as\u00ed la costumbre, pero yo lo quiero. Dile que las reciba; Dios las bendecir\u00e1 y gozar\u00e1n de una gran paz.<\/em><\/p>\n<p><em>La comunidad gozar\u00e1 de una gran paz, crecer\u00e1.<\/em><\/p>\n<p><em>Pero vendr\u00e1n grandes calamidades, el peligro ser\u00e1 grande, <\/em><em>pero no tem\u00e1is, diles que no teman. La protecci\u00f3n de Dios <\/em><em>est\u00e1 siempre con vosotras de una manera muy especial y san Vicente las proteger\u00e1 (la Virgen estaba siempre triste), pero yo misma estar\u00e9 con vosotras, tengo siempre mi mirada sobre vosotras, yo les otorgar\u00e9 muchas gracias&#8230;<\/em><\/p>\n<p><em>Llegar\u00e1 el momento en que el peligro ser\u00e1 grande, se creer\u00e1 <\/em><em>que todo est\u00e1 perdido, estar\u00e9 entonces con vosotras, tened <\/em><em>confianza. Os dar\u00e9is cuenta de que os he visitado, reconocer\u00e9is laprotecci\u00f3n de Dios a la comunidad y la de san Vicente so\u00adbre las dos comunidades.<\/em><\/p>\n<p><em>Tened confianza, no es desanim\u00e9is, yo estar\u00e9 con vosotras.<\/em><\/p>\n<p><em>Pero no suceder\u00e1 lo mismo en las otras comunidades, habr\u00e1 <\/em><em>v\u00edctimas (la Virgen ten\u00eda l\u00e1grimas en los ojos al decir esto). <\/em><em>Entre el clero de Par\u00eds habr\u00e1 v\u00edctimas, el se\u00f1or arzobispo <\/em><em>(con estas palabras le afloraron de nuevo las l\u00e1grimas).<\/em><\/p>\n<p><em>Hija m\u00eda, la cruz ser\u00e1 despreciada, se la tirar\u00e1 por tierra, <\/em><em>la sangre correr\u00e1, se abrir\u00e1 de nuevo el costado de Nuestro <\/em><em>Se\u00f1or, las calles estar\u00e1n llenas de sangre. El se\u00f1or arzobispo <\/em><em>ser\u00e1 despojado de sus vestiduras (Aqu\u00ed la Virgen no pod\u00eda <\/em><em>hablar ya, la pena hab\u00eda inundado su rostro). Hija m\u00eda, me de\u00adc\u00eda, el inundo entero se hundir\u00e1 en la tristeza. Al o\u00edr estas pa\u00adlabras yo pensaba \u00bfcu\u00e1ndo suceder\u00e1 esto?&#8230; Comprend\u00ed que a los cuarenta a\u00f1os. Con respecto a esto, el P. Aladel me repli\u00adc\u00f3: \u00bfSabe si usted y yo estaremos all\u00ed? Yo le respond\u00ed: otros estar\u00e1n si nosotros no lo estamos.<\/em><\/p>\n<p>En esta \u00e9poca la capilla s\u00f3lo ten\u00eda una nave, sin naves laterales. Hacia el medio, adosados a la pared, dos altares: el de la Virgen a la derecha y en frente de \u00e9l el de san Vi\u00adcente. El presbiterio estaba al mismo nivel. La pared del fondo, un poco ahuecada, estaba provista de tres cuadros, el del medio representaba el coraz\u00f3n de Jes\u00fas adorado por dos \u00e1ngeles. Delante, a la derecha, un cuadro de san Jos\u00e9; a la izquierda, el de santa Ana. La sacrist\u00eda estaba detr\u00e1s. El altar mayor de entonces existe a\u00fan hoy: est\u00e1 situado bajo la imagen de san Vicente.<\/p>\n<p>Estos detalles me han sido facilitados para situar los acontecimientos relatados por Catalina. El del 18 al 19 de julio tuvo por escenario el presbiterio de la capilla. Ella va a exponer ahora c\u00f3mo ocurri\u00f3 la aparici\u00f3n del 27 de noviembre.<\/p>\n<p>J. M. J.<\/p>\n<p><em>El 27 de noviembre de 1830, s\u00e1bado anterior al primer <\/em><em>domingo de Adviento, a las cinco <\/em>y <em>media de la tarde, despu\u00e9s <\/em><em>del punto de meditaci\u00f3n, en medio de un gran silencio, es decir, <\/em><em>algunos minutos despu\u00e9s de meditaci\u00f3n, me ha parecido o\u00edr <\/em><em>un ruido al lado del p\u00falpito, junto al cuadro de san Jos\u00e9, como el roce de un vestido de seda. Mir\u00e9 hacia ese lado y vi a la Vir\u00ad<\/em><em>gen a la altura del cuadro de san Jos\u00e9. La Virgen estaba de <\/em><em>pie, vestida de blanco, con un vestido de seda blanco y res\u00ad<\/em><em>plandeciente, el distintivo de la Virgen, mangas lisas, un velo <\/em><em>blanco que descend\u00eda hasta el suelo, bajo el velo asomaba su <\/em><em>pelo, melena lisa, y encima llevaba un encaje de tres cent\u00ed\u00ad<\/em><em>metros de altura, sin pliegues, es decir, apoyado ligeramente sobre sus cabellos; la cara al descubierto, los pies sobre una b<\/em><em>ola, es decir, media bola o al menos s\u00f3lo me pareci\u00f3 que <\/em><em>media; sosten\u00eda en sus manos una bola que representaba la <\/em><em>esfera terrestre, sus manos estaban elevadas a la altura de la cintura, y sus ojos miraban al cielo.<\/em><\/p>\n<p><em>Su cara resplandec\u00eda de belleza, soy incapaz de descri\u00adbirla&#8230; Luego, de pronto, descubr\u00ed unos anillos en sus dedos <\/em><em>en los que iban engastados piedras preciosas, unas m\u00e1s bellas <\/em><em>que otras, unas m\u00e1s grandes y otras m\u00e1s peque\u00f1as, que despe\u00add\u00edan destellos unos m\u00e1s bellos que otros. Los destellos sal\u00edan de las piedras, de entre los grandes destellos los mayores se ensanchaban constantemente y de entre los peque\u00f1os los me\u00adnores se extend\u00edan hacia abajo inundando el suelo de forma que yo no pod\u00eda ver sus pies. En este momento en que la con\u00adtemplaba, la Virgen baj\u00f3 sus ojos y me mir\u00f3. Se dej\u00f3 o\u00edr una voz que trajo hasta m\u00ed estas palabras: La bola que ves repre\u00adsenta al mundo entero, especialmente a Francia&#8230; y a cada persona en particular&#8230; No s\u00e9 expresar ahora lo que experiment\u00e9 y lo que vi: la belleza y el esplendor, los rayos tan bo\u00adnitos&#8230; Simbolizan las gracias que reparto entre las personas que me piden. Me hizo comprender qu\u00e9 agradable era rezarle a la Virgen, cu\u00e1nta generosidad derrochaba hacia las perso\u00adnas que le rezaban&#8230; cu\u00e1ntas gracias concede a las personas que se las piden, qu\u00e9 alegr\u00eda siente el concederlas&#8230; Entonces me parec\u00eda existir y no existir&#8230; yo gozaba, yo no s\u00e9&#8230; <\/em><\/p>\n<p><em>Un cuadro, algo ovalado, se form\u00f3 alrededor de la Virgen, en lo alto del cuadro hab\u00eda escritas estas palabras: <\/em>O Marie concue s.p.p.n.q.av. a vous <em>\u2014escritas en letras de oro\u2014. Entonces se dej\u00f3 o\u00edr una voz que me dijo: Haga, haga acu\u00f1ar <\/em><em>una medalla con este modelo; todas las personas que la lleven recibir\u00e1n grandes gracias al llevarla al cuello, las gracias ser\u00e1n abundantes para las personas que la lleven con con\u00adfianza&#8230; <\/em><\/p>\n<p><em> De pronto, me pareci\u00f3 que el cuadro se daba la vuelta y vi <\/em><em>entonces el reverso de la Medalla. Inquieta por saber lo que <\/em><em>hab\u00eda que poner en el reverso de la medalla, despu\u00e9s de mu\u00adchas oraciones, un d\u00eda en la meditaci\u00f3n, me ha parecido o\u00edr <\/em><em>una voz que me dec\u00eda: La M y los dos corazones ya expresan bastante&#8230; Ahora despu\u00e9s de dos a\u00f1os, <\/em>escribe Catalina al padre Aladel, <em>me siento atormentada y apremiada a decirle que se <\/em><em>eleve un altar, tal como os lo he pedido, en lugar en que se <\/em><em>apareci\u00f3 la Virgen; ser\u00e1 privilegiado y gozar\u00e1 de muchas <\/em><em>gracias e indulgencias. Le traer\u00e1 una abundancia de gracias <\/em><em>a usted y a toda la comunidad y a todas las personas que ven\u00ad<\/em><em>gan a rezar.<\/em><\/p>\n<p>Estos son los \u00fanicos documentos escritos de los que dis\u00adponemos. Un estudio cr\u00edtico permitir\u00e1 fecharlos con exac\u00adtitud. Pero tal estudio no har\u00e1 aparecer nada que no est\u00e9 ya en las relaciones de la vidente al P. Aladel, constituyen su \u00abevangelio\u00bb. Y aunque muy corto, es suficiente.<\/p>\n<p>La continuaci\u00f3n de la historia de Catalina es conocida: ella es el reverso de la historia, la abolici\u00f3n de la historia. \u00bfHab\u00eda adivinado Catalina que lo dif\u00edcil, lo peligroso, lo casi insoportable para un \u00abevidente\u00bb es sobrevivir a la vi\u00adsi\u00f3n? Ella se sumi\u00f3 en el anonimato absoluto, y no se sali\u00f3 de \u00e9l. Se dice incluso (y no es imposible) que una especie de gracia, como una amnesia, a veces la ayud\u00f3. \u00abYo he sido s\u00f3lo un instrumento, afirma. Yo no sab\u00eda nada, incluso ni escribir. Por eso es por lo que la Virgen me ha elegido\u00bb.<\/p>\n<p>Mientras que la medalla se extend\u00eda (10 millones en cua\u00adtro a\u00f1os se acu\u00f1a en Francia y fuera de Francia: en B\u00e9lgica, en Suiza, en Italia e incluso en Londres), mientras que el pueblo le asignaba el nombre de \u00abmilagrosa\u00bb por los prodi\u00adgios que realizaba, Catalina era verdaderamente inencontra\u00adble. Se sab\u00eda que viv\u00eda en alguna parte, que era \u00abHija de la Caridad\u00bb \u2014y las curiosas hijas deb\u00edan con frecuencia mi\u00adrarse unas a otras insistentemente o preguntar para saber qui\u00e9n era Catalina\u2014. Se mostraba tan inalterable, tan tran\u00adquila, con un aspecto tan indiferente y tan banal cuando delante de ella se hablaba de la hermana desconocida, que nadie la pudo desenmascarar abiertamente. S\u00f3lo hab\u00eda cier\u00adtas suposiciones sin pruebas. Ni el arzobispo de Par\u00eds que hab\u00eda autorizado la acu\u00f1aci\u00f3n de la medalla, ni los indaga\u00addores de 1836 pudieron lograr levantar el inc\u00f3gnito. Tuvie\u00adron el acierto de no exigirlo. Catalina permaneci\u00f3 desapercibida: verdadera \u00abnovela polic\u00edaca\u00bb de tipo m\u00edstico, que dur\u00f3 hasta su muerte, el 31 de diciembre de 1876.<\/p>\n<p>Viv\u00eda en el hospicio de Enghien en Reuilly. Su superiora, la madre Duf\u00e9s, que estuvo con ella seis a\u00f1os, no la recono\u00adci\u00f3. Como ocurre frecuentemente en las comunidades re\u00adligiosas, fue severa, y a veces muy injusta, con sor Catalina.<\/p>\n<p>El P. Aladel hab\u00eda muerto en 1865. Catalina se confesaba con el P. Chinchon, pero \u00e9ste fue reemplazado en 1876; el superior general crey\u00f3 que no deb\u00eda autorizarle a continuar escuchando a Catalina; design\u00f3 a otro Pa\u00fal como confesor de la casa de Enghien. Ocasion\u00f3 gran pena a Catalina que \u00abno quer\u00eda presentarse ante la Virgen sin haber hecho cum\u00adplir su voluntad\u00bb.<\/p>\n<p>Decidi\u00f3 confiarse a sor Duf\u00e9s, y as\u00ed lo hizo en el locuto\u00adrio del hospicio. Entrevista de dos horas en que ni la una ni la otra se preocuparon por sentarse. Catalina revel\u00f3 a su superiora su identidad. \u00a1Estos cuarenta a\u00f1os de silencio!<\/p>\n<p>Todos \u00ablos ruegos de la Madre de Dios\u00bb, declar\u00f3 Cata\u00adlina, hab\u00edan sido satisfechos, excepto uno, que hab\u00eda per\u00admanecido en suspenso. Y \u00abesto constitu\u00eda el martirio de mi vida\u00bb, a\u00f1ad\u00eda.<\/p>\n<p>Recordar\u00e1n las dos fases de la aparici\u00f3n del 27 de no\u00adviembre: en la primera la Virgen sosten\u00eda en sus manos una bola rematada con una cruz de oro. La bola simboliza la esfera terrestre. Mar\u00eda quer\u00eda mostrar con ello, he dicho, cu\u00e1n querida le es \u00abla tierra\u00bb, que lleva a todos los habitan\u00adtes en su coraz\u00f3n, ofreci\u00e9ndoselos al Padre.<\/p>\n<p>El deseo de Mar\u00eda era que un altar y una estatua conme\u00admorasen este gesto de ofrenda de la tierra al Padre. Sor Cata\u00adlina, sinti\u00e9ndose morir, se hab\u00eda atrevido a hablar. \u00abLa Virgen del Globo\u00bb y su altar no ser\u00e1n autorizados hasta Le\u00f3n XIII.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>4.\u00a0Las apariciones de 1830 No poseemos edici\u00f3n cr\u00edtica de los diversos testimonios sobre la aparici\u00f3n y sobre la medalla: todo ha sido envuel\u00adto enseguida por el silencio. El confesor de Catalina recibi\u00f3 sus confidencias. Al &#8230; <a href=\"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":27264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20,8],"tags":[190],"class_list":["post-28945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-catalina-laboure","category-virgen-maria","tag-rue-du-bac"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"4.\u00a0Las apariciones de 1830 No poseemos edici\u00f3n cr\u00edtica de los diversos testimonios sobre la aparici\u00f3n y sobre la medalla: todo ha sido envuel\u00adto enseguida por el silencio. El confesor de Catalina recibi\u00f3 sus confidencias. Al ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-22T07:53:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T15:29:09+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830\",\"datePublished\":\"2013-11-22T07:53:04+00:00\",\"dateModified\":\"2016-07-26T15:29:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/\"},\"wordCount\":3211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Rue du Bac\"],\"articleSection\":[\"Catalina Labour\u00e9\",\"Virgen Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/\",\"name\":\"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2013-11-22T07:53:04+00:00\",\"dateModified\":\"2016-07-26T15:29:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/","og_locale":"es_ES","og_type":"article","og_title":"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830 - Somos Vicencianos","og_description":"4.\u00a0Las apariciones de 1830 No poseemos edici\u00f3n cr\u00edtica de los diversos testimonios sobre la aparici\u00f3n y sobre la medalla: todo ha sido envuel\u00adto enseguida por el silencio. El confesor de Catalina recibi\u00f3 sus confidencias. Al ... Read More","og_url":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2013-11-22T07:53:04+00:00","article_modified_time":"2016-07-26T15:29:09+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830","datePublished":"2013-11-22T07:53:04+00:00","dateModified":"2016-07-26T15:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/"},"wordCount":3211,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#primaryimage"},"thumbnailUrl":"","keywords":["Rue du Bac"],"articleSection":["Catalina Labour\u00e9","Virgen Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/","url":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/","name":"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#primaryimage"},"thumbnailUrl":"","datePublished":"2013-11-22T07:53:04+00:00","dateModified":"2016-07-26T15:29:09+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/la-supersticion-superada-rue-du-bac-4-las-apariciones-de-1830\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"La superstici\u00f3n superada. Rue du Bac. 4. Las apariciones de 1830"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-7wR","jetpack-related-posts":[{"id":53281,"url":"https:\/\/vincentians.com\/es\/el-mensaje-de-rue-du-bac-iii-la-aparicion-se-repitio-muchas-veces\/","url_meta":{"origin":28945,"position":0},"title":"El mensaje de Rue du Bac (III. La aparici\u00f3n se repiti\u00f3 muchas veces)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/11\/2023","format":false,"excerpt":"Todos cuantos han escrito sobre la Medalla o sobre la vida de Santa Catalina Labour\u00e9 coinciden en afirmar que la aparici\u00f3n de la Virgen de los Rayos y tambi\u00e9n de la Virgen del Globo, ya que es la misma en fases distintas, se repiti\u00f3 varias veces. Pero, \u00bfcu\u00e1ntas? Joseph Dirvin,\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2022\/08\/imagen-1-2.jpg?fit=350%2C349&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2522,"url":"https:\/\/vincentians.com\/es\/una-relectura-del-mensaje-de-la-rue-du-bac-para-nuestro-tiempo\/","url_meta":{"origin":28945,"position":1},"title":"Una relectura del mensaje de la Rue du Bac para nuestro tiempo","author":"Francisco Javier Fern\u00e1ndez Chento","date":"23\/12\/2023","format":false,"excerpt":"Introducci\u00f3n No es \u00e9sta la primera vez que se pide a alguien tratar este tema. \u00bfC\u00f3mo actualizar el mensaje de la Rue du Bac?. La preocupaci\u00f3n por este enfoque surgi\u00f3 especialmente a partir de la celebraci\u00f3n del 150 aniversario de las apariciones de la Virgen a Santa Catalina y desde\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/La-milagrosa3.jpg?fit=670%2C430&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/La-milagrosa3.jpg?fit=670%2C430&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/La-milagrosa3.jpg?fit=670%2C430&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":53272,"url":"https:\/\/vincentians.com\/es\/el-mensaje-de-rue-du-bac-introduccion\/","url_meta":{"origin":28945,"position":2},"title":"El mensaje de Rue du Bac (Introducci\u00f3n)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/10\/2023","format":false,"excerpt":"Es dif\u00edcil precisar el significado y mensaje de las apariciones de la Virgen Mar\u00eda a Santa Catalina Labour\u00e9. Aunque fueron las primeras de todas las mariofan\u00edas modernas no han tenido a\u00fan ni un historiador ni un te\u00f3logo que las haya estudiado en profun\u00addidad. Cierto que las biograf\u00edas de la vidente\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2022\/08\/imagen-1-2.jpg?fit=350%2C349&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":53279,"url":"https:\/\/vincentians.com\/es\/el-mensaje-de-rue-du-bac-ii-carta-del-p-aladel-al-abate-le-guillou\/","url_meta":{"origin":28945,"position":3},"title":"El mensaje de Rue du Bac (II. Carta del P. Aladel al Abate Le Guillou)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/11\/2023","format":false,"excerpt":"Par\u00eds, 17 de marzo de 1834. \"... Hacia finales del a\u00f1o 1830, Sor N..., novicia en una Co\u00admunidad de Par\u00eds consagrada al servicio de los pobres, hab\u00eda cre\u00eddo ver, durante la oraci\u00f3n, como en un cuadro, a la Sant\u00ed\u00adsima Virgen, tal como se la representa de ordinario bajo el t\u00ed\u00adtulo\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2022\/08\/imagen-1-2.jpg?fit=350%2C349&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8198,"url":"https:\/\/vincentians.com\/es\/los-incorruptos-de-paris\/","url_meta":{"origin":28945,"position":4},"title":"Los incorruptos de Par\u00eds","author":"Francisco Javier Fern\u00e1ndez Chento","date":"30\/10\/2017","format":false,"excerpt":"Cuando uno viaja a Par\u00eds, lo hace pensando en la subida a una torre de v\u00e9rtigo, a 320 metros del suelo. El turista piensa en bonitos paseos por las Tuller\u00edas, inolvidables rutas en bateau mouche por el Sena o en aut\u00e9nticos recorridos por el museo Louvre, dignos del m\u00e1s puro\u2026","rel":"","context":"En \u00abCatalina Labour\u00e9\u00bb","block_context":{"text":"Catalina Labour\u00e9","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/catalina-laboure\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37523,"url":"https:\/\/vincentians.com\/es\/apariciones-de-la-virgen-maria-a-sor-catalina-laboure\/","url_meta":{"origin":28945,"position":5},"title":"Apariciones de la Virgen Mar\u00eda a sor Catalina Labour\u00e9","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/11\/2013","format":false,"excerpt":"Apariciones de la Virgen Mar\u00eda. \"La Virgen de la Medalla Milagrosa\" La Virgen Mar\u00eda se aparece en 1830 a una joven postulante a noviciado en el convento de la Rue de Bac, iniciando una era de apariciones que permiten catalogar a los tiempos desde all\u00ed en adelante como una verdadera\u2026","rel":"","context":"En \u00abCatalina Labour\u00e9\u00bb","block_context":{"text":"Catalina Labour\u00e9","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/catalina-laboure\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/05\/medalla_milagrosa-269x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/28945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=28945"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/28945\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=28945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=28945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=28945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}