{"id":28340,"date":"2011-02-06T02:00:29","date_gmt":"2011-02-06T01:00:29","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/28340\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/"},"modified":"2016-07-26T11:08:09","modified_gmt":"2016-07-26T09:08:09","slug":"luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/","title":{"rendered":"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre"},"content":{"rendered":"<p>Sierva de los Pobres Enfermos<\/p>\n<p>Nantes<\/p>\n<p>(10 de julio de 1647)<\/p>\n<p>Mi querida Hermana:<\/p>\n<p>Ayer recibimos noticias de que Sor Isabel<span id='easy-footnote-1-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-1-28340' title='Sor Isabel Mart\u00edn, (ver C. 27 n. 1).'><sup>1<\/sup><\/a><\/span> ha ido a Angers, y el se\u00f1or Vicente me ha ordenado le diga que permanezca all\u00ed hasta que reciba \u00f3rdenes nuestras; por eso, querida Hermana, no tendr\u00e1 usted m\u00e1s que despachar pronto el otro asunto<span id='easy-footnote-2-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-2-28340' title='Habla de hacer marchar a Sor Catalina Bagard, una de las responsables de  que se hubieran formado partidos o bander\u00edas en la comunidad'><sup>2<\/sup><\/a><\/span> cuando el se\u00f1or Lamberto llegue a Nantes. Puede usted proponerle para que acompa\u00f1e a la otra<span id='easy-footnote-3-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-3-28340' title='Catalina Bagard (ver C. 84, n. 4).'><sup>3<\/sup><\/a><\/span> a Sor Enriqueta<span id='easy-footnote-4-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-4-28340' title='Enriqueta Gesseaume (ver C. 86, n. 1).'><sup>4<\/sup><\/a><\/span> o a Sor Claudia,<span id='easy-footnote-5-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-5-28340' title='Claudia Carr\u00e9 (ver C. 561 n. 5).'><sup>5<\/sup><\/a><\/span> y en caso de que no le parezca bien servirse de la una o la otra, proponga, por favor, al se\u00f1or Lamberto si no ser\u00eda conveniente llamar a Nantes para ello a Sor Turgis, rog\u00e1ndole lo haga inmediatamente, dici\u00e9ndole que es el se\u00f1or Vicente quien ordena hacerle esta proposici\u00f3n; pero que, por favor, no se marche de Nantes mientras esa Hermana no haya salido de ah\u00ed por lo menos dos d\u00edas antes que \u00e9l y que de ning\u00fan modo pase ella por Angers.<\/p>\n<p>\u00a1Dios m\u00edo, querida Hermana! \u00a1Cu\u00e1nta necesidad tiene usted de su gracia para llevar a cabo lo que Dios le ha encomendado! Pero no haga nada sin el parecer del se\u00f1or Lamberto y del se\u00f1or de Joncheres,<span id='easy-footnote-6-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-6-28340' title='Se\u00f1or de Joncheres, consejero de las Hermanas (ver C. 161, n. 3).'><sup>6<\/sup><\/a><\/span> y fuera de ellos, no se comunique con nadie, a no ser con la buena se\u00f1orita de la Carisiere<span id='easy-footnote-7-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-7-28340' title='Se\u00f1ora de Nantes'><sup>7<\/sup><\/a><\/span> para explicarle que tanto el se\u00f1or Lamberto como usted no har\u00edan nada sino por orden del se\u00f1or Vicente, a quien de ning\u00fan modo se atrever\u00edan a desobedecer, y que indudablemente, si ella contribuye a que los Padres acepten y aprueben el traslado que ustedes se ven obligados a hacer, tiene usted la seguridad de que Dios otorgar\u00e1 nuevas bendiciones a esa santa obra y a sus trabajos.<\/p>\n<p>Aqu\u00ed tiene unas p\u00edldoras que le mando para ella y la receta para hacerlas; si le parece que puede usted necesitarlas, qu\u00e9dese con algunas, pero ya sabe que el mejor uso que se puede hacer de las medicinas es servirse raras veces de ellas. Diga usted a esa buena se\u00f1orita el bien que hacen y que sirven para verse libre de la gran sujeci\u00f3n a que la reducen todos los d\u00edas sus enfermedades.<\/p>\n<p>Asegure a todas nuestras Hermanas, en general y a cada una en particular el afecto que les tengo y d\u00edgales que todas esas revueltas y murmuraciones me hacen esperar un gran bien cuando sea del agrado de la bondad de Dios hacerlas cesar: lo ordinario en el diablo es oponerse siempre a las mejores acciones. Les recomiendo el servicio a los enfermos rog\u00e1ndoles pongan en \u00e9l mucho esmero; me han dicho que hace poco se hab\u00eda muerto una muchacha sin asistencia<span id='easy-footnote-8-28340' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#easy-footnote-bottom-8-28340' title='Una carta de Sor Margarita de Noret a la se\u00f1orita, con fecha 18 de marzo, le comunica tal incidente (Ver Anales 1979, 477-478).'><sup>8<\/sup><\/a><\/span> y que hab\u00eda ocurrido as\u00ed porque varias de las Hermanas estaban por la ciudad; si es verdad, mucho me sorprende porque no tienen que salir. Dios m\u00edo, Hermanas, \u00a1cu\u00e1ntos motivos tenemos para humillarnos al ver que somos objeto de las habladur\u00edas y desprecio de todos los habitantes de Nantes, que nos hab\u00edan llamado para remediar los des\u00f3rdenes en la casa de Dios, y nosotras la profanamos en tal grado en la opini\u00f3n de los hombres; todo ello por apego a nuestra propia satisfacci\u00f3n y gusto! Yo quisiera poder hacer penitencia, y le aseguro que siempre que oigo a la gente hablar bien de nuestra Compa\u00f1\u00eda, me sonrojo de verg\u00fcenza al pensar en el desorden de Nantes. Suplico a la bondad de Dios ponga el remedio que a su bondad le parezca necesario y soy en su sant\u00edsimo amor, querida Hermana, su muy humilde servidora v afect\u00edsima hermana<\/p>\n<p>P.D. No diga que he escrito a Sor Isabel que no regrese en seguida. Haga saber a las Hermanas que la gente de Nantes murmura de ellas m\u00e1s de lo que se pueden imaginar y por cosas de importancia; pero que es el Maligno el que hace esos juegos, y no saldr\u00e1 victorioso si ellas se api\u00f1an y unen entre s\u00ed en torno a la Cruz, como los polluelos bajo las alas de su madre cuando les amenaza la lechuza.<\/p>\n<p>Salude de nuestra parte al se\u00f1or Lamberto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sierva de los Pobres Enfermos Nantes (10 de julio de 1647) Mi querida Hermana: Ayer recibimos noticias de que Sor Isabel ha ido a Angers, y el se\u00f1or Vicente me ha ordenado le diga que &#8230; <a href=\"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":393751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[67],"tags":[144,151],"class_list":["post-28340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-luisa-de-marillac","tag-lambert","tag-sor-turgis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Sierva de los Pobres Enfermos Nantes (10 de julio de 1647) Mi querida Hermana: Ayer recibimos noticias de que Sor Isabel ha ido a Angers, y el se\u00f1or Vicente me ha ordenado le diga que ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-06T01:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T09:08:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre\",\"datePublished\":\"2011-02-06T01:00:29+00:00\",\"dateModified\":\"2016-07-26T09:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/\"},\"wordCount\":825,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Lambert\",\"Sor Turgis\"],\"articleSection\":[\"Escritos de Luisa de Marillac\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/\",\"name\":\"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2011-02-06T01:00:29+00:00\",\"dateModified\":\"2016-07-26T09:08:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/","og_locale":"es_ES","og_type":"article","og_title":"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre - Somos Vicencianos","og_description":"Sierva de los Pobres Enfermos Nantes (10 de julio de 1647) Mi querida Hermana: Ayer recibimos noticias de que Sor Isabel ha ido a Angers, y el se\u00f1or Vicente me ha ordenado le diga que ... Read More","og_url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2011-02-06T01:00:29+00:00","article_modified_time":"2016-07-26T09:08:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre","datePublished":"2011-02-06T01:00:29+00:00","dateModified":"2016-07-26T09:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/"},"wordCount":825,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1","keywords":["Lambert","Sor Turgis"],"articleSection":["Escritos de Luisa de Marillac"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/","url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/","name":"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1","datePublished":"2011-02-06T01:00:29+00:00","dateModified":"2016-07-26T09:08:09+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0207-a-mi-querida-sor-juana-lepintre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Luisa de Marillac, Carta 0207: A mi querida Sor Juana Lepintre"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-7n6","jetpack-related-posts":[{"id":114875,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0661-a-sor-barbara\/","url_meta":{"origin":28340,"position":0},"title":"Luisa de Marillac, Carta 0661: A Sor B\u00e1rbara","author":"Francisco Javier Fern\u00e1ndez Chento","date":"10\/11\/2012","format":false,"excerpt":"Hija de la Caridad Sierva de los Pobres Enfermos Ch\u00e2teaudun Hoy, 24 de noviembre (1658) Mi querida Hermana: Se me hac\u00eda ya muy largo el que no me diera usted sus apreciadas noticias; \u00a1alabado sea Dios porque son buenas! No ha llegado usted a decirme si Sor Ana ha estado\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":114876,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0660-al-senor-abad-de-vaux\/","url_meta":{"origin":28340,"position":1},"title":"Luisa de Marillac, Carta 0660: Al se\u00f1or Abad de Vaux","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/11\/2012","format":false,"excerpt":"Hoy, 17 de noviembre (1658) Se\u00f1or: He tenido el honor de escribir al se\u00f1or Ratier por el \u00faltimo correo, para avisarle la marcha de nuestras Hermanas y tambi\u00e9n participarle la alegr\u00eda que era para m\u00ed el que Dios nos haya permitido poder cumplir con este deber. Puedo decirle, se\u00f1or, que\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119456,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0682-a-mi-querida-sor-catalina-gesse\/","url_meta":{"origin":28340,"position":2},"title":"Luisa de Marillac, Carta 0682: A mi querida Sor Catalina Gesse","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/04\/2013","format":false,"excerpt":"Hija de la Caridad Sierva de los Pobres Enfermos, Montmirail Hoy, 4 de mayo de 1659 Mi querida Hermana: Le devolvemos a Isabel a quien, por bien suyo, no nos ha parecido conveniente recibir como Hermana, ya que es muy ni\u00f1a de cuerpo y esp\u00edritu. Le hago el mismo ruego\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":114873,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0663-a-mi-querida-sor-barbara-angiboust\/","url_meta":{"origin":28340,"position":3},"title":"Luisa de Marillac, Carta 0663: A mi querida Sor B\u00e1rbara Angiboust","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/12\/2012","format":false,"excerpt":"Hija de la Caridad Sierva de los Pobres Enfermos Ch\u00e2teaudun Hoy, 8 de diciembre de 1658 Mi querida Hermana: Me alegro mucho de que haya recibido tan pronto mis cartas, pero le ruego considere detenidamente si el car\u00e1cter de Sor Marta se acomodar\u00e1 bien con el de Sor Claudia. Con\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":101428,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0616-a-mi-querida-sor-barbara-angiboust\/","url_meta":{"origin":28340,"position":4},"title":"Luisa de Marillac, Carta 0616: A mi querida Sor B\u00e1rbara Angiboust","author":"Francisco Javier Fern\u00e1ndez Chento","date":"23\/08\/2012","format":false,"excerpt":"Hija de la Caridad Sierva de los Pobres Enfermos Ch\u00e2teaudun Hoy, 6 de enero de 1658 Mi muy querida Hermana: Se me hac\u00eda ya muy largo el no recibir sus apreciadas noticias y mucho tem\u00eda que se hubieran perdido nuestras cartas, como sigo crey\u00e9ndolo, ya que la respuesta que me\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":103907,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0641-a-mi-querida-sor-nicolasa-haran\/","url_meta":{"origin":28340,"position":5},"title":"Luisa de Marillac, Carta 0641: A mi querida Sor Nicolasa Haran","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/09\/2012","format":false,"excerpt":"Nantes Hoy, 8 de agosto (1658) Mi querida Hermana: Es cierto que el se\u00f1or Vicario de Santa Cruz me ha hecho el honor de escribirme, pero yo he tenido tambi\u00e9n el de contestarle y por el mismo conducto escrib\u00ed a Sor Francisca M\u00e9nage, d\u00e1ndole amplias noticias de su familia. Le\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/28340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=28340"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/28340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/393751"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=28340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=28340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=28340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}