{"id":1696,"date":"2008-11-11T12:00:00","date_gmt":"2008-11-11T10:00:00","guid":{"rendered":"http:\/\/www.vicencianos.org\/web\/?p=1696"},"modified":"2016-07-26T11:12:47","modified_gmt":"2016-07-26T09:12:47","slug":"vicente-de-paul-carta-0104-a-luisa-de-marillac","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/","title":{"rendered":"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac"},"content":{"rendered":"[Hacia 1632]\n<p>\u00bfNo le dije ayer, se\u00f1orita, que hab\u00eda que acceder a lo que ped\u00eda, porque su coraz\u00f3n no estar\u00eda tranquilo si esto no se hac\u00eda? H\u00e1galo, pues, en buen hora, tranquilamente y sin prisas. Usted ser\u00e1 la causa de que yo tambi\u00e9n lo haga, uno de estos d\u00edas. Pero vea luego al se\u00f1or Bouvard. \u00a1Ojal\u00e1 se cure pronto para servir a Dios! \u00bfC\u00f3mo lo desea mi coraz\u00f3n, y que sea cuanto antes! Animo, haga por su parte lo que sea necesario. Est\u00e9 alegre y haga con alegr\u00eda lo que tenga que hacer, y yo ser\u00e9, en el amor de Nuestro Se\u00f1or y de su santa Madre, su muy humilde servidor<\/p>\n<p>V. D.<\/p>\n<p>Me gustar\u00eda saber si el se\u00f1or Meynard es procurador en Chatelet en la Corte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Hacia 1632] \u00bfNo le dije ayer, se\u00f1orita, que hab\u00eda que acceder a lo que ped\u00eda, porque su coraz\u00f3n no estar\u00eda tranquilo si esto no se hac\u00eda? H\u00e1galo, pues, en buen hora, tranquilamente y sin prisas. &#8230; <a href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":393753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[],"class_list":["post-1696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-vicente-de-paul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"[Hacia 1632] \u00bfNo le dije ayer, se\u00f1orita, que hab\u00eda que acceder a lo que ped\u00eda, porque su coraz\u00f3n no estar\u00eda tranquilo si esto no se hac\u00eda? H\u00e1galo, pues, en buen hora, tranquilamente y sin prisas. ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-11T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T09:12:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac\",\"datePublished\":\"2008-11-11T10:00:00+00:00\",\"dateModified\":\"2016-07-26T09:12:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"articleSection\":[\"Escritos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/\",\"name\":\"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2008-11-11T10:00:00+00:00\",\"dateModified\":\"2016-07-26T09:12:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0104-a-luisa-de-marillac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac - Somos Vicencianos","og_description":"[Hacia 1632] \u00bfNo le dije ayer, se\u00f1orita, que hab\u00eda que acceder a lo que ped\u00eda, porque su coraz\u00f3n no estar\u00eda tranquilo si esto no se hac\u00eda? H\u00e1galo, pues, en buen hora, tranquilamente y sin prisas. ... Read More","og_url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2008-11-11T10:00:00+00:00","article_modified_time":"2016-07-26T09:12:47+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac","datePublished":"2008-11-11T10:00:00+00:00","dateModified":"2016-07-26T09:12:47+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","articleSection":["Escritos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/","url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/","name":"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","datePublished":"2008-11-11T10:00:00+00:00","dateModified":"2016-07-26T09:12:47+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0104-a-luisa-de-marillac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal, Carta 0104: A Luisa de Marillac"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-rm","jetpack-related-posts":[{"id":103884,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0978-luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":1696,"position":0},"title":"Vicente de Pa\u00fal, Carta 0978: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/09\/2012","format":false,"excerpt":"D\u00eda de pascua [21 abril 1647] Padre: He cre\u00eddo necesario que viera usted esta carta del se\u00f1or de Annemont antes de que las hermanas partan para Nantes. Dos cosas creo que debe usted indicarme. si ser\u00e1 necesario comunicar que pensamos cambiar a la hermana Catalina a los se\u00f1ores de Jonch\u00e8res\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119347,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1113-a-luisa-de-marillac\/","url_meta":{"origin":1696,"position":1},"title":"Vicente de Pa\u00fal, Carta 1113: A Luisa De Marillac","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/04\/2013","format":false,"excerpt":"Par\u00eds, 5 septiembre 1648. \u00a1Bendito sea Dios, se\u00f1orita, por la solicitud que le da Nuestro Se\u00f1or por sus queridas hijas y por m\u00ed en medio de estas agitaciones populares!\u00a0 Todos estamos bien, gracias a Dios, sin que Nuestro Se\u00f1or nos haya hecho dignos de sufrir nada por \u00e9l en esta\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":114807,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0996-a-luisa-de-marillac\/","url_meta":{"origin":1696,"position":2},"title":"Vicente de Pa\u00fal, Carta 0996: A Luisa De Marillac","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/11\/2012","format":false,"excerpt":"[Hacia 1647] Se\u00f1orita: La se\u00f1ora duquesa ha obtenido cien escudos del se\u00f1or superintendente para esas buenas religiosas. Que se los [entreguen], con la condici\u00f3n de que se vuelvan a su casa. Entretanto h\u00e1gales que den clase y vea c\u00f3mo llevan la escuela. Tienen gracia de Dios para esto. Haga el\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":398967,"url":"https:\/\/vincentians.com\/es\/vicente-paul-carta-1355-una-abadesa\/","url_meta":{"origin":1696,"position":3},"title":"Vicente de Pa\u00fal, Carta 1355: A Una Abadesa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/11\/2016","format":false,"excerpt":"\u00a0 \u00a0[Entre 1643 y 1652] Me tomo la confianza, se\u00f1ora abadesa, de interceder ante usted, para rogarle que acepte en su abad\u00eda a una de sus religiosas, que dice ser priora de..., y que no pudiendo seguir en su priorato por culpa de la miseria de los tiempos, ha quedado\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":126114,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1186-al-senor-des-vergnes\/","url_meta":{"origin":1696,"position":4},"title":"Vicente de Pa\u00fal, Carta 1186: Al Se\u00f1or Des Vergnes","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/12\/2013","format":false,"excerpt":"Par\u00eds, 4 septiembre 1649. Padre: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Recib\u00ed su paquete con la alegr\u00eda y el respeto que debo persona y a los motivos de consuelo que contiene. Puede usted creer que le he dado gracias de todo coraz\u00f3n a Dios por las que\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":136751,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1263-a-bernardo-codoing-superior-de-richelieu\/","url_meta":{"origin":1696,"position":5},"title":"Vicente de Pa\u00fal, Carta 1263: A Bernardo Codoing, Superior De Richelieu","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/01\/2015","format":false,"excerpt":"D\u00eda de ramos, 1650 Le ruego que presente sus excusas al se\u00f1or de Maisonneuve por el cambio que solicita del molino y el cortijo de Tuet por una renta de valor parecido, tanto porque esos bienes le valdr\u00e1n quiz\u00e1s dentro de treinta a\u00f1os el doble de lo que ahora valen,\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/1696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=1696"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/1696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/393753"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=1696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=1696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=1696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}