{"id":15900,"date":"2008-12-12T14:07:53","date_gmt":"2008-12-12T12:07:53","guid":{"rendered":"http:\/\/www.vicencianos.org\/web\/2008\/12\/12\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/"},"modified":"2016-07-26T11:11:01","modified_gmt":"2016-07-26T09:11:01","slug":"vicente-de-paul-carta-0428-a-luisa-de-marillac","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/","title":{"rendered":"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac"},"content":{"rendered":"<p>Richelieu, 24 de noviembre de 1639<\/p>\n<p>Se\u00f1orita:<\/p>\n<p>La gracia de Nuestro Se\u00f1or sea siempre con nosotros.<\/p>\n<p>Las disenter\u00edas de este barrio est\u00e1n degenerando en contagio. Los magistrados de esta ciudad acaban de enviar a buscar al padre Lamberto, su p\u00e1rroco, para pensar en las \u00f3rdenes que hay que tomar en esta ciudad por la peste, que se ha presentado en tres sitios. Esto me ofrece la ocasi\u00f3n de rogarle que retrase su viaje, aunque le he indicado al se\u00f1or abad de Vaux, vicario mayor de Angers, que podr\u00eda estar all\u00ed a principios del mes pr\u00f3ximo, Espere nuestro regreso, se\u00f1orita, por favor, y ya veremos.<\/p>\n<p>Hace dos d\u00edas que estoy en esta ciudad, y he visto a sor Luisa al entrar en la iglesia; est\u00e1 muy ilusionada con la esperanza de verla.<\/p>\n<p>Todav\u00eda no he visto a sor B\u00e1rbara. Las cosas van mejor, gracias a Dios.<\/p>\n<p>Espero salir de esta ciudad dentro de tres o cuatro d\u00edas y estar en Par\u00eds hacia el diez o el doce del mes pr\u00f3ximo; entretanto, con la esperanza de encontrarla all\u00ed, soy. en el amor de Nuestro Se\u00f1or&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Richelieu, 24 de noviembre de 1639 Se\u00f1orita: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Las disenter\u00edas de este barrio est\u00e1n degenerando en contagio. Los magistrados de esta ciudad acaban de enviar a buscar &#8230; <a href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":393753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[157,144],"class_list":["post-15900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-vicente-de-paul","tag-abad-de-vaux","tag-lambert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Richelieu, 24 de noviembre de 1639 Se\u00f1orita: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Las disenter\u00edas de este barrio est\u00e1n degenerando en contagio. Los magistrados de esta ciudad acaban de enviar a buscar ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-12T12:07:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T09:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac\",\"datePublished\":\"2008-12-12T12:07:53+00:00\",\"dateModified\":\"2016-07-26T09:11:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Abad de Vaux\",\"Lambert\"],\"articleSection\":[\"Escritos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/\",\"name\":\"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2008-12-12T12:07:53+00:00\",\"dateModified\":\"2016-07-26T09:11:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0428-a-luisa-de-marillac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac - Somos Vicencianos","og_description":"Richelieu, 24 de noviembre de 1639 Se\u00f1orita: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Las disenter\u00edas de este barrio est\u00e1n degenerando en contagio. Los magistrados de esta ciudad acaban de enviar a buscar ... Read More","og_url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2008-12-12T12:07:53+00:00","article_modified_time":"2016-07-26T09:11:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac","datePublished":"2008-12-12T12:07:53+00:00","dateModified":"2016-07-26T09:11:01+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","keywords":["Abad de Vaux","Lambert"],"articleSection":["Escritos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/","url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/","name":"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","datePublished":"2008-12-12T12:07:53+00:00","dateModified":"2016-07-26T09:11:01+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0428-a-luisa-de-marillac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal, Carta 0428: A Luisa De Marillac"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-48s","jetpack-related-posts":[{"id":125085,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1155-a-luisa-de-marillac\/","url_meta":{"origin":15900,"position":0},"title":"Vicente de Pa\u00fal, Carta 1155: A Luisa De Marillac","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/11\/2013","format":false,"excerpt":"Richelieu, d\u00eda siguiente de la Ascensi\u00f3n [1649] Se\u00f1orita: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. El padre Lamberto le habr\u00e1 podido comunicar mi llegada a este lugar. Las visitas que tuve al d\u00eda siguiente de llegar por la ma\u00f1ana me impidieron escribirle a tiempo para que llegara la\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":114876,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0660-al-senor-abad-de-vaux\/","url_meta":{"origin":15900,"position":1},"title":"Luisa de Marillac, Carta 0660: Al se\u00f1or Abad de Vaux","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/11\/2012","format":false,"excerpt":"Hoy, 17 de noviembre (1658) Se\u00f1or: He tenido el honor de escribir al se\u00f1or Ratier por el \u00faltimo correo, para avisarle la marcha de nuestras Hermanas y tambi\u00e9n participarle la alegr\u00eda que era para m\u00ed el que Dios nos haya permitido poder cumplir con este deber. Puedo decirle, se\u00f1or, que\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":103908,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0636-al-senor-abad-de-vaux\/","url_meta":{"origin":15900,"position":2},"title":"Luisa de Marillac, Carta 0636: Al se\u00f1or Abad de Vaux","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/09\/2012","format":false,"excerpt":"Angers Hoy, 4 de julio de 1658 Se\u00f1or: Tengo que confesarle que no hay mortificaci\u00f3n m\u00e1s humillante para m\u00ed que la que me proporcionan nuestras Hermanas al hacer tan mal uso de los consejos que su caridad no deja de darles. Espero, se\u00f1or, con la gracia de Dios, que se\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":117492,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1064-luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":15900,"position":3},"title":"Vicente de Pa\u00fal, Carta 1064: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/01\/2013","format":false,"excerpt":"Padre: Hace m\u00e1s de un mes que nos comunicaron que el se\u00f1or abad de Vaux deber\u00eda venir a esta ciudad a principios de mayo, y que es necesario que \u00e9l nombre un director para nuestras hermanas, lo cual no har\u00e1 hasta que yo le haya indicado a usted todas sus\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":101834,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0625-al-senor-abad-de-vaux\/","url_meta":{"origin":15900,"position":4},"title":"Luisa de Marillac, Carta 0625: Al se\u00f1or Abad de Vaux","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/09\/2012","format":false,"excerpt":"(hacia marzo de 1658) Se\u00f1or: Hace alg\u00fan tiempo que, habiendo sabido por su caridad que dos buenas j\u00f3venes deseaban ser de nuestra Compa\u00f1\u00eda, despu\u00e9s de haber usted probado su vocaci\u00f3n, como tuvo la bondad de dec\u00edrnoslo, el se\u00f1or Vicente me orden\u00f3 le suplicara humildemente, se\u00f1or, nos las enviara si las\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":128959,"url":"https:\/\/vincentians.com\/es\/el-gran-hospital-de-angers\/","url_meta":{"origin":15900,"position":5},"title":"El gran hospital de Angers","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/05\/2025","format":false,"excerpt":"Males de la comunidad Entre 1640 y 1644, Luisa sinti\u00f3 miedo por la comunidad de Angers que con tanta ilu\u00adsi\u00f3n hab\u00eda ido a fundar ella misma. Le llegaban noticias desalentadoras. A veces, eran de\u00adcisiones de los administradores que tanto ellos como la gente consideraban insignifican\u00adtes, pero que a Luisa la\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Cuba4.png?fit=1200%2C715&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Cuba4.png?fit=1200%2C715&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Cuba4.png?fit=1200%2C715&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Cuba4.png?fit=1200%2C715&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Cuba4.png?fit=1200%2C715&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/15900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=15900"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/15900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/393753"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=15900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=15900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=15900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}