{"id":141786,"date":"2015-03-18T06:15:58","date_gmt":"2015-03-18T05:15:58","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=141786"},"modified":"2015-03-18T06:15:58","modified_gmt":"2015-03-18T05:15:58","slug":"unidos-en-la-oracion","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/","title":{"rendered":"Unidos en la oraci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/asd7.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-141787\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/asd7-269x300.jpg?resize=269%2C300\" alt=\"asd\" width=\"269\" height=\"300\" \/><\/a>\u00abSi aqu\u00ed en la tierra dos de vosotros se ponen de acuerdo, cualquier asunto por el \u00ad que pidan les resultar\u00e1, por obra de mi Padre del cielo, pues donde est\u00e1n dos o tres reunidos apelando a m\u00ed, all\u00ed en medio de ellos estoy yo\u00bb. (Mt 18, 19-20).<\/p>\n<p style=\"text-align: justify\">\u00abLa comunidad se crea constantemente a s\u00ed misma renovando, ante todo, los ele\u00admentos m\u00e1s importantes de nuestro modo de vivir y de obrar, a saber: La oraci\u00f3n, sobre todo en la Eucarist\u00eda, que se convierte en fuente de nuestra vida espiritual, comunitaria apost\u00f3lica\u00bb. (C 25,3).<\/p>\n<p style=\"text-align: justify\">El tercer elemento renovador de la comunidad vicenciana, seg\u00fan las Constituciones, es la oraci\u00f3n. Resul\u00adta, en efecto, impensable una comunidad sin oraci\u00f3n. El apostolado, que pueden desarrollar los Misioneros, ser\u00eda poco menos que infructuoso, si llegara a faltar de la comunidad el ejercicio de la oraci\u00f3n. Sin la oraci\u00f3n, todos los aspectos que comprende la vida comunitaria quedar\u00edan deteriorados.<\/p>\n<h2 style=\"text-align: justify\"><strong>1. \u00abEl Se\u00f1or se nos dar\u00e1 juntamente a todos\u00bb.<\/strong><\/h2>\n<p style=\"text-align: justify\">Como quer\u00eda San Vicente, no basta que nos reuna\u00admos para orar; es necesario, adem\u00e1s, permanecer uni\u00addos en la oraci\u00f3n. De \u00e9sta surgen los efectos necesarios para crear comunidad cristiana y apost\u00f3lica; tales efec\u00adtos son otras tantas razones que San Vicente expon\u00eda para vivir unidos en la oraci\u00f3n:<\/p>\n<p style=\"text-align: justify\"><em>\u00abSi nos encontramos todos juntos ante nuestro Se\u00ad\u00f1or y nos presentamos a El al mismo tiempo, como ha\u00adc\u00edan los primeros cristianos, El se nos dar\u00e1 juntamente a todos, nos iluminar\u00e1n con sus luces y realizar\u00e1 El mis\u00admo en nosotros y por nosotros los bienes que tenemos obligaci\u00f3n de hacer en la Iglesia; en fin, nos dar\u00e1 la <\/em><em>gracia ele llegar al grado de perfecci\u00f3n que desea de nosotros, para que le podamos poseer alg\u00fan d\u00eda plena\u00admente en la eternidad de los siglos\u00bb. <\/em><em>(III <\/em>494-495).<\/p>\n<h2 style=\"text-align: justify\"><strong>2. \u00abLa fidelidad a la oraci\u00f3n o el abandono de la misma son el paradigma de la vitalidad o de la decadencia de la vida religiosa\u00bb.<\/strong><\/h2>\n<p style=\"text-align: justify\">Los Misioneros se sienten unidos con <em>el <\/em>Se\u00f1or en la oraci\u00f3n; gracias a \u00e9sta, es posible descubrir a Jesucristo en los hermanos y amar a todos en la persona del Hijo de Dios. El Esp\u00edritu de Jes\u00fas nos ilumina y nos enri\u00adquece con su sabidur\u00eda para recoger las manifestaciones de su amor, si estamos profundamente penetrados por el esp\u00edritu de oraci\u00f3n. A este respecto, escuchemos las palabras de Pablo VI:<\/p>\n<p style=\"text-align: justify\"><em>\u00abNo <\/em><em>olvid\u00e9is el testimonio ele la historia: la fideli\u00addad a la oraci\u00f3n o el abandono de la misma son el pa\u00adradigma de la vitalidad o de la decadencia de la vida religiosa. Es, pues, la oraci\u00f3n el logro de la intimidad con Dios, deseo de adorar, voluntad de interceder; la experiencia de la santidad cristiana nos demuestra la fe\u00adcundidad de la oraci\u00f3n, en la cual Dios se mani f esta al esp\u00edritu y al coraz\u00f3n de sus siervos. El Se\u00f1or nos da este conocimiento de S\u00ed mismo en el fuego del amor\u00bb. <\/em>(ET 42).<\/p>\n<h2 style=\"text-align: justify\"><strong>3. \u00abLa Eucarist\u00eda, coraz\u00f3n de la comunidad y fuente de vida\u00bb.<\/strong><\/h2>\n<p style=\"text-align: justify\">Pero ninguna oraci\u00f3n ha de sernos tan querida como la Eucarist\u00eda:<\/p>\n<p style=\"text-align: justify\"><em>\u00abReunidas en su nombre, las comunidades tienen de por s\u00ed como centro la Eucarist\u00eda, sacramento de amor, signo de unidad, v\u00ednculo de caridad. Es, pues, conve\u00adniente que ellas se encuentren visiblemente reunidas en torno a un oratorio, donde la presencia de la Sagrada <\/em><em>Eucarist\u00eda expresa y realiza a la vez lo que debe ser la principal misi\u00f3n de toda familia religiosa, como, por otra parte, de toda asamblea cristiana. La Eucarist\u00eda, gracias a la cual no cesamos de anunciar la muerte y la resurrecci\u00f3n del Se\u00f1or y de prepararnos a su venida glo\u00adriosa, trae constantemente a la memoria los sufrimientos f\u00edsicos y morales que agobian a Cristo y que, sin embar\u00adgo, hab\u00edan sido aceptados libremente por El hasta la agon\u00eda y la muerte en la Cruz. Las amarguras que se os presentan sean para vosotros la ocasi\u00f3n de llevar junta\u00admente con el Se\u00f1or y ofrecer al Padre tantas desgracias y sufrimientos injustos como afligen a nuestros herma\u00adnos y a los cuales s\u00f3lo el sacrificio de Cristo puede dar, en la fe, un significado\u00bb. <\/em>(ET 48).<\/p>\n<ul style=\"text-align: justify\">\n<li><em>\u00bfAsisto todos los d\u00edas a la oraci\u00f3n para crear constantemente comunidad con mis hermanos?<\/em><\/li>\n<li><em>\u00bfConcelebro la Eucarist\u00eda, siempre que es posi\u00adble, con otros sacerdotes, bien de la Congrega\u00adci\u00f3n, diocesanos o religiosos?<\/em><\/li>\n<\/ul>\n<h2 style=\"text-align: justify\">Oraci\u00f3n:<\/h2>\n<p style=\"text-align: justify\">\u00abSe\u00f1or, que por el misterio pascual de tu Hijo realizas\u00adte la redenci\u00f3n de los hombres, conc\u00e9denos avanzar por el camino de la salvaci\u00f3n a quienes, celebrando los sacramen\u00adtos, proclamamos con fe la muerte y resurrecci\u00f3n de Cris\u00adto. Que vive y reina contigo\u00bb. (Mro, Votiva de la Sant\u00edsima Eucarist\u00eda).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSi aqu\u00ed en la tierra dos de vosotros se ponen de acuerdo, cualquier asunto por el \u00ad que pidan les resultar\u00e1, por obra de mi Padre del cielo, pues donde est\u00e1n dos o tres reunidos &#8230; <a href=\"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":141787,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-141786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unidos en la oraci\u00f3n - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unidos en la oraci\u00f3n - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"\u00abSi aqu\u00ed en la tierra dos de vosotros se ponen de acuerdo, cualquier asunto por el \u00ad que pidan les resultar\u00e1, por obra de mi Padre del cielo, pues donde est\u00e1n dos o tres reunidos ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-18T05:15:58+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Unidos en la oraci\u00f3n\",\"datePublished\":\"2015-03-18T05:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/\"},\"wordCount\":849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/\",\"name\":\"Unidos en la oraci\u00f3n - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-18T05:15:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/unidos-en-la-oracion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unidos en la oraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unidos en la oraci\u00f3n - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/","og_locale":"es_ES","og_type":"article","og_title":"Unidos en la oraci\u00f3n - Somos Vicencianos","og_description":"\u00abSi aqu\u00ed en la tierra dos de vosotros se ponen de acuerdo, cualquier asunto por el \u00ad que pidan les resultar\u00e1, por obra de mi Padre del cielo, pues donde est\u00e1n dos o tres reunidos ... Read More","og_url":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-18T05:15:58+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Unidos en la oraci\u00f3n","datePublished":"2015-03-18T05:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/"},"wordCount":849,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#primaryimage"},"thumbnailUrl":"","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/","url":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/","name":"Unidos en la oraci\u00f3n - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-18T05:15:58+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/unidos-en-la-oracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Unidos en la oraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-ASS","jetpack-related-posts":[{"id":387156,"url":"https:\/\/vincentians.com\/es\/en-comunidad-fraterna-y-espiritual\/","url_meta":{"origin":141786,"position":0},"title":"En comunidad fraterna y espiritual","author":"Mitxel Olabu\u00e9naga","date":"07\/03\/2016","format":false,"excerpt":"\u00abOs lo digo otra vez: Si aqu\u00ed en la tierra dos de vos\u00adotros se ponen de acuerdo, cualquier asunto por el que pidan les resultar\u00e1, por obra de mi Padre del cielo, pues donde est\u00e1n dos o tres re\u00adunidos apelando a m\u00ed, all\u00ed, en medio de ellos, estoy yo\u00bb. (Mt\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/03\/asd-300x227.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":131332,"url":"https:\/\/vincentians.com\/es\/vida-fraterna-en-comun\/","url_meta":{"origin":141786,"position":1},"title":"Vida fraterna en com\u00fan","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/10\/2014","format":false,"excerpt":"\"Mientras sub\u00eda a la monta\u00f1a fue llamando a los que \u00e9l quiso y se reunieron con \u00e9l. Design\u00f3 a doce para que fueran sus compa\u00f1eros y para enviarles a predicar con poder de expulsar demonios\". (Mc. 7, 13.15). \"La Congregaci\u00f3n de la Misi\u00f3n es una sociedad clerical de vida apost\u00f3lica\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"duccio296","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/10\/duccio296-300x240.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":131330,"url":"https:\/\/vincentians.com\/es\/en-renovacion-continua\/","url_meta":{"origin":141786,"position":2},"title":"En renovaci\u00f3n continua","author":"Francisco Javier Fern\u00e1ndez Chento","date":"22\/05\/2015","format":false,"excerpt":"\"Nadie le pone una pieza de pa\u00f1o sin estrenar a un manto pasado, porque el remiendo tira del manto, lo nuevo de lo viejo, y deja el roto peor. Nadie echa tampoco vino nuevo en odres viejos; sino, el vino revienta los odres; no, a vino nuevo, odres nuevos\". (Mt\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"eucaristia espiritu","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/09\/eucaristia-espiritu-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":142315,"url":"https:\/\/vincentians.com\/es\/dadme-un-hombre-de-oracion\/","url_meta":{"origin":141786,"position":3},"title":"\u00abDadme un hombre de oraci\u00f3n\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/04\/2015","format":false,"excerpt":"\u00abNinguna situaci\u00f3n tiene se\u00adcretos para m\u00ed, ni estar har\u00adto, ni pasar hambre, ni tener sobra, ni pasar falta; para todo me siento con fuerzas, gracias al que me robustece\u00bb. (Flp 4,12-13). \u00abDadme un hombre de ora\u00adci\u00f3n y ser\u00e1 capaz de todo'\u00bb (SV XI 83; ES XI 778). En efecto, seg\u00fan\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"oracion-viva1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/04\/oracion-viva1-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387803,"url":"https:\/\/vincentians.com\/es\/jesus-ora-al-padre-movido-por-el-espiritu\/","url_meta":{"origin":141786,"position":4},"title":"Jes\u00fas ora al Padre, movido por el Esp\u00edritu","author":"Mitxel Olabu\u00e9naga","date":"08\/09\/2016","format":false,"excerpt":"Jes\u00fas de Nazaret es un trabajador fiel que hace de su vida oraci\u00f3n, y de la oraci\u00f3n compromiso de salvaci\u00f3n para los hombres. Trabajo y oraci\u00f3n se funden indisolublemente en su persona. Es inconcebible un Jes\u00fas que no ora expresamente al Padre y que no ense\u00f1a a sus disc\u00edpulos a\u2026","rel":"","context":"En \u00abOraci\u00f3n\u00bb","block_context":{"text":"Oraci\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/oracion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-ora-al-padre.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":387147,"url":"https:\/\/vincentians.com\/es\/reconciliados-con-el-padre-y-la-iglesia\/","url_meta":{"origin":141786,"position":5},"title":"Reconciliados con el Padre y la Iglesia","author":"Mitxel Olabu\u00e9naga","date":"05\/03\/2016","format":false,"excerpt":"\u00abSi reconocemos nuestros pe\u00adcados, Dios, que es fiel y justo, perdona nuestros pe\u00adcados y, adem\u00e1s, nos limpia de toda injusticia\u00bb. (I Jai 1,9). \u00abNos acercamos frecuente\u00admente al Sacramento de la Penitencia a fin de poder con\u00adseguir la conversi\u00f3n conti\u00adnua y la sinceridad de la vo\u00adcaci\u00f3n\u00bb. (C 45,2). Aunque llamados a\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/02\/asd-7-300x230.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/141786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=141786"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/141786\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=141786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=141786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=141786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}