{"id":141135,"date":"2015-03-08T08:32:38","date_gmt":"2015-03-08T07:32:38","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=141135"},"modified":"2015-03-08T08:32:38","modified_gmt":"2015-03-08T07:32:38","slug":"concordes-unos-con-otros","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/","title":{"rendered":"Concordes unos con otros"},"content":{"rendered":"<p style=\"text-align: justify\">\u00abSi hay un est\u00edmulo en el \u00adMes\u00edas y un aliento en el \u00adamor mutuo, si existe una solidaridad de esp\u00edritu y un cari\u00f1o entra\u00f1able, hacedme feliz del todo y andad de acuerdo, teniendo un amor rec\u00edproco y un inter\u00e9s un\u00e1nime por la unidad\u00bb. (Flp 2,1-2).<\/p>\n<p style=\"text-align: justify\">\u00ad\u00abPara realizar nuestra misi\u00f3n nos empe\u00f1aremos en lograr la concordia, ofreci\u00e9ndonos ayuda mutua, especialmente en la adversidad y compartiendo la alegr\u00eda con sencillez de coraz\u00f3n\u00bb. (C 24,1).<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/solidaridad1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-141203\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/solidaridad1-300x225.jpg?resize=300%2C225\" alt=\"solidaridad\" width=\"300\" height=\"225\" \/><\/a>El pensamiento de San Vicente sobre la uniformidad lo trasladamos hoy a la unidad y a la concordia, t\u00e9rminos b\u00edblico-teol\u00f3gicos mucho m\u00e1s ricos espiritualmente que el primero. La concordia implica participaci\u00f3n en los mismos sentimientos de los otros y conduce a la una\u00adnimidad y caridad. San Vicente se inspir\u00f3 en los conse\u00adjos de San Pablo para exhortar a los Misioneros a la solidaridad de esp\u00edritu y el amor mutuo.<\/p>\n<h2 style=\"text-align: justify\"><strong>1. \u00abEl ejemplo del Hijo de Dios\u00bb.<\/strong><\/h2>\n<p style=\"text-align: justify\">Como de ordinario, San Vicente nos propone tam\u00adbi\u00e9n en este caso el ejemplo de Jesucristo, que se hizo semejante a nosotros:<\/p>\n<p style=\"text-align: justify\"><em>\u00abEl Hijo de Dios, al hacerse hombre, quiso llevar una vida en com\u00fan para conformarse a los hombres. Para mejor acercarse a nosotros, se hizo semejante a nosotros; y como la semejanza engendra amor, quiso parecer y obrar como nosotros, para hacerse amar; qui\u00adso injertarse en nuestra naturaleza para unirnos a El; se hizo hombre para hacernos ver, por su forma de vi\u00advir, c\u00f3mo hemos de vivir nosotros. Era la imagen del Padre, pero, como si esto no bastase, quiso unir a esta imagen adorable su uniformidad con los hombres, para ganarlos a todos\u00bb. <\/em>(XI 543-544).<\/p>\n<h2 style=\"text-align: justify\"><strong>2. \u00abEngendra la uni\u00f3n en la Compa\u00f1\u00eda\u00bb.<\/strong><\/h2>\n<p style=\"text-align: justify\">El logro de la concordia implica una lucha tenaz con\u00adtra la envidia y el deseo de singulizarse, vicios de los que no est\u00e1n exentos los Misioneros. Se nos recomienda la concordia y el amor rec\u00edproco porque:<\/p>\n<p style=\"text-align: justify\"><em>\u00abEngendran <\/em><em>la uni\u00f3n <\/em><em>en la <\/em><em>Compa\u00f1\u00eda, que es el <\/em><em>ce\u00admento que nos <\/em><em>a\u00fana, la <\/em><em>belleza que <\/em><em>nos hace amables <\/em><em>y nos permite <\/em><em>arrastrar a los dem\u00e1s. Y ese amor rec\u00edpro\u00adco es el que hace que procuremos tener las mismas <\/em><em>ma\u00adneras de entender, las <\/em><em>mismas <\/em><em>cosas que <\/em><em>querer y <\/em><em>los mismos proyectos que perseguir. Por <\/em><em>el contrario, <\/em><em>si quit\u00e1is de entre vosotros esa uniformidad <\/em><em>que produce la semejanza, quit\u00e1is <\/em><em>de all\u00ed el amor; <\/em><em>no ser\u00edamos <\/em><em>ya m\u00e1s que <\/em><em>un <\/em><em>cuerpo desfigurado y <\/em><em>una desolaci\u00f3n total. <\/em><em>Donde hay esp\u00edritus que <\/em><em>se singularizan, <\/em><em>all\u00ed <\/em><em>hay almas <\/em><em>divididas\u00bb. (XI <\/em>544).<\/p>\n<p style=\"text-align: justify\">Como a San Pablo, la concordia entre los Misione-los colmaban tambi\u00e9n plenamente la dicha de San Vi\u00adcente:<\/p>\n<p style=\"text-align: justify\"><em>\u00abNo s\u00e9 <\/em><em>que haya en la tierra m\u00e1s <\/em><em>para\u00edso que el que existe <\/em><em>entre los que se acomodan unos a otros para ser <\/em><em>todos <\/em><em>iguales; no <\/em><em>s\u00e9 que <\/em><em>haya nada en el mundo que <\/em><em>pueda <\/em><em>colmar nuestra <\/em><em>dicha <\/em><em>m\u00e1s que la uniformidad en\u00adtre nosotros, <\/em><em>que nos hace <\/em><em>semejantes a nuestro Se\u00f1or y nos une <\/em><em>con Dios\u00bb. <\/em>(X 547).<\/p>\n<h2 style=\"text-align: justify\"><strong>3. \u00abNosotros debemos ofrecer a los fieles la imagen de hombres adultos en la fe\u00bb.<\/strong><\/h2>\n<p style=\"text-align: justify\">A fin <em>de <\/em>evitar el peligro contra la unidad en la evan\u00adgelizaci\u00f3n, a la que est\u00e1 ordenada la vida comunitaria, tengamos esto presente:<\/p>\n<p style=\"text-align: justify\"><em>\u00abLa <\/em><em>fuerza de la evangelizaci\u00f3n quedar\u00e1 muy debili\u00adtada <\/em><em>si los <\/em><em>que anuncian <\/em><em>el Evangelio <\/em><em>est\u00e1n divididos <\/em><em>enter <\/em><em>s\u00ed por <\/em><em>tantas clases <\/em><em>de rupturas. \u00bfNo <\/em><em>estar\u00e1 quiz\u00e1 <\/em><em>ah\u00ed uno de los m\u00e1s <\/em><em>grandes males de la evangelizaci\u00f3n? <\/em><em>En efecto, si <\/em><em>el Evangelio <\/em><em>que <\/em><em>proclamamos aparece <\/em><em>desgarrado por querellas doctrinales, por <\/em><em>polarizaciones <\/em><em>ideol\u00f3gicas o por <\/em><em>condenas <\/em><em>rec\u00edprocas entre <\/em><em>cristianos, al <\/em><em>antojo de sus <\/em><em>diferentes <\/em><em>teor\u00edas sobre <\/em><em>Cristo y sobre <\/em><em>la Iglesia, e incluso <\/em><em>a causa de <\/em><em>sus <\/em><em>distintas concepcio\u00adnes <\/em><em>de la sociedad y <\/em><em>de las <\/em><em>instituciones <\/em><em>humanas, \u00bfc\u00f3mo <\/em><em>pretender que aquellos a los que se <\/em><em>dirige nuestra pre\u00addicaci\u00f3n no <\/em><em>se muestren perturbados, <\/em><em>desorientados, si <\/em><em>no escandalizados? El testamento espiritual del Se\u00f1or nos dice que la unidad <\/em><em>entre <\/em><em>sus seguidores <\/em><em>no es <\/em><em>sola\u00admente la prueba de que somos suyos, sino <\/em><em>tambi\u00e9n <\/em><em>la prueba de que El es el enviado del Padre, prueba <\/em><em>de <\/em><em>credibilidad de los cristianos y del mismo Cristo. <\/em><em>Evan\u00adgelizadores: <\/em><em>nosotros <\/em><em>debemos ofrecer a <\/em><em>los fieles <\/em><em>de <\/em><em>Cristo, no <\/em><em>la imagen de hombres divididos y separados <\/em><em>por las luchas <\/em><em>que no sirven <\/em><em>para <\/em><em>construir nada, sino la <\/em><em>de hombres <\/em><em>adultos en la fe, capaces de encontrarse m\u00e1s all\u00e1 de <\/em><em>las tensiones <\/em><em>reales gracias a la <\/em><em>b\u00fasqueda <\/em><em>com\u00fan, <\/em><em>sincera y desinteresada de <\/em><em>la verdad\u00bb. <\/em>(EN 77).<\/p>\n<ul style=\"text-align: justify\">\n<li><em>\u00bfFomento la armon\u00eda <\/em><em>y concordia <\/em><em>entre <\/em><em>los her\u00admanos de <\/em><em>comunidad?<\/em><\/li>\n<li><em>\u00bfReduzco la virtud de la concordia <\/em><em>a decir sim\u00adplemente <\/em><em>s\u00ed a todo, o, por <\/em><em>el contrario, me es\u00adfuerzo en <\/em><em>hacer part\u00edcipes a los <\/em><em>dem\u00e1s de mis sentimientos <\/em><em>con <\/em><em>sencillez <\/em><em>de coraz\u00f3n?<\/em><\/li>\n<\/ul>\n<h2 style=\"text-align: justify\">Oraci\u00f3n:<\/h2>\n<p style=\"text-align: justify\">\u00abTe pedimos, Dios nuestro, que nos hagas a todos, lo mismo que a los primeros cristianos, un solo coraz\u00f3n y una sola alma. Conc\u00e9denos la gracia de que no tengamos dos corazones ni dos almas, sino un solo coraz\u00f3n y una sola alma, que informen y uniformen a toda la comunidad; qu\u00edtanos nuestros corazones particulares y nuestras almas particulares que se apartan de la unidad; qu\u00edtanos nuestro obrar particular, cuando no est\u00e9 en conformidad con el obrar com\u00fan\u00bb. (XI 543).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSi hay un est\u00edmulo en el \u00adMes\u00edas y un aliento en el \u00adamor mutuo, si existe una solidaridad de esp\u00edritu y un cari\u00f1o entra\u00f1able, hacedme feliz del todo y andad de acuerdo, teniendo un amor &#8230; <a href=\"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":141203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-141135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concordes unos con otros - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concordes unos con otros - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"\u00abSi hay un est\u00edmulo en el \u00adMes\u00edas y un aliento en el \u00adamor mutuo, si existe una solidaridad de esp\u00edritu y un cari\u00f1o entra\u00f1able, hacedme feliz del todo y andad de acuerdo, teniendo un amor ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-08T07:32:38+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Concordes unos con otros\",\"datePublished\":\"2015-03-08T07:32:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/\"},\"wordCount\":928,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/\",\"name\":\"Concordes unos con otros - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-08T07:32:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/concordes-unos-con-otros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concordes unos con otros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concordes unos con otros - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/","og_locale":"es_ES","og_type":"article","og_title":"Concordes unos con otros - Somos Vicencianos","og_description":"\u00abSi hay un est\u00edmulo en el \u00adMes\u00edas y un aliento en el \u00adamor mutuo, si existe una solidaridad de esp\u00edritu y un cari\u00f1o entra\u00f1able, hacedme feliz del todo y andad de acuerdo, teniendo un amor ... Read More","og_url":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-08T07:32:38+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Concordes unos con otros","datePublished":"2015-03-08T07:32:38+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/"},"wordCount":928,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#primaryimage"},"thumbnailUrl":"","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/","url":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/","name":"Concordes unos con otros - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-08T07:32:38+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/concordes-unos-con-otros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Concordes unos con otros"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-AIn","jetpack-related-posts":[{"id":140998,"url":"https:\/\/vincentians.com\/es\/unidos-por-la-fuerza-del-espiritu\/","url_meta":{"origin":141135,"position":0},"title":"Unidos por la fuerza del Esp\u00edritu","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/02\/2015","format":false,"excerpt":"\u00abLa Iglesia se iba construyendo, progresaba en la fidelidad al Se\u00f1or y se multipli\u00adcaba, alentada por el Esp\u00edritu Santo\u00bb. (Hch 9,31).\u00ad \u00abBajo el soplo del Esp\u00edritu Santo construimos la unidad entre nosotros al realizar la misi\u00f3n, a fin de dar un testimonio fehaciente de Cristo Salvador\u00bb. C 20,3). Si Cristo\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/asd7-300x274.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":137543,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1280-a-juan-midot-vicario-general-de-toul\/","url_meta":{"origin":141135,"position":1},"title":"Vicente de Pa\u00fal, Carta 1280: A Juan Midot, Vicario General De Toul","author":"Francisco Javier Fern\u00e1ndez Chento","date":"15\/02\/2015","format":false,"excerpt":"8 de junio de 1650 Se\u00f1or: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Recib\u00ed su carta con un nuevo sentimiento de gratitud por los favores que le debemos y con nuevos deseos de que quiera Dios conservarle largos a\u00f1os para bien de su iglesia, en la cual me\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":131634,"url":"https:\/\/vincentians.com\/es\/al-servicio-de-la-iglesia-universal\/","url_meta":{"origin":141135,"position":2},"title":"Al servicio de la Iglesia universal","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/10\/2014","format":false,"excerpt":"\"Convoc\u00f3 a los Doce y les dio poder y autoridad sobre toda clase de demonios y para curar enfermedades. Luego los envi\u00f3 a proclamar el reinado de Dios y curar a los enfermos, dici\u00e9ndoles: No coj\u00e1is nada en el camino ni bast\u00f3n, ni alforja, ni pan, ni dinero, ni llev\u00e9is\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"iglesia1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/10\/iglesia1-240x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":136771,"url":"https:\/\/vincentians.com\/es\/amigos-de-los-sacerdotes\/","url_meta":{"origin":141135,"position":3},"title":"Amigos de los sacerdotes","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/02\/2015","format":false,"excerpt":"\u00abEsa copa de la bendici\u00f3n que bendecimos, \u00bfno signifi\u00adca solidaridad con la sangre del Mes\u00edas? Ese pan que partimos, \u00bfno significa soli\u00addaridad con el Cuerpo del Mes\u00edas?\u00bb (I Cor 10,16). \u00abPresten, adem\u00e1s, los Misio\u00adneros ayuda espiritual a los sacerdotes, favoreciendo su formaci\u00f3n continua y fomen\u00adtando el estudio pastoral. Susciten en\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":34545,"url":"https:\/\/vincentians.com\/es\/filipinas-1898-v\/","url_meta":{"origin":141135,"position":4},"title":"Filipinas (1898) (V)","author":"Mitxel Olabu\u00e9naga","date":"25\/05\/2014","format":false,"excerpt":"D\u00eda 9 de. Agosto.\u2014Me encuentro en la Concordia. Esta\u00admos en d\u00edas de agon\u00eda. La sentencia est\u00e1 fallada, y desde el d\u00eda 7 nos hallamos como el reo en capilla. El Comodoro yanqui est\u00e1 jugando con nosotros y nos est\u00e1 zarandeando a su placer. Anteayer intim\u00f3 la rendici\u00f3n de Manila, fijando\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/situacionbaler3-204x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":136686,"url":"https:\/\/vincentians.com\/es\/hermana-sirviente-de-una-comunidad-unida\/","url_meta":{"origin":141135,"position":5},"title":"Hermana sirviente de una comunidad unida","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/01\/2015","format":false,"excerpt":"Santa Luisa ense\u00f1a el gobierno En los primeros a\u00f1os la Compa\u00f1\u00eda ven\u00eda a ser como una Comunidad grande con una superiora, la se\u00f1orita Le Gras. La Compa\u00f1\u00eda comenz\u00f3 con un grupito de cuatro o cinco j\u00f3venes a las que ella prepar\u00f3. Al ir aumentando el n\u00famero de Hermanas, la se\u00f1orita\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"hermanas sirvientes","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/hermanas-sirvientes-300x204.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/141135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=141135"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/141135\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=141135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=141135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=141135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}