{"id":14076,"date":"2021-08-25T07:50:05","date_gmt":"2021-08-25T05:50:05","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/?p=14076"},"modified":"2021-06-07T09:03:10","modified_gmt":"2021-06-07T07:03:10","slug":"como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/","title":{"rendered":"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy"},"content":{"rendered":"<p>Desde el Vaticano II las dos comunidades fundadas por San Vicente han experimentado grandes cambios. Ambas han re-elaborado totalmente sus constituciones y estatutos, y su proceso de toma de decisiones es mucho m\u00e1s participativo. Casi todas las provincias han emprendido una seria evaluaci\u00f3n y reestructuraci\u00f3n de sus obras. Al mismo tiempo han florecido los estudios vicencianos. Han aparecido nuevas traducciones de las obras de San Vicente y Santa Luisa en varias lenguas modernas. Se han escrito nuevas biograf\u00edas de ambos. Se ha despertado un renovado inter\u00e9s en su espiritualidad. Las dos Compa\u00f1\u00edas han elaborado una nueva instrucci\u00f3n sobre los votos. Las virtudes que Vicente propuso a ambos grupos han sido nuevamente estudiadas en profundidad. Las dos comunidades han organizado numerosos cursillos y programas m\u00e1s amplios de formaci\u00f3n permanente en el \u00e1mbito provincial, interprovincial e internacional.<\/p>\n<p>Durante este tiempo se han dado tambi\u00e9n cambios significativos en la vida comunitaria. El estilo de vida menos formal, la autoridad menos impositiva, los horarios menos r\u00edgidos. Muchos tienen la sensaci\u00f3n de que las relaciones interpersonales son menos formalistas y mucho m\u00e1s personales. Sin embargo, a\u00fan reconociendo estos importantes cambios, algunos sacerdotes, hermanos y hermanas manifiestan cierta desaz\u00f3n sobre la vida comunitaria. Preguntan ellos, en este periodo de transici\u00f3n acelerada \u00bfhemos encontrado nosotros la f\u00f3rmula correcta para la vida en com\u00fan? \u00bfofrece la comunidad el apoyo de la fe, el est\u00edmulo, la comprensi\u00f3n, la solidaridad en la acci\u00f3n, el hogar que hoy tantos buscan \u2014especialmente los j\u00f3venes\u2014 ?<\/p>\n<p>Plenamente convencido de no tener una respuesta definitiva a estas preguntas, ofrezco este ensayo como punto de partida para un ulterior di\u00e1logo sobre esta importante cuesti\u00f3n. Sirvi\u00e9ndome de la metodolog\u00eda que he seguido con frecuencia, este ensayo examinar\u00e1:<\/p>\n<p style=\"padding-left: 30px\">I. La vida comunitaria en la tradici\u00f3n vicenciana,<\/p>\n<p style=\"padding-left: 30px\">II. Cambios de horizonte entre los siglos XVII y XX,<\/p>\n<p style=\"padding-left: 30px\">III. La vida comunitaria hoy \u2014 algunos modelos,<\/p>\n<p style=\"padding-left: 30px\">IV. Am\u00e1ndonos profundamente unos a otros.<\/p>\n<h2><strong>I. La vida comunitaria en la tradici\u00f3n vicenciana <\/strong><\/h2>\n<p>Vicente y Luisa no escribieron sobre la vida comunitaria de forma sistem\u00e1tica. Un examen de los \u00edndices de sus obras nos proporcionan escasos resultados sobre este tema. Pero las reglas de ambas Compa\u00f1\u00edas, en varios cap\u00edtulos, tratan la mayor\u00eda de los puntos clave y de los problemas de la vida com\u00fan. M\u00e1s a\u00fan, los dos fundadores trataron con frecuencia de la vida junto en una gran variedad de contextos. A lo largo de los a\u00f1os, quiz\u00e1 porque el material en las fuentes est\u00e1 bastante desperdigado, sorprendentemente se ha escrito poco sobre la vida comunitaria en la Congregaci\u00f3n de la Misi\u00f3n y en la Compa\u00f1\u00eda de las Hijas de la Caridad.<span id='easy-footnote-1-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-1-14076' title='Esto en manera alguna significa que lo que se ha escrito no tenga valor. Todo lo contrario, ha habido algunos art\u00edculos muy buenos sobre la vida de comunidad. Cf. A. Dodin, \u00abEl nacer de una familia vicenciana: Las Hijas de la Caridad\u00bb en &lt;em&gt;Lecciones sobre Vicencianismo &lt;\/em&gt;(Salamanca: CEME, 1978) 139-160; A. Dodin, \u00abEvoluci\u00f3n de la Vida comunitaria y sus exigencias\u00bb en &lt;em&gt;Vicente de Pa\u00fal, Inspirador de la Vida Comunitaria &lt;\/em&gt;(Salamanca: CEME, 1975) 13\u00ad35; A. Dodin, \u00abLa organizaci\u00f3n y el esp\u00edritu de la Vida Com\u00fan seg\u00fan San Vicente de Pa\u00fal\u00bb en &lt;em&gt;ibid. &lt;\/em&gt;139-160; J. Corera, \u00abLas Reglas o Constituciones de la C.M..\u00bb en &lt;em&gt;Vicente de Pa\u00fal, la Inspiraci\u00f3n Permanente &lt;\/em&gt;(Salamanca: CEME, 1982) 187-216; R. Chalumeau, \u00abLa Vie Commune dans la Companie apr\u00e8s Saint Vincent\u00bb en &lt;em&gt;Bulletin des Lazaristes de France &lt;\/em&gt;(N\u00ba 34, mai 1972) 7-9; J. Corera, \u00abLa Comunidad en las Reglas Comunes\u00bb en &lt;em&gt;Diez Estudios Vicencianos &lt;\/em&gt;(Salamanca: CEME, 1983) 89-106; J. Corera, \u00abIdeas de San Vicente de Pa\u00fal sobre la Autoridad\u00bb en &lt;em&gt;ibid. &lt;\/em&gt;107-128; J. Corera, \u00abBases Econ\u00f3micas de la Comunidad Vicenciana\u00bb en &lt;em&gt;ibid. &lt;\/em&gt;129-157; J. Corera, \u00abLas Hijas de la Caridad no son Religiosas\u00bb en &lt;em&gt;ibid. &lt;\/em&gt;158-184; J. Corera, \u00abEntregadas a Dios para los pobres\u00bb en &lt;em&gt;ibid. &lt;\/em&gt;185-199; M. Lloret, \u00abLa comunidad vicenciana, realidad viva de fe\u00bb en &lt;em&gt;Identidad Vicenciana en un mundo de increencia &lt;\/em&gt;(Salamanca: CEME, 1990) 161-180; J. Morin, \u00abSaint Vincent de Paul et la Communaut\u00e9\u00bb en &lt;em&gt;Bulletin des Lazaristes de France &lt;\/em&gt;(N\u00ba 41, octubre 1973) 46-65); P. Pardi\u00f1as, \u00abDe los Reglamentos a las Constituciones de las Hijas de la Caridad\u00bb en &lt;em&gt;Vicente de Pa\u00fal, la Inspiraci\u00f3n Permanente, op. cit &lt;\/em&gt;277-314; J. Suescun, Vida Fraterna para la Misi\u00f3n\u00bb en &lt;em&gt;Don total para el Servicio &lt;\/em&gt;(Salamanca: CEME, 1982) 153-179; J. Suescun, \u00abLa identidad de las Hijas de la Caridad y los dinamismos comunitarios\u00bb en &lt;em&gt;Identidad de las Hijas de la Caridad en las Constituciones y Estatutos de 1983 &lt;\/em&gt;(Salamanca: CEME, 1984) 115-160; J. Rybolt, \u00abAs &amp;#8216;Good Friends&amp;#8217; Reflections on the Devolopment of the Concept of Fraternal Life in the Congregration of the Mission\u00bb en &lt;em&gt;Vincentiana &lt;\/em&gt;XXXVII (1993) 475-488; M. P\u00e9rez Flores, \u00abIdentidad de la Comunidad Vicenciana\u00bb en &lt;em&gt;Correo Vicentino \u2014Comunidad para la Misi\u00f3n &lt;\/em&gt;Septiembre\/Octubre 1997) 13-18.'><sup>1<\/sup><\/a><\/span>\n<p>Cuando uno examina lo que los fundadores esperaban crear, surgen unos cuantos temas:<\/p>\n<h3><strong>a. una nueva forma de vida, para una misi\u00f3n <\/strong><\/h3>\n<p>Aunque es claro que Vicente, al fundar ambas Compa\u00f1\u00edas, concibi\u00f3 una forma nueva de comunidad, lo que cre\u00f3 de ning\u00fan modo totalmente nuevo. \u00c9l, m\u00e1s bien, espig\u00f3 en la experiencia de la Iglesia los elementos clave adecuados a su proyecto. Como indic\u00f3 Andr\u00e9 Dodin,<span id='easy-footnote-2-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-2-14076' title='Cf. A. Dodin, \u00abLa evoluci\u00f3n de la vida comunitaria y sus exigencias\u00bb en &lt;em&gt;Vicente de Pa\u00fal, Inspirador de la vida comunitaria &lt;\/em&gt;(Salamanca: CEME, 1975) 15-35; \u00abLa organizaci\u00f3n y el esp\u00edritu de la vida com\u00fan seg\u00fan san Vicente de Pa\u00fal\u00bb, &lt;em&gt;ibid. &lt;\/em&gt;141-160; cf. especialmente, 145-150. '><sup>2<\/sup><\/a><\/span>Vicente aprovech\u00f3 la riqueza que le ofrec\u00eda la tradici\u00f3n, modelando un tipo de comunidad que combinaba la estabilidad de los monasterios, el ministerio prof\u00e9tico de los mendicantes, y la contemplaci\u00f3n activa de los Jesuitas. Sus dos Compa\u00f1\u00edas ser\u00edan sociedades apost\u00f3licas. Ambas ser\u00edan comunidades <em>para <\/em>una misi\u00f3n: los Misioneros pondr\u00edan el acento en la predicaci\u00f3n del evangelio a los pobres, pero nunca olvidar\u00edan las obras de caridad; las Hijas de la Caridad pondr\u00edan el acento en la caridad pr\u00e1ctica de cada d\u00eda, pero nunca deb\u00edan olvidar las palabras de fe que condujeran los corazones de los pobres a Dios. Los miembros de ambas comunidades ser\u00edan contemplativos en la acci\u00f3n y ap\u00f3stoles en la oraci\u00f3n. Se dedicar\u00edan a un ministerio prof\u00e9tico.<\/p>\n<p>En el caso de las Hijas de la Caridad, la nueva forma de comunidad que Vicente instituy\u00f3 fue de lo m\u00e1s sorprendente. Vicente, casi por primera vez en la historia de la Iglesia, lanz\u00f3 al mundo un numeroso grupo de mujeres consagradas que no estaban vinculadas al claustro sino a Dios y a los pobres. Las famosas palabras que proclam\u00f3 el 24 de agosto de 1659, describen con una fuerza impresionante la vocaci\u00f3n de las Hijas de la Caridad:<\/p>\n<p style=\"padding-left: 30px\"><em>Tendr\u00e1n presente que no est\u00e1n en una orden religiosa, ya que ese estado no es compatible con las ocupaciones de su vocaci\u00f3n. Sin embargo, como quiera que se ven m\u00e1s expuestas a las ocasiones de pecado que las religiosas obligadas a guardar clausura, no teniendo <\/em><\/p>\n<p style=\"padding-left: 30px\"><em>-por monasterio sino las casas de los enfermos y aquella donde reside la Superiora, <\/em>&#8211;<em>ni m\u00e1s celda que un cuarto de alquiler, -ni m\u00e1s capilla que la iglesia parroquial, -ni m\u00e1s claustro que las calles de la ciudad, -ni m\u00e1s clausura que la obediencia, sin que tengan que ir a otra parte m\u00e1s que a las casas de los enfermos o a los lugares necesarios para su servicio, <\/em>&#8211;<em>ni m\u00e1s rejas que el temor de Dios, <\/em>&#8211;<em>ni m\u00e1s velo que la santa modestia <\/em><\/p>\n<p style=\"padding-left: 30px\"><em>y no haciendo otra profesi\u00f3n para asegurar su vocaci\u00f3n mas que <\/em><\/p>\n<p style=\"padding-left: 30px\"><em>-una constante confianza en la divina Providencia -y la ofrenda que hacen a Dios de todo lo que son -y de su servicio en la persona de los pobres, <\/em><\/p>\n<p style=\"padding-left: 30px\"><em>por todas estas razones, deben tener tanta o m\u00e1s virtud que si fueran profesas en una orden religiosa; por eso, procurar\u00e1n portarse en todos esos lugares al menos con tanta modestia, recogimiento y edificaci\u00f3n como las verdaderas religiosas en su convento<\/em>.<span id='easy-footnote-3-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-3-14076' title='SV X, 66 \/ IX, 1178-1179.'><sup>3<\/sup><\/a><\/span>\n<p>Vicente esperaba lo mejor de los dos mundos. Proclam\u00f3 con fuerza que los Misioneros y las Hijas de la Caridad no eran religiosos, pero quiso que incorporaran en su vida muchos elementos de la vida religiosa. En 1639 escribi\u00f3 a Juana Francisca de Chantal sobre la Congregaci\u00f3n de la Misi\u00f3n:<span id='easy-footnote-4-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-4-14076' title='SV I, 562-563 \/ I, 550-551.'><sup>4<\/sup><\/a><\/span>\n<p><em>Y como desea saber en qu\u00e9 consiste nuestra humilde manera de vivir, le dir\u00e9, mi dign\u00edsima Madre&#8230; que la mayor parte de nosotros hemos hecho los tres votos de pobreza, castidad y obediencia, y un cuarto de dedicarnos, todo el tiempo de nuestra vida a la asistencia del pobre pueblo; &#8230; que practicamos la pobreza y la obediencia y nos esforzamos, por la misericordia de Dios, en vivir religiosamente, aunque no seamos religiosos. <\/em><\/p>\n<h3><strong>b. con profundas ra\u00edces teol\u00f3gicas <\/strong><\/h3>\n<p>Como fundamentos teol\u00f3gicos para la vida comunitaria, Vicente ofrece a sus Compa\u00f1\u00edas tres fuentes principales:<\/p>\n<ol>\n<li><em>La Trinidad. <\/em>\u00c9l habl\u00f3 con frecuencia del misterio de la Sant\u00edsima Trinidad a los Misioneros y a las Hijas de la Caridad. En una reuni\u00f3n del Consejo General de las Hermanas el 19 de junio de 1647, les dijo \u00abque tienen que ser la imagen de la Sant\u00edsima Trinidad, aun cuando sean muchas, sin embargo no tienen que ser m\u00e1s que un solo coraz\u00f3n y una sola alma\u00bb<span id='easy-footnote-5-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-5-14076' title='SV XIII, 633 \/ X, 766.'><sup>5<\/sup><\/a><\/span>. Record\u00f3 a los miembros de la Congregaci\u00f3n de la Misi\u00f3n que la bula de erecci\u00f3n de la misma les obligaba \u00aba venerar de manera especial a la Sant\u00edsima Trinidad\u00bb<span id='easy-footnote-6-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-6-14076' title='RC X, 2.'><sup>6<\/sup><\/a><\/span>. En la conferencia del 23 de mayo de 1659, exhort\u00f3 a sus cohermanos: \u00abManteng\u00e1monos en este esp\u00edritu, si queremos tener en nosotros la imagen de la adorable Trinidad, si queremos tener una santa uni\u00f3n con el Padre, con el Hijo y con el Esp\u00edritu Santo. \u00bfQu\u00e9 es lo que forma esa unidad y esa intimidad en Dios sino la igualdad y la distinci\u00f3n de las tres personas? \u00bfY qu\u00e9 es lo que constituye su amor, sino esa semejanza?\u00bb<span id='easy-footnote-7-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-7-14076' title='SV XII, 256-257 \/ XI, 548-549.'><sup>7<\/sup><\/a><\/span>.<\/li>\n<li><em>El Cuerpo M\u00edstico. <\/em>Vicente ruega a los Misioneros que sean conscientes de que forman un solo cuerpo. Como las partes de un cuerpo est\u00e1n unidas unas con otras estrechamente, esta misma uni\u00f3n debe reinar entre los miembros de la Compa\u00f1\u00eda<span id='easy-footnote-8-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-8-14076' title='SV XI, 120 \/ XI, 44. 9'><sup>8<\/sup><\/a><\/span>. En una conferencia sobre un art\u00edculo de las Reglas Comunes relativo a la caridad,<span id='easy-footnote-9-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-9-14076' title='RC II, 12.'><sup>9<\/sup><\/a><\/span> exclam\u00f3: \u00ab\u00a1C\u00f3mo! \u00a1ser cristiano y ver afligido a un hermano, sin llorar con \u00e9l ni sentirse enfermo con \u00e9l! Eso es no tener caridad; es ser cristiano en pintura; es carecer de humanidad; es ser peor que las bestias\u00bb<span id='easy-footnote-10-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-10-14076' title='SV XII, 271 \/ XI, 561.'><sup>10<\/sup><\/a><\/span>. En el mismo art\u00edculo de las Reglas Comunes, que estaba comentando, presenta una lista de medios altamente evang\u00e9licos para crecer en la caridad que unir\u00eda a los miembros de la Compa\u00f1\u00eda como un cuerpo: 1) tratar a los dem\u00e1s como razonablemente esperar\u00edamos ser tratados por ellos; 2) conformarnos con su parecer y aceptarlo todo en el Se\u00f1or; 3) soportarnos mutuamente sin murmurar; 4) llorar con los que lloran; 5) alegrarse con los que se alegran; 6) darnos precedencia unos a otros; 7) ser amables y ayudarnos unos a otros con toda sinceridad; 8) por fin, hacernos todo a todos para ganarlos a todos para Cristo.<\/li>\n<li><em>La imitaci\u00f3n de los ap\u00f3stoles y de los primeros cristianos. <\/em>Vicente evoca la vida comunitaria y la comuni\u00f3n de bienes que florecieron entre los primeros cristianos<span id='easy-footnote-11-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-11-14076' title='SV XI, 226 \/ XI, 140; cf. RC VIII, 1.'><sup>11<\/sup><\/a><\/span>. Menos de un a\u00f1o antes de su muerte, anim\u00f3 a los Misioneros a alabar y dar gracias a Dios por haberlos colocado en el estado de su Hijo, de los ap\u00f3stoles y de los primeros cristianos, que ten\u00edan todas las cosas en com\u00fan<span id='easy-footnote-12-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-12-14076' title='SV XII, 385 \/ XI, 654; cf. RC III, 1, 3.'><sup>12<\/sup><\/a><\/span>.<\/li>\n<\/ol>\n<h3><strong>c. con apoyos institucionales <\/strong><\/h3>\n<p>En el \u00e1mbito institucional, las Reglas Comunes que Vicente compuso para los sacerdotes y hermanos usan tres mecanismos para crear una estrecha cohesi\u00f3n en las comunidades locales: 1) las relaciones superior s\u00fabdito; 2) la uniformidad; 3) la comuni\u00f3n de bienes<span id='easy-footnote-13-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-13-14076' title='Para el tratamiento de los aspectos institucionales de la comunidad en las Reglas Comunes, debo mucho, qued\u00e1ndole muy agradecido, a Jaime Corera, \u00abLa Congregaci\u00f3n de la Misi\u00f3n: La comunidad en las Reglas Comunes\u00bb en &lt;em&gt;Diez Estudios Vicencianos &lt;\/em&gt;(Salamanca: CEME, 1983) 89-106.'><sup>13<\/sup><\/a><\/span>.<\/p>\n<p>4. Hoy, volviendo la mirada hacia atr\u00e1s, resulta sorprendente el papel tan importante que el superior local ten\u00eda en tiempo de Vicente. En las reglas de la Congregaci\u00f3n de la Misi\u00f3n las relaciones superior-s\u00fabdito aparecen \u00a1en 63 de los 142 art\u00edculos! El superior local interviene directamente en muchos aspectos de la vida diaria<span id='easy-footnote-14-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-14-14076' title='RC V, 11-14; VI, 4; VIII, 5; IX, 5-7, 11-15.'><sup>14<\/sup><\/a><\/span>: en el reparto del trabajo<span id='easy-footnote-15-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-15-14076' title='RC II, 10; V, 8-10; XI, 2-4, 8-11.'><sup>15<\/sup><\/a><\/span>, en la distribuci\u00f3n de los bienes econ\u00f3micos<span id='easy-footnote-16-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-16-14076' title='RC III, 3-6, 9.'><sup>16<\/sup><\/a><\/span>, en la regulaci\u00f3n de asuntos concernientes a la vida espiritual y a\u00fan de conciencia de los s\u00fabditos<span id='easy-footnote-17-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-17-14076' title='RC II, 16-17; IV, 4; VIII, 8; ; X, 8, 11, 13, 15, 21; XII, 4, 9, 14.'><sup>17<\/sup><\/a><\/span>. Pero Vicente reconoci\u00f3 que tales intervenciones de parte de los superiores \u00fanicamente resultar\u00edan eficaces si iban acompa\u00f1adas de una buena comunicaci\u00f3n humana; de lo contrario, podr\u00edan parecer meras intromisiones. El 20 de junio de 1647 dice al Consejo de las Hijas de la Caridad: \u00ab\u00a1Oh Dios m\u00edo! Qu\u00e9 necesario es eso: una gran comunicaci\u00f3n mutua. Eso abarca todas las cosas. No hay nada tan necesario. Eso une los corazones\u00bb<span id='easy-footnote-18-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-18-14076' title='SV XIII, 641 \/ X, 773.'><sup>18<\/sup><\/a><\/span>.<\/p>\n<ol>\n<li>Un segundo mecanismo institucional para crear cohesi\u00f3n dentro de la comunidad era la uniformidad, que Vicente describe como \u00abguardiana del orden y de la uni\u00f3n santa entre nosotros\u00bb<span id='easy-footnote-19-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-19-14076' title='RC II, 11.'><sup>19<\/sup><\/a><\/span>. Vicente pide esta uniformidad en la manera de vestir, en la comida, en las cosas que tienen en la habitaci\u00f3n, as\u00ed como en la manera de dirigir, ense\u00f1ar y predicar, y en las pr\u00e1cticas espirituales. A un lector moderno,<span id='easy-footnote-20-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-20-14076' title='Cf. RC X, 6; VIII, 7-8.'><sup>20<\/sup><\/a><\/span> algunas de estas regulaciones le parecer\u00e1n demasiado detalladas, y hasta r\u00edgidas, ya que hoy hacemos m\u00e1s hincapi\u00e9 en la unidad que en la uniformidad.<\/li>\n<li>Un tercer mecanismo institucional para crear cohesi\u00f3n era la comuni\u00f3n de bienes. \u00abTodas nuestras pertenencias son comunes, cosas tales como la comida, el vestido, los libros, los muebles y dem\u00e1s, y ser\u00e1 el superior quien las distribuya a cada uno seg\u00fan sus necesidades\u00bb<span id='easy-footnote-21-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-21-14076' title='RC III, 3.'><sup>21<\/sup><\/a><\/span>. Para salvaguardar la comuni\u00f3n de bienes, estableci\u00f3 que el superior dar\u00eda a cada cohermano lo que \u00e9ste necesitara. Las llaves personales, con las que uno pudiera cerrar sus pertenencias, estaban prohibidas<span id='easy-footnote-22-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-22-14076' title='RC III, 8.'><sup>22<\/sup><\/a><\/span>. En todo esto, Vicente sinti\u00f3 claramente la influencia de la descripci\u00f3n en los Hechos de los Ap\u00f3stoles de la comunidad ideal cristiana, que \u00abten\u00eda un alma y un coraz\u00f3n, y nadie llamaba propia a ninguna de sus posesiones, sino que lo ten\u00edan todo en com\u00fan\u00bb<span id='easy-footnote-23-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-23-14076' title='Hch 4, 32; Cf. Hch 2, 42-45 y 5, 1-11.'><sup>23<\/sup><\/a><\/span>. En su descripci\u00f3n del voto de pobreza cita expresamente el ejemplo de esta comunidad ideal.<\/li>\n<\/ol>\n<p>A\u00fan haciendo notar los mecanismos institucionales que Vicente puso en las reglas para consolidar la comunidad, es importante no perder de vista el tono evang\u00e9lico que \u00e9l establece, porque \u00e9ste es la clave para entender su visi\u00f3nfundamental de la vida en com\u00fan. \u00c9l piensa en un grupo de personas que viven en comunidad \u00abcomo amigos que se aman unos a otros profundamente\u00bb<span id='easy-footnote-24-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-24-14076' title='RC VIII, 2.'><sup>24<\/sup><\/a><\/span>.<\/p>\n<h2><strong>II. Cambios de horizonte entre los siglos XVII Y XX <\/strong><\/h2>\n<p>He escrito en muchas ocasiones sobre la naturaleza e importancia de los cambios de horizonte. Estos tienen una profunda influencia en nuestra visi\u00f3n de la vida. La vista del mundo desde la cima del Everest es notablemente diferente de la vista desde la profundidad de la plataforma del metro de Londres. La manera de reaccionar, favorable o desfavorable, a un determinado cambio de horizonte nos afecta enormemente e influye en como vemos el mundo a nuestro alrededor<span id='easy-footnote-25-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-25-14076' title='Cf. &lt;em&gt;The way of Vincent de Paul &lt;\/em&gt;(New York: New City Press, 1992) 48-52, 90-96 (en espa\u00f1ol: &lt;em&gt;El camino de Vicente de Pa\u00fal&lt;\/em&gt;, CEME, Salamanca 1993); tambi\u00e9n, &lt;em&gt;He hears the Cry of the Poor &lt;\/em&gt;(New York: New City Press, 1995) 60-63, 83-85 ( en espa\u00f1ol: &lt;em&gt;Escucha el clamor de los pobres, &lt;\/em&gt;CEME, Salamanca 1996).'><sup>25<\/sup><\/a><\/span>. Estos cambios generalmente acontecen gradualmente, hasta sin darnos cuenta de que nuestra manera de ver las cosas est\u00e1 cambiando. Con frecuencia, mirando hacia los a\u00f1os pasados, podemos sorprendernos de c\u00f3mo nuestra visi\u00f3n de la vida ha cambiado. A veces tales cambios en la manera de ver el mundo se dan en unas personas y en otras no. Pero a\u00fan para aquellos cuya perspectiva permanece inalterada, los cambios de horizonte suponen un impacto significativo ya que, estas personas, viven cada vez m\u00e1s en un mundo donde los que les rodean tienen una visi\u00f3n de las cosas desde una perspectiva muy diversa de las suyas.<\/p>\n<p>Tres cambios de horizonte han tenido gran influencia en nuestra manera de contemplar la vida de comunidad.<\/p>\n<h3><strong>1. <em>El cambio de un modelo mon\u00e1rquico de autoridad a uno participativo. <\/em><\/strong><\/h3>\n<p>La <em>Lumen Gentium, <\/em>la <em>Perfectae Caritatis, <\/em>la <em>Ecclesiae Sanctae, <\/em>la <em>Evangelica Testificatio <\/em>y otros muchos documentos han hecho de este cambio algo oficial en el pensamiento de la Iglesia<span id='easy-footnote-26-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-26-14076' title='Cf. &lt;em&gt;Lumen Gentium&lt;\/em&gt; 18-28; &lt;em&gt;Perfectae Caritatis &lt;\/em&gt;14;&lt;em&gt; Ecclesiae Sanctae &lt;\/em&gt;18;&lt;em&gt; Evangelica Testificatio &lt;\/em&gt;25.'><sup>26<\/sup><\/a><\/span>. Las constituciones revisadas de la mayor\u00eda de las Congregaciones r\u00e1pidamente siguieron esa misma l\u00ednea.<\/p>\n<p>Este nuevo paradigma trae consigo nuevas expectativas: el di\u00e1logo, el cuestionar, la participaci\u00f3n en la toma de decisiones, la responsabilidad compartida. Ello pone de relieve que la autoridad sirve a la comunidad y pretende dar atribuciones al grupo y con \u00e9l a la persona.<\/p>\n<p>Pero este cambio de horizonte, a veces, tambi\u00e9n ha originado crisis respecto a la autoridad en la Iglesia y en la sociedad civil. Disentir de la ense\u00f1anza oficial de la Iglesia se ha hecho bastante com\u00fan; por ejemplo, en relaci\u00f3n con el control de la natalidad y otros aspectos de la moral sexual. El descontento civil se ha convertido en la respuesta inevitable a gobiernos que niegan la voz al pueblo respecto a decisiones que afectan a su futuro, desembocando, por ejemplo, en un cambio sorprendentemente r\u00e1pido de la situaci\u00f3n pol\u00edtica en Rusia y en la Europa del Este, y en cierta apertura y alguna opresi\u00f3n renovada en China.<\/p>\n<p>Las comunidades son hoy muy conscientes de los modelos b\u00edblicos de la autoridad, en los que se pone de relieve su naturaleza participativa<span id='easy-footnote-27-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-27-14076' title='Bernard Lee \u00abCommunity\u00bb en &lt;em&gt;The New Dictionary of Catholic Spirituality, &lt;\/em&gt;editado por Michael Downey (Collegeville: Liturgical Press. 1993) 183-192.'><sup>27<\/sup><\/a><\/span>. El modelo del siervo indica con gran fuerza que el l\u00edder procede de la comunidad y ejerce la autoridad como uno de sus miembros, para unirla en la prosecuci\u00f3n de sus objetivos. El l\u00edder-siervo no \u00abse\u00f1orea\u00bb sobre los miembros, sino que trata de promover sus dones, animar su crecimiento espiritual y canalizar sus energ\u00edas hacia los fines apost\u00f3licos del grupo. El modelo-administrador afirma que el l\u00edder no \u00abposee\u00bb la autoridad ni es \u00abpropietario\u00bb de los bienes de la comunidad. Se ponen en sus manos el poder y la responsabilidad sobre las cosas materialescomo un cr\u00e9dito. \u00c9l es responsable, ante Dios y ante la comunidad, de usarlos bien. El modelo-pastor se fija especialmente en la cercan\u00eda del l\u00edder con el grupo. Conoce y ama a los miembros del grupo, llam\u00e1ndolos por su nombre. Se preocupa sinceramente, incluso por los que se han extraviado. Est\u00e1 dispuesto a dar su vida por sus amigos.<\/p>\n<h3><strong>2. <em>Una transici\u00f3n de estructuras universalmente establecidas por ley a unas concertadas por las comunidades locales. <\/em><\/strong><\/h3>\n<p>Durante siglos, las estructuras b\u00e1sicas de la vida de comunidad estaban establecidas por ley para toda la congregaci\u00f3n. Hace cuarenta a\u00f1os, por ejemplo, un visitante, poco importaba que fuera a Roma o a R\u00edo, encontrar\u00eda que, aunque los Misioneros hablaban idiomas diferentes en esos lugares, la forma fundamental de la vida comunitaria era totalmente similar. La comunidad se levantaba a las 5 a.m., se reun\u00eda para la oraci\u00f3n y meditaba por espacio de una hora. A continuaci\u00f3n los sacerdotes probablemente celebraban la Misa en privado, desayunaban, y se dirig\u00edan a sus respectivos apostolados. A mediod\u00eda todos se reun\u00edan para el examen particular, al que segu\u00eda la comida. Por la tarde antes de la cena, rezaban V\u00edsperas y quiz\u00e1 anticipaban el rezo de Maitines. Finalmente, hac\u00edan en comunidad las oraciones de la noche, despu\u00e9s empezaba el gran silencio.<\/p>\n<p>Hoy, \u00e9stas y otras muchas estructuras establecidas por ley para todos han desaparecido. Dentro del marco general de las constituciones, estatutos y normas provinciales, cada comunidad local est\u00e1 llamada a crear las estructuras que concreten los diversos valores de su vida: \u00bfc\u00f3mo realizaremos en esta casa nuestra misi\u00f3n espec\u00edfica vicenciana? \u00bfc\u00f3mo compartiremos la vida cotidiana? \u00bfcu\u00e1ndo y c\u00f3mo oraremos juntos? \u00bfcon qu\u00e9 frecuencia nos reuniremos para dialogar como parte del proceso de toma de decisiones? \u00bfa qu\u00e9 comidas y otros encuentros de \u00abfamilia\u00bb nos vamos a comprometer? En lugar de estructuras universalmente legisladas, se nos pide que elaboremos estructuras <em>concertadas. <\/em><\/p>\n<p>Preguntas como las anteriores proporcionan el marco para algunas de las decisiones que forman el acuerdo formal y serio.<\/p>\n<p>Es evidente que llegar a un compromiso, por medio de proyectos comunitarios, requiere considerable creatividad y responsabilidad en los miembros de la comunidad. No existen ya estructuras detalladas establecidas por ley que nos obliguen desde fuera; nos toca a nosotros crear estructuras que nos obliguen desde dentro. El haber llegado a un acuerdo formal y serio implica que, habiendo creado dichas estructuras, la comunidad se atiene a ellas. La fidelidad al acuerdo formal comunitario es crucial.<\/p>\n<p>Las Constituciones y Estatutos proponen el proyecto comunitario local como el instrumento b\u00e1sico para formular un acuerdo formal y serio. Al mismo tiempo enumera los puntos que deben entrar inevitablemente en dicho acuerdo<span id='easy-footnote-28-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-28-14076' title='C 27: \u00abCada comunidad se esforzar\u00e1 por elaborar su proyecto com\u00fan seg\u00fan las Constituciones, los Estatutos y las Normas Provinciales. Este proyecto se tendr\u00e1 presente en la ordenaci\u00f3n de la vida y del trabajo, en la celebraci\u00f3n de los consejos y en la evaluaci\u00f3n peri\u00f3dica de nuestra vida y actividad\u00bb. E 16: \u00abEl proyecto comunitario que cada comunidad confecciona, en cuanto sea posible al comienzo del a\u00f1o de trabajo, ha de abarcar: la actividad apost\u00f3lica, la oraci\u00f3n, el uso de los bienes, el testimonio cristiano en el lugar de trabajo, la formaci\u00f3n permanente, los tiempos de reflexi\u00f3n comunitaria, el tiempo necesario de esparcimiento y de estudio y el orden del d\u00eda. Todo esto se revisar\u00e1 peri\u00f3dicamente\u00bb.'><sup>28<\/sup><\/a><\/span> as\u00ed como la necesidad de evaluarlo y revisarlo peri\u00f3dicamente.<\/p>\n<p>Muchas comunidades locales elaboran proyectos comunitarios serios, y los observan fielmente. Otras, desafortunadamente, tienen menos \u00e9xito, debati\u00e9ndose con este nuevo instrumento. A veces, el proyecto comunitario es poco m\u00e1s que un orden del d\u00eda. Otras, es principalmente obra del superior local, con la participaci\u00f3n s\u00f3lo superficial de los cohermanos de la casa. Otras, se reduce a ser la misma copia a\u00f1o tras a\u00f1o con escaso esfuerzo de evaluaci\u00f3n y revisi\u00f3n.<\/p>\n<h3><strong>3. <em>Un cambio de una sociedad industrial a una sociedad de la informaci\u00f3n. <\/em><\/strong><\/h3>\n<p>Pocas cosas han influido en la vida comunitaria m\u00e1s profundamente. En m\u00e1s y m\u00e1s pa\u00edses se han hecho omnipresentes la televisi\u00f3n y otros medios de comunicaci\u00f3n. En muchas de nuestras comunidades la TV aparece imponente en la sala de recreo, atrayendo intensamente la atenci\u00f3n de casi todos. Cada vez con m\u00e1s frecuencia, hay cohermanos que tienen aparatos personales de televisi\u00f3n en su habitaci\u00f3n, algunas veces al precio de aislarse del resto de la comunidad. En la \u00faltima d\u00e9cada, los ordenadores han llegado tambi\u00e9n a ocupar un importante lugar en nuestras vidas. Son una ayuda significativa en nuestro apostolado, pero pueden convertirse tambi\u00e9n en un cebo para el aislamiento. En muchas casas el tel\u00e9fono suena constantemente. En algunas partes del mundo tel\u00e9fonos port\u00e1tiles acompa\u00f1an a bastantes cohermanos a dondequiera que vayan. Ha habido cohermanos que han respondido a su tel\u00e9fono port\u00e1til hasta cuando hablaban conmigo en mi habitaci\u00f3n de la Curia General o mientras charlaba con ellos a la mesa en el comedor durante una visita a una provincia.<\/p>\n<p>La r\u00e1pida comunicaci\u00f3n y las interrupciones de la \u00absociedad de la informaci\u00f3n\u00bb contrastan vivamente con la atm\u00f3sfera de las casas de la comunidad de hace tres o cuatro d\u00e9cadas, cuando el silencio, la lectura a la mesa, y el \u00abpronto a la cama, pronto levantarse\u00bb eran factores prominentes en la vida de comunidad.<\/p>\n<p>A la luz de estos cambios de horizonte, puede ser conveniente reflexionar de nuevo sobre los tres mecanismos que San Vicente emple\u00f3 para crear una estrecha cohesi\u00f3n en las comunidades locales.<\/p>\n<ul>\n<li>Ciertamente las relaciones superior-s\u00fabdito han cambiado enormemente en estas \u00faltimas d\u00e9cadas. Sin embargo, el cambio en estas relaciones no es un fen\u00f3meno nuevo. En el curso de la historia de la Iglesia se han dado varios modelos de autoridad. La cuesti\u00f3n clave, cualquiera que sea el <em>modus agendi <\/em>en una \u00e9poca particular, es la sumisi\u00f3n al misterio de la presencia de Dios que nos llega por la mediaci\u00f3n de otros. La Iglesia en su conjunto, y cada comunidad en ella, tiene procesos de toma de decisi\u00f3n, que son caminos para discernir lo que Dios nos est\u00e1 pidiendo en un determinado tiempo. Tales procesos han sido muy variados a lo largo de los siglos. Algunas veces son plenamente democr\u00e1ticos, como en la elecci\u00f3n del Papa y en la de un abad. Otras, han sido totalmente mon\u00e1rquicos, como cuando los pr\u00edncipes-obispos reg\u00edan sus di\u00f3cesis de la misma manera en que gobernaban sus principados. Otras, han sido ampliamente participativos, dejando empero, la \u00faltima decisi\u00f3n en las manos de una sola persona. Hoy seguimos un modelo de autoridad mucho m\u00e1s dialogante que en tiempo de San Vicente.<\/li>\n<li>El lugar de la \u00abuniformidad\u00bb ha cambiado significativamente con la transici\u00f3n de unas estructuras establecidas por ley para todos a unas concertadas por las comunidades locales. Hoy hablamos mucho m\u00e1s de la \u00abunidad en la diversidad\u00bb<span id='easy-footnote-29-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-29-14076' title='Cf. C 22.'><sup>29<\/sup><\/a><\/span>. Las comunidades manifiestan una creciente conciencia de que, en todas las relaciones, se debe tener un profundo respeto por el \u00abirreducible otro\u00bb. Las personas de un grupo no pueden ser fusionadas en una masa en la que sus identidades personales sean irreconocibles; ni nadie debe tratar de absorber o dominar la personalidad de otro. Al comprometernos a un futuro com\u00fan en el Se\u00f1or, los medios evang\u00e9licos propuestos por San Vicente en RC II, 12 (enumerados anteriormente) son esenciales. En el centro de estos medios est\u00e1 el amor genuino al hermano o hermana de la comunidad \u00abcomo a uno mismo\u00bb. En otras palabras, los reconocemos como enteramente iguales a nosotros, como compa\u00f1eros en camino hacia el Se\u00f1or.<\/li>\n<li>El tercer mecanismo de San Vicente para crear una estrecha cohesi\u00f3n, \u00abla comuni\u00f3n de bienes\u00bb, sigue siendo muy importante, a\u00fan considerada desde el cambio de horizontes de la sociedad de la informaci\u00f3n. Las desigualdades materiales en la comunidad siguen creando tensiones. El problema surge, a veces, un tanto dolorosamente en Asia, \u00c1frica y Am\u00e9rica Latina. Cohermanos nacidos en esos pa\u00edses ven que los misioneros que viven y trabajan con ellos hombro con hombro en la comunidad disponen de muchos m\u00e1s recursos econ\u00f3micos que ellos. Este problema, que no es f\u00e1cil de resolver, crea inevitablemente alg\u00fan distanciamiento. Hoy, adem\u00e1s de hablar de la comuni\u00f3n de \u00abbienes\u00bb en el sentido material de los mismos, ponemos de relieve la importancia de otras formas de comuni\u00f3n: compartir nuestro camino, nuestra historia personal, nuestras experiencias espirituales y apost\u00f3licas<span id='easy-footnote-30-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-30-14076' title='C 46.'><sup>30<\/sup><\/a><\/span>. Compartir informaci\u00f3n es tambi\u00e9n vital si todos se han de sentir incluidos en la vida y en las decisiones de la Congregaci\u00f3n. E-mail, que es r\u00e1pido y relativamente barato, est\u00e1 ya jugando un importante papel en este campo.<\/li>\n<\/ul>\n<h2><strong>III. Vida Comunitaria Hoy -algunos modelos <\/strong>\u00ad<\/h2>\n<p>En la mayor\u00eda de los casos, con toda seguridad no podemos volver ahora a las estructuras que dieron forma a la vida comunitaria en una \u00e9poca anterior. La mayor parte de las mismas cumplieron con su fin a su debido tiempo, pero gradualmente se fueron quedando en f\u00f3rmulas sin vida, inflexibles y superadas. Sin embargo, con frecuencia apuntaban a valores de validez perenne: la uni\u00f3n mutua, una perspectiva y vitalidad com\u00fan en el apostolado, la oraci\u00f3n, la penitencia y conversi\u00f3n.<\/p>\n<p>Desaparecidas las antiguas estructuras, a mi juicio, no hemos sabido ofrecer todav\u00eda los medios suficientes para crear comunidades locales que sean plenamente vivas y atractivas a los j\u00f3venes.<\/p>\n<p>En un libro reciente<span id='easy-footnote-31-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-31-14076' title='Robert P. Maloney, &lt;em&gt;Seasons in Spirituality &lt;\/em&gt;(Hyde Park, NY, 1998) 143-150. (En espa\u00f1ol: &lt;em&gt;Espiritualidad para diversos tiempos, &lt;\/em&gt;CEME, Salamanca 1998, 179-189). Cf. tambi\u00e9n, Bernard Lonergan, &lt;em&gt;A Third Collection &lt;\/em&gt;(Mahwah, NJ. 1985) 5-6.'><sup>31<\/sup><\/a><\/span> he tratado con cierta amplitud los diversos niveles en los que se construye la comunidad, subrayando la necesidad de la experiencia com\u00fan, la comprensi\u00f3n com\u00fan, el juicio com\u00fan y la acci\u00f3n com\u00fan. Tambi\u00e9n he descrito los cinco momentos clave de la vida comunitaria: las comidas, la oraci\u00f3n, el esparcimiento, las reuniones y el apostolado.<\/p>\n<p>Dada la complejidad de las relaciones humanas, no debe sorprendernos que la comunidad sea a con frecuencia imperfecta. Si la comunidad es realmente algo hacia lo que debemos trabajar, ello significa que no est\u00e1 en nuestras manos conseguirla de una vez para siempre. Deberemos esforzarnos siempre por crearla. A veces habr\u00e1 altos, otras bajos. Tendremos una comunidad mejor en una casa que en otra, y a\u00fan en la misma casa nos ir\u00e1 mejor en unos aspectos que en otros.<\/p>\n<p>Cuando se considera las grandes diferencias culturales y la variedad de situaciones en las que vive la Congregaci\u00f3n en el mundo entero, es evidente que no se le puede aplicar a toda ella un \u00fanico modelo de comunidad. Es posible, y hasta necesaria, una considerable variedad.<\/p>\n<p>El proyecto comunitario local, preceptuado por nuestras Constituciones y Estatutos,<span id='easy-footnote-32-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-32-14076' title='C 27; E 16.'><sup>32<\/sup><\/a><\/span> permite gran diversidad y creatividad. De hecho, cuando las comunidades locales tratan de concretar las Constituciones y Estatutos en la vida cotidiana dentro del \u00e1mbito de culturas diferentes, surgen muchas formas diversas. A continuaci\u00f3n presento varios modelos, reconociendo que ninguno de ellos existe en una forma pura. Como los colores del espectro, se mezclan unos con otros. Sin duda alguna, son posibles otros muchos modelos intermedios. Con el fin de describir esos modelos m\u00e1s concretamente, les he dado unos nombres, consciente de las limitaciones de tal nomenclatura. Las comunidades mencionadas son ficticias, aunque, como ser\u00e1 obvio para el lector, existen comunidades parecidas.<\/p>\n<h3><strong>1. <em>Un Modelo Tradicional Modificado <\/em><\/strong><\/h3>\n<p>La casa de San Juan Gabriel, como muchas casas provinciales, es una comunidad local numerosa. Adem\u00e1s de los miembros de la administraci\u00f3n provincial, residen en ella otros muchos cohermanos, incluido un peque\u00f1o equipo de misiones, 15 sacerdotes y hermanos ancianos que siguen prestando sus servicios generosamente seg\u00fan sus capacidades, y ocho miembros de la provincia enfermos, que necesitan cuidados continuos.<\/p>\n<p>El orden del d\u00eda en la casa es bastante tradicional, acomodado a los tiempos. La oraci\u00f3n de la ma\u00f1ana empieza a las 6:30, seguida de media hora de meditaci\u00f3n en com\u00fan y de la Eucarist\u00eda concelebrada. Un cohermano es asignado cada semana para animar la oraci\u00f3n de la ma\u00f1ana y de la tarde: escoge los himnos y diversas maneras de recitar los salmos, siguiendo la \u00abInstrucci\u00f3n General de la Liturgia de las Horas\u00bb.<span id='easy-footnote-33-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-33-14076' title='\u00abGeneral Instruction of the Liturgy of Hours\u00bb en &lt;em&gt;Documents on the Liturgy, 1963-1979: Conciliar, Papal and Curial Texts &lt;\/em&gt;(Collegeville, 1982) 426 nos. 3431-2714).'><sup>33<\/sup><\/a><\/span> Otro cohermano anima la Eucarist\u00eda concelebrada diariamente.<\/p>\n<p>El desayuno es a las 7:45. A continuaci\u00f3n, la mayor\u00eda de los cohermanos van a sus respectivos trabajos.<\/p>\n<p>A las 12: 30, se sirve la comida, a la que precede el examen particular. A la comida sigue una media hora de recreo en com\u00fan. Despu\u00e9s, algunos cohermanos descansan; otros se emplean en diversos apostolados.<\/p>\n<p>A las 6:40 de la tarde, la comunidad recita las V\u00edsperas, a las que sigue un breve examen. La mayor\u00eda est\u00e1n presentes para la cena a las 7:00. El equipo de misiones, por supuesto, frecuentemente est\u00e1 fuera misionando.<\/p>\n<p>Una vez al mes, el superior organiza una reuni\u00f3n de la comunidad, presentando una agenda el d\u00eda anterior despu\u00e9s de haber pedido puntos y sugerencias a los cohermanos. En la reuni\u00f3n dialogan sobre los principales asuntos que afectan a la vida y apostolados de la casa. Cuatro veces al a\u00f1o, un s\u00e1bado por la ma\u00f1ana, los cohermanos tienen medio d\u00eda de retiro. Anualmente, todos hacen cinco d\u00edas de Ejercicios Espirituales, habiendo invitado a un cohermano de la provincia a dirigirlos.<\/p>\n<p>En una comunidad numerosa, como la de San Juan Gabriel, el superior tiene que tomar muchas decisiones. Lo hace con la ayuda de un reducido consejo, nombrado por el Visitador<span id='easy-footnote-34-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-34-14076' title='Cf. C 134, 2.'><sup>34<\/sup><\/a><\/span>. Al menos una vez al a\u00f1o tiene un encuentro con cada uno de los cohermanos de la casa (la \u00abcomunicaci\u00f3n\u00bb).<\/p>\n<p>Los Visitadores han descubierto que necesitan un administrador bastante bueno para hacer que la casa marche bien. La experiencia ha ense\u00f1ado que cuando las cosas quedan sin hacer, los cohermanos se desazonan bastante. Por otra parte, los cohermanos tienen una amplia experiencia de vida com\u00fan y se han adaptado, razonablemente bien, a muchos cambios a lo largo de los a\u00f1os.<\/p>\n<h3><strong>2. <em>Un Modelo \u00abBurbujeante desde el Fondo\u00bb <\/em><\/strong><\/h3>\n<p>Ocho cohermanos viven en la comunidad del Colegio \u00abFederico Ozanam\u00bb, situado en un barrio muy pobre. Un \u00fanico apostolado unifica sus actividades, aunque, naturalmente, todos se ocupan en algunos otros ministerios en la medida que el tiempo se lo permite. Como todos los cohermanos trabajan en el colegio, pasan mucho tiempo juntos. El P. Juan, que es el director del colegio, aunque no es el superior de la comunidad, tiene una reuni\u00f3n a la semana para discutir los asuntos principales del colegio. Adem\u00e1s de los cohermanos, asisten a la reuni\u00f3n diez profesores seglares. El superior, P. Jorge, trabaja en \u00edntima colaboraci\u00f3n con el P. Juan. Tiene la convicci\u00f3n de que para que la comunidad permanezca verdaderamente unida, todos deben corresponsabilizarse de la vida de la misma. Los convoca dos veces a la semana para una reuni\u00f3n de comunidad en la que se discuten los asuntos principales (y otros no tanto, tambi\u00e9n), tomando las decisiones correspondientes. Todos los cohermanos, que participan en estas reuniones, forman el \u00abconsejo dom\u00e9stico\u00bb<span id='easy-footnote-35-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-35-14076' title='Cf. E 79.'><sup>35<\/sup><\/a><\/span>. Todos pueden presentar libremente asuntos para la agenda, que Jorge prepara y entrega el d\u00eda previo a la reuni\u00f3n.<\/p>\n<p>Los cohermanos celebran la oraci\u00f3n de la ma\u00f1ana a las 7:00, seguida de la oraci\u00f3n mental. Uno de ellos se encarga cada d\u00eda de preparar cuidadosamente este tiempo de oraci\u00f3n, con m\u00fasica, s\u00edmbolos, diversas maneras de recitar los salmos, y esmerada selecci\u00f3n de lecturas, que algunas veces son \u00abvicencianas\u00bb. Dos veces a la semana, durante la meditaci\u00f3n, existe la posibilidad de un intercambio espiritual espont\u00e1neo.<\/p>\n<p>Despu\u00e9s del desayuno, todos van a sus clases o a sus responsabilidades administrativas en el colegio. El P. Juan, respondiendo a una sugerencia del P. Jorge, ha dispuesto el plan escolar de manera que la mayor\u00eda de los cohermanos quede libre por la tarde para la concelebraci\u00f3n de la Eucarist\u00eda. Bastantes estudiantes participan libremente en esta celebraci\u00f3n, que est\u00e1 muy bien preparada por un peque\u00f1o equipo de liturgia del colegio.<\/p>\n<p>La comida es r\u00e1pida e informal, pues todos tienen que estar de nuevo en las clases o en el despacho a las 1:15 p.m. No disponen de cocinero a mediod\u00eda.<\/p>\n<p>Las clases terminan a las 3:20, pero las actividades extra escolares retienen a casi todos los cohermanos en el colegio por lo menos hasta las 5:00. A las 6:00 se re\u00fanen para V\u00edsperas, que preparan por turno. Sigue un breve examen, variado en la forma, y despu\u00e9s la cena. Como la comida es tan r\u00e1pida e informal, los cohermanos se han propuesto esforzarse por estar presentes regularmente en la cena. Al no ser esto posible siempre, se han comprometido firmemente a dos tardes \u00abinviolables\u00bb.<\/p>\n<p>Despu\u00e9s de la cena, hay m\u00e1s actividades escolares, pero todos se re\u00fanen alrededor de las 9:30 p.m. para un tiempo de recreo juntos. Una vez a la semana ven juntos un film en video, discuti\u00e9ndolo despu\u00e9s, al mismo tiempo que gozan de unos refrescos. Un miembro de la comunidad se encarga de esto, preguntando a los dem\u00e1s antes de la elecci\u00f3n del film.<\/p>\n<p>Los cohermanos hacen juntos un retiro anual de cinco d\u00edas fuera de casa, ordinariamente en el seminario local o en una casa de ejercicios. Dos veces al semestre, un s\u00e1bado por la ma\u00f1ana, hacen el retiro espiritual, con mucho tiempo para la meditaci\u00f3n y para el intercambio espiritual.<\/p>\n<p>Han convenido en que cuatro veces al a\u00f1o leer\u00e1n todos y discutir\u00e1n el mismo libro, un jueves por la tarde, como ayuda para su propia formaci\u00f3n permanente. Eligen el libro en uno de los consejos dom\u00e9sticos, se hacen con ejemplares, y por turno dirigen la discusi\u00f3n.<\/p>\n<p>El P. Jorge se re\u00fane con cada cohermano dos veces al a\u00f1o en una comunicaci\u00f3n informal con el fin de ver c\u00f3mo le va a cada uno.<\/p>\n<h3><strong>3. <em>Un Modelo de Peque\u00f1a Comunidad <\/em><\/strong><\/h3>\n<p>Tres cohermanos viven en la parroquia de San Justino. Como las misas de la ma\u00f1ana son a las 8:00 y 9:00 y la de la tarde a las 6:00, han convenido en reunirse para Laudes y meditaci\u00f3n a las 7:00. El lunes, en la meditaci\u00f3n, leen y meditan las lecturas del domingo siguiente. Han visto que esto les ayuda a comenzar la preparaci\u00f3n de la homil\u00eda del domingo.<\/p>\n<p>Cada uno celebra una de las misas de la parroquia. El desayuno es informal, ya que todos est\u00e1n desde muy pronto ocupados con las misas y la atenci\u00f3n a los feligreses. Al tener cada uno un d\u00eda libre a la semana, seg\u00fan el proyecto comunitario, a menudo se sustituyen mutuamente en la celebraci\u00f3n de las misas.<\/p>\n<p>Tienen juntos la comida, que es la principal del d\u00eda, a las 12:30. Casi siempre est\u00e1n presentes los tres. Las ma\u00f1anas y las tardes est\u00e1n ocupadas con una amplia variedad de actividades: visita a los feligreses, orientaci\u00f3n pastoral personal, ocasionalmente clases en la escuela parroquial, reuniones con diversos grupos de oraci\u00f3n, organizaci\u00f3n y acompa\u00f1amiento de las asociaciones parroquiales en su asistencia a los pobres.<\/p>\n<p>Los cohermanos intentan cenar juntos alrededor de las 7:00. Es un tanto r\u00e1pida e informal (no tienen cocinero por la tarde), pues enseguida hay muchas reuniones parroquiales, y , a veces, visitas a las familias. Todos se esfuerzan por estar de vuelta alrededor de las 10:00 p.m. para un rato de relajaci\u00f3n, acompa\u00f1ado ordinariamente con un bocadillo. Rezan completas juntos a las 10:45.<\/p>\n<p>Hacen los Ejercicios Espirituales en tiempo diferente cada uno, ordinariamente con los miembros de otras casas de la provincia o, a veces, con el clero diocesano de la misma ciudad. Participan tambi\u00e9n con otros sacerdotes de parroquia en algunos de los programas de formaci\u00f3n permanente que ofrece la di\u00f3cesis. Adem\u00e1s de esto, han convenido con los Franciscanos de la parroquia vecina pasar una tarde juntos, una vez al mes, en formaci\u00f3n permanente. En esa reuni\u00f3n, discuten un tema pastoral-teol\u00f3gico, habi\u00e9ndolo preparado previamente con lecturas apropiadas y con los puntos para la discusi\u00f3n.<\/p>\n<p>El P. Juan es el superior y el p\u00e1rroco. Aunque esta peque\u00f1a comunidad se halla frecuentemente junta, el superior organiza una reuni\u00f3n formal a la semana en la que \u00e9l y los PP. Santiago y Federico discuten los principales puntos en su vida y ministerios, tomando las decisiones correspondientes.<\/p>\n<h3><strong>4. <em>Un Modelo de Comunidad Dispersa <\/em><\/strong><\/h3>\n<p>La comunidad del Beato Francisco R\u00e9gis Clet est\u00e1 situada en una extensa \u00e1rea misionera confiada a la Congregaci\u00f3n de la Misi\u00f3n. La comunidad est\u00e1 compuesta por once cohermanos, aunque, de hecho, residen en siete pueblos diferentes. En cuatro de los pueblos viven dos cohermanos juntos; en los otros tres uno. Algunos viven bastante cerca de la casa-centro, en la que reside el superior; otros est\u00e1n a m\u00e1s de 50 kil\u00f3metros por carretera, carreteras de monta\u00f1a sin pavimentar, llenas de baches, que en la estaci\u00f3n de lluvias son dif\u00edciles de transitar. En el proyecto comunitario se han comprometido seriamente a reunirse todos los lunes. Hoy es raro que alguno falte. En el pasado, la tendencia al empe\u00f1o excesivo en el trabajo manten\u00eda a algunos cohermanos lejos, pero la comunidad se ha mantenido firme en insistir en la fidelidad al compromiso com\u00fan de asistir.<\/p>\n<p>El orden del d\u00eda los lunes var\u00eda algo, pero en general los cohermanos oran juntos por la ma\u00f1ana y comparten su fe ya sea despu\u00e9s de la meditaci\u00f3n o en la Eucarist\u00eda concelebrada. Normalmente tienen una reuni\u00f3n cuyo tema es a veces sobre el proyecto apost\u00f3lico, otras veces sobre formaci\u00f3n permanente, a veces sobre la elaboraci\u00f3n o evaluaci\u00f3n del proyecto comunitario, o para tratar asuntos provinciales, consultas, preparaci\u00f3n de Asambleas, etc.<\/p>\n<p>Los cohermanos comen juntos a mediod\u00eda y dedican el resto de la jornada al descanso y recreo juntos. Confiesan que, despu\u00e9s de una semana plena de ocupaciones, esperan con gozo la oportunidad de descansar y disfrutar de la compa\u00f1\u00eda de los dem\u00e1s. Su recreaci\u00f3n var\u00eda. Algunas veces, un grupo hace deporte. Otras, ven la televisi\u00f3n. Otras, nadan en el mar, que no est\u00e1 lejos. Algunos pasean. Otros juegan a las cartas. Otros se ejercitan en los ordenadores.<\/p>\n<p>El superior local, P. Eduardo, se re\u00fane con cada cohermano cuatro veces al a\u00f1o, algunas veces en los pueblos, otras en la casa-centro. Como los cohermanos se hallan tan dispersos, considera importante sentarse con ellos personalmente con bastante frecuencia y discutir lo que va surgiendo en sus vidas y trabajo.<\/p>\n<p>Una vez al a\u00f1o los cohermanos se re\u00fanen durante cinco d\u00edas para hacer el retiro anual juntos, habiendo invitado a un cohermano de fuera de la misi\u00f3n para que lo dirija. Este retiro tiene lugar ordinariamente en las monta\u00f1as en el l\u00edmite de la misi\u00f3n, donde hay un monasterio Trapense.<\/p>\n<p>Aunque viven en diferentes lugares, los cohermanos tratan de ayudarse mutuamente con la oraci\u00f3n diaria. Reconociendo el peligro del aislamiento, han elaborado juntos un ritmo de oraci\u00f3n que todos intentan seguir, vivan solos o con otros, aunque naturalmente ese ritmo, a veces, debe acomodarse a las cambiantes circunstancias, como las exigencias apost\u00f3licas o los horarios de misas. Los cohermanos confiesan que, en general, est\u00e1n siendo capaces de observar este programa que incluye la oraci\u00f3n de Laudes m\u00e1s media hora de meditaci\u00f3n, empezando a las 6:30 de la ma\u00f1ana y la oraci\u00f3n de V\u00edsperas al atardecer antes de la cena, que ordinariamente toman de vuelta a casa en sus pueblos. La mayor parte del resto del d\u00eda lo pasan yendo a las diversas lugares de la misi\u00f3n, celebrando la misa all\u00ed, visitando a la gente y preparando dirigentes laicos. En esta extensa zona misional hay casi 300 aldeas.<\/p>\n<p>\u00c9stos son cuatro modelos. Animo al lector a crear otros. Sin duda que hay muchas posibilidades.<\/p>\n<h2><strong>IV. Amarse unos a otros profundamente <\/strong><\/h2>\n<p>El desaf\u00edo en cada modelo es, por supuesto, ser \u00abamigos que se aman unos a otros profundamente\u00bb<span id='easy-footnote-36-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-36-14076' title='RC VIII, 2.'><sup>36<\/sup><\/a><\/span>. Esto es una parte esencial del compromiso mutuo y con el Se\u00f1or al entrar en la comunidad vicenciana. En este sentido presento aqu\u00ed unas cuantas sugerencias. Se podr\u00eda escribir mucho m\u00e1s. En este art\u00edculo estoy meramente \u00abdelimitando el terreno\u00bb. Animo a otros a desarrollarlo.<\/p>\n<p>Es un error yuxtaponer la comunidad y la misi\u00f3n. Es claro que en una sociedad apost\u00f3lica, nuestra santidad est\u00e1 unida intr\u00ednsecamente con nuestra misi\u00f3n apost\u00f3lica. Pero es tambi\u00e9n claro que el crecimiento en la vida de Dios y en la misi\u00f3n recibimos tambi\u00e9n fuerza de los lazos de una profunda caridad forjada entre nosotros en la comunidad.<\/p>\n<p>En estos \u00faltimos a\u00f1os la obra de arte en el hermoso tr\u00edptico de Kurt Welther pintado para la Capilla de la Merced en la Parroquia de San Vicente en Graz se ha hecho muy popular. La usamos como cubierta del documento final de la 39 Asamblea de la Congregaci\u00f3n de la Misi\u00f3n. Apareci\u00f3 en nuestra p\u00e1gina web de internet durante toda la Asamblea, y posteriormente ha ilustrado la portada de muchas de nuestras publicaciones vicencianas. En el cuadro, Vicente est\u00e1 sentado entre los pobres como uno de ellos. Un rostro, resplandeciente desde el centro de la mesa, refleja la presencia de Cristo. Este cuadro nos evoca la Ultima Cena, el banquete sacramental del amor de Dios para su pueblo.<\/p>\n<p>Este cuadro, \u00bfno nos dice tambi\u00e9n algo sobre la vida de comunidad? \u00bfEn realidad, no debemos reunirnos alrededor de la mesa en profunda comuni\u00f3n con el Se\u00f1or y unos con otros, justamente como esperamos reunirnos con los pobres? En el evangelio de Marcos, Jes\u00fas elige a los doce tanto \u00abpara que estuvieran con \u00e9l\u00bb como \u00abpara enviarlos a predicar\u00bb (Mc 3, 14-15). En \u00faltimo t\u00e9rmino, la comuni\u00f3n es el objetivo de la misi\u00f3n de Jes\u00fas, y las comunidades en armon\u00eda son un signo vivo de que esta misi\u00f3n se est\u00e1 haciendo realidad. Por esa raz\u00f3n la exhortaci\u00f3n apost\u00f3lica <em>Vita Consecrata <\/em>afirma que la Iglesia necesita urgentemente comunidades \u00edntimamente unidas, que por \u00absu misma existencia contribuyan a la nueva evangelizaci\u00f3n, ya que muestran de manera fehaciente y concreta los frutos del &#8216;mandamiento nuevo'\u00bb<span id='easy-footnote-37-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-37-14076' title='&lt;em&gt;Vita Consecrata, &lt;\/em&gt;45.'><sup>37<\/sup><\/a><\/span>. A esa luz, pienso que hay dos verdades complementarias respecto a la comunidad y misi\u00f3n.<\/p>\n<p>\u00abLa comunidad es para la misi\u00f3n\u00bb expresa con fuerza que nuestra Comunidad Vicenciana, como las otras sociedades apost\u00f3licas, naci\u00f3 para servir a un particular fin apost\u00f3lico urgente. Todas nuestras decisiones fundamentales tienen que hacerse a la luz de tal fin. M\u00e1s a\u00fan, las estructuras de la vida comunitaria han de mantenerse siempre flexibles, de manera que podamos responder a las necesidades urgentes de aquellos a quienes servimos<span id='easy-footnote-38-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-38-14076' title='San Vicente acostumbraba expresar este concepto, especialmente a las Hijas de la Caridad, dici\u00e9ndoles que ten\u00edamos que sentirnos libres para \u00abdejar a Dios por Dios\u00bb.'><sup>38<\/sup><\/a><\/span>. Pero nuestras estructuras comunitarias no ha de ser tan flexibles que lleguen a hundirse. Nuestro objetivo vicenciano de profunda comuni\u00f3n con el pobre se realizar\u00e1 de manera \u00f3ptima cuando vivamos en profunda comuni\u00f3n unos con otros en el Se\u00f1or.<\/p>\n<p>\u00abLa comunidad es una parte integral de la misi\u00f3n\u00bb pone de relieve que la comunidad no es \u00fanicamente un medio para un fin: tiene un valor en s\u00ed misma. La comunidad refleja y alimenta nuestra naturaleza como personas humanas y, en el contexto cristiano, es el lugar para la irrupci\u00f3n de la Palabra de Dios. Una comunidad determinada realiza en un lugar y tiempo una manera concreta de ser Iglesia. Es una de la muchas c\u00e9lulas vivientes que componen la m\u00e1s amplia comunidad cristiana. Por supuesto, estas comunidades determinadas deben trabajar siempre por reforzar los lazos con la comunidad m\u00e1s amplia, de lo contrario, corren el riesgo de cerrarse y quedar absorbidas por s\u00ed mismas<span id='easy-footnote-39-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-39-14076' title='Cf. &lt;em&gt;F.A.B.C. Papers, &lt;\/em&gt;# 83: \u00abCommunion and solidarity: A New Way of Being Church in Asia, a Colloquium on the Church in Asia in the 21st Century\u00bb (F.A.B.C., 16 Caine Road, Hong Kong) 7. &lt;em&gt;F.A.B.C.. Papers &lt;\/em&gt;es un proyecto de la Federaci\u00f3n de las Conferencias de Obispos de Asia.'><sup>39<\/sup><\/a><\/span>.<\/p>\n<p>En otras palabras, como en todas las proposiciones verdaderas, \u00abla comunidad es para la misi\u00f3n\u00bb es parte de un conjunto m\u00e1s amplio de verdades. S\u00f3lo dentro de ese conjunto m\u00e1s amplio puede ella entenderse adecuadamente. Sin duda es cierto que San Vicente fund\u00f3 la Congregaci\u00f3n <em>para <\/em>la misi\u00f3n. Pero cuando se exagera esta proposici\u00f3n, caemos en la trampa de usar un modelo de trabajo para entender la comunidad. En ese modelo, la casa de una comunidad local f\u00e1cilmente degenera en un hotel o se convierte en una gasolinera donde llenamos el dep\u00f3sito para el viaje del d\u00eda siguiente o cargamos nuestras pilas para seguir trabajando.<\/p>\n<p>\u00bfC\u00f3mo podemos fomentar nuestra comuni\u00f3n mutua, o nuestro vivir \u00abcomo amigos que se aman unos a otros profundamente\u00bb? Como conclusi\u00f3n de este largo art\u00edculo sugiero lo siguiente:<\/p>\n<p>Para que una comunidad sea verdaderamente viva<span id='easy-footnote-40-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-40-14076' title='Una de las razones sociol\u00f3gicas por las que las personas ingresan en las comunidades es la b\u00fasqueda de la satisfacci\u00f3n de ciertas necesidades b\u00e1sicas humanas que toda persona tiene: e.g., suficientes bienes de vida, identidad personal, intimidad, solidaridad y participaci\u00f3n, engendramiento, realizaci\u00f3n. Estas necesidades no pueden ser satisfechas plenamente por la &lt;em&gt;sola &lt;\/em&gt;vida de comunidad, pero la comunidad debe jugar un papel significativo en afrontarlas. Para una muy l\u00facida e interesante discusi\u00f3n de esta cuesti\u00f3n, cf. Sandra Schneiders, &lt;em&gt;New Wineskins &lt;\/em&gt;New York: Paulist Press, 1986) 255-263.'><sup>40<\/sup><\/a><\/span>, debemos crear:<\/p>\n<ol>\n<li>un lugar de experiencia com\u00fan, donde todos hayan compartido una sana formaci\u00f3n inicial, actos simb\u00f3licos de iniciaci\u00f3n e incorporaci\u00f3n, y una formaci\u00f3n permanente bien estructurada.<\/li>\n<li>un lugar de vida compartida, inter\u00e9s mutuo y perd\u00f3n;<\/li>\n<li>un lugar de bienes compartidos, alegr\u00edas compartidas, sufrimientos compartidos, oraci\u00f3n compartida, silencio compartido;<\/li>\n<li>un lugar donde se comparten la experiencia, los frutos, las esperanzas y los miedos de la vida apost\u00f3lica;<\/li>\n<li>un lugar donde descansamos juntos, comemos juntos, y gozamos de la compa\u00f1\u00eda mutua;<\/li>\n<li>un lugar de ayuda mutua, tanto en el apostolado como en las otras muchas cosas diarias que afectan la vida en com\u00fan;<\/li>\n<li>un lugar donde gozamos de libertad personal y de iniciativa, pero donde, al mismo tiempo, estamos profundamente comprometidos con el bien com\u00fan de los cohermanos y nuestra misi\u00f3n apost\u00f3lica;<\/li>\n<li>un lugar impregnado por el amor afectivo y efectivo de unos para con otros y por toda la Congregaci\u00f3n;<\/li>\n<li>un lugar donde cada uno de nosotros pueda decir con el Se\u00f1or, como una comunidad Eucar\u00edstica, \u00abEste es mi cuerpo que ser\u00e1 entregado <em>por <\/em>vosotros\u00bb.<\/li>\n<\/ol>\n<p>Dietrich Bonhoeffer, que muri\u00f3 m\u00e1rtir en un campo de concentraci\u00f3n Nazi al final de la Segunda Guerra Mundial, escribi\u00f3 lo siguiente acerca de la comunidad:<\/p>\n<p><em>Entre la muerte de Cristo y el \u00daltimo D\u00eda es solo por la gracia de una anticipaci\u00f3n de las \u00faltimas realidades el que los cristianos tengan el privilegio de vivir en visible comuni\u00f3n con otros cristianos. Es por la gracia de Dios por lo que una comunidad puede reunirse visiblemente en este mundo para compartir la palabra de Dios y el sacramento. No todos los cristianos reciben esta bendici\u00f3n. El prisionero, el enfermo, los solitarios dispersos, los anunciadores del evangelio en tierras de gentiles se encuentran solos. Ellos saben que la comuni\u00f3n visible es una bendici\u00f3n. Recuerdan, como el Salmista, c\u00f3mo iban \u00abcon la multitud&#8230; a la casa de Dios, con cantos de j\u00fabilo y loa\u00bb (Sal 42, 4).<\/em><span id='easy-footnote-41-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-41-14076' title='Dietrich Bonhoeffer, &lt;em&gt;Life Together &lt;\/em&gt;(London: SCM Press, 1954) 8.'><sup>41<\/sup><\/a><\/span>\n<p>Hablamos hoy de la necesidad de \u00abconcertar\u00bb, de \u00abconstruir comunidad\u00bb,<span id='easy-footnote-42-14076' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#easy-footnote-bottom-42-14076' title='Cf. un art\u00edculo muy interesante de John Rybolt \u00abAs &amp;#8216;Good Friends&amp;#8217; Reflections on the Development of the Concept of Fraternal Life in the Congregati\u00f3n of the Mission\u00bb en &lt;em&gt;Vincentiana XXXVII &lt;\/em&gt;(1993): 475\u00ad488; esp. 481.'><sup>42<\/sup><\/a><\/span> de formar comunidades \u00abde intenci\u00f3n \u00bb cuyos miembros dicen \u00abs\u00ed\u00bb a las exigencias de la pertenencia al mismo tiempo que ayudan a formularlas. Construir tales comunidades requiere tiempo, energ\u00eda, participaci\u00f3n y responsable realizaci\u00f3n. Si en una \u00e9poca anterior la mayor\u00eda de las estructuras estaban legisladas y lo que hab\u00eda que hacer era adaptarse a ellas, hoy nos enfrentamos con el reto de <em>crear <\/em>estructuras para las comunidades locales que nos ayuden a vivir juntos \u00abcomo amigos que se aman unos a otra profundamente\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Vaticano II las dos comunidades fundadas por San Vicente han experimentado grandes cambios. Ambas han re-elaborado totalmente sus constituciones y estatutos, y su proceso de toma de decisiones es mucho m\u00e1s participativo. Casi &#8230; <a href=\"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":400152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[172],"class_list":["post-14076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Desde el Vaticano II las dos comunidades fundadas por San Vicente han experimentado grandes cambios. Ambas han re-elaborado totalmente sus constituciones y estatutos, y su proceso de toma de decisiones es mucho m\u00e1s participativo. Casi ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-25T05:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"45 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy\",\"datePublished\":\"2021-08-25T05:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/\"},\"wordCount\":9035,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/10\\\/ranquines.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/\",\"name\":\"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/10\\\/ranquines.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2021-08-25T05:50:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/10\\\/ranquines.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/10\\\/ranquines.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/","og_locale":"es_ES","og_type":"article","og_title":"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy - Somos Vicencianos","og_description":"Desde el Vaticano II las dos comunidades fundadas por San Vicente han experimentado grandes cambios. Ambas han re-elaborado totalmente sus constituciones y estatutos, y su proceso de toma de decisiones es mucho m\u00e1s participativo. Casi ... Read More","og_url":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2021-08-25T05:50:05+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"45 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy","datePublished":"2021-08-25T05:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/"},"wordCount":9035,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1","keywords":["Pobreza"],"articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/","url":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/","name":"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1","datePublished":"2021-08-25T05:50:05+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/como-amigos-que-se-aman-profundamente-reflexiones-sobre-la-vida-de-comunidad-ayer-y-hoy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Como amigos que se aman profundamente. Reflexiones sobre la vida de comunidad ayer y hoy"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-3F2","jetpack-related-posts":[{"id":116383,"url":"https:\/\/vincentians.com\/es\/bibliografia-vicenciana-1960-1970-en-torno-a-la-espiritualidad-de-san-vicente\/","url_meta":{"origin":14076,"position":0},"title":"Bibliograf\u00eda Vicenciana 1960-1970 en torno a la espiritualidad de San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2021","format":false,"excerpt":"Lo que antes se llamaba Asc\u00e9tica y M\u00edstica, hoy se llama com\u00fanmen\u00adte Espiritualidad. Es una palabra tra\u00edda de Francia, como tantas otras, que tambi\u00e9n han hecho fortuna, m\u00e1s por moda que por convencimiento. As\u00ed se bautizan los tratados de Historia, desde Pourrat (1926) hasta Bouyer-Vandenbroucke (1963). El recomendar tan insistentemente\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":122934,"url":"https:\/\/vincentians.com\/es\/introduccion-a-la-espiritualidad-vicenciana-laical\/","url_meta":{"origin":14076,"position":1},"title":"Introducci\u00f3n a la espiritualidad vicenciana laical","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/06\/2015","format":false,"excerpt":"1. Lo que pretendo De momento, en este trabajo, no pretendo ofre\u00adcer un tratado perfecto y acabado de la espiritua\u00adlidad vicenciana laical, sino m\u00e1s bien asentar unos principios a modo de introducci\u00f3n. El pro\u00adyecto es ofrecer algunos criterios que puedan ayudar al laico vicenciano a vivir su condici\u00f3n de cristiano,\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"sanvi_famvi","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2010\/12\/sanvi_famvi-300x296.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":117130,"url":"https:\/\/vincentians.com\/es\/elaboracion-del-proyecto-provincial\/","url_meta":{"origin":14076,"position":2},"title":"Elaboraci\u00f3n del Proyecto Provincial","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/10\/2018","format":false,"excerpt":"Elaboraci\u00f3n del Proyecto Provincial La elaboraci\u00f3n tiene diversas fases desde la concepci\u00f3n hasta la ejecuci\u00f3n. El proyecto como tal debe comprometer a todos los miembros de la provincia. Es de capital importancia que todos los coher\u00admanos, de una manera o de otra, participen en su elaboraci\u00f3n en todas las etapas.\u2026","rel":"","context":"En \u00abDocumentos de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Documentos de la Congregaci\u00f3n de la Misi\u00f3n","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/documentos-oficiales-de-la-familia-vicenciana\/documentos-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":131925,"url":"https:\/\/vincentians.com\/es\/interesados-en-conocer-el-espiritu-de-la-congregacion\/","url_meta":{"origin":14076,"position":3},"title":"Interesados en conocer el esp\u00edritu de la Congregaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/08\/2019","format":false,"excerpt":"\"Todo letrado que entiende del reinado de Dios se paree a un padre de familia que saca de su arc\u00f3n cosas nuevas y antiguas\". (Mt 13,52). \"Todos se afanar\u00e1n siempre por conocer m\u00e1s profundamente este esp\u00edritu, volviendo al Evangelio, al ejemplo de San Vicente y a su doctrina, en la\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/ranquines.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":116979,"url":"https:\/\/vincentians.com\/es\/espiritualidad-vicenciana-y-renovacion-conciliar\/","url_meta":{"origin":14076,"position":4},"title":"Espiritualidad vicenciana y renovaci\u00f3n conciliar","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/03\/2015","format":false,"excerpt":"En la Iglesia posconciliar se necesita un estudio s\u00f3lido y diverso de la espiritualidad cristiana b\u00e1sica y de las \"espiritualidades\" que han aplicado la Espiritualidad evang\u00e9lica a distintas situa\u00adciones hist\u00f3ricas y a familias religiosas y apost\u00f3licas, para reali\u00adzar la \"adecuada renovaci\u00f3n\" de estas espiritualidades a la au\u00adt\u00e9ntica espiritualidad Cristoc\u00e9ntrica y\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"concilio1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/concilio1-300x113.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":119136,"url":"https:\/\/vincentians.com\/es\/el-templo-nacional-de-las-conferencias-de-san-vicente-de-paul\/","url_meta":{"origin":14076,"position":5},"title":"El templo nacional de las Conferencias de san Vicente de Pa\u00fal","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/01\/2022","format":false,"excerpt":"Conforme acabo de indicar en l\u00edneas anteriores, el 12 de enero se celebra con una solemne Misa Pontifical, oficiada por Mos, Garc\u00eda Lahiguera, la entrada en servicio de las obras de ampliaci\u00f3n del templo nacional de las Conferencias de San Vicente de Pa\u00fal. He aqu\u00ed la rese\u00f1a que de ese\u2026","rel":"","context":"En \u00abHistoria de la Sociedad de san Vicente de Pa\u00fal\u00bb","block_context":{"text":"Historia de la Sociedad de san Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-sociedad-de-san-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/14076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=14076"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/14076\/revisions"}],"predecessor-version":[{"id":403650,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/14076\/revisions\/403650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/400152"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=14076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=14076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=14076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}