{"id":133840,"date":"2015-01-18T05:58:55","date_gmt":"2015-01-18T04:58:55","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=133840"},"modified":"2015-01-18T05:58:55","modified_gmt":"2015-01-18T04:58:55","slug":"constructores-de-un-mundo-nuevo","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/","title":{"rendered":"Constructores de un mundo nuevo"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/nuevo-mundo.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-135282\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/nuevo-mundo-300x225.jpg?resize=300%2C225\" alt=\"nuevo-mundo\" width=\"300\" height=\"225\" \/><\/a>\u00abAteni\u00e9ndonos a la promesa, aguardamos un cielo nuevo y una tierra nueva, en los que habite la justicia. Por eso, amigos, mientras aguard\u00e1is esto, poned empe\u00f1o en estar en paz con \u00e9l, libres de mancha y defecto\u00bb. (II Pe 3,13-14).<\/p>\n<p>\u00abEn las diversas circunstancias de tiempo y lugar, nuestra evangelizaci\u00f3n, de palabra y de obra, debe tender a que todos, por la conversi\u00f3n y la celebraci\u00f3n de los sacramentos se adhieran al Reino, es decir, al mundo nuevo, al estado de cosas, a la nueva manera de ser, a la nueva forma de vivir, y por cierto de vivir juntos, que inaugura el Evangelio (EN 23)\u00bb. (C 11).<\/p>\n<p>La construcci\u00f3n de un mundo nuevo, basado en la justicia y santidad, es el resultado al que tiende la evangelizaci\u00f3n de Jes\u00fas: \u00abBuscad primero el Reino de Dios y su justicia; lo dem\u00e1s se os dar\u00e1 por a\u00f1adidura\u00bb (Mt 6,33). De igual manera, los Misioneros han de procurar, de palabra y de obra, implantar en s\u00ed mismos luego en los dem\u00e1s el Reino de Dios, llevando a cabo la obra encomendada.<\/p>\n<h2>1.- \u00abNuestro Se\u00f1or quiere que ante todo busquemos su gloria, su reino&#8230;\u00bb.<\/h2>\n<p>Al Misionero se le conoce por el esp\u00edritu y por la actividad apost\u00f3lica que desarrolla en nombre de Jes\u00fas; ha de cuidar, sin embargo, no caer en el activismo como herej\u00eda, tentaci\u00f3n que ronda frecuentemente a los hombres de mucha actividad. S\u00f3lo la atenci\u00f3n a las exigencias del Reino de Dios le librar\u00e1 de este peligro. Es posible que alguien objete, como en tiempo de San Vicente: \u00ab\u00a1Pero hay tantas cosas que hacer, tantas tareas en la casa, tantas ocupaciones en la ciudad, en el campo!<\/p>\n<p>Trabajo por todas partes. \u00bfHabr\u00e1 que dejarlo todo para no pensar m\u00e1s que en Dios? No, pero hay que santificar esas ocupaciones buscando en ellas a Dios, y hacerlas m\u00e1s por encontrarle a El all\u00ed que por verlas hechas. Nuestro Se\u00f1or quiere que ante todo busquemos su Reino, su gloria, su justicia, y para eso que insistamos sobre todo en la vida interior, en la fe, la confianza, el amor, los ejercicios de religi\u00f3n, la religi\u00f3n, la oraci\u00f3n, la confusi\u00f3n, las humillaciones, los trabajos y las penas, con vistas a Dios, nuestro Se\u00f1or soberano; que le presentemos continuas oblaciones de servicio y de anhelos Por ganar reinos para su bondad, gracias para su Iglesia y virtudes para la Compa\u00f1\u00eda\u00bb. (XI 430).<\/p>\n<h2>2.- \u00abDios reina de una manera especial sobre los justos\u00bb.<\/h2>\n<p>La implantaci\u00f3n del Reino en las almas espera del evangelizador una entrega constante a la obra apost\u00f3lica; de ah\u00ed que el Misionero no deba contentarse con los m\u00ednimos espirituales, sino procurar hacer de todos los hombres verdaderos hijos de Dios. Tal es la recomendaci\u00f3n de San Vicente:<\/p>\n<p>\u00abDios reina de una manera especial sobre los justos que le honran y le sirven; sobre las almas buenas, que se entregan a Dios y no respiran m\u00e1s que a Dios; sobre los elegidos, que deber\u00e1n glorificarle eternamente. Sobre esas personas es sobre las que reina de una manera especial, por medio de las virtudes que practican y que han recibido de El. El es el Dios de las virtudes, y no hay ninguna que no venga de El\u00bb. (XI 431).<\/p>\n<h2>3.- \u00abLa finalidad de la evangelizaci\u00f3n es, por consiguiente, este cambio interior\u00bb.<\/h2>\n<p>Las palabras de San Vicente, que acabamos de escuchar, sobre el establecimiento del Reino de Dios en los justos, adquieren plena categor\u00eda por el testimonio de Pablo VI, que afirma:<\/p>\n<p>La verdad es que no hay humanidad si no hay, en primer lugar, hombres nuevos con la novedad del bautismo y de la vida seg\u00fan el Evangelio. La finalidad de la evangelizaci\u00f3n es, por consiguiente, este cambio interior, v. si hubiera que resumirlo en una palabra, lo mejor ser\u00eda que la Iglesia evangeliza cuando, por la sola fuerza divina del Mensaje que proclama, trata de convertir mismo tiempo la conciencia personal y colectiva de los hombres, la actividad en que ellos est\u00e1n comprometidos, su vida y ambientes concretos. Posiblemente podr\u00edamos expresar todo esto diciendo: lo que importa es evangelizar \u2014no de una manera decorativa, como con un barniz superficial, sino de manera vital, en profundidad y hasta sus mismas ra\u00edces\u2014 la cultura y las culturas del hombre en el sentido rico y amplio que tienen sus t\u00e9rminos en la Gaudium et Spes, 53, tomando siempre como punto de partida la persona y teniendo siempre presentes las relaciones de las personas entre s\u00ed y con Dios\u00bb. (EN 20).<\/p>\n<ul>\n<li>\u00bfMe dejo arrastrar por el activismo, no atendiendo a la vida espiritual?<\/li>\n<li>\u00bfBusco, a trav\u00e9s de la evangelizaci\u00f3n, construir un mundo nuevo de hombres impregnados del Esp\u00edritu, capaces de cambiar los ambientes en que est\u00e1n comprometidos?<\/li>\n<\/ul>\n<h2>Oraci\u00f3n:<\/h2>\n<p>\u00abOh Dios, que has llamado a todos los hombres a cooperar en el plan inmenso de la creaci\u00f3n, haz que en el esfuerzo com\u00fan por construir un mundo nuevo, m\u00e1s justo y m\u00e1s fraterno, se consiga que todo hombre encuentre el puesto que su dignidad pide, para que realice plenamente su vocaci\u00f3n y contribuya al progreso de todos los dem\u00e1s hombres seg\u00fan la Buena Nueva que nos predic\u00f3 tu Hijo, Jesucristo, nuestro Se\u00f1or\u00bb. (Mro, Votiva por el trabajo).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abAteni\u00e9ndonos a la promesa, aguardamos un cielo nuevo y una tierra nueva, en los que habite la justicia. Por eso, amigos, mientras aguard\u00e1is esto, poned empe\u00f1o en estar en paz con \u00e9l, libres de mancha &#8230; <a href=\"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":135282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-133840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constructores de un mundo nuevo - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constructores de un mundo nuevo - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"\u00abAteni\u00e9ndonos a la promesa, aguardamos un cielo nuevo y una tierra nueva, en los que habite la justicia. Por eso, amigos, mientras aguard\u00e1is esto, poned empe\u00f1o en estar en paz con \u00e9l, libres de mancha ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-18T04:58:55+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Constructores de un mundo nuevo\",\"datePublished\":\"2015-01-18T04:58:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/\"},\"wordCount\":915,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/\",\"name\":\"Constructores de un mundo nuevo - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-01-18T04:58:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/constructores-de-un-mundo-nuevo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Constructores de un mundo nuevo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constructores de un mundo nuevo - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/","og_locale":"es_ES","og_type":"article","og_title":"Constructores de un mundo nuevo - Somos Vicencianos","og_description":"\u00abAteni\u00e9ndonos a la promesa, aguardamos un cielo nuevo y una tierra nueva, en los que habite la justicia. Por eso, amigos, mientras aguard\u00e1is esto, poned empe\u00f1o en estar en paz con \u00e9l, libres de mancha ... Read More","og_url":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-01-18T04:58:55+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Constructores de un mundo nuevo","datePublished":"2015-01-18T04:58:55+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/"},"wordCount":915,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#primaryimage"},"thumbnailUrl":"","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/","url":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/","name":"Constructores de un mundo nuevo - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-01-18T04:58:55+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/constructores-de-un-mundo-nuevo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Constructores de un mundo nuevo"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-yOI","jetpack-related-posts":[{"id":119438,"url":"https:\/\/vincentians.com\/es\/anunciar-a-jesucristo-hoy\/","url_meta":{"origin":133840,"position":0},"title":"Anunciar a Jesucristo, hoy","author":"Francisco Javier Fern\u00e1ndez Chento","date":"10\/04\/2013","format":false,"excerpt":"I - Un nuevo escenario cultural Vivimos un momento de cambios y transformaciones importantes en todos los \u00e1mbitos de la existencia humana; \"una acelerada transformaci\u00f3n\" de la sociedad ha generado un nuevo escenario cultural caracterizado por la p\u00e9rdida de la consistencia ontol\u00f3gica del alma, una crisis de verdad, una perversi\u00f3n\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"anunciar","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/anunciar-211x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":104293,"url":"https:\/\/vincentians.com\/es\/novena-biblica-en-honor-al-beato-federico-ozanam-dia-septimo\/","url_meta":{"origin":133840,"position":1},"title":"Novena b\u00edblica en honor al beato Federico Ozanam: D\u00eda s\u00e9ptimo","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/09\/2012","format":false,"excerpt":"Oraci\u00f3n Oh Dios de Caridad infinita, que no dejas de compadecerte de nosotros y contin\u00faas la obra misericordiosa de tu Divino Hijo Jesucristo en la historia de cada hombre. Te damos infinitas gracias por el amor que se hace manifiesto por medio de la gracia bautismal en todos y cada\u2026","rel":"","context":"En \u00abFederico Ozanam\u00bb","block_context":{"text":"Federico Ozanam","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/federico-ozanam\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/09\/beato_ozanam_pobre-225x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":128402,"url":"https:\/\/vincentians.com\/es\/aportes-vicencianos-a-la-nueva-evangelizacion\/","url_meta":{"origin":133840,"position":2},"title":"Aportes vicencianos a la nueva evangelizaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"15\/06\/2024","format":false,"excerpt":"Introducci\u00f3n Desde hace bastante tiempo, estamos oyendo, en la Congregaci\u00f3n de la Misi\u00f3n y en muchos c\u00edrculos de la Familia Vicenciana, dos cuestiones referentes al \"ser\" y al \"quehacer\" vicencianos. Por un lado, todos estamos plenamente de acuerdo en que el carisma, el \"ser\", la identidad, el sello caracter\u00edstico de\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":131931,"url":"https:\/\/vincentians.com\/es\/la-gracia-de-evangelizar\/","url_meta":{"origin":133840,"position":3},"title":"La gracia de evangelizar","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/12\/2014","format":false,"excerpt":"\"\u00bfC\u00f3mo van a invocarlo sin creer en \u00e9l?, y \u00bfc\u00f3mo van a creer sin o\u00edr hablar de \u00e9l?, y \u00bfc\u00f3mo van a o\u00edr sin uno que lo anuncie?, y \u00bfc\u00f3mo lo van a anunciar sin ser enviados? Seg\u00fan aquello de la Escritura: Bienvenidos los que traen buenas noticias\". (C 10).\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"hora-de-evangelizar","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/12\/hora-de-evangelizar-300x236.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":26261,"url":"https:\/\/vincentians.com\/es\/servir-al-pobre-espiritual-y-corporalmente\/","url_meta":{"origin":133840,"position":4},"title":"Servir al pobre espiritual y corporalmente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/06\/2015","format":false,"excerpt":"Hay muchas formas de expresar el carisma vicentino. Una forma de definirlo es: acompa\u00f1ar a los pobres en la construcci\u00f3n del Reino de Dios. El Reino es el centro de la vida y misi\u00f3n de Jes\u00fas, es la proclamaci\u00f3n, por medio de la palabra y de las obras, de la\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/01\/lavado_de_pies-300x261.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":59209,"url":"https:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/","url_meta":{"origin":133840,"position":5},"title":"Evangelizaci\u00f3n y Servicio","author":"Francisco Javier Fern\u00e1ndez Chento","date":"30\/03\/2015","format":false,"excerpt":"\"Ustedes fueron fundadas \u00fanicamente para servir al mundo de los desheredados, de los \"peque\u00f1os\". Yo les exhorto m\u00e1s que nunca a compartir la miseria del mundo contempor\u00e1neo...\" Al escuchar los informes de los grupos, he podido percibir que ya se han dado muchas respuestas a esta cuesti\u00f3n, seg\u00fan la llamada\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"maria-discipula-1340x1008","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/maria-discipula-1340x1008-300x226.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/133840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=133840"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/133840\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=133840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=133840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=133840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}