{"id":13089,"date":"2008-12-04T07:05:25","date_gmt":"2008-12-04T06:05:25","guid":{"rendered":"http:\/\/www.vicencianos.org\/web\/2008\/12\/04\/vicente-de-paul-carta-0329-a-leonardo-boucher\/"},"modified":"2016-07-26T11:11:18","modified_gmt":"2016-07-26T09:11:18","slug":"vicente-de-paul-carta-0329-a-leonardo-boucher","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/","title":{"rendered":"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher"},"content":{"rendered":"<p>Padre:<\/p>\n<p>La gracia de Nuestro Se\u00f1or sea siempre con nosotros.<\/p>\n<p>El domingo pasado, a punto de salir de la ciudad para ir a los campos, recib\u00ed la suya del 10 de este mes, y al volver anteayer por la tarde un poco cansado, no tuve \u00e1nimos para hacer que le enviaran a alguien para la asistencia del buen padre Mouton. Lo hago esta ma\u00f1ana y le env\u00edo a Mateo que est\u00e1 lleno de ardor y de caridad,como sabe. Le suplico, padre, que no escatime nada con \u00e9l. En Montmirail hay boticarios y buenos cirujanos; al m\u00e9dico, hay que mandarlo a buscar a Chateau-Thierry. Hay uno llamado se\u00f1or Fournier, que es un buen m\u00e9dico y amigo nuestro. Puede servirse de \u00e9l, si no ha tomado ya a alg\u00fan otro. Y como estar\u00e1 en un lugar m\u00e1s c\u00f3modo en Montmirail, le ruego que lo haga trasladar all\u00ed. Le escribo al conserje, se\u00f1or Octobre, para que le busque alojamiento. Le suplico, padre, que no lo abandone, a no ser que se ponga mejor, en cuyo caso podr\u00eda acabar la misi\u00f3n comenzada o juntarse con el padre Lucas, mientras descansa el padre Mouton.<\/p>\n<p>Saludo muy humildemente a dicho padre Mouton y lo abrazo en esp\u00edritu con un coraz\u00f3n lleno de cari\u00f1o, de dolor y de mansedumbre. No dejaremos de rogar a Dios por \u00e9l, como puede pensar.<\/p>\n<p>No le digo nada sobre lo dem\u00e1s de su carta a prop\u00f3sito de las Caridades, sino que me doy cuenta de que no tenemos tiempo para restablecerlas. Nuestro Se\u00f1or nos lo dar\u00e1 en paz m\u00e1s oportunamente si as\u00ed lo quiere.<\/p>\n<p>Soy, padre, en su amor, su muy humilde servidor,<\/p>\n<p>VICENTE DEPAUL<\/p>\n<p>Par\u00eds, 17 marzo 1638.<\/p>\n<p>Direcci\u00f3n: Al padre Boucher, sacerdote de la Misi\u00f3n, en Montmirail.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. El domingo pasado, a punto de salir de la ciudad para ir a los campos, recib\u00ed la suya del 10 de este mes, y al &#8230; <a href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":393753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[131],"class_list":["post-13089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-vicente-de-paul","tag-montmirail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Padre: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. El domingo pasado, a punto de salir de la ciudad para ir a los campos, recib\u00ed la suya del 10 de este mes, y al ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-04T06:05:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T09:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher\",\"datePublished\":\"2008-12-04T06:05:25+00:00\",\"dateModified\":\"2016-07-26T09:11:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"Montmirail\"],\"articleSection\":[\"Escritos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/\",\"name\":\"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2008-12-04T06:05:25+00:00\",\"dateModified\":\"2016-07-26T09:11:18+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-0329-a-leonardo-boucher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher - Somos Vicencianos","og_description":"Padre: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. El domingo pasado, a punto de salir de la ciudad para ir a los campos, recib\u00ed la suya del 10 de este mes, y al ... Read More","og_url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2008-12-04T06:05:25+00:00","article_modified_time":"2016-07-26T09:11:18+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher","datePublished":"2008-12-04T06:05:25+00:00","dateModified":"2016-07-26T09:11:18+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","keywords":["Montmirail"],"articleSection":["Escritos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/","url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/","name":"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","datePublished":"2008-12-04T06:05:25+00:00","dateModified":"2016-07-26T09:11:18+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0329-a-leonardo-boucher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal, Carta 0329: A Leonardo Boucher"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-3p7","jetpack-related-posts":[{"id":116631,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1037-a-guillermo-delville\/","url_meta":{"origin":13089,"position":0},"title":"Vicente de Pa\u00fal, Carta 1037: A Guillermo Delville","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/12\/2012","format":false,"excerpt":"Par\u00eds 11 octubre 1647. Padre: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Le enviamos seis o siete sacerdotes, cinco de la Compa\u00f1\u00eda y otros dos del seminario de Bons-Enfants. De los cinco, hay dos de Montmirail y uno de los otros tres es el padre Watebled, cuya bondad\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":126976,"url":"https:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0731-al-senor-vicente\/","url_meta":{"origin":13089,"position":1},"title":"Luisa de Marillac, Carta 0731: Al se\u00f1or Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/01\/2014","format":false,"excerpt":"(despu\u00e9s de 1650) Mi muy Honorable Padre: La pobre Sor Nicolasa, de Montmirail, ha dicho a nuestras Hermanas que la se\u00f1orita de Montdesir, madre de la se\u00f1ora Tuboeuf, la hab\u00eda recibido para que fuera a servir a los pobres enfermos del pueblo de Issy, en lugar de las Hermanas a\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":115903,"url":"https:\/\/vincentians.com\/es\/obrero-de-la-primera-hora-padre-portail-en-mosaico-ii\/","url_meta":{"origin":13089,"position":2},"title":"Obrero de la primera hora: Padre Portail en mosaico (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"20\/05\/2021","format":false,"excerpt":"2. En los or\u00edgenes de la Misi\u00f3n En el d\u00eda 4 de septiembre de 1626, juntamente con Vicente de Pa\u00fal, Francisco du Coudray y Jean de la Salle, los dos \u00faltimos del clero de Amiens, Portail firma el Acta de Asociaci\u00f3n, certificado de nacimiento de la Congregaci\u00f3n da Misi\u00f3n (cf.\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":142638,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-1310-a-esteban-blatiron-superior-de-genova\/","url_meta":{"origin":13089,"position":3},"title":"Vicente de Pa\u00fal, Carta 1310: A Esteban Blatiron, Superior De G\u00e9nova","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/04\/2015","format":false,"excerpt":"2 de septiembre de 1650 Temo que, si empieza usted a presentar cuentas, se seguir\u00e1 haciendo as\u00ed y que luego el se\u00f1or cardenal y el arzobispo que le suceda, al ver que as\u00ed lo ha hecho, le obligue a continuar; y es eso precisamente lo que hay que evitar por\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":119698,"url":"https:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-preceptor\/","url_meta":{"origin":13089,"position":4},"title":"El Se\u00f1or Vicente relee su vida: Preceptor","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/02\/2022","format":false,"excerpt":"Fue en la segunda mitad de 1613 cuando concluy\u00f3 mi b\u00fasqueda que tanto dur\u00f3. Recib\u00eda en efecto \"el cargo de preceptor de los hijos del Se\u00f1or Philippe-Emmanuel de Gondi, Conde de Joigny, General de las Galeras de Francia\". El mayor de los hijos, Pierre, ten\u00eda 11 a\u00f1os, el segundo, Henri,\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6244,"url":"https:\/\/vincentians.com\/es\/vicente-de-paul-carta-0306-a-antonio-lucas\/","url_meta":{"origin":13089,"position":5},"title":"Vicente de Pa\u00fal, Carta 0306: A Antonio Lucas","author":"Francisco Javier Fern\u00e1ndez Chento","date":"02\/12\/2008","format":false,"excerpt":"Padre: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Ha hecho bien, padre, al no aceptar los ofrecimientos del se\u00f1or Vizconde de Soud\u00e9, y har\u00e1 bien al no escuchar jam\u00e1s la proposici\u00f3n de alimentarnos; es una regla fundamental de nuestro peque\u00f1o Instituto. Pues bien, supongo que habr\u00e1 acabado ya\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/13089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=13089"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/13089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/393753"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=13089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=13089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=13089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}