{"id":121662,"date":"2024-07-25T08:53:47","date_gmt":"2024-07-25T06:53:47","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=121662"},"modified":"2023-08-20T00:06:11","modified_gmt":"2023-08-19T22:06:11","slug":"san-vicente-de-paul-y-los-gondi-capitulo-14","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/","title":{"rendered":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14"},"content":{"rendered":"<h2><b><b>Cap\u00edtulo <\/b>XIV<\/b><\/h2>\n<p style=\"text-align: center\"><i>Vicente de Pa\u00fal durante la Fronda. &#8211; El cardenal de Retz cabeza de los Frondistas. &#8211; Vicente diplom\u00e1tico y gran capell\u00e1n de Francia. &#8211; Plenos poderes que le da Luis XIV, lo mismo que a los sacerdotes de la Misi\u00f3n. <\/i>&#8211; <i>Vicente proclamado padre de la patria. &#8211; Sus negociaciones en favor de la paz. &#8211; Sus cartas al cardenal Mazarino. &#8211; Arresto del cardenal de Retz.<\/i><\/p>\n<p>Hasta la publicaci\u00f3n del libro de Alfonso Feillet, la <i>Miseria en el tiempo de la Fronda, <\/i>se andaba lejos de suponer de qu\u00e9 terribles plagas fue presa Francia durante los cinco a\u00f1os que dur\u00f3 esta fatal guerra civil; y, por otra parte, no se conoc\u00eda sino imperfectamente el grande y noble papel, a la vez totalmente pac\u00edfico y caritativo que, durante todo ese tiempo, no ces\u00f3 de desempe\u00f1ar Vicente de Pa\u00fal. Los autores de las Memorias contempor\u00e1neas, gentilhombres en su mayor parte, solo han hallado inter\u00e9s en el relato de las intrigas pol\u00edticas y galantes de los grandes se\u00f1ores y de las grandes damas de su tiempo; en el espect\u00e1culo de la lucha de los pr\u00edncipes, del cardenal de Retz y de sus frondistas contra la corte y Mazarino; en el cuadro de las tormentosas sesiones del Parlamento, en las que se pon\u00eda precio a la cabeza del cardenal ministro; en los brillantes combates que se libraban los dos mayores capitanes de su siglo, Cond\u00e9 y Turena. Bien por indiferencia, bien por c\u00e1lculo, han echado un velo sobre el aspecto m\u00e1s sombr\u00edo, el m\u00e1s lamentable de este drama tragic\u00f3mico; se olvidaron de decirnos que, en Par\u00eds y en varias provincias, la peste y el hambre que acompa\u00f1aban a los ej\u00e9rcitos, segaron a miles de hombres de entre las clases pobres. En este cap\u00edtulo, as\u00ed como en la admirable entrega de Vicente de Pa\u00fal y en sus negociaciones en favor de la paz, el libro de Alphonse Feillet ha sido una verdadera revelaci\u00f3n. Nosotros completaremos lo que hay de esencial en su relato por algunas cartas del santo sacadas de su correspondencia, que acaban de publicar, para su uso particular, los RR. PP. Lazaristas.<\/p>\n<p>\u00a1Qu\u00e9 contraste m\u00e1s extra\u00f1o entre la conducta de Vicente durante la Fronda y la de su indigno alumno, el coadjutor de Par\u00eds! Mientras que Pablo de Gondi, para echar a Mazarino y conquistar el capelo y el ministerio, levanta barricadas, arma a un regimiento contra las tropas del Rey, transforma la c\u00e1tedra sagrada en tribuna pol\u00edtica, se convierte en el jefe de los frondistas y, durante m\u00e1s de cuatro a\u00f1os, con un poder de intriga sin igual, alimenta la guerra civil con sus panfletos, con sus emisarios, con sus manejos secretos entre el pueblo, en el parlamento, en la nobleza, en el clero y ante el duque de Orl\u00e9ans, lugarteniente general del reino, Vicente de Pa\u00fal, con una perseverancia infatigable, con el m\u00e1s noble patriotismo y la caridad m\u00e1s ardiente, se interpone entre los frondistas y la corte, se esfuerza por poner fin a esta lucha imp\u00eda y llevar auxilios a todas las v\u00edctimas de la guerra y del hambre.<\/p>\n<p>Fue pocos d\u00edas despu\u00e9s de las jornadas de las Barricadas del 26 y 27 de agosto, cuando comenz\u00f3 a jugar este papel de pacificador; pero se puede ver por la carta que vamos a reproducir que los esp\u00edritus estaban todav\u00eda demasiado recalentados para entregarse a sus exhortaciones. Mazarino se hab\u00eda mostrado hacia ellas tan sordo como el coadjutor, quien dec\u00eda bien claro que el cardenal no le convencer\u00eda a \u00e9l con tanta facilidad como al sr Vicente<span id='easy-footnote-1-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-1-121662' title='Carnets de Mazarino.'><sup>1<\/sup><\/a><\/span>.<\/p>\n<p>\u00abSe\u00f1orita, escrib\u00eda Vicente a la se\u00f1orita La Gras<span id='easy-footnote-2-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-2-121662' title='Par\u00eds, 5 de septiembre de 1648.'><sup>2<\/sup><\/a><\/span>, que se encontraba por entonces en Liancourt, bendito sea Dios por la solicitud que Nuestro Se\u00f1or os da hacia vuestras queridas hijas y hacia m\u00ed, en estas emociones populares. Aqu\u00ed estamos todos, por la gracia de Dios, sin que Nuestro Se\u00f1or nos haya hecho dignos de sufrir algo por \u00e9l en estas circunstancias. Estad segura, por lo dem\u00e1s, que no hay nada que yo haya pensado deber decir que no haya dicho por la gracia de Dios; yo digo con respecto a todo. El mal es que Dios no ha bendecido mis palabras, aunque yo vea las que se dicen de la persona (Mazarino) de quien o\u00eds hablar. Es verdad que trato de decirlas de la manera que lo hacen los buenos \u00e1ngeles, que proponen sin perturbarse, cuando no se hace uso de sus luces. Es la lecci\u00f3n que me ense\u00f1\u00f3 el bienaventurado cardenal de B\u00e9rulle; y tengo las pruebas de que no tengo gracia, sino que lo estropeo todo, cuando las uso de diferente manera&#8230;\u00bb<\/p>\n<p>Pero si bien Vicente no hizo causa com\u00fan con los malos \u00e1ngeles, es decir con los frondistas, como compart\u00eda la opini\u00f3n de ellos sobre Mazarino, y nadie hubiera tenido nunca una libertad de hablar tan grande como \u00e9l, crey\u00f3 prestar un verdadero servicio al Rey y al Estado, aconsej\u00e1ndole que abandonara Francia. El cardenal, lejos de seguir este consejo, no le perdon\u00f3 nunca, se dice, este exceso de franqueza.<\/p>\n<p>Durante el sitio de Par\u00eds, cuando la pol\u00edtica a ultranza de la regente, demasiado bien servida por los implacables rigores de Cond\u00e9, hubo hecho sentir a los Parisinos todos los horrores del hambre, un solo hombre se atrevi\u00f3 a hacerles escuchar la voz de la clemencia, es otra vez Vicente quien aboga en favor de los sitiados y quien, por su diplomacia llena de dulzura, se esfuerza, pero en vano, por calmar los sentimientos de venganza de Ana de Austria. Un papel de \u00e9l a la Reina, descubierto por Alphonse Feillet, nos revela a la vez todo lo que \u00e9l mostr\u00f3 en esta circunstancia de caridad y de firmeza en su lenguaje:<\/p>\n<p>\u00abSe\u00f1ora, Par\u00eds se siente contento maravillosamente cuando ha sabido que la incomparable bondad del Rey y la de Vuestra Majestad quer\u00edan que, sin impedimento, se trajera trigo; pero esta alegr\u00eda se ve seguida en un poco de tristeza, porque la gente de guerra no permite dejar a las trops recoger los trigos, como yo lo he visto, sino que corren a los propietarios que se atreven a acercarse para hacer sus cosechas. Suplico muy humildemente a Vuestra Majestad que tenga a bien que le haga esta observaci\u00f3n, porque Ella me ha hecho el honor de decirme que el Rey no ha prohibido que los que han sembrado las tierras recojan los frutos, y que yo s\u00e9 que, si es del agrado de Su Majestad y de la Vuestra remediar el impedimento que se les hace, ello contribuir\u00e1 grandemente a persuadir al pueblo que Ellas le son mejores de lo que se pueda pensar\u00bb.<\/p>\n<p>Despu\u00e9s de esta carta, continuaron los estragos como antes. Pero este fracaso, lejos de desanimar el celo de Vicente, le dio un nuevo impulso. Movido a compasi\u00f3n ante la vista de todos los males que sufr\u00edan los Parisinos, tuvo el valor de salir de San L\u00e1zaro<span id='easy-footnote-3-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-3-121662' title='13 de enero de 1649.'><sup>3<\/sup><\/a><\/span>, atravesar el campo infestado de bandas de saqueadores y presentarse en Saint-Germain, para suplicar a la regente que pusiera fin a los horrores del asedio. Hab\u00eda tenido la precauci\u00f3n antes de salir, de no ver a nadie de los frondistas, a fin de poder afirmar a la Reina con toda conciencia que, para intentar dar este paso, \u00e9l no hab\u00eda tomado consejo m\u00e1s que de s\u00ed mismo, y que no hab\u00eda sido acordado con nadie. Escrib\u00eda al primer presidente del Parlamento, Mathieu Mol\u00e9, que su \u00fanico prop\u00f3sito al acudir a Saint-Germain, ante la corte, era trabajar en la paz, y que si \u00e9l no lo hab\u00eda visto antes de salir de Par\u00eds, era para no despertar ninguna sospecha en el esp\u00edritu de la Reina. Este viaje de Vicente no tuvo m\u00e1s \u00e9xito que su carta. Ana de Austria, entera en su venganza, no prest\u00f3 esta vez ninguna atenci\u00f3n a las s\u00faplicas del hombre de Dios.<\/p>\n<p>Mientras que \u00e9l se agotaba en vanos esfuerzos para calmar los resentimientos de esta princesa, los panfletarios no la perdonaban m\u00e1s que ella en sus <i>Mazarinades. <\/i>La acusaban principalmente de haber prestado su ministerio a un pretendido matrimonio secreto entre la Reina y el cardenal Mazarino. Se puede leer en la <i>Requ\u00eate civile contre la conclusion de la paix: <\/i><\/p>\n<p>\u00abSi es verdad, lo que se dice, que ellos (la regente y el cardenal) est\u00e9n liados juntos por un matrimonio de conciencia, y que el P. Vicente, superior de la Misi\u00f3n, haya ratificado el contrato, ellos pueden todo lo que hacen, y m\u00e1s lo que nosotros no vemos\u00bb.<\/p>\n<p>En otro panfleto, de un cinismo m\u00e1s repugnante todav\u00eda, se halla una lista fant\u00e1stica de los amantes supuestos de Ana de Austria: Montmorency, Buckingham, Leganez y Mazarino, con quien se la pretende siempre casada por el P. Vicente. M\u00e1s tarde, despu\u00e9s del regreso de Luis XIV a Par\u00eds, el populacho, presa de un furor bestial contra el santo hombre, a quien acusa de mazarinismo, se precipita sobre San L\u00e1zaro, donde cada d\u00eda se le distribuye pan en abundancia, y lo habr\u00eda saqueado, sin la intervenci\u00f3n de los guardias de corps del joven Rey.<\/p>\n<p>Vicente, condenado a la impotencia entre el ej\u00e9rcito real y el de los Parisinos, crey\u00f3 no tener otra cosa que hacer que visitar en las provincias a las diversas casas de su Orden, que comenzaban a sufrir por los primeros des\u00f3rdenes de la Fronda. Pero de lejos o de cerca, su vigilante caridad estaba siempre sobre aviso, y si bien su casa de San L\u00e1zato y la granja de Orsigny, que depend\u00eda de ella, hab\u00edan sufrido muchos saqueos, hizo todos sus esfuerzos, en la medida de sus d\u00e9biles recursos, para venir en ayuda de los Parisinos hambrientos. Hall\u00e1ndose en Mans, el 4 de marzo de 1649, escrib\u00eda al sr Portail, uno de sus sacerdotes de la Misi\u00f3n, en Marsella: \u00ab&#8230; Usted sabe las p\u00e9rdidas que sufrimos no s\u00f3lo por los trigos que ten\u00edamos en Orsigny y en San L\u00e1zaro, sino por la privaci\u00f3n de todas nuestras rentas (colocadas en gran parte sobre las diligencias), lo que nos ha obligado a descargar a San L\u00e1zaro y a los Bons-Enfants, donde ya no hay m\u00e1s que siete u ocho sacerdotes, dieciocho escolares y algunos hermanos. Los dem\u00e1s han sido enviados a Richelieu y otras partes; y todav\u00eda se ver\u00e1n obligados a salir cuando ya no haya nada. Del poco trigo que hay, se distribuyen todos los d\u00edas tres o cuatro sextarios a los pobres, lo que nos sirve de un muy sensible consuelo en los extremos en que nos vemos, y que nos hace esperar de que Dios no nos abandonar\u00e1\u00bb. No hay ninguna carta suya, durante su viaje por las provincias, que no se preocupe por la suerte de los pobres de Par\u00eds, y por mejores medios de socorrerlos.<\/p>\n<p>Pero, como consecuencia de la guerra civil, las rentas hab\u00edan sufrido una baja considerable, todos los dem\u00e1s valores estaban m\u00e1s depreciados todav\u00eda, el dinero se hab\u00eda hecho extremadamente raro. San L\u00e1zaro, agotado por todas sus caridades, iba a tener falta de trigo tambi\u00e9n, cuando la paz fue firmada en Saint-Germain, lo que permiti\u00f3 a los misioneros, por medio de algunos empr\u00e9stitos, hacer nuevas provisiones para atender a la angustia de los Parisinos.<\/p>\n<p>Durante ese tiempo, Vicente, abrumado de asuntos y fatigas, hab\u00eda ca\u00eddo gravemente enfermo en Richelieu. No pudo regresar a Par\u00eds hasta mucho tiempo despu\u00e9s de la paz de Saint-Germain, y esta larga ausencia nos explica porqu\u00e9, durante el tiempo de la Fronda, no fue colocado hasta bastante despu\u00e9s por el Rey a la cabeza de la asistencia p\u00fablica. Seg\u00fan Abelly, su intervenci\u00f3n no se manifest\u00f3 de nuevo, sino de una manera m\u00e1s eficaz, hasta despu\u00e9s del asedio de Guisa (2 de julio de 1650). Al retirarse, el ej\u00e9rcito real y el de los Espa\u00f1oles hab\u00edan dejado abandonados por los caminos a un gran n\u00famero de soldados heridos y enfermos que, por centenares, mor\u00edan de hambre o por las heridas. Vicente, movido por la suerte de estos desdichados, y encontrando en una dama jansenista, la presidenta de Herse, una auxiliar caritativa, envi\u00f3 a los sitios a dos de sus sacerdotes de la Misi\u00f3n, con una suma de quinientas libras. Pero el n\u00famero de las v\u00edctimas de la guerra era tan alto, ya en Picard\u00eda, ya en Champa\u00f1a, que Vicente se vio obligado a hacer una llamada urgente a sus damas de caridad, y a rogar a Francisco de Gondi, arzobispo de Par\u00eds, que mandara a sus predicadores que movieran, desde lo alto de sus p\u00falpitos, la caridad de los fieles en favor de estas dos provincias. Enseguida se volvieron a abrir todas las bolsas que hab\u00eda cerrado el terror causado por la guerra civil; y la reina de Polonia, Mar\u00eda de Gonzaga, \u00abesta hija de Port-Royal\u00bb, envi\u00f3 doce mil libras a la Madre Ang\u00e9lica, para las provincias angustiadas, pero dici\u00e9ndole que se entendiera con el sr Vicente, para la repartici\u00f3n de esta suma<span id='easy-footnote-4-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-4-121662' title='Carta de la Madre Ang\u00e9lica a la se\u00f1orita de Lamoignon.'><sup>4<\/sup><\/a><\/span>.<\/p>\n<p>Vicente puso en pie dos cofrad\u00edas admirables: a los Sacerdotes y a los Hermanos de la Misi\u00f3n, y a las Hijas de la Caridad, que ya hab\u00edan prestado los mayores servicios en medio de los desastres de la Lorena. Manda salir inmediatamente para la Picard\u00eda y la Champa\u00f1a a seis de sus misioneros y a cierto n\u00famero de sus Hijas. En Guisa, en Ribemont, en Laon, en la F\u00e8re, en San Quint\u00edn, en Marle, etc., una espantosa mortandad hab\u00eda diezmado a la poblaci\u00f3n, y el n\u00famero de los enfermos, privados de todo socorro y muri\u00e9ndose de hambre en la paja podrida, era espantoso. Vicente, a fin de darse cuenta de una parte del mal se traslad\u00f3 en persona a Noyon y a Chauny.<\/p>\n<p>Jam\u00e1s los des\u00f3rdenes de las gentes de guerra hab\u00edan llegado m\u00e1s lejos. No eran s\u00f3lo los Espa\u00f1oles quienes se entregaban a los \u00faltimos excesos, que devastaban los campos, que asaltaban las cosechas, que saqueaban los pueblos, eran tambi\u00e9n los soldados del ej\u00e9rcito real. Nubes de campesinos, que hu\u00edan de sus casitas incendiadas, andaban errantes a la aventura con sus mujeres y sus hijos para mendigar el pan. Despu\u00e9s del combate, muertos y heridos quedaban abandonados, unos sin sepultura, otros sin auxilio. No se distingu\u00edan en nada las tropas del Rey de las del enemigo; no se encontraba ya disciplina, ni piedad, ni respeto por las cosas m\u00e1s santas. Los misioneros de Vicente hab\u00edan sido detenidos por los bandidos del conde de Harcourt y de Turena, y todo lo que llevaban para los pobres y los heridos entregado al pillaje.<\/p>\n<p>Vicente protest\u00f3 con toda fuerza contra esta abominable violaci\u00f3n de los derechos de la guerra, y la regente y el Rey, para poner fin a tales excesos, publicaron una orden que daba plenos poderes a Vicente y a sus misioneros para reparar los males sin n\u00famero de la guerra civil, que declaraba a sus personas inviolables y sagradas, y prohib\u00eda a los soldados, bajo pena de muerte, cometer el menor robo en su da\u00f1o. Esta orden que lleva fecha del 14 de febrero de 1651, ha sido sacada de nuevo a la luz por Alphonse Feillet. Ella constituye un t\u00edtulo demasiado glorioso para Vicente de Pa\u00fal para que no pongamos algunos fragmentos a los ojos del lector:<\/p>\n<p>\u00bb Su Majestad habi\u00e9ndose informado que los habitantes de la mayor parte de los pueblos de sus fronteras de Picard\u00eda y de Champa\u00f1a se ven reducidos a la mendicidad y a una completa miseria, por estar expuestos al pillaje y hostilidades de los enemigos, y al paso y alojamiento de todos los ej\u00e9rcitos; que varias iglesias han sido saqueadas y despojadas de sus ornamentos, y que para sostener y alimentar a los pobres y reparar las iglesias, varias personas de su buena ciudad de Par\u00eds hacen grandes y abundantes limosnas, que se emplean muy \u00fatilmente por los sacerdotes de la Misi\u00f3n del sr Vicente y otras personas caritativas enviadas a los lugares donde ha habido m\u00e1s ruinas y m\u00e1s da\u00f1os, de suerte que un gran n\u00famero de esta pobre gente se han visto aliviados en la necesidad y en la enfermedad; pero que mientras se hac\u00eda esto, las gentes de la guerra, al pasar y alojarse en los lugares donde dichos misioneros se encontraban se han apoderado y salteado los ornamentos de iglesia y las provisiones de v\u00edveres, ropas y otras cosas que iban destinadas para los pobres, de manera que no tienen seguridad por parte de Su Majestad, les ser\u00eda imposible continuar una obra tan caritativa y tan importante para gloria de Dios y alivio de los s\u00fabditos de Su Majestad; deseando contribuir en ello con todo cuanto pueda estar en su poder, Su Majestad, por consejo de la Reina regente, proh\u00edbe muy expresamente a los gobernadores y lugartenientes generales en sus provincias y ej\u00e9rcitos, mariscales y maestres de campo, coroneles, capitanes, etc&#8230; franceses y extranjeros, alojarse ni permitir que se alojen ninguna gente de guerra en los pueblos de las dichas fronteras de Picard\u00eda y de Champa\u00f1a, para las cuales los sacerdotes de la Misi\u00f3n les pidan salvaguarda para asistir a los pobres y a los enfermos, y realizar en ellas la distribuci\u00f3n de las provisiones que lleven, para que est\u00e9n en plena y entera libertad de ejercer su caridad en la manera y a aquellos a quienes les parezca. Proh\u00edbe, asimismo, Su Majestad a todas las gentes de guerra que se apoderen de nada de los sacerdotes de la Misi\u00f3n ni de las personas empleadas con ellos o por ellos, con pena de vida, tom\u00e1ndolos bajo su protecci\u00f3n y salvaguarda especial, imponiendo muy expresamente a todos los magistrados, senescales, jueces, prebostes de mariscales, etc. &#8230; mano dura en la ejecuci\u00f3n y publicaci\u00f3n de la presente, y persecuci\u00f3n de los contraventores, de suerte que el castigo les sirva de ejemplo, etc.<span id='easy-footnote-5-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-5-121662' title='Colecci\u00f3n Cang\u00e9, Ordenanzas militares, t. XXVIII.'><sup>5<\/sup><\/a><\/span>\u00ab.<\/p>\n<p>Esta ordenanza que, hasta Fillet, hab\u00eda escapado a la atenci\u00f3n de los bi\u00f3grafos de Vicente de Pa\u00fal, es uno de los monumentos que m\u00e1s honran su memoria: \u00abQue se pesen todas las palabras: la confesi\u00f3n del da\u00f1o al principio de la ordenanza, la barbarie de los soldados llevada hasta ese punto de no respetar ni a los que llegan a llevar auxilio a ellos y a sus v\u00edctimas&#8230; Esta acta atribuye a Vicente un papel p\u00fablico y oficial&#8230; \u00c9l es en adelante el <i>Grand Aumonier de la France, <\/i>en cuyas manos la realeza abdica voluntariamente lo que constituye su m\u00e1s noble privilegio, el poder de hacer el bien<span id='easy-footnote-6-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-6-121662' title='&lt;i&gt;La Mis\u00e8re au temps de la Fronde, &lt;\/i&gt;por Alph. Feillet.'><sup>6<\/sup><\/a><\/span>\u00ab.<\/p>\n<p>Lo que no puede el tesoro del Estado, medio agotado para sostener la guerra, lo encuentra Vicente en los inagotables recursos de su ingeniosa caridad, despierta siempre, siempre en acci\u00f3n. \u00bfQui\u00e9n iba a creer que en las dos provincias m\u00e1s devastadas por la guerra, la Champa\u00f1a y la Picard\u00eda, Vicente, el humilde campesino de las Landas, encuentra medio de distribuir al mes quince mil libras en limosnas, y esto durante casi un a\u00f1o! Nada es m\u00e1s cierto sin embargo, seg\u00fan lo prueba una de sus cartas, de fecha del 20 de mayo de 1651. Y estas sumas tan considerables para la \u00e9poca, y que habr\u00eda que multiplicar hoy por ocho o por diez, \u00bfd\u00f3nde se las encuentra? En la bolsa de sus damas de caridad.<\/p>\n<p>En cada p\u00e1gina del libro de Feillet, se trata de los cuadros m\u00e1s horribles, a cual m\u00e1s dolorosos. \u00abLa miseria es tan grande, escribe a Vicente el gobernador de Saint-Quentin, que no quedan habitantes ya en los pueblos que tengan siquiera paja para acostarse, y los m\u00e1s calificados de la regi\u00f3n no tienen de qu\u00e9 vivir&#8230; es lo que me obliga, en el rango en que estoy y el agradecimiento que siento a suplicaros que volv\u00e1is a ser el <i>P\u00e8re de la Patrie, <\/i>para conservar la vida a tantos moribundos y en extrema debilidad, a los que vuestros sacerdotes asisten, y lo hacen con toda dignidad\u00bb.<\/p>\n<p>Por doquier, al paso de sus misioneros, se eleva un concierto de bendiciones y gratitud. En todas las provincias que han sido presa de la guerra y del hambre, Vicente se preocupa de establecer almacenes de cebada y de trigo, para que se hagan distribuciones regulares a los necesitados.<\/p>\n<p>\u00abVos prove\u00e9is a las necesidades de los pobres con tanto orden y celo, le escribe el presidente y lugarteniente general de Rethel, por los sacerdotes de vuestra congregaci\u00f3n a quienes emple\u00e1is en todos los lugares circunvecinos donde los pobres se ven reducidos al pasto de los animales, hasta comerse perros, como yo he visto a pobres. Ellos han salvado la vida a un n\u00famero incalculable de personas y han consolado y asistido a los otros hasta la muerte\u00bb.<\/p>\n<p>Pronto las dem\u00e1s provincias, en particular la Normand\u00eda, la Provenza y la Borgo\u00f1a, ofrecieron un espect\u00e1culo m\u00e1s lamentable que la Picard\u00eda y la Champa\u00f1a. Como consecuencia del paso de los ej\u00e9rcitos, de las malas cosechas y del hambre, se declar\u00f3 la peste por all\u00ed y all\u00ed hizo estragos con la m\u00e1s extrema violencia. En Rouen, se llev\u00f3 a cuatro mil personas en quince d\u00edas. En los hospitales de Normand\u00eda, se ve\u00edan amontonados en el mismo lecho hasta ocho o diez enfermos; la peste irrumpi\u00f3 produciendo espantosos desastres; diecisiete mil personas perecieron all\u00ed. En los hospitales de Par\u00eds, donde entr\u00f3 el contagio en 1652, la mortandad no fue menos terrible. Veintid\u00f3s m\u00e9dicos encontraron la muerte, cuidando a los apestados. En Borgo\u00f1a, en Provenza, durante el a\u00f1o de 1651, los mismos desastres causados por la peste. \u00bfQu\u00e9 pod\u00edan hacer los misioneros de Vicente en medio de tantas calamidades?<\/p>\n<p>\u00abNuestra pobreza aumenta con las miserias p\u00fablicas, escrib\u00eda el 1\u00ba de marzo de 1652; las confusiones nos han quitado de una vez veintitr\u00e9s mil libras de renta ya que, fuera de la privaci\u00f3n de las ayudas (rentas sobre las bebidas), los coches no andan ya<span id='easy-footnote-7-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-7-121662' title='Los misioneros ten\u00edan rentas sobre la empresa de los coches.'><sup>7<\/sup><\/a><\/span>&#8230; Somos ahora treinta y cinco sacerdotes; ya pod\u00e9is pensar cu\u00e1les son nuestras dificultades para subsistir\u00bb.<\/p>\n<p>El 21 de junio siguiente, escrib\u00eda al sr Lagault, doctor en Sorbona, que hab\u00eda sido enviado a Roma, con Fran\u00e7ois Hallier, otro doctor en Sorbona y s\u00edndico de la Facultad de teolog\u00eda, para combatir all\u00ed al partido jansenista:<\/p>\n<p>\u00abLe dir\u00e9, a prop\u00f3sito del descenso solemne del relicario de santa Genoveva y de las procesiones generales que se han hecho para pedir a Dios el cese de los sufrimientos p\u00fablicos, por la intercesi\u00f3n de esta santa, que nunca se ha visto en Par\u00eds m\u00e1s concurso de gente, ni de devoci\u00f3n exterior. El efecto de esto ha sido que antes del octavo d\u00eda, el duque de Lorena, que ten\u00eda su ej\u00e9rcito a las puertas de Par\u00eds, y que estaba \u00e9l mismo en la ciudad, ha levantado el campo para volverse a su regi\u00f3n, habiendo tomado esta resoluci\u00f3n en el momento que el ej\u00e9rcito del Rey iba a caer sobre el suyo. Se contin\u00faa tambi\u00e9n desde entonces tratando de la paz con los pr\u00edncipes, y se espera de la bondad de Dios que se haga, tanto m\u00e1s cuanto se esfuerzan por apaciguar su justicia por grandes bienes que se hacen en Par\u00eds, con relaci\u00f3n a los pobres vergonzantes y con la pobre gente de los campos que se han refugiado aqu\u00ed. Se da cada d\u00eda potaje a catorce o quince mil que se morir\u00edan de hambre sin este socorro. Y tambi\u00e9n, se ha retirado a las j\u00f3venes a casas particulares, en n\u00famero de ocho o novecientas; y se va a enclaustrar a todas las religiosas refugiadas que se alojan por la ciudad&#8230; en un monasterio propuesto a este efecto, donde ser\u00e1n dirigidas por las Hijas de Santa Mar\u00eda\u00bb.<\/p>\n<p>El 21 de junio, Vicente pintaba al sr Lambert, superior de la casa de Varsovia, un cuadro de los m\u00e1s penosos de la miseria de Par\u00eds.<\/p>\n<p>Pocos d\u00edas despu\u00e9s el 2 de julio, se libraba el famoso combate del arrabal de San Antonio, entre los dos mayores capitanes del siglo, Turena y Cond\u00e9. El pr\u00edncipe estaba ya a punto de entrar rodeado por el peque\u00f1o ej\u00e9rcito del mariscal de la Fert\u00e9, que marchaba al socorro de Turena, cuando la Gran Se\u00f1orita (Ane-Marie-Louise d\u2019Orl\u00e9ans) mand\u00f3 sacar el ca\u00f1\u00f3n de la Bastilla sobre las tropas del Rey y forz\u00f3 a los Parisinos a abrir sus puertas a Cond\u00e9. Dos d\u00edas despu\u00e9s, el 4 de julio, ten\u00eda lugar en el Ayuntamiento una asamblea de los m\u00e1s notables burgueses de Par\u00eds. Como se mostraban titubeantes en abrazar la causa de Cond\u00e9 contra la del Rey, una multitud inmensa y amenazadora, enteramente entregada al pr\u00edncipe, y en la que se hab\u00edan infiltrado gran n\u00famero de sus soldados disfrazados, invadi\u00f3 de repente la plaza de Gr\u00e8ve y conmin\u00f3 a la asamblea para que firmara un decreto de uni\u00f3n con Cond\u00e9, para poner fin a sus vacilaciones, el populacho se precipita sobre el Ayuntamiento, le pega fuego, deg\u00fcella a cierto n\u00famero de burgueses, arranca a la asamblea aterrorizada el decreto de uni\u00f3n. Es lamentablemente cierto que los soldados del pr\u00edncipe, apostados en las ventanas de las casas, hicieron fuego sobre el Ayuntamiento, y que fue debido a este abominable atentado que se rindiera Cond\u00e9, pero tan s\u00f3lo por algunos d\u00edas, due\u00f1o de Par\u00eds y del Parlamento, \u00e9l forz\u00f3 a este \u00faltimo a renovar los decretos de proscripci\u00f3n contra Mazarino y a declarar al duque de Orl\u00e9ans lugarteniente general del reino.<\/p>\n<p>La corte se encontraba entonces en Saint-Denis, a donde hab\u00eda llegado a reunirse con ella el cardenal Mazarino. Nunca hab\u00eda ofrecido la guerra civil, desde el comienzo de la Fronda, un espect\u00e1culo m\u00e1s espantoso y m\u00e1s amenazador. Cond\u00e9 parec\u00eda resuelto a llevar las cosas al \u00faltimo extremo, si la corte se negaba a ceder a sus enormes pretensiones, y ella sab\u00eda todo lo que ten\u00eda que temer de \u00e9l. Vicente de Pa\u00fal, con el fin de conjurar las nuevas desgracias que iban a caer sobre Francia, trat\u00f3 de ponerse por medio nuevamente entre los pr\u00edncipes y la corte. Tuvo varias entrevistas con Cond\u00e9, con la Reina, con Mazarino, y tuvo la audacia de aconsejar a \u00e9ste \u00faltimo, para poner fin a los disturbios, que dejara otra vez Francia. Veamos una muy curiosa carta que le dirig\u00eda, poco despu\u00e9s del incendio del Ayuntamiento, para darle cuenta de sus negociaciones y para comprometerle a volver al camino del exilio:<\/p>\n<p>\u00abSuplico humildemente a Vuestra Eminencia que me perdone por haberme vuelto ayer por la tarde sin haber tenido el honor de recibir sus mandatos; me vi obligado a ello, por sentirme mal. El sr duque de Orl\u00e9ans acaba de notificarme que \u00e9l me enviar\u00e1 hoy al sr d\u2019Ornano (su notario de mandatos) para formularme respuesta, que ha deseado concertar con el Se\u00f1or pr\u00edncipe. Dije ayer a la Reina que hab\u00eda tenido el honor de celebrar una conversaci\u00f3n con los dos por separado, que fue respetuosa y de gracias. Dije a Su Alteza Real que si se restableciera al Rey en su autoridad y se diera un decreto de justificaci\u00f3n<span id='easy-footnote-8-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-8-121662' title='En favor del pr\u00edncipe de Cond\u00e9.'><sup>8<\/sup><\/a><\/span>. Vuestra Eminencia dar\u00eda la satisfacci\u00f3n que se desea (es decir su salida del reino); que dif\u00edcilmente se podr\u00eda arreglar este gran asunto por diputados, y que se necesitaban personas de rec\u00edproca confianza, que trataran las cosas de buenas a buenas. \u00c9l me testimoni\u00f3, de palabra y gesto, que esto le agradaba, y me dijo que hablar\u00eda con su consejo. Ma\u00f1ana por la ma\u00f1ana espero estar en condiciones de llevarle esta respuesta a Vuestra Eminencia\u00bb.<\/p>\n<p>Pero la actitud de Cond\u00e9 y del Parlamento se hab\u00eda vuelto cada vez m\u00e1s hostil al favorito. El Rey, para romper la resistencia del Parlamento, le orden\u00f3 dirigirse a Pontoise, donde resid\u00eda la corte entonces; pero la gran mayor\u00eda de sus miembros se neg\u00f3 a obedecerle.<\/p>\n<p>Desde el incendio y las masacres del ayuntamiento, Par\u00eds era presa de tal terror y de una miseria tan horrible, que la mayor parte de los que se hab\u00edan mostrado hasta entonces los m\u00e1s ardientes frondistas no aspiraban ya m\u00e1s que a la paz y suspiraban por el regreso del Rey.<\/p>\n<p>Su antiguo jefe, el cardenal de Retz, que hab\u00eda recibido desde hac\u00eda alg\u00fan tiempo la noticia de su promoci\u00f3n a la p\u00farpura (19 de febrero de 1652), se manten\u00eda prudentemente aparte, no se mezclaba m\u00e1s en intrigas, ostensiblemente al menos, y tan s\u00f3lo esperaba la ocasi\u00f3n de hacer olvidar su pasado mediante un tr\u00e1mite deslumbrante en favor de la paz. Implacable enemigo de Cond\u00e9, no pudiendo sacar nada en limpio del duque de Orl\u00e9ans, cuyo esp\u00edritu d\u00e9bil, irresoluto, sin cesar presa de terrores a menudo imaginarios, no le daba ninguna esperanza de continuar la lucha, Retz no pensaba ya, como \u00e9l mismo lo dijo, m\u00e1s que en salir con honra del juego. El Parlamento, fiel hasta el final en su odio contra Mazarino, fulminaba contra \u00e9l sus decretos de destierro y hab\u00eda puesto de nuevo precio a su cabeza. El cardenal, de acuerdo con la corte, hab\u00eda renovado la comedia que hab\u00eda representado ya varias veces; hab\u00eda fingido ceder a las amenazas del Parlamento, y se hab\u00eda retirado a Bouillon, muy resuelto con todo a regresar a Francia, cuando el cansancio de la gente hiciera posible su regreso. Aprovecharse de su ausencia para pedir la paz al Rey y su vuelta a Par\u00eds, pareci\u00f3 al cardenal de Retz un golpe maestro. Con ello, escapaba a toda sospecha de mazarinismo, y se colocaba el primero como negociador y \u00e1rbitro de la paz, convertida en el deseo m\u00e1s ardiente de los Parisinos. Retz se abri\u00f3 con este proyecto a la princesa Palatina, Anne de Gonzaga, cuyo genio pol\u00edtico \u00e9l conoc\u00eda. La princesa le propuso precipitar las cosas y sorprender a la corte, para que Mazarino exiliado no tuviera tiempo de oponerse a un paso que pod\u00eda asegurar a su rival la impunidad y hasta el favor real. Esta clara previsi\u00f3n de la princesa estaba tan bien fundada, que Mazarino, cada vez m\u00e1s inquieto por el silencio del hombre a quien m\u00e1s tem\u00eda en Par\u00eds, escrib\u00eda a uno de sus confidentes, en septiembre de 1652, esta carta caracter\u00edstica, que hace ya prever la cat\u00e1strofe final del antiguo jefe de la Fronda: \u00abOs conjuro que os dediqu\u00e9is a romper, por todos los medios posibles, los designios del cardenal de Retz, y tener como art\u00edculo de fe que, no obstante todas las cosas hermosas que haga y las protestas de su pasi\u00f3n al servicio de la Reina, y querer servirme sinceramente y empujar al sr pr\u00edncipe, no tiene nada bueno en el alma, ni para el Estado, ni para la Reina, ni para m\u00ed. Conviene pues guardar bien las apariencias y evitar que se introduzca y que pueda jugar aparentemente, ni en la corte, ni en Par\u00eds, el personaje de servidor del Rey, bien intencionado, ya que es incapaz de serlo nunca. No os costar\u00e1 gran cosa con la Reina en esto, puesto que le conoce demasiado bien para fiarse nunca<span id='easy-footnote-9-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-9-121662' title='Mazarino a Nicolas Foucquet, procurador general, 6 de septiembre de 1652.'><sup>9<\/sup><\/a><\/span>\u00ab.<\/p>\n<p>Antes de referir el viaje que hizo el cardenal de Retz a Compi\u00e8gne, a la cabeza de su clero, para pedir la paz al Rey y su regreso a Par\u00eds, es indispensable recordar al lector las diversas tentativas que hizo Vicente con el mismo prop\u00f3sito, y que precedieron a este viaje. Hemos visto c\u00f3mo, en varias ocasiones, bajo la antigua Fronda, hab\u00eda tratado, con miras a la paz, de poner a prueba su cr\u00e9dito ante la Reina y Mazarino, y qu\u00e9 mal le hab\u00eda salido. Durante la residencia de la corte en Saint-Denis, hab\u00eda intentado, no menos vanamente reconciliar al Rey y a los pr\u00edncipes (julio de 1652). En el mes de agosto siguiente, hab\u00eda dirigido al papa Inocencio X una carta conmovedora para implorar sus plegarias y su intervenci\u00f3n, \u00abcon el fin de reunir a la casa real y de apagar la guerra civil\u00bb. Pero el Papa, muy poco satisfecho de la pol\u00edtica galicana de Mazarino, se hab\u00eda guardado mucho de ayudarle, ech\u00e1ndole una mano a una reconciliaci\u00f3n de los pr\u00edncipes con la corte.<\/p>\n<p>Por una extra\u00f1a coincidencia, que se podr\u00eda creer a primera vista efecto de un acuerdo entre el cardenal de Retz y de Vicente de Pa\u00fal, \u00e9ste, el 11 de septiembre de 1652, es decir la v\u00edspera misma del viaje de Retz a Compi\u00e8gne, dirigi\u00f3 al cardenal Mazarino una carta de las m\u00e1s importantes sobre el estado de la gente en la capital, carta que nos revela al propio tiempo por su parte un notable talento diplom\u00e1tico. \u00bfFue acaso inspirada esta carta a Vicente por su antiguo alumno? En un principio nos sentir\u00edamos tentados a suponerlo, tan digna es del genio de Retz, por la extrema habilidad que en ella se descubre en cada l\u00ednea; pero Vicente declara con toda seriedad a Mazarino que no se lo ha comunicado a nadie en el mundo, y la palabra de Vicente debe sernos suficiente. Esta es la carta, que nos muestra a Vicente bajo un aspecto totalmente nuevo de un negociador muy al corriente de las cuestiones m\u00e1s delicadas, y conocedor de las soluciones con tanta prudencia como destreza en las cuestiones m\u00e1s dif\u00edciles. En ella se ver\u00e1 sobre todo con qu\u00e9 arte y qu\u00e9 recursos aconseja al cardenal Mazarino que no vuelva a Par\u00eds con el Rey, lo que podr\u00eda volver a prender el fuego de la sedici\u00f3n, pero que provoque \u00e9l mismo el regreso del Rey, sobre quien ya se sabe que su influencia es grande, lo que le conciliar\u00e1 poco a poco los esp\u00edritus m\u00e1s hostiles y har\u00e1 pronto f\u00e1cil su propio regreso.<\/p>\n<p>\u00abPar\u00eds, a 11 de septiembre de 1652.<\/p>\n<p>\u00abMonse\u00f1or,<\/p>\n<p>\u00abMe tomo la confianza de escribir a Vuestra Eminencia. Yo la suplico que la reciba con agrado y que le diga que veo ahora la ciudad de Par\u00eds recobrada del estado en que estaba, y pedir al Rey y a la Reina a voz en cuello; que no voy a ning\u00fan lugar y no veo a nadie que no me hable de lo mismo. No hay hasta las Damas de la Caridad, que son las primeras de Par\u00eds, que no me digan que si Sus Majestades se acercan, que ir\u00edan un regimiento de Damas a recibirlas en triunfo. Y seg\u00fan eso, Monse\u00f1or, pienso que Vuestra Eminencia har\u00e1 un acto digno de su bondad aconsejando al Rey y a la Reina que vuelvan a tomar posesi\u00f3n de su ciudad y de los corazones de Par\u00eds. Pero como hay muchas cosas que decir contra esto, estas son las dificultades m\u00e1s importantes y la respuesta que yo les doy y que yo suplico muy humildemente a Vuestra Eminencia que lea y considere.<\/p>\n<p>\u00abLa primera es que habiendo todav\u00eda cantidad de almas buenas en Par\u00eds y de burgueses que est\u00e1n en los sentimientos que digo, hay sin embargo cantidad de otras que son de sentimiento contrario, al menos no conozco a nadie, y que los indiferentes, si los hay, ser\u00e1n arrastrados por la multitud y la fuerza de los que ponen calor en ello, que es la mayor parte de Par\u00eds, quiz\u00e1s aquellos que temer\u00edan la tocada<span id='easy-footnote-10-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-10-121662' title='El castigo.'><sup>10<\/sup><\/a><\/span>, si no esperaran la amnist\u00eda.<\/p>\n<p>\u00abEn segundo lugar que hay raz\u00f3n para temer que la presencia de los jefes del partido contrario haga repetir la jornada del Palais<span id='easy-footnote-11-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-11-121662' title='La jornada del 25 de junio de 1652, en que los pr\u00edncioes de Cond\u00e9 y de Gondi, decleraron en las c\u00e1maras en asamblea que tan pronto como el cardenal Mazarino estuviera fuera del reino, ellos ejecutar\u00edan fielmente todos los art\u00edculos comprendidos en la respuesta del Rey, etc.'><sup>11<\/sup><\/a><\/span> y la de la casa de la ciudad<span id='easy-footnote-12-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-12-121662' title='Sitio e incendio del Ayuntamiento por los soldados disfrazados del pr\u00edncipe de Cond\u00e9.'><sup>12<\/sup><\/a><\/span>; a lo que respondo que uno de ellos<span id='easy-footnote-13-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-13-121662' title='El duque de Orl\u00e9ans.'><sup>13<\/sup><\/a><\/span> estar\u00e1 encantado por esta ocasi\u00f3n para arreglarse con el Rey, y que el otro<span id='easy-footnote-14-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-14-121662' title='El pr\u00edncope de Cond\u00e9.'><sup>14<\/sup><\/a><\/span>, viendo Par\u00eds devuelto a la obediencia del Rey, se someter\u00e1, de lo que no se ha de dudar, lo s\u00e9 de buena tinta.<\/p>\n<p>\u00abEn tercer lugar, algunos ir\u00e1n tal vez a decir a Vuestra Eminencia que hay que castigar a Par\u00eds para que recobre la cordura; y yo pienso, Monse\u00f1or, que conviene que Vuestra Eminencia se acuerde de c\u00f3mo se comportaron los reyes bajo los cuales se revolucion\u00f3 Par\u00eds; hallar\u00e1 que procedieron con suavidad, y que Carlos VI, por haber castigado a un gran n\u00famero de rebeldes, desarmado y quitado las cadenas de la ciudad<span id='easy-footnote-15-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-15-121662' title='Caatigo de los maillotinos y desrden de los cabochiens, Bourgui\u00f1ones y Armagnacos.'><sup>15<\/sup><\/a><\/span>, no hizo sino echar le\u00f1a al fuego e incendiar lo dem\u00e1s, de manera que durante diecis\u00e9is a\u00f1os continuaron la sedici\u00f3n, contradijeron al Rey m\u00e1s que antes, y se coaligaron para ello con los enemigos del Estado, y por fin a Enrique III, ni el propio Rey<span id='easy-footnote-16-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-16-121662' title='Luis XIV, bajo la primera Fronda, puso asedio a Par\u00eds.'><sup>16<\/sup><\/a><\/span>, no les fue bien por bloquearlos. Decir que Vuestra Eminencia firmar\u00e1 la paz con Espa\u00f1a, y volver\u00e1 triunfante a caer sobre Par\u00eds y ponerle en raz\u00f3n, yo respondo, Monse\u00f1or, que mucho menos se establezca mejor en los esp\u00edritus del reino por la paz con Espa\u00f1a; que por el contrario adquirir\u00e1 m\u00e1s odio que nunca, en el supuesto que se devuelva al Espa\u00f1ol todo lo que tenemos suyo, como se dice que quiere hacer Vuestra Eminencia&#8230;<\/p>\n<p>\u00abQue se piense que antes del regreso de Sus Majestades a esta ciudad, es mejor tratar con Espa\u00f1a y los se\u00f1ores pr\u00edncipes, permitidme que os diga que en tal caso Par\u00eds se ver\u00e1 comprendido en los art\u00edculos de la paz y ganar\u00e1 con su amnist\u00eda de Espa\u00f1a y de dichos se\u00f1ores, y no del Rey, de quien recibir\u00e1 un agradecimiento tal , que se declarar\u00e1 en su favor en la primera ocasi\u00f3n.<\/p>\n<p>\u00abAlgunos podr\u00e1n decir a Su Eminencia que sus intereses particulares requieren que el Rey no reciba en gracia a este pueblo, y no vuelva a Par\u00eds sin Ella, pero que conviene embarullar los asuntos y mantener la guerra, para dar a entender que no es Vuestra Eminencia la que levanta la tempestad sino la malignidad de la gente que no quieren someterse a la voluntad de su pr\u00edncipe. Respondo, Monse\u00f1or, que no importa tanto que el regreso de Vuestra Eminencia sea antes o despu\u00e9s del Rey, mientras sea, y que el Rey restablecido en Par\u00eds, Su Majestad podr\u00e1 mandar volver a Vuestra Eminencia cuando guste, y estoy seguro de ello. Adem\u00e1s, si es que vuestra Eminencia, que tiene en consideraci\u00f3n principalmente el bien del Rey, de la Reina y del Estado, contribuye a la reuni\u00f3n de la casa real y de Par\u00eds, y a la obediencia del Rey, con toda seguridad, Monse\u00f1or, volver\u00e1 a ganarse las mentes, y en poco tiempo ser\u00e1 llamada, afortunadamente, como ya he dicho; pero mientras que la gente se halle alborotada, es de temer que nunca podr\u00e1 lograrse la paz en estas condiciones, por tratarse de la locura popular, y la experiencia nos ense\u00f1a que los que est\u00e1n heridos de esta enfermedad no curan nunca por lo mismo que false\u00f3 las ruedas de su mente. Y si es verdad, como se dice, que vuestra Eminencia ha dado orden de que el Rey no escuche a los se\u00f1ores pr\u00edncipes, que no les d\u00e9 pasaportes para acudir a Sus Majestades, que no se escuche ninguna representaci\u00f3n ni delegaci\u00f3n, y que a este efecto Vuestra Eminencia ha colocado con el Rey y la Reina a extranjeros, sus criados, que cierran las entradas por todos los lados a fin de impedir que se hable con Sus Majestades, es mucho de temer que esto contin\u00fae, que la ocasi\u00f3n se pierda. Si Vuestra Eminencia aconseja al Rey que venga a recibir las aclamaciones de este pueblo, se ganar\u00e1 los corazones de aquellos del reino que saben bien de lo que es capaz ante el Rey y la Reina, y todos deberemos esta gracia a vuestra Eminencia.<\/p>\n<p>\u00abEsto es, Monse\u00f1or, cuanto me atrevo a proponeros, en la confianza de que no lo ve\u00e1is con malos ojos, sobre todo cuando sep\u00e1is que no se lo he dicho a nadie del mundo m\u00e1s que a un servidor de Vuestra Eminencia, a quien me doy el honor de escribirle, y que no estoy en comunicaci\u00f3n con mis antiguos amigos, que tienen los sentimientos contrarios a la voluntad del Rey<span id='easy-footnote-17-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-17-121662' title='Alphonse Feillet ha dicho, en una nota de su volumen, &lt;i&gt;la Mis\u00e8re&lt;\/i&gt;&lt;i&gt; au temps de la Fronde&lt;\/i&gt; que, en este pasaje, Vicente dssignaba entre otros al cardenal de Retz fuera de los sentimientos del Rey. Es un error, el cardenal deseaba vivamente entonces la vuelta de Luis XIV a Par\u00eds, y se puso incluso, como se ver\u00e1 pronto, a la cabeza de una delegaci\u00f3n del clero de Par\u00eds, para ir a pedir la paz.'><sup>17<\/sup><\/a><\/span>; que no he comunicado la presente a nadie, y que vivir\u00e9 y morir\u00e9 en la obediencia a Vuestra Eminencia, a la que Nuestro Se\u00f1or me ha dado de una manera particular. Por todo lo cual os aseguro, ser para siempre, Monse\u00f1or, vuestro muy humilde, obediente y muy fiel servidor.<\/p>\n<p>Vicente de Pa\u00fal.\u00bb<\/p>\n<p>Al d\u00eda siguiente del d\u00eda en que se escribi\u00f3 esta carta, el cardenal de Retz, sin sospechar de las instrucciones que hab\u00eda enviado Mazarino contra \u00e9l a la corte, pon\u00eda en marcha el plan que hab\u00eda concertado con la princesa Palatina. Esperaba, desempe\u00f1ando, al final de la Fronda, el papel de pacificador general, al que le llamaba bastante naturalmente su doble calidad de arzobispo de Par\u00eds y de cardenal, no s\u00f3lo a entrar en gracia a la corte, sino tambi\u00e9n a ganarse quiz\u00e1, en ausencia de Mazarino, el favor de la Reina. Ten\u00eda, adem\u00e1s, un pretexto muy oportuno para dirigirse a Compi\u00e8gne, y era ir a recibir de las manos del Rey, su capelo de cardenal, que hac\u00eda poco hab\u00eda llegado de Roma. El 12 de septiembre, se puso pues en camino con una larga fila de carrozas, llenas de can\u00f3nigos del cap\u00edtulo de Nuestra Se\u00f1ora y de los p\u00e1rrocos de Par\u00eds, escoltados por los guardas del duque de Orl\u00e9ans y por numerosos gentilhombres a caballo. El joven Rey y la Reina madre se reservaron hasta el punto de darle una buena acogida; Retz mismo, tan fino de ordinario, por un momento se vio enga\u00f1ado. Recibi\u00f3 en primer lugar, en gran ceremonia, de las manos de Luis XIV, el gorro de cardenal; luego, en presencia de toda la corte, \u00abel h\u00e1bil burl\u00f3n\u00bb pronunci\u00f3 una arenga muy elocuente, llena de sentimientos elevados, y tal como era de esperar de un hombre capaz de representar todos los papeles. El Rey, con el fin de meditar su respuesta con tranquilidad, esper\u00f3 hasta el d\u00eda siguiente para transmit\u00edrsela por escrito. A trav\u00e9s de las palabras de una aparente suavidad, hac\u00eda esperar su regreso pr\u00f3ximo a Par\u00eds, con tal que, a\u00f1ad\u00eda se\u00f1alando con medias palabras al jefe de la nueva Fronda, al pr\u00edncipe de Cond\u00e9 y sus partidarios, con tal que los Parisinos hicieran algo para apresurarlo, \u00ab<i>no aguantando m\u00e1s el poder violento de los que quer\u00edan hacer proseguir los disturbios, <\/i>que hab\u00edan expulsado a los enemigos extranjeros y dom\u00e9sticos, opresores de sus libertades, para recibir al rey Enrique el Grande en su ciudad\u00bb.<\/p>\n<p>Los Parisinos, hac\u00eda algunos meses, hab\u00edan asistido, efectivamente, a un espect\u00e1culo extra\u00f1o: hab\u00edan visto ondear en el Puente Nuevo las banderas y los estandartes de Espa\u00f1a., y cruzarse por sus calles, con toda libertad, las fajas amarillas de Lorena, amarillo p\u00e1lido (isabelinas) de Cond\u00e9 y fajas azules del duque de Orl\u00e9ans. Solas, las fajas blancas del Rey estaban proscritas del escenario<span id='easy-footnote-18-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-18-121662' title='Antes de la adopci\u00f3n de la escarapela, los ej\u00e9rcitos de Europa se distingu\u00edan unos de otros por el color de sus fajas.'><sup>18<\/sup><\/a><\/span>. La respuesta de Luis XIV distaba mucho de lo que hab\u00eda esperado el cardenal de Retz, hab\u00eda llegado a esperar concluir la paz en nombre del duque de Orl\u00e9ans y, al conseguir el regreso en gracia de este pr\u00edncipe, ponerse \u00e9l mismo a cubierto. Pero la corte ten\u00eda otros planes y Retz, en sus Memorias, confiesa que su negociaci\u00f3n no tuvo gran \u00e9xito. Le remitieron a Servien y a Le Tellier quienes, debidamente <i>soplados<\/i> por Mazarino, le pagaron con vanas palabras y se guardaron muy bien de concluir nada con \u00e9l, \u00abde manera que reemprendi\u00f3 el camino de Par\u00eds sin llevarse nada m\u00e1s que su capelo de cardenal<span id='easy-footnote-19-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-19-121662' title='Bazin, &lt;i&gt;Histoire de France sous le minist\u00e8re du cardinal Mazarin. &lt;\/i&gt;'><sup>19<\/sup><\/a><\/span>\u00ab, y a\u00f1adamos tambi\u00e9n la esperanza, un tanto quim\u00e9rica, de su perd\u00f3n: feliz todav\u00eda y contento por el escaso precio, ya que los \u00e1nimos violentos, tales como el abate Fouquet, hab\u00edan agitado en el consejo de la Reina si hab\u00eda que detenerlo y matarlo; y no hab\u00eda escapado a la prisi\u00f3n o a la muerte m\u00e1s que por miedo a violar, por tal atentado, la fe p\u00fablica. De regreso a Par\u00eds, Retz se enter\u00f3 de estos detalles por su padre, a quien se los hab\u00eda revelado el P. Senault, del Oratorio, seg\u00fan \u00f3rdenes del pr\u00edncipe Thomas de Savoie, que hab\u00eda asistido a la deliberaci\u00f3n, y se hab\u00eda opuesto con fuerza a este plan criminal<span id='easy-footnote-20-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-20-121662' title='&lt;i&gt;M\u00e9moires de Retz, &lt;\/i&gt;edic. Hachette, tomo IV, p. 337 y 338.'><sup>20<\/sup><\/a><\/span>.<\/p>\n<p>Poco despu\u00e9s, el Rey entraba en Par\u00eds en medio de las aclamaciones de un pueblo inmenso. Cond\u00e9 no hab\u00eda esperado hasta entonces para salir de all\u00ed con las escasas tropas que le hab\u00edan seguido fieles. El h\u00e9roe de Rocroi y de Lens iba a desempe\u00f1ar en el campo espa\u00f1ol el papel de <i>condottiere (<\/i>capit\u00e1n de soldados aventureros)<i>.<\/i> El Rey, en un lecho de justicia, le hab\u00eda declarado \u00abcriminal de lesa majestad y traidor a la patria\u00bb, lo mismo que al pr\u00edncipe de Conti, la duquesa de Longueville, el duque de la Rochefoucauld, el pr\u00edncipe de Tarento y dem\u00e1s afiliados. El duque de Orl\u00e9ans, el duque de Beaufort, el marqu\u00e9s de Ch\u00e2teauneuf y Broussel, este antiguo \u00eddolo del pueblo, hab\u00edan sido desterrados. Un \u00fanico hombre tuvo la ilusi\u00f3n de creer que estar\u00eda al abrigo de los rigores del poder, y este hombre, el m\u00e1s culpable de todos, era el antiguo jefe de la vieja Fronda, el cardenal de Retz. Para ahorrarse una violencia contra la p\u00farpura de la que estaba revestido, el Rey la hab\u00eda ofrecido la direcci\u00f3n de los asuntos de Francia en Roma, durante tres a\u00f1os, con el pago de sus deudas y un rico trato para producirse all\u00ed en gran figura. Con una imprudencia y una audacia sin igual, Retz no acept\u00f3 esta oferta m\u00e1s que a condici\u00f3n de que la corte hiciera justicia con antelaci\u00f3n a las pretensiones de sus amigos las cuales, realmente, eran muy exageradas. A partir de entonces se decret\u00f3 su perdici\u00f3n, y la corte, a fin de apoderarse de su persona, no descuid\u00f3 nada para adormecer a su vigilancia. Por una palabra artificiosa de la Reina, que hab\u00eda dicho en p\u00fablico, para que corriera la voz, que el regreso del Rey era obra suya, este hombre, tan prudente de ordinario, tan penetrante, tan dif\u00edcil de enga\u00f1ar, se dej\u00f3 caer en la trampa como un novicio. Se puso con toda tranquilidad a predicar y a visitar a las se\u00f1oras. Fi\u00e1ndose un tanto demasiado de la credulidad de sus oyentes y de su ausencia de memoria, tuvo la extra\u00f1a audacia, en Saint-Germain l\u2019Auxerrois, en la misma presencia de la corte, de pronunciar un serm\u00f3n contra la ambici\u00f3n. El serm\u00f3n tuvo por otra parte el mayor \u00e9xito. La Rochefoucauld encontr\u00f3 en \u00e9l el tema tan agradable en la boca de Retz, que escribi\u00f3 a uno de sus amigos \u00abque no se esperaba otra cosa contra los sediciosos\u00bb. Y en verdad, el nuevo cardenal era muy capaz de ello, \u00e9l que, en su juventud, habr\u00eda hecho uno contra la hipocres\u00eda.<\/p>\n<p>Lleg\u00f3 hasta tal punto su ceguera y audacia que se atrevi\u00f3 a desafiar a la corte, a pasear por Par\u00eds, con una numerosa escolta, \u00aba ocupar el pavimento\u00bb, como \u00e9l mismo dec\u00eda, esperando que acabar\u00eda por capitular y suscribir todas sus exigencias en favor de sus amigos. Pero el tiempo de las bravatas se hab\u00eda pasado, y el joven Rey, alentado por Mazarino, quien le traslad\u00f3 instrucciones secretas, resolvi\u00f3 acabar con este genio turbulento e incapaz de descansar. Dio orden a Pradelle, capit\u00e1n de sus guardias, orden escrita y firmada de su propia mano, que a\u00fan existe, de detener al cardenal de Retz, <i>muerto o vivo, en caso de <\/i>r<i>esistencia por su parte.<\/i> Se sabe c\u00f3mo, el 19 de diciembre de 1652, lleno de una confianza ciega, a pesar de varios avisos secretos que le aconsejaban abstenerse, el prelado se dirigi\u00f3 al Louvre, y c\u00f3mo fue detenido all\u00ed por el marqu\u00e9s de Villequier y de all\u00ed conducido al castillo de Vincennes<span id='easy-footnote-21-121662' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#easy-footnote-bottom-21-121662' title='Se encontr\u00f3 en sus bolsillos el plan, escrito por su propia mano, que deb\u00eda predicar en el Oratorio el mes de junio siguiente, y cuyo original de encuentra en la Biblioteca nacional, en los papeles de Le Tellier.'><sup>21<\/sup><\/a><\/span>.<\/p>\n<p>\u00bfQu\u00e9 debi\u00f3 pensar Vicente de Pa\u00fal de la detenci\u00f3n de su antiguo alumno? Sus sentimientos sobre este particular no pod\u00edan ser dudosos, si bien, en los documentos de la \u00e9poca, no queda ning\u00fan rastro de esto. El antiguo jefe de la vieja Fronda era seguramente un gran culpable, pero quedaba a cubierto de la amnist\u00eda; pr\u00edncipe de la Iglesia, arzobispo designado de la di\u00f3cesis de Par\u00eds, revestido de un car\u00e1cter sagrado, el poder civil no ten\u00edan ning\u00fan derecho a retenerle en prisi\u00f3n, sin haberle mandado juzgar de antemano por una corte eclesi\u00e1stica, lo que nunca se llev\u00f3 a cabo durante todo el tiempo de su detenci\u00f3n. Vicente de Pa\u00fal no pod\u00eda pues aprobar esta odiosa violencia de un cardenal contra otro cardenal y, a prop\u00f3sito de un hecho an\u00e1logo, ya tendremos enseguida la prueba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cap\u00edtulo XIV Vicente de Pa\u00fal durante la Fronda. &#8211; El cardenal de Retz cabeza de los Frondistas. &#8211; Vicente diplom\u00e1tico y gran capell\u00e1n de Francia. &#8211; Plenos poderes que le da Luis XIV, lo mismo &#8230; <a href=\"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":404925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[218,224,119,144,172,127,143],"class_list":["post-121662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vicente-de-paul","tag-abelly","tag-berulle","tag-gondi","tag-lambert","tag-pobreza","tag-portail","tag-san-lazaro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Cap\u00edtulo XIV Vicente de Pa\u00fal durante la Fronda. &#8211; El cardenal de Retz cabeza de los Frondistas. &#8211; Vicente diplom\u00e1tico y gran capell\u00e1n de Francia. &#8211; Plenos poderes que le da Luis XIV, lo mismo ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T06:53:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1875\" \/>\n\t<meta property=\"og:image:height\" content=\"1292\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"38 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14\",\"datePublished\":\"2024-07-25T06:53:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/\"},\"wordCount\":8929,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aaaf.jpg?fit=1875%2C1292&ssl=1\",\"keywords\":[\"Abelly\",\"Berulle\",\"Gondi\",\"Lambert\",\"Pobreza\",\"Portail\",\"San L\u00e1zaro\"],\"articleSection\":[\"Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/\",\"name\":\"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aaaf.jpg?fit=1875%2C1292&ssl=1\",\"datePublished\":\"2024-07-25T06:53:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aaaf.jpg?fit=1875%2C1292&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/aaaf.jpg?fit=1875%2C1292&ssl=1\",\"width\":1875,\"height\":1292},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-y-los-gondi-capitulo-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/","og_locale":"es_ES","og_type":"article","og_title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14 - Somos Vicencianos","og_description":"Cap\u00edtulo XIV Vicente de Pa\u00fal durante la Fronda. &#8211; El cardenal de Retz cabeza de los Frondistas. &#8211; Vicente diplom\u00e1tico y gran capell\u00e1n de Francia. &#8211; Plenos poderes que le da Luis XIV, lo mismo ... Read More","og_url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2024-07-25T06:53:47+00:00","og_image":[{"width":1875,"height":1292,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"38 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14","datePublished":"2024-07-25T06:53:47+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/"},"wordCount":8929,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1","keywords":["Abelly","Berulle","Gondi","Lambert","Pobreza","Portail","San L\u00e1zaro"],"articleSection":["Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/","url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/","name":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1","datePublished":"2024-07-25T06:53:47+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1","width":1875,"height":1292},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 14"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1875%2C1292&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-vEi","jetpack-related-posts":[{"id":121666,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-15\/","url_meta":{"origin":121662,"position":0},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 15","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/07\/2024","format":false,"excerpt":"Cap\u00edtulo XV El cardenal de Retz e Inocencio X. - Muerte del arzobispo de Par\u00eds, Juan Francisco de Gondi, y toma de posesi\u00f3n del arzobispado por Retz. - Exilio del P. de Gondi en sus tierras de Villepreux. - Vana tentativa de Vicente de Pa\u00fal en su favor. - Retz\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":121661,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-18-y-ultimo\/","url_meta":{"origin":121662,"position":1},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 18 y \u00faltimo","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/08\/2024","format":false,"excerpt":"Cap\u00edtulo XVIII: Ep\u00edlogo Regreso del cardenal de Retz a Commercy. - Su dimisi\u00f3n del arzobispado de Par\u00eds a cambio de la abad\u00eda de Saint-Denis. - El Se\u00f1or de Marca, su sucesor. - Muerte del P. de Gondi. - Regreso a Par\u00eds del cardenal de Retz. Su hubi\u00e9ramos tenido que consultar\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":126489,"url":"https:\/\/vincentians.com\/es\/el-cardenal-jean-francois-paul-retz\/","url_meta":{"origin":121662,"position":2},"title":"El Cardenal Jean Fran\u00e7ois-Paul Retz","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/01\/2024","format":false,"excerpt":"l. Los comienzos de una carrera prometedora Juan Francisco Pablo de Gondi naci\u00f3 en 1613 en el castillo de Montmirail. Su bautismo lleva la fecha del 20 de setiembre. Es el tercer hijo de Felipe Manuel de Gondi, general de las galeras, y de Margarita de Silly. Pertenece a la\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":121642,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-04\/","url_meta":{"origin":121662,"position":3},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 04","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/07\/2024","format":false,"excerpt":"Cap\u00edtulo IV Vicente de Pa\u00fal en la casa del general de las galeras. - Retratos de familia: Felipe Manuel de Gondi, su mujer Margarita de Silly y sus hijos. - Vicente de Pa\u00fal, fundador. Volvamos sobre nuestros pasos y entremos en el castillo de Montmirail donde, hacia el fin del\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":121665,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-16\/","url_meta":{"origin":121662,"position":4},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 16","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2024","format":false,"excerpt":"Cap\u00edtulo XVI \u00daltimas obras de Vicente de Pa\u00fal. - Sus cartas de adi\u00f3s al cardenal de Retz y al Padre de Gondi. - Sus \u00faltimos momentos, su muerte y sus funerales. El maravilloso impulso que Vicente de Pa\u00fal hab\u00eda impreso a la caridad p\u00fablica se hab\u00eda aminorado singularmente durante los\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":121641,"url":"https:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-03\/","url_meta":{"origin":121662,"position":5},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 03","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/07\/2024","format":false,"excerpt":"Cap\u00edtulo III Jean-Fran\u00e7ois de Gondi, primer arzobispo de Par\u00eds. Retrato de este prelado por su sobrino el cardenal de Retz y por el Padre Rapin. - Administraci\u00f3n de Fran\u00e7ois de Gondi. - Sus diferendos con su sobrino, el coadjutor de Par\u00eds. - Jugada que le hace \u00e9ste a su t\u00edo\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/121662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=121662"}],"version-history":[{"count":1,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/121662\/revisions"}],"predecessor-version":[{"id":405402,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/121662\/revisions\/405402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/404925"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=121662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=121662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=121662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}