{"id":121247,"date":"2013-05-04T07:14:10","date_gmt":"2013-05-04T05:14:10","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=121247"},"modified":"2013-05-04T07:14:10","modified_gmt":"2013-05-04T05:14:10","slug":"escuchar-la-palabra-de-dios","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/","title":{"rendered":"Escuchar la Palabra de Dios"},"content":{"rendered":"<p style=\"padding-left: 30px;text-align: justify\"><i>Cada ma\u00f1ana me despierta para que oiga, para que escuche como disc\u00edpulo. El Se\u00f1or Yahv\u00e9 me ha abierto el o\u00eddo. <\/i>Is 50,4-5<\/p>\n<p style=\"padding-left: 30px;text-align: justify\"><i>Ante todo cada uno de nosotros se esforzar\u00e1 por convencerse de esta verdad: que la ense\u00f1anza de Cristo no puede enga\u00f1ar nunca, mientras que la del mundo es siempre falaz. El mismo Cristo afirma que \u00e9sta es como una casa construida sobre arena, mientras que su propia doctrina es como un edificio fundamentado sobre roca s\u00f3lida. <\/i>RC II,1<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/leer_la_palabra.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-121250\" alt=\"leer_la_palabra\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/leer_la_palabra-300x191.jpg?resize=300%2C191\" width=\"300\" height=\"191\" \/><\/a>Como disc\u00edpulo que eres, el primer servicio que debes a Dios es el de escucharle. En tiempo de Jes\u00fas todos los jud\u00edos fieles aprend\u00edan de memoria las vivas palabras del Deuteronomio (6,4-7): \u00ab\u00a1Escucha Israel! \u00a1El Se\u00f1or es nuestro Dios, el \u00fanico Se\u00f1or! Por eso, amar\u00e1s al Se\u00f1or tu Dios con todo tu coraz\u00f3n, con toda tu alma, y con todas tus fuerzas. Graba en tu coraz\u00f3n estas palabras que te digo hoy. Ens\u00e9\u00f1aselas a tus hijos. Habla de ellas en casa y fuera de ella, en el trabajo y en el descanso.\u00bb<\/p>\n<p style=\"text-align: justify\">El amor de Dios comienza por escuchar la pala\u00adbra de Dios y por tener fe en el amor que Dios nos tiene: \u00abEn esto consiste el amor: no en que nosotros amemos a Dios sino en que \u00e9l nos am\u00f3 primero\u00bb (1 Jn 4,10). Tambi\u00e9n tu amor al pr\u00f3jimo tiene que comenzar por escuchar.<\/p>\n<p style=\"text-align: justify\">Aprende, pues a escuchar bien. Deja que te informen, que te ense\u00f1en, que te cambien otros cuando \u00abanuncian el evangelio\u00bb a trav\u00e9s de lo que hacen y dicen, los miembros de tu familia, los que trabajan contigo, y sobre todo los pobres. Tienes que o\u00edr primero la buena noticia antes de que puedas responder a ella y puedas vivirla.<\/p>\n<p style=\"text-align: justify\">Mientras escuchas, la palabra de Dios ir\u00e1 entrando en tu vida de modos sorprendentes y diversos. Te cambiar\u00e1. Te vendr\u00e1 a veces como comida (Sal 19,11) para darte fuerzas y hacerte cre\u00adcer. Otras veces ser\u00e1 como agua fresca (Is 55,10) para calmar tu sed mientras caminas. Otras veces la palabra de Dios te golpear\u00e1 como el martillo que rompe la roca (Jr 23,29), destrozando tus h\u00e1bitos rutinarios o tu dureza de coraz\u00f3n. O tal vez te hiera como una espada de dos filos (Hb 4,12) para atrave\u00adsar tu pasividad.<\/p>\n<p style=\"text-align: justify\">Lee cada d\u00eda a manera de meditaci\u00f3n un trozo<em> de la Escritura. San Vicente de Pa\u00fal nos dice que la palabra de Dios no falla nunca. Llega siempre al fondo de la persona. Se dirige no s\u00f3lo a toda la comunidad de los creyentes sino tambi\u00e9n a ti de m<\/em>anera individual. Esc\u00fachala, med\u00edtala, digi\u00e9rela, y act\u00faa movido por ella. As\u00ed llegar\u00e1s a ser como \u00abuna casa construida sobre roca\u00bb. Como una manera pr\u00e1ctica de meditar cada d\u00eda en la Escritura, algunos meditan las lecturas que la Iglesia escoge para la misa del d\u00eda. Otros prefieren una lectura sistem\u00e1tica de toda la Biblia a lo largo de un a\u00f1o.<\/p>\n<p style=\"text-align: justify\">Dios se queja muy a menudo en las Escrituras de que, aunque \u00e9l hable, su pueblo \u00abno escucha\u00bb. Los verdaderos profetas eran oyentes eximios, o\u00edan lo que Dios ten\u00eda que decir, y luego hablaban en nombre de Dios. \u00abHabla, Se\u00f1or, que tu siervo escucha\u00bb, dec\u00eda el ni\u00f1o Samuel (1Sm 3,10) al comenzar su carrera de profeta.<\/p>\n<p style=\"text-align: justify\">Nosotros creemos que Jes\u00fas es la Palabra de Dios, el cumplimiento de las Escrituras. En \u00e9l se ha sellado definitivamente la alianza nueva y eterna entre Dios y el pueblo de Dios. La persona de Jes\u00fas y sus palabras nos revelan a Dios.<\/p>\n<p style=\"text-align: justify\">Mar\u00eda es la disc\u00edpula preeminente. Ella escucha la palabra de Dios y la pone en pr\u00e1ctica. Cuando le habla el \u00e1ngel Gabriel, responde con toda su alma: \u00abH\u00e1gase en m\u00ed seg\u00fan tu palabra\u00bb (Lc 1,38).<\/p>\n<p style=\"text-align: justify\">Jos\u00e9 reacciona de manera parecida. Le hablan cuatro mensajeros ang\u00e9licos. En cuanto se entera de lo que quieren, se levanta de inmediato y lleva a cabo las \u00f3rdenes de Dios (Mt 2, 14,21).<\/p>\n<p style=\"text-align: justify\">Ser\u00e1n felices los que obran de manera seme\u00adjante. Los evangelios nos aseguran que la verdadera felicidad no consiste en estar cerca de Jes\u00fas f\u00edsica\u00admente, ni tampoco en las relaciones de parentesco con \u00e9l, sino en escuchar la palabra de Dios y poner\u00adla en pr\u00e1ctica.<\/p>\n<p style=\"text-align: justify\"><i>Mientras estaba hablando, una mujer de entre la multitud gritando le dijo: \u00abDichoso el vientre que te llev\u00f3 y los pechos que te amamantaron.\u00bb Pero Jes\u00fas replic\u00f3: \u00abDichosos m\u00e1s bien los que oyen la palabra de Dios y la ponen en pr\u00e1ctica.\u00bb <\/i>(Lc 11,27-28).<\/p>\n<p style=\"text-align: justify\">El escuchar y la humildad van muy unidas. Los que reconocen con humildad agradecida que la vida, la verdad, la sabidur\u00eda y el amor son regalos de Dios han conseguido ya que el escuchar sea su actitud fundamental.<\/p>\n<p style=\"text-align: justify\">San Vicente llama a la humildad fundamento de la espiritualidad evang\u00e9lica. Los humildes ven todo como un regalo. Creen que Dios est\u00e1 siempre inten\u00adtando entrar en sus vidas para hablar con ellos. Por eso est\u00e1n siempre en actitud de alerta, atentos y deseosos de o\u00edr la Palabra de Dios. Los humildes saben y la verdad que les hace libres viene de fuera: a trav\u00e9s de la Escritura, de la Iglesia, de los\u00a0 miembros de su familia, del clamor de los pobres.<\/p>\n<p style=\"text-align: justify\">Escucha, pues, a tu familia. Escucha a los que trabajan contigo. Escucha la Palabra de Dios cada<em> d<\/em>\u00eda, escogiendo un peque\u00f1o pasaje de la Escritura como alimento de tu oraci\u00f3n.<\/p>\n<p style=\"text-align: justify\">El escuchar es especialmente importante cuando se tiene autoridad, como los padres, los maestros, los doctores, las enfermeras, los patronos. Si tienes autoridad, aseg\u00farate de que pides consejo con fre\u00adcuencia. Acepta el consejo. En el seguimiento de Cristo no hay lugar para la arrogancia.<\/p>\n<p style=\"text-align: justify\">Las primeras palabras de la Regla de San Benito son fundamentales para los que quieren aprender del Se\u00f1or: \u00abEscucha con cuidado las instrucciones del maestro, y rec\u00edbelas con atenci\u00f3n a trav\u00e9s de los o\u00eddos de tu coraz\u00f3n.\u00bb<\/p>\n<p style=\"text-align: justify\">Como ayuda para escuchar:<\/p>\n<ul>\n<li style=\"text-align: justify\">Cuando oras, rel\u00e1jate y respira profundamente. Comienza de manera sencilla y tranquila. Deja que se calmen los sonidos, los pensamientos, y toda ansiedad. Estate tranquilo. Intenta o\u00edr la palabra de Dios.<\/li>\n<li style=\"text-align: justify\">Toma cada d\u00eda unos minutos para sentarte y escuchar a tu esposo o esposa, hijo, amigo, compa\u00f1ero de trabajo o a un pobre. Escucha con atenci\u00f3n mientras te cuentan algo que les ha sucedido ese d\u00eda, o bien alg\u00fan problema, algo que les preocupa, o alguna alegr\u00eda. Escucha sin interrumpir con comentarios, consejos o juicios. C\u00e9ntrate totalmente en su persona.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cada ma\u00f1ana me despierta para que oiga, para que escuche como disc\u00edpulo. El Se\u00f1or Yahv\u00e9 me ha abierto el o\u00eddo. Is 50,4-5 Ante todo cada uno de nosotros se esforzar\u00e1 por convencerse de esta verdad: &#8230; <a href=\"https:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":121250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[139],"class_list":["post-121247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","tag-san-benito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escuchar la Palabra de Dios - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuchar la Palabra de Dios - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Cada ma\u00f1ana me despierta para que oiga, para que escuche como disc\u00edpulo. El Se\u00f1or Yahv\u00e9 me ha abierto el o\u00eddo. Is 50,4-5 Ante todo cada uno de nosotros se esforzar\u00e1 por convencerse de esta verdad: ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-04T05:14:10+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Escuchar la Palabra de Dios\",\"datePublished\":\"2013-05-04T05:14:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/\"},\"wordCount\":1149,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"San Benito\"],\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/\",\"name\":\"Escuchar la Palabra de Dios - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2013-05-04T05:14:10+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/escuchar-la-palabra-de-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuchar la Palabra de Dios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuchar la Palabra de Dios - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/","og_locale":"es_ES","og_type":"article","og_title":"Escuchar la Palabra de Dios - Somos Vicencianos","og_description":"Cada ma\u00f1ana me despierta para que oiga, para que escuche como disc\u00edpulo. El Se\u00f1or Yahv\u00e9 me ha abierto el o\u00eddo. Is 50,4-5 Ante todo cada uno de nosotros se esforzar\u00e1 por convencerse de esta verdad: ... Read More","og_url":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2013-05-04T05:14:10+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Escuchar la Palabra de Dios","datePublished":"2013-05-04T05:14:10+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/"},"wordCount":1149,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#primaryimage"},"thumbnailUrl":"","keywords":["San Benito"],"articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/","url":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/","name":"Escuchar la Palabra de Dios - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#primaryimage"},"thumbnailUrl":"","datePublished":"2013-05-04T05:14:10+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/escuchar-la-palabra-de-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Escuchar la Palabra de Dios"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-vxB","jetpack-related-posts":[{"id":130869,"url":"https:\/\/vincentians.com\/es\/el-camino-de-san-vicente-el-lugar-del-evangelio\/","url_meta":{"origin":121247,"position":0},"title":"El camino de San Vicente: El lugar del Evangelio","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/02\/2015","format":false,"excerpt":"Escucha con cuidado, hermano m\u00edo, qu\u00e9 impresionante fe ten\u00eda san Vicente en el poder del evangelio: \"Ante todo, cada uno de nosotros se esforzar\u00e1 por convencerse de esta verdad: que la ense\u00f1anza de Cristo no puede enga\u00f1ar nunca, mientras que la del mundo es siempre falaz. El mismo Cristo afirma\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"evangelio","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/evangelio-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387094,"url":"https:\/\/vincentians.com\/es\/discipulos-de-cristo\/","url_meta":{"origin":121247,"position":1},"title":"Disc\u00edpulos de Cristo","author":"Mitxel Olabu\u00e9naga","date":"20\/02\/2016","format":false,"excerpt":"\u00abNadie puede acercarse a mi si el Padre no se lo conce\u00adde. Desde entonces muchos disc\u00edpulos se echaron atr\u00e1s v no volvieron m\u00e1s con \u00e9l. Jes\u00fas pregunt\u00f3 a los Doce: \u00bfTambi\u00e9n vosotros quer\u00e9is marcharos? Sim\u00f3n Pedro le contesto: Se\u00f1or, y \u00bfa qui\u00e9n vamos a recurrir? En tus palabras hay vida\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/02\/asd-300x193.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130881,"url":"https:\/\/vincentians.com\/es\/el-camino-de-san-vicente-actos-de-piedad\/","url_meta":{"origin":121247,"position":2},"title":"El camino de San Vicente: Actos de piedad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/02\/2015","format":false,"excerpt":"Escucha, hermano, lo que dice san Vicente acerca de la vida de piedad: Cristo el Se\u00f1or y sus disc\u00edpulos ten\u00edan sus ejercicios de piedad, como por ejemplo subir al templo, retirarse de vez en cuando a la soledad, dedicarse a la oraci\u00f3n, y cosas semejantes. Por ello parece muy justo\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"oracion-en-capilla","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/oracion-en-capilla-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":125704,"url":"https:\/\/vincentians.com\/es\/la-escucha-como-fundamento-para-la-espiritualidad\/","url_meta":{"origin":121247,"position":3},"title":"La escucha como fundamento para la espiritualidad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"30\/11\/2013","format":false,"excerpt":"Has notado alguna vez, qu\u00e9 poco \u00e9nfasis \"expl\u00edcito\" se da a la escucha en las \"Reglas\" de las Comunidades, en los \"manuales\" ordi\u00adnarios de la vida espiritual, e incluso en los cl\u00e1sicos? Es in\u00fatil buscar un cap\u00edtulo sobre la escucha en los escritos de S. Benito o S. Ignacio, e\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"libro y gerbera","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/11\/libro-y-gerbera.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":136560,"url":"https:\/\/vincentians.com\/es\/evangelizados-por-los-pobres\/","url_meta":{"origin":121247,"position":4},"title":"Evangelizados por los pobres","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/01\/2015","format":false,"excerpt":"\u00abEscuchad, queridos hermanos \u00bfno fue Dios quien escogi\u00f3 a los que son pobres a los ojos del mundo para que fueran eran ricos de fe y herederos del Reino que \u00e9l prometi\u00f3 a los que lo aman? Vos\u00adotros, en cambio, hab\u00e9is afrentado al pobre\u00bb. Sant 2,5-6). \u00abEn la obra de\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"vicente_pobre","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/vicente_pobre-241x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":121245,"url":"https:\/\/vincentians.com\/es\/centrar-la-vida-entera-en-cristo\/","url_meta":{"origin":121247,"position":5},"title":"Centrar la vida entera en Cristo","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/01\/2016","format":false,"excerpt":"Cristo habite en vuestros corazones por la\u00a0fe, de manera que, enraizados en su amor, pod\u00e1is llegar a comprender con todos los santos cu\u00e1l es la anchura, la longitud, la altura y la profundidad, y conociendo el amor de Cristo que sobrepasa todo conocimiento, se\u00e1is colmados con la plenitud de Dios.\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"cristo","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2013\/04\/cristo.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2013\/04\/cristo.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2013\/04\/cristo.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2013\/04\/cristo.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2013\/04\/cristo.jpg?resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/121247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=121247"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/121247\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=121247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=121247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=121247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}