{"id":120615,"date":"2015-03-24T03:26:46","date_gmt":"2015-03-24T02:26:46","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=120615"},"modified":"2015-03-24T03:26:46","modified_gmt":"2015-03-24T02:26:46","slug":"una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias","status":"publish","type":"post","link":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/","title":{"rendered":"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas"},"content":{"rendered":"<h2>I. La plegaria por la consumaci\u00f3n<\/h2>\n<h3>1. La palabra Maran\u00e1 Tha<\/h3>\n<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/05\/sigo_a_jesus.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-120780\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/05\/sigo_a_jesus-300x242.jpg?resize=300%2C242\" alt=\"sigo_a_jesus\" width=\"300\" height=\"242\" \/><\/a>El comienzo de nuestra reflexi\u00f3n toma como punto de partida el grito lit\u00fargico, proveniente de la primera hora y recogido por el Ap\u00f3stol Pablo, en su literalidad: <i>Marana tha <\/i>(1Cor 16,22). Este texto aparece en Pablo en el contexto del final de la primera Carta a los Corintios. \u00abSi alguno no ama al Se\u00f1or \u00a1sea maldito!, Marana tha\u00bb. Y contin\u00faa, concluyendo la carta, con el saludo: \u00abLa gracia del Se\u00f1or Jes\u00fas sea con vosotros. Os amo a todos en Cristo Jes\u00fas\u00bb (1Cor 16,23-24).<\/p>\n<p>Esta expresi\u00f3n aramea aparece tambi\u00e9n en Didaj\u00e9 10,6, en la oraci\u00f3n eucar\u00edstica: <i>Venga la Gracia <\/i>y <i>pase este mundo. \u00a1Hosan\u00adna al Dios de David! El que sea santo que se acerque! \u00a1El que no lo sea que haga penitencia! Marana tha. Am\u00e9n.<\/i><\/p>\n<p><i>Marana tha <\/i>es una palabra aramea, la lengua materna de Jes\u00fas y que los primeros disc\u00edpulos han recogido como palabra muy cualificada. Su significado es motivo de interpretaci\u00f3n entre los ex\u00e9getas. <i>Maran <\/i>o <i>marana, <\/i>Se\u00f1or nuestro, ha de ir unido al verbo <i>ata, <\/i>y entonces significa nuestro Se\u00f1or ha venido, est\u00e1 aqu\u00ed entre nosotros. O bien en un sentido imperativo, <i>marana tha, \u00a1ven, <\/i>Se\u00f1or nuestro!. Viendo este doble significado tambi\u00e9n es un texto muy parecido el de \u00abel Se\u00f1or est\u00e1 cerca\u00bb (Flp 4,5).<\/p>\n<p>Quien parece unir las dos interpretaciones, aunque de un modo ya imperativo, es el libro del Apocalipsis: \u00abVen, Se\u00f1or Jes\u00fas\u00bb (Ap 22,20). Estas palabras pueden ser una traducci\u00f3n de los dos significados de la invocaci\u00f3n primitiva. Si a esto a\u00f1a\u00addimos la palabra, tambi\u00e9n aramea, de \u00abAbba\u00bb (Mc 14,36; Rom 8,15; Gal 4,6), nos parece comprensible unir en la expresi\u00f3n <i>Marana tha <\/i>este triple significado: 1-invocaci\u00f3n, 2-presencia y 3-llamada al futuro. Es decir: <i>\u00a1Se\u00f1or.. ya est\u00e1s aqu\u00ed&#8230; ven pronto, no tardes!<\/i><\/p>\n<h3>2. En la Eucarist\u00eda, memorial de la cena del Se\u00f1or<\/h3>\n<p>Al comienzo tild\u00e1bamos esta palabra de \u00ablit\u00fargica\u00bb. Pues bien, todo parece indicar que es en el contexto eucar\u00edstico donde ha nacido esta expresi\u00f3n. En el libro de la Didaj\u00e9 aparece como un fragmento de las incipientes Plegarias eucar\u00edsticas. En 1Cor 11,26 vemos que la Cena del Se\u00f1or se celebraba esperando su pronta venida. La Eucarist\u00eda, acontecimiento y Memorial de la presencia Pascual de la muerte y resurrecci\u00f3n del Se\u00f1or, es tambi\u00e9n \u00ablugar\u00bb de esperanza de la manifestaci\u00f3n gloriosa del mismo Se\u00f1or al final de los d\u00edas. A las palabras del Memorial, \u00abtradici\u00f3n recibida del mismo Se\u00f1or\u00bb, Pablo a\u00f1ade \u00abcada vez que com\u00e9is de este pan y beb\u00e9is de esta copa, anunci\u00e1is la muerte del Se\u00f1or, hasta que vuelva\u00bb (1Cor 11,26). La Euca\u00adrist\u00eda es, pues, proclamaci\u00f3n de la muerte de Jes\u00fas como cumplimiento de presencia salvadora, y esperanza ardiente de consumaci\u00f3n, que se traduce en la s\u00faplica o \u00abgrito\u00bb del <i>Marana tha.<\/i><\/p>\n<p>San Lucas, en su evangelio, coloca al comienzo de la Cena Pascual estas palabras: \u00abHe deseado ardientemente comer esta Pascua con vosotros, antes de padecer. Os aseguro que no la vol\u00adver\u00e9 a comer hasta que se cumpla en el Reino de Dios. Y toman\u00addo una copa, dio gracias y dijo: tomad esto y repartidlo entre vosotros; porque yo os digo que, a partir de este momento, no beber\u00e9 del producto de la vid hasta que llegue el Reino de Dios\u00bb (Lc 22,15-18). Tambi\u00e9n las tradiciones de Mateo y Marcos reco\u00adgen este \u00abdicho escatol\u00f3gico\u00bb de Jes\u00fas (Mt 26,29; Mc 14,25). En la \u00faltima Cena se se\u00f1ala esta dimensi\u00f3n escatol\u00f3gica de la entrega de Jes\u00fas en la Pascua como realizaci\u00f3n del Reino de Dios, abierta a la consumaci\u00f3n final.<\/p>\n<p>En el Cuerpo y Sangre del Se\u00f1or est\u00e1 todo el Don del Padre al mundo (Jn 3,16). La entrega de Jes\u00fas en la Cruz, <i>voluntaria\u00admente aceptada <\/i>(PE II), se anticipa en la Mesa de la \u00faltima cena, como <i>entrega ofrecida <\/i>(Mt 26, 26-28; Mc 14, 22-24; Lc 22, 19\u00ad20; 1Col, 23-25); alcanza su fin en el \u00abTodo est\u00e1 consumado. E inclinando la cabeza entreg\u00f3 el esp\u00edritu\u00bb (Jn 19,30), como <i>entre\u00adga culminada; <\/i>y se convierte en <i>entrega victoriosa <\/i>en la Pascua, cuando reencontrando a los disc\u00edpulos <i>les parte el Pan, abri\u00e9n\u00addoles los ojos <\/i>(Lc 24, 13-35; Jn 21,9-14). Pero esta entrega ser\u00e1 <i>entrega consumada y \u00faltima <\/i>cuando \u00c9l vuelva de nuevo, \u00abcuan\u00addo entregue a Dios Padre el Reino, despu\u00e9s de haber destruido todo Principado, Dominaci\u00f3n y Potestad\u00bb (1Co 15, 24).<\/p>\n<p>Quien nos revela muy bien esta perspectiva escatol\u00f3gica es la Liturgia eucar\u00edstica del Concilio Vaticano II. A las palabras del Memorial eucar\u00edstico sobre el Pan y el vino, que mediante <i>la efusi\u00f3n del Esp\u00edritu, <\/i>se convierten en el Cuerpo y la Sangre del Se\u00f1or, el pueblo en la celebraci\u00f3n aclama: <i>Anunciamos tu muerte, proclamamos tu Resurrecci\u00f3n, ven, Se\u00f1or Jes\u00fas. <\/i>O aquella otra aclamaci\u00f3n menos conocida y usada: <i>Cada vez que comemos de este pan y bebemos de este c\u00e1liz, anunciamos tu muerte, Se\u00f1or, hasta que vuelvas. <\/i>Despu\u00e9s el sacerdote contin\u00faa orando: <i>As\u00ed, pues, Padre, al celebrar ahora el memorial de la pasi\u00f3n salvadora de tu Hijo, de su admirable resurrecci\u00f3n y ascensi\u00f3n al cielo, mientras esperamos su venida gloriosa, te ofrecemos, en esta acci\u00f3n de gracias, el sacrificio vivo y santo <\/i>(PE III).<\/p>\n<h3>3. \u00abMientras esperamos su venida gloriosa\u00bb<\/h3>\n<p>Este <i>mientras esperamos su venida gloriosa <\/i>es nuestro tiempo. El tiempo de la Iglesia. Tiempo que va desde el \u00abya\u00bb est\u00e1 aqu\u00ed el Se\u00f1or, ya ha realizado su obra y es el Se\u00f1or (Kyrios) sentado a la derecha del Padre \u00abpor encima de todo Principado, Potestad, Virtud, Dominaci\u00f3n\u00bb (Ef 1,21), hasta la espera de su vuelta. Y entonces s\u00ed que entendemos que el <i>Marana tha <\/i>sea un \u00abgrito\u00bb: \u00a1Ven, Se\u00f1or, no tardes! Escuchemos una Liturgia primi\u00adtiva que nos lo revela con claridad: \u00abDice el que da testimonio de todo esto: s\u00ed, vengo pronto. Am\u00e9n. \u00a1Ven, Se\u00f1or Jes\u00fas! Que la Gracia del Se\u00f1or sea con todos. Am\u00e9n. (Ap 22, 20-21). Tambi\u00e9n recoge admirablemente este \u00abtiempo de espera\u00bb la Plegaria euca\u00adr\u00edstica de la Reconciliaci\u00f3n: <i>As\u00ed como nos has reunido aqu\u00ed en torno a la mesa de tu Hijo&#8230; re\u00fane tambi\u00e9n a los hombres de cualquier clase y condici\u00f3n, de toda raza y lengua, en el banque\u00adte de la unidad eterna, en un mundo donde brille la plenitud de tu paz <\/i>(PE. Rec. II).<\/p>\n<p>El <i>Marana tha <\/i>es un grito para que se consume el amor pas\u00adcual. Y cuanto m\u00e1s se siente el \u00abya\u00bb de la salvaci\u00f3n m\u00e1s se desea su consumaci\u00f3n. Ahora vamos a comprender por qu\u00e9 queremos situar en este contexto el encargo que se nos ha hecho: <i>Una vida espiritual sin rebajas. C\u00f3mo huir de las median\u00edas. <\/i>La Iglesia del Se\u00f1or, por tanto, que vive del pasado que se hace memorial presente (\u00abanunciamos tu muerte, proclamamos tu resurrec\u00adci\u00f3n\u00bb), pende su vida radicalmente del futuro de la consumaci\u00f3n (\u00abVen, Se\u00f1or Jes\u00fas\u00bb).<\/p>\n<p>\u00bfQu\u00e9 nos puede pasar en esta espera? \u00bfQu\u00e9 puede pasarle a la Iglesia, y sus miembros, \u00abmientras esperamos la gloriosa venida de nuestro Salvador Jesucristo\u00bb? \u00a1Pues que caigamos en dejaci\u00f3n; que rebajemos las exigencias de la espera! Es en esta perspectiva donde queremos situar nuestra aportaci\u00f3n. El segui\u00admiento radical (radical viene de ra\u00edz) de Jes\u00fas no proviene de una imitaci\u00f3n voluntarista, solamente, ni de nuestros c\u00e1lculos racionales, ni de nuestros sentimientos bondadosos. Viene de un \u00abAmor dado\u00bb que hemos recibido ya, y de un \u00abAmor consumado\u00bb que aguardamos.<\/p>\n<p>La Fuente de (podemos llamarla as\u00ed) esta \u00ab\u00e9tica escatol\u00f3gica\u00bb es la Eucarist\u00eda, donde el \u00abEsp\u00edritu que ha sido derramado en nuestro corazones\u00bb (Gal 4,6; Rom 8,15) en la comuni\u00f3n del Cuerpo y Sangre del Se\u00f1or nos hace exclamar \u00abAbba\u00bb&#8230; \u00abH\u00e1ga\u00adse tu voluntad\u00bb&#8230; \u00abvenga tu Reino\u00bb&#8230; \u00abno nos dejes caer en la tentaci\u00f3n\u00bb&#8230; Que no caigamos en las median\u00edas, en las rebajas de su amor, en la rutina ap\u00e1tica de la misi\u00f3n de cada d\u00eda&#8230; \u00abmientras aguardamos su \u00faltima venida\u00bb (Pref. III de Adviento).<\/p>\n<h2>II. No nos dejes caer en la tentaci\u00f3n de las rebajas y las median\u00edas<\/h2>\n<p>En esta espera del Se\u00f1or la vida del disc\u00edpulo est\u00e1 presidida y alentada por una palabra muy querida en el Nuevo Testamento: vigilancia. \u00abEstad atentos y vigilad\u00bb (Mc 13,33). La tentaci\u00f3n del enfriamiento de la fe es algo que nos puede suceder en cualquier momento. Es tambi\u00e9n estar muy atentos a \u00ablos signos de los tiempos\u00bb, expresi\u00f3n tan querida por el Papa Juan XXIII y reco\u00adgida en el Concilio Vaticano II.<\/p>\n<p>Vamos a fijarnos para ello en tres experiencias del Nuevo Testamento.<\/p>\n<h3>1. La espera ardiente y activa<\/h3>\n<p>En el evangelio de san Mateo encontramos palabras muy sig\u00adnificativas que nos ayudan a comprender y vivir esta vigilancia: en <i>la espera ardiente y activa. <\/i>\u00abDe la higuera aprended esta par\u00e1\u00adbola cuando ya sus ramas est\u00e1n tiernas y brotan las hojas sab\u00e9is que el verano est\u00e1 cerca, a las puertas. As\u00ed tambi\u00e9n vosotros cuando ve\u00e1is todo esto sabed que \u00c9l esta cerca, a las puertas\u00bb (Mt 24,32ss). Los disc\u00edpulos deben vivir vigilantes en medio del mundo y prestar atenci\u00f3n a los signos que en \u00e9l ocurren: son se\u00f1ales del paso del Se\u00f1or por la historia humana. Pero esta pasi\u00f3n por lo que pasa en el mundo no es para caer en sus redes, ni encontrar en \u00e9l su seguridad. Porque vivimos, a veces, tan seguros en nosotros mismos, y tan acomodados en la inmediatez de la vida que no nos damos cuenta de la presencia cercana y \u00abviniente\u00bb de Jes\u00fas. \u00abComo en los d\u00edas de No\u00e9, as\u00ed ser\u00e1 la veni\u00adda del Hijo del Hombre. Porque como en los d\u00edas que precedie\u00adron a la venida del diluvio, com\u00edan y beb\u00edan, tomaban marido o mujer, hasta el d\u00eda que entr\u00f3 Noe en el arca y no se dieron cuen\u00adta y los arras\u00f3 a todos&#8230; velad, pues, no sab\u00e9is el d\u00eda que vendr\u00e1 vuestro Se\u00f1or\u00bb (Mt 24, 37-41).<\/p>\n<p>Las rebajas o las median\u00edas pueden llevarnos a caer en la infi\u00addelidad, la diversi\u00f3n, la violencia,&#8230; Es como aquel siervo pere\u00adzoso que porque su \u00abamo tarda, y se pone a pegarle y golpear a sus compa\u00f1eros, y come y bebe con los borrachos&#8230; vendr\u00e1 el Se\u00f1or de aquel siervo el d\u00eda que no espera, le separar\u00e1 y le se\u00f1a\u00adlar\u00e1 s suerte&#8230;\u00bb (Mt 24, 45-51). Y si hay una par\u00e1bola que sim\u00adboliza la vigilancia y actividad que hemos de tener en la fideli\u00addad y la caridad ardiente es la de las v\u00edrgenes sensatas y necias. \u00abA media noche se oy\u00f3 una voz: \u00a1Que llega el Esposo! \u00a1Salid a su encuentro!\u00bb (Mt 25, 6). El Esposo lleg\u00f3 y se cerr\u00f3 la puerta. Y vinieron las que hab\u00edan ido a comprar aceite diciendo: \u00ab\u00a1Se\u00f1or, \u00e1brenos! Pero \u00e9l respondi\u00f3: En verdad os digo que no os conozco. Velad, pues, porque no sab\u00e9is ni el d\u00eda ni la hora\u00bb (Mt 25, 12-13).<\/p>\n<p>Sin embargo, estas \u00abpar\u00e1bolas de crisis\u00bb no son para quedar\u00adnos simplemente tensionados por llevar una vida espiritual sin tacha e intimista; sino que la vigilancia debe ser principalmente para estar prestos en la caridad y el servicio a los pobres, a los peque\u00f1os: \u00abCuando el Hijo del Hombre venga&#8230; se sentar\u00e1 en su trono de gloria. Ser\u00e1n congregadas delante d\u00e9 todas las naciones&#8230; Entonces el Rey dir\u00e1 a los de su derecha: Venid benditos de mi Padre, recibid la herencia del Reino preparado para vos\u00adotros desde la creaci\u00f3n del mundo. Porque tuve hambre y me dis\u00adteis de comer; tuve sed y me disteis de beber&#8230;\u00bb (Mt 25, 31-46).<\/p>\n<p>Todas son palabras de Jes\u00fas que nos remiten al \u00abestar atentos y vigilad\u00bb, que se repiten sin cesar. Nos llevan a estar atentos al porvenir, a comprender la hora presente, a no pretender calcular las \u00e9pocas. Vivir la espera de forma aut\u00e9ntica es saberse llamado a cumplir desde ahora con todas las fuerzas la voluntad del Padre.<\/p>\n<p>Y qu\u00e9 bien entendemos, a la luz de estas palabras, las ense\u00ad\u00f1anzas del Serm\u00f3n de la Monta\u00f1a, tambi\u00e9n en san Mateo. En esta espera del Se\u00f1or \u00abno amonton\u00e9is tesoros en la tierra, donde hay polilla que los corroen, y ladrones que roban. Amontonaos m\u00e1s bien tesoros en el cielo&#8230;\u00bb (Mt 6,19-21) \u00abNo and\u00e9is preocu\u00adpados por vuestra vida, qu\u00e9 comer\u00e9is, qu\u00e9 vestir\u00e9is, ni por vues\u00adtro cuerpo, con qu\u00e9 os vestir\u00e9is&#8230; Buscad primero el Reino de Dios y su Justicia, y todas esa cosas se os dar\u00e1n por a\u00f1adidura\u00bb (Mt 6,25-34). Estas llamadas profundas al seguimiento tambi\u00e9n en el Serm\u00f3n del Monte tienen un fuerte componente escatol\u00f3gi\u00adco. \u00abNo todo el que diga: Se\u00f1or, Se\u00f1or entrar\u00e1 en el Reino de los Cielos&#8230; muchos dir\u00e1n aquel d\u00eda \u00bfno profetizamos en tu nom\u00adbre&#8230; no hicimos milagros?&#8230; Y entonces les dir\u00e9: Jam\u00e1s os conoc\u00ed&#8230;\u00bb (Mt 7,21-23).<\/p>\n<h3>2. Alentados por la victoria de Jes\u00fas<\/h3>\n<p>El presente ya est\u00e1 <i>iluminado por la Victoria de Cristo en la Resurrecci\u00f3n. <\/i>El grito del <i>Marana tha, <\/i>es decir, su vuelta, ilumi\u00adna al hombre y al mundo. Esto nos lo dibuja muy bien el Evan\u00adgelio de san Marcos en el discurso apocal\u00edptico del Cap. 13. \u00abY entonces ver\u00e1n al Hijo del Hombre que viene entre nubes con poder y gloria; entonces enviar\u00e1 a los \u00e1ngeles y reunir\u00e1 de los cuatro vientos a sus elegidos, desde el extremo de la tierra hasta el extremo del cielo\u00bb (Mc 13,26-27). No es la historia del mundo, ni \u00abel tiempo\u00bb de los hombres los que iluminan a Cristo; es la venida del Se\u00f1or la que est\u00e1 iluminando el presente hist\u00f3ri\u00adco, de los hombres y del universo, porque ya poseen en sus entra\u00ad\u00f1as las primicias de la Redenci\u00f3n.<\/p>\n<p>El final del Evangelio de Marcos es muy significativo para entender la tensi\u00f3n escatol\u00f3gica en la que la Iglesia debe vivir: est\u00e1 el episodio de la viuda que en el cepillo del templo \u00abech\u00f3 todo lo que ten\u00eda para vivir\u00bb (Mc 12,44); a continuaci\u00f3n, inter\u00adcalado, viene el Cap\u00edtulo 13 se\u00f1alado; para continuar inme\u00addiatamente despu\u00e9s con el relato de la Pasi\u00f3n y Resurrecci\u00f3n (Mc 14-16).<\/p>\n<p>La viuda es el ejemplo vivo del disc\u00edpulo que incondicional\u00admente cumple la voluntad del Padre, frente a los disc\u00edpulos que no han comprendido nada de los anuncios de la Pasi\u00f3n (Mc 8,31\u00ad33; 9,30-32; 10,32-34). Los disc\u00edpulos de Jes\u00fas no entienden lo de \u00abnegarse a s\u00ed mismo&#8230; perder la vida&#8230; tomar la Cruz\u00bb (Mc 8,34ss); en el camino discuten quien \u00abes el mayor entre ellos\u00bb (Mc 9, 33-37); piden recompensan por lo que han dejado y quie\u00adren un puesto importante en el Reino de Dios (Mc 10, 28-31. 35- 45); no quieren perderse, darse hasta la muerte; quieren seguir a Jes\u00fas, pero con la \u00abrebaja\u00bb de no pasar por la Cruz y la entrega; por eso tienen que escuchar algo directamente dirigido a ellos: \u00abEl Hijo del Hombre no ha venido a ser servido, sino a servir y dar su vida en rescate por muchos\u00bb (Mc 10,45).<\/p>\n<p>No s\u00f3lo los disc\u00edpulos se cierran al camino de la Cruz, sino que el mismo pueblo de Israel va a rechazar a Jes\u00fas. La par\u00e1bo\u00adla de los Vi\u00f1adores homicidas lo expresa muy bien: \u00ab\u00c9ste es el heredero. Vamos, mat\u00e9mosle y ser\u00e1 nuestra la herencia. Le aga\u00adrraron, le mataron y lo arrojaron fuera de la vi\u00f1a\u00bb (Mc 12,7-8).<\/p>\n<p>As\u00ed el Cap. 13, que vamos a analizar, se encuentra entre la incomprensi\u00f3n de los disc\u00edpulos (8-10), el rechazo del Pueblo de Israel (11-12), y el relato de la Pasi\u00f3n. Este texto de Mc 13 es un \u00abcanto firme\u00bb de la Victoria que brota de la Pascua y que debe alentar el camino de los seguidores de Jes\u00fas por el mundo. Una llamada fuerte a la perseverancia, a la firmeza del seguimiento, sostenidos en la victoria del Crucificado.<\/p>\n<p>Hay que hacer frente a la mediocridad que se averg\u00fcenza de las palabras y del camino de Jes\u00fas, dando testimonio suyo \u00abante gobernadores y reyes\u00bb (Mc 13,9). En este camino testimonial y martirial de los disc\u00edpulos, que ha de ser igual que el del Maes\u00adtro, hay que estar muy alerta para no caer en la tentaci\u00f3n de irse tras \u00abfalsos cristos y profetas\u00bb (Mc 13,22), \u00abque vendr\u00e1n usur\u00adpando mi nombre, diciendo \u00abyo soy\u00bb, y enga\u00f1aran a muchos\u00bb (Mc 13,5-6).<\/p>\n<p>La firmeza del seguimiento llevar\u00e1 a la incomprensi\u00f3n fami\u00adliar y al rechazo de estos: \u00abSer\u00e9is odiados de todos por causa de mi nombre\u00bb (Mc 13,13). El disc\u00edpulo debe estar preparado para no hacer rebajas del Evangelio por culpa del miedo. El testimo\u00adnio que dan los disc\u00edpulos ante el mundo sucede en el Esp\u00edritu Santo \u00abno ser\u00e9is vosotros los que habl\u00e9is, sino el Esp\u00edritu Santo\u00bb (Mc 13,11).<\/p>\n<p>Hoy la gran tentaci\u00f3n es vivir un cristianismo c\u00f3modo, que no moleste; hacerlo \u00abviable y no estridente\u00bb, \u00abcomprensible\u00bb para el hombre de hoy. En el conflicto entre el se\u00f1or\u00edo de este mundo y el se\u00f1or\u00edo de Cristo que est\u00e1 irrumpiendo es muy f\u00e1cil el abandonar, o pasarnos a los \u00eddolos. Por eso, tambi\u00e9n en este cap\u00edtulo las palabras de Jes\u00fas son una llamada a estar despiertos, vigilantes: \u00abel que persevere se salvar\u00e1&#8230; estad sobre aviso&#8230; estad atentos y vigilad&#8230; Lo que a vosotros os digo, a todos lo digo: Velad\u00bb (Mc 13,13.23.29). Y una llamada constante a la esperanza en la vuelta del Se\u00f1or: \u00abSabed que \u00c9l est\u00e1 cerca, a las puertas\u00bb (Mc 13,29).<\/p>\n<p>Todos tenemos deseos de la plenitud del Reino de Dios, pero tenemos miedo a los padecimientos, a la persecuci\u00f3n. Por eso el texto central de este relato es el v. 32. No hay que temer. La vigi\u00adlancia debe ir unida a la confianza. Porque todo esto es un misterio de amor que est\u00e1 escondido en el coraz\u00f3n del Padre. Perma\u00adneced en su amor, \u00abs\u00f3lo el Padre\u00bb. Abandonarnos al Misterio de su amor es el camino.<\/p>\n<h3>3. \u00abSe requiere la resistencia y la fe de los santos\u00bb<\/h3>\n<p>El avance del Evangelio en la primera hora sucede en medio de la persecuci\u00f3n como hemos visto en Marcos. A la persecuci\u00f3n sigue la seducci\u00f3n, que ocurre en la segunda hora, como vere\u00admos en Apocalipsis. Para ello es necesario, \u00abla resistencia y la fe de los santos\u00bb (Ap 13,10).<\/p>\n<p>La comunidad que escribe el Apocalipsis traza con rasgos vigorosos el entramado del mundo de la opresi\u00f3n e idolatr\u00eda, por donde hace camino la Iglesia peregrina del Se\u00f1or. Son los cap\u00ed\u00adtulos 12 y 13 de este Libro.<\/p>\n<p>\u00abApareci\u00f3 una se\u00f1al en el cielo: un gran drag\u00f3n rojo, con siete cabezas y diez cuernos, y sobre sus cabezas siete diademas\u00bb (Ap 12,3). Es \u00abla serpiente antigua, el llamado diablo y Satan\u00e1s, el seductor del mundo\u00bb (12,9; 20,2), que ahora est\u00e1 con sus \u00e1nge\u00adles actuando en la tierra. Este pr\u00edncipe del mundo entrega \u00absu poder y su trono y gran poder\u00edo\u00bb (13,3) a una enorme \u00abBestia\u00bb del mar, que es el imperio romano con todas sus fuerzas alzadas contra las comunidades peregrinas del Se\u00f1or (13,1-10). El Impe\u00adrio, para su dominio, se sirve de otros agente hist\u00f3ricos, profetas de la bestia, \u00abque seducen a los habitantes de la tierra con las se\u00f1ales\u00bb (13,14; 16,13; 19,20; 20,10). \u00abLa tierra entera sigui\u00f3 maravillada da la Bestia\u00bb (13,13). Y todos se someten al drag\u00f3n, que ha entregado su poder a la bestia y confiesan su grandeza y fuerza. \u00ab\u00bfQui\u00e9n como la Bestia?\u00bb (13,4). De la persecuci\u00f3n se pasa a la seducci\u00f3n. Las comunidades del Apocalipsis tienen las grandes tentaciones de idolatrar el poder y sucumbir a su seduc\u00adci\u00f3n. La resistencia puede llevar a la c\u00e1rcel, el martirio o a la exclusi\u00f3n social. \u00abY vi como la mujer se embriagaba con la san\u00adgre de los santos y con la sangre de los m\u00e1rtires\u00bb (17,6).<\/p>\n<p>Es m\u00e1s f\u00e1cil dejarse llevar por el enga\u00f1o. Y as\u00ed se logra que \u00abtodos, peque\u00f1os y grandes, ricos y pobres, libres y esclavos, se hagan una marca en la mano derecha o en la frente, y nadie pueda comprar nada ni vender nada, sino el que lleve la marca con el nombre de la Bestia o con la cifra de su nombre\u00bb (13,16\u00ad17). La apostas\u00eda por el bienestar, y vivir seg\u00fan las normas del imperio, es la gran tentaci\u00f3n de la rebaja y mediocridad. Los des\u00adtinatarios de la Carta a los Hebreos son de esta \u00e9poca, y nos dice su autor, \u00abmantengamos firme la confesi\u00f3n de la esperanza, pues fiel es el autor de la promesa&#8230; sin abandonar vuestra propia asamblea, como algunos acostumbran a hacerlo, antes bien, ani\u00adm\u00e1ndoos; tanto m\u00e1s, cuanto que veis que se acerca ya el d\u00eda\u00bb (Hb 10,23-25).<\/p>\n<p>Son las \u00abcartas a las Iglesias\u00bb de Apocalipsis las que mejor des\u00adcriben la situaci\u00f3n de estas comunidades. Estas cartas (Ap 2-3) son una exhortaci\u00f3n a la resistencia y a la fe. Primeramente hace poner la mirada de los destinatarios ante Aquel que ha vencido: \u00abEl Testigo fiel y Veraz&#8230; el Primero y el \u00faltimo, el que estuvo muerto y ha vuelto a la vida\u00bb (Ap 2,8; 3,14). Es decir, \u00abJesucris\u00adto, el Primog\u00e9nito de entre los muertos&#8230; Al que nos ama y nos ha lavado con su sangre de nuestros pecados y ha hecho de nos\u00adotros un reino de sacerdotes para su Dios y Padre\u00bb (Ap 1,5-6).<\/p>\n<p>Despu\u00e9s, en cada Carta hay una alabanza a las comunidades por su permanencia en la tribulaci\u00f3n y seducci\u00f3n. \u00abConozco tus fatigas&#8230; no te dejaste seducir&#8230; conozco tu tribulaci\u00f3n y pobre\u00adza&#8230; s\u00e9 de tu fe, caridad, servicio y paciencia&#8230; has guardado mi palabra y no has renegado de mi nombre&#8230;\u00bb (Ap 2,2; 2,13.19; 3, 8).<\/p>\n<p>Seguidamente, en cada carta, hay una fuerte acusaci\u00f3n a su apostas\u00eda e infidelidad. \u00abHas perdido el amor primero\u00bb (Ap 2,4). Te has pasado a otros profetas mas f\u00e1ciles y c\u00f3modos de seguir, dej\u00e1ndote enga\u00f1ar y pas\u00e1ndote a los \u00eddolos falsos (Ap 2,14.20). Es muy vigorosa la acusaci\u00f3n de mediocridad a la Iglesia de Laodicea: \u00abNo eres ni fr\u00edo ni caliente. \u00a1Ojal\u00e1 fueras fr\u00edo o calien\u00adte! Pero, puesto que eres tibio&#8230; voy a vomitarte de mi boca\u00bb (Ap 3,15-16). Y a\u00f1ade a esta misma Iglesia: te crees rica y pode\u00adrosa; y, sin embargo, \u00aberes pobre, digna de compasi\u00f3n, ciega y desnuda\u00bb (Ap 3,17).<\/p>\n<p>Las llamadas a la conversi\u00f3n revelan lo \u00abque el Esp\u00edritu dice a las Iglesias\u00bb (Ap 3, 13). \u00abArrepi\u00e9ntete y vuelve a tu conducta primera&#8230; No temas lo que vas a sufrir&#8230; mantente fiel hasta la muerte&#8230; Acu\u00e9rdate de c\u00f3mo o\u00edste y recibiste mi Palabra, gu\u00e1r\u00addala y arrepi\u00e9ntete&#8230; mant\u00e9n la firmeza que tienes, para que nadie te arrebate tu corona\u00bb (Ap 2,5.10; 3,3.10).<\/p>\n<p>Y al final de cada Carta hay una promesa a cada comunidad de darle parte en la Victoria del Cordero Degollado. Todas estas promesas comienzan: \u00abAl vencedor&#8230;\u00bb. Al vencedor le dar\u00e9: \u00ab&#8230; a comer del \u00e1rbol de la vida&#8230; no sufrir\u00e1 da\u00f1o en la muerte segunda&#8230; una piedrecilla blanca, y grabado en la piedrecilla, un nombre nuevo&#8230; le dar\u00e9 poder sobre las acciones&#8230; le revestir\u00e9 de vestiduras blancas y no borrar\u00e9 su nombre del libro de la Vida&#8230; le pondr\u00e9 de columna en el Santuario de mi Dios\u00bb (Ap 2,7.11.17.26; 3,5.12).<\/p>\n<p>Pero nos fijamos especialmente en la llamada a la conversi\u00f3n y en la promesa dirigida al vencedor de la Iglesia de Laodicea: \u00abS\u00e9 ferviente&#8230; mira que estoy a la puerta y llamo; si alguno oye mi voz y me abre la puerta, entrar\u00e9 en su casa y cenar\u00e9 con \u00e9l y \u00e9l conmigo\u00bb (Ap 3,20-21).<\/p>\n<h2>III. El horizonte de nuestra pastoral<\/h2>\n<h3>1. El misterio trinitario como fundamento. La recapitulaci\u00f3n como horizonte<\/h3>\n<p>En nuestro primer apartado hemos querido poner la mirada en el Misterio Pascual que se desvela y revela en la Eucarist\u00eda, memorial de la Muerte, Resurrecci\u00f3n, Ascensi\u00f3n, y Parus\u00eda del Se\u00f1or. Y en \u00e9l insert\u00e1bamos la s\u00faplica del <i>Marana tha. <\/i>La Cena del Se\u00f1or, Mesa de la Trinidad nos manifiesta, en presencia y actualidad, todo lo que el Padre ha hecho por nosotros, en la entrega de su Hijo, por la fuerza del Esp\u00edritu Santo. Es el Miste\u00adrio de amor, escondido desde siglos y ahora manifestado, revela\u00addo por el Esp\u00edritu (Ef 3,5ss). Este ha sido el prop\u00f3sito de Amor del Padre, que eligi\u00e9ndonos en Cristo, por pura gracia y benevo\u00adlencia, nos ha hecho sus hijos, hermanos en Jes\u00fas y herederos de la Promesa. Todo ello en la Sangre del Hijo derramada en la Cruz. Y, as\u00ed, engendrados por la Palabra y el sello del Esp\u00edritu Santo, recibidos en el Bautismo, esperamos la herencia prometi\u00adda. Este es el fundamento que aparece claramente en el Himno de Efesios 1,3-14. El don del Amor Trinitario es el origen y fun\u00addamento, a la vez que sost\u00e9n y aliento permanente de la Iglesia.<\/p>\n<p>Pero si el Misterio es el fundamento y origen de la Iglesia \u00bfCu\u00e1l es el horizonte y la meta? Nos lo se\u00f1ala el Himno de Colo\u00adsenses 1,15-20, al se\u00f1alarnos que si todo fue creado por el Hijo, todo tiene consistencia en \u00c9l. Jes\u00fas, por su Victoria, es la Cabe\u00adza de muchos hermanos, el Primog\u00e9nito de entre los muertos; y todas las cosas han sido reconciliadas por \u00e9l y para \u00e9l por la sangre de su Cruz. El Primog\u00e9nito es cabeza de los hermanos redimidos por \u00e9l. Y, as\u00ed, siendo Cabeza de la Iglesia, es tambi\u00e9n Se\u00f1or del Universo. El Padre levant\u00e1ndolo del abismo de la muerte le ha sentado a su derecha, por encima de todo Princi\u00adpado y Potestad. \u00abTodo lo puso bajo sus pies, y le dio como Cabeza del Universo a la Iglesia, que es su Cuerpo, la plenitud del que lleva todo a plenitud\u00bb (Ef 1,22-23).<\/p>\n<p>Hasta que esto suceda \u00aben plenitud\u00bb, por su vuelta, \u00abcuando hayan sido sometidas todas las cosas a \u00e9l, entonces tambi\u00e9n el Hijo se someter\u00e1 a Aquel que ha sometido a \u00e9l todas las cosas, para que Dios sea todo en todo\u00bb (1Cor 15,28), la Iglesia peregri\u00adna en el mundo entre las seducciones (aqu\u00ed las hemos llamado median\u00edas y rebajas) y persecuciones de este mundo, anuncian\u00addo y esperando la cruz y la muerte del Se\u00f1or hasta que vuelva (1Cor 11,26).<\/p>\n<p>Este ha sido el marco en el que hemos situado nuestra refle\u00adxi\u00f3n:<\/p>\n<p>El Misterio Trinitario como, Fundamento y Origen de la Igle\u00adsia en una exposici\u00f3n Cristol\u00f3gica y Eucar\u00edstica.<\/p>\n<p>Y en el horizonte, la Recapitulaci\u00f3n. En la Eucarist\u00eda se anti\u00adcipa la Plenitud del Reino de Dios, pero esperamos la Mesa \u00falti\u00adma y definitiva. All\u00ed, la Iglesia y el Universo entero, alcanzar\u00e1n la restauraci\u00f3n de todas las cosas en Cristo. En este \u00abmientras tanto\u00bb, gritamos: <i>Marana tha.<\/i><\/p>\n<p>No perder esta doble perspectiva es esencial. Es la \u00fanica mane\u00adra de superar las mediocridades y la rebajas: vivir del Amor dado y vivir de la espera del Amor consumado. Este \u00abdescentramiento\u00bb, hacia lo alto y hacia lo ancho, es esencial para la Iglesia, hoy. Esto es lo que hemos visto al asomamos a las comunidades de los Evangelios de san Mateo y san Marcos; y en las comunidades del Libro del Apocalipsis. El mayor peligro de median\u00eda y rebaja ven\u00eda por olvidar el amor con que hab\u00edan sido amadas. Y olvidar la esperanza a la que estaban llamadas. Perdiendo as\u00ed la fe.<\/p>\n<p>La Iglesia, inserta entre estos dos polos, es \u00absacramento de Sal\u00advaci\u00f3n para la humanidad\u00bb. Peregrina en el mundo como sal, luz y fermento de nueva humanidad. La Iglesia es Reino de Cristo en Misterio, Pueblo de Dios, cuerpo de Cristo y Templo del Esp\u00edritu que quiere pasar la Redenci\u00f3n a todos los hombres y al Universo.<\/p>\n<p>En los \u00faltimos a\u00f1os nos quejamos de muchas cosas en la Igle\u00adsia. El descenso vocacional, la esterilidad de nuestros planes pas\u00adtorales (nunca hemos hecho tantos como ahora), la aton\u00eda de la vida cristiana&#8230; pod\u00edamos hacer una lista grande. \u00bfNo nos habre\u00admos olvidado de estos dos polos? Puede ser que s\u00ed.<\/p>\n<p>Nos hemos quedado sin Misterio, lo hemos dado \u00abpor supuesto\u00bb. Nos hemos quedado sin la Recapitulaci\u00f3n, la olvida\u00admos. Cuando nos asomamos a las programaciones de Di\u00f3cesis, parroquias, movimientos, institutos religiosos, etc, comproba\u00admos dos opciones y acciones primordiales: Comuni\u00f3n y Misi\u00f3n.<\/p>\n<p>Pero resulta que&#8230;<\/p>\n<h3>2. No hay comuni\u00f3n sin misterio<\/h3>\n<p>Existe un gran peligro en nuestra vida pastoral, y es olvidar de d\u00f3nde nace nuestra comuni\u00f3n. Si miramos la vida de las Di\u00f3\u00adcesis, parroquias, comunidades, movimientos, institutos religio\u00adsos, etc., estamos demasiado preocupados, a lo mejor exagero, por la organizaci\u00f3n y la eficacia. La gran palabra, casi m\u00e1gica, que ha sustituido a la de comuni\u00f3n, es \u00a1 coordinaci\u00f3n! Y enton\u00adces, en esta gran tarea que es vivir la Comuni\u00f3n, nos parece que somos nosotros los que \u00abconstruimos y organizamos\u00bb la Iglesia. En algunas ocasiones parecemos, sin m\u00e1s, \u00abcompa\u00f1eros unos de otros\u00bb. Nosotros programamos, nosotros revisamos&#8230; Es el peli\u00adgro de un \u00abeclesiocentrismo organizativo\u00bb.<\/p>\n<p>El texto de Lc 5,1-11 nos puede ayudar a comprender estas palabras y a encontrar soluciones y caminos nuevos. En este texto de la pesca milagrosa en medio de la noche, Juan y Santia\u00adgo son designados como \u00abkoinonoi\u00bb (compa\u00f1eros); tambi\u00e9n de Pedro. Esto es precioso. \u00a1Y que palabra m\u00e1s bonita! Compa\u00f1eros de un mismo trabajo, una misma barca. Son compa\u00f1eros de una tarea com\u00fan, compartiendo los bienes, la propiedad com\u00fan. Es una forma de trabajo com\u00fan admirable.<\/p>\n<p>Pero el Texto nos se\u00f1ala algo m\u00e1s. Esta comunidad de traba\u00adjo es preludio de una nueva compa\u00f1\u00eda (nueva Koinon\u00eda). \u00bfY c\u00f3mo sucede esto? Ser\u00e1 por la llamada pro-cedente y pre-ceden\u00adte de Jes\u00fas. Esta llamada, don de su Gracia, se produce cuando Jes\u00fas, despu\u00e9s de una noche de fracaso absoluto, les dice: \u00abRemad mar adentro\u00bb. Y Pedro, \u00abpor la Palabra\u00bb de Jes\u00fas, echa de nuevo las redes alcanzando una pesca abundante.<\/p>\n<p>Los disc\u00edpulos ser\u00e1n la \u00abnueva Koinon\u00eda\u00bb por la llamada de Jes\u00fas, por el milagro de su Gracia que proporciona la riqueza del mar, tras una noche sin esperanza. Esta Comuni\u00f3n nace del Se\u00f1or. Y as\u00ed: son \u00abuno\u00bb en \u00c9l; \u00abuno\u00bb entre ellos; \u00abuno\u00bb para la misi\u00f3n.<\/p>\n<p>Nosotros estamos en la barca de la Iglesia. Somos compa\u00f1e\u00adros unos de otros, es verdad. Pero, sobre todo somos los compa\u00f1eros del Se\u00f1or. El es el Fundamento de nuestra Comuni\u00f3n. La acogida del Don precede a la comuni\u00f3n y a la misi\u00f3n. La dimen\u00adsi\u00f3n horizontal resulta de la vertical, y s\u00f3lo desde esta puede entenderse aquella.<\/p>\n<p>Buen comentario es este texto de san Juan: \u00abPermaneced en m\u00ed, como yo en vosotros; lo mismo que el sarmiento no puede dar fruto por s\u00ed mismo; as\u00ed tampoco vosotros si no permanec\u00e9is en rn\u00ed\u00bb (Jn 15,4)<\/p>\n<h3>3. No hay misi\u00f3n sin recapitulaci\u00f3n<\/h3>\n<p>Es reconocido por todos nosotros el gran esfuerzo que en la Iglesia hemos hecho en el servicio a los pobres y la lucha por la justicia. La Pascua del Se\u00f1or que acontece en la Eucarist\u00eda nos lleva a la transformaci\u00f3n escatol\u00f3gica del mundo para el Reino de Dios, que se anticipa ya en la Mesa del Se\u00f1or. Y en esta trans\u00adformaci\u00f3n escatol\u00f3gica del mundo, el servicio a los pobres y la promoci\u00f3n por la Justicia es esencial.<\/p>\n<p>Es verdad que, reconociendo los muchos esfuerzos, hay tam\u00adbi\u00e9n algunas lagunas, como las que brevemente se\u00f1alar\u00e9:<\/p>\n<p>Nos hemos quedado en algunas ocasiones solamente con la evangelizaci\u00f3n como ense\u00f1anza. Adem\u00e1s del \u00abeclesiocentrismo organizativo\u00bb, hemos ca\u00eddo en un \u00abeclesiocentrismo catequ\u00e9ti\u00adco\u00bb. Y no hemos unido a la dimensi\u00f3n evangelizadora la dimen\u00adsi\u00f3n caritativa, separ\u00e1ndolas.<\/p>\n<p>Por otra parte hemos hecho un \u00abescapismo\u00bb del mundo, diso\u00adciando oraci\u00f3n, Palabra, Eucarist\u00eda, Sacramentos&#8230; del proyecto de amor trinitario sobre los hombres y sobre el Universo.<\/p>\n<p>Hemos delegado, tambi\u00e9n, el servicio a los pobres a otros. Dedic\u00e1ndonos s\u00f3lo a tareas evangelizadora-catequ\u00e9ticas, le \u00abhemos pasado\u00bb esta tarea de servir a los pobres a \u00abpersonas carism\u00e1ticas\u00bb (\u00abes cosa suya\u00bb); a instituciones coma C\u00e1ritas o Institutos Religiosos (\u00abpara eso est\u00e1n\u00bb). Y no hemos creado verdaderas comunidades evangelizadoras-servidoras de los pobres y de promoci\u00f3n por la justicia.<\/p>\n<p>Pero nos vamos a fijar, sobre todo, en un aspecto que hemos descuidado. \u00bfNo hemos dado, en algunas ocasiones, la impre\u00adsi\u00f3n de haber sido en este aspecto simples agentes sociales del servicio a los pobres? Como si simplemente fu\u00e9semos una aso\u00adciaci\u00f3n de servicios sociales o de promoci\u00f3n humana. Hemos desligado esta tarea del Misterio de Dios y de la Recapitulaci\u00f3n que esperamos.<\/p>\n<p>Solamente la \u00abdinamizaci\u00f3n de la historia\u00bb no vale. Esto es caer en un \u00abcosmocentrismo\u00bb, donde el aspecto evangelizador y creador de una humanidad y creaci\u00f3n Nuevas lo hemos margina\u00addo y olvidado \u00bfNo hemos identificado, en algunas ocasiones, nuestro logros sociales y caritativos, con la plenitud del Reino de Dios? \u00bfNo nos hemos apoyado, en ocasiones demasiado, en ins\u00adtituciones, medios y subvenciones que han desvirtuado lo genui\u00adno del Evangelio?<\/p>\n<p>Es elocuente el texto del Libro de los Hechos de los Ap\u00f3stoles, por otra parte muy conocido. Pedro y Juan suben al Templo a orar. Un paral\u00edtico se acerca y le pide limosna. Pedro le responde: \u00abNo tengo oro ni plata; pero lo que tengo te doy en nombre de Jesucristo&#8230; ponte andar.\u00bb (Hech 3,1-10).<\/p>\n<p>Tambi\u00e9n el Texto de la curaci\u00f3n de los diez leprosos. Invocan a Jes\u00fas su curaci\u00f3n; \u00c9l les env\u00eda a los sacerdotes y por el camino quedan limpios de la lepra. S\u00f3lo uno vuelve \u00aby rostro en tierra a los pies de Jes\u00fas, le daba gracias; y este era un Samaritano\u00bb (Lc 17,16). Nueve de ellos quedaron \u00abcurados\u00bb y uno \u00absalvado\u00bb.<\/p>\n<p>Hemos de realizar \u00abgestos m\u00e1s escatol\u00f3gicos\u00bb. Y esperar la Consumaci\u00f3n de nuestro esfuerzo por la llegada del Reino. Ges\u00adtos como la semilla sembrada (Mt 13,24), o el grano de mostaza (Mt 13,31) o la levadura (Mt 13,33), que van creciendo lenta\u00admente, transform\u00e1ndolo todo desde el interior, hasta que \u00abpase este mundo\u00bb (1Cor 7,31) y oigamos decir \u00abal que est\u00e1 sentado en el trono: &#8216;Mira que hago un mundo nuevo<sup>\u2014<\/sup> (Ap 21, 5).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I. La plegaria por la consumaci\u00f3n 1. La palabra Maran\u00e1 Tha El comienzo de nuestra reflexi\u00f3n toma como punto de partida el grito lit\u00fargico, proveniente de la primera hora y recogido por el Ap\u00f3stol Pablo, &#8230; <a href=\"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":120780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226],"tags":[],"class_list":["post-120615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"I. La plegaria por la consumaci\u00f3n 1. La palabra Maran\u00e1 Tha El comienzo de nuestra reflexi\u00f3n toma como punto de partida el grito lit\u00fargico, proveniente de la primera hora y recogido por el Ap\u00f3stol Pablo, ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-24T02:26:46+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas\",\"datePublished\":\"2015-03-24T02:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/\"},\"wordCount\":5979,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Espiritualidad vicenciana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/\",\"name\":\"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-24T02:26:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/","og_locale":"es_ES","og_type":"article","og_title":"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas - Somos Vicencianos","og_description":"I. La plegaria por la consumaci\u00f3n 1. La palabra Maran\u00e1 Tha El comienzo de nuestra reflexi\u00f3n toma como punto de partida el grito lit\u00fargico, proveniente de la primera hora y recogido por el Ap\u00f3stol Pablo, ... Read More","og_url":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-24T02:26:46+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"30 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas","datePublished":"2015-03-24T02:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/"},"wordCount":5979,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Espiritualidad vicenciana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/","url":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/","name":"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-24T02:26:46+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/una-vida-espiritual-cristiana-sin-rebajas-como-huir-de-las-medianias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Una vida espiritual cristiana sin rebajas. C\u00f3mo huir de las median\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"https:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-vnp","jetpack-related-posts":[{"id":387828,"url":"https:\/\/vincentians.com\/es\/si-alguien-quiere-venir-en-pos-de-mi\/","url_meta":{"origin":120615,"position":0},"title":"Si alguien quiere venir en pos de m\u00ed\u2026","author":"Mitxel Olabu\u00e9naga","date":"23\/09\/2016","format":false,"excerpt":"La llamada de Jes\u00fas a seguirle implica muchas y radica\u00adles renuncias: negaci\u00f3n de .s\u00ed mismo, ruptura total con la ideolog\u00eda del mundo, desprendimiento efectivo de la familia, aceptaci\u00f3n ge\u00adnerosa de la cruz de cada d\u00eda. El Se\u00f1or nos invita a participar en su vida y muerte, para ser con \u00e9l\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/07\/asd-6-300x215.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":132931,"url":"https:\/\/vincentians.com\/es\/acercandonos-al-libro-de-los-hechos-de-los-apostoles-04\/","url_meta":{"origin":120615,"position":1},"title":"Acerc\u00e1ndonos al libro de los Hechos de los Ap\u00f3stoles (04)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"22\/12\/2014","format":false,"excerpt":"Cap\u00edtulo III: De Antioqu\u00eda hasta el confin del mundo. 1. Primera misi\u00f3n de Pablo (Hch 13,1-14,28) a. Bernab\u00e9 y Pablo enviados por la comunidad de Antioqu\u00eda (Hch 13-14) La comunidad de Antioqu\u00eda se fortalec\u00eda y empiezan a organizarse con responsabilidades que recogen t\u00edtulos jud\u00edos como son los \"profetas\" y \"maestros\"\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"pentecostes","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/12\/pentecostes-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":50420,"url":"https:\/\/vincentians.com\/es\/en-respuesta-a-tu-llamada-presentacion\/","url_meta":{"origin":120615,"position":2},"title":"En respuesta a tu llamada: Presentaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/11\/2019","format":false,"excerpt":"PRESENTACI\u00d3N Hermana: Quiero obsequiarte con esta obra sencilla y vulgar, sa\u00adlida de mi modesta artesan\u00eda. Naci\u00f3 al soplo de tu inspiraci\u00f3n y viene al farragoso mundo bibliogr\u00e1fico, como un ni\u00f1o t\u00edmido y balbuciente, asido de tus manos. La estimaci\u00f3n que alcance ser\u00e1 la que t\u00fa le des. T\u00fa eres su\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"https:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/voluntad-del-padre.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/voluntad-del-padre.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/voluntad-del-padre.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/voluntad-del-padre.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/voluntad-del-padre.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14060,"url":"https:\/\/vincentians.com\/es\/las-mujeres-comprometidas-con-el-evangelio\/","url_meta":{"origin":120615,"position":3},"title":"Las mujeres comprometidas con el Evangelio","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/06\/2015","format":false,"excerpt":"Primera parte: charla \u00bfPens\u00e1is que Pablo limit\u00f3 la participaci\u00f3n de las mujeres en las comunidades? \u00bfPor qu\u00e9? \u00bfPablo contrario a la participaci\u00f3n de las mujeres? Algunas personas se apoyan en Pablo para argumentar que la mujer debe estar callada en la comunidad y someterse al hombre. La misi\u00f3n de las\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"https:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"famvinmex5-300x279","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/06\/famvinmex5-300x279.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387086,"url":"https:\/\/vincentians.com\/es\/maria-madre-de-cristo-y-de-la-iglesia\/","url_meta":{"origin":120615,"position":4},"title":"Mar\u00eda, madre de Cristo y de la Iglesia","author":"Mitxel Olabu\u00e9naga","date":"18\/02\/2016","format":false,"excerpt":"\u00abAl ver a su madre y a su lado al disc\u00edpulo preferido, dijo Jes\u00fas: Mujer, ese es tu hijo. Y luego al disc\u00edpulo: Esa es tu madre\u00bb. (Jn 19,26-27). \u00abVeneraremos tambi\u00e9n con especial devoci\u00f3n a Mar\u00eda, Madre de Cristo y de la Iglesia, quien, seg\u00fan las palabras de San Vicente,\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"https:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/02\/asd-279x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":118401,"url":"https:\/\/vincentians.com\/es\/el-puro-amor-en-san-vicente-y-santa-luisa\/","url_meta":{"origin":120615,"position":5},"title":"El &quot;puro amor&quot; en san Vicente y santa Luisa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/10\/2021","format":false,"excerpt":"Introducci\u00f3n hist\u00f3rica No es f\u00e1cil saber de qui\u00e9n hab\u00edan tomado esta doctrina y este t\u00e9rmino el se\u00f1or Vicente y la se\u00f1orita Legras, Luisa de Marillac. Muchos autores de su \u00e9poca hab\u00edan publicado libros en los que aparec\u00eda esta doctrina del amor desinteresado de Dios, pero sin duda el t\u00e9rmino proced\u00eda\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"https:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2014\/12\/humility-daughter-of-charity.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/120615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=120615"}],"version-history":[{"count":0,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/120615\/revisions"}],"wp:attachment":[{"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=120615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=120615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=120615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}