{"id":87461,"date":"2017-12-19T08:34:28","date_gmt":"2017-12-19T07:34:28","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=87461"},"modified":"2017-11-13T10:34:07","modified_gmt":"2017-11-13T09:34:07","slug":"el-sentido-de-la-vida-religiosa-hoy","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/","title":{"rendered":"El sentido de la vida religiosa hoy"},"content":{"rendered":"<div>\n<h2><strong>1. Buscando una historia<\/strong><\/h2>\n<p>Se me ha pedido que les hable de \u00abLa vida religiosa, \u00bfqu\u00e9 sentido tiene hoy?\u00bb. La cuesti\u00f3n se plantea con urgencia a los religiosos hoy, porque muchos de noso\u00adtros nos preguntamos si el modo de vida en el que estamos comprometidos tiene el menor sentido. En Europa Occidental hay menos vocaciones que antes; en Francia, muchas congregaciones van disminuyendo en n\u00famero y algunas mueren; ser religioso no aporta ya el mismo estatus ni el respeto que suscitaba. Damos la impresi\u00f3n de haber perdido nuestro cometido en una Iglesia que parece se ha hecho m\u00e1s clerical y de haber perdido nuestra importancia en una sociedad en la que los laicos hacen ahora tantas cosas que antes hac\u00edan en gran parte los reli\u00adgiosos. Con el nuevo sentir de la santidad del matrimonio, ya no se considera incluso que nuestro modo de vida sea m\u00e1s perfecto que otro y es comprensible que muchos religiosos pregunten: \u2039&lt;La vida religiosa, \u00bf,qu\u00e9 sentido tiene hoy?'\u00bb.<\/p>\n<p>En esta situaci\u00f3n, ser\u00eda natural tratar de encontrar el sentido de la vida religiosa en algo que nos es particular, algo que nosotros hacemos y que ning\u00fan otro hace, algo que nos d\u00e9 nuestro lugar especial, nuestra identidad particular. Somos como herradores, en un mundo de autom\u00f3viles, en b\u00fasqueda de un nuevo rol. Me parece que es una de las razones por las cuales nosotros, religiosos, hablamos a menudo con ardor de nosotros mismos como de profetas. Pretendemos ser la parte prof\u00e9\u00adtica de la vida de la Iglesia. Esto nos da una identidad, un rol, una etiqueta. Creo, efectivamente que la vida religiosa est\u00e1 llamada a ser prof\u00e9tica, pero no como soluci\u00f3n a nuestra crisis de identidad. Me gustar\u00eda m\u00e1s bien partir de otro punto, a saber de la crisis del sentido que atraviesa la sociedad occidental. Creo que la vida religiosa es m\u00e1s importante que antes debido a la manera como nos vemos llamados a afrontar la crisis de sentido de nuestros contempor\u00e1neos. Nuestra vida debe ser una respuesta a la pregunta: \u00abLa vida religiosa, &#8216;\u00bfqu\u00e9 sentido tiene hoy?'\u00bb. Quiz\u00e1 ha sido \u00e9ste el testimonio esencial de la vida religiosa.<\/p>\n<p>\u00bfC\u00f3mo podemos solamente comenzar a reflexionar en una cuesti\u00f3n tan amplia como la crisis contempor\u00e1nea de sentido? Para decir cualquier cosa apropiada, har\u00eda falta haber estudiado libros sobre lo moderno y lo post-moderno. Yo no los he le\u00eddo. Mi excusa es que, como viajo con mucha frecuencia, no he tenido tiempo. Pero la verdad es que, si leyera esos libros, probablemente no los comprender\u00eda. \u00a1Est\u00e1n es\u00adcritos principalmente por Franceses inteligentes y superan el entendimiento de un Ingl\u00e9s! Voy a intentar, por el contrario, un enfoque m\u00e1s sencillo. Quisiera proponerles el contraste entre dos im\u00e1genes, dos historias impl\u00edcitas de la vida humana.<\/p>\n<p>Toda cultura tiene necesidad de historias para encarnar una comprensi\u00f3n de lo que significa un ser humano, de lo que es el modelo de la vida. Necesitamos historias que nos digan qui\u00e9nes somos y ad\u00f3nde vamos. Cuando una sociedad vive una crisis de sentido, uno de sus s\u00edntomas es que las historias contadas por esta sociedad no dan ya sentido a nuestra experiencia. Ya no son adaptadas. Cuando una sociedad atraviesa un momento de profundo cambio, necesita un nuevo tipo de historias para dar sentido a su vida.<\/p>\n<p>Voy a mostrar que la crisis fundamental de sentido en nuestra sociedad, es que la historia subyacente a la cultura europea no tiene sentido ya desde hace varios siglos. Es una historia de progreso, de una supervivencia del m\u00e1s adaptado, del triunfo del m\u00e1s fuerte. El h\u00e9roe de esta historia es el yo moderno. Est\u00e1 solo (es generalmente un hombre) y libre. Es la historia impl\u00edcita de nuestras novelas, de nuestras pel\u00edculas, de nuestra filosof\u00eda, de nuestra econom\u00eda y de nuestra pol\u00edtica. Pero ha dejado de dar sentido a nuestra experiencia. Voy a tomar como s\u00edmbolo de esta historia el cartel de un oso que he visto con frecuencia en los muros de Roma.<\/p>\n<p>As\u00ed, somos una sociedad sedienta de una nueva historia que de un sentido a nuestra identidad. Creo que el sentido de la vida religiosa consiste en responder a esta pregunta: : \u00abLa vida humana, &#8216;\u00bfqu\u00e9 sentido tiene hoy?'\u00bb. La gente debe poder reconocer en nuestras vidas una invitaci\u00f3n a ser un humano de una nueva manera. El s\u00edmbolo de esta otra historia ser\u00e1 para m\u00ed una monja cantando en la oscuridad, al pie del cirio pascual.<\/p>\n<p>Me gustar\u00eda, pues, proponer este contraste entre dos im\u00e1genes, dos historias, la de un oso y la de una monja. Me gustar\u00eda ponerlos en contraste considerando los tres elementos necesarios a toda historia: una intriga que evoluciona en el tiempo, los acontecimientos que hacen avanzar la acci\u00f3n y los actores. Si nuestros contempor\u00e1neos se sienten perdidos y desorientados, es porque las historias modernas no dan ya sentido a nuestra experiencia del tiempo, de los acontecimientos y de lo que significa ser un individuo. Nosotros, religiosos, deber\u00edamos encarnar otra manera de ser en la vida.<\/p>\n<h2><strong>2. La intriga y el tiempo<\/strong><\/h2>\n<p>Perm\u00edtanme que comience habl\u00e1ndoles de mi oso. Hace un a\u00f1o, los muros de Roma estaban llenos de carteles que representaban a un gran oso en c\u00f3lera. Y la inscripci\u00f3n en el cartel dec\u00eda: <em>\u00abLa forza del prezzo giusto\u00bb <\/em>(la fuerza del justo precio). Mientras esperaba al autob\u00fas, tuve toda la posibilidad de contemplar este oso que capta bien la historia de la modernidad.<\/p>\n<p>En primer lugar, este oso sugiere que la trama fundamental de la historia es un progreso irresistible. Es un oso del que Darwin hubiera estado orgulloso, un vencedor en el proceso de evoluci\u00f3n. La historia humana es una marcha hacia adelante. Es tambi\u00e9n un s\u00edmbolo de la econom\u00eda mundial, del mercado. Lo que hace avanzar la historia humana es la econom\u00eda. <em>\u00abLa forza del prezzo giusto\u00bb <\/em>(la fuerza del justo pre\u00adcio). La Historia, esto es el relato de un progreso inevitable, a trav\u00e9s de la liberaliza\u00adci\u00f3n del mercado. El mejor sistema econ\u00f3mico triunfa. El oso es el vencedor.<\/p>\n<p>Cuando yo era ni\u00f1o (y al verles pienso que muchos de ustedes lo eran tambi\u00e9n en aquel entonces), pod\u00edamos muy bien creer que la humanidad estaba en camino hacia un porvenir radiante. Pero, ya se perfilaban las sombras. Yo nac\u00ed una semana antes de que terminara una guerra que caus\u00f3 50 millones de muertos. Nos hemos enterado poco a poco del holocausto y de los 6 millones de jud\u00edos muertos en los campos de concentraci\u00f3n. Yo crec\u00ed bajo la amenaza de la bomba. Recuerdo c\u00f3mo mi madre hac\u00eda reservas de botes de conserva en el s\u00f3tano, para el caso en que estallara una guerra nuclear. Y sin embargo, era todav\u00eda posible acogerse a la idea de que la humanidad iba hacia adelante. Cada a\u00f1o ve\u00eda la independencia que se iba concediendo a nuestras antiguas colonias, la medicina eliminaba las enferme\u00addades como la tuberculosis y la malaria. Con toda seguridad se ver\u00eda muy pronto terminar tambi\u00e9n con la pobreza. Hasta los aviones y los coches iban m\u00e1s aprisa cada a\u00f1o. Las cosas ir\u00edan mejorando a\u00fan.<\/p>\n<p>Hoy estamos menos seguros de nosotros. El abismo entre ricos y pobres con\u00adtin\u00faa ensanch\u00e1ndose. La malaria y la tuberculosis se dan de nuevo y, dentro de un a\u00f1o, habr\u00e1 probablemente 40 millones de personas afectadas por el sida. Solamen\u00adte en Europa, el desempleo afecta a 20 millones de personas. Los sue\u00f1os de un mundo justo parecen alejarse. \u00bfA d\u00f3nde va la humanidad? Nuestra historia \u00bftiene un sentido, una direcci\u00f3n? O estamos dando vueltas, vagando por el desierto, sin acercarnos siquiera un poco al mundo de la tierra prometida? Hasta la Iglesia, que parec\u00eda orientarse hacia una renovaci\u00f3n y una nueva vida despu\u00e9s del Concilio Vaticano II, no parece ahora saber a d\u00f3nde va.<\/p>\n<p>Hay, en el coraz\u00f3n de la modernidad, una contradicci\u00f3n y, por esto, su historia ya no es plausible. Por un lado, el oso es efectivamente irresistible. En todas partes, el mercado mundial triunfa de todos sus enemigos. El comunismo ha ca\u00eddo en Europa del Este e incluso en China parece que est\u00e1 a punto de sucumbir. Pero, por otro lado, la historia no nos conduce al Reino. Lo que tenemos ante la vista es la pobreza creciente y la guerra. Hasta los tigres asi\u00e1ticos est\u00e1n enfermos. El oso es irresistible, pero nos est\u00e1 haciendo trizas. As\u00ed, la trama de los tiempos modernos contiene una insoportable contradicci\u00f3n. Ya no podemos encontrarnos en ella.<\/p>\n<p>No podemos vivir sin historias. Como hemos llegado a dudar de la marcha hacia adelante de la humanidad, hacen falta otras historias para llenar el vac\u00edo. Ser\u00e1n quiz\u00e1 historias milenarias de fin del mundo, historias de extraterrestres, historias de victoria de la copa del mundo (bravo por Francia). Bastante a menudo, es solamen\u00adte lo que llamamos en ingl\u00e9s <em>\u00absoap operas\u00bb, <\/em>las series insignificantes de la tele\u00advisi\u00f3n. Recientemente, el \u00faltimo episodio de un <em>\u00absoap opera\u00bb <\/em>ha sido contemplado en los Estados Unidos por 80 millones de personas. Los restaurantes cerraban al anochecer. El anuncio de que un asteroide gigante chocar\u00eda con la tierra el 26 de Octubre des 2028 suscit\u00f3 menos inter\u00e9s. Como hemos dejado de creer en el mito del progreso, nos refugiamos en la ficci\u00f3n.<\/p>\n<p>Es quiz\u00e1 la sed de una historia la que explica la extraordinaria reacci\u00f3n a la muer\u00adte de la princesa Diana. Los ingleses son, como saben ustedes, gente poco emotiva, o al menos los Franceses se complacen en creerlo. Sin embargo, jam\u00e1s he visto una pena semejante. Era como si la historia en el coraz\u00f3n de la humanidad hubiera llega\u00addo a su fin bajo un puente de Par\u00eds. Millones de personas lloraron como si hubieran perdido a su esposa, a su hija o a su madre. Por todas partes adonde voy por el mundo, s\u00e9 que al final la gente va a preguntarme por la princesa. Espero responder a preguntas sobre ella despu\u00e9s de esta conferencia. En Vietnam me dijeron incluso que me parec\u00eda al pr\u00edncipe William. Yo me sent\u00eda feliz, pero es que esas gentes son de una extrema cortes\u00eda. Era la <em>soap opera <\/em>del mundo. Quiz\u00e1 su historia hablaba a tantas personas porque en ella precisamente pod\u00edamos vernos a nosotros mismos. Era una persona buena pero no perfecta, que se interesaba realmente por los dem\u00e1s, cuya vida hubiera debido ser maravillosa y que, sin embargo, inexplicablemente, ha\u00adb\u00eda sido un fracaso. Es una historia triste y f\u00fatil, que evocaba la futilidad sentida por tantas personas que se preguntan ad\u00f3nde va su propia vida.<\/p>\n<p>\u00bfEn qu\u00e9 sentido la vida religiosa puede sugerir otra trama, una contrahistoria?<\/p>\n<p>Perm\u00edtanme que les proponga otra imagen. Este a\u00f1o, he celebrado la Pascua en un monasterio de monjas contemplativas dominicas. El monasterio est\u00e1 construi\u00addo en una colina detr\u00e1s de Caracas, en Venezuela. La iglesia estaba llena de j\u00f3venes. Encendimos el cirio pascual y lo colocamos en su soporte. Y una joven monja cant\u00f3, acompa\u00f1ando con la guitarra, un canto de amor al pie del cirio. El canto ten\u00eda toda la fuerza y la pasi\u00f3n de Andaluc\u00eda. Confieso que qued\u00e9 comple\u00adtamente conmovido con esta imagen de una joven religiosa cantado en la oscuridad un canto de amor al fuego reci\u00e9n nacido. Esta imagen suger\u00eda que estamos cogidos por otro drama, otra historia. Aqu\u00ed est\u00e1 nuestra historia, no es la del oso en c\u00f3lera que devora a sus rivales.<\/p>\n<p>En primer lugar, la monja que canta en la noche sugiere que la intriga funda\u00admental de la historia de la humanidad no es ya la que representaba el oso. Fuera, en el jard\u00edn, el celebrante hab\u00eda grabado el cirio diciendo estas palabras: \u00abCristo ayer y hoy, principio y fin, alfa y omega. Suyo es el tiempo y la eternidad. A \u00c9l la gloria y el poder, por los siglos de los siglos. Am\u00e9n\u00bb.<\/p>\n<p>La vida religiosa es quiz\u00e1, ante todo, un vivo Am\u00e9n a esta perspectiva temporal m\u00e1s larga. Es en esta extensi\u00f3n de la historia entre el alfa y la omega, de la creaci\u00f3n del Reino, donde todo ser humano debe encontrar su sentido. Nosotros somos los que vivimos para el Reino, para el tiempo en que, como ha dicho Juli\u00e1n Norwich: \u00abTodo estar\u00e1 bien, toda clase de cosas ser\u00e1 buena\u00bb.<\/p>\n<p>La vocaci\u00f3n que pone a la luz m\u00e1s radicalmente esta apertura hacia el futuro es la de los monjes y monjas contemplativos. Su vida no tiene ning\u00fan sentido si no est\u00e1n en el camino del Reino. El cardenal Basil Hume es el cristiano m\u00e1s respetado de Inglaterra, en parte porque es monje. Y ha escrito de los monjes lo siguiente: \u00abNo consideramos que tenemos una misi\u00f3n o una funci\u00f3n especial en la Iglesia. No nos dedicamos a cambiar el curso de la Historia. Estamos ah\u00ed, eso es todo, casi por accidente desde un punto de vista humano. Y felizmente, continuamos \u00abestan\u00addo aqu\u00ed, eso es todo\u00bb.<\/p>\n<p>Los monjes est\u00e1n all\u00ed, eso es todo, y su vida no tiene ning\u00fan sentido sino el de anunciar el cumplimiento de los tiempos, ese encuentro con Dios. Son como per\u00adsonas que esperan la llegada del autob\u00fas. S\u00f3lo el hecho de que est\u00e1n all\u00e1, indica que el autob\u00fas, sin duda, va a llegar. No hay sentido provisional ni sentido parcial. Ni hijos, ni carrera, ni realizaciones, ni promoci\u00f3n, ni utilidad. Es a trav\u00e9s de una ausencia de sentido como su vida revela una plenitud de sentido que nosotros no podemos definir. Lo mismo que el sepulcro vac\u00edo anuncia la resurrecci\u00f3n, o el centelleo en la \u00f3rbita de una estrella indica el invisible planeta.<\/p>\n<p>El monaquismo occidental naci\u00f3 en un momento de crisis. Mientras que el Imperio Romano se mor\u00eda lentamente bajo los asaltos b\u00e1rbaros, Benito fue a Su\u00adbiaco y fund\u00f3 una comunidad de monjes. Mientras que la historia de la humanidad parec\u00eda no ir a ninguna parte, Benito fund\u00f3 una comunidad de personas cuya vida no ten\u00eda otro sentido que el de indicar este fin \u00faltimo, el Reino.<\/p>\n<p>Se podr\u00eda decir que la vida religiosa nos fuerza a vivir al descubierto la crisis moderna. La mayor parte de la gente sigue un modelo de vida y una historia que permite guardar a distancia la cuesti\u00f3n principal. Una vida puede tener su propio significado por el hecho de enamorarse, casarse, tener hijos y nietos. O bien, la historia de otro encontrar\u00e1 su sentido en una carrera, ascendiendo los grados de la promoci\u00f3n, haciendo fortuna e incluso ganando la notoriedad. Se pueden contar muchas historias para dar un modelo provisional y un sentido a nuestra estancia en a tierra. Y esto es justo y bueno. Pero nuestros votos no nos ofrecen este consuelo. Nosotros no tenemos matrimonio para dar forma a nuestra vida. No tenemos carrera. Nos encontramos desprovistos ante la cuesti\u00f3n: \u00abLa vida humana, \u00bfqu\u00e9 sentido tiene?\u00bb<\/p>\n<p>Pero no basta con sentarse y esperar la venida del Reino. Los hermanos m\u00e1s j\u00f3venes no est\u00e1n a veces de acuerdo conmigo, sin embargo hay que levantarse cada ma\u00f1ana para hacer algo. \u00a1Hasta los monjes y las monjas tienen que hacer algo! Re\u00adcuerdo haber preguntado un d\u00eda a un hermano, especialmente perezoso, qu\u00e9 hac\u00eda. Me respondi\u00f3 que \u00e9l \u00abera un signo escatol\u00f3gico\u00bb, que esperaba la venida del Reino.<\/p>\n<p>\u00bfC\u00f3mo valorizamos lo que hacemos ahora? La mayor parte de entre nosotros pasan sus d\u00edas en actividades \u00fatiles, ense\u00f1ar, trabajar en los hospitales, ayudar en las parroquias, ocuparse de los olvidados. \u00bfC\u00f3mo nuestra vida cotidiana habla de la historia de la humanidad?<\/p>\n<p>Volvamos de nuevo a aquella joven monja. Es de noche y ella canta ese canto lleno de emoci\u00f3n y de fuerza vital. Es de noche cuando canta las alabanzas de Dios. Incluso en la oscuridad, entre el comienzo y el fin, podemos encontrar a Dios y glori\u00adficarlo. Ahora es la hora. Mientras esperaba ser asesinado, Jes\u00fas dice a sus disc\u00edpu\u00adlos: \u00abEn el mundo encontrar\u00e9is dificultades y tendr\u00e9is que sufrir, pero tened \u00e1nimo, yo he vencido al mundo\u00bb (Jn 16, 33). Es ahora la hora de la victoria y de la alabanza.<\/p>\n<p>Lo que esto inspira es un nuevo sentimiento del tiempo. Lo que da su forma al tiempo no es la historia de la inevitable progresi\u00f3n hacia la riqueza y el \u00e9xito. La forma oculta de nuestra vida es el crecimiento en la amistad de Dios, en c\u00f3mo lo encontramos en el camino y decimos Am\u00e9n. No es s\u00f3lo el final de la historia lo que le da un sentido. El modelo de mi vida es el encuentro con Dios y mi respuesta a su invitaci\u00f3n. Es lo que hace de mi vida no una simple sucesi\u00f3n de acontecimientos sino un destino. Como ha dicho Cornelius Ernst, o.p.,: \u00abEl destino es la llamada y la invitaci\u00f3n del Dios de Amor a que le respondamos mediante un consentimiento creador y lleno de amor\u00bb&#8216;. Incluso en las tinieblas, en la desesperanza, cuando nada tiene sentido, podemos encontrar al Dios de Vida. Como escrib\u00eda un fil\u00f3sofo jud\u00edo: \u00abCada instante puede ser la peque\u00f1a puerta por la que el Mes\u00edas puede entrar\u00bb. La historia de nuestras vidas es la historia de ese encuentro con el Dios que viene en la oscuridad como un amante. Es lo que celebramos al glorificarle.<\/p>\n<p>Los momentos m\u00e1s emocionantes que he vivido en estos seis \u00faltimos a\u00f1os han sido posibilidades de compartir con mis hermanos y hermanas la alabanza de Dios en las circunstancias m\u00e1s dif\u00edciles: en un monasterio de Burundi, despu\u00e9s de haber viajado a trav\u00e9s de un pa\u00eds desgarrado por la violencia \u00e9tnica; en Irak, en espera de las bombas; en Argelia, con nuestro hermano Pierre Claverie antes de su ase\u00adsinato. Es esencial para la vida religiosa que cantemos las alabanzas de Dios, incluso en las tinieblas. Cantamos los Salmos, el <em>tehillim, <\/em>el libro de las alabanzas. Medimos la jornada por las horas del oficio divino, por la liturgia de los salmos, y no solamente por las horas mec\u00e1nicas del reloj. \u00abSiete veces al d\u00eda te glorifico\u00bb. Pues, bien, al menos dos veces la mayor parte de nosotros.<\/p>\n<p>Recuerdo una historia que ilustra bien c\u00f3mo el tiempo de la alabanza puede ejercer una interacci\u00f3n con el tiempo del reloj, el tiempo moderno. Cuando uno de mis hermanos era peque\u00f1o, en la escuela, un dentista vino un d\u00eda a dar una clase de higiene dental a los ni\u00f1os. Pregunt\u00f3 a la clase cu\u00e1ndo hay que lavarse los dientes. Silencio absoluto. Insisti\u00f3: \u00abVamos, vosotros sab\u00e9is muy bien cu\u00e1ndo deb\u00e9is \u00a1avaros los dientes: por la ma\u00f1ana y por la noche&#8230;.\u00bb. Esto debi\u00f3 poner en funcionamiento un resorte en la mente de aquellos buenos peque\u00f1os cat\u00f3licos que sab\u00edan su catecismo y siguieron todos: \u00abantes y despu\u00e9s de las comidas\u00bb. \u00abExce\u00adlente\u00bb, dijo el dentista; y los ni\u00f1os a\u00f1adieron: \u00abEn la tentaci\u00f3n y en la hora de nuestra muerte\u00bb. Pues bien, si nos lav\u00e1ramos siempre los dientes en el momento de las tentaciones, podr\u00edamos evitar muchos pecados.<\/p>\n<p>El ritmo regular de la alabanza es m\u00e1s que un simple optimismo, confiando que todo ir\u00e1 bien al final. Proclamamos que, desde ahora, en el desierto, el Se\u00f1or de la Vida viene a nosotros y da forma a nuestra vida. En este sentido, la vida religiosa deber\u00eda ser verdaderamente prof\u00e9tica, pues el profeta es el que ve c\u00f3mo el porvenir hace irrupci\u00f3n en el presente. Como dice Habacuc: \u00abAunque la higuera no eche sus brotes, ni den su fruto las vi\u00f1as; aunque falle la cosecha del olivo, no produzcan nada los campos, (&#8230;) yo me alegrar\u00e9 en el Se\u00f1or, tendr\u00e9 mi gozo en Dios mi Salvador\u00bb (3, 17-18).<\/p>\n<p>Recientemente he hablado con los promotores de Justicia y Paz de la Orden en Am\u00e9rica Latina. Es una nueva generaci\u00f3n, no viejos sesentones como yo. J\u00f3venes, hombres y mujeres, que tienen un sue\u00f1o en su vida. Yo esperaba encontrarlos desanimados, vista la situaci\u00f3n econ\u00f3mica que empeora, la violencia que crece, la desintegraci\u00f3n social en su continente. \u00a1En absoluto! Dicen que es precisamente ahora, cuando todas las utop\u00edas han desaparecido, cuando el Reino parece m\u00e1s lejos que nunca, cuando nosotros, religiosos, debemos cumplir nuestra misi\u00f3n. Nadie m\u00e1s podr\u00eda so\u00f1ar ahora. Pero batirse hoy en favor de un mundo m\u00e1s justo, mientras que se tiene la impresi\u00f3n de no progresar, significa que hay que ser una persona de profunda oraci\u00f3n. Como ha escrito nuestro hermano brasile\u00f1o Fray Betto, hay que ser un m\u00edstico hoy para creer en la justicia y la paz.<\/p>\n<h2><strong>3. La acci\u00f3n<\/strong><\/h2>\n<p>Hay un segundo contraste que me gustar\u00eda marcar entre la historia del oso y la de la monja, con relaci\u00f3n a c\u00f3mo suceden las cosas. \u00bfCu\u00e1l es el motor de la historia? \u00bfQu\u00e9 es lo que hace avanzar el relato? Necesitamos a la vez una trama y unos hechos.<\/p>\n<p>Hemos visto ya que el oso representa la competici\u00f3n para sobrevivir. Lo que anima la historia es esa competici\u00f3n en la que el d\u00e9bil perece y el fuerte prospera. Ya estudiemos la evoluci\u00f3n o la econom\u00eda, es exactamente as\u00ed como pasan las cosas. Es el principio b\u00e1sico de la historia moderna. El motor que impulsa la historia<br \/>\nes la libre competici\u00f3n que elimina al anormal, al desesperado, al no viable.<\/p>\n<p>Pero, una vez m\u00e1s, vemos ah\u00ed una contradicci\u00f3n. Pues este oso simboliza la libertad misma que est\u00e1 en el coraz\u00f3n de la modernidad: libertad de competencia en el libre mercado, donde cada uno es libre para escoger lo que quiere. Sin embargo, hemos visto que esta libertad es, tambi\u00e9n, en cierta medida, ilusoria. Porque estamos cogidos en una transformaci\u00f3n general del mundo que nos hace impotentes y que nadie es capaz de detener, una transformaci\u00f3n que destruye las comunidades y devora el planeta. As\u00ed se encuentra en el coraz\u00f3n de la historia moderna una doble contradicci\u00f3n. Se nos ofrece el progreso y encontramos la pobreza; se nos ofrece la libertad y nos encontramos impotentes. \u00bfQu\u00e9 otra historia puede encarnar la vida religiosa?<\/p>\n<p>Pero, consideremos otra vez a esta monja joven que canta su canto de amor en la oscuridad. Representa otra manera de contar. La historia que celebra es la de un hombre abatido por los fuertes pero que vive para siempre. El gran oso de Roma y de Jerusal\u00e9n devoran al peque\u00f1o hombre de Galilea. Lo que celebramos en esta historia no es la fuerza superior de Dios, \u00abel m\u00e1s grande oso\u00bb sino su absoluta creatividad en la Resurrecci\u00f3n de Jes\u00fas de entre los muertos.<\/p>\n<p>No hay historia m\u00e1s que si ocurre algo nuevo. Las historias cuentan c\u00f3mo las cosas cambian. Pero el modelo del cambio de la era moderna es la supervivencia del m\u00e1s fuerte.<\/p>\n<p>La evoluci\u00f3n biol\u00f3gica o econ\u00f3mica aportan transformaciones, pero a trav\u00e9s de la competici\u00f3n para sobrevivir. Mientras que nuestra historia de la monja propone una novedad todav\u00eda m\u00e1s radical: el inimaginable don de una vida nueva. Glorifi\u00adcamos a Dios que dice: \u00abHe aqu\u00ed que hago nuevas todas las cosas\u00bb. Nosotros, los religiosos, estamos llamados a ser signos de la indecible novedad de Dios, de su inefable creatividad.<\/p>\n<p>Como religiosos \u00bfc\u00f3mo ser signos de esta extra\u00f1a historia del Dios de muerte y de resurrecci\u00f3n? La se\u00f1al m\u00e1s evidente aparece en la presencia de todos esos reli\u00adgiosos que rehusan dejar lugares de muerte y de violencia, confiando en el Se\u00f1or que resucita a los muertos. Por todas partes donde hace estragos la violencia, en Rwan\u00adda, Burundi, en el Congo, en Chiapas, se encuentran religiosos y religiosas cuya pre\u00adsencia es una se\u00f1al de esta historia cantada por nuestra monja. Naturalmente, aqu\u00ed, en Francia, pensamos en los numerosos religiosos muertos en Argelia. Todos uste\u00addes deben de conocer muy bien aquellas palabras maravillosas de Christian de Cher\u00adg\u00e9, prior de los monjes trapenses, cuando escribi\u00f3 su testamento espiritual poco an\u00adtes de su muerte. Espero que me permitir\u00e1n repetirlas una vez m\u00e1s:<\/p>\n<p>\u00abCuando un A-Dios se vislumbra\u00bb.<\/p>\n<p>\u00abSi me ocurriera un d\u00eda \u2014y eso podr\u00eda ser hoy- ser v\u00edctima del terrorismo que parece querer englobar ahora a todos los extranjeros que viven en Argelia, me gustar\u00eda que mi comunidad, mi Iglesia, mi familia, recordaran que mi vida estaba dada a todos y a este pa\u00eds. Que acepten que el \u00danico Due\u00f1o de toda vida no podr\u00eda ser extra\u00f1o a esta partida brutal. Que recen por m\u00ed: \u00bfc\u00f3mo voy a ser encontrado digno de tal ofrenda? Que sepan asociar esta muerte a tantas otras tambi\u00e9n vio\u00adlentas dejadas en la indiferencia del anonimato (&#8230;).<\/p>\n<p>\u00abDoy gracias a Dios porque esta vida perdida, totalmente m\u00eda, y totalmente suya, parece haberla querido toda entera para esta Alegr\u00eda, contra todo y a pesar de todo\u00bb.<\/p>\n<p>La preparaci\u00f3n de semejante testimonio consiste ciertamente en que toda co\u00admunidad religiosa es un lugar donde se aprende c\u00f3mo ir al mundo a trav\u00e9s de la muerte y de la resurrecci\u00f3n. Una de mis t\u00edas se hizo religiosa del Sagrado Coraz\u00f3n. A la edad de siete a\u00f1os, asust\u00f3 a sus numerosas hermanas cuando la encontraron sujetando con alfileres, en la pared de la habitaci\u00f3n de las ni\u00f1as, una hoja de papel que dec\u00eda: \u00abQuiero ser disuelta y unida a Cristo\u00bb. Dudo que, en nuestros d\u00edas, muchos candidatos a la vida religiosa hagan este tipo de gesto, \u00a1gracias a Dios! Pero una comunidad religiosa debe ser un lugar donde aprendamos a morir y a resucitar, un lugar de transformaci\u00f3n. No somos los prisioneros de nuestro pasado. Podemos crecer en santidad. Podemos morir y ser renovados.<\/p>\n<p>Esto no ocurrir\u00e1 probablemente si huimos el afrontar la muerte de nuestras propias instituciones. Hoy, en Europa occidental, muchas congregaciones, comuni\u00addades, monasterios y provincias deben hacer frente a la muerte. Hay muchas estrategias para evitar esta verdad. Se puede beatificar a un fundador, lanzar importantes programas de construcci\u00f3n, escribir magn\u00edficos documentos sobre pro\u00adyectos que nunca se pondr\u00e1n en marcha. Cuando enviamos hermanos y hermanas a Filipinas, Colombia, Brasil, \u00bfes con un repentino y nuevo celo misionero o porque queremos vocaciones para sobrevivir? Si no podemos afrontar la perspectiva de la muerte \u00bfqu\u00e9 tenemos entonces que decir del Se\u00f1or de la Vida? Un d\u00eda visitaba un monasterio de dominicas en Inglaterra con un hermano anciano. El monasterio tocaba con toda evidencia al fin de su vida, pero una de las monjas dijo a mi compa\u00f1ero: \u00ab\u00a1Padre, ciertamente, nuestro querido Se\u00f1or no podr\u00eda dejar morir este monasterio!\u00bb A lo que \u00c9l respondi\u00f3: \u00abSin embargo, \u00bfno dej\u00f3 morir a su Hijo?\u00bb.<\/p>\n<p>Una de nuestras maneras de vivir esta inimaginable historia de muerte y resu\u00adrrecci\u00f3n es indudablemente poner en el mundo una vida nueva en lugares inespe\u00adrados. Nosotros debemos ser los que van al valle de la muerte y muestran su fe en el Dios que resucita a los muertos. Recuerdo a uno de mis hermanos escoce\u00adses, que era poeta y luchador, inveros\u00edmil asociaci\u00f3n, pero era de todas formas un hombre inveros\u00edmil. Lanz\u00f3 un programa en Escocia para iniciar a los presos en el arte. Estaba convencido de que si no cre\u00edamos en su creatividad, no se rehar\u00edan nunca. Su primera tentativa tuvo lugar en una c\u00e1rcel muy dura de Glasgow. Pre\u00adgunt\u00f3 a los presos qu\u00e9 les gustar\u00eda probar: pintura, poes\u00eda, escultura, danza. \u00a1Pue\u00adden ustedes imaginarse sus reacciones! Entonces se remang\u00f3 y dijo: \u00ab\u00a1Si alguno de vosotros piensa que el arte no es para verdaderos hombres, bien, me pelear\u00e9 con \u00e9l!\u00bb. Y es lo que hizo&#8230; con cada uno de ellos. Y comenzaron todos clases de poes\u00eda y de pintura. Felizmente no es esa la \u00fanica manera de llevar a la gente a la fe en el Dios que hace nuevas todas las cosas.<\/p>\n<p>Otra manera, quiz\u00e1 m\u00e1s tradicional, de la que los religiosos han sido siempre un signo del Dios Eterno Creador, es a trav\u00e9s de la belleza. Ustedes han sido conscientes de esto en Francia m\u00e1s que en otros pa\u00edses. Hace unas semanas, habl\u00e9 en Alemania con un anciano dominico, pintor y escultor. Y le pregunt\u00e9 qu\u00e9 es lo que m\u00e1s le gusta hacer. Me contest\u00f3 que siempre le ha gustado grabar piedras tumbales. Hay heridas tan profundas que s\u00f3lo la belleza puede curar. Ante ciertos sufrimientos, la esperanza no se puede expresar m\u00e1s que a trav\u00e9s del arte. Una piedra tumbal muy hermosa puede hablar con elocuencia de la esperanza en la resurrecci\u00f3n, del Dios que sabe resucitar a los muertos.<\/p>\n<p>Por \u00faltimo, est\u00e1 la belleza de la Liturgia, la belleza del canto de alabanza a Dios, que habla del Dios que transforma todas las cosas. Es la belleza por la que hemos comenzado, la de una monja joven que canta un canto de amor, en la noche, ante un cirio. Es la belleza de un canto lleno de la pasi\u00f3n de las gentes del sur de Espa\u00f1a lo que me conmovi\u00f3. Esto me hace pensar en Pablo Neruda que dec\u00eda que, entre los dramas del nacimiento y de la muerte, hab\u00eda escogido la guitarra.<\/p>\n<h2><strong>4. El actor<\/strong><\/h2>\n<p>Por \u00faltimo, no hay historia sin actores, sin personajes. Cada historia debe tener su h\u00e9roe. Y \u00bfqu\u00e9 mejor imagen del yo moderno podr\u00edamos encontrar que nuestro oso, en c\u00f3lera y solo? Pero el \u00abyo moderno\u00bb est\u00e1 en crisis.<\/p>\n<p>Este nuevo sentimiento de lo que significa un ser humano es fundamental para la era moderna; un yo separado y aut\u00f3nomo, desprendido y libre, y en fin de cuentas: solo. Es el fruto de una evoluci\u00f3n que dura hace siglos, en que los lazos sociales se han disuelto y donde lo privado se ha hecho posible e incluso un ideal. Es nuestro h\u00e9roe desde la \u00e9poca de Descartes. Lo vemos en cualquier <em>western <\/em>americano, figura solitaria.<\/p>\n<p>La crisis de la modernidad es en parte debida a que este \u00abyo moderno\u00bb encierra una contradicci\u00f3n. Porque no podemos ser un \u00abyo\u00bb absolutamente solo. No pode\u00admos existir como un \u00e1tomo solitario, aut\u00f3nomo. No podemos existir sin comunidad, sin personas a las que hablar, sin lo que Charles Taylor llama \u00abredes de interlo\u00adcuci\u00f3n\u00bb. Es la contradicci\u00f3n que est\u00e1 en el coraz\u00f3n de la Historia moderna: nos vemos como esencialmente solitarios, mientras que, de hecho, nadie puede ser un individuo fuera de toda forma de comunidad. No es posible ser largo tiempo un \u00abyo moderno\u00bb. El oso del cartel representa un ideal imposible. Solo, morir\u00eda.<\/p>\n<p>Volvamos por \u00faltima vez a nuestra monja que cantaba ante el cirio pascual. No est\u00e1 sola. Apenas visible al resplandor del cirio, est\u00e1 la multitud de j\u00f3venes. La vigilia pascual es una reuni\u00f3n del pueblo de Dios. Lo que nace esa noche es una comunidad. Nos reunimos para recordar nuestro bautismo en el Cuerpo de Cristo y expresar juntos una Fe com\u00fan. Esto representa otra visi\u00f3n de lo que significa ser persona.<\/p>\n<p>\u00abLa vida humana, \u00bf`qu\u00e9 sentido tiene hoy&#8217;?\u00bb Una de las maneras de intentar responder a este interrogante en la vida religiosa, es vivir en comunidad. Encontrar la propia identidad en esta comunidad, como hermano, hermana, es vivir otra imagen del yo, otra manera de ser un humano. Encarna una `contrahistoria&#8217; a la del h\u00e9roe moderno. En los comienzos, se llamaba a una comunidad de dominicos una <em>sacra predicatio, <\/em>una \u00absanta predicaci\u00f3n\u00bb. Vivir juntos como hermanos \u00abcon un solo coraz\u00f3n y un solo esp\u00edritu\u00bb era una predicaci\u00f3n, incluso antes de que alguien hubiera pronunciado una sola palabra. Probablemente, los j\u00f3venes son llevados a la vida religiosa m\u00e1s por la b\u00fasqueda de comunidad que por ninguna otra raz\u00f3n. Seg\u00fan la exhortaci\u00f3n apost\u00f3lica postsinodal sobre la vida religiosa, somos un signo de comuni\u00f3n para toda la Iglesia, un testimonio de la vida de la Sant\u00edsima Trinidad.<\/p>\n<p>Pero si es la comunidad lo que lleva a los j\u00f3venes a la vida religiosa, es tambi\u00e9n la dificultad de la vida com\u00fan lo que los lleva tambi\u00e9n a abandonarla. Aspiramos a la comuni\u00f3n y sin embargo, es muy dolorosa vivirla. Cuando encuentro a j\u00f3venes dominicos en periodo de formaci\u00f3n, les pregunto con frecuencia qu\u00e9 es lo mejor y lo peor que encuentran en la vida religiosa, y, en general, dan la misma respuesta a las dos preguntas: vivir en comunidad. Es que somos hijos de nuestra \u00e9poca, estamos modelados por su percepci\u00f3n del yo moderno. No somos lobos bajo piel de oveja. Somos osos bajo piel de monja.<\/p>\n<p>Se podr\u00eda decir que en la vida religiosa, vivimos en espejo la imagen de la crisis del yo moderno. El individuo moderno aspira a una autonom\u00eda, una libertad, un des\u00adprendimiento que son imposibles, porque no se puede ser un humano solo. Para ser humanos, necesitamos pertenecer a comunidades, pensemos lo que pensemos. Pero, nosotros, religiosos, vivimos el reflejo de este drama. Entramos en la vida reli\u00adgiosa aspirando a la comunidad, deseando verdaderamente ser hermanos y herma\u00adnas los unos de los otros, pero as\u00ed y todo somos producto de la era moderna, esta\u00admos marcados por su individualismo, su miedo al compromiso, su sed de independencia. La mayor parte de nosotros han nacido en familias de 1,5 hijos y es duro vivir con la multitud. Por eso, el individuo moderno y el religioso son dos aspec\u00adtos de una misma tensi\u00f3n. El individuo moderno sue\u00f1a con una imposible autonom\u00eda y nosotros, religiosos, aspiramos a una comunidad que es dura de soportar.<\/p>\n<p>El oso no puede hacerse monja en el espacio de un a\u00f1o de noviciado. Ha de darse la lenta educaci\u00f3n para hacerse humano, para aprender a hablar y a escu\u00adchar, a romper el cerco del egocentrismo y del ego\u00edsmo, que hacen de m\u00ed el centro del mundo. Es el lento renacimiento que ha de hacerse por medio de la oraci\u00f3n y la conversi\u00f3n, que me libera de las falsas im\u00e1genes de Dios y de los dem\u00e1s.<\/p>\n<p>En esto vivimos, despojados, intensamente, el drama de la Iglesia moderna. Ja\u00adm\u00e1s se hab\u00eda presentado antes la Iglesia con tanta insistencia como una comunidad.<\/p>\n<p>La <em>Koinonia <\/em>es el coraz\u00f3n de todas las eclesiolog\u00edas contempor\u00e1neas. Y, sin embar\u00adgo, jam\u00e1s la Iglesia, al menos en la Europa occidental, hab\u00eda ofrecido antes tan poca comuni\u00f3n verdadera. Hablamos el lenguaje de la comuni\u00f3n, pero s\u00f3lo la vivimos ra\u00adramente. El lenguaje y la realidad est\u00e1n separados. Uno de nuestros intentos para dar cuerpo a este sue\u00f1o de comuni\u00f3n es, con toda seguridad, atreverse a construir comunidades en lugares imposibles, all\u00e1 donde todos los dem\u00e1s los han abandona\u00addo. Con frecuencia, en estos \u00faltimos a\u00f1os, he encontrado peque\u00f1as comunidades de religiosos, en general mujeres, que formaban una comunidad all\u00ed donde todos los dem\u00e1s parec\u00edan desesperar, donde los seres humanos estaban aplastados y deses\u00adperados por la violencia y la pobreza. All\u00e1 donde todo parece sin esperanza, encon\u00adtraremos algunas religiosas que instalan una casa con la puerta abierta.<\/p>\n<p>Una sola imagen resumir\u00e1 muchos recuerdos. Al d\u00eda siguiente de la vigilia pas\u00adcual, celebrada con aquella monja, en el monasterio, fui a visitar una peque\u00f1a capilla a cargo de los hermanos en Caracas, en uno de los <em>barrios <\/em>m\u00e1s violentos de Am\u00e9rica Latina. La Capilla estaba acribillada de agujeros de proyectiles. Como media, 28 per\u00adsonas son asesinadas por bala cada fin de semana en la parroquia. En la pared de\u00adtr\u00e1s del altar, hay un fresco pintado por los ni\u00f1os del barrio. Es una pintura de la Cena, con Jes\u00fas comiendo, rodeado de dominicos y de dominicas. Domingo acaricia a su perro. Pero el disc\u00edpulo al que \u00e9l amaba, reclinado sobre el costado de Jes\u00fas, es un ni\u00f1o del barrio, un ni\u00f1o de la calle. S\u00edmbolo del ni\u00f1o que al fin ha encontrado una pertenencia en este mundo violento, la promesa de un hogar.<\/p>\n<h2><strong>5. Conclusi\u00f3n<\/strong><\/h2>\n<p>Tengo que acabar. Afirmaba, al comenzar, que no podemos encontrar el sentido de la vida religiosa m\u00e1s que comprendiendo que es una respuesta a la b\u00fasqueda de <em>sentido <\/em>de la vida humana. He sugerido despu\u00e9s que una de las maneras de comprender la actual crisis de sentido de la sociedad occidental se formula as\u00ed: la historia fundamental que contamos para decir qui\u00e9nes somos y ad\u00f3nde vamos ya no funciona. Esto est\u00e1 simbolizado por nuestro querido oso. Es una historia llena de contradicciones. Habla de progreso, pero parece llevarnos a la pobreza. Ofrece la libertad y sin embargo nos encontramos con frecuencia impotentes. Invita a ser el \u00abyo moderno\u00bb, aut\u00f3nomo y solitario, pero descubrimos que no podemos ser humanos sin comunidad.<\/p>\n<p>Por eso la vida religiosa no puede responder a esta sed de sentido m\u00e1s que encarnando otra historia, otra visi\u00f3n de lo que es ser un humano, cuyo s\u00edmbolo vemos en nuestra a\u00fan m\u00e1s querida monja, que canta ante el cirio en la noche. Es una historia que ofrece otro sentido del tiempo. No es tanto la inevitable marcha del progreso como el relato del c\u00f3mo nos encontramos con el Se\u00f1or que nos llama a \u00c9l. Y lo que anima esta historia, no es la libre competencia, sino la inimaginable creatividad de Dios que resucita a los muertos. Y el h\u00e9roe de esta historia no es el h\u00e9roe solitario de los tiempos modernos, sino el hermano y la hermana que se encuentran en comunidad y construyen para los dem\u00e1s una comunidad.<\/p>\n<p>La vida religiosa no es otra cosa m\u00e1s que una tentativa de vivir esta otra historia, la historia pascual de la muerte y de la resurrecci\u00f3n. Como ha escrito Bruno Chenu en su excelente libro, que he le\u00eddo demasiado tarde: \u00abLos religiosos quieren poner en pr\u00e1ctica una cierta l\u00f3gica del Bautismo, una vida en Cristo llevada hasta sus \u00faltimas consecuencias\u00bb. Los votos no dan un sentido diferente o espe\u00adcial a nuestra vida, hacen p\u00fablico y expl\u00edcito nuestro rechazo de la historia del oso. La obediencia, por ejemplo, es un claro rechazo de la imagen del yo aut\u00f3nomo, solitario y liberado. Es una declaraci\u00f3n de nuestra intenci\u00f3n de vivir a trav\u00e9s de esta otra historia, de descubrir qui\u00e9nes somos en la vida com\u00fan de los hermanos. Es un compromiso para liberarse de la insostenible carga del yo moderno y solitario. En la obediencia, rechazamos tambi\u00e9n la imagen de la vida como combate por la fuerza, lo mismo que en la pobreza, renunciamos p\u00fablicamente a la competici\u00f3n por el \u00e9xito, el &#8216;puerto de arrebatacapas&#8217; de la sociedad de consumo. En la casti\u00addad, aceptamos que la fertilidad m\u00e1s profunda que podamos jam\u00e1s tener es la del Dios Creador que resucita a los muertos.<\/p>\n<p>Estos votos nos dejan despojados y expuestos. Invierten cualquier otra historia que vendr\u00eda a dar un sentido provisional a nuestra vida y a permitirnos continuar un d\u00eda m\u00e1s. Prometemos abandonar carrera, \u00e9xito financiero, todos los escondites que pudieran sugerir que despu\u00e9s de todo, el oso tiene raz\u00f3n. Si esta historia pascual no es verdadera, entonces nuestras vidas no tienen ning\u00fan sentido y \u00abso\u00admos los m\u00e1s miserables de todos los hombres\u00bb (1 Co 15, 19).<\/p>\n<p>No es f\u00e1cil. Somos los hijos de la era moderna y hemos sido formados por sus historias, hemos compartido sus sue\u00f1os. S\u00e9, por ejemplo, que me parezco m\u00e1s al oso que a la monja. Mis respuestas instintivas son m\u00e1s a menudo las del yo solitario que las de un hermano. S\u00e9 que apenas he comenzado el proceso de renacimiento.<\/p>\n<p>Mi imaginaci\u00f3n s\u00f3lo est\u00e1 refundida a medias. Cuando espero la parada del autob\u00fas en Roma y miro los carteles, es a mi mismo a quien estoy viendo.<\/p>\n<p>De ello saco dos conclusiones. Primero, puedo al menos compartir con mis contempor\u00e1neos un combate para dejar la m\u00e1scara del oso y tomar figura humana. Si no compartiera esta lucha, no tendr\u00eda nada que responder a la pregunta: : \u00abLa vida humana, `\u00bf,qu\u00e9 sentido tiene hoy?'\u00bb. El religioso no es un ser celestial, que escapa a la modernidad, sino una persona cuyos votos han hecho inevitable y sin escapatoria el combate por renacer. Compartimos con los dem\u00e1s las angustias del renacimiento. Si somos honrados en nuestros combates, quiz\u00e1 los dem\u00e1s compar\u00adtir\u00e1n nuestra esperanza.<\/p>\n<p>Despu\u00e9s, como esto es dif\u00edcil, debemos dedicarnos verdaderamente a construir comunidades donde esta nueva vida pascual sea posible. Una comunidad religiosa debe ser m\u00e1s que un lugar donde comer, decir algunas oraciones y entrar a dormir todas las noches. Es un lugar de muerte y de resurrecci\u00f3n, donde nos ayudamos rec\u00edprocamente a hacernos nuevos. Comienzo a apreciar la idea de la vida religiosa como ecosistema, concepto que he desarrollado en otro lugar<sup>4<\/sup>. Un ecosistema es lo que permite existir a formas de vida extra\u00f1as. Toda forma de vida extra\u00f1a necesita su ecosistema. Esto es particularmente verdadero para los j\u00f3venes que vienen hoy a la vida religiosa, que con frecuencia han llegado a la fe en Dios, recientemente. Una rana, por ejemplo, no puede vivir, reproducirse y tener un futuro m\u00e1s que si dispone de todos elementos indispensables de su ecosistema: un es\u00adtanque, sombra, diversas plantas, mucho barro, y otras ranas. Ser religioso, es escoger una forma de vida extra\u00f1a y cada uno de nosotros necesitar\u00e1 su entorno que lo sostenga: oraci\u00f3n, silencio, comunidad. Sin ello no podremos crecer. Por eso, un buen superior es un ecologista que ayuda a sus hermanos a construir los entornos necesarios para su buen desarrollo. Pero los ecosistemas no son peque\u00ad\u00f1as c\u00e1rceles que nos cortan del mundo moderno. Un ecosistema permite a una forma de vida florecer y reaccionar de manera creativa a otras formas de vida.<\/p>\n<p>Necesitamos ecosistemas que sostengan en nosotros el sentido del tiempo pascual, el ritmo del a\u00f1o lit\u00fargico que nos lleva de Adviento a Pentecost\u00e9s. Nece\u00adsitamos comunidades que est\u00e9n marcadas por sus ritmos, por sus marcos de celebraci\u00f3n y de ayuno. Necesitamos comunidades donde no nos limitemos a re\u00adcitar por obligaci\u00f3n algunos salmos antes de ir a trabajar, sino donde sostengamos en nosotros mismos a aquel que, incluso en el desierto, terminar\u00e1 por cantar las alabanzas. Necesitamos construir comunidades en las que podamos compartir nuestra fe y nuestra desesperanza, con el fin de ayudarnos mutuamente a atrave\u00adsar el desierto. Necesitamos comunidades en las que poder lentamente renacer como hermanos y hermanas, hijos del Dios vivo.<\/p>\n<p>La monja canta en la oscuridad, como Domingo cantaba caminando en el sur de Francia. Esa es la vocaci\u00f3n cristiana. San Agust\u00edn nos dec\u00eda: \u00abSeguid el cami\u00adno. Cantad mientras camin\u00e1is. Es lo que hacen los viajeros para aligerar su carga (&#8230;). Cantad un c\u00e1ntico nuevo. No dej\u00e9is que nadie venga a repetir sin cesar los viejos estribillos. Cantad cantos de amor de vuestro pa\u00eds (&#8230;). Como cantan los viajeros, y cantan con frecuencia durante la noche. Todos los ruidos que oyen alrededor son espantosos. Pero cantan incluso cuando tienen miedo de los bandi\u00addos\u00bb. \u00a1O de los osos!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>1. Buscando una historia Se me ha pedido que les hable de \u00abLa vida religiosa, \u00bfqu\u00e9 sentido tiene hoy?\u00bb. La cuesti\u00f3n se plantea con urgencia a los religiosos hoy, porque muchos de noso\u00adtros nos preguntamos &#8230; <a href=\"http:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":400011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[29],"tags":[168],"class_list":["post-87461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion-cristiana","tag-argel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sentido de la vida religiosa hoy - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sentido de la vida religiosa hoy - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"1. Buscando una historia Se me ha pedido que les hable de \u00abLa vida religiosa, \u00bfqu\u00e9 sentido tiene hoy?\u00bb. La cuesti\u00f3n se plantea con urgencia a los religiosos hoy, porque muchos de noso\u00adtros nos preguntamos ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-19T07:34:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"38 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"El sentido de la vida religiosa hoy\",\"datePublished\":\"2017-12-19T07:34:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/\"},\"wordCount\":7518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/09\\\/sencillos-como-palomas.jpg?fit=1200%2C630\",\"keywords\":[\"Argel\"],\"articleSection\":[\"Formaci\u00f3n Cristiana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/\",\"name\":\"El sentido de la vida religiosa hoy - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/09\\\/sencillos-como-palomas.jpg?fit=1200%2C630\",\"datePublished\":\"2017-12-19T07:34:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/09\\\/sencillos-como-palomas.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/09\\\/sencillos-como-palomas.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/el-sentido-de-la-vida-religiosa-hoy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sentido de la vida religiosa hoy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sentido de la vida religiosa hoy - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/","og_locale":"es_ES","og_type":"article","og_title":"El sentido de la vida religiosa hoy - Somos Vicencianos","og_description":"1. Buscando una historia Se me ha pedido que les hable de \u00abLa vida religiosa, \u00bfqu\u00e9 sentido tiene hoy?\u00bb. La cuesti\u00f3n se plantea con urgencia a los religiosos hoy, porque muchos de noso\u00adtros nos preguntamos ... Read More","og_url":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2017-12-19T07:34:28+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"38 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"El sentido de la vida religiosa hoy","datePublished":"2017-12-19T07:34:28+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/"},"wordCount":7518,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630","keywords":["Argel"],"articleSection":["Formaci\u00f3n Cristiana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/","url":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/","name":"El sentido de la vida religiosa hoy - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630","datePublished":"2017-12-19T07:34:28+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/el-sentido-de-la-vida-religiosa-hoy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"El sentido de la vida religiosa hoy"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-mKF","jetpack-related-posts":[{"id":118077,"url":"http:\/\/vincentians.com\/es\/anotaciones-al-decreto-conciliar-perfectae-caritatis-ii\/","url_meta":{"origin":87461,"position":0},"title":"Anotaciones al decreto conciliar \u00abPerfectae Caritatis\u00bb (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/09\/2021","format":false,"excerpt":"VII.\u2014Transformaci\u00f3n de la vida actual y exigencias de la vida religiosa Los institutos religiosos apost\u00f3licos viven una hora importante. Las transformaciones socioculturales del mundo de hoy crean una exigencia de adaptaci\u00f3n, lo cual supone para la Iglesia un discernimiento : \"Se afirman unos aciertos apost\u00f3licos, mientras que la mediocridad o\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"http:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":109321,"url":"http:\/\/vincentians.com\/es\/la-congregacion-de-la-mision-secular-o-religiosa\/","url_meta":{"origin":87461,"position":1},"title":"La Congregaci\u00f3n de la Misi\u00f3n \u00bfSecular o Religiosa?","author":"Francisco Javier Fern\u00e1ndez Chento","date":"02\/06\/2021","format":false,"excerpt":"Nuestra Compa\u00f1\u00eda \u00bfes secular o regular? Dicho de otro modo: nosotros \u00bfsomos seculares o religiosos? Pensar\u00e1n algunos que aqu\u00ed se trata s\u00f3lo de una pol\u00e9mica de palabras. Falso. La respuesta que demos a la cuesti\u00f3n condicionar\u00e1 m\u00e1s de una de las opciones que adoptemos en vistas al futuro de la\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":124417,"url":"http:\/\/vincentians.com\/es\/de-la-religion-de-san-pedro-ii\/","url_meta":{"origin":87461,"position":2},"title":"De la religi\u00f3n de san Pedro (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/04\/2023","format":false,"excerpt":"SECULARIDAD DE LA CONGREGACI\u00d3N DE LA MISI\u00d3N Ser\u00e1 del cuerpo del clero secular (X, 437) 14.- Son muchas las veces que san Vicente dijo que los misioneros no eran religiosos, sino del clero secular. El Breve \"Ex Commissa Nobis\" afirma que, no obstante los votos simples de pobreza, castidad, obediencia\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/Almeria-2.jpg?fit=600%2C400&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/Almeria-2.jpg?fit=600%2C400&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/Almeria-2.jpg?fit=600%2C400&resize=525%2C300 1.5x"},"classes":[]},{"id":122048,"url":"http:\/\/vincentians.com\/es\/el-signo-de-estos-tiempos-tesis-8a-liberacion-de-los-pobres-y-arquitectura-de-la-iglesia\/","url_meta":{"origin":87461,"position":3},"title":"El signo de estos tiempos. Tesis 8\u00aa: Liberaci\u00f3n de los pobres y \u00abarquitectura\u00bb de la Iglesia","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/07\/2015","format":false,"excerpt":"Tesis 8\u00aa: Liberaci\u00f3n de los pobres y \"arquitectura\" de la Iglesia La verdadera opci\u00f3n por los pobres como manifestaci\u00f3n preferencial de la misi\u00f3n universal de la Iglesia afectar\u00e1 profundamente a la visi\u00f3n tradicional de sus estructuras y de sus instituciones fundamentales: teolog\u00eda, ministerio, vida religiosa, vida laical. La expresi\u00f3n \"arquitectura\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":134948,"url":"http:\/\/vincentians.com\/es\/los-votos-no-religiosos-y-el-habito-como-las-campesinas\/","url_meta":{"origin":87461,"position":4},"title":"Los votos \u00abno religiosos\u00bb y el h\u00e1bito \u00abcomo las campesinas\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/01\/2015","format":false,"excerpt":"Al tratar del car\u00e1cter secular de las Hijas de la Caridad (c. III), he afirmado que los Fundadores, en orden a salvaguardar la identidad, evitaron cuidadosamente cuanto era propio de la vida religiosa: votos, h\u00e1bito, terminolog\u00eda, usos, como rejas en el locutorio, cambio del nombre del bautismo, etc. \u00bfC\u00f3mo, entonces,\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"guardame","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/guardame-300x246.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":124579,"url":"http:\/\/vincentians.com\/es\/los-miembros-de-la-congregacion-de-la-mision-emiten-votos-i\/","url_meta":{"origin":87461,"position":5},"title":"Los miembros de la Congregaci\u00f3n de la Misi\u00f3n emiten votos (I)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/07\/2023","format":false,"excerpt":"DE LOS VOTOS SIMPLES A LOS VOTOS \"NO RELIGIOSOS\" 1.- Votos privados - simples Confirmamos y aprobamos por la presente dicha Congregaci\u00f3n de la Misi\u00f3n,... con la emisi\u00f3n de los votos simples... no intervendr\u00e1 nadie que los acepte ni en nombre de de la Congregaci\u00f3n, ni en el Nuestro o\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/11\/400es-01-copy.png?fit=1200%2C936&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/11\/400es-01-copy.png?fit=1200%2C936&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/11\/400es-01-copy.png?fit=1200%2C936&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/11\/400es-01-copy.png?fit=1200%2C936&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/11\/400es-01-copy.png?fit=1200%2C936&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/87461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=87461"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/87461\/revisions"}],"predecessor-version":[{"id":401391,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/87461\/revisions\/401391"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/400011"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=87461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=87461"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=87461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}