{"id":83188,"date":"2017-10-04T08:09:46","date_gmt":"2017-10-04T06:09:46","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=83188"},"modified":"2017-10-01T15:55:55","modified_gmt":"2017-10-01T13:55:55","slug":"p-felipe-sobies-cuarto-visitador","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/","title":{"rendered":"P. Felipe Sobies, Cuarto Visitador"},"content":{"rendered":"<p>Naci\u00f3 en Cubells (L\u00e9rida) el 26 de enero de 1747. Siendo estudiante y con patrimo\u00adnio, entr\u00f3 en la Congregaci\u00f3n el 24 de febre\u00adro de 1765, haciendo los votos dos a\u00f1os des\u00adpu\u00e9s el d\u00eda 25 del citado mes. Aprovech\u00f3<sup>,<\/sup> \u00abmucho en virtud en el Seminario y en las letras en los estudios\u00bb, se lee en la nota ne\u00adcrol\u00f3gica que le dedica el libro de difuntos de la casa de Barcelona. Le emple\u00f3 luego la obediencia a en las funciones del Instituto, se\u00ad\u00f1aladamente en las misiones y ejercicios. \u00abA los 30 a\u00f1os de edad o poco m\u00e1s\u00a0 pro\u00adsigue la citada nota, le juzgaron ya digno de gobernar, y as\u00ed le hicieron Superior de la casa de Guisona, cuyo cargo desempe\u00f1\u00f3 por el espacio de ocho a\u00f1os con gran esp\u00edri\u00adtu y prudencia, como tambi\u00e9n el de ense\u00ad\u00f1ar a que despu\u00e9s fue llamado a Barcelona; por lo que a los cuarenta y nueve a\u00f1os de edad fue ya nombrado Superior de la casa de Barcelona y Visitador de toda la Provin\u00adcia de Espa\u00f1a, cuyos cargos obtuvo a satis\u00adfacci\u00f3n\u00bb de todos.<\/p>\n<p>Fue, pues, nombrado Visitador en los pri\u00admeros meses de 1796. Del 9 de marzo al 2 de abril de dicho a\u00f1o hizo la visita can\u00f3nica de la casa de Barcelona, manifestando en las or\u00addenanzas que dej\u00f3 el \u00abgrande e indecible consuelo con que queda ba\u00f1ado nuestro coraz\u00f3n por los buenos y devotos sentimientos<sup>,<\/sup> y ardientes deseos que con tanta confianza nos hab\u00e9is comunicado, no s\u00f3lo de la propia perfecci\u00f3n, sino tambi\u00e9n de mantener, y a\u00fan<sup>,<\/sup> de aumentar la observancia regular, y siendo de nuestra obligaci\u00f3n el fomentarlos, a fin de que tengan el debido efecto, hemos Juzga\u00addo conveniente el dejaros las siguientes or\u00addenanzas, que fielmente observadas servir\u00e1n para tener lejos la relajaci\u00f3n, y de medios para revestiros siempre m\u00e1s y m\u00e1s del esp\u00ed\u00adritu de nuestra santa vocaci\u00f3n.<\/p>\n<p>\u00abDeb\u00e9is, se\u00f1ores, en el ocio santo de la oraci\u00f3n aumentar en vuestros corazones el amor a nuestras santas reglas, a cuyo fin de\u00adb\u00e9is mirarlas como medios los m\u00e1s propios que la divina Providencia os ofrece por me\u00addio de nuestro santo Instituidor, como por otro Mois\u00e9s, para adquirir la perfecci\u00f3n pro\u00adpia a nuestro estado. Ellas, no solamente regulan nuestro exterior con la mortificaci\u00f3n de los sentidos y crucificando la carne con sus desarreglados deseos; sino que principalmente pulen y perfeccionan nuestro interior, conduci\u00e9ndonos al m\u00e1s perfecto desapego de todo lo terreno y, sobre todo, de nosotros mismos con la mortificaci\u00f3n de las pasiones y entera abnegaci\u00f3n de nuestro propio juicio y voluntad que forman el car\u00e1cter de un ver\u00addadero disc\u00edpulo de nuestro Redentor.<\/p>\n<p>\u00ab\u00a1Oh, qu\u00e9 espect\u00e1culo tan agradable a los ojos de Dios, admirable a los \u00e1ngeles y a todo el mundo es un Misionero que regula todos sus pensamientos, palabras, obras y movi\u00admientos exteriores e interiores conforme al modelo de nuestras Reglas! En cualquier par\u00adte que se presente semejante Misionero de\u00adrramar\u00e1 el buen olor de Jesucristo y con se\u00adguridad podr\u00e1 decir con el Ap\u00f3stol: imitad\u00adme a m\u00ed, as\u00ed como yo imito a Jesucristo\u00bb.<\/p>\n<p>Tiene, adem\u00e1s, la casa de Barcelona moti\u00advos especiales para ser muy puntual en la ob\u00adservancia de las Reglas. \u00abElla, se\u00f1ores y her\u00admanos car\u00edsimos, es como la madre de las dem\u00e1s. En ella es donde se reciben y cr\u00edan los sujetos, y es como la fuente que se de\u00adrrama para fertilizar las dem\u00e1s casas del rei\u00adno que est\u00e1n fundadas y en adelante se fun\u00addar\u00e1n: por esto os deb\u00e9is considerar m\u00e1s obli\u00adgados a llenaros con la m\u00e1s estrecha obser\u00advancia del esp\u00edritu propio de la Congregaci\u00f3n, y a tener lejos la m\u00e1s m\u00ednima relajaci\u00f3n que introducida en esta casa, con facilidad tras\u00adcender\u00eda y se har\u00eda com\u00fan a las dem\u00e1s&#8230; Por tanto, pondere cada uno con seria reflexi\u00f3n el grande mal que har\u00eda autorizando como pr\u00e1cticas de la Congregaci\u00f3n, de esta u otras casas, algunas cosas que no est\u00e1n en uso, o han sido siempre reprobadas de los Visitado\u00adres y Superiores, o sosteniendo e introdu\u00adciendo abusos, interpretando a su capricho las reglas contra su virtuoso sentido, y qui\u00adtando la autoridad de las Asambleas Genera\u00adles, a las \u00f3rdenes de las visitas y a las dis\u00adposiciones de los Superiores: cosas todas que de nuestros buenos y venerables ancianos eran respetadas como sacrosantas. An\u00edmense, pues, se\u00f1ores, a mantener a\u00fan a aumentar la observancia hasta en las cosas m\u00e1s peque\u00ad\u00f1as en que tanto se ha distinguido esta casa, y no quieran incurrir en la vergonzosa igno\u00adminia de que la posteridad fije en nuestros d\u00edas la \u00e9poca de su relajaci\u00f3n nuestra Provincia\u00bb.<\/p>\n<p>Aunque todas las reglas merecen nuestro aprecio, dice, debe ocupar el primer lugar en nuestro coraz\u00f3n, las que se refieren a la ca\u00adridad fraterna; porque ella es \u00abla dicha y fe\u00adlicidad de las comunidades, el car\u00e1cter dis\u00adtintivo de los hijos de Dios y la divisa de sus disc\u00edpulos\u00bb. Despu\u00e9s de animar a la pr\u00e1ctica de esta virtud con las razones m\u00e1s eficaces, a\u00f1ade: \u00abPor las entra\u00f1as de Jesucristo, por el bien de la Congregaci\u00f3n y de cada uno en particular os rogamos encarecidamente de te\u00adner la mayor vigilancia para que no se in\u00adtroduzca entre vosotros el lobo rapaz de la murmuraci\u00f3n que todo lo arruina y devora. Oponeos a cualquiera que, aunque por inad\u00advertencia, empezara a tiznar y censurar las acciones de los dem\u00e1s contra lo que pres\u00adcriben nuestras Reglas\u00bb. Recomienda sobre todo la caridad con los enfermos de casa, conforme la ha practicado siempre la Com\u00adpa\u00f1\u00eda. \u00abPor esto, deseando conservar este es\u00adp\u00edritu de caridad en la Congregaci\u00f3n, renova\u00admos en primer lugar todas las precedentes ordenanzas, hechas para su consuelo y alivio. Segundo: encargamos al Prefecto de los en\u00adfermos y Enfermero de cumplir puntualmen\u00adte las disposiciones que ordenare el m\u00e9dico. Y, por \u00faltimo, exhortamos a todos y a cada uno en particular de visitar con frecuencia nuestros enfermos, consol\u00e1ndolos en sus pe\u00adnas, y, sobre todo, os rogamos que cuando sea necesario velar o practicar cualesquiera otro servicio penoso por exigirlo las circunstan\u00adcias de la enfermedad, nadie se excuse. Por m\u00e1s que los Superiores deseen y procuren la buena y caritativa asistencia de los enfer\u00admos, jam\u00e1s se lograr\u00e1 si los particulares, sin\u00adgularmente los destinados a su servicio, repugnan y no cooperan con el ejercicio de la caridad a su alivio\u00bb.<\/p>\n<p>Recomienda luego la fidelidad a la oraci\u00f3n de la ma\u00f1ana. \u00abA ella deb\u00e9is aplicaros todos los d\u00edas, aun en los de reposo, por el espa\u00adcio de una hora. Aprovechen, se\u00f1ores, este precioso tiempo que la Congregaci\u00f3n les con\u00adcede para tratar con Dios. Cuiden de que no entre la tibieza en un acto de piedad que es la columna de la vida espiritual. Mas los buenos sentimientos que el Se\u00f1or les pueda comunicar en ella, f\u00e1cilmente los perder\u00e1n, si no se pone alg\u00fan l\u00edmite en el trato de las criaturas, singularmente en estos tiempos tan peligrosos en que la libertad (mejor dir\u00e9, li\u00adbertinaje) reina tan impunemente en el mun\u00addo, y en que el infierno por estos malignos fil\u00f3sofos, sus emisarios, procura esparcir las m\u00e1ximas m\u00e1s perversas y hacer que penetren hasta el lugar m\u00e1s santo para profanarlo. As\u00ed me veo precisado, ahora m\u00e1s que nunca, a recomendarles con toda eficacia el retiro del inundo y a huir el trato con seglares, fue\u00adra de los casos que permiten las Reglas, y entonces sea con aquella circunspecci\u00f3n y gravedad que requiere nuestro car\u00e1cter, de suerte que nuestra modestia sea una t\u00e1cita, pero eficaz reprensi\u00f3n de su disipaci\u00f3n y li\u00adviandad. Esta separaci\u00f3n del mundo de poco servir\u00eda sino se guardara en casa el silencio tan conducente para santificar este lugar de retiro. Esta regla, se\u00f1ores, es de las m\u00e1s ne\u00adcesarias, no s\u00f3lo para evitar muchas faltas, la p\u00e9rdida del tiempo y tener lejos la relaja\u00adci\u00f3n, sino tambi\u00e9n para la edificaci\u00f3n y pro\u00advecho de tantos ejercitantes que concurren a esta casa para valerse de la soledad y si\u00adlencio, a fin de tratar las cosas de su conciencia con Dios\u00bb.<\/p>\n<p>Despu\u00e9s de recordar los lugares y ocasiones en que particularmente debe guardarse el silencio, concluye diciendo: \u00abNo puedo omitir decir dos palabras a la juventud que ocupa gran parte de nuestra atenci\u00f3n, solici\u00adtud y desvelos. A nuestros car\u00edsimos estu\u00addiantes encargamos hermanar estas tres co\u00adsas: virtud, ciencia y salud para que a su tiempo puedan ser aplicados sin peligro pro\u00adpio y con provecho de los dem\u00e1s a los minis\u00adterios propios de la vocaci\u00f3n. Hagan caso de cosas peque\u00f1as; no juzguen que esto sea pe\u00adculiar de los seminaristas; entiendan que un verdadero Misionero toda su vida se mira y contempla como seminarista, sin permitirse libertades contrarias a la Regla\u00bb.<\/p>\n<p>Tales son algunos de los preciosos docu\u00admentos y saludables advertencias, contenidos en las ordenanzas que dej\u00f3 el P. Sob\u00edes a la casa de Barcelona. Como era al mismo tiem\u00adpo superior de ella, no volvi\u00f3 a pasar all\u00ed vi\u00adsita. Por el contrari\u00f3, en la de Palma de Ma\u00adllorca la hizo cuatro veces, a saber: en mayo de 1796, diciembre de 1798, mayo de 1802, y julio de 1806. \u00abNo deb\u00e9is, dice en las or\u00addenanzas de la primera, contentaros con una observancia exterior que puede tal vez satis\u00adfacer a los hombres y lisonjearos a vosotros mismos, pero no a Dios que escudri\u00f1a los co\u00adrazones&#8230; Por esto deb\u00e9is revestiros de los sentimientos que inspiran las m\u00e1ximas del sagrado Evangelio para regular con ellas to\u00addas<sup>&#8211;<\/sup>vuestras operaciones, pero singularmen\u00adte con las que nos recomienda nuestro Santo Fundador en el cap\u00edtulo segundo de las Re\u00adglas comunes, que conducen a un alt\u00edsimo grado de perfecci\u00f3n y forman un hombre verdaderamente espiritual y apost\u00f3lico. Mas si quer\u00e9is que mi gozo sea cumplido, procu\u00adrad que entre vosotros reine sobre todo la caridad fraterna, por ser ella el documento que m\u00e1s encarecidamente recomend\u00f3 el Se\u00ad\u00f1or en su Evangelio, y quien le observa guar\u00adda toda la ley, seg\u00fan San Pablo, y es el camino breve para adquirir la perfecci\u00f3n. S\u00ed, mis car\u00edsimos hermanos, esta virtud es el car\u00e1cter<sup>&#8211;<\/sup> y distintivo de los hijos de Dios, la divisa de los disc\u00edpulos de nuestro Redentor y la que forma la dicha y la felicidad de las comunida\u00addes. Por esto amaos unos a otros, como ver\u00addaderos hermanos e hijos de una misma ma\u00addre, la Congregaci\u00f3n, en cuyo seno os uni\u00f3 el amor de Jesucristo. Mas este amor, para ser verdadero, no debe ce\u00f1irse a solas palabras, sino que debe pasar a las obras, practicando entre vosotros los actos de una verdadera ca\u00adridad. As\u00ed cada uno procure condescender con los dem\u00e1s en lo que pueda sin contrave\u00adnir a la Regla y a la ley de Dios, haciendo con los dem\u00e1s lo que justamente quisiera que los otros practicaran consigo. Nada hag\u00e1is que pueda contristar a vuestro hermano, sino soportad sus defectos con paciencia sin lamentos ni quejas, no profiriendo palabra alguna que pueda lastimar su coraz\u00f3n. Ves\u00adt\u00edos de un coraz\u00f3n compasivo, usando la ex\u00adpresi\u00f3n del Esp\u00edritu Santo, de entra\u00f1as de misericordia que no admiten un celo amargo contra las faltas del pr\u00f3jimo, sino dulce, pac\u00edfico y caritativo que inspira la sabidur\u00eda del cielo, seg\u00fan nos ense\u00f1a Santiago en su can\u00f3nica\u00bb.<\/p>\n<p>Les exhorta luego a huir del vicio de la cr\u00edtica y murmuraci\u00f3n y a que sea muy tier\u00adna su caridad con los enfermos. Siguiendo \u00abel esp\u00edritu de San Vicente y de nuestra bue\u00adna madre la Congregaci\u00f3n, ellos \u2014dice el P. Sob\u00edes\u2014 ser\u00e1n siempre los que ocupen la mayor parte de mis desvelos, para que sean tratados con toda caridad, socorridos y ali\u00adviados en sus penas seg\u00fan exigiere su dolen\u00adcia. As\u00ed encargamos al Superior y Prefecto de sanidad de hacer cumplir puntualmente lo que ordenare el m\u00e9dico. Procurar\u00e1n asimis\u00admo todos consolarles en sus penas, visit\u00e1ndoles unos en unas horas y otros en otras, singularmente en el tiempo de la convalecen\u00adcia, lo que es m\u00e1s necesario en casas pe\u00adque\u00f1as\u00bb.<\/p>\n<p>Concluye recomend\u00e1ndoles el apartamien\u00adto del mundo, el retiro y el silencio, virtudes que desde los principios dieron tanto cr\u00e9dito a aquella casa.<\/p>\n<p>De Barbastro, aunque consta por las apro\u00adbaciones de los libros de cuentas que pas\u00f3 visita seis veces, o sea desde 1796 hasta 1806 cada dos a\u00f1os durante el verano, se han perdido por desgracia las ordenanzas que dej\u00f3. Seguramente que otras tantas veces por lo menos pas\u00f3 visita en las casas de Reus y Palma. S\u00f3lo de esta \u00faltima se conservan en nuestro archivo los avisos que vamos a trans\u00adcribir de las visitas de 1796 y 1798. <strong>\u00abAvisos <\/strong><strong>de la visita de 1796 para el gobierno del Su<\/strong><strong>perior\u00bb.<\/strong><\/p>\n<ul>\n<li>Que\u00a0 con todo cuidado se procure dar buen pan.<\/li>\n<li>Nadie salga de casa de noche y despu\u00e9s del examen, sino por indispensable necesidad, como es para confesar enfermos<\/li>\n<li>El reloj de plata que sirva \u00fanicamente para la Comunidad y no para alg\u00fan particu\u00adlar; y que cuando se vuelve de Misi\u00f3n, si se han servido de \u00e9l, que se lleve a la procura.<\/li>\n<li>Comp\u00f3ngase el horno y que se desv\u00ede el agua, de la bodega.<\/li>\n<li>Cuando la casa pueda, que se hagan roquetes, y las misas podr\u00e1n entonces servirse con ellos, por pedirlo as\u00ed la virtud de la reli\u00adgi\u00f3n.<\/li>\n<li>A los Hermanos que se vistan en esta casa, que haya uno que cuide de instruirles en todo, y vayan a pedirle penitencia.<\/li>\n<li>Fuera del d\u00eda de paseo, si alguno por al\u00adg\u00fan negocio sale fuera de casa, que procure asistir al rezo, ex\u00e1menes y dem\u00e1s actos de la Comunidad.<\/li>\n<li>Que se instruyan bien los Hermanos en servir la santa misa, que algunos no lo saben.<\/li>\n<li>Que se torne todos los a\u00f1os inventario de las cosas de la casa. Aunque est\u00e9 fuera el Su\u00adperior, t\u00e9nganse las consultas [consejo] y p\u00eddanse las necesidades todas las semanas. Felipe Sob\u00edes\u00bb.<\/li>\n<\/ul>\n<p>De la visita que pas\u00f3, del 13 al 24 de sep\u00adtiembre de 1798, son estos avisos: \u00abA fin de que se mantenga la vida com\u00fan en su vigor, mandamos que sean sin dilaci\u00f3n subvenidas las necesidades de los individuos, cuando las piden; y que por lo que Mira al sustento, se suministre a todos, as\u00ed en la cantidad como en la calidad, conforme al estilo de la Con\u00adgregaci\u00f3n, singularmente en orden al pan, que con toda especialidad encargo sea bueno.<\/p>\n<p>En segundo lugar, ordenamos que en la iglesia no se oigan confesiones, singular mente de mujeres, en tiempo de la comida: todos deben asistir a la primera, mesa, cele\u00adbrando de antemano la misa&#8230;<\/p>\n<p>Por \u00faltimo, encargamos encarecidamente a los Hermanos la limpieza de la casa en todo lo que pertenece a sus oficinas y empleos, a fin de que se eviten las quejas, y los externos no se retraigan de venir a hacer los ejerci\u00adcios espirituales, de lo que el Se\u00f1or les pedi\u00adr\u00e1 estrech\u00edsima cuenta.\u00bb<\/p>\n<p>Aunque no llevan fecha, son indudable\u00admente de una de estas primeras visitas los si\u00adguientes preciosos <strong>Avisos para Misi\u00f3n: <\/strong>\u00abEn particular prevengo que en las recreaciones ordinarias, no se admitan los sedares; pues con el frecuente trato se engendra la familia\u00adridad y menosprecio y poca estima de los Mi\u00adsioneros. Aunque en el d\u00eda de recreaci\u00f3n se permite que vayan con nosotros, pero ningu\u00adno se ir\u00e1 muy lejos con alguno de ellos.<\/p>\n<p>Gu\u00e1rdese el orden del d\u00eda con toda pun\u00adtualidad, as\u00ed en ir a la iglesia y levantarse del confesonario, como en las horas de comida, cena y recreaci\u00f3n, y todo lo dem\u00e1s ordenado.<\/p>\n<p>En cuanto a las funciones, prevengo no se prolonguen m\u00e1s de lo que est\u00e1 ya determi\u00adnado por las Asambleas, y tan recomendado en las precedentes visitas.<\/p>\n<p>Asimismo es propio que cada funci\u00f3n se haga seg\u00fan el esp\u00edritu que ella exige; quiero decir, que el doctrinero no pase a ser plati\u00adquista, ni el platiquista predicador. Cada funci\u00f3n tiene su fin y utilidad particular. Aunque todas las funciones deben ser senci\u00adllas y <strong>ad captum populi, <\/strong>pero deben ser pru\u00addentes, no diciendo cosa que pueda sonrojar a alguno, ni ofender los castos o\u00eddos, y mu\u00adcho menos ense\u00f1ar lo que santamente se ig\u00adnora. La misma prudencia dicta que cuanto se diga sea autorizado y fundado, sin propo\u00adner ejemplos inciertos, ni mezclar cosas ri\u00add\u00edculas que exciten a risa a los oyentes, pro\u00adfanando el sagrado ministerio que ejercen. No puedo dejar de advertir que no os dej\u00e9is enga\u00f1ar y sorprender de la preocupaci\u00f3n de algunos que canonizan por simplicidad el ha\u00adcer las funciones sin orden ni prevenci\u00f3n, diciendo lo que ocurre: esto es tentar a Dios, desacreditar los ministerios y la misma Con\u00adgregaci\u00f3n. Como la administraci\u00f3n del sa\u00adcramento de la penitencia sea la m\u00e1s grave e importante funci\u00f3n de vuestro ministerio, os exhortamos teng\u00e1is presente las reglas de los graves autores, y sobre todo las que pres\u00adcribe San Carlos Borromeo para su cabal desempe\u00f1o.<\/p>\n<p>Procurad que la curiosidad, tan afeada por los buenos directores de esp\u00edritu, no se introduzca en un ministerio y ejercicio tan santo. H\u00e1ganse las preguntas necesarias, pero d\u00e9jense las impertinentes y curiosas, que pueden ser de mucho peligro y siempre impropias de aquel lugar santo.<\/p>\n<p>Vean, se\u00f1ores y hermanos car\u00edsimos, lo que ha tenido a bien el Se\u00f1or inspirarme para comunic\u00e1roslo, en testimonio del deseo y amor que tengo a vuestra perfecci\u00f3n y al bien com\u00fan de la Congregaci\u00f3n&#8230;\u00bb.<\/p>\n<p>Tales son algunas de las muestras de la sabidur\u00eda, y prudencia del P. Sob\u00edes que he\u00admos podido recoger hasta ahora. En ellas se echa de ver su ardiente celo por la gloria de Dios y por el buen nombre de la Congrega\u00adci\u00f3n, y su cuidado maternal por el bienestar temporal y espiritual de los individuos de la misma.<\/p>\n<p>Siguieron en Barcelona y en las dem\u00e1s ca\u00adsas florecientes y pr\u00f3speros los ministerios de la Congregaci\u00f3n, mayormente las Misio\u00adnes y ejercicios, hasta que sobrevino la gue\u00adrra de la Independencia, en que por necesi\u00addad se paraliz\u00f3 todo&#8217;.<\/p>\n<p>Por dos cartas al Vicario general de la Congregaci\u00f3n, P. Brunet, del P. Vicherat. pro-Vicario Apost\u00f3lico de Argel, de donde sali\u00f3 por intrigas de Inglaterra, en los pri\u00admeros meses de 1801, retir\u00e1ndose a nuestra casa de Barcelona, sabemos algo del estado de \u00e9sta, del car\u00e1cter y gobierno del P. So\u00adb\u00edes y de lo que le hicieron sufrir algunos es\u00adp\u00edritus inquietos y revoltosos, que nunca fal\u00adlan, a\u00fan en las congregaciones m\u00e1s regula\u00adres. En la primera, de 14 de julio de 1801, le dice entre otras cosas: \u00abA pesar de lo que uno o dos individuos de la casa de Reus le digan del P. Sob\u00edes, siga usted esta conducta.<\/p>\n<p>Abst\u00e9ngase en sus cartas, de recordarle las quejas o acusaciones contra \u00e9l, ni mucho me\u00adnos se tome la molestia de transcribirlas, por\u00adque sospechar\u00eda que usted no tiene ya plena confianza en \u00e9l, y vi\u00e9ndose en la imposibili\u00addad de gobernar como se debe, creer\u00edase en el caso de enviar su renuncia; pero si esto sucede, no se la acepte: ser\u00eda un desastre para la provincia. Por mucho que inste, de\u00adjadle en su puesto. Cumple bien su oficio, y aunque \u00e9ste es como para irse a galeras; con Iodo, \u00e9l a\u00fan puede desempe\u00f1arlo mucho Tiempo.<\/p>\n<p>Cierre usted los o\u00eddos a las delaciones de individuos m\u00e1s o menos extraviados, porque no le dir\u00e1n sino calumnias.<\/p>\n<p>Vi la carta que usted escribi\u00f3 al P. Sob\u00edes. Estoy persuadido que todas esas diatribas es\u00adcandalosas contra \u00e9l no son m\u00e1s que una ca\u00adlumnia atroz. En los cuatro meses que llevo aqu\u00ed, no he observado en el P. Sob\u00edes el me\u00adnor motivo para tan duras imputaciones. Por el contrario, todo en \u00e9l respira dulzura, fir\u00admeza y gracia sin igual en el trato: me com\u00adprometo a enviaros una certificaci\u00f3n firmada por todos los miembros de la Comunidad, si usted lo desea. Porque, empezando por los Superiores y asistentes de las otras casas, no hay un Misionero que no respete, ame y venere al Sr. Visitador, como muy hombre de bien y modelo de todos. Ellos le comunica\u00adr\u00edan noticias muy satisfactorias sobre la con\u00adducta y gobierno del P. Sob\u00edes&#8230; Moment\u00e1\u00adneamente os han enga\u00f1ado con un papelucho lleno de artificiosas calumnias; pero pronto pod\u00e9is descubrir la mala entra\u00f1a, el esp\u00edritu de espionaje y la pasi\u00f3n manifiesta de los de\u00adlatores. Dios ha permitido que usted no viera claro en el asunto para dar ocasi\u00f3n al P. So\u00adb\u00edes de humillarse y ocultar bajo el velo de esta virtud el bien que hace. De todo saca el Se\u00f1or su gloria para provecho de sus elegi\u00addos. Confieso que si usted persiste en su pre\u00adocupaci\u00f3n no me quedar\u00e1 otro recurso que dolerme y lamentarme de esta desgracia y de que se\u00e1is, sin pensarlo, instrumento ciego de la insubordinaci\u00f3n de los revoltosos, conoci\u00addos ya como tales.<\/p>\n<p>Toda la ciudad, tanto los religiosos como los seglares, hablan muy bien de este semi\u00adnario, as\u00ed como tambi\u00e9n del Superior y de la Comunidad, que es mirada como la m\u00e1s re\u00adgular y observante de la poblaci\u00f3n. El Vica\u00adrio General de Montaub\u00e1n, que tiene ochen\u00adta y cuatro a\u00f1os de edad, me dec\u00eda: \u00abParece casa de trapenses: los seglares besan sus mu\u00adros y bendicen a sus moradores\u00bb. Diariamen\u00adte veo multitud de eclesi\u00e1sticos, los m\u00e1s res\u00adpetables, que vienen a confesarse aqu\u00ed; de suerte que es una verdadera piscina de Silo\u00e9 esta morada. Gu\u00e1rdese usted de causar seme\u00adjante trastorno a esta Comunidad y a toda la provincia. Tampoco hay raz\u00f3n para la visita extraordinaria. Rogad a Dios que conserve la casa en el estado floreciente de prosperidad en que se halla: si usted estuviera aqu\u00ed dos o tres d\u00edas, derramar\u00eda l\u00e1grimas de contento. Deja usted entrever que hay peligro de sepa\u00adraci\u00f3n; no lo tema de hombres tan piadosos como los que forman esta provincia; s\u00f3lo al\u00adgunos audaces quieren introducir en ella la turbaci\u00f3n: no conoce usted la fogosidad del car\u00e1cter espa\u00f1ol cuando el temor de Dios no le retiene en los deberes de la caridad y obe\u00addiencia. H\u00e1blase solamente de tal quim\u00e9rica separaci\u00f3n a fin de entorpecer vuestro go\u00adbierno y mantenerse en la insubordinaci\u00f3n. Sentir\u00eda en el alma que hicierais caso de ta\u00adles acusaciones, a todas luces, falsas; y cu\u00adyas consecuencias llenar\u00edan de amargura vuestro coraz\u00f3n. Ya ten\u00e9is bastantes penas, no procur\u00e9is gratuitamente otras nuevas; porque el P. Sob\u00edes es digno de vuestros m\u00e1s calurosos elogios y de la veneraci\u00f3n de todos los hombres de bien. Uno de los calumniado\u00adres, por parecer un\u00e1nime del consejo y de todos los dem\u00e1s, despu\u00e9s -de haberle sopor\u00adtado seis meses, fue expulsado, y a\u00fan esta determinaci\u00f3n s\u00f3lo se tom\u00f3 cuando ya no ha\u00adb\u00eda esperanzas de que se corrigiera, y ade\u00adm\u00e1s hab\u00eda manifiesto peligro de que con su mal ejemplo echara a perder a los otros y arruinara la piedad de que esta casa es maes\u00adtra. El que escribi\u00f3 a usted tambi\u00e9n le ha dado a entender que no hab\u00eda motivo para la expulsi\u00f3n de tres seminaristas. En una pala\u00adbra, supone que el P. Sob\u00edes no perdona nun\u00adca, ni se vuelve atr\u00e1s, y de ah\u00ed toma ocasi\u00f3n para vengarse de la injuria que pretende ha\u00adber recibido con su expulsi\u00f3n&#8230;\u00bb<\/p>\n<p>Tres d\u00edas despu\u00e9s escrib\u00eda el mismo P. Vi\u00adcherat, al P. Brunet: \u00abEntregu\u00e9 al P. Sob\u00edes la carta de usted; me hizo sentar, y durante tres horas, con la carta en la mano me ex\u00adplic\u00f3, como un novicio a su director, l\u00ednea por l\u00ednea, de la manera m\u00e1s clara y satisfac\u00adtoria, cuanto hab\u00eda pasado. No existe ni si\u00adquiera sombra de sospecha, y se necesita la maldad diab\u00f3lica del calumniador para con\u00advertir en cr\u00edmenes los hechos m\u00e1s inocentes. El Director del Seminario, antiguo Visi\u00adtador, aunque de edad de 76 a\u00f1os, es m\u00e1s vi\u00adgoroso que yo, preside todos los ejercicios. y s\u00f3lo el esp\u00edritu de calumnia puede deducir de su avanzada edad que sea inepto para la direcci\u00f3n del Seminario. Los seminaristas son recogidos, amables, edificantes, y todos es\u00adt\u00e1n animados del esp\u00edritu de piedad. Hay ocho postulantes, dos de ellos sacerdotes, a quie\u00adnes admitir\u00e1, despu\u00e9s de probada su voca\u00adci\u00f3n, el P. Sob\u00edes.<\/p>\n<p>El gobierno del P. Sob\u00edes nada tiene de absoluto, duro o altanero; antes, al contra\u00adrio, es un hombre de bien y el m\u00e1s humilde de la provincia, habiendo recibido delicada y excelente educaci\u00f3n. Sus avisos en el cap\u00edtu\u00adlo y dem\u00e1s ocasiones van mezclados de bon\u00addad, dulzura y firmeza, tan necesaria para hacer el bien. Todos los amantes de la regu\u00adlaridad, aman su gobierno; si los dem\u00e1s no lo aman, nada tiene de extra\u00f1o. El calumnia\u00addor quiere haceros ver que la falta de secre\u00adtario que entienda el espa\u00f1ol es la causa de que otros no escriban contra el P. Sob\u00edes. Mas, \u00bfno pod\u00edan hacerlo en lat\u00edn? Cierta\u00admente, y si no escriben, es porque nada tie\u00adnen que deciros. Busca c\u00f3mo disculparse de ser el \u00fanico que calumnia. Los dem\u00e1s son bastante ecu\u00e1nimes y piadosos para dejarse arrastrar por el delator. Ha escrito aqu\u00ed para inducir y enzarzar a otros en la rebeli\u00f3n, y el P. Sob\u00edes tiene las pruebas en su poder. <strong>So\u00ad<\/strong><strong>Ilicitat corda virorum Israel. <\/strong>Es tan falso como Absal\u00f3n.<\/p>\n<p>Respecto de lo que dice de la ignorancia, le aseguro que si lo supieran en las casas, todos se indignar\u00edan. \u00abM\u00e1s a\u00fan, dado que fue\u00adra tal como se dice, el P. Sob\u00edes, en los cinco a\u00f1os que lleva de Visitador, ha demostrado lo ,contrario. Su moral es sana, prueba de que los estudios fueron suficientes; porque no se requiere ser doctor por la Sorbona para confesar o predicar bien: ambas cosas se hacen en todas estas casas con edificaci\u00f3n y la mo\u00adral de los misioneros es la m\u00e1s sana de Es\u00adpa\u00f1a. Se ense\u00f1a por Antoine y los profesores son competentes y estudiosos\u00bb.<\/p>\n<p>Por la circular de 1 de enero de 1789 del P. General consta, que ya estaba acep\u00adtada y admitida la fundaci\u00f3n de una casa de nuestra Congregaci\u00f3n en C\u00e1diz. \u00abMe olvida\u00adba comunicaros \u2014dice el P. Cayla\u2014 que \u00e9l establecimiento de C\u00e1diz ha sido aceptado y nuestros hermanos no tardar\u00e1n mucho en po\u00adsesionarse de \u00e9l. Hasta<sup>&#8211;<\/sup> ahora nuestro Insti\u00adtuto era poco conocido en aquella parte de Espa\u00f1a que nos acerca a la capital. Hay fun\u00addadas esperanzas de que la Congregaci\u00f3n se extienda por el reino, si la Providencia mul\u00adtiplica los individuos y los conserva en el es\u00adp\u00edritu de&#8217; regularidad que entre ellos reina actualmente\u00bb. Ignoramos qu\u00e9 dificulta<sup>\u00ad<\/sup>des sobrevinieron para que no se llevara a efecto la fundaci\u00f3n. .<\/p>\n<p>Por los a\u00f1os de 1801 y siguientes trat\u00f3se tambi\u00e9n de que fueran algunos misioneros espa\u00f1oles a Argel. La corte de Espa\u00f1a esta\u00adba dispuesta a conceder para esta misi\u00f3n 700 duros anuales, con tal que fuera nom\u00adbrado Vicario Apost\u00f3lico, el P. Salvador Ola\u00adriana, de nuestra Comunidad de Barcelona.<\/p>\n<p>El Vicario General de la Congregaci\u00f3n, Padre Brunet, vino en ello de muy buena voluntad, nombrando Superior de la misi\u00f3n de Argel al P. Clariana y dando los pasos necesarios para que en Roma le nombraran Vicario Apost\u00f3li\u00adco. Pero surgieron tales dificultades, particu\u00adlarmente por parte del c\u00f3nsul franc\u00e9s de Ar\u00adgel, que no se pudo llevar a efecto el pro\u00adyecto.<\/p>\n<p>En cambio, fueron los misioneros a Bada\u00adjoz en diciembre de 1802. A pesar de la es\u00adcasez de personal, el P. Sob\u00edes, cediendo a las reiteradas instancias del Ilmo. Sr. D. Ma\u00adteo Delgado y Moreno, envi\u00f3 all\u00e1 a los Pa\u00addres Murillo, Camprod\u00f3n y Zabalza. Se en\u00adcargaron de la formaci\u00f3n de los seminaris\u00adtas, padeciendo muchas contradicciones de dentro y fuera, sin lograr establecer definiti\u00advamente la fundaci\u00f3n. Hacia fines del verano de 1803 fue a Badajoz el P. Sob\u00edes para ver sobre el terreno el modo de solucionar las dificultades y realizar de una vez la fundaci\u00f3n; pero nada consigui\u00f3, tomando entonces la determinaci\u00f3n de llevarse consigo a los misioneros; mas no lo consinti\u00f3 el Sr. Obis\u00adpo, quien dio esperanzas de un pronto arre\u00adglo. En consecuencia el Visitador dej\u00f3 en Badajoz a los PP. Vallhonesta y Zabalza con el Hermano Coll, el primero como Rector y el segundo como Vicerrector del Seminario de San At\u00f3n, en cuyos empleos sufrieron no poco, ya por hab\u00e9rselas con muchachos in\u00addisciplinados, ya porque cualquier falta que se cometiera, reca\u00eda, como suele suceder, con raz\u00f3n o sin ella, sobre los directores. De este modo continuaron cuatro a\u00f1os con la espe\u00adranza de que se efectuara la fundaci\u00f3n; pero eran tantas las dificultades que surg\u00edan de una y otra parte, que parec\u00eda imposible po\u00adder vencerlas, por lo que en m\u00e1s de una oca\u00adsi\u00f3n quisieron dejar el Seminario.<\/p>\n<p>Por fin, el Sr. Obispo, resolvi\u00f3 levantar un departamento o casa de ordenandos para ha\u00adbitaci\u00f3n al propio tiempo de los misioneros. Concluido el edificio, dejaron \u00e9stos el Semi\u00adnario y traslad\u00e1ronse a la nueva casa el 19 de octubre de 1807. Instalados en ella, deseaba el P. Sob\u00edes que se hiciera inmediatamente la escritura de fundaci\u00f3n; pero no fue posible hasta pasados m\u00e1s de dos a\u00f1os, formaliz\u00e1ndo\u00adse finalmente el contrato de fundaci\u00f3n el 14 de febrero de 1810. A 15 de septiembre del a\u00f1o anterior hab\u00eda otorgado el P. Sob\u00edes un poder en T\u00e1rrega, a favor de los PP. Vallho\u00adnesta y Zabalza, para que firmaran la escritura en su nombre y en el de la Congregaci\u00f3n. Con el establecimiento de los misioneros en Bada\u00adjoz, franquearon \u00e9stos los linderos de Catalu\u00f1a y del Alto Arag\u00f3n y qued\u00f3 expedito el camino para extender su acci\u00f3n y darse a conocer en el resto de la pen\u00ednsula. Justo es reconocer que, adem\u00e1s del P. Sob\u00edes, se de\u00adbi\u00f3 esto en gran parte al esclarecido P. Mu\u00adrillo.<\/p>\n<p>En el verano de 1805, dispuso el P. So\u00adb\u00edes que nuestros estudiantes de teolog\u00eda mo\u00adral fueran desde entonces a cursarla en el Seminario de Barbastro. As\u00ed se hizo hasta que sobrevinieron los trastornos de la guerra de la independencia. Durante \u00e9sta el P. So\u00adb\u00edes, junto con otros misioneros, se retir\u00f3 a la casa de Mallorca, adonde no alcanzaba la ferocidad de los soldados de la revoluci\u00f3n.<\/p>\n<p>Escribi\u00f3 el P. Sob\u00edes en febrero de 1808 al P. Han\u00f3n, ofreci\u00e9ndole sus respetos, ase\u00adgur\u00e1ndole de su perfecta sumisi\u00f3n a la Vo\u00adluntad del Papa y reconoci\u00e9ndole a \u00e9l corno Vicario General de toda la Congregaci\u00f3n. Al a\u00f1o siguiente escrib\u00eda en su circular de 1\u00ba de enero el citado P. Han\u00f3n: No tenemos noti\u00adcias recientes de Espa\u00f1a y Portugal; pero creemos que nuestros hermanos se habr\u00e1n conducido con prudencia en las cr\u00edticas cir\u00adcunstancias por que atraviesan. Pronto lleva\u00adremos cerca de su Majestad imperial y real, y de sus agentes en aquellos pa\u00edses, la pode\u00adrosa recomendaci\u00f3n de su Eminencia el Car\u00addenal Fesch\u00bb. Hay fundados motivos para creer que de nada les sirvi\u00f3 tal recomenda\u00adci\u00f3n, si es que se hizo.<\/p>\n<p>A 6 de octubre de 1810 expidi\u00f3 en C\u00e1diz el Excmo. Sr. D. Pedro Gravina, Nuncio de Su Santidad en Espa\u00f1a, un decreto nombran\u00addo, seg\u00fan se le ped\u00eda por el interesado y atendidas las circunstancias, Vicario General de la Congregaci\u00f3n de la Misi\u00f3n en los rei\u00adnos de Espa\u00f1a, al P. Felipe Sob\u00edes, confiri\u00e9n\u00addole para el efecto toda la autoridad que compete al Superior General, concedi\u00e9ndole asimismo que pudiera elegir dos misioneros id\u00f3neos para asistentes. Facultaba adem\u00e1s, para despu\u00e9s de la muerte del P. Sob\u00edes, a los Superiores locales, con tal que se reuniesen la mayor parte, para nombrar nuevo Vicario, cuya aprobaci\u00f3n y confirmaci\u00f3n se deb\u00eda pe\u00addir al propio Sr. Nuncio. Nada de extra\u00f1o llene esta medida, si consideramos la imposibilidad en que se encontraba de comunicar con los Vicarios Generales de la Congrega\u00adci\u00f3n el Visitador de la Provincia de Espa\u00f1a.<\/p>\n<p>Terminaremos estas notas sobre el P. Sob\u00edes trasladando aqu\u00ed la semblanza que de \u00e9l hace el libro de difuntos de la casa de Bar\u00adcelona. \u00abFue este se\u00f1or un sujeto de raras prendas y de aquellos que ha tenido pocos la Congregaci\u00f3n, as\u00ed por su virtud como por su talento y prudencia&#8230; Su gobierno era admi\u00adrable: en \u00e9l brillaba un gran celo por la ob\u00adservancia, un esp\u00edritu grande de religi\u00f3n en los oficios eclesi\u00e1sticos, haciendo se hiciesen con la debida solemnidad y con la mayor exactitud de ceremonias, en las que siendo muy h\u00e1bil, no dejaba pasar defecto que no corrigiese; un gran cuidado en que se ejer\u00adcitasen con el debido modo las funciones del Instituto, y en una palabra, una tal pruden\u00adcia, que al paso que con la debida severidad procuraba la exactitud en las m\u00e1s m\u00ednimas observancias, vigilando \u00e9l mismo hasta lle\u00adgar a semejanza de Santo Tom\u00e1s de Villa- nueva a visitar los aposentos de los estudian\u00adtes para ver si estaban todos retirados a la hora; trataba a todos con el mayor cari\u00f1o y afabilidad, se compadec\u00eda de sus aflicciones, y teni\u00e9ndoles ganado el coraz\u00f3n, les hac\u00eda cumplir con su deber sin necesitar regular mente de medios fuertes; por esto era suma\u00admente amado de todos. Ni era menos amado de los externos, as\u00ed por sus virtudes y talen\u00adtos, como principalmente por la afabilidad con que trataba con todos, de modo que era muy consultado, y se hac\u00eda mucho caso de sus resoluciones. Habiendo el a\u00f1o 1808, por causa de la guerra de Independencia, inte\u00adrrumpido la comunicaci\u00f3n con el Vicario Ge\u00adneral de nuestra Congregaci\u00f3n, de Roma, y aun con el Sumo Pont\u00edfice que estaba preso, fue nuestro Sr. Sob\u00edes nombrado por el se\u00ad\u00f1or Nuncio de Su Santidad en Espa\u00f1a Vicario General de las casas de la Congregaci\u00f3n de esta Provincia, cuyo empleo desempe\u00f1\u00f3 con igual suceso que los dem\u00e1s, hasta que por los sustos y desgracias, y herido de perles\u00eda, se le trastorn\u00f3 la cabeza, y habiendo pasado tres a\u00f1os de este modo, como lelo o simple, pero no tanto que no pudiese recibir los santos sa\u00adcramentos, que efectivamente recibi\u00f3 con devoci\u00f3n, muri\u00f3 tranquilamente en el Se\u00ad\u00f1or.\u00bb Acaeci\u00f3 su muerte el 18 de .marzo de 1815 en la casa de Matamoros, donde se ha\u00adllaba instalada la comunidad de Barcelona, a causa de continuar su casa sirviendo de hos\u00adpital militar, a que hab\u00eda sido destinada por los franceses.<\/p>\n<p>A pesar de lo desfavorable de los tiempos, fue tambi\u00e9n beneficios\u00edsima la gesti\u00f3n del P. Sob\u00edes como Director las Hijas de la Caridad; puesto que en su tiempo se estable\u00adcieron en Madrid, en la Inclusa, fundando adem\u00e1s Carlos IV el Real Noviciado, que fue la base del desarrollo y futura grandeza de las Hijas de la Caridad en nuestra patria; pero de esto hablar\u00e1 m\u00e1s largamente mi dis\u00adtinguido compa\u00f1ero el P. Nieto en la historia de las Hermanas. Fueron encomendadas asimismo a las Hijas de la Caridad en tiempo del P. Sob\u00edes, la Inclusa de Pamplona y la Misericordia de Tortosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Naci\u00f3 en Cubells (L\u00e9rida) el 26 de enero de 1747. Siendo estudiante y con patrimo\u00adnio, entr\u00f3 en la Congregaci\u00f3n el 24 de febre\u00adro de 1765, haciendo los votos dos a\u00f1os des\u00adpu\u00e9s el d\u00eda 25 del &#8230; <a href=\"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":391249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19],"tags":[168,160],"class_list":["post-83188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biografias-de-misioneros-paules","tag-argel","tag-nimes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P. Felipe Sobies, Cuarto Visitador - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P. Felipe Sobies, Cuarto Visitador - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Naci\u00f3 en Cubells (L\u00e9rida) el 26 de enero de 1747. Siendo estudiante y con patrimo\u00adnio, entr\u00f3 en la Congregaci\u00f3n el 24 de febre\u00adro de 1765, haciendo los votos dos a\u00f1os des\u00adpu\u00e9s el d\u00eda 25 del ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-04T06:09:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"32 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"P. Felipe Sobies, Cuarto Visitador\",\"datePublished\":\"2017-10-04T06:09:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/\"},\"wordCount\":6317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"keywords\":[\"Argel\",\"Nimes\"],\"articleSection\":[\"Biograf\u00edas de Misioneros Pa\u00fales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/\",\"name\":\"P. Felipe Sobies, Cuarto Visitador - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"datePublished\":\"2017-10-04T06:09:46+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/p-felipe-sobies-cuarto-visitador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P. Felipe Sobies, Cuarto Visitador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P. Felipe Sobies, Cuarto Visitador - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/","og_locale":"es_ES","og_type":"article","og_title":"P. Felipe Sobies, Cuarto Visitador - Somos Vicencianos","og_description":"Naci\u00f3 en Cubells (L\u00e9rida) el 26 de enero de 1747. Siendo estudiante y con patrimo\u00adnio, entr\u00f3 en la Congregaci\u00f3n el 24 de febre\u00adro de 1765, haciendo los votos dos a\u00f1os des\u00adpu\u00e9s el d\u00eda 25 del ... Read More","og_url":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2017-10-04T06:09:46+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"32 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"P. Felipe Sobies, Cuarto Visitador","datePublished":"2017-10-04T06:09:46+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/"},"wordCount":6317,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","keywords":["Argel","Nimes"],"articleSection":["Biograf\u00edas de Misioneros Pa\u00fales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/","url":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/","name":"P. Felipe Sobies, Cuarto Visitador - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","datePublished":"2017-10-04T06:09:46+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/p-felipe-sobies-cuarto-visitador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"P. Felipe Sobies, Cuarto Visitador"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"http:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-lDK","jetpack-related-posts":[{"id":119687,"url":"http:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-colegial-estudiante-y-sacerdote\/","url_meta":{"origin":83188,"position":0},"title":"El Se\u00f1or Vicente relee su vida: Colegial, estudiante y sacerdote","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/01\/2022","format":false,"excerpt":"Hacia 1592, mi padre trat\u00f3 de hacerme estudiar, con la esperanza de poder un d\u00eda obtener alg\u00fan beneficio eclesi\u00e1stico, es decir rentas de alguna abad\u00eda o de una buena parroquia, y as\u00ed aliviar a la familia, como lo hab\u00eda hecho mi t\u00edo, prior de Poymartet. Me puso pues de pensi\u00f3n\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/g-3.jpg?fit=1170%2C692&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/g-3.jpg?fit=1170%2C692&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/g-3.jpg?fit=1170%2C692&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/g-3.jpg?fit=1170%2C692&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/g-3.jpg?fit=1170%2C692&resize=1050%2C600 3x"},"classes":[]},{"id":121434,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-nacio-en-francia-v-segunda-dificultad\/","url_meta":{"origin":83188,"position":1},"title":"San Vicente de Pa\u00fal naci\u00f3 en Francia. V. Segunda dificultad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"30\/04\/2015","format":false,"excerpt":"Segunda dificultad En el cap\u00edtulo titulado la vocaci\u00f3n, contin\u00faa el traduc\u00adtor: Arturo Loth afirma que el Santo naci\u00f3 en Pouy, el 24 de Abril de 1576. Afirmaci\u00f3n tan categ\u00f3rica parece que ha de tener por base el \u00fanico documento irrefragable: la partida de bautismo; pero \u00e9sta no existe en los\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":121437,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-nacio-en-francia-ix-la-prensa-periodica\/","url_meta":{"origin":83188,"position":2},"title":"San Vicente de Pa\u00fal naci\u00f3 en Francia. IX. La prensa peri\u00f3dica","author":"Francisco Javier Fern\u00e1ndez Chento","date":"04\/05\/2015","format":false,"excerpt":"La prensa peri\u00f3dica El traductor de Arturo Loth, nos ha dicho contar con el concurso de la prensa peri\u00f3dica, y nosotros hemos ofrecido examinar el apoyo que prestan al Sr Feli\u00fa, los peri\u00f3dicos El Correo Catal\u00e1n de Barcelona, La Controversia de Ma\u00addrid, y El Pilar de Zaragoza. Tenemos tres n\u00fameros\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":387071,"url":"http:\/\/vincentians.com\/es\/los-primeros-misioneros-en-espana-1704-1774\/","url_meta":{"origin":83188,"position":3},"title":"Los primeros misioneros en Espa\u00f1a (1704-1774)","author":"Mitxel Olabu\u00e9naga","date":"20\/08\/2019","format":false,"excerpt":"Introducci\u00f3n Dec\u00eda el cantautor que \u201cquien pierde sus or\u00edgenes, pierde identidad\u201d (Raimon \u201cYo vengo de un silencio\u201d). Quiz\u00e1 este sea uno de los motivos ocultos por el que nos hemos centrado en este tema dentro de Seminario de H\u00aa de la CM en Espa\u00f1a que venimos desarrollando en el Estudiantado\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision-en-espana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/04\/tres-descubrimientos-de-Vicente-de-Paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/04\/tres-descubrimientos-de-Vicente-de-Paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/04\/tres-descubrimientos-de-Vicente-de-Paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/04\/tres-descubrimientos-de-Vicente-de-Paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/04\/tres-descubrimientos-de-Vicente-de-Paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":121299,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-nacio-en-francia-ii-estudios\/","url_meta":{"origin":83188,"position":4},"title":"San Vicente de Pa\u00fal naci\u00f3 en Francia. II. Estudios","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/04\/2015","format":false,"excerpt":"II. Estudios En lo concerniente a los estudios teol\u00f3gicos de Vicente de Pa\u00fal, los detalles no ser\u00e1n abundantes, dado el cuidado del Santo por hacerse pasar por un estudiante de cuarto a\u00f1o. Sin embargo. despu\u00e9s de su muerte, se encuentran tres documentos, cuya existencia no se sospechaba, y que arrojan\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":131248,"url":"http:\/\/vincentians.com\/es\/vida-y-virtudes-del-sr-sen-just-i\/","url_meta":{"origin":83188,"position":5},"title":"Vida y virtudes del sr. Sen-Just (I)","author":"Mitxel Olabu\u00e9naga","date":"05\/09\/2014","format":false,"excerpt":"NACIMIENTO. INFANCIA.ESTUDIO Y OCUPACIONES DE FRANCISCO.ES NOMBRADO CAN\u00d3NIGO DE URGEL.SU CELO EN EL PRIORATO DE SANTA OLIVA. El Muy Lustre Sr. Francisco Sen-just y Pag\u00e9s naci\u00f3 en Barcelona; fue por su nacimiento hijo de una de las m\u00e1s Ilustres y nobles familias de la capital del Principado, como lo da\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"ESCUDOCM","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/09\/ESCUDOCM.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/83188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=83188"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/83188\/revisions"}],"predecessor-version":[{"id":401295,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/83188\/revisions\/401295"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/391249"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=83188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=83188"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=83188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}