{"id":80370,"date":"2017-09-16T08:17:36","date_gmt":"2017-09-16T06:17:36","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=80370"},"modified":"2017-07-27T17:52:32","modified_gmt":"2017-07-27T15:52:32","slug":"p-fernando-nualart-segundo-visitador-1781-1788-i","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/","title":{"rendered":"Fernando Nualart. Segundo Visitador (1781-1788) (I)"},"content":{"rendered":"<p align=\"center\"><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-400138 alignleft\" src=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/Logo-CM-II-248x300.jpg?resize=248%2C300\" alt=\"\" width=\"248\" height=\"300\" \/>CAPITULO PRIMERO<\/strong><\/p>\n<p align=\"center\">Misionero.\u2014Superior de las casas de Guisona y Mallorca.\u2014Postulador de la causa de beatificaci\u00f3n y bi\u00f3grafo de Pedro Borguny (1728-1781).<\/p>\n<p>El 30 de abril de 1746 ingresaba en el no\u00adviciado de la Congregaci\u00f3n de la Misi\u00f3n de la casa de Barcelona Fernando Nualart, \u00abestu\u00addiante ret\u00f3rico\u00bb. Terminado que hubo sus dos a\u00f1os de prueba, durante los cuales tuvo por director y maestro al virtuoso P. Jos\u00e9 Armesto, natural de Benavente, hizo los vo\u00adtos el primero de mayo de 1748. Hab\u00eda na\u00adcido el 15 de julio de 1728 en Palautordera (Barcelona), poblaci\u00f3n situada al pie del ma\u00adjestuoso Monseny y a la derecha del r\u00edo Tor\u00addera, en terreno ondulado y cubierto de pi\u00adnos, encinas, vi\u00f1edos y cereales.<\/p>\n<p>Orden\u00f3se de sacerdote en 1753, y en oc\u00adtubre del a\u00f1o siguiente ya sali\u00f3 a misiones con los PP. Melci\u00f3n, Sell\u00e9s, Dalmau y Ribal\u00adta. Dieron la primera en Arb\u00f3s, predicando el P. Nualart las pl\u00e1ticas de las ma\u00f1ana, lo mismo que en la de T\u00e1rrega, que dur\u00f3 del 21 de noviembre al 24 de diciembre, donde se conmovi\u00f3 mucho la gente, dando muestras inequ\u00edvocas de arrepentimiento y confes\u00e1n\u00addose todos con los misioneros. De all\u00ed pasaron a dar misi\u00f3n en Anglesola y luego en Cerve\u00adra. Acerca de la \u00faltima nos dice con su laco\u00adnismo habitual el precioso <strong>Libro de Misio\u00ad<\/strong><strong>nes <\/strong>de la casa de Barcelona:<\/p>\n<p>\u00abEl 14 de enero de 1755 comenz\u00f3 la mi\u00adsi\u00f3n en la ciudad de Cervera, del obispado de Solsona y distante dos jornadas de Barcelona. Incluyendo los estudiantes, tiene unas cuatro mil almas de comuni\u00f3n. Fue constante y numerosa la concurrencia y el fruto extraordinario y general, siendo tan grande el fervor de aquella buena gente y estudiantes que, a\u00fan en los d\u00edas de carnaval, con ser los \u00falti\u00admos tan inclinados a m\u00e1scaras y amigos de bulla, fue tal la quietud, que todos afirmaban parec\u00eda que est\u00e1bamos en Semana Santa, y los catedr\u00e1ticos ve\u00edan en todas las acciones, palabras y proceder de los escolares m\u00e1s mo\u00addestia y circunspecci\u00f3n que de ordinario. Hubo conversiones extraordinarias de almas que no se hab\u00edan confesado en ocho, diez, veinte y m\u00e1s a\u00f1os, de modo que, ni por la ma\u00f1ana ni por la tarde, pod\u00edamos oir jam\u00e1s a todos los que se acercaban al confesona\u00adrio. fue universal y muy expresivo el j\u00fabilo y contento, y grande la admiraci\u00f3n del pue\u00adblo y de los catedr\u00e1ticos de la universidad. Comulgaron 4.000 almas el d\u00eda de la co\u00admuni\u00f3n general, y m\u00e1s de 1.000 en los cua\u00adtro d\u00edas posteriores que permanecimos all\u00ed para consuelo de los fieles. Los operarios [misioneros] fueron los mismos que en las misiones precedentes: el P. Melci\u00f3n predic\u00f3 los sermones y cuatro pl\u00e1ticas a los eclesi\u00e1s\u00adticos, el P. Nualart las doctrinas y el P. Ri\u00adbalta las pl\u00e1ticas de la ma\u00f1ana. Concluy\u00f3se la misi\u00f3n el 21 de febrero\u00bb.<\/p>\n<p>Despu\u00e9s de dar misi\u00f3n en Biosca, regresa\u00adron a casa para trabajar en los ejercicios que all\u00ed se daban a toda clase de personas.<\/p>\n<p>El 1.\u00b0 de noviembre sali\u00f3 de nuevo a mi\u00adsiones el P. Nualart, asistiendo a las que se dieron aquel curso y el siguiente en Sellera de Angl\u00e9s, Mieras, Besal\u00fa, Cadaqu\u00e9s, Caste\u00adll\u00f3, Garriga, Montseny, Calella, Pineda y Arenys de Mar, predicando en unas las doctri\u00adnas, en otras las pl\u00e1ticas y en algunas parte de los sermones. No precisan en cu\u00e1l de ellas, pero hubo, entre otras, una conversi\u00f3n extraordinaria de cierto pecador que viv\u00eda entregado al demonio desde mucho tiempo atr\u00e1s, y, pasando casualmente por el pueblo, fue a o\u00edr a los misioneros y Dios toc\u00f3 su co\u00adraz\u00f3n.<\/p>\n<p>Aparece asimismo en aquellos a\u00f1os el Pa\u00addre Nualart como director de multitud de ejercitantes, y haciendo la lectura y medita\u00adci\u00f3n, o bien, predicando las pl\u00e1ticas en mu\u00adchas tandas de ejercicios a toda clase de per\u00adsonas.<\/p>\n<p>Tales muestras de virtud, saber y pruden\u00adcia debi\u00f3 dar, que no hab\u00eda cumplido todav\u00eda treinta y dos a\u00f1os de edad, cuando el 20 de mayo de 1760 parti\u00f3 de Barcelona para Su\u00adperior de Guisona. Estuvo al frente de aque\u00adlla importante residencia cerca de cinco a\u00f1os, ayudando a levantar las cargas de misiones y ejercicios de la casa. Por haberse extraviado los libros y documentos de ella, nos es im\u00adposible apreciar debidamente la labor del Pa\u00addre Nualart.<\/p>\n<p>En 1765 fue trasladado, con el cargo lam\u00adbien de. Superior a la caso de Palma de Ma\u00adllorca, adonde lleg\u00f3 con el P. Company el 18 de Junio. En el mes de septiembre aparece ya haciendo la lectura y meditaci\u00f3n a los or\u00addenandos, que practican all\u00ed los ejercicios y dirige y predica las pl\u00e1ticas en las tandas de noviembre y diciembre. Durante los nueve a\u00f1os escasos que estuvo al frente de aquella comunidad, figura siempre en las tandas anuales de ejercicios a ordenandos, en las se dan a toda clase de personas y a los que los prac\u00adticaban separadamente.<\/p>\n<p>Tambi\u00e9n sali\u00f3 a misi\u00f3n en varias ocasio\u00adnes, predicando en general las doctrinas, y las pl\u00e1ticas a los eclesi\u00e1sticos. En la misi\u00f3n de Sineu (23 de enero a 28 de febrero de 1770); dio adem\u00e1s ejercicios a las monjas, instaladas en el antiguo edificio que fue pa\u00adlacio de los reyes de Mallorca.<\/p>\n<p>Con el ejemplo y bajo la direcci\u00f3n de tan experto gu\u00eda se mantuvieron en estado muy floreciente los ejercicios espirituales y las misiones en aquella antigua y benem\u00e9rita casa.<\/p>\n<p>Por un poder otorgado al procurador se\u00ad\u00f1or Domenge el 31 de enero de 1774 consta que ya no era entonces Superior de la Comu\u00adnidad el P. Nualart. Cuatro d\u00edas despu\u00e9s, apa\u00adrece en otro documento como Superior el P. Jos\u00e9 Vila.<\/p>\n<p>En la asamblea dom\u00e9stica, celebrada en la casa de Palma, el 16 de marzo de 1774, fue elegido diputado el P. Nualart, y el 23 del mismo mes y a\u00f1o dejaba \u00abla m\u00e1s deliciosa, morigerada y recomendable\u00bb de las islas del Mediterr\u00e1neo, como \u00e9l mismo la llama, para dirigirse a la asamblea provincial que se ha\u00adb\u00eda de tener en G\u00e9nova. Trat\u00f3se all\u00ed, entre otras cosas, de formar una provincia aparte con las casas de Espa\u00f1a, proposici\u00f3n que fue aceptada por la asamblea general, nombrando el P. Jacquier Visitador de la nueva pro\u00advincia al P. Vicente Ferrer.<\/p>\n<p>De G\u00e9nova, por haber sido nombrado pos\u00adtulador de la causa del mallorqu\u00edn Pedro Borguny, fue el P. Nualart a Roma, morando varios a\u00f1os en aquella capital y en N\u00e1poles. Estando en Roma public\u00f3 en 1780 la Vida y martirio del siervo de Dios, Pedro Borgu\u00adny, dedic\u00e1ndola al muy ilustre Ayunta\u00admiento de la ciudad de Palma. Afirma en el pr\u00f3logo que la Vida de Borguny la saca \u00abprincipalmente de los monumentos ciertos que se hallan en esta capital del mundo, ar\u00adchivados con mucha custodia en la Sagrada Congregaci\u00f3n de Propaganda Fide, y que se ha dignado comunicarme el Ilmo. y Reveren\u00add\u00edsimo Monse\u00f1or Esteban de Borja, Secreta\u00adrio de dicha Congregaci\u00f3n, por el grande y devoto deseo que tiene de que se promueva con todo ardor su causa de beatificaci\u00f3n y se d\u00e9 a luz cuanto desde Argel escribi\u00f3 de este siervo de Dios a dicha Congregaci\u00f3n el Reve\u00adrend\u00edsimo Felipe Le Vacher, sacerdote de la Congregaci\u00f3n de la Misi\u00f3n, enviado all\u00e1 por su Patriarca y Fundador San Vicente de Pa\u00fal, para consuelo de los infelices esclavos\u00bb.<\/p>\n<p>Divide la obra en dos partes: en la primera cuenta las andanzas y desvar\u00edos de Pedro Borguny, y se extiende con frecuencia en sa\u00adludables reflexiones y advertencias a los pa\u00addres e hijos. En el cap\u00edtulo primero no ocul\u00adta su cari\u00f1o a la tierra del m\u00e1rtir ni puede olvidar entre los esplendores de Roma las bellezas. de Mallorca, \u00absingularmente el ge\u00adnio, piedad y religi\u00f3n grande\u00bb de sus mora\u00addores que ha conocido a fondo en el tiempo que tuvo la fortuna de habitar all\u00ed, y por eso no puede pasar en silencio \u00abque su ge\u00adnio es amabil\u00edsimo; su docilidad muy singu\u00adlar; el aprecio que com\u00fanmente hacen de los forasteros tan sin parang\u00f3n, que cuantos han ido a aquella isla no pueden dejar<sup>&#8211;<\/sup> de quedar agradecid\u00edsimos; tan prendados y aficionados a ella, que regularmente todos la alaban y di\u00adcen mucho bien de ella con el mayor apre\u00adcio, sin que apenas me acuerde haber jam\u00e1s o\u00eddo alguno que no la haya despu\u00e9s muy mu\u00adcho elogiado\u00bb.<\/p>\n<p>Narra en la segunda parte de su obra el P. Nualart la conversi\u00f3n de Borguny, los inauditos tormentos a que le sometieron y el horrible suplicio con que termin\u00f3 su vida, muriendo quemado por la fe cat\u00f3lica. Desha\u00adce luego las objeciones que pod\u00edan oponerse a la beatificaci\u00f3n del h\u00e9roe cristiano, y refte-<sup>&#8211;<\/sup>&#8211;<sup>&#8211;<\/sup> re algunos hechos prodigiosos atribuidos su<sup>&#8211;<\/sup>intercesi\u00f3n. La Vida de Borguny est\u00e1 bas\u00adtante bien escrita y revela en su autor cierto buen gusto, entonces poco com\u00fan; aunque su estilo es un tanto difuso y recargado de refle\u00adxiones morales, por lo menos en la primera parte.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAPITULO PRIMERO Misionero.\u2014Superior de las casas de Guisona y Mallorca.\u2014Postulador de la causa de beatificaci\u00f3n y bi\u00f3grafo de Pedro Borguny (1728-1781). El 30 de abril de 1746 ingresaba en el no\u00adviciado de la Congregaci\u00f3n de &#8230; <a href=\"http:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":391249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19],"tags":[168],"class_list":["post-80370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biografias-de-misioneros-paules","tag-argel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fernando Nualart. Segundo Visitador (1781-1788) (I) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fernando Nualart. Segundo Visitador (1781-1788) (I) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAPITULO PRIMERO Misionero.\u2014Superior de las casas de Guisona y Mallorca.\u2014Postulador de la causa de beatificaci\u00f3n y bi\u00f3grafo de Pedro Borguny (1728-1781). El 30 de abril de 1746 ingresaba en el no\u00adviciado de la Congregaci\u00f3n de ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-16T06:17:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"Fernando Nualart. Segundo Visitador (1781-1788) (I)\",\"datePublished\":\"2017-09-16T06:17:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/\"},\"wordCount\":1612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"keywords\":[\"Argel\"],\"articleSection\":[\"Biograf\u00edas de Misioneros Pa\u00fales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/\",\"name\":\"Fernando Nualart. Segundo Visitador (1781-1788) (I) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"datePublished\":\"2017-09-16T06:17:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/bio-cm.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/p-fernando-nualart-segundo-visitador-1781-1788-i\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fernando Nualart. Segundo Visitador (1781-1788) (I)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fernando Nualart. Segundo Visitador (1781-1788) (I) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/","og_locale":"es_ES","og_type":"article","og_title":"Fernando Nualart. Segundo Visitador (1781-1788) (I) - Somos Vicencianos","og_description":"CAPITULO PRIMERO Misionero.\u2014Superior de las casas de Guisona y Mallorca.\u2014Postulador de la causa de beatificaci\u00f3n y bi\u00f3grafo de Pedro Borguny (1728-1781). El 30 de abril de 1746 ingresaba en el no\u00adviciado de la Congregaci\u00f3n de ... Read More","og_url":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2017-09-16T06:17:36+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"Fernando Nualart. Segundo Visitador (1781-1788) (I)","datePublished":"2017-09-16T06:17:36+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/"},"wordCount":1612,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","keywords":["Argel"],"articleSection":["Biograf\u00edas de Misioneros Pa\u00fales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/","url":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/","name":"Fernando Nualart. Segundo Visitador (1781-1788) (I) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","datePublished":"2017-09-16T06:17:36+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-i\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Fernando Nualart. Segundo Visitador (1781-1788) (I)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"http:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-kUi","jetpack-related-posts":[{"id":131025,"url":"http:\/\/vincentians.com\/es\/fernando-nualart-1781-1788-visitador\/","url_meta":{"origin":80370,"position":0},"title":"Fernando Nualart (1781-1788) (Visitador)","author":"Mitxel Olabu\u00e9naga","date":"07\/08\/2014","format":false,"excerpt":"Naci\u00f3 en Palautordera (Barcelona) el 15 de junio de 1728 e ingres\u00f3 en la Congregaci\u00f3n el 30 de abril de 1746. Hechos los votos y ordenado sacerdote se dedic\u00f3 alg\u00fan tiempo a las misiones siendo pronto nombrado superior de Guissona. En 1765 fue destinado como superior a Mallorca. Desde 1781\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":93561,"url":"http:\/\/vincentians.com\/es\/p-fernando-nualart\/","url_meta":{"origin":80370,"position":1},"title":"Fernando Nualart","author":"Mitxel Olabu\u00e9naga","date":"09\/07\/2012","format":false,"excerpt":"56. P. Fernando Nualart.\u2014Escribimos en otra par\u00adte la vida de este ilustre Misionero, segundo Visitador de la Provincia espa\u00f1ola y uno de los principales instrumen\u00adtos de que se vali\u00f3 la Providencia para introducir las Hi\u00adjas de la Caridad en Espa\u00f1a. Consignaremos aqu\u00ed \u00fanica\u00admente que naci\u00f3 en Palautordera (Barcelona) el 15\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":80377,"url":"http:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-ii\/","url_meta":{"origin":80370,"position":2},"title":"Fernando Nualart. Segundo Visitador (1781-1788) (II)","author":"Mitxel Olabu\u00e9naga","date":"24\/09\/2017","format":false,"excerpt":"CAPITULO II Segundo Visitador de la provincia de Espa\u00f1a. Visita de las casas y algunas de las Orde\u00adnanzas que dej\u00f3.\u2014Estado de la provincia y desarrollo de los ministerios mientras fue visitador el P. Nualart. (1781-1788). El 18 de abril de 1781 fue nombrado visi\u00adtador de la provincia de Espa\u00f1a el\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":83160,"url":"http:\/\/vincentians.com\/es\/p-fernando-nualart-segundo-visitador-1781-1788-iii\/","url_meta":{"origin":80370,"position":3},"title":"P. Fernando Nualart. Segundo Visitador (1781-1788) (III)","author":"Mitxel Olabu\u00e9naga","date":"30\/09\/2017","format":false,"excerpt":"CAPITULO III El P. Nualart y la introducci\u00f3n del Instituto de las. Hijas de la Caridad en Espa\u00f1a.\u2014El P. Nualart y los Hermanos de! Hospital de la Santa. Cruz. de Barcelona.\u2014\u00daltimos d\u00edas y muerte del P. Nualart (1792-1793). Hac\u00eda ya m\u00e1s de setenta a\u00f1os que se hab\u00eda establecido la Congregaci\u00f3n\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":131023,"url":"http:\/\/vincentians.com\/es\/vicente-ferrer-1774-1781-visitador\/","url_meta":{"origin":80370,"position":4},"title":"Vicente Ferrer (1774-1781) (Visitador)","author":"Mitxel Olabu\u00e9naga","date":"05\/08\/2014","format":false,"excerpt":"Naci\u00f3 en Blanes el 26 de Octubre de 1721 y, casi concluida la carrera eclesi\u00e1stica, entr\u00f3 en la Congregaci\u00f3n el 2 de junio de 1743. Destinado en un principio a la formaci\u00f3n de los j\u00f3venes misioneros, se dedic\u00f3 posteriormente a la predicaci\u00f3n en las Misiones Populares y a la direcci\u00f3n\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":80358,"url":"http:\/\/vincentians.com\/es\/el-p-vicente-ferrer-primer-visitador-1774-1781-vi\/","url_meta":{"origin":80370,"position":5},"title":"El P. Vicente Ferrer, Primer Visitador (1774-1781) (VI)","author":"Mitxel Olabu\u00e9naga","date":"04\/09\/2017","format":false,"excerpt":"CAPITULO VI Erecci\u00f3n de la provincia de Espa\u00f1a y nom\u00adbramiento del P. Ferrer para Visitador de la misma.\u2014La gobierna durante siete a\u00f1os. (1774-1781 ) . Dada la dificultad de las comunicaciones y la distancia que separaba a las casas de la Misi\u00f3n de Espa\u00f1a de la provincia de Lombar\u00add\u00eda, de\u2026","rel":"","context":"En \u00abBiograf\u00edas de Misioneros Pa\u00fales\u00bb","block_context":{"text":"Biograf\u00edas de Misioneros Pa\u00fales","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/biografias-vicencianas\/biografias-de-misioneros-paules\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/bio-cm.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/80370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=80370"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/80370\/revisions"}],"predecessor-version":[{"id":401112,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/80370\/revisions\/401112"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/391249"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=80370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=80370"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=80370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}