{"id":72946,"date":"2017-07-30T08:20:17","date_gmt":"2017-07-30T06:20:17","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=72946"},"modified":"2017-04-16T12:27:22","modified_gmt":"2017-04-16T10:27:22","slug":"la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/","title":{"rendered":"La llegada de las Hijas de la Caridad al continente Americano (I)"},"content":{"rendered":"<div>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"398522\" data-permalink=\"http:\/\/vincentians.com\/es\/las-hijas-de-la-caridad-en-el-servicio-a-los-pobres\/hijas-caridad\/\" data-orig-file=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630\" data-orig-size=\"1195,630\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"hijas caridad\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=846%2C446\" class=\"alignnone size-medium wp-image-398522 alignleft\" src=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=300%2C158\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=300%2C158 300w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=768%2C405 768w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=1024%2C540 1024w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=100%2C53 100w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=846%2C446 846w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?resize=1004%2C529 1004w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?w=1195 1195w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cuando San Vicente naci\u00f3 en 1581, no hab\u00edan transcurrido todav\u00eda cien a\u00f1os desde que Crist\u00f3bal Col\u00f3n hab\u00eda abordado aquel continente, que no sab\u00eda todav\u00eda que iba a llamarse \u00abAm\u00e9rica\u00bb.<\/p>\n<p>\u00bfPens\u00f3 San Vicente en enviar Misioneros a aquel vasto continente? Encontramos una alusi\u00f3n a ello en una carta suya del 3 de mayo de 1652, dirigida a Lamberto aux Couteaux:<\/p>\n<p>\u00abel proyecto de Am\u00e9rica (se trata aqu\u00ed de Canad\u00e1) no ha resultado por lo que a nosotros se refiere. No es que no se haga el embarco, sino que el que nos hab\u00eda pedido sacerdotes no ha vuelto a hablarnos de ello, quiz\u00e1 por la dificultad que yo mismo puse al principio de no poder d\u00e1rselos si no era con la aprobaci\u00f3n y las facultades de la Sagrada Congregaci\u00f3n de Propaganda; en eso no hab\u00eda pensado \u00e9l, y me pareci\u00f3 que los sacerdotes que llevan all\u00e1, marchan sin ello. Yo creo que es conveniente&#8230; enviar nuestros sacerdotes para la conversi\u00f3n de los infieles, pero esto hay que\u00a0 entenderlo cuando tienen una misi\u00f3n leg\u00edtima&#8230; \u203a<\/p>\n<p>Sin embargo, poco antes del 25 de abril de 1652, San Vicente escribe a la Superiora de las religiosas de la Misericordia del Hospital de Quebec:<\/p>\n<p><em>\u00ab&#8230; en efecto miro esa obra <\/em>(las misiones en Canad\u00e1) <em>como una de las m\u00e1s grandes <\/em><em>que se han llevado a cabo desde hace mil quinientos a\u00f1os&#8230;\u00bb<\/em><\/p>\n<p>\u00bfCu\u00e1ndo y c\u00f3mo fueron llegando las Hijas de la Caridad al continente americano. Las circunstancias de su llegada a uno u otro pa\u00eds son muy diversas. Es lo que quisiera presentarles en estas l\u00edneas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>I. A M\u00e9xico <\/em><\/strong><em>(1844)<\/em><\/p>\n<p>A principios del siglo XIX exist\u00edan en las ciudades de este pa\u00eds establecimientos de beneficencia, asilos&#8230; para necesitados. Se sosten\u00edan por la caridad, con frecuencia muy generosa, de los habitantes. Pero lo que faltaba era un buen sistema de administraci\u00f3n, de tal forma que lleg\u00f3 a darse el vicio con la consiguiente paralizaci\u00f3n de tan fecundas instituciones. Como instrumentos de una regeneraci\u00f3n que se hab\u00eda hecho necesaria, se llam\u00f3 a las Hijas de la Caridad.<\/p>\n<p>La persona que Dios escogi\u00f3 para poner en marcha esta fundaci\u00f3n fue la Condesa Mar\u00eda Ana G\u00f3mez de la Cortina, a la que se unieron otras dos se\u00f1oras y dos caballeros.<\/p>\n<p>Sus gestiones obtuvieron con facilidad la autorizaci\u00f3n del gobierno. Y en 1843, una ley autorizaba a los Sacerdotes de la Misi\u00f3n y a las Hijas de la Caridad para que se establecieran en M\u00e9xico y les aseguraban, adem\u00e1s, ayuda y protecci\u00f3n. La petici\u00f3n de las Hermanas hab\u00eda sido dirigida al P. Roca, c.m., Director de las Hijas de la Caridad de Espa\u00f1a. El P. Roca obtuvo, a su vez, autorizaci\u00f3n del Superior General para responder afirmativamente a dicha petici\u00f3n, y el 31 de agosto un Real Decreto autorizaba a las Hermanas a salir de la Pen\u00ednsula para dirigirse a M\u00e9xico.<\/p>\n<p>La peque\u00f1a expedici\u00f3n se compon\u00eda de diez Hijas de la Caridad, espa\u00f1olas, bajo la direcci\u00f3n de Sor Inza y de dos Sacerdotes de la Misi\u00f3n como directores de las Hermanas. El 8 de septiembre de 1844, se embarcaron en C\u00e1diz y el 4 de noviembre siguiente desembarcaron en Veracruz. Despu\u00e9s de cuatro d\u00edas de descanso, el grupo se dirigi\u00f3 a Puebla. A cuatro leguas de esta ciudad, el obispo con numerosos ciudadanos salieron a su encuentro para recibirles. El 15 de noviembre, llegaron por fin a M\u00e9xico, la capital. Apenas llevaban un mes en el pa\u00eds, cuando estall\u00f3 una revoluci\u00f3n. Se llam\u00f3 a las Hermanas para que cuidaran de los heridos del partido del gobierno, y ellas aceptaron con la condici\u00f3n de poder cuidar indistintamente a los heridos de los dos partidos, cosa que les fue concedida. La revuelta dur\u00f3 poco y casi no tuvieron tiempo de ejercitar su celo. Pero su actitud les gan\u00f3 la simpat\u00eda de todos.<\/p>\n<p>Desde los primeros a\u00f1os de estancia en M\u00e9xico, se presentaron j\u00f3venes mexicanas solicitando su ingreso en la Compa\u00f1\u00eda. El Seminario se abri\u00f3 en 1855. Desgraciadamente, tras haberse hecho con el poder un partido calificado de antirreligioso, las Hermanas fueron expulsadas en enero de 1875. En total, cuatrocientas diez que atend\u00edan a unos diecis\u00e9is mil pobres, en cuarenta y tres casas, salieron del pa\u00eds. Algunas de ellas se dirigieron a la Casa Madre de Par\u00eds y, despu\u00e9s de un breve tiempo, fueron destinadas a Espa\u00f1a, Italia, Argelia, Oriente, sin excluir China. Otras quedaron en Francia. Otras, por \u00faltimo, se diseminaron por los diversos pa\u00edses de Am\u00e9rica: Guatemala, El Salvador, Panam\u00e1, Nicaragua, Ecuador, Per\u00fa y Chile. Tambi\u00e9n alguna fue a California. A M\u00e9xico, las Hijas de la Caridad pudieron regresar en 1945.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>II.- A Cuba <\/em><\/strong><em>(1847)<\/em><\/p>\n<p>Desde 1492, esta Isla pertenec\u00eda a Espa\u00f1a. En 1660 y en 1762, los ingleses se apoderaron de ella y la saquearon. Fue devuelta a Espa\u00f1a en 1763. En 1847, algunas Hermanas espa\u00f1olas marcharon a Cuba para hacerse cargo de la \u00abCasa de Maternidad y Beneficencia\u00bb, siendo durante varios a\u00f1os la \u00fanica en que hubo Hermanas.<\/p>\n<p><em>En <\/em>1862 estall\u00f3 una revuelta de Criollos y Negros, dando lugar a luchas que duraron varios a\u00f1os. Esta fue la ocasi\u00f3n de que, en 1894, las autoridades de la Isla pidieran Hermanas a Espa\u00f1a para atender a los heridos. En julio de 1895, llegaron veinte Hermanas. Pero la necesidad hizo que se pidieran m\u00e1s, y en 1897, se enviaron sesenta, en dos grupos.<\/p>\n<p>En 1898, se declara en la Isla la guerra entre Estados Unidos y Espa\u00f1a. Por aquel entonces, una Hermana escrib\u00eda a la Superiora General, Madre Lamartinie: <em>\u00abTres plagas <\/em><em>han ca\u00eddo sobre nosotras: la guerra, la peste, el hambre&#8230; Con excepci\u00f3n de \u00a0dos <\/em><em>Hermanas, todas las dem\u00e1s han estado enfermas. En cuanto a los pobres, \u00a1son <\/em><em>notables los que mueren cada d\u00eda\u00bb.<\/em><\/p>\n<p>En septiembre de aquel mismo a\u00f1o \u2014despu\u00e9s de la victoria obtenida por los Estados Unidos\u2014, las Hermanas de Santiago de Cuba salieron de la Isla y regresaron Espa\u00f1a. Seis Hermanas murieron en el camino o reci\u00e9n llegadas. En algunos Hospitales, los Estadounidenses sustituyeron a las Hermanas por Se\u00f1oras protestantes\u00ad, De todas formas, quedaron en la Isla doscientas diecinueve Hermanas. A pesar de las casas que tuvieron que dejar, en 1906 conservaban todav\u00eda diecis\u00e9is en las que gu\u00edan trabajando.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div>\n<p><strong><em>III.- Al Brasil <\/em><\/strong><em>(1849-1904-1935)<\/em><\/p>\n<p>Estas tres diferentes fechas corresponden al hecho de que las Hijas de la Caridad llegaron a Brasil, en diversas \u00e9pocas, procedentes de otros tantos pa\u00edses europeos respondiendo a la llamada de emigrantes de esos pa\u00edses establecidos en diversas regiones de Brasil, muy distantes unas de otras. Desde entonces, hace ya mucho tiempo que esos tres grupos quedaron unificados.<\/p>\n<p>En 1810, los Sacerdotes de la Misi\u00f3n, expulsados de Portugal, marcharon establecerse en Brasil. En 1848, uno de ellos, que hab\u00eda sido nombrado obispo <strong>Mariana, <\/strong>ciudad del centro de Brasil, expres\u00f3 el deseo de tener en su di\u00f3cesis Hijas de la Caridad. El 23 de noviembre de 1848, el sacerdote brasile\u00f1o a quien el obispo hab\u00eda encomendado el asunto, sal\u00eda de Par\u00eds con doce Hijas de la Caridad, seis Misioneros y tres Hermanos. El grupo se embarc\u00f3 en El Havre en un barco que sali\u00f3 del puerto el 28 de noviembre.<\/p>\n<p>El 8 de febrero de 1849, la peque\u00f1a expedici\u00f3n llegaba a la bah\u00eda de R\u00edo de Janeiro, despu\u00e9s de setenta d\u00edas de viaje. A causa de las lluvias, la marcha hacia Mariana hubo de retrasarse hasta el mes siguiente. Las Hermanas aprovecharon la espera para empezar a aprender el portugu\u00e9s.<\/p>\n<p>El 11 de marzo de 1849, Hermanas y Misioneros se embarcaron para el puerto de !a Estrella, en donde, al d\u00eda siguiente, se form\u00f3 la caravana que hab\u00eda de llevarlos hasta Mariana. Dicha caravana se compon\u00eda de veintis\u00e9is viajeros a caballo y una treintena de mulos de carga.<\/p>\n<p>Animosamente y sin perder la alegr\u00eda aquella caravana se adentr\u00f3 entre las monta\u00f1as. El viaje conllevaba peligros. Por todas partes, hab\u00eda que escalar rocas escarpadas, y bajar despu\u00e9s las correspondientes cuestas, vados dif\u00edciles de atravesar, precipicios bordeando el sendero tortuoso, que hab\u00eda que ir sorteando durante horas. Despu\u00e9s de veintitr\u00e9s d\u00edas de semejante viaje, la caravana arrib\u00f3 a su destino: Mariana.<\/p>\n<p>La casa que se hab\u00eda destinado para las Hermanas era muy pobre, porque el obispo no pose\u00eda nada: todo lo que llegaba a sus manos iba a parar a los pobres. La comida era frugal, pero la Providencia no dejaba de velar por los suyos. As\u00ed ocurri\u00f3 un d\u00eda, a las 11 y media, empezaron las Hermanas a preguntarse, sin que les faltaran motivos para ello, qu\u00e9 iban a comer, pues no ten\u00edan nada en absoluto. No obstante, hicieron como de ordinario el examen particular y se fueron al refectorio, donde se pusieron a re\u00edr ante los platos vac\u00edos, desesperadamente vac\u00edos. Iban ya a marcharse, cuando llamaron a la puerta. Era un negro que llevaba sobre la cabeza una bandeja bien provista. La deposit\u00f3 en silencio, y se march\u00f3. M\u00e1s tarde supieron que se habla equivocado de direcci\u00f3n, pero por supuesto era demasiado tarde para deshacer el error y restituir. En Mariana, las Hermanas empezaron por hacer la visita a los pobres, ya pie, ya a caballo, y despu\u00e9s abrieron clases para los ni\u00f1os pobres.<\/p>\n<p>En n agosto de 1852, treinta Hijas de la Caridad llegaban a R\u00edo de Janeiro para hacerse cargo del gran hospital de la ciudad. Al a\u00f1o siguiente, siete de ellas mor\u00edan v\u00edctimas de la fiebre amarilla. Ya en 1849, empezaron a entrar en la Compa\u00f1\u00eda algunas j\u00f3venes de aquella regi\u00f3n.<\/p>\n<p>En 1798, en el Estado de Paran\u00e1, al sur del pa\u00eds, hab\u00eda empezado una coloniza\u00adci\u00f3n eslava. A principios del siglo XX, unos cien mil Polacos formaban una colonia compacta, que hab\u00eda conservado su lengua y sus costumbres. Este grupo humano quiso tener para su atenci\u00f3n espiritual a Sacerdotes de la Misi\u00f3n Polacos, y los pidieron a Polonia. Poco tiempo despu\u00e9s, en 1904, llegaban tambi\u00e9n Hijas de la Caridad de la Provincia de Chelmno para ocuparse de los pobres, de los enfermos y de los ni\u00f1os de la Colonia.<\/p>\n<p>En 1934, algunas Hijas de la Caridad austriacas se dirigieron, con un grupo de doscientos cincuenta colonos tiroleses, a integrarse en un grupo de la misma nacionalidad, que anteriormente se hab\u00eda establecido en el Estado de Paran\u00e1, en el Brasil meridional. Tres d\u00edas les cost\u00f3, en tren \u2014sin duda no demasiado r\u00e1pido\u2014 llegar a buen destino y poder ocuparse de los ni\u00f1os y enfermos de la colonia austriaca.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>IV.- A los Estados Unidos <\/em><\/strong><em>(1850)<\/em><\/p>\n<p>Los comienzos de la Comunidad en los Estados Unidos se deben a la Sra. SETON, mujer admirable, nacida en 1774, en el seno de una familia episcopaliana. Casada y viuda a los veintinueve a\u00f1os, con cinco hijos, fue a residir a Baltimore y se convirti\u00f3 al catolicismo. Bajo la direcci\u00f3n de Monse\u00f1or Dubourg, resolvi\u00f3 consagrarse a Dios. Y con esta finalidad, fund\u00f3 en 1809, en Emmitsburgo, la Comunidad de Hermanas de la Caridad, de la que fue elegida superiora.<\/p>\n<p>El Se\u00f1or Cooper, rico armador, convertido hac\u00eda 1805, fue el instrumento del que se vali\u00f3 la Providencia para el establecimiento de las primeras Hermanas norteamericanas. El 31 de julio de 1809, Madre Seton y sus Hermanas tomaron posesi\u00f3n de su Humilde casa.<\/p>\n<p>La intenci\u00f3n de la fundadora, desde un primer momento, fue la de asimilar completamente el nuevo Instituto al de las Hijas de la Caridad, de Francia. De acuerdo con Monse\u00f1or Dubourg, rog\u00f3 a Monse\u00f1or Flagot, obispo de Kentucky, que se dirig\u00eda, en 1810, a Francia, que intentase algunas gestiones a tal efecto con loe Superiores de Par\u00eds. Estos \u00faltimos se interesaron profundamente por la nueva Comunidad, hasta el punto de nombrar a tres Hermanas: Sor Bizeray, Sor Voisin y Sor Chauvin, para ir a formar seg\u00fan el esp\u00edritu y las costumbres de la Comunidad, a las Hermanas norteamericanas. Se hallaban ya en Burdeos a punto de embarcarse, cuando se les notific\u00f3 le prohibici\u00f3n, por parte del gobierno, de salir de Francia. Monse\u00f1or Piaget se vio pues obligado a marchar sin ellas, llev\u00e1ndose tan s\u00f3lo un ejemplar de las Reglas.<\/p>\n<p>Madre Seton muri\u00f3 en 1821. En el transcurso de los a\u00f1os, se intent\u00f3 repetidamente reanudar las negociaciones con Francia, pero, por diversos motivos, no se lleg\u00f3 a ning\u00fan resultado, Y por la fuerza de las circunstancias, las Hermanas de la Caridad quedaron bajo la direcci\u00f3n y dependencia de los Sulpicianos de Baltimore. Este estado de cosas ofrec\u00eda, sin embargo, muchos inconvenientes.<\/p>\n<p>En 1848, Monse\u00f1or Deluol, sulpiciano, era el Superior de las Hermanas, y en dicha fecha, estableci\u00f3 contactos con Monse\u00f1or Chance, amigo suyo, y con Monse\u00f1or Eccleston, arzobispo de Baltimore. Monse\u00f1or Chance se dispon\u00eda a salir de viaje para Europa, y el Se\u00f1or Deluol, de acuerdo con el arzobispo, le entreg\u00f3 una petici\u00f3n para el Superior General de la Congregaci\u00f3n de la Misi\u00f3n. Despu\u00e9s de muchas comunicaciones, sobre todo por carta, el Se\u00f1or Maller, c.m., que trabajaba en Missouri, se puso en contacto con las Hermanas y viaj\u00f3 a Francia para entrevistarse con el Padre Etienne. Apenas desembarc\u00f3, el Padre Maller se vio interpelado por un sacerdote anciano que le pregunt\u00f3 si en los Estados Unidos hab\u00eda una Comunidad de Hijas de la Caridad, a\u00f1adiendo que \u00e9l confesaba a Hijas de la Caridad y que una de ellas habla tenido una visi\u00f3n en la que San Vicente le hab\u00eda dicho que ten\u00eda Hijas fuera de Francia que deseaban unirse con la Comunidad primera. Cuando el Padre Maller comunic\u00f3 el hecho al Padre Etienne, la reacci\u00f3n de este fue: <em>\u00abPues si San Vicente ha dicho que yo tambi\u00e9n digo que s\u00ed\u00bb. <\/em>El Padre Maller fue nombrado Director de las Hermanas de Provincia de los Estados Unidos.<\/p>\n<p>En marzo de 1850, todas las Hermanas hicieron por primera vez los votos de las Hijas de la Caridad. Despu\u00e9s de esto, cuatro de ellas fueron nombradas para ir a Par\u00eds y formarse directamente en el estilo de la Comunidad. Durante algunos meses, permanecieron en la Casa Madre, una en el economato, otra en el seminario, otra en el oficio de h\u00e1bitos y otra en secretar\u00eda.<\/p>\n<p>En la primavera de 1851, Sor Etienne Hall, nombrada Visitadora, fue tambi\u00e9n a Par\u00eds con otra compa\u00f1era. Entre tanto, el Padre Etienne hab\u00eda enviado, el 1\u00b0 de Enero de 1850, una circular a todas las Hermanas de la nueva Provincia, que terminaba diciendo: <em>\u00abLas tendr\u00e9 siempre presente ante Dios y me complacer\u00e9 en <\/em><em>colocarlas todos los d\u00edas bajo su poderosa protecci\u00f3n\u00bb.<\/em><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>V &#8211; A Chile <\/em><\/strong><em>(1854)<\/em><\/p>\n<p>Las Hijas de la Caridad fueron llamadas a este pa\u00eds por el Arzobispo de Santiago <strong>y <\/strong>el Presidente de la Rep\u00fablica. Treinta Hermanas salieron de Burdeos el 18 de noviembre de 1853. Despu\u00e9s de la traves\u00eda del Oc\u00e9ano Atl\u00e1ntico y de contornear la Tierra de Fuego, llegaron a Valpara\u00edso el 14 de marzo de 1854, tras un viaje bastante accidentado. De Valpara\u00edso marcharon hacia la capital, Santiago.<\/p>\n<p>En la catedral se les hizo un recibimiento magn\u00edfico. En el templo les esperaba con impaciencia una verdadera multitud. Durante las semanas siguientes, doce Hermanas fueron destinadas al Hospital de hombres, seis al de mujeres, otras seis con los Ni\u00f1os Exp\u00f3sitos. En cuanto a las seis restantes, quedaron encargadas de organizar otras actividades en la Casa Provincial, entre ellas un internado para ni\u00f1as y j\u00f3venes.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>VI &#8211; A Per\u00fa <\/em><\/strong><em>(1858)<\/em><\/p>\n<p>Una joven peruana, la Se\u00f1orita Carassa, que hab\u00eda le\u00eddo la vida de San Vicente, se determin\u00f3 a pedir a su padre la autorizaci\u00f3n para ser Hija de la Caridad. <em>\u00abS\u00ed, a condici\u00f3n de que no salgas de Per\u00fa\u00bb, <\/em>fue la respuesta que recibi\u00f3. -\u00a1Pues que por eso no quede!. La Se\u00f1orita est\u00e1 segura de lo que quiere. Y se dirige a la Sociedad de Beneficencia para gestionar una fundaci\u00f3n en Lima. Consigue, a continuaci\u00f3n la conformidad del Presidente del Estado Peruano y la del Arzobispo. Queda, sin embargo, un obst\u00e1culo a vencer: la falta de fondos. Por lo que se dedica a pedir y no tarda mucho en reunir la cantidad necesaria para dar comienzo a un primer estable\u00adcimiento y para el viaje de las Hermanas.<\/p>\n<p>El 19 de septiembre de 1857, cuarenta y cinco Hijas de la Caridad se embarcan en Burdeos, acompa\u00f1adas por cuatro Sacerdotes de la Misi\u00f3n. Iban con el encargo de ocuparse del servicio de tres Hospitales y de la Casa de Misericordia.<\/p>\n<p>Llegaron a Per\u00fa el 2 de febrero de 1858 y, antes de ir a tomar posesi\u00f3n de sus diferentes puestos de trabajo, dejaron instalada la Casa Provincial.<\/p>\n<p>En el Hospital de Santa Ana, la primera noche fue \u00abde campeonato\u00bb. Forzoso fue olvidar que aquellas horas estaban dedicadas al silencio y al sue\u00f1o, porque toda una invasi\u00f3n de ratas, habituadas a ser \u00fanicas due\u00f1as del terreno, les disputaban a las reci\u00e9n llegadas, que no dispon\u00edan m\u00e1s que de un somier en el suelo, el amplio espacio del que hasta entonces hab\u00edan disfrutado, y saltaban de una Hermana a otra, con una agilidad y destreza incre\u00edbles. Cada una se vio en la necesidad de armarse de un palo para echar a aquellos due\u00f1os inc\u00f3modos. Pero la cosa \u00a1no fue tan f\u00e1cil!<\/p>\n<p>Durante los primeros a\u00f1os de su presencia en Per\u00fa, se fue encargando a las Hermanas de orfanatos y hospitales. En la mayor\u00eda de estos establecimientos, sobre todo al principio, tuvieron que pasar por muchas dificultades, pues no se trataba de obras nuevas, sino de situaciones que hab\u00eda que reformar.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>VII. A Argentina <\/em><\/strong><em>(1859)<\/em><\/p>\n<p>Como los dem\u00e1s del Continente, este pa\u00eds pertenec\u00eda a Espa\u00f1a. En 1810, entr\u00f3 en el movimiento de insurrecci\u00f3n y proclam\u00f3 su independencia en 1818. Pero no pudo conseguir cierta tranquilidad hasta 1853.<\/p>\n<p>El 2 de febrero de 1858, a petici\u00f3n del presidente de la municipalidad de Buenos Aires, el Padre Etienne firmaba un contrato establecido entre los Superiores Gene\u00adrales de las Congregaciones y el Encargado de Negocios del Estado argentino. En virtud de dicho contrato, el 21 de julio de 1859, dos Sacerdotes de la Misi\u00f3n y doce Hijas de la Caridad se embarcan en El Havre y llegaban a Buenos Aires el 13 de septiembre siguiente. Las Hijas de la Caridad iban a hacerse cargo de la direcci\u00f3n del hospital de hombres. En dicho hospital, no hab\u00eda orden, ni autoridad, ni organizaci\u00f3n. Se las recibi\u00f3 bastante mal por el conjunto de secciones del mismo y por el personal.<\/p>\n<p>Esta situaci\u00f3n dur\u00f3 hasta que estall\u00f3 la guerra civil y las Hermanas se hicieron cargo de las ambulancias en donde cuidaron a los heridos de ambos bandos, acto de abnegaci\u00f3n que les atrajo las simpat\u00edas de todos.<\/p>\n<p>En los a\u00f1os sucesivos continuaron al cuidado de los heridos de la guerra civil \u20141865-1867&#8211; y de los afectados por el c\u00f3lera. Varias Hermanas sucumbieron v\u00edctimas de esta epidemia. Entre 1860 y 1870, se abri\u00f3 un Seminario en La Plata.<\/p>\n<p>En 1890, la especulaci\u00f3n desencaden\u00f3 en Argentina, que cuenta con inmensas riquezas naturales, una crisis financiera de la que tard\u00f3 muchos a\u00f1os en reponerse y a costa de grandes esfuerzos. Por otra parte, en aquel final del siglo XIX, otro de los males que afectaban al pa\u00eds era la indiferencia religiosa por parte del pueblo. Esto explica que el clero, en su mayor parte, procediera de otros lugares: de Espa\u00f1a, Italia, Francia&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>En 1869, el General Mosquera, presidente de la Rep\u00fablica, pidi\u00f3 Hijas de la Caridad al Padre Etienne. Este puso como condici\u00f3n para dejar marchar a las Hermanas que fueran acompa\u00f1adas por Sacerdotes de la Misi\u00f3n. El Presidente no acept\u00f3 esta condici\u00f3n y las Hermanas no marcharon. Al no poder conseguir Hijas de la Caridad, el Presidente se dirigi\u00f3 a otra Comunidad cuyo nombre inclu\u00eda el de Hermanas de la Caridad.<\/p>\n<p>Los Sacerdotes de la Misi\u00f3n llegaron, por fin, a Colombia en 1870, y las Hermanas pudieron ir en 1882, pero, entonces, tuvieron que adoptar el nombre de \u00abVicentinas\u00bb.<\/p>\n<p>En 1885, se produjo un cambio de presidente al frente del pa\u00eds, con lo que mejoraron las relaciones con las Hijas de la Caridad, que pudieron extenderse por diferentes regiones, entre otras en la ocupada por los Indios Paeces.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>XVIII &#8211; A Bolivia <\/em><\/strong><em>(1883)<\/em><\/p>\n<p>A lo largo del siglo XIX, e decir, de 1809 a 1882, Bolivia \u2014conocida tambi\u00e9n por \u00abAlto Per\u00fa\u00bb\u2014 estuvo en continuas guerras, ya contra las naciones vecinas: Argentina y Chile, ya contra diferentes facciones rivales del mismo pa\u00eds.<\/p>\n<p>Las Hermanas llegaron a La Paz el 11 de junio de 1883, procedentes de Chile. Se las recibi\u00f3 con gran solemnidad: repique de campanas, gente ataviada con indumentaria de fiesta, flores arrojadas desde los balcones&#8230; Durante tres d\u00edas, fueron hu\u00e9spedes de honor en varias casas.<\/p>\n<p>Por fin, al d\u00eda siguiente se las llev\u00f3 a su vivienda: una casa, antiguo convento en que hab\u00edan residido otras religiosas. Entonces, una vez all\u00ed, tuvieron que gustar las espinas de las flores con que antes hab\u00edan sido obsequiadas. En general, puertas y ventanas brillaban por su ausencia. Varias habitaciones con el piso hundido imped\u00edan circular libremente por el resto de la casa. Tuvieron que improvisar las primeras instalaciones. A pesar de todo, apenas transcurrido un mes desde su llegada, ten\u00edan ya quince ni\u00f1as hu\u00e9rfanas.<\/p>\n<p>En 1904, se hicieron cargo del hospital de San Juan de Dios, en Puno, y abrieron, en esta ciudad, clases externas. Al orfanato de La Paz se a\u00f1adi\u00f3 una Cuna y una residencia de ancianos.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>XIX &#8211; A Honduras <\/em><\/strong><em>(1931)<\/em><\/p>\n<p>Honduras, Estado de Am\u00e9rica Central, se halla situado entre Guatemala y Nicaragua. Hasta 1821, estuvo incorporado a Guatemala. Despu\u00e9s, qued\u00f3 vincula\u00addo a las Provincias unidas de Am\u00e9rica Central, de 1824 a 1838, formando una Confederaci\u00f3n con el Salvador y Nicaragua de 1842 a 1844. Fueron frecuentes las luchas con los pa\u00cdses vecinos por reivindicaciones territoriales.<\/p>\n<p>Este pa\u00eds, que posee los bananales m\u00e1s importantes de Am\u00e9rica Central, tuvo que padecer fuertemente la influencia de la \u00abUnited Fruit Company\u00bb. Ocupado por los \u00abmarines\u00bb de 1911 a 1933, cay\u00f3 en una dictadura (1933-1949).<\/p>\n<p>Fue en 1931, durante el per\u00edodo de ocupaci\u00f3n por los \u00abmarines\u00bb, cuando las Hermanas llegaron al Hospital de Tegucigalpa, la capital, situada a mil cuatrocientos metros de altitud. Las acogi\u00f3 el Ministro del Interior, en representaci\u00f3n del Presidente. Despu\u00e9s de algunas dificultades en los comienzos, debidas a las calumnias de cierta pesonalidad, todo se apacigu\u00f3 y, en 1932, pudieron abrir otro Hospital en San Pedro Sula, al Noroeste del pa\u00eds. Durante la guerra civil (1933) que se sald\u00f3 con la dictadura, las Hermanas permanecieron serenas, entregadas al cumplimiento de su deber.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>XX &#8211; A Canada <\/em><\/strong><em>(1948)<\/em><\/p>\n<p>En la Provincia de Quebec, zona franc\u00f3fona, el obispo de Sherbrooke, Monse\u00f1or Desranleau, pidi\u00f3 y obtuvo Hijas de la Caridad para encargarse de una obra de adopci\u00f3n, que empez\u00f3 el 27 de marzo de 1948. Ya en 1841, se hab\u00eda cursado una primera petici\u00f3n, que no obtuvo resultados, al entonces Superior General, Padre Etienne.<\/p>\n<p>El 2 de octubre de 1948, otras tres Hermanas sal\u00edan de la Casa Madre para hacerse cargo del Hospital San Lucas, en el Centro minero de Ambestos, situado igualmente en la Provincia de Quebecz.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>XX &#8211; A Venezuela <\/em><\/strong><em>(1950)<\/em><\/p>\n<p>Situada en el extremo norte de Am\u00e9rica del Sur, Venezuela se vio asaltada por tremendas guerras civiles, combinadas con dictaduras m\u00e1s o menos eficaces, situaci\u00f3n que con el impulso de la producci\u00f3n petrol\u00edfera, llena casi por completo los a\u00f1os 1546 a 1964.<\/p>\n<p>En 1930, Monse\u00f1or Dubuc, Obispo de Barquisimeto, se aloj\u00f3 durante un viaje en el Seminario de San Juan, Puerto Rico, y qued\u00f3 maravillado por la formaci\u00f3n que en el mismo se daba a los Seminaristas. Esto le movi\u00f3 a pedir Sacerdotes de la Misi\u00f3n para su Seminario.<\/p>\n<p>Para hacerse cargo del Seminario Venezolano, se envi\u00f3 al P. Gaude, c.m., de Puerto Rico quien, en 1934, fue nombrado Visitador.<\/p>\n<p>Su amor a los Pobres le impulso a emprender numerosas gestiones para conseguir el establecimiento de las Hijas de la Caridad en Venezuela. All\u00ed se encuentran desde 1950, procedentes, sobre todo, de Colombia\u00bb.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>XXII &#8211; A Santo Domingo <\/em><\/strong><em>(1952)<\/em><\/p>\n<p>Al final del siglo XIX, en 1892, se hicieron tentativas, que no tuvieron resultado, para introducir, en Santo Domingo a las Hijas de la Caridad, procedentes de Puerto Rico.<\/p>\n<p>S\u00f3lo pudieron hacerlo en 1952, llegadas, efectivamente, de Puerto Rico. En 1965, Santo Domingo pas\u00f3 a ser Vice-Provincia de San Sebasti\u00e1n (Espa\u00f1a), y en 1967 qued\u00f3 erigida en Provincia aut\u00f3noma. El Seminario empez\u00f3 en 1970.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>XXIII &#8211; A Hait\u00ed <\/em><\/strong><em>(1973)<\/em><\/p>\n<p>Hait\u00ed forma parte del Archipi\u00e9lago de las Antillas Mayores, en el que comparte con la Rep\u00fablica Dominicana, la Isla La Espa\u00f1ola o Hispaniola. La lengua oficial es el franc\u00e9s, pero lo m\u00e1s corrientemente hablado por el pueblo es el criollo.<\/p>\n<p>La situaci\u00f3n sociopol\u00edtica del pa\u00eds es muy problem\u00e1tica y esto pone trabas a un verdadero desarrollo, a todos los niveles y bajo todos los aspectos.<\/p>\n<p>Las Hijas de la Caridad llegaron a Hait\u00ed en 1973, para dar respuesta a las llamadas urgentes de los Pobres. Fue a trav\u00e9s de la Provincia de Puerto Rico como la Compa\u00f1\u00eda se hizo all\u00ed presente.<\/p>\n<p>M\u00faltiples son las llamadas y m\u00faltiples tambi\u00e9n tratan de ser las formas de servicio que realizan las Hermanas: cuidados a los enfermos, ni\u00f1os abandonados, promo\u00adci\u00f3n de adultos, ense\u00f1anza, formaci\u00f3n religiosa, asistencia a las necesidades m\u00e1s elementales, acompa\u00f1ar o seguir a las personas en momentos dif\u00edciles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando San Vicente naci\u00f3 en 1581, no hab\u00edan transcurrido todav\u00eda cien a\u00f1os desde que Crist\u00f3bal Col\u00f3n hab\u00eda abordado aquel continente, que no sab\u00eda todav\u00eda que iba a llamarse \u00abAm\u00e9rica\u00bb. \u00bfPens\u00f3 San Vicente en enviar Misioneros &#8230; <a href=\"http:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":398522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[237],"tags":[168,161,144,147],"class_list":["post-72946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-de-las-hijas-de-la-caridad","tag-argel","tag-etienne","tag-lambert","tag-santo-domingo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La llegada de las Hijas de la Caridad al continente Americano (I) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La llegada de las Hijas de la Caridad al continente Americano (I) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Cuando San Vicente naci\u00f3 en 1581, no hab\u00edan transcurrido todav\u00eda cien a\u00f1os desde que Crist\u00f3bal Col\u00f3n hab\u00eda abordado aquel continente, que no sab\u00eda todav\u00eda que iba a llamarse \u00abAm\u00e9rica\u00bb. \u00bfPens\u00f3 San Vicente en enviar Misioneros ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-30T06:20:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1195\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"La llegada de las Hijas de la Caridad al continente Americano (I)\",\"datePublished\":\"2017-07-30T06:20:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/\"},\"wordCount\":4406,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/hijas-caridad.jpg?fit=1195%2C630\",\"keywords\":[\"Argel\",\"Etienne\",\"Lambert\",\"Santo Domingo\"],\"articleSection\":[\"Historia de las Hijas de la Caridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/\",\"name\":\"La llegada de las Hijas de la Caridad al continente Americano (I) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/hijas-caridad.jpg?fit=1195%2C630\",\"datePublished\":\"2017-07-30T06:20:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/hijas-caridad.jpg?fit=1195%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/hijas-caridad.jpg?fit=1195%2C630\",\"width\":1195,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La llegada de las Hijas de la Caridad al continente Americano (I)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La llegada de las Hijas de la Caridad al continente Americano (I) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/","og_locale":"es_ES","og_type":"article","og_title":"La llegada de las Hijas de la Caridad al continente Americano (I) - Somos Vicencianos","og_description":"Cuando San Vicente naci\u00f3 en 1581, no hab\u00edan transcurrido todav\u00eda cien a\u00f1os desde que Crist\u00f3bal Col\u00f3n hab\u00eda abordado aquel continente, que no sab\u00eda todav\u00eda que iba a llamarse \u00abAm\u00e9rica\u00bb. \u00bfPens\u00f3 San Vicente en enviar Misioneros ... Read More","og_url":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2017-07-30T06:20:17+00:00","og_image":[{"width":1195,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630&ssl=1","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"La llegada de las Hijas de la Caridad al continente Americano (I)","datePublished":"2017-07-30T06:20:17+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/"},"wordCount":4406,"commentCount":4,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630","keywords":["Argel","Etienne","Lambert","Santo Domingo"],"articleSection":["Historia de las Hijas de la Caridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/","url":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/","name":"La llegada de las Hijas de la Caridad al continente Americano (I) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630","datePublished":"2017-07-30T06:20:17+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630","width":1195,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/la-llegada-de-las-hijas-de-la-caridad-al-continente-americano-i\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"La llegada de las Hijas de la Caridad al continente Americano (I)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"http:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridad.jpg?fit=1195%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-iYy","jetpack-related-posts":[{"id":114848,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1014-lamberto-aux-couteaux-a-san-vicente\/","url_meta":{"origin":72946,"position":0},"title":"Vicente de Pa\u00fal, Carta 1014: Lamberto Aux Couteaux A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/11\/2012","format":false,"excerpt":"Nantes, 26 julio 1647. Padre: \u00a1Su bendici\u00f3n, por favor! Estamos a punto de partir de Nantes, despu\u00e9s de haber hecho todas las cosas que le voy a explicar. Puedo asegurarle que nuestras hermanas han estado muy agitadas; ciertamente, si han cometido algunas faltillas, la Providencia de Dios las ha puesto\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":122038,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1141-a-las-damas-de-la-caridad\/","url_meta":{"origin":72946,"position":1},"title":"Vicente de Pa\u00fal, Carta 1141: A Las Damas De La Caridad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/05\/2013","format":false,"excerpt":"[Fr\u00e9neville], 11 febrero 1649. Se\u00f1oras: La gracia de Nuestro Se\u00f1or sea siempre con nosotros. Aunque la providencia de Dios me ha alejado de ustedes, no dejo de verlas a ustedes con frecuencia en el santo altar y de ofrecerlas a ustedes y a sus familias a Nuestro Se\u00f1or, con la\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":128969,"url":"http:\/\/vincentians.com\/es\/momentos-de-descanso-ii\/","url_meta":{"origin":72946,"position":2},"title":"Momentos de descanso (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"18\/08\/2026","format":false,"excerpt":"Saint-Denis \u00a0Nantes y los Consejos Luisa pronto se olvid\u00f3 de Le Mans. En mayo de 1646, cuando tem\u00eda su fracaso, los administradores del Gran Hospital de Nantes pidieron Hijas de la Caridad. Hab\u00edan o\u00eddo c\u00f3mo en poco tiempo hab\u00edan reorganizado el Gran Hospital de Angers, hab\u00edan le\u00eddo el re\u00adglamento de\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=1050%2C600 3x"},"classes":[]},{"id":127035,"url":"http:\/\/vincentians.com\/es\/afianzar-la-compania\/","url_meta":{"origin":72946,"position":3},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"23\/01\/2024","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=1050%2C600 3x"},"classes":[]},{"id":387673,"url":"http:\/\/vincentians.com\/es\/afianzar-la-compania-2\/","url_meta":{"origin":72946,"position":4},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"17\/04\/2016","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"LOGO HHC","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/03\/LOGO-HHC.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387671,"url":"http:\/\/vincentians.com\/es\/la-direccion-de-la-compania-2\/","url_meta":{"origin":72946,"position":5},"title":"La direcci\u00f3n de la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"20\/04\/2016","format":false,"excerpt":"De nuevo, en Par\u00eds El 24 de febrero, Luisa se puso en camino hacia Par\u00eds. Trayecto pesado y largo de va\u00adrios d\u00edas. El se\u00f1or Abad de Vaux le prest\u00f3 su carroza; Luisa estaba d\u00e9bil y quer\u00eda seguir los consejos que le hab\u00eda dado el se\u00f1or Vicente de no volver por\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"Hijas de la Caridad","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/04\/Hijas-de-la-Caridad-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/72946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=72946"}],"version-history":[{"count":2,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/72946\/revisions"}],"predecessor-version":[{"id":400744,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/72946\/revisions\/400744"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398522"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=72946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=72946"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=72946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}