{"id":59209,"date":"2015-03-30T05:53:36","date_gmt":"2015-03-30T03:53:36","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=59209"},"modified":"2015-03-30T05:53:36","modified_gmt":"2015-03-30T03:53:36","slug":"evangelizacion-y-servicio","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/","title":{"rendered":"Evangelizaci\u00f3n y Servicio"},"content":{"rendered":"<p style=\"text-align: right\"><em>\u00abUstedes fueron fundadas \u00fanicamente para servir al mundo de los desheredados, de los \u00abpeque\u00f1os\u00bb.<\/em><br \/>\n<em>Yo les exhorto m\u00e1s que nunca a compartir la miseria del mundo contempor\u00e1neo&#8230;\u00bb<\/em><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/maria-discipula-1340x1008.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-142423\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/maria-discipula-1340x1008-300x226.jpg?resize=300%2C226\" alt=\"maria-discipula-1340x1008\" width=\"300\" height=\"226\" \/><\/a>Al escuchar los informes de los grupos, he podido percibir que ya se han dado muchas respuestas a esta cuesti\u00f3n, seg\u00fan la llamada del Papa. Por mi parte, me gustar\u00eda a\u00f1adir algunos puntos m\u00e1s que, acaso, puedan enriquecer la reflexi\u00f3n que han hecho ustedes.<\/p>\n<p>Las Hijas de la Caridad, por medio de un voto especial, se comprometen a servir a los Pobres, corporal y espiritualmente. Este voto nos es espec\u00edfico: es nuestra raz\u00f3n de ser. El voto de Servicio a Cristo en los Pobres es un acto de Amor afectivo y efectivo&#8230; (Cf. Conf. de S. Vicente y Const. 2.9). Por lo tanto, ha de haber en nosotras una preocupaci\u00f3n constante por todo el Hombre.<\/p>\n<p>La consagraci\u00f3n es el fundamento s\u00f3lido del Servicio a los Pobres y es la que le confiere su verdadero sentido. Por su parte, el Servicio a los Pobres especifica nuestra Consagraci\u00f3n. Nuestros votos ratifican el don o la entrega total a Dios, entrega que vivimos esencialmente en el Servicio a Cristo en los Pobres.<\/p>\n<p>Apoyada en esto, mi exposici\u00f3n va a detenerse en dos aspectos: Evangelizaci\u00f3n y Servicio, es decir, Servicio espiritual y corporal.<\/p>\n<p>Los \u00faltimos Documentos y Discursos del Santo Padre son claros e incisivos al afirmar que la Evangelizaci\u00f3n ha de tomar otra fisonom\u00eda, otro dinamismo, y en ese sentido, \u00e9l la llama: NUEVA EVANGELIZACION.<\/p>\n<h2>I. Nueva evangelizaci\u00f3n<\/h2>\n<p>La primera vez que el Papa se sirvi\u00f3 de esta expresi\u00f3n fue en el Encuentro del CELAM (Conferencia Episcopal Latino-Americana), en Puerto Pr\u00edncipe (Hait\u00ed), el 9 de marzo de 1983.<\/p>\n<p>Pronto, esta expresi\u00f3n: Nueva Evangelizaci\u00f3n pas\u00f3 a ser como una especie de \u00abeslogan\u00bb, sobre todo en los ambientes eclesiales de Am\u00e9rica Latina. Inicialmente, la propuesta hecha por el Papa de una nueva evangelizaci\u00f3n se limitaba a este continente, como preparaci\u00f3n a los 500 a\u00f1os de su \u00abdescubrimiento\u00bb y de su primera evangelizaci\u00f3n&#8230;<\/p>\n<p>Pero poco tiempo despu\u00e9s, Juan Pablo II preconiza una Nueva Evangelizaci\u00f3n para todo mundo, tambi\u00e9n como preparaci\u00f3n al III Milenio del Cristianismo. Se trata de dos fechas-s\u00edmbolos: 1992 y 2000, que han de ser consideradas y aprovechadas como un tiempo oportuno de gracia, de decisi\u00f3n y de mudanza en la forma de anunciar la Buena Nueva, como tambi\u00e9n de dar testimonio de ella con nuestra vivencia.<\/p>\n<h3>A \u2014 Caracter\u00edsticas de la nueva evangelizaci\u00f3n<\/h3>\n<p>A los participantes del CELAM, en Hait\u00ed, en 1983, Juan Pablo II les explicit\u00f3 con toda claridad tres caracter\u00edsticas de la Nueva Evangelizaci\u00f3n:<\/p>\n<ul>\n<li>Nueva, en su ardor (en su entusiasmo),<\/li>\n<li>Nueva en sus m\u00e9todos y<\/li>\n<li>Nueva en su expresi\u00f3n\u00bb.<\/li>\n<\/ul>\n<p>Pero en su Discurso est\u00e1 impl\u00edcita otra cuarta caracter\u00edstica: Nueva en sus sujetos: la urgencia que presentan los Pobres.<\/p>\n<p>\u00abLos m\u00e1s pobres tienen que tener un lugar de preferencia en vuestros corazones de \u00abpadres\u00bb y en vuestra solicitud de pastores\u00bb, les dijo el Papa a los Obispos all\u00ed reunidos. Al final, les record\u00f3 el Documento de Puebla y lo puso como baliza o como marco de una Nueva Evangelizaci\u00f3n para Am\u00e9rica Latina. Ahora bien, este Documento establece la \u00abOpci\u00f3n Preferencial por los Pobres\u00bb, no s\u00f3lo como objeto de la Acci\u00f3n Eclesial, sino como Sujetos de la Evangelizaci\u00f3n.<\/p>\n<p>En sus diversas alocuciones, el Papa menciona los Desaf\u00edos, las Tentaciones, las Esperanzas y las Exigencias de la Nueva Evangelizaci\u00f3n.<\/p>\n<p>1. Desaf\u00edos que presenta el momento hist\u00f3rico de la Nueva Evangelizaci\u00f3n.<\/p>\n<ul>\n<li>La escasez de agentes, es decir de evangelizadores seglares debidamente cualificados;<\/li>\n<li>La secularizaci\u00f3n de la sociedad, que propone valores diferentes de los que presenta el Evangelio;<\/li>\n<li>El contratestimonio de algunos cristianos; ciertas divisiones que se dan en la Iglesia;<\/li>\n<li>El clamor de una urgente Justicia;<\/li>\n<li>La corrupci\u00f3n en la vida p\u00fablica, los conflictos armados, la falta de sentido \u00e9tico;<\/li>\n<li>La falta de solidaridad entre las Naciones.<\/li>\n<\/ul>\n<p>2. Tentaciones contra la vocaci\u00f3n cristiana, que desfiguran el rostro del hombre.<\/p>\n<ul>\n<li>B\u00fasqueda de modelos sociales que prescinden de la vocaci\u00f3n cristiana y de sus valores;<\/li>\n<li>Intento de hacer de la Fe una ideolog\u00eda, debilitando as\u00ed la Comuni\u00f3n Eclesial. En la misma l\u00ednea, promover la difusi\u00f3n de las sectas religiosas.<\/li>\n<li>B\u00fasqueda de soluciones con la fuerza de las armas o con la opresi\u00f3n ideol\u00f3gica, o tambi\u00e9n, hacerse \u00eddolos de la riqueza y del placer;<\/li>\n<li>Uso de las drogas y de la permisividad pornogr\u00e1fica, factores que causan el debilitamiento de la fibra moral y de la Esperanza de los Pobres;<\/li>\n<li>Campa\u00f1as contra la vida;<\/li>\n<li>Interferencia de Potencias que tratan de imponer sus intereses y sus ideolog\u00edas, manteniendo a las Naciones Pobres bajo su dependencia.<\/li>\n<\/ul>\n<p>En la Enc\u00edclica Centesimus Annus, Juan Pablo II explica con claridad que, aprovechando la ca\u00edda del comunismo, el capitalismo liberal podr\u00eda verse inclinado a desarrollar de nuevo y con m\u00e1s vigor sus aspectos negativos de explotaci\u00f3n del hombre por el hombre.<\/p>\n<p>Adem\u00e1s de esto, una de las tentaciones m\u00e1s sutiles para los pa\u00edses del Este sobre todo, s\u00ed ser\u00eda de manera especial la de no saber resistir a la atracci\u00f3n del materialismo capitalista, despu\u00e9s de haber conocido los horrores del materialismo marxista.<\/p>\n<p>3. Esperanzas de la Nueva Evangelizaci\u00f3n<\/p>\n<ul>\n<li>La de una Iglesia unida en su Misi\u00f3n Evangelizadora;<\/li>\n<li>La del crecimiento de las vocaciones en algunos pa\u00edses;<\/li>\n<li>La de una Iglesia fuertemente empe\u00f1ada en la Catequesis;<\/li>\n<li>La de los J\u00f3venes, que quieren dar nuevo vigor a su fidelidad a Dios y a su pueblo;<\/li>\n<li>La de un laicado comprometido en su Misi\u00f3n Eclesial y en su papel en el mundo;<\/li>\n<li>La de los Movimientos de Trabajadores que luchan por conseguir condiciones m\u00e1s dignas de vida y de trabajo;<\/li>\n<li>La de los sectores intelectuales que empiezan a reencontrar valores \u00e9ticos y culturales en el pueblo.<\/li>\n<\/ul>\n<p>4. Exigencias para la eficacia de la Nueva Evangelizaci\u00f3n<\/p>\n<ul>\n<li>Invertir lo mejor de las energ\u00edas en la construcci\u00f3n de verdaderas comunidades cristianas, como la de los primeros hermanos en la Fe, sobre todo en el estilo de vida evang\u00e9lico: en el compartir, en la vivencia plena de la Eucarist\u00eda;<\/li>\n<li>Todos los bautizados deben sentirse miembros vivos de la Iglesia y comprometidos en su Misi\u00f3n;<\/li>\n<li>Formaci\u00f3n constante de los Evangelizadores y de los Evangelizados: una formaci\u00f3n integrante e integral &#8211; cultural, profesional, doctrinal, espiritual y apost\u00f3lica;<\/li>\n<li>Espiritualidad basada en la fidelidad a la Palabra de Dios, fidelidad al hombre y a su historia, en la cual prosigue la acci\u00f3n del Esp\u00edritu Santo.<\/li>\n<\/ul>\n<h3>B &#8211; Nueva evangelizaci\u00f3n y \u00abopci\u00f3n preferencial por los pobres\u00bb<\/h3>\n<p>Adem\u00e1s de ser una constante en la tradici\u00f3n b\u00edblica y eclesial, la \u00abOpci\u00f3n preferencial por los Pobres\u00bb constituye uno de los aspectos m\u00e1s importantes de la Nueva Evangelizaci\u00f3n.<\/p>\n<p>La predilecci\u00f3n de la Iglesia por los Pobres le viene de Cristo. Es una caracter\u00edsica de la espiritualidad cristiana, que vivieron las primeras comunidades cristianas y tantos Fundadores de Congregaciones o Sociedades de Vida Apost\u00f3lica, como tambi\u00e9n lo hicieron San Vicente y Santa Luisa al fundar la Compa\u00f1\u00eda de las Hijas de la Caridad, cuyo carisma bien conocemos: El servicio a Cristo en los pobres.<\/p>\n<p>Hoy, la vida consagrada s\u00f3lo tiene sentido si es prof\u00e9tica y fiel de manera creativa a su carisma vocacional&#8230; si vive en escucha permanente a las manifestaciones de Dios en el mundo, a las llamadas de los Pobres y de la Iglesia, en las diversas situaciones del actual contexto hist\u00f3rico.<\/p>\n<p>La Nueva Evangelizaci\u00f3n reafirma la preferencia evang\u00e9lica por los Pobres, sin complejos y sin miedos, pues esa predilecci\u00f3n dimana de la Revelaci\u00f3n b\u00edblica. Las motivaciones de esta Opci\u00f3n deben fundamentarse en la Fe, en la Esperanza y en el Amor, a imitaci\u00f3n de Cristo.<\/p>\n<p>El punto de arranque de la Opci\u00f3n preferencial por los Pobres, como todos saben, se encuentra en Medell\u00edn y Puebla. No obstante, \u00faltimamente se percibe cierto debilitamiento en la pr\u00e1ctica pastoral de la Iglesia con relaci\u00f3n a esta Opci\u00f3n preferencial, tal como la entend\u00eda Puebla; pero el Papa insiste de continuo en ella ante las Conferencias Episcopales, como ya hemos visto.<\/p>\n<p>Ya San Vicente nos dec\u00eda:<\/p>\n<p>\u00abLos pobres son nuestros se\u00f1ores y maestros\u00bb.<\/p>\n<p>Y esto no es pura ret\u00f3rica. Los Pobres realmente nos evangelizan y convierten, como el mismo San Vicente lo experiment\u00f3. La Nueva Evangelizaci\u00f3n ha de reconocer el potencial evangelizador que existe en los Pobres: su saber compartir la Fe, su solidaridad, su servicio, su sencillez, su disponibilidad, su manera de acoger la Palabra de Dios y la del hermano. Los pobres evangelizan tambi\u00e9n con su propia existencia, su clamor, las \u00abpeque\u00f1as liberaciones y conquistas\u00bb que consiguen a trav\u00e9s de diversas Organizaciones&#8230; Es cierto que no se puede caer en el extremo de idealizar al Pobre en su potencial evang\u00e9lico. Pero la verdad nos obliga a reconocer que representan una riqueza moral, con frecuencia desconocida&#8230;<\/p>\n<p style=\"text-align: center\">* * *<\/p>\n<p>Una vez hecha esta breve exposici\u00f3n, a modo de s\u00edntesis, vuelvo al Tema de la Asamblea General de 1991:<\/p>\n<p>\u00abLa hija de la Caridad en el mundo y para el mundo de hoy\u00bb.<\/p>\n<p>Y me refiero tambi\u00e9n a la Alocuci\u00f3n del Santo Padre dirigida a los miembros de la misma Asamblea, a los que dio un nuevo \u00abEnv\u00edo a Misi\u00f3n\u00bb con estas palabras:<\/p>\n<p>\u00abQueridas Hermanas, en nombre de Cristo y de la Iglesia, me atrevo a movilizarlas de nuevo en favor del mundo inmenso y tan diverso de la pobreza\u00bb.<\/p>\n<p>Entonces, surge sin duda en nuestros corazones esta preguntar. C\u00f3mo ir a ese mundo de los Pobres, con la identidad propia de la Hija de la Caridad, en un proceso din\u00e1mico y renovado?<\/p>\n<p>Y la respuesta a esta pregunta nos lleva a hablar del servicio. L\u00f3gicamente, en la pr\u00e1ctica no se separan Evangelizaci\u00f3n y Servicio: ambos son inseparables. Pero, a efectos did\u00e1cticos, hemos de abordar uno tras otro.<\/p>\n<h2>II. Servicio<\/h2>\n<p>La Hija de la Caridad, a imitaci\u00f3n de los doce Ap\u00f3stoles, intenta ser fiel al seguimiento de Cristo, prolongando en el mundo su presencia de SERVIDOR. Asume el vivir su carisma de una forma creativa y original, en un continuo esfuerzo de fidelidad al Evangelio y a las Constituciones, con una actitud de sierva.<\/p>\n<p>La experiencia que San Vicente y Santa Luisa tuvieron junto a los Pobres, a los que prestaron las m\u00e1s diversas formas de servicio corporal y espiritual, sigue siendo de toda actualidad, porque esta inspiraci\u00f3n de los Fundadores tiene su origen en el Evangelio.<\/p>\n<p>Para nosotras, esa experiencia consiste, precisamente, en saber unir Evangelizaci\u00f3n y Servicio, en un proceso din\u00e1mico y con una presencia prof\u00e9tica, frente a la realidad en la que hoy vive el Pobre.<\/p>\n<p>\u00abLa iniciativa nace del Amor\u00bb, dec\u00eda Madre Rog\u00e9, y puede, por lo tanto, desaparecer con la rutina. El peligro para una Hija de la Caridad es el de que tenga una mirada y un coraz\u00f3n acostumbrados a lo que vive, a lo que ve, a lo que hace. De ah\u00ed, la necesidad de las revisiones apost\u00f3licas.<\/p>\n<p>Son tres los pilares que sustentan nuestra actitud de SIERVAS:<\/p>\n<p>1) La contemplaci\u00f3n del misterio de un Dios hecho hombre &#8211; Pobre, Solidario y Servidor;<\/p>\n<p>2) La convicci\u00f3n de la necesidad de una continua conversi\u00f3n para seguir a Cristo Libertador y Siervo;<\/p>\n<p>3. El esfuerzo por descubrir, en Fe, el rostro de Cristo en el Pobre: en el enfermo de Sida, en el ni\u00f1o de la calle, en el analfabeto, el marginado, etc.<\/p>\n<p>La vivencia diaria de nuestro ser siervas tiene sus exigencias y se traduce en gestos concretos y en ciertas actitudes.<\/p>\n<p>Voy a citar solamente algunas de \u00e9stas, entre tantas otras:<\/p>\n<h2>III. Actitudes<\/h2>\n<h3>Disponibilidad para un verdadero servicio<\/h3>\n<p>Dec\u00eda Madre ROG\u00c9: \u00abNo se puede poner en marcha ning\u00fan Proyecto Comunitario, local o provincial, no se puede alcanzar ninguna perspectiva misionera, si cada sierva, es decir, cada Hermana, hace lo que quiere y como quiere&#8230;<\/p>\n<p>Una vez que se han comprometido libremente a servir a Cristo, su entrega debe ser \u00absin retorno\u00bb, la entrega de una sierva humilde, pobre y disponible\u00bb (Ecos n.911 &#8211; noviembre 1976, p. 429)<\/p>\n<p>Y contin\u00faa Madre Rog\u00e9:<\/p>\n<p>\u00abLa verdadera sierva &#8216;comulga&#8217; con la vida de su Amo. Cuanto m\u00e1s desprovisto de todo sea \u00e9ste, tanto m\u00e1s querr\u00e1 ella estar a su servicio. Est\u00e1 obligada por vocaci\u00f3n, seg\u00fan dec\u00eda San Vicente, a servir a los m\u00e1s miserables, a los m\u00e1s abandonados, a los m\u00e1s destrozados por la miseria corporal o espiritual&#8230;\u00bb (Idem).<\/p>\n<p>Esto lleva consigo la necesidad de unas actitudes de:<\/p>\n<ul>\n<li>acogida al Pobre, con una gran sensibilidad respecto a sus derechos;<\/li>\n<li>escucha y di\u00e1logo, con el fin de llegar a descubrir sus valores y ayudarle a tomar conciencia de su potencial;<\/li>\n<li>respeto a sus derechos humanos, ayud\u00e1ndole a tomar conciencia tambi\u00e9n de ellos, dentro de la justicia;<\/li>\n<li>solidaridad, tomando parte en su vida, sus dificultades, sus luchas, alent\u00e1ndole a desarrollar su potencial humano, tanto tiempo sin explotar, con miras a su auto-promoci\u00f3n;<\/li>\n<li>Fe, que permita llevarles alegr\u00eda y esperanza, ante la seguridad de que Dios los ama;<\/li>\n<li>oraci\u00f3n encarnada en la vida, rezando con ellos y por ellos. El mundo de hoy, cada vez m\u00e1s desenganado en su busca del placer, en la evasi\u00f3n de la droga, en el desatino del terrorismo, experimenta una gran sed de Dios y de los valores espirituales.<\/li>\n<\/ul>\n<p>Por \u00faltimo, las Constituciones (2. 9) nos dicen: \u00abCualesquiera sean su forma de trabajo y su nivel profesional, se mantienen ante los Pobres en una actitud de siervas, es decir, en la puesta en pr\u00e1ctica de las virtudes de su estado: humildad, sencillez y caridad. Tienen especial empe\u00f1o en conservar el desinter\u00e9s del coraz\u00f3n y el sentido de la gratuidad, que se manifiestan en el esp\u00edritu de su servicio y en la calidad de su presencia\u00bb.<\/p>\n<p>El Documento InterAsambleas y las reflexiones de la misma Asamblea de 1991 presentan algunas l\u00edneas de acci\u00f3n encaminadas a hacer de nosotras constructoras de la Nueva Evangelizaci\u00f3n y de la promoci\u00f3n plena del hombre, mediante la vivencia de la Justicia y del Amor; nos indican tambi\u00e9n c\u00f3mo mantenernos en la postura de Siervas, al recomendarnos:<\/p>\n<ul>\n<li>Reservar tiempos fuertes de oraci\u00f3n, como alimento de nuestra acci\u00f3n;<\/li>\n<li>Reservarnos tiempos fuertes en Comunidad, para infundir dinamismo a la vida fraterna, vivida con alegr\u00eda, sabiendo compartir, todo ello como exigencia de la Misi\u00f3n;<\/li>\n<li>Reservar tiempo para la formaci\u00f3n personal y comunitaria, para estar al corriente de lo que ocurre en la sociedad y en la Iglesia con el objetivo de ayudar a los Pobres y empobrecidos, a defender sus derechos, sin apartarse del amor y la justicia;<\/li>\n<li>Cuestionarnos acerca de las prioridades y proseguir con audacia y creatividad la revisi\u00f3n de Obras y actividades;<\/li>\n<li>Emprender con valent\u00eda la reforma de nuestro estilo de vida, buscando la cercan\u00eda a los Pobres, content\u00e1ndonos con lo necesario y rechazando lo superfluo;<\/li>\n<li>Tomar a Mar\u00eda como modelo de disponibilidad, de Sierva, en nuestro caminar diario y como \u00abEstrella de la Evangelizaci\u00f3n para todos los pueblos, llev\u00e1ndoles la alegr\u00eda, la Fe y la Esperanza\u00bb. (Cf. Juan Pablo II);<\/li>\n<li>Dar nuevo impulso a la Pastoral Vocacional, haci\u00e9ndola din\u00e1mica y creativa, con el fin de formar nuevas Siervas para el Servicio a los Pobres.<\/li>\n<\/ul>\n<p>Y respecto a este punto, conviene que nos cuestionemos:<\/p>\n<ul>\n<li>\u00bfPerciben las j\u00f3venes que estamos plenamente convencidas de nuestra Vocaci\u00f3n de Hijas de la Caridad?<\/li>\n<li>\u00bfNos ven como personas consagradas que dan testimonio de Alegr\u00eda, de Fraternidad, de Amor y Ternura hacia los Pobres?<\/li>\n<li>\u00bfNos ven rezar?<\/li>\n<li>Por nuestra parte, como Hijas de la Caridad, \u00bfcreemos en la Pastoral Vocacional y en sus frutos?<\/li>\n<\/ul>\n<p>\u00abHay que creer en lo que se hace y hacerlo con entusiasmo\u00bb. El Due\u00f1o de la Mies sigue llamando Obreros para su Cosecha&#8230;<\/p>\n<h2>Conclusi\u00f3n<\/h2>\n<p>Me gustar\u00eda poner fin a esta exposici\u00f3n con las palabras del mismo Cristo que, a mi modo de ver, trazan un programa de vida para la Hija de la Caridad, Sierva:<\/p>\n<p>\u00abOs he dado ejemplo, para que tambi\u00e9n vosotros hag\u00e1is como yo he hecho con vosotros. En verdad, en verdad os digo: No es el siervo mayor que su se\u00f1or, ni el enviado mayor que quien le env\u00eda. Dichosos vosotros si practic\u00e1is estas cosas que sab\u00e9is&#8230;\u00bb (Jn. 13, 15-17).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abUstedes fueron fundadas \u00fanicamente para servir al mundo de los desheredados, de los \u00abpeque\u00f1os\u00bb. Yo les exhorto m\u00e1s que nunca a compartir la miseria del mundo contempor\u00e1neo&#8230;\u00bb Al escuchar los informes de los grupos, he &#8230; <a href=\"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":142423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226,199],"tags":[172],"class_list":["post-59209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","category-hijas-de-la-caridad","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evangelizaci\u00f3n y Servicio - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evangelizaci\u00f3n y Servicio - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"\u00abUstedes fueron fundadas \u00fanicamente para servir al mundo de los desheredados, de los \u00abpeque\u00f1os\u00bb. Yo les exhorto m\u00e1s que nunca a compartir la miseria del mundo contempor\u00e1neo&#8230;\u00bb Al escuchar los informes de los grupos, he ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-30T03:53:36+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Evangelizaci\u00f3n y Servicio\",\"datePublished\":\"2015-03-30T03:53:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/\"},\"wordCount\":2847,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Espiritualidad vicenciana\",\"Hijas de la Caridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/\",\"name\":\"Evangelizaci\u00f3n y Servicio - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-30T03:53:36+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/evangelizacion-y-servicio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evangelizaci\u00f3n y Servicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evangelizaci\u00f3n y Servicio - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/","og_locale":"es_ES","og_type":"article","og_title":"Evangelizaci\u00f3n y Servicio - Somos Vicencianos","og_description":"\u00abUstedes fueron fundadas \u00fanicamente para servir al mundo de los desheredados, de los \u00abpeque\u00f1os\u00bb. Yo les exhorto m\u00e1s que nunca a compartir la miseria del mundo contempor\u00e1neo&#8230;\u00bb Al escuchar los informes de los grupos, he ... Read More","og_url":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-30T03:53:36+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Evangelizaci\u00f3n y Servicio","datePublished":"2015-03-30T03:53:36+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/"},"wordCount":2847,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#primaryimage"},"thumbnailUrl":"","keywords":["Pobreza"],"articleSection":["Espiritualidad vicenciana","Hijas de la Caridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/","url":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/","name":"Evangelizaci\u00f3n y Servicio - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-30T03:53:36+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/evangelizacion-y-servicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Evangelizaci\u00f3n y Servicio"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-foZ","jetpack-related-posts":[{"id":119636,"url":"http:\/\/vincentians.com\/es\/identidad-de-la-compania-de-las-hijas-de-la-caridad\/","url_meta":{"origin":59209,"position":0},"title":"Identidad de la Compa\u00f1\u00eda de las Hijas de la Caridad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/11\/2022","format":false,"excerpt":"Introducci\u00f3n San Vicente estaba convencido de que, con la fundaci\u00f3n de la Compa\u00f1\u00eda de las Hijas de la Caridad, Dios hab\u00eda suscitado algo nuevo en la Iglesia. Y esa novedad no estaba s\u00f3lo en el fin de la Compa\u00f1\u00eda (servir a Cristo en los pobres); ni tampoco en el estilo\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Hijas-de-la-Caridad.jpg?fit=400%2C300&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":134894,"url":"http:\/\/vincentians.com\/es\/apostoles-de-la-caridad\/","url_meta":{"origin":59209,"position":1},"title":"\u00abAp\u00f3stoles de la Caridad\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/01\/2015","format":false,"excerpt":"\"Los pobres en el centro\", \"volver a partir desde los \u00faltimos\": son algunos de los dichos en uso en la Iglesia durante los a\u00f1os del Concilio Ecum\u00e9nico Vaticano II y despu\u00e9s. Partiendo del presupuesto de que la pobreza es el signo de la Encarnaci\u00f3n y lo debe ser, por consiguiente,\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"apostoles caridad","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/apostoles-caridad-300x196.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387673,"url":"http:\/\/vincentians.com\/es\/afianzar-la-compania-2\/","url_meta":{"origin":59209,"position":2},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"17\/04\/2016","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abEspiritualidad\u00bb","block_context":{"text":"Espiritualidad","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/"},"img":{"alt_text":"LOGO HHC","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/03\/LOGO-HHC.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387836,"url":"http:\/\/vincentians.com\/es\/los-votos-nos-afianzan-en-el-seguimiento-de-jesus\/","url_meta":{"origin":59209,"position":3},"title":"Los votos nos afianzan en el seguimiento de Jes\u00fas","author":"Mitxel Olabu\u00e9naga","date":"29\/09\/2016","format":false,"excerpt":"Al margen de la historia de los votos y de las cuestio\u00adnes jur\u00eddicas que \u00e9stos puedan suscitar, el Fundador de la Misi\u00f3n se mostr\u00f3 partidario de seguir a Jes\u00fas viviendo la entrega total y radical a Dios por medio de votos. Su experiencia religiosa as\u00ed lo confirma. La promesa que\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/07\/asd-8-248x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":127035,"url":"http:\/\/vincentians.com\/es\/afianzar-la-compania\/","url_meta":{"origin":59209,"position":4},"title":"Afianzar la Compa\u00f1\u00eda","author":"Mitxel Olabu\u00e9naga","date":"23\/01\/2024","format":false,"excerpt":"Los votos Durante el verano de 1640, mientras Luisa organizaba las comunidades de Angers y de los ni\u00f1os abandonados y se preocupaba de los galeotes, no olvidaba avanzar en las es\u00adtructuras de la Compa\u00f1\u00eda. Estaba convencida de que las Hijas de la Caridad formaban bastante m\u00e1s que una simple cofrad\u00eda;\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=1050%2C600 3x"},"classes":[]},{"id":134948,"url":"http:\/\/vincentians.com\/es\/los-votos-no-religiosos-y-el-habito-como-las-campesinas\/","url_meta":{"origin":59209,"position":5},"title":"Los votos \u00abno religiosos\u00bb y el h\u00e1bito \u00abcomo las campesinas\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/01\/2015","format":false,"excerpt":"Al tratar del car\u00e1cter secular de las Hijas de la Caridad (c. III), he afirmado que los Fundadores, en orden a salvaguardar la identidad, evitaron cuidadosamente cuanto era propio de la vida religiosa: votos, h\u00e1bito, terminolog\u00eda, usos, como rejas en el locutorio, cambio del nombre del bautismo, etc. \u00bfC\u00f3mo, entonces,\u2026","rel":"","context":"En \u00abHijas de la Caridad\u00bb","block_context":{"text":"Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/ramas\/hijas-de-la-caridad\/"},"img":{"alt_text":"guardame","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/guardame-300x246.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/59209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=59209"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/59209\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=59209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=59209"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=59209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}