{"id":54880,"date":"2015-02-16T08:59:16","date_gmt":"2015-02-16T07:59:16","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=54880"},"modified":"2015-02-16T08:59:16","modified_gmt":"2015-02-16T07:59:16","slug":"pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/","title":{"rendered":"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/pobres.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-139919\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/pobres-1024x406.jpg?resize=846%2C335\" alt=\"pobres\" width=\"846\" height=\"335\" \/><\/a><\/p>\n<p>Los pobres son nuestros \u00abamos\u00bb y debemos servirles como a tales. Son tambi\u00e9n nuestros <em>\u00abmaestros\u00bb y, <\/em>como tales, nos ense\u00f1an; por tanto, hemos de aprender de ellos.<\/p>\n<p>Esta es, no lo dudemos, una impor\u00adtante dimensi\u00f3n de nuestro enfoque de la pobreza evang\u00e9lica y de nuestro modo de vivirla. San Vicente, al invitar a sus cohermanos a que pidieran por la paz, en un momento particularmente tr\u00e1gico, en el que los \u00abpr\u00edncipes cristia\u00adnos\u00bb se destrozaban entre ellos en de\u00adtrimento de las masas populares, es\u00adcrib\u00eda:<\/p>\n<p><em>\u00abiOh Salvador! i0h Salvador! Si por cua\u00ad<\/em><em>tro meses que hemos tenido la guerra <\/em><em>encima hemos tenido tanta miseria en el <\/em><em>coraz\u00f3n de Francia, donde los v\u00edveres <\/em><em>abundaban por doquier, \u00bfqu\u00e9 har\u00e1n esas pobres gentes de la frontera, que llevan sufriendo esas miserias desde hace vein\u00adte a\u00f1os? S\u00ed, hace veinte a\u00f1os que est\u00e1n continuamente en guerra; s\u00ed siembran, no est\u00e1n seguros de poder cosechar; vie\u00adnen los ej\u00e9rcitos y los saquean y lo roban todo; y lo que no han robado los solda\u00addos, los alguaciles lo cogen y se lo lle\u00advan. Despu\u00e9s de todo esto, \u00bfqu\u00e9 hacer?, \u00bfqu\u00e9 pasar\u00e1? No queda m\u00e1s que morir.<\/em><\/p>\n<p><em>Si existe una religi\u00f3n verdadera&#8230;, \u00bfqu\u00e9 <\/em><em>es lo que digo, miserable?&#8230;, isi existe <\/em><em>una religi\u00f3n verdadera! iDios me lo per\u00ad<\/em><em>done! Hablo materialmente. <\/em>Es entre ellos, entre esa pobre gente, donde se conserva la verdadera religi\u00f3n, la fe viva. <em>Creen sencillamente, sin hurgar; su\u00admisi\u00f3n a las \u00f3rdenes, paciencia en las miserias que hay que sufrir mientras Dios quiera, unos por las guerras, otros por trabajar todo el d\u00eda bajo el ardor del sol; pobres vi\u00f1adores que nos dan su trabajo, que esperan que recemos por ellos, mientras que ellos se fatigan por alimentarnos&#8230; <\/em>(Coste XI, 200; S\u00edg. XI\/3, 120).<\/p>\n<p>De este cuadro que ciertamente no podr\u00edamos hacer nuestro hoy sin algu\u00adnos matices, tengamos en cuenta sobre todo esta invitaci\u00f3n a dejarnos interpe\u00adlar por los pobres y, en particular, a exa\u00adminar bajo esta luz nuestra propia vida de pobreza. En efecto, \u00bfqu\u00e9 ocurrir\u00eda a la Compa\u00f1\u00eda y a los mismos pobres sin esta pobreza?<\/p>\n<p><em>\u00abTengo miedo, mis queridas Herma\u00ad<\/em><em>nas, de que se llegue a faltar en este <\/em><em>punto, pues entonces habr\u00eda que temer <\/em><em>que pereciera esta obra. He pensado mu\u00ad<\/em><em>chas veces en qu\u00e9 es lo que podr\u00eda cau\u00ad<\/em><em>sar este mal y producir esta devastaci\u00f3n: <\/em><em>que no se viera ya en Par\u00eds a tantas v\u00edr\u00ad<\/em><em>genes y viudas yendo a visitar a los po\u00ad<\/em><em>bres; de d\u00f3nde podr\u00eda venir que no se <\/em><em>viera ya en esta ciudad a esas personas llevando el puchero de los pobres enfer\u00ad<\/em><em>mos. Y solamente se me ha ocurrido <\/em><em>pensar como causa el que se empezara a retener algo del dinero de los pobres. No es que no haya otros cr\u00edmenes que pu\u00addieran echar abajo esta obra, pero \u00e9ste es de los principales. iQu\u00e9 desgracia si se dieran motivos para decir que las Hi\u00adjas de la Caridad son ladronas del bien de los pobres, que son unas granujas, que han querido apropiarse del dinero de los pobres con el pretexto de servirles, que no hay que fiarse de ellas y que son unas malas personas! Mis queridas Her\u00admanas, si se llegara a eso, habr\u00eda que de\u00adcir adi\u00f3s a la Caridad\u00bb <\/em>(Coste X, 216; Conf. Esp. n\u00fam. 1 553).<\/p>\n<p>Aprendamos, pues, como disc\u00edpulas d\u00f3ciles, de estos maestros terriblemen\u00adte exigentes que son los pobres.<\/p>\n<h2><strong>1. Maestros exigentes<\/strong><\/h2>\n<p>Si los pobres son nuestros maestros y maestros tan exigentes, es esencialmente \u2014dentro de una \u00f3ptica evang\u00e9lica\u2014 porque nos remiten a ese Maestro, tambi\u00e9n terri\u00adblemente exigente, que es Jesucristo.<\/p>\n<h3>A. <strong>Nuestros maestros&#8230; <\/strong><strong>\u00bfPor qu\u00e9?<\/strong><\/h3>\n<p>Se trata, pues, de una \u00fanica y de una\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 misma actitud: aprender de los pobres y aprender de Cristo, como los primeros cristianos lo comprendieron tan bien.<\/p>\n<h4><strong>1) \u00abBienaventurados los Pobres\u00bb<\/strong><\/h4>\n<p>Repitamos que la pobreza que tene\u00admos que vivir, es ante todo, un esp\u00edritu, el que Jes\u00fas ha beatificado. Es tambi\u00e9n una pobreza de hecho: Jes\u00fas quiso vi\u00advirla personalmente, compartiendo la vida de los pobres. Quer\u00eda estar total\u00admente dedicado a \u00ablas cosas de su Pa\u00addre\u00bb y dependiente de El con una con\u00adfianza total: <em>\u00abNo and\u00e9is preocupados por <\/em><em>vuestra vida&#8230; \u00bfNo vale m\u00e1s la vida que <\/em><em>el alimento, y el cuerpo m\u00e1s que el vesti\u00ad<\/em><em>do?&#8230; Ya sabe vuestro Padre celestial <\/em><em>que ten\u00e9is necesidad de todas esas co\u00ad<\/em><em>sas. Buscad primero su Reino y su justi\u00ad<\/em><em>cia\u00bb <\/em>(Mat. VI-25 y ss.).<\/p>\n<p>A este discurso que dirige a todos, Jes\u00fas a\u00f1ade exigencias particulares para los que quieren seguirle m\u00e1s de cerca: <em>\u00abSi quieres ser perfecto, vete, ven\u00ad<\/em><em>de lo que tienes y d\u00e1selo a los pobres, y <\/em><em>tendr\u00e1s un tesoro en los cielos; luego <\/em><em>ven y s\u00edgueme\u00bb <\/em>(Mat. XIX, 21).<\/p>\n<p>As\u00ed pues, la pobreza no es solamente un estado; lleva a los actos, lleva a dar y sobre todo a darse. De tal modo que el estado de privaci\u00f3n es una conse\u00adcuencia del don. Por ejemplo, puede uno privarse del fruto del propio trabajo, d\u00e1ndolo a otros.<\/p>\n<p>Los pobres a quienes Jes\u00fas proclama \u00abbienaventurados\u00bb son los que santifi\u00adcan su pobreza; las pruebas materiales y espirituales les han acostumbrado a no contar m\u00e1s que con Dios, dentro de la tradici\u00f3n de los salmos: <em>\u00abCuanto a m\u00ed <\/em><em>pobre y menesteroso, mi Se\u00f1or cuidar\u00e1 de m\u00ed\u00bb <\/em>(Salmo XL, 1 8).<\/p>\n<p>Jes\u00fas \u00abevangeliz\u00f3 a los pobres\u00bb, en primer lugar, seg\u00fan la profec\u00eda de Isa\u00edas, asegur\u00e1ndoles que poseen ya (y no solamente que poseer\u00e1n) en su co\u00adraz\u00f3n los verdaderos bienes, los bienes del Reino con los que se identifica El mismo: <em>\u00abSe anuncia a los pobres la Bue\u00ad<\/em><em>na Nueva\u00bb <\/em>(Mat. XI, 5). Este anuncio es, juntamente con los milagros, el signo de su misi\u00f3n mesi\u00e1nica.<\/p>\n<p>Pero Jes\u00fas no proclam\u00f3 bienaventu\u00adrada la pobreza material como tal. Al contrario, <em>\u00abcon el fin de que no haya nin\u00ad<\/em><em>g\u00fan pobre junto a ti\u00bb, <\/em>ordena el Deutero\u00adnomio (XV, 4); pero el texto dice m\u00e1s adelante: <em>\u00abCiertamente nunca faltar\u00e1n <\/em><em>pobres en este pa\u00eds; por eso te doy yo este mandamiento: debes abrir tu mano <\/em><em>a tu hermano, a aquel de los tuyos que <\/em><em>es indigente y pobre en tu tierra.\u00bb <\/em>Cristo recordar\u00e1 este texto y le dar\u00e1 otro al\u00adcance que est\u00e1 en el centro de nuestra vocaci\u00f3n: <em>\u00abPorque pobres tendr\u00e9is siem\u00ad<\/em><em>pre con vosotros y podr\u00e9is hacerles bien <\/em><em>cuando quer\u00e1is; pero a M\u00ed no me tendr\u00e9is <\/em><em>siempre\u00bb (Mc. <\/em>XIV, 7). Y, de hecho, vol\u00advemos a encontrar a Jes\u00fas en los pobres:<\/p>\n<p><em>\u00ab\u00bfQui\u00e9n querr\u00eda ser rico despu\u00e9s de que el Hijo de Dios ha querido ser po\u00ad<\/em><em>bre?&#8230; Si el Rey de reyes se abraz\u00f3 con <\/em><em>la pobreza cuando vino a este mundo, y <\/em><em>por el contrario fulmin\u00f3 su maldici\u00f3n <\/em><em>contra los que est\u00e1n apegados a las ri\u00ad<\/em><em>quezas, con estos t\u00e9rminos: \u00abiPero, ay de <\/em><em>vosotros los ricos, porque hab\u00e9is recibi\u00ad<\/em><em>do vuestro consuelo!&#8217;; pueden conside\u00ad<\/em><em>rarse bienaventuradas las Hijas de la Ca\u00ad<\/em><em>ridad por haber elegido una <\/em>forma de vida que tiene como fin principal la imitaci\u00f3n de la del Hijo de Dios, <em>el cual, a <\/em><em>pesar de que pod\u00eda tener todos los teso\u00ad<\/em><em>ros de la tierra, los despreci\u00f3 y vivi\u00f3 tan pobremente que no ten\u00eda ni una piedra donde reposar su cabeza\u00bb <\/em>(Coste X, 205, 206; Conf. Esp. n\u00fam. 1532).<\/p>\n<h4>2) <strong>Los primeros cristianos<\/strong><\/h4>\n<p>Jes\u00fas, en efecto, desapareci\u00f3, pero su Esp\u00edritu gu\u00eda a sus disc\u00edpulos por la misma v\u00eda. Nadie puede desconocer la importancia que habr\u00e1 de tener en la vida de la Iglesia, a trav\u00e9s de los tiem\u00adpos, el cuadro, el modelo de las prime\u00adras comunidades: <em>\u00abNadie llamaba suyos <\/em><em>a sus bienes, sino que todo lo ten\u00edan en <\/em><em>com\u00fan\u00bb <\/em>(Act. IV, 32).<\/p>\n<p>Una Sociedad de Vida apost\u00f3lica, como la nuestra, debe hacer una parti\u00adcular referencia a esta vida de los pri\u00admeros cristianos. Los Fundadores no han dejado de hacerla:<\/p>\n<p><em>\u00abiQu\u00e9 dicha para la Misi\u00f3n poder imi\u00ad<\/em><em>tar a los primeros cristianos, vivir como <\/em><em>ellos en com\u00fan y en pobreza! \u00a1Oh, Salva\u00ad<\/em><em>dor! iQu\u00e9 ventaja para nosotros! Pid\u00e1\u00ad<\/em><em>mosle a Dios que, por su misericordia, <\/em><em>nos d\u00e9 este esp\u00edritu de pobreza. S\u00ed, el es\u00ad<\/em><em>p\u00edritu de pobreza es el esp\u00edritu de Dios&#8230; <\/em><em>Y \u00e9se es el esp\u00edritu de Dios: amar como <\/em><em>El y los suyos, la pobreza a la que se <\/em><em>opone el esp\u00edritu del mundo, ese esp\u00edritu <\/em><em>de propiedad y de comodidad que busca <\/em><em>la satisfacci\u00f3n propia, ese esp\u00edritu de <\/em><em>apego a las cosas de la tierra, ese esp\u00edri\u00ad<\/em><em>tu de anticristo, s\u00ed de anticristo, no de <\/em><em>ese anticristo que ha de venir un poco <\/em><em>antes de Nuestro Se\u00f1or, sino de ese es\u00ad<\/em><em>p\u00edritu de riquezas opuesto a Dios, de <\/em><em>esas m\u00e1ximas contrarias a las que ha en\u00adse\u00f1ado el Hijo de Dios\u00bb <\/em>(Coste XI, 226; S\u00edg. XI\/3, 141).<\/p>\n<p>Y San Vicente, una vez m\u00e1s, pone este esp\u00edritu en relaci\u00f3n con la Misi\u00f3n:<\/p>\n<p><em>\u00ab&#8230; Gracias a Dios, siempre ha existido <\/em><em>en esta peque\u00f1a Compa\u00f1\u00eda ese esp\u00edritu <\/em><em>de abandono de todas las cosas, que nos hace dejarlo todo por Dios, que nos aleja de las comodidades&#8230; para ir ac\u00e1 o a las Indias; ioh s\u00ed, este esp\u00edritu, por la gracia de Dios existe en la Misi\u00f3n. Uno tiene que marcharse a cien leguas: \u00bfcu\u00e1ndo se va a marchar usted, padre, a ese lugar tan lejano? \u2014Hoy, ma\u00f1ana, esta misma ma\u00f1ana. Y se va uno tan f\u00e1cilmente a cuatrocientas leguas, a Roma&#8230;!\u00bb <\/em>(Cos\u00adte XI, 227; S\u00edg. <strong>XI\/3, 141).<\/strong><\/p>\n<h4><strong>3) Adoptemos esta actitud<\/strong><\/h4>\n<p>De hecho, el amor busca la semejan\u00adza y tiende a suprimir los muros y las barreras. Es el amor el que, de manera natural, nos impulsar\u00e1 a decir quiz\u00e1: Me gustar\u00eda, como Jes\u00fas, ir hacia los po\u00adbres, hacerme pobre entre ellos, con el fin de hacerles accesibles el mensaje que el mismo Cristo quiso dejarnos a trav\u00e9s de su propia vida de pobreza.<\/p>\n<p><strong>Esta semejanza de vida favorecer\u00e1 <\/strong><strong>nuestro \u00abser para los pobres\u00bb y <\/strong><strong>nuestros \u00abestar con los pobres\u00bb y por <\/strong><strong>otra parte no se justifica si no es en <\/strong><strong>funci\u00f3n de nuestro \u00abser para los po\u00ad<\/strong><strong>bres\u00bb y de nuestro \u00abestar con los po\u00ad<\/strong><strong>bres\u00bb. <\/strong>Si deseamos entrar en comuni\u00f3n tan real como sea posible con ellos, es para ayudarles a salir de la situaci\u00f3n di\u00adf\u00edcil en la que se encuentran o a vivirla de una manera liberadora: el Hijo de Dios se hizo pobre para enriquecernos con su pobreza y no para hacer perpe\u00adtua nuestra miseria o para mantenernos en ella. El se despoj\u00f3 de su rango para que nosotros lleg\u00e1ramos a ser, como El y en El, hijos de Dios.<\/p>\n<p>En el filme \u00abMonsieur Vincent\u00bb, se pone acertadamente en su boca que te\u00adnemos que hacernos perdonar nuestra intrusi\u00f3n en el mundo de los pobres y que esto no ser\u00e1 posible sino en raz\u00f3n de nuestro amor y en proporci\u00f3n a ese amor. Efectivamente, es importante, que los pobres perciban este amor nuestro y que, en la medida de lo posi\u00adble, les expliquemos tambi\u00e9n con amor la significaci\u00f3n humana y cristiana de nuestra actitud. Por otra parte, todo ello debe hacerse patente, m\u00e1s por nues\u00adtros actos que por nuestras palabras y, sobre todo, a trav\u00e9s de todo un com\u00adportamiento de relaci\u00f3n amistosa que nos permitir\u00e1 aprender de ellos<\/p>\n<h3><strong>B. Nuestros maestros&#8230; \u00bfC\u00f3mo?<\/strong><\/h3>\n<p>No es que haya que \u00abcanonizar\u00bb a los pobres. Si su servicio es un ideal tan te\u00adrriblemente exigente es, entre otras ra\u00adzones, porque requiere, como ya lo he\u00admos dicho, mucho desinter\u00e9s, mucha paciencia, mucha perseverancia ante los defectos que hay que soportar, ante todo un \u00abnegativo\u00bb que pudiera desani\u00admarnos. Los Fundadores no se llamaron a enga\u00f1o al asegurarnos que, en defini\u00adtiva, s\u00f3lo la Fe nos permitir\u00e1, haciendo que \u00abdemos vuelta a la medalla\u00bb, en\u00adcontrar a Jesucristo en el Pobre e ir al encuentro del Pobre con las disposicio\u00adnes de Jesucristo&#8230; Es cierto que tene\u00admos mucho que aprender de ellos, y que ellos con frecuencia nos \u00abense\u00ad\u00f1an\u00bb y nos evangelizan.<\/p>\n<h4><strong>1) Valores humanos<\/strong><\/h4>\n<p>\u00bfQui\u00e9n no ha quedado impresionado, alguna vez, por la riqueza de valores humanos que se viven frecuentemente en el mundo de los pobres?&#8230; De todos modos, si no tenemos que cerrar los ojos sobre lo \u00abnegativo\u00bb para ayudarles a tomar conciencia de ello y a superar\u00adlo, tenemos que estar atentos, sobre todo, a lo \u00abpositivo\u00bb para hacerlo pro\u00adgresar. Todo lo que existe de aut\u00e9ntica\u00admente bueno, justo, verdadero, como tal, viene de Dios, aun cuando no sea\u00admos conscientes de ello e incluso cuan\u00addo no queramos serlo. Ah\u00ed es donde se encuentran esas \u00absemillas del Verbo\u00bb de las que tanto hablamos desde el Concilio: haciendo tomar conciencia a los pobres de estos valores, vivi\u00e9ndolos con ellos, caminando con ellos para ha\u00adcerlos progresar en los corazones y en las estructuras, esperamos que, final\u00admente, el Se\u00f1or ser\u00e1 reconocido, en\u00adcontrado y acogido en dichos valores, ya que El s\u00f3lo les dar\u00e1 su pleno signifi\u00adcado y su plena realizaci\u00f3n.<\/p>\n<p>Los pobres nos ense\u00f1an con frecuen\u00adcia la verdadera amistad, todo un calor humano del que nuestras Comunidades no son siempre modelos, debido a un \u00absobrenatural\u00bb mal comprendido o, sencillamente, debido a la rutina, al conformismo, al legalismo en el que nos instalamos&#8230; Santa Luisa insist\u00eda en una gozosa cordialidad y hay que creer que, ya en sus tiempos, ella comproba\u00adba la ausencia o la insuficiencia de la misma entre las Hermanas. San Vicen\u00adte, lo hemos visto, estaba particular\u00admente impresionado por la serenidad, la \u00abresignaci\u00f3n\u00bb (en el mejor sentido de la palabra), la confianza inquebrantable de los pobres en medio de sus pruebas. Ellos saben dar y recibir, con la misma sencillez. Comparten de buen grado lo poco que tienen, saben acoger y escu\u00adchar. Son para nosotros, con frecuen\u00adcia, el reflejo de la paciencia y de la ternura a Dios.<\/p>\n<p>No, no es que los pobres tengan to\u00addas las cualidades ni los dem\u00e1s todos los defectos; no es que los pobres ten\u00adgan siempre raz\u00f3n y los dem\u00e1s no. Se impone un discernimiento cuando se trata de tomar partido en favor o en contra de los comportamientos de una persona o de un grupo. Pero hay que optar siempre por el explotado contra el explotador, por el oprimido contra el opresor, Y, sobre todo, tenemos que es\u00adtar muy atentos a toda esta \u00abense\u00f1an\u00adza\u00bb t\u00e1cita del mundo de los pobres que, individual y colectivamente, vive muy a menudo su suerte con dignidad y lucha con no menor dignidad. Y es tanto m\u00e1s importante que estemos sensibilizados a estos valores, cuanto que pueden ser explotados por toda clase de ideolog\u00edas, que su dinamismo puede ser desviado de los verdaderos caminos de libera\u00adci\u00f3n y que el mundo actual corre el riesgo de ahogarlos bajo las m\u00faltiples formas de su materialismo.<\/p>\n<h4>2) <strong>Los evangelizadores&#8230; <\/strong><strong>evangelizados<\/strong><\/h4>\n<p>\u00abLos pobres nos evangelizan\u00bb&#8230; Fre\u00adcuentemente repetimos esta f\u00f3rmula. Ha llegado el momento de preguntar\u00adnos si, de hecho, en contacto con los pobres sentimos que crece en nosotros la inquietud y la verg\u00fcenza de estar nosotros mismos tan poco evangeliza\u00addos. Es una profunda actitud de pobre\u00adza el dejarnos interpelar as\u00ed: \u00bfno hemos apreciado nuestra vida, con demasiada frecuencia, a la luz de los valores de este mundo m\u00e1s que a la de los valores evang\u00e9licos?&#8230; \u00bfExperimentamos, con\u00adcretamente, el deseo de una vida de pobreza que est\u00e9 m\u00e1s marcada por las exigencias del Evangelio y de nuestro ideal vicenciano?&#8230; De este modo los pobres, por el solo hecho de que exis\u00adten y de que nosotros los encontramos, nos ayudan a ser, con tal de que nos dejemos interpelar por ellos, lo que he\u00adnos elegido ser: testigos del Amor infi\u00adnito de Dios hacia nosotros.<\/p>\n<p>Por otra parte, al comprometernos en favor de los pobres con Fe y con una Caridad sencilla y humilde, colabora\u00admos con el Esp\u00edritu en el crecimiento de Cristo en nosotros y en ellos, nos hace\u00admos m\u00e1s \u00abservidores\u00bb y \u00abservidoras\u00bb de Dios en el pobre; nuestro ser cristia\u00adno se desarrolla, el testimonio de nues\u00adtra vida se hace m\u00e1s palpable y, desde este punto de vista tambi\u00e9n, los pobres nos ayudan a llegar a ser lo que somos, lo que debemos ser.<\/p>\n<p>El pobre nos recuerda constantemen\u00adte nuestra propia pobreza, tanto la que procede de nuestra cobard\u00eda como la que se refiere a nuestras limitaciones de toda clase. Si los pobres tienen necesidad de otros para vivir, nosotros te\u00adnemos, lo mismo que ellos, incompara\u00adblemente m\u00e1s necesidad de Dios para existir, de ah\u00ed la importancia de esta di\u00admensi\u00f3n de dependencia sobre la que insistiremos de nuevo.<\/p>\n<p>Pero, sobre todo, y, finalmente, los pobres nos remiten constantemente al Pobre por excelencia que es Cristo Je\u00ads\u00fas con quien est\u00e1n identificados. Si\u00adguiendo a nuestros Fundadores, que nos lo han repetido tantas veces, dis\u00adcernimos en los rasgos de los pobres los rasgos mismos del Se\u00f1or, de tal manera que nuestra presencia junto a ellos se convierte en presencia junto a El. El rostro del pobre nos recuerda que nosotros todos hemos sido salvados por un Pobre, el Pobre por excelencia; comulgando con su pobreza es como completamos lo que falta a su Pasi\u00f3n: \u00abLa Caridad de Jes\u00fas Crucificado nos apremia\u00bb.<\/p>\n<p>iQu\u00e9 riqueza cuando sabemos llevar a la reflexi\u00f3n y a la oraci\u00f3n, personal y comunitariamente, todo lo vivido en la misi\u00f3n!&#8230; Esta es la finalidad principal de la reflexi\u00f3n apost\u00f3lica. Al \u00abreleer\u00bb en la Fe y a la luz de nuestro ideal vicenciano nuestra vida al lado de los pobres, uno de nuestros principales interrogan\u00adtes debe ser: \u00bfNos dejamos ense\u00f1ar, evangelizar por los pobres? \u00bfNos esfor\u00adzamos por ser disc\u00edpulas dignas de ta\u00adles maestros a trav\u00e9s de los cuales nos habla y nos interpela el Maestro: <em>\u00abHa\u00ad<\/em><em>bla, Se\u00f1or, tu siervo escucha\u00bb&#8230;?<\/em><\/p>\n<h2><strong>II. Disc\u00edpulos d\u00f3ciles<\/strong><\/h2>\n<p>Una mirada sincera y l\u00facida sobre nuestra vida personal y comunitaria y sobre la forma en que vivimos nuestra opci\u00f3n preferencial por los pobres, ser\u00e1 muy instructiva. Pero, repit\u00e1moslo, se trata de una mirada en profundidad: la profundidad de la Fe, la profundidad de la pobreza evang\u00e9lica, la profundidad de nuestra vocaci\u00f3n en lo que tiene de m\u00e1s espec\u00edfico y, finalmente, la profundidad de una oraci\u00f3n, impregnada toda ella de pobreza.<\/p>\n<h3><strong>A. Una mirada l\u00facida y sincera<\/strong><\/h3>\n<p>\u00bfExisten criterios y signos que nos permitan confrontar nuestra vida con la de los pobres y saber en qu\u00e9 medida somos d\u00f3ciles a las ense\u00f1anzas que nos dan en materia de pobreza?&#8230; Vea\u00admos algunos:<\/p>\n<h4><strong>1) Sentir la \u00abmordedura\u00bb concreta <\/strong><strong>de la pobreza en nuestras vidas<\/strong><\/h4>\n<p>Santa Luisa nos da la orientaci\u00f3n ge\u00adneral: <em>\u00abEl esp\u00edritu de pobreza es el de Jesu\u00adcristo. El dice hablando de S\u00ed mismo: las zorras tienen sus madrigueras y los p\u00e1ja\u00adros sus nidos, pero el Hijo del Hombre no tiene d\u00f3nde reclinar su cabeza. Viendo que El am\u00f3 tanto esta virtud, yo he con\u00adcebido una gran estima de ella y un gran deseo de imitarle. Y como no me en\u00adcuentro en estado de poderla practicar realmente como El, me he propuesto <\/em>usar con confusi\u00f3n de lo superfluo, y soportar sin decir nada lo que me falte, <em>y tratar\u00e9 de <\/em>despojarme de todo, <em>en la <\/em><em>medida de lo posible, someti\u00e9ndome a su divina Providencia.<\/em><\/p>\n<p>Yo quiero, pues, amar de todo coraz\u00f3n la pobreza de bienes, por el honor que debo y quiero rendir a la opci\u00f3n que mi Salvador hizo de ella. Y si su Bondad per\u00admite que me tropiece con algunas nece\u00adsidades, mirar\u00e9 su santa voluntad, ele\u00advar\u00e9 a El mi esp\u00edritu y recurrir\u00e9 a El solo, considerando que, desde toda la eterni\u00addad, El solo ha sido suficiente a S\u00ed mis\u00admo, por consiguiente que nos puede y nos debe bastar, y que estando en un estado en el que debemos tenerlo a El solo como consuelo, debemos aceptar amorosamente la privaci\u00f3n de lo que nos falte fuera de El\u00bb (Escritos, Ed. 1961).<\/p>\n<p>Esta visi\u00f3n de Santa Luisa acerca de la pobreza es impresionante, tanto por su profundidad como por su realismo, en funci\u00f3n de la vocaci\u00f3n de las Hijas de la Caridad. Coincide con San Vicente cuando habla de la mortificaci\u00f3n:<\/p>\n<p>\u00abPero, Padre, \u00bfqu\u00e9 nos dice usted? iEs muy duro eso de no desear nuestras sa\u00adtisfacciones ni lo que nos agrada! \u00bfQu\u00e9 medios habr\u00e1 para mortificarse siempre y resistir continuamente a las inclinacio\u00adnes que, de ordinario, nos llevan a obte\u00ad<em>ner esas cosas de las que usted nos en <\/em><em>se\u00f1a que hay que huir?<\/em><\/p>\n<p>Responder\u00e9 a ello que es la concupis\u00adcencia de la carne la que nos hace usar ese lenguaje. Y vivir seg\u00fan la carne es morir, pero morir a la vida de la gracia, que es muy distinta de la del cuerpo. Por tanto, los que quieran satisfacerse y vivir seg\u00fan la carne no tienen la vida del esp\u00ed\u00adritu. Moriemini, dice San Pablo, morir\u00e9is si quer\u00e9is vivir seg\u00fan la carne. Acordaos de lo que os digo hoy, que no pod\u00e9is guardar vuestras reglas y seguir los pla\u00adceres de la carne. Es incompatible. Her\u00admanas m\u00edas, si la Compa\u00f1\u00eda perece por culpa de la falta de observancia de algu\u00adna regla, ser\u00e1 sobre todo por no haber guardado \u00e9sta\u00bb (Coste X, 217; Conf. Esp. n\u00fam. 1 554).<\/p>\n<p>Esta pobreza \u00abde hecho\u00bb, concreta San Vicente, si debe vivirse en el servi\u00adcio a los pobres, en la misma medida y en funci\u00f3n de este servicio, debe carac\u00adterizar la vida personal y comunitaria de las Hermanas:<\/p>\n<p><em>\u00abNuestra buena Santa Genoveva am\u00f3 tambi\u00e9n mucho la pobreza, como buena <\/em><em>aldeana; y todas las buenas Hijas de la <\/em><em>Caridad tienen que tomar afecto a la <\/em><em>pr\u00e1ctica de esta virtud. Os hablo de <\/em>la pr\u00e1ctica, <em>hijas m\u00edas; no bastar\u00eda con <\/em><em>amar la virtud desde fuera; <\/em>hay que amar las necesidades que pueden acontecer, <em>y no quejarse de las que se <\/em><em>sufren.<\/em><\/p>\n<p>Querer tener lo que no se tiene, hijas m\u00edas, no es la pobreza de las verdaderas campesinas que se contentan con lo que tienen, bien sea en el vestir, bien en el alimento. Y por lo que se refiere a sus bienes, nunca piensan en ellos, e incluso no presumen de los que tienen, sino que son aficionadas a la pobreza. Trabajan como si nada tuvieran; y en esto, hijas m\u00edas, se conocer\u00e1 que sois verdaderas Hijas de la Caridad, si no ambicion\u00e1is nada, si os content\u00e1is con lo que se os da por la gracia de Dios. Las que Dios llam\u00f3 primero a vuestra manera de vivir han obrado de esta forma\u00bb (Conf. Esp. n\u00fam. 147).<\/p>\n<p>Existe siempre esta preocupaci\u00f3n por cuidar de los bienes de los pobres y de la Comunidad. Como toda corresponsa\u00adbilidad, la gesti\u00f3n de los bienes supone:<\/p>\n<ul>\n<li>informaci\u00f3n rec\u00edproca,<\/li>\n<li>revisi\u00f3n comunitaria del uso de los bienes materiales y de la forma de vida de la Comunidad.<\/li>\n<li>elaboraci\u00f3n de un presupuesto den\u00adtro del marco del proyecto comuni\u00adtario,<\/li>\n<li>rendici\u00f3n de cuentas.<\/li>\n<\/ul>\n<p>San Vicente propone, como ejemplo, esta ilustraci\u00f3n que no carece de inte\u00adr\u00e9s: <em>\u00abId primero a los pobres y socorredles; luego si pod\u00e9is hacer lo dem\u00e1s, hacedlo enhorabuena. Sin embargo, los que ac\u00adtualmente adornan las iglesias de ese modo <\/em>(magn\u00edfico) <em>no obran mal, dado <\/em><em>que como tienen muchos bienes, pueden hacer lo uno y lo otro <\/em>(ayudar tambi\u00e9n a los Pobres). <em>Pero vosotras ten\u00e9is que <\/em><em>amar la pobreza que hace que no se de\u00adseen cosas bonitas. Pues apenas una tenga algo bonito, que tenga un altarcito bien arreglado, la Hermana que lo vea tendr\u00e1 deseos de tener otro tanto. Y dir\u00e1: iqu\u00e9 bello altar tiene mi hermana de tal lugar; hay esto y esto! i0h!, iqu\u00e9 devo\u00adci\u00f3n me da! \u00a1Es preciso que yo compre otro tanto!<\/em><\/p>\n<p>Y, \u00bfde d\u00f3nde sacar el dinero para ello? Tendr\u00e1 que rob\u00e1rselo a los pobres, ya que vosotras no ten\u00e9is nada. Y si emplea en ello lo que le dan para sus gastos, tampoco est\u00e1 permitido lo mismo que to\u00adm\u00e1rselo a los pobres\u00bb (Coste X, 359; Conf. Esp. n\u00fam 1792-1793).<\/p>\n<p>La Madre GUILLEMIN, en su circu\u00adlar sobre la pobreza de febrero de 1965, da unas normas generales que no podemos repetir aqu\u00ed con detalle: dejar siempre un margen a la mortifica\u00adci\u00f3n en las instalaciones necesarias, te\u00adner cuidado de no aprovechar las facili\u00addades de vida que aportan las obras, mantener una diferencia claramente os\u00adtensible entre los locales de la Comuni\u00addad y los destinados a las obras&#8230; Y conclu\u00eda:<\/p>\n<p>\u00abProcuremos hacernos semejantes a los pobres. Esta directiva se encuentra a cada paso en las ense\u00f1anzas de San Vi\u00adcente y de Santa Luisa, y es la que debe regular la apreciaci\u00f3n de nuestra pobreza exterior (de una manera prudente, como lo hicieron ellos mismos, sin exageraci\u00f3n y sin debilidad)&#8230; El estilo de vida y el ni\u00advel de pobreza exterior variar\u00e1n forzosa\u00admente seg\u00fan las circunstancias y los pa\u00ed\u00adses, aun en el interior de la Compa\u00f1\u00eda, porque \u00e9sta se encuentra de hecho en si\u00adtuaciones muy diversas. Sin embargo, que nuestro coraz\u00f3n se incline siempre del lado de los pobres y de su pobreza.\u00bb<\/p>\n<p>Por su parte, la Madre ROGE ha vuel\u00adto a tratar con frecuencia este tema con mucha precisi\u00f3n.<\/p>\n<h4>2) <strong>\u00abOrientemos nuestro coraz\u00f3n <\/strong><strong>hacia los pobres y su pobreza\u00bb<\/strong><\/h4>\n<p>Siguiendo esta recomendaci\u00f3n de la Madre GUILLEMIN, debemos pregun\u00adtarnos si nuestra existencia est\u00e1 marca\u00adda por determinados rasgos, y si acep\u00adtamos de buen grado que lo est\u00e9, ras\u00adgos que nos permitan entrar en comu\u00adni\u00f3n con los pobres a trav\u00e9s de seme\u00adjanzas, de analog\u00edas. Podemos pensar especialmente en la <em>dependencia y la in\u00ad<\/em><em>seguridad.<\/em><\/p>\n<p>Los pobres <em>dependen <\/em>de mucha gen\u00adte, de muchas cosas, de muchos acon\u00adtecimientos&#8230; Frecuentemente se ha descrito este cuadro, cuadro que en las circunstancias actuales, en muchos pa\u00ed\u00adses, se va agravando hasta la tragedia. Y nosotros, \u00bfaceptamos verdadera\u00admente vivir esta dimensi\u00f3n de la pobre\u00adza cada vez que la ocasi\u00f3n se presente y bajo las m\u00faltiples formas en que pue\u00adda presentarse? Es tambi\u00e9n la Madre GILLEMIN quien ilustra esto mediante el siguiente ejemplo:<\/p>\n<p>\u00abEl pobre ve restringida su indepen\u00addencia como consecuencia de la pobre\u00adza; tiene que pedir y esperar y, con fre\u00adcuencia, sufrir algunas incomodidades. Est\u00e1 en situaci\u00f3n de dependencia. La for\u00adma en que nosotras hemos de practicar la pobreza es la dependencia, y su salvaguarda es la obligaci\u00f3n que tene\u00admos de pedir permiso para ejecutar un acto de propiedad de cualquier clase que sea. Demos al acto de pedir un permiso todo su profundo sentido, y no lo convir\u00adtamos en una simple formalidad rutinaria y de tipo reglamentario, que se limita a sancionar la decisi\u00f3n que ya hab\u00edamos tomado interiormente; por el contrario, pong\u00e1monos en disposici\u00f3n de aceptar que se nos conceda o rehuse lo que pedi\u00admos. Manifestar descontento ante una negativa, \u00bfno es indicio de que seguimos consider\u00e1ndonos propietarias?\u00bb<\/p>\n<p>Repito una vez m\u00e1s, \u00e9ste no es m\u00e1s que un ejemplo entre mil, y podr\u00edamos citar muchos otros que nos afectan, quiz\u00e1, m\u00e1s profundamente todav\u00eda. Al hablar a las Hermanas de las ofrendas que se hacen con motivo del Jubileo, San Vicente les dec\u00eda:<\/p>\n<p><em>\u00abSe dice que hay que dar limosna.<\/em><\/p>\n<p>Pero de eso no ten\u00e9is que preocuparos. La Compa\u00f1\u00eda dar\u00e1 por todas en general, ya que sois pobres y la mayor parte ha\u00adb\u00e9is hecho voto de pobreza, lo cual os impide poseer. En nuestra casa lo hemos ordenado as\u00ed. As\u00ed pues, la Casa dar\u00e1 li\u00admosna por todas, y vosotras pod\u00e9is ofre\u00adcer a Nuestros Se\u00f1or lo que se d\u00e9 por vosotras, uniendo vuestra intenci\u00f3n a la de los Superiores\u00bb (Coste X, 237; Conf. Esp. n\u00fam. 1 592).<\/p>\n<p>\u00abUniendo vuestra intenci\u00f3n\u00bb: la ex\u00adpresi\u00f3n dice claramente lo que quiere decir. A trav\u00e9s de las diversas formas que puede tomar la dimensi\u00f3n de de\u00adpendencia, es sobre todo el esp\u00edritu con el que se vive dicha dependencia el que cuenta y le da todo su valor. Por otra parte, en nuestra vocaci\u00f3n, \u00bfno se ejer\u00adcita esta dependencia con relaci\u00f3n a los mismos pobres, nuestros amos y se\u00f1ores?<\/p>\n<p>Dentro de este deseo de asemejar\u00adnos a ellos y de compartir su suerte, seremos felices, si llega el caso, de po\u00adder vivir en distintas formas de <em>inseguri\u00ad<\/em><em>dad, <\/em>de incertidumbre&#8230; Es sin duda algu\u00adna porque Juliana LORET hab\u00eda mani\u00adfestado, al escribir a Santa Luisa, una excesiva preocupaci\u00f3n con relaci\u00f3n a los bienes materiales, por lo que la Fun\u00addadora le responde:<\/p>\n<p>\u00abQuerida Hermana, \u00bfquiere usted que le diga que su carta no huele a pobre, <em>sino que tiene un olor que no les est\u00e1 <\/em><em>permitido a las Hijas de la Caridad?\u00bb <\/em>(Escritos Esp. Ed. 1983, p\u00e1g. 462; ver comentario de Madre ROGE en Ecos de la Compa\u00f1\u00eda, noviembre de 1981, p\u00e1g. 451).<\/p>\n<p>Esta referencia a los pobres es signi\u00adficativa, ya que nuestros problemas y nuestras dificultades son con frecuen\u00adcia m\u00ednimas al lado de las suyas&#8230; Pen\u00adsemos en el contexto actual que agrava hasta la desesperanza la marginaci\u00f3n de tantas personas, en particular de los j\u00f3venes. Crece el n\u00famero de los que no tienen trabajo, las reconversiones est\u00e1n sometidas a menudo a tantas exigen\u00adcias que son pr\u00e1cticamente imposibles para la mayor parte de los interesados: entonces, \u00bfc\u00f3mo afrontarlas? \u00bfY qu\u00e9 ser\u00e1 del ma\u00f1ana? Los esfuerzos y los sacrificios de hoy tendr\u00e1n al menos, al\u00adg\u00fan resultado?..<\/p>\n<p>Sabemos que esta mirada realista sobre la condici\u00f3n de los pobres era la de San Vicente:<\/p>\n<p>\u00abHermanas m\u00edas, iqu\u00e9 honor! Es Dios el que os ha encomendado el cuidado de sus pobres, y ten\u00e9is que comportaros con ellos con su mismo esp\u00edritu, compa\u00addeciendo sus miserias y sinti\u00e9ndolas en vosotras mismas.<\/p>\n<p>Yo he visto <em>a esas pobres gentes <\/em>(se refiere aqu\u00ed a los galeotes), <em>tratadas <\/em><em>como bestias; esto fue lo que hizo que <\/em><em>Dios se llenara de compasi\u00f3n. Le dieron <\/em><em>l\u00e1stima y luego su Bondad hizo dos co<\/em><em>sas en su favor; primero, hizo que com<\/em><em>praran una casa para ellos; segundo, qui\u00adso disponer las cosas de tal modo que fueran servidos por sus propias hijas, puesto que decir una Hija de la Caridad es decir una hija de Dios\u00bb <\/em>(Coste X, 125; Conf. Esp. n\u00fam. 1394).<\/p>\n<h3>B. <strong>Una mirada en profundidad<\/strong><\/h3>\n<p>Estas \u00faltimas palabras de San Vicen\u00adte nos remiten al esp\u00edritu de la voca\u00adci\u00f3n, y debemos terminar estas refle\u00adxiones sobre la pobreza volviendo a lo esencial.<\/p>\n<h4><strong>1) \u00abBienaventurados los pobres de <\/strong><strong>esp\u00edritu\u00bb<\/strong><\/h4>\n<p>\u00bfHay que repetir hasta qu\u00e9 punto capt\u00f3 San Vicente la bienaventuranza evang\u00e9lica, que le hac\u00eda exclamar: <em>i\u00bbDesdichado el que no se contenta con <\/em><em>Dios\u00bb!? <\/em>(Coste X, 210; Conf. Esp. n\u00fam. 1541).<\/p>\n<p>S\u00ed, esta pobreza espiritual fija el cora\u00adz\u00f3n en Dios, Bien Absoluto, y hace que prefiramos \u00abposeer un tesoro en el Cie\u00adlo\u00bb, poniendo la esperanza en los bie\u00adnes del Reino y fijando en ellos nuestro coraz\u00f3n.<\/p>\n<p>Y es precisamente esta pobreza espi\u00adritual la que va a garantizar la paz de nuestro coraz\u00f3n ante las contradiccio\u00adnes, los fracasos, las limitaciones per\u00adsonales y las de los dem\u00e1s, haciendo que las relativicemos comparadas con los bienes del Reino, que elevemos el deseo y la mirada que la naturaleza diri\u00adge espont\u00e1neamente sobre los bienes de este mundo. Las Constituciones expresan muy bien todo esto y nos ase\u00adguran que, por este medio, nuestro co\u00adraz\u00f3n se abre al amor de todos y se sensibiliza hacia las necesidades de los pobres, impuls\u00e1ndonos a poner verda\u00adderamente a su servicio nuestra perso\u00adna, nuestro tiempo, nuestros bienes, nuestro trabajo, etc., siguiendo a Jes\u00fas, que siendo Pobre El mismo, pas\u00f3 ha\u00adciendo el bien (Act. X, 38).<\/p>\n<p>Repitamos que esta pobreza espiri\u00adtual se requiere para que humildemente podamos aprender de los pobres:<\/p>\n<p><em>\u00ab!Sabemos acaso lo que es ser <\/em><em>pobre? \u2014dice tambi\u00e9n la Madre GUILLE\u00adMIN\u2014. Sin darnos cuenta de ello, somos <\/em><em>ricas de muchas cosas, vivimos en la ilu\u00ad<\/em><em>si\u00f3n y sobre \u00e9sta fundamentamos nues\u00ad<\/em><em>tra seguridad, a despecho de las afirma\u00ad<\/em><em>ciones que hacemos en contrario: ricas <\/em><em>de nuestra salud y de nuestro equilibrio <\/em><em>humano; ricas de dones naturales, de ex\u00ad<\/em><em>periencia o de conocimientos adquiridos, <\/em><em>aun cuando no sean muchos; ricas de re\u00ad<\/em><em>laciones, de influencia, de la importancia y del renombre de la Compa\u00f1\u00eda, y ricas <\/em><em>incluso de recursos espirituales. Mien\u00ad<\/em><em>tras nuestra fuerza y nuestra esperanza <\/em><em>se basen en estos valores personales, no somos pobres de esp\u00edritu, y frente al he\u00adcho cotidiano, nuestras reacciones no dan el sentido justo de la pobreza. Hay que comprender la profundidad de la po\u00adbreza, hay que haber valorado la nada de todo, y estar desprendido de todo, para responder en toda circunstancia de acuerdo con la pobreza.\u00bb<\/em><\/p>\n<p>Y la continuaci\u00f3n del texto indica la ra\u00edz profunda de esta actitud:<\/p>\n<p>\u00abHay que hacerse pobres y mante\u00adnerse pobres ante Dios. <em>Esa es, sencilla\u00ad<\/em><em>mente, la actitud fundamental del hom\u00ad<\/em><em>bre ante su Creador.<\/em><\/p>\n<p><em>Hacernos pobres es establecernos en <\/em><em>nuestra verdadera posici\u00f3n frente a Dios. <\/em><em>Consiste, ante todo, <\/em>en reconocer en la verdad y la humildad lo que somos: <em>nuestra peque\u00f1ez, nuestra impotencia, <\/em><em>nuestra miseria y, sobre todo, la absolu\u00ad<\/em><em>ta dependencia en que nos encontra\u00ad<\/em><em>mos con respecto a El. Pero consiste <\/em><em>tambi\u00e9n en descubrir al mismo tiempo, <\/em><em>en la alabanza y en la adoraci\u00f3n, su So\u00adberano Dominio, la omnipotente Bon\u00addad de su Providencia, su inefable mi\u00adsericordia y su paternidad con respecto a nosotros. En una palabra, la pobreza consiste en reconocer que El lo es todo, y que nosotros no somos nada. Para llegar a un tal conocimiento no basta la raz\u00f3n; hace falta la ayuda de una ora\u00adci\u00f3n humilde y constante para implorar el don de Dios en la Fe. Y, precisamen\u00adte, cuanto m\u00e1s nos ilumine la fe, m\u00e1s lograremos penetrar en la profundidad de nuestra nada, y cuanto m\u00e1s nos abismemos en nuestra pobreza m\u00e1s nos inundar\u00e1 la fe con los esplendores de la m\u00e1s pura alegr\u00eda.<\/em><\/p>\n<p>Entonces aprenderemos a esperarlo todo de Dios, en la actitud de un ver\u00addadero pobre.\u00bb (Circular de febrero de 1965).<\/p>\n<h4><strong>2) Revisar nuestra opci\u00f3n prefe<\/strong><strong>rencial en favor de los pobres<\/strong><\/h4>\n<p>La \u00abrevisi\u00f3n de obras\u00bb, por emplear la expresi\u00f3n consagrada, es una necesi\u00addad permanente. Se impone m\u00e1s a\u00fan en nuestra \u00e9poca de r\u00e1pidas y profun\u00addas mutaciones. Pero revisar nuestras actividades y sus modalidades no ten\u00addr\u00eda ning\u00fan sentido si no hici\u00e9ramos <em>un <\/em><em>examen a nivel de la calidad, de las moti\u00advaciones, de la expresi\u00f3n esencial de nuestra opci\u00f3n preferencial en favor de los pobres.<\/em><\/p>\n<p>Ser\u00eda preciso que volvi\u00e9semos a tra\u00adtar aqu\u00ed de la Instrucci\u00f3n sobre algunos aspectos de la Teolog\u00eda de la Liberaci\u00f3n que presentamos en los Ecos de la Compa\u00f1\u00eda de diciembre de 1984 y, so\u00adbre todo, la parte titulada precisamente: La opci\u00f3n preferencial en favor de los Pobres: una Evangelizaci\u00f3n basada en la verdad (verdad sobre Jesucristo, ver\u00addad sobre la Iglesia, verdad sobre el hombre), una evangelizaci\u00f3n basada en el respeto a todo hombre, una evangeli\u00adzaci\u00f3n basada en el respeto al pobre, todo esto con miras a una \u00abcivilizaci\u00f3n del Amor\u00bb, seg\u00fan la expresi\u00f3n de Pa\u00adblo VI, que Puebla hizo suya.<\/p>\n<p>En este aspecto tambi\u00e9n se trata de que aprendamos de los pobres. Las Teolog\u00edas de la Liberaci\u00f3n, en lo que tienen de m\u00e1s positivo, pretenden ser esencialmente una expresi\u00f3n obstinada del deseo de liberaci\u00f3n de los pobres, releyendo con ellos la Palabra de Dios que, de pronto, adquiere una apasio\u00adnante actualidad.<\/p>\n<p>En el centro de la espiritualidad de las Hijas de Vicente de Paul, encontramos toda una visi\u00f3n de la <em>actitud de \u00absierva\u00bb <\/em>que las Constituciones describen, y en lo que la Madre ROGE nos ha hecho meditar con frecuencia. Y que puede y debe llevarnos muy lejos en las implica\u00adciones pr\u00e1cticas, pero a condici\u00f3n, una vez m\u00e1s, de que la actitud sea com\u00adprendida, revisada, re-actualizada en profundidad. Tenemos, por ejemplo, toda la cuesti\u00f3n de los \u00abmedios humil\u00addes\u00bb y de la revisi\u00f3n de nuestro estilo de vida. Con un esp\u00edritu de realismo, hay que saber \u00abrelativizar\u00bb todo, pero la orientaci\u00f3n general y la inspiraci\u00f3n de fondo no ofrecen duda: ir con preferen\u00adcia hacia las tareas humildes, ir hacia comunidades en las que pueda vivirse verdaderamente un proyecto vicencia\u00adno, permanecer atentas y fieles a lo que constituye la vida de los pobres en su tejido cotidiano de alegr\u00edas y de penas y, a partir de ah\u00ed, dejarse transformar desde dentro, estar siempre alerta para no perder de vista la exigencia \u00abprof\u00e9ti\u00adca\u00bb de nuestra vocaci\u00f3n, es decir, la de\u00adnuncia de todo lo que aplasta a los m\u00e1s pobres, y la llamada a correr hacia ellos <em>\u00abcomo se corre para apagar el fuego\u00bb.<\/em><\/p>\n<h4>3) <strong>Seguir la acci\u00f3n divina<\/strong><\/h4>\n<p>Este esp\u00edritu de pobreza, como lo re\u00adcordaba tambi\u00e9n la Madre GUILLEMIN, es una dura y larga conquista que siem\u00adpre estaremos tratando de alcanzar, de revisar, de volver a empezar.<\/p>\n<p>La voz de Dios nos solicita en todo y, en primer lugar, a trav\u00e9s de los mismos pobres, para que demos una respuesta de pobre a la gracia de cada momento. Tenemos, pues, que seguir e implorar la acci\u00f3n divina, reconocer sus llamadas en cada acontecimiento, acogerla bien cuando nos purifica y nos interpela.<\/p>\n<p>Como conclusi\u00f3n de su conferencia del 20 de agosto de 1656 sobre la po\u00adbreza, San Vicente invitaba a las Her\u00admanas a pedir esta gracia al Se\u00f1or. Lo hace refiri\u00e9ndose a la tres tentaciones de Jes\u00fas en el desierto&#8230; y esto est\u00e1 lle\u00adno de significaci\u00f3n: la primera nos remi\u00adte a la necesidad fundamental de tener; la segunda trata de la cuesti\u00f3n de los medios para hacerse valer; la tercera culmina en torno al deseo de poder. Nos encontramos en el centro de la op\u00ad ci\u00f3n que Cristo hizo de la pobreza, de su rechazo a servirse y a que le sirvie\u00adran, de su determinaci\u00f3n a no ser m\u00e1s que \u00abServidor\u00bb&#8230; Nos encontramos, pues, por este mismo hecho, en el cen\u00adtro de nuestra vocaci\u00f3n (Coste X, 223; Conf. Esp. n\u00fam. 1566).<\/p>\n<p>San Vicente no separa jam\u00e1s a Mar\u00eda de Jes\u00fas. En su conferencia, tan impor\u00adtante para las Hijas de la Caridad, sobre la imitaci\u00f3n de las j\u00f3venes campesinas, dice: <em>\u00abHijas m\u00edas, \u00bfqu\u00e9 pens\u00e1is que ha sido la vida del Hijo de Dios y la de su <\/em><em>Santa Madre? Una vida de perfecta po\u00ad<\/em><em>breza\u00bb <\/em>(Coste IX, 87; Conf. Esp. n\u00fam. 147). Los Fundadores nos invitan a contemplar en Mar\u00eda, a la luz de Cristo servidor, <em>\u00aba la Sierva fiel y humilde de los designios del Padre, modelo de los <\/em><em>corazones pobres\u00bb <\/em>(Coste 1, 12).<\/p>\n<p>Y es as\u00ed como gustamos de contem\u00adplarla en su Anunciaci\u00f3n, en su Magni\u00adficat, en Can\u00e1, en el Calvario, en Pente\u00adcost\u00e9s. As\u00ed es como nos gusta rezarle.<\/p>\n<p>La creaci\u00f3n de una comisi\u00f3n pontifi\u00adcia para la pastoral de los servicios de la salud, el 11 de febrero \u00faltimo, en la fiesta de Nuestra Se\u00f1ora de Lourdes, viene a confirmar, de alguna manera, esta dimensi\u00f3n mariana de nuestra vo\u00adcaci\u00f3n. Juan Pablo <strong>II, <\/strong>al anunciar este nuevo organismo que, en uni\u00f3n con el Consejo Pontificio para los seglares, debe coordinar todas las instituciones comprometidas, siguiendo a Cristo, en el servicio a los que sufren, nos remite a su Carta Apost\u00f3lica del 11 de febrero precedente, sobre el sentido cristiano del sufrimiento humano. Es un texto que han de volver a leer y meditar las Hijas de la Caridad, que han consagra\u00addo su vida, siguiendo los pasos de Je\u00ads\u00fas-Servidor y de Mar\u00eda-Sierva a sus hermanos los pobres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los pobres son nuestros \u00abamos\u00bb y debemos servirles como a tales. Son tambi\u00e9n nuestros \u00abmaestros\u00bb y, como tales, nos ense\u00f1an; por tanto, hemos de aprender de ellos. Esta es, no lo dudemos, una impor\u00adtante dimensi\u00f3n &#8230; <a href=\"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":139919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226,199],"tags":[172],"class_list":["post-54880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","category-hijas-de-la-caridad","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Los pobres son nuestros \u00abamos\u00bb y debemos servirles como a tales. Son tambi\u00e9n nuestros \u00abmaestros\u00bb y, como tales, nos ense\u00f1an; por tanto, hemos de aprender de ellos. Esta es, no lo dudemos, una impor\u00adtante dimensi\u00f3n ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-16T07:59:16+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"35 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026\",\"datePublished\":\"2015-02-16T07:59:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/\"},\"wordCount\":6972,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Espiritualidad vicenciana\",\"Hijas de la Caridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/\",\"name\":\"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-02-16T07:59:16+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/","og_locale":"es_ES","og_type":"article","og_title":"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026 - Somos Vicencianos","og_description":"Los pobres son nuestros \u00abamos\u00bb y debemos servirles como a tales. Son tambi\u00e9n nuestros \u00abmaestros\u00bb y, como tales, nos ense\u00f1an; por tanto, hemos de aprender de ellos. Esta es, no lo dudemos, una impor\u00adtante dimensi\u00f3n ... Read More","og_url":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-02-16T07:59:16+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"35 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026","datePublished":"2015-02-16T07:59:16+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/"},"wordCount":6972,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#primaryimage"},"thumbnailUrl":"","keywords":["Pobreza"],"articleSection":["Espiritualidad vicenciana","Hijas de la Caridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/","url":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/","name":"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-02-16T07:59:16+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/pobreza-por-el-servicio-a-los-pobres-en-humildad-sencillez-y-caridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pobreza por el servicio a los pobres en humildad, sencillez y caridad\u2026"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-eha","jetpack-related-posts":[{"id":116700,"url":"http:\/\/vincentians.com\/es\/caridad-en-san-vicente-de-paul\/","url_meta":{"origin":54880,"position":0},"title":"Caridad en San Vicente de Pa\u00fal","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/10\/2018","format":false,"excerpt":"Introducci\u00f3n Hablar de la caridad en Vicente de Pa\u00fal en esta semana de Estudios Vicencianos significa hacer una \"relectura\" de la misma. Esta relectura implica no una simple exposici\u00f3n de lo que dijo e hizo Vicente de Pa\u00fal referente a la caridad, sino un volver a leer su ense\u00f1anza y\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2017\/07\/San-Vicente-7.jpg?fit=600%2C416&resize=525%2C300 1.5x"},"classes":[]},{"id":131677,"url":"http:\/\/vincentians.com\/es\/caridad-compasiva-y-eficaz\/","url_meta":{"origin":54880,"position":1},"title":"Caridad compasiva y eficaz","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/11\/2014","format":false,"excerpt":"\"Al salir de Jeric\u00f3 lo sigui\u00f3 mucha gente. Hab\u00eda dos ciegos, sentados a la vera del camino, y al o\u00edr que Jes\u00fas pasaba, se pusieron a gritar: ;Ten compasi\u00f3n de nosotros, Se\u00f1or, Hijo de David! Jes\u00fas se detuvo, los llam\u00f3 y les dijo: \u00bfQu\u00e9 quer\u00e9is que haga por vosotros? Le\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"caridad_compasiva","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/11\/caridad_compasiva-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":118011,"url":"http:\/\/vincentians.com\/es\/la-iglesia-de-los-pobres-y-la-familia-vicenciana\/","url_meta":{"origin":54880,"position":2},"title":"La Iglesia de los pobres y la familia vicenciana","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/04\/2014","format":false,"excerpt":"El problema de los pobres y de la pobreza ocupa el primer plano en las preocupaciones de la Iglesia en nuestro tiempo, es\u00adpecialmente desde que Juan XXIII anunci\u00f3 al mundo, al abrir el Concilio Vaticano II (11 septiembre 1962) que la Iglesia era \"preferentemente de los pobres y para los\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"san-vicente-de-paul","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/san-vicente-de-paul.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":136560,"url":"http:\/\/vincentians.com\/es\/evangelizados-por-los-pobres\/","url_meta":{"origin":54880,"position":3},"title":"Evangelizados por los pobres","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/01\/2015","format":false,"excerpt":"\u00abEscuchad, queridos hermanos \u00bfno fue Dios quien escogi\u00f3 a los que son pobres a los ojos del mundo para que fueran eran ricos de fe y herederos del Reino que \u00e9l prometi\u00f3 a los que lo aman? Vos\u00adotros, en cambio, hab\u00e9is afrentado al pobre\u00bb. Sant 2,5-6). \u00abEn la obra de\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"vicente_pobre","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/vicente_pobre-241x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":120175,"url":"http:\/\/vincentians.com\/es\/el-compromiso-con-la-justicia-dimension-esencial-del-servicio\/","url_meta":{"origin":54880,"position":4},"title":"El compromiso con la justicia, dimensi\u00f3n esencial del servicio","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/05\/2013","format":false,"excerpt":"Introducci\u00f3n Cuando se habla del compromiso con la justicia en favor de los pobres y de lo que implica en la vida, es necesario, antes, estar incluidos entre los hombres y las mujeres mejor informados y for\u00admados referente a los pobres, a la pobreza y a la marginaci\u00f3n. La necesidad\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"justicia","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/justicia-300x203.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":139378,"url":"http:\/\/vincentians.com\/es\/sensibles-ante-las-distintas-pobrezas\/","url_meta":{"origin":54880,"position":5},"title":"Sensibles ante las distintas pobrezas","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/02\/2015","format":false,"excerpt":"\u00abMuero de cansancio, sin dormir muchas noches, con hambre, con fr\u00edo y sin ro\u00adpa. Y aparte de eso exte\u00adrior, la carga de cada d\u00eda, la preocupaci\u00f3n por todas las comunidades. \u00bfQui\u00e9n enfer\u00adma sin que yo enferme? \u00bfQui\u00e9n cae sin que a m\u00ed me d\u00e9 fiebre?\u00bb (II Cor 11,27-29). \u00abSiguiendo a\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/asd-300x201.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/54880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=54880"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/54880\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=54880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=54880"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=54880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}