{"id":54587,"date":"2015-02-13T06:30:50","date_gmt":"2015-02-13T05:30:50","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=54587"},"modified":"2015-02-13T06:30:50","modified_gmt":"2015-02-13T05:30:50","slug":"apresados-por-jesucristo","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/","title":{"rendered":"Apresados por Jesucristo"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/jesus-de-nazaret.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-139712\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/jesus-de-nazaret-300x188.jpg?resize=300%2C188\" alt=\"jesus-de-nazaret\" width=\"300\" height=\"188\" \/><\/a>Hemos visto c\u00f3mo en su consideraci\u00f3n de Jesucristo, los Fundadores tienen un \u00abenfoque selectivo\u00bb que constituye precisamente su \u00abcarisma\u00bb y que nosotros debe\u00admos hacer nuestro al vivir el esp\u00edritu de la Compa\u00f1\u00eda:<\/p>\n<p>\u00abCuando se dice: \u00abEl Esp\u00edritu de Nuestro Se\u00f1or est\u00e1 en tal persona o en tales \u00ad obras\u00bb, \u00bfc\u00f3mo se entiende esto? \u00bfEs que se ha derramado sobre ellas el mismo Esp\u00edritu Santo? S\u00ed, el Esp\u00edritu Santo, en <em>cuanto a su Persona, se derrama sobre <\/em>los justos y habita personalmente en ellos. Cuando se dice que el Esp\u00edritu Santo<em> act\u00faa en una persona, quiere decirse<\/em><em> que este Esp\u00edritu, al habitar en ella, le da <\/em><em>las mismas inclinaciones y <\/em>disposiciones que ten\u00eda Jesucristo en la tierra, y \u00e9stas le hacen obrar en igual manera, no digo que con la misma perfecci\u00f3n, pero s\u00ed seg\u00fan la medida de los dones de este divino Esp\u00edritu\u00bb. (Coste XII, 108; S\u00edg. <em>IX\/3, 41.)<\/em><\/p>\n<p>Ah\u00ed tenemos, pues, a la Hija de la Caridad llamada a centrar su vida en Jesucristo, en Jesucristo como consagrado y enviado a llevar la Buena Nueva a los pobres. Por eso, \u00ablos Consejos Evang\u00e9\u00adlicos\u00bb son, por lo que a ella se refiere, ante todo y sobre todo, ese Amor, esa humildad, esa sencillez que la identifi\u00adcan con El en tal aspecto y que, al mis\u00admo tiempo y tambi\u00e9n con El, la acercan a los m\u00e1s desheredados. El Amor de Jes\u00fas Crucificado la apremia, porque \u00absi el amor de Dios es un fuego, el celo es su llama; si el Amor de Dios es un sol, el celo es su rayo; el celo (el verda\u00addero, por supuesto) es lo m\u00e1s puro que tiene el Amor de Dios\u00bb. Y si de la hu\u00admildad se trata, \u00abdecidme, puntualiza San Vicente, \u00bfc\u00f3mo podr\u00eda un orgulloso acomodarse con la pobreza? Nuestro fin es el pobre pueblo, gente ruda y gro\u00adsera. Ahora bien, si no nos ponemos a su alcance, no les seremos de ning\u00fan provecho\u00bb&#8230; Lo mismo en cuanto a la sencillez: \u00abPues bien, si debe haber en el mundo personas que tengan que po\u00adseer la sencillez, son los Misioneros, porque toda nuestra vida est\u00e1 dedicada a ejercer actos de caridad, ya hacia Dios ya hacia el pr\u00f3jimo. Y tanto para una cosa como para otra, hace falta sencillez.\u00bb<\/p>\n<p>No era distinto el lenguaje empleado por Santa Luisa:<\/p>\n<p style=\"padding-left: 30px\"><em>\u00ab\u00a1Ah! \u00a1Cu\u00e1nto he deseado que este di\u00ad<\/em><em>vino Esp\u00edritu perfeccione de continuo a la <\/em><em>Iglesia, seg\u00fan el deseo del Hijo de Dios, <\/em><em>que, al despedirse de ella<strong>, <\/strong>dijo lo necesi\u00ad<\/em><em>taba!<br \/>\nPero \u00a1oh Esp\u00edritu Santol, os dais en <\/em><em>particular a cada alma, \u00bfPara qu\u00e9? para <\/em><em>depositar en ella el verdadero esp\u00edritu de <\/em><em>Jesucristo y ense\u00f1arle de manera eficaz <\/em><em>sus m\u00e1ximas.\u00bb<\/em><\/p>\n<p>Y convencida de que el Esp\u00edritu act\u00faa en ella y en sus Hermanas para hacer que vivan el Bautismo seg\u00fan las \u00abm\u00e1xi\u00admas evang\u00e9licas\u00bb que hacen de ellas verdaderas Hijas de la Caridad, a\u00f1ade:<\/p>\n<p style=\"padding-left: 30px\"><em>\u00ab\u00a1Dad sencillez a mi alma, Unidad per\u00adfecta! \u00a1Humillad mi coraz\u00f3n, para asentar el fundamento de vuestras gracias! Y que la capacidad de amar que hab\u00e9is puesto en mi alma no se detenga ya nun\u00adca m\u00e1s en el desarreglo de mi propia su\u00adficiencia, que no es, en efecto, m\u00e1s que un obst\u00e1culo y un impedimento al puro amor que he de recibir con la efusi\u00f3n del Esp\u00edritu Santo\u00bb.<\/em><\/p>\n<p>A la luz de estos textos tan profundos se comprende mejor por qu\u00e9 el acoger al Esp\u00edritu y el acercamiento a los pobres no constituyen m\u00e1s que una sola cosa: es el Esp\u00edritu el que crea en nosotros, como dicen las Constituciones, la semejanza con Cristo, manso y humilde de Coraz\u00f3n, centro o n\u00facleo de nuestra vocaci\u00f3n:<\/p>\n<p style=\"padding-left: 30px\"><em>\u00abPracticar\u00e1n todos sus ejercicios, tanto espirituales como corporales, con esp\u00edritu de humildad, sencillez y caridad y en uni\u00f3n de los que Nuestro Se\u00f1or Jesucristo hizo en la tierra, dirigiendo su intenci\u00f3n a este fin desde la ma\u00f1ana y al principio de cada acci\u00f3n principal, particularmente cuando van a servir a los enfermos, y no deben olvidar que es\u00adtas tres virtudes son como las tres facultades del alma que deben animar a todo el cuer\u00adpo en general y a cada miembro en particular de su Comunidad, y que, en una palabra, \u00e9ste es el esp\u00edritu propio de su Compa\u00f1\u00eda.\u00bb (<span style=\"text-decoration: underline\">Reg. Com<\/span>., I, 4.).<\/em><\/p>\n<p>Puesto que aqu\u00ed se trata del \u00abSeguimiento de Cristo\u00bb en la vida de las Hijas de la Caridad, volv\u00e1monos hacia El con tal prop\u00f3sito:<\/p>\n<h2>A. <strong>Adorador del Padre<\/strong><\/h2>\n<h3><strong>1) Contemplar a Cristo <\/strong><strong>y contemplar con Cristo<\/strong><\/h3>\n<p>Jes\u00fas nos ha dicho que El es el \u00abCa\u00admino, la Verdad y la Vida\u00bb. <em>Pero es, a la <\/em><em>vez, el camino y lo que se encuentra al <\/em><em>t\u00e9rmino de ese camino, <\/em>porque es, a la vez tambi\u00e9n, Dios y hombre. Le adora\u00admos y le contemplamos porque es Dios \u2014un solo Dios\u2014 con el Padre y el Esp\u00ed\u00adritu Santo. Ahora bien, en un sentido no menos exacto y no menos importante, podemos y debemos decir que es, para el hombre, como gusta de recordar Juan Pablo II, el Camino, el \u00fanico Cami\u00adno que lo conduce al Padre en el Esp\u00ed\u00adritu.<\/p>\n<p>Cristo est\u00e1 enteramente \u00abvuelto ha\u00adcia el Padre\u00bb y hacia el cumplimiento de su voluntad. Se podr\u00eda decir que esto es lo m\u00e1s esencial, lo m\u00e1s consti\u00adtucional, que se da en El puesto que es lo que traduce su actitud filial. De tal suerte, que no hay para nosotros forma m\u00e1s perfecta de entrar en su actitud de Hijo que la de unirnos a El en esa \u00abmi\u00adrada hacia el Padre\u00bb, la de hacernos \u00abcontemplativos\u00bb con El. Esta \u00abcon\u00adtemplaci\u00f3n\u00bb tendr\u00e1 indudablemente as\u00adpectos y modalidades muy diversos se\u00adg\u00fan las vocaciones y las situaciones en que estemos llamados a vivir. Pero no hay vida espiritual digna de este nom\u00adbre que no conlleve su dimensi\u00f3n con\u00adtemplativa y sus tiempos fuertes de contemplaci\u00f3n. Y aqu\u00ed es donde <em>la Hija <\/em><em>de la Caridad, <\/em>siguiendo las insistentes ense\u00f1anzas de los Fundadores, <em>tiene <\/em><em>que encontrar su manera peculiar de <\/em><em>contemplar a Cristo y de contemplar con <\/em><em>Cristo, <\/em>lo mismo cuando se encuentre junto a los pobres que se lo represen\u00adtan, como en los tiempos propiamente dichos de oraci\u00f3n, ya personal, ya co\u00admunitaria. Ser\u00e1 el Esp\u00edritu quien se lo dictar\u00e1, quien se lo ense\u00f1ar\u00e1, en la me\u00addida en que ella sea d\u00f3cil.<\/p>\n<h3><strong>2) Humildad, sencillez, caridad <\/strong><strong>y actitud filial<\/strong><\/h3>\n<p>Si hay una expresi\u00f3n privilegiada de la actitud filial, es indudablemente <em>la <\/em>(le un amor sencillo y humilde. <em>Y <\/em>al tratar aqu\u00ed m\u00e1s especialmente de la vida de oraci\u00f3n, recordemos dos cosas:<\/p>\n<h4><em>\u2022 Es el Esp\u00edritu de Jes\u00fas el que ora en <\/em><em>nosotros.<\/em><\/h4>\n<p>Nos referimos, por supuesto, a la en\u00adse\u00f1anza tan expl\u00edcita de San Pablo a este respecto. Pero \u00bfpor qu\u00e9 ora en no\u00adsotros el Esp\u00edritu filial con gemidos ine\u00adnarrables? Porque \u2014precisamente por ser Esp\u00edritu filial\u2014 desea ente todo que crezcamos como hijos de Dios en el Hijo, de la misma manera que el ni\u00f1o peque\u00f1ito llora reclamando su alimento, esencial para crecer, para llegar a ser adulto. Observemos de paso porque esto tiene una vinculaci\u00f3n especial con nuestra vocaci\u00f3n, que esta oraci\u00f3n he\u00adcha bajo la acci\u00f3n del Esp\u00edritu es, por el motivo que acabamos de apuntar, inse\u00adparable de la Esperanza, que es la vir\u00adtud del crecimiento en Cristo: ahora bien, nadie, tanto como las Hijas de la Caridad, necesita ser mensajero de Es\u00adperanza. Y nadie, sino el Esp\u00edritu, im\u00adpregnar\u00e1 su oraci\u00f3n de ese amor senci\u00adllo y humilde que debe caracterizarla.<\/p>\n<h4><em>\u2022 Contemplaci\u00f3n <\/em>y <em>sencillez <\/em><em>marchan <\/em><em>unidas.<\/em><\/h4>\n<p>Si la contemplaci\u00f3n es esencialmente una mirada filial dirigida con Jes\u00fas ha\u00adcia el Padre, \u00bfc\u00f3mo no ha de ir ante todo unida a la sencillez? De hecho, los Fundadores siempre situaron la senci\u00adllez en primer lugar en cuanto a su rela\u00adci\u00f3n con Dios, simplic\u00edsimo en su per\u00adfecta unidad.<\/p>\n<p>Si tantas dificultades tenemos para entrar en contemplaci\u00f3n, ello es debido a nuestra \u00abcomplicaci\u00f3n\u00bb. Empezamos por considerarla como algo muy por en\u00adcima de nuestro alcance, como algo ex\u00adcepcional, cuando en realidad se trata de la misma sencillez de nuestra mira\u00adda filial dirigida al Padre en uni\u00f3n con Cristo. Y esto tendr\u00eda que ser tanto m\u00e1s evidente para las Hijas de la Caridad, cuanto que, en funci\u00f3n de su vocaci\u00f3n, San Vicente no ha dejado de ponerlas en guardia frente a confusiones de este tipo y, sobre todo, de orientarlas en una l\u00ednea de sencillez (Cf. conf. sobre la ora\u00adci\u00f3n del 31 de mayo de 1648 y del 13 de octubre de 1658).<\/p>\n<h2><strong>B. Srevidor de su designio de amor<\/strong><\/h2>\n<h3><strong>1) Servidor<\/strong><\/h3>\n<p>Sin duda la palabra \u00abServidor\u00bb es la que mejor expresa y sintetiza las di\u00admensiones preferenciales de Cristo como \u00abRegia de las Hijas de la Cari\u00addad\u00bb. En Cristo Servidor es donde de\u00adben ellas buscar su inspiraci\u00f3n m\u00e1s fundamental, es decir<\/p>\n<h4><em>\u2022 El sentido profundo del servicio.<\/em><\/h4>\n<p>San Vicente dec\u00eda a los Misioneros, el 15 de octubre de 1655:<\/p>\n<p><em>\u00abLas razones que tenemos para entre\u00adgarnos a Dios con el fin de adquirir esta <\/em><em>santa pr\u00e1ctica de cumplir la voluntad de Dios siempre y en todas las cosas&#8230; es <\/em><em>que Nuestro Se\u00f1or nos ha dado ejemplo <\/em><em>de ello, pues no vino a la tierra m\u00e1s que para esto, para hacer la voluntad de Dios <\/em><em>su Padre, llevando a cabo la obra de <\/em><em>nuestra redenci\u00f3n; en esto consist\u00edan <\/em><em>sus delicias, en hacer la voluntad de Dios <\/em><em>su Padre&#8230; iQu\u00e9 dicha hacer siempre y <\/em><em>en todas las cosas la voluntad de Dios! <\/em><em>\u00bfNo es esto hacer lo que el Hijo de Dios <\/em><em>vino a hacer en la tierra, como ya hemos dicho? El Hijo de Dios vino a evangelizar a los pobres; y nosotros, \u00bfno hemos sido enviados a lo mismo? S\u00ed, los misioneros han sido enviados a evangelizar a los po\u00adbres. iQu\u00e9 dicha hacer en la tierra lo mis\u00admo que hizo Nuestro Se\u00f1or, que es ense\u00ad\u00f1ar el camino del Cielo a los pobres!\u00bb <\/em>(Coste XI, 313; S\u00edg. IX\/3, 208.)<\/p>\n<p>Vemos, pues, c\u00f3mo Nuestro Se\u00f1or se pone en estado y en actitud de servicio y que nosotros estamos llamados a en\u00adtrar, con El, en ese mismo estado y en esa misma actitud junto a los pobres. San Vicente habr\u00e1 de usar el mismo lenguaje con las Hijas de la Caridad es\u00adpecialmente en sus c\u00e9lebres conferen\u00adcias sobre las buenas aldeanas y sobre el esp\u00edritu de la Compa\u00f1\u00eda. El acta de erecci\u00f3n de las Hijas de la Caridad como \u00abCofrad\u00eda\u00bb, el 20 de noviembre de 1646, dec\u00eda:<\/p>\n<p>\u00ab&#8230; <em>Y para mejor honrar a Nuestro Se\u00ad\u00f1or, su patrono, tendr\u00e1n en todas sus ac\u00ad<\/em><em>ciones la recta intenci\u00f3n de complacerle <\/em><em>y procurar\u00e1n conformar su vida a la <\/em><em>suya, particularmente en su pobreza, su <\/em><em>humildad, su mansedumbre, su sencillez y su sobriedad.\u00bb <\/em>(C. XIII, 563; S\u00edg. X, 703.)<\/p>\n<p>Son \u00e9stos, en efecto, los rasgos del Esp\u00edritu de Servidor que encontrar\u00e1 su punto culminante en el Misterio Pas\u00adcual. Resultar\u00e1, entonces, evidente que las opciones de Cristo son las de un Servidor que se pone de rodillas ante sus hermanos para lavarles los pies. El mismo, en ese momento, nos dir\u00e1 que por ese \u00abamor-servicio\u00bb se conocer\u00e1 a sus disc\u00edpulos, amor que s\u00f3lo de El puede venir, como se lo explica a Pedro no sin cierta severidad. Eso mismo que\u00adremos significar nosotros tambi\u00e9n por medio de nuestro compromiso vicen\u00adciano y, pese a nuestras debilidades, podremos llegar a anunciar algo de la Buena Nueva si intentamos unirnos e imitar a Cristo Servidor en esa \u00abPas\u00adcua\u00bb que es el acontecimiento fundador de la Nueva Alianza.<\/p>\n<h4><em>\u2022 El sentido profundo de la disponibili\u00ad<\/em><em>dad.<\/em><\/h4>\n<p>\u00abHabiendo amado a los suyos que estaban en el mundo, los am\u00f3 hasta el fin.\u00bb Ya sabemos que ese \u00abhasta el fin\u00bb tiene el doble significado de \u00abhasta el fin de su vida\u00bb y \u00abhasta el extremo\u00bb.<\/p>\n<p>Aqu\u00ed tambi\u00e9n necesitamos de todas las luces de la Fe, de todos los recursos del Esp\u00edritu de Amor \u2014especialmente de un amor sencillo y humilde\u2014 para poder seguir a Jesucristo, para descu\u00adbrirle, y servirle en el pobre. Su abati\u00admiento, ya tan impresionante si le con\u00adtemplamos Ni\u00f1o en el Pesebre o Cruci\u00adficado del Viernes Santo, va a hacerse todav\u00eda m\u00e1s impresionante en esa iden\u00adtificaci\u00f3n suya con el pobre. Verdadera\u00admente, nos ser\u00e1 necesario \u00abdar la vuel\u00adta a la medalla\u00bb para poder reconocerle en ese indigente que, humanamente hablando, acaso me repugna. En ver\u00addad, necesitaremos de mucha perseve\u00adrancia en el amor, de <em>\u00abestar, flexibles, en <\/em><em>la mano de Dios\u00bb, <\/em>seg\u00fan la bella expre\u00adsi\u00f3n de San Vicente (C. IX, 126; conf. esp. n. 208), es decir realmente dispo\u00adnibles al Esp\u00edritu, para participar en la misma fidelidad de Cristo a su Misi\u00f3n de Servidor del<\/p>\n<h3><strong>2) Designio de Amor del Padre<\/strong><\/h3>\n<p>Si la expresi\u00f3n \u00abDios ha muerto en Jesucristo\u00bb tiene un sentido, no puede ser otro que el de Filipenses (2, 6): \u00abEl cual, siendo de condici\u00f3n divina, no re\u00adtuvo \u00e1vidamente el ser igual a Dios. Sino que se despoj\u00f3 de s\u00ed mismo, to\u00admando condici\u00f3n de siervo, haci\u00e9ndose semejante a los hombres, etc.\u00bb Siguien\u00addo la l\u00ednea de los Fundadores, hemos hecho repetidas veces alusi\u00f3n a ese \u00abanonadamiento\u00bb. Dios, en Jesucristo, se ha hecho \u00abMendigo de Amor\u00bb, por\u00adque su Designio sobre nosotros es un Designio de Amor Misericordioso y re\u00adquiere de nuestra parte una respuesta de amor.<\/p>\n<h4><em>\u2022 Amor Misericordioso.<\/em><\/h4>\n<p>Este calificativo es el que le conviene con mayor exactitud, como tan bien lo ha expuesto Juan Pablo II en una enc\u00ed\u00adclica que debemos meditar con fre\u00adcuencia. La palabra no est\u00e1 ahora quiz\u00e1 muy de moda, porque evoca la idea de \u00abtener piedad\u00bb, \u00abinfundir piedad\u00bb, que puede, en efecto, tener resonancias peyorativas, m\u00e1xime en nuestro tiempo en que tanto se exalta la persona y su promoci\u00f3n. Expresa, sin embargo, una verdad esencial, lo mismo que la pala\u00adbra \u00abcondescendencia\u00bb, que tampoco tiene buena prensa, por razones similares.<\/p>\n<p>El Amor de Dios por nosotros no puede ser m\u00e1s que un Amor que tiene piedad, que tiene misericordia, porque somos pobres criaturas y sobre todo pobres pecadores. Y para mostrarnos ese Amor, ha tenido que tomar la iniciativa inaudita de \u00abdescender\u00bb entre nosotros, de hacerse uno de los nuestros. Se comprende por qu\u00e9 Santa Luisa no se cansaba de admirar esa \u00abhumildad\u00bb, esa \u00absencillez\u00bb extraordinarias de Dios en su Amor hacia nosotros y en el que nos pide le tengamos a El, del mismo modo que Isabel de la Trinidad, recien\u00adtemente beatificada, no se cansaba de meditar en \u00abel grande amor\u00bb <em>(propter <\/em><em>nimian caritatem) <\/em>de que habla el Ap\u00f3s\u00adtol (Ef. 2, 4).<\/p>\n<p>Ahora bien, el Esp\u00edritu Santo es ese Amor en persona, esa misericordia en persona: \u00abRecibid el Esp\u00edritu Santo: a quien perdonar\u00e9is los pecados, les se\u00adr\u00e1n perdonados, etc.\u00bb (Jn. 20, 22, ss.) Si hay bautizados que deban, m\u00e1s que ninguno otro, estar impregnados de este Amor, de este Esp\u00edritu, en segui\u00admiento de Jes\u00fas, son indudablemente las Hijas de la Caridad.<\/p>\n<h4><em>\u2022 Amor efectivo.<\/em><\/h4>\n<p>La docilidad al Esp\u00edritu ser\u00e1 la que les permita pasar, incesantemente, del amor afectivo al amor efectivo, del que San Vicente dice que es \u00abel servicio de los pobres emprendido con alegr\u00eda, va\u00adlor, constancia, amor\u00bb.<\/p>\n<p>Nos encontramos como ante el esta\u00adllido, la explosi\u00f3n de Pentecost\u00e9s, ja\u00adm\u00e1s terminada, que no deja a nadie fuera de ese Amor: a todos los hombres y a todo el hombre, a todos los pobres y a todo el pobre, todos amados en Cristo y como Cristo los ama. En cuanto a los Misioneros, como a las hijas de la Cari\u00addad, San Vicente no s\u00f3lo no fijaba nin\u00adg\u00fan l\u00edmite a las obras que hab\u00eda que emprender desde el momento en que se trataba de aut\u00e9nticas llamadas de Dios a trav\u00e9s de los pobres, sino que quer\u00eda estuvi\u00e9ramos en constante alar ta para poderlas o\u00edr y responder a ellas lo mejor posible. Nos pon\u00eda en guardia contra los \u00abque se limitan a una peque\u00ad\u00f1a circunferencia\u00bb (periferia, era la pa\u00adlabra empleada por San Vicente, C. XII, 92; S\u00edg. IX\/3, 397), contra los que creen siempre que se hace demasiado, y pro\u00adfetizaba para la Compa\u00f1\u00eda un futuro en que el Se\u00f1or habr\u00eda de confiarle cada vez mayor n\u00famero de pobres, a condi\u00adci\u00f3n de que se mantuviera fiel a su es\u00adp\u00edritu original.<\/p>\n<h2><strong>C. Evangelizador de los pobres<\/strong><\/h2>\n<h3><strong>1) La Ley de las Bienaventuranzas<\/strong><\/h3>\n<p>Podemos escuchar a los Fundadores que con frecuencia nos dicen: <em>\u00bfC\u00f3mo <\/em><em>encontrar al Se\u00f1or en los pobres, si no\u00ad<\/em><em>sotros mismos no tenemos un coraz\u00f3n <\/em><em>de pobres, seg\u00fan el Evangelio? <\/em>Por eso, pasar por la Ley de las Bienaventuran\u00adzas es la primera condici\u00f3n para vivir de este esp\u00edritu. Y hemos de tener en cuen\u00adta las dos versiones que nos ofrecen San Mateo y San Lucas.<\/p>\n<p>Seg\u00fan el primero, Jes\u00fas empieza por felicitar (iBienaventurados!) a los que se encuentran en esa situaci\u00f3n, la m\u00e1s cercana, la m\u00e1s favorable para recibir el Reino. Son verdaderamente sus disc\u00ed\u00adpulos y a ellos ha sido enviado. Se trata esencialmente de una llamada a la po\u00adbreza interior.<\/p>\n<p>San Lucas opone los pobres a los ri\u00adcos por medio de cuatro bienaventuran\u00adzas y cuatro maldiciones.<\/p>\n<p>En efecto, en el Evangelio, los pobres son a la vez los que no tienen nada pro\u00adpio (con frecuencia como resultado de la opresi\u00f3n y de la injusticia, como los profetas lo hab\u00edan denunciado ya en t\u00e9rminos llenos de vigor) y los que es\u00adt\u00e1n cercanos al Reino por su disponibili\u00addad interior, por el amplio espacio de su coraz\u00f3n. Los signos de la venida del Mes\u00edas son a la vez las curaciones, el remedio ofrecido a los pobres y la bue\u00adna Noticia que se les anuncia. Sabemos muy bien que el pobre, el desprovisto de todo, pide que se le defienda, que se le acoja; molesta a todo el mundo, obli\u00adga a los corazones a revelarse. Por eso\u00a0estamos llamados <em>a una disponibilidad <\/em><em>total y a no contar m\u00e1s que con Dios.<\/em><\/p>\n<p>Las otras bienaventuranzas son como una explicaci\u00f3n, una glosa de la pobre\u00adza. Vivir esas Bienaventuranzas no pue\u00adde ser sino fruto del Esp\u00edritu, y a cuan\u00adtos las viven lo m\u00e1s perfectamente que pueden, Jes\u00fas les dice: iBienaventurados!&#8230; Dios no os abandona&#8230; El Esp\u00edritu no se os escatima. iQu\u00e9 lejos queda esto de las falsas tranquilidades que denunciaba San Vicente!<\/p>\n<h3><strong>2) La Humildad y la Sencillez del <\/strong><strong>Pobre por excelencia<\/strong><\/h3>\n<p>Jes\u00fas es el Pobre por excelencia. Con El es con quien las Hijas de la Caridad tienen que identificarse, d\u00eda tras d\u00eda, si es que quieren encontrarle en el pobre. En este punto fundamental, pueden darse tentaciones sutiles contra las que los Fundadores no cesan de poner en guardia.<\/p>\n<p>Y se comprende por qu\u00e9, en esta misma l\u00ednea, insist\u00edan tanto en la humil\u00addad y la sencillez. No podemos ser dis\u00adc\u00edpulos de Cristo, disc\u00edpulos que cono\u00adcen verdaderamente a su Maestro, si no conocemos profundamente su hu\u00admildad y \u00abcomulgamos\u00bb con ella. A este Cristo humilde, lo encontramos in\u00adseparablemente en el Evangelio y en el pobre, con tal de que dirijamos tanto a uno como a otro una mirada sencilla\u00admente abierta, con tal de que ajuste\u00admos nuestra vida a las interpelaciones que de uno y otro emanan.<\/p>\n<p>Y lo mismo podemos decir de la sen\u00adcillez, porque en ella encontramos la misma disposici\u00f3n do rocoptividad y de disponibilidad a lo divino:<\/p>\n<p><em>\u00abCreedme, hijas m\u00edas, nuestra bajeza <\/em><em>no aparta al Hijo de Dios de nosotros; El <\/em><em>no tiene nada que ver con la grandeza. <\/em><em>Es la grandeza misma, pero quiere cora\u00adzones sencillos y humildes, y cuando los <\/em><em>encuentra, iqu\u00e9 hermoso es verle hacer <\/em><em>en ellos su morada! En la Sagrada Escri\u00ad<\/em><em>tura nos dice que sus delicias consisten <\/em><em>en tratar con los peque\u00f1os. S\u00ed, Hermanas m\u00edas, el gusto de Dios, la alegr\u00eda de Dios, el contento de Dios, por as\u00ed decirlo, con\u00adsiste en estar con los humildes y senci\u00adllos que permanecen en el conocimiento de su miseria; iqu\u00e9 gran motivo de con\u00adsuelo y de esperanza es para nosotros y c\u00f3mo tenemos que humillarnos por ello!\u00bb (C. IX, 392; conf. esp. n. 656.)<\/em><\/p>\n<p>San Vicente precisa que la oraci\u00f3n es uno de los lugares privilegiados para esta comunicaci\u00f3n:<\/p>\n<p><em>\u00ab\u00a1Qu\u00e9 bondad de Dios, tan grande e in\u00adcomprensible al poner sus delicias en co\u00ad<\/em><em>municarse a los sencillos y a los ignoran\u00ad<\/em><em>tes, para darnos a conocer que toda la ciencia del mundo no es m\u00e1s que igno\u00ad<\/em><em>rancia en comparaci\u00f3n con la que El da a <\/em><em>los que se esfuerzan en buscarle por el <\/em><em>camino de la santa oraci\u00f3n!\u00bb <\/em>(C. IX, 422; conf. esp. n. 701.)<\/p>\n<p>Al terminar esta reflexi\u00f3n sobre la manera c\u00f3mo las Hijas de la Caridad est\u00e1n llamadas a seguir a Cristo para ser testigos de su amor hacia los po\u00adbres, recordemos que dichas Hijas de la Caridad <em>confirman su entrega total a <\/em><em>Dios por medio de votos que sit\u00faan a <\/em><em>plena luz lo espec\u00edfico de su vocaci\u00f3n.. <\/em>por una parte, su voto \u00abespecial\u00bb es el de servir a Cristo en los pobres, en la Com\u00adpa\u00f1\u00eda y seg\u00fan su esp\u00edritu, con lo que dan su tonalidad a los compromisos de castidad, pobreza y obediencia. Por otra parte, como hemos tenido muchas ve\u00adces ocasi\u00f3n de decirlo, estos votos son esencialmente \u2014no obstante las impli\u00adcaciones jur\u00eddicas que se les han adherido a lo largo de toda una evoluci\u00f3n hist\u00f3rica\u2014 la expresi\u00f3n de un amor que quiere llegar hasta las \u00faltimas exigen\u00adcias de la radicalidad, dentro de la l\u00ednea propia de la vocaci\u00f3n, el t\u00e9rmino de un caminar espiritual que lleva el compro\u00admiso de la Hija de la Caridad hasta el v\u00ednculo m\u00e1s sagrado entre ella y Jesu\u00adcristo. Sabemos que Santa Luisa suele hablar de <em>ese \u00abpacto\u00bb entre el alma y <\/em><em>Dios, <\/em>designando con esa palabra los votos o, m\u00e1s exactamente, el voto.<\/p>\n<p>Asimilando y viviendo cada vez m\u00e1s su Regla de vida, las Constituciones, las Hi\u00adjas de la Caridad pueden estar seguras de que en ellas encuentran <em>\u00abun compendio del <\/em><em>Evangelio, acomodado al uso que les es m\u00e1s adecuado para unirse a Jesucristo y res\u00ad<\/em><em>ponder a sus designios\u00bb <\/em>(Cf. C. XII, 129; S\u00edg. IX\/3, 427). \u00bfSer\u00eda exagerado decir que es, para ellas, \u00abel Santo Evangelio seg\u00fan San Vicente y Santa Luisa\u00bb?&#8230; En todo caso, esa es \u00absu espiritualidad\u00bb.<em><br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos visto c\u00f3mo en su consideraci\u00f3n de Jesucristo, los Fundadores tienen un \u00abenfoque selectivo\u00bb que constituye precisamente su \u00abcarisma\u00bb y que nosotros debe\u00admos hacer nuestro al vivir el esp\u00edritu de la Compa\u00f1\u00eda: \u00abCuando se dice: &#8230; <a href=\"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":139712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[226,199],"tags":[172],"class_list":["post-54587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritualidad-vicenciana","category-hijas-de-la-caridad","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apresados por Jesucristo - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apresados por Jesucristo - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Hemos visto c\u00f3mo en su consideraci\u00f3n de Jesucristo, los Fundadores tienen un \u00abenfoque selectivo\u00bb que constituye precisamente su \u00abcarisma\u00bb y que nosotros debe\u00admos hacer nuestro al vivir el esp\u00edritu de la Compa\u00f1\u00eda: \u00abCuando se dice: ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-13T05:30:50+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Apresados por Jesucristo\",\"datePublished\":\"2015-02-13T05:30:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/\"},\"wordCount\":3946,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Espiritualidad vicenciana\",\"Hijas de la Caridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/\",\"name\":\"Apresados por Jesucristo - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-02-13T05:30:50+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/apresados-por-jesucristo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apresados por Jesucristo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apresados por Jesucristo - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/","og_locale":"es_ES","og_type":"article","og_title":"Apresados por Jesucristo - Somos Vicencianos","og_description":"Hemos visto c\u00f3mo en su consideraci\u00f3n de Jesucristo, los Fundadores tienen un \u00abenfoque selectivo\u00bb que constituye precisamente su \u00abcarisma\u00bb y que nosotros debe\u00admos hacer nuestro al vivir el esp\u00edritu de la Compa\u00f1\u00eda: \u00abCuando se dice: ... Read More","og_url":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-02-13T05:30:50+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Apresados por Jesucristo","datePublished":"2015-02-13T05:30:50+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/"},"wordCount":3946,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#primaryimage"},"thumbnailUrl":"","keywords":["Pobreza"],"articleSection":["Espiritualidad vicenciana","Hijas de la Caridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/","url":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/","name":"Apresados por Jesucristo - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-02-13T05:30:50+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/apresados-por-jesucristo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Apresados por Jesucristo"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-ecr","jetpack-related-posts":[{"id":131671,"url":"http:\/\/vincentians.com\/es\/participes-del-espiritu-de-cristo\/","url_meta":{"origin":54587,"position":0},"title":"Part\u00edcipes del Esp\u00edritu de Cristo","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/02\/2015","format":false,"excerpt":"\"Pedimos a Dios que os d\u00e9 pleno conocimiento de su designio, con todo el saber e inteligencia que procura el Esp\u00edritu. As\u00ed vivir\u00e9is como el Se\u00f1or se merece, agrad\u00e1ndole en todo: dando fruto\u00a0 creciente en toda actividad, gracias al conocimiento de Dios; fortalecidos en todo aspecto por el poder que\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"OXYGEN Volume 8","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/11\/thespirit-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":120297,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-la-fe-que-dio-sentido-a-su-vida-vii-obrar-segun-el-espiritu-de-dios\/","url_meta":{"origin":54587,"position":1},"title":"Vicente de Pa\u00fal: la fe que dio sentido a su vida. VII. Obrar seg\u00fan el Esp\u00edritu de Dios","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/01\/2015","format":false,"excerpt":"VII. Obrar seg\u00fan el Esp\u00edritu de Dios El Se\u00f1or Vicente cre\u00eda en el diablo. Y aun hablaba de \u00e9l m\u00e1s a menudo que del Esp\u00edritu Santo. Pero no debe dete\u00adnerse uno en esta comprobaci\u00f3n simplista, si uno quiere dar cuenta de su verdadero pensamiento. Habla \u00e9l constantemente de Dios, que\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"Vincent-de-Paul-and-bible-alternate","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/Vincent-de-Paul-and-bible-alternate-216x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387816,"url":"http:\/\/vincentians.com\/es\/espiritu-de-jesus-espiritu-de-la-familia-vicenciana\/","url_meta":{"origin":54587,"position":2},"title":"Esp\u00edritu de Jes\u00fas, esp\u00edritu de la Familia Vicenciana","author":"Mitxel Olabu\u00e9naga","date":"14\/09\/2016","format":false,"excerpt":"El Esp\u00edritu de Jes\u00fas es el Esp\u00ed\u00adritu Santo, Se\u00f1or y dador de vida, trasmitido a los cristianos por la participaci\u00f3n en la misi\u00f3n sacerdotal de Jesucristo. Pero se en\u00adtiende tambi\u00e9n por esp\u00edritu de Jes\u00fas un talante o estilo de vida que le distingue de los maestros de la Ley. Jes\u00fas\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/espiritu-de-jesus.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":116856,"url":"http:\/\/vincentians.com\/es\/sentido-vicenciano-del-termino-espiritu\/","url_meta":{"origin":54587,"position":3},"title":"Sentido vicenciano del t\u00e9rmino \u00abEsp\u00edritu\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"22\/05\/2015","format":false,"excerpt":"\u00a1Qu\u00e9 negocio tan importante \u00e9ste de revestirse del esp\u00edritu de Cristo! (XI, 410). 1) San Vicente us\u00f3 el t\u00e9rmino \"esp\u00edritu\" dentro de circunstancias extrema\u00addamente variadas. Si empezamos por lo alto, dice el P. Dodin, san Vicente habla del esp\u00edritu de Dios, despu\u00e9s del esp\u00edritu de Jes\u00fas, luego del esp\u00edritu del\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"christ_spirit","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/christ_spirit-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":140961,"url":"http:\/\/vincentians.com\/es\/en-comunidad-como-jesus-con-sus-discipulos\/","url_meta":{"origin":54587,"position":4},"title":"En comunidad como Jes\u00fas con sus disc\u00edpulos","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/02\/2015","format":false,"excerpt":"\u00abPor aquel entonces se fue \u00ada la monta\u00f1a a orar y se pas\u00f3 \u00adla noche orando a Dios. Cuando se hizo de d\u00eda llam\u00f3 a sus disc\u00edpulos, escogi\u00f3 a doce de ellos y los nombr\u00f3 ap\u00f3stoles\u00bb. (Lc 6,12-13). \u00abSeguimos a Cristo que convoca a los ap\u00f3stoles y disc\u00edpulos y que\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/asd3-300x195.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":142214,"url":"http:\/\/vincentians.com\/es\/obedientes-como-jesucristo\/","url_meta":{"origin":54587,"position":5},"title":"Obedientes como Jesucristo","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/04\/2015","format":false,"excerpt":"\u00abEl, a pesar de su condici\u00f3n divina, no se aferr\u00f3 a su ca\u00adtegor\u00eda de Dios; al contrario, se despoj\u00f3 de su rango y tom\u00f3 la condici\u00f3n de escla\u00advo, haci\u00e9ndose uno de tan\u00adtos. As\u00ed, present\u00e1ndose como simple hombre, se abaj\u00f3, obedeciendo hasta la muerte y muerte de cruz\u00bb. (FI 2,6-8). \u00abConscientes\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"asd","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/asd22.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/54587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=54587"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/54587\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=54587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=54587"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=54587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}