{"id":5388,"date":"2015-02-24T04:25:39","date_gmt":"2015-02-24T03:25:39","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/?p=5388"},"modified":"2020-01-20T16:08:08","modified_gmt":"2020-01-20T15:08:08","slug":"vicente-de-paul-y-la-biblia","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/","title":{"rendered":"Vicente de Pa\u00fal y la Biblia"},"content":{"rendered":"<p>Una triple constante determina el m\u00e9todo para mejor conocer las relaciones de san Vicente de Pa\u00fal con la Biblia.<\/p>\n<h2><strong>Las alternativas biogr\u00e1ficas <\/strong><\/h2>\n<p>Cuatro biograf\u00edas aseguraron, durante dos siglos y medio<span id='easy-footnote-1-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-1-5388' title='1664-1932'><sup>1<\/sup><\/a><\/span>, el conocimiento de la vida, ense\u00f1anzas y doctrina del fundador de la Misi\u00f3n: la de Louis Abelly en 1664; la de Pierre Collet en 1748; la de Ulyses Maynard en 1860; y la de Pierre Coste en 1932. Fueron cuatro presentaciones destinadas a armonizar la existencia del renovador de la Iglesia con otras tantas situaciones nuevas: la muerte de Vicente de Pa\u00fal<span id='easy-footnote-2-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-2-5388' title='27 de septiembre de 1660'><sup>2<\/sup><\/a><\/span> ; la canonizaci\u00f3n<span id='easy-footnote-3-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-3-5388' title='1737'><sup>3<\/sup><\/a><\/span> y el fin, o el apaciguamiento, de las pol\u00e9micas jansenistas; el auge del catolicismo social; el renacimiento de la Misi\u00f3n tras la primera guerra mundial. Las cuatro biograf\u00edas aparecieron por mandato institucional, y estaban s\u00f3lidamente garantizadas, pero ten\u00edan asimismo el efecto de inmovilizar. Bastaron aun as\u00ed a fecundar la imaginaci\u00f3n de pintores, escultores, grabadores, imagineros de Epinal y de otras partes. Su poder se intensific\u00f3 cuando, el a\u00f1o 1947, Pierre Fresnay, en el filme de Maurice Cloche, dot\u00f3 a aquellas im\u00e1genes de una voz y de una movilidad extraordinarias.<\/p>\n<h2><strong>La riqueza retadora de los textos <\/strong><\/h2>\n<p>Como el alma y el dinamismo sobrenatural de Vicente de Pa\u00fal quedaban velados, era oportuno restaurar la juntura, o aun la corriente entre las efigies y las palabras del personaje. La operaci\u00f3n dio comienzo en 1920-1925, cuando Pierre Coste edit\u00f3 la Correspondencia, las Conferencias y los principales Documentos en 13 vol\u00famenes, enriquecidos por un \u00edndice, y prolongados en 1970 por un 15\u00ba volumen que conten\u00eda Cartas y Conferencias, y la bibliograf\u00eda de las biograf\u00edas en lengua francesa.<\/p>\n<p>La mole de este acopio provoc\u00f3 una temerosa reverencia. Sin embargo, representaba apenas una d\u00e9cima parte de lo que Vicente escribi\u00f3 o dijo. Nada obst\u00f3 el que estas 8.700 reunieran textos tan diferentes, cuales son los contratos, los informes sobre una situaci\u00f3n, los consejos religiosos, las reglas de gobierno y las notas necrol\u00f3gicas. Esta diversidad revelaba simult\u00e1neamente la extensi\u00f3n, la variedad y la movilidad extrema de la actividad vicenciana. Al mismo tiempo, todos pod\u00edan comprobar la flexibilidad extraordinaria de aquel esp\u00edritu, que cita m\u00e1s de 3.500 veces la Sagrada Escritura, adapt\u00e1ndola a las necesidades de sus interlocutores. Al escribir o &#8211; desde 1643 \u2013 dictar sus cartas, Vicente atend\u00eda antes que nada a su corresponsal, y aduc\u00eda el texto b\u00edblico apropiado. Si se dirig\u00eda a las Hijas de la Caridad<span id='easy-footnote-4-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-4-5388' title='1634-1660'><sup>4<\/sup><\/a><\/span>, su estilo se hac\u00eda m\u00e1s vivaz y pintoresco. Los preceptos se hac\u00edan m\u00e1s imperiosos y los personajes de la Escritura parec\u00edan presentar el mismo atuendo y las mismas reacciones que los que las Hijas de la Caridad ve\u00edan diariamente en la calle o en su diminuta comunidad. Cuando hablaba a los misioneros, Vicente mezclaba la an\u00e9cdota y la noticia con las ense\u00f1anzas evang\u00e9licas. Pero hab\u00eda rele\u00eddo a sus autores antes de tomar la palabra al fin del d\u00eda, o bien en la meditaci\u00f3n de la ma\u00f1ana. Es bien perceptible en la conferencia del 7 de marzo de 1659, sobre la conformidad con la voluntad de Dios, donde hallamos frases del capuchino Benito de Canfield, autor de la Regla de perfecci\u00f3n<span id='easy-footnote-5-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-5-5388' title='SVP, XI, 445-457'><sup>5<\/sup><\/a><\/span> \u00bfNo iba a vigilar la exactitud de las citas escritur\u00edsticas delante de sus sacerdotes?<\/p>\n<h2><strong>Un biblismo tard\u00edo <\/strong><\/h2>\n<p>Una lectura cr\u00edtica tambi\u00e9n revela que, antes de 1617, es decir, antes de cumplir los 36 a\u00f1os, Vicente no emplea la Biblia, y nos hace sospechar que la conoc\u00eda poco. En 1607 le o\u00edmos hablar de la \u00abfortuna\u00bb, cuando exhuma de una teolog\u00eda muy escolar un Dios calculador bastante brumoso. Habla de Dios, de la Providencia, de la Virgen; pero el nombre y el rostro de Jes\u00fas aparecen por primera vez en el reglamento de la caridad de Ch\u00e2tillon el mi\u00e9rcoles 23 de agosto de 1617<span id='easy-footnote-6-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-6-5388' title='SVP, X, 567-573'><sup>6<\/sup><\/a><\/span>.<\/p>\n<p>La explicaci\u00f3n de tan tard\u00eda apertura a la Biblia es muy prosaica. Subdi\u00e1cono desde el 11 de diciembre de 1598, Vicente pod\u00eda con facilidad hallar en su breviario los 150 salmos atribuidos David. Pero debemos plantearnos algunas cuestiones poco habituales. \u00bfQu\u00e9 breviario se imprim\u00eda entonces? \u00bfD\u00f3nde se lo pod\u00eda hallar y cu\u00e1nto deb\u00eda pagarse para adquirirlo? \u00bfC\u00f3mo lo llevaba uno consigo? Poseemos en efecto<span id='easy-footnote-7-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-7-5388' title='Par\u00eds, 95, rue de S\u00e8vres, sala de reliquias'><sup>7<\/sup><\/a><\/span> los dos tomos del breviario que se encontr\u00f3 en la habitaci\u00f3n de Vicente cuando muri\u00f3. Los recogi\u00f3 el capell\u00e1n de Ana de Austria y, en 1664, se los dio a Michel Caset, sacerdote de la Misi\u00f3n. Al cabo de un periplo que condujo, de la biblioteca de Sens a una venta p\u00fablica, los adquiri\u00f3 en 1850, por la suma de 1.500 francos, Sor Mazin, Superiora General de las Hijas de la Caridad, quien aquel mismo a\u00f1o los remiti\u00f3 a rue de S\u00e9vres. Esos dos paralelep\u00edpedos rectangulares<span id='easy-footnote-8-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-8-5388' title='185 x 120 x 75 mm'><sup>8<\/sup><\/a><\/span> se imprimieron en 1656, y pesan cada uno 1.550 g. Son 3,100 kg. de no f\u00e1cil manejo y transporte.<\/p>\n<p>Cierto que desde 1625, en el Colegio de los Buenos Hijos y sobre todo en el priorato de San L\u00e1zaro, donde hab\u00edan reunido los Victorinos varios millares de vol\u00famenes, pod\u00eda Vicente consultar 101 Biblias latinas y 51 int\u00e9rpretes de la Biblia<span id='easy-footnote-9-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-9-5388' title='cfr., Biblioth\u00e8que mazarine, ms. 4169'><sup>9<\/sup><\/a><\/span>. Pero \u00bfdispondr\u00eda de tiempo y medios para examinar aquel gran \u00abin-folio\u00bb en su cuarto, de una desnudez ejemplar?<\/p>\n<p>De haber tenido tiempo y material b\u00edblico, su estudio habr\u00eda llegado a resultados muy diferentes de los que comprobamos. La curiosidad, aquella peste que le acosaba, s\u00f3lo le habr\u00eda posibilitado la adquisici\u00f3n de conocimientos profanos y utilitarios<span id='easy-footnote-10-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-10-5388' title='SVP, XI, 514'><sup>10<\/sup><\/a><\/span>. Pero sobre todo, no le hab\u00eda alcanzado a\u00fan el Cristo que vive en los pobres, no le hab\u00eda capacitado para descifrar la letra de la Escritura. El esp\u00edritu de Vicente a\u00fan no compart\u00eda lo bastante el Esp\u00edritu de Jes\u00fas. Fueron precisos muchos a\u00f1os para preparar esta mutaci\u00f3n profunda y liberar, \u00a1al precio de qu\u00e9 sufrimientos!, un yo preso y confinado a un angosta periferia. La especie de retiro inactivo impuesto por la capellan\u00eda de los Gondi fue un bloqueo. Gozaba adem\u00e1s de otros cuatro beneficios: la abad\u00eda de San Leonardo de Chaumes<span id='easy-footnote-11-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-11-5388' title='17 de mayo de 1610, SVP, X, 17'><sup>11<\/sup><\/a><\/span>, el curato de Clichy<span id='easy-footnote-12-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-12-5388' title='2 de mayo de 1612, SVP, X, 27'><sup>12<\/sup><\/a><\/span>, el curato de Gamaches<span id='easy-footnote-13-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-13-5388' title='28 de noviembre de 1614'><sup>13<\/sup><\/a><\/span>, la canonj\u00eda de Ecuis<span id='easy-footnote-14-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-14-5388' title='27 de mayo de 1615, SVP, X, 30'><sup>14<\/sup><\/a><\/span>. Progresivamente percibi\u00f3 que todas estas riquezas eran s\u00f3lo \u00abhumo\u00bb, y que no eran transportables a la eternidad. Achacoso, replegado sobre su interior, empapado de tristeza, hab\u00eda llegado a dudar de todo, de Dios como de s\u00ed mismo<span id='easy-footnote-15-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-15-5388' title='cfr., Abelly, III, 116'><sup>15<\/sup><\/a><\/span>. Hasta la se\u00f1ora de Gondi hab\u00eda llamado su atenci\u00f3n sobre aquel humor ingrato y enojoso<span id='easy-footnote-16-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-16-5388' title='SVP, XI, 725-726'><sup>16<\/sup><\/a><\/span>. Fue preciso que el Cristo de los pobres, encerrado en un agonizante de Gannes, le llamara, le hiciera se\u00f1as, viniera hacia \u00e9l y le diera su modo de mirar, su poder singular de \u00abvolver la medalla\u00bb y de ver las cosas como son en Dios<span id='easy-footnote-17-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-17-5388' title='SVP, XI, 725'><sup>17<\/sup><\/a><\/span>. Ya no era ver algo de Dios en el se\u00f1or general de las Galeras, ni algo de la Virgen Mar\u00eda en la se\u00f1ora de Gondi<span id='easy-footnote-18-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-18-5388' title='SVP, IX, 27, 958'><sup>18<\/sup><\/a><\/span>. Todos los estados de la humanidad dibujaban ante su vista los estados del Hijo de Dios<span id='easy-footnote-19-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-19-5388' title='Abelly, 99'><sup>19<\/sup><\/a><\/span>. Vicente compendi\u00f3 su actitud en una sola frase: \u00abNada me place sino en Jesucristo<span id='easy-footnote-20-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-20-5388' title='Abelly, 95-96'><sup>20<\/sup><\/a><\/span>. El Cristo llegado de Gannes le puso ante los ojos algo que habr\u00eda podido sospechar, que hab\u00eda mirado sin verlo o adivinado sin comprenderlo. Los pobres, que ten\u00edan s\u00f3lo pastores mercenarios, incapaces de instruirles, de guardarles, de guiarles, estaban en peligro de perdici\u00f3n. Con su miseria y sufrimiento, demostraban y hac\u00edan sentir que Cristo agonizar\u00eda hasta el fin de los tiempos, que el Jes\u00fas ag\u00f3nico no efect\u00faa \u00c9l solo, en un instante, en un reducto del mundo, la redenci\u00f3n. \u00c9sta se prolonga hasta que el mundo acabe, hasta que Dios est\u00e9 todo en todos<span id='easy-footnote-21-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-21-5388' title='1Cor 15,28'><sup>21<\/sup><\/a><\/span>. La Regla de perfecci\u00f3n, que el buen Monsieur Andr\u00e9 Duval puso en sus manos probablemente el a\u00f1o 1610, le hab\u00eda convencido de que lo \u00fanico necesario era unir el fondo m\u00e1s profundo de su ser a un Dios misterioso y trascendente. Percib\u00eda ahora c\u00f3mo el Dios que le hac\u00eda part\u00edcipe de su omnipotencia, le ped\u00eda amarle d\u00e1ndose a \u00c9l en los pobres, sagrarios que encerraban su amor pur\u00edsimo. Hay que amar, pues, verdaderamente, es decir \u00aba expensas de nuestros brazos, \u2026 con el sudor de nuestro rostro\u00bb<span id='easy-footnote-22-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-22-5388' title='SVP, XI, 733; Abelly, 98'><sup>22<\/sup><\/a><\/span>. Vicente tuvo el beneficio de una evidencia inolvidable: Dios se revela a quienes se dan a \u00c9l. No se entrega m\u00e1s que a quienes le buscan, a quienes en esa b\u00fasqueda misteriosa e incesante, se eternizan en Jesucristo. En adelante, la mirada de Vicente se fijar\u00e1 en el rostro iluminador de Cristo Jes\u00fas no menos que en el rostro de los pobres, en quienes Cristo mora m\u00edsticamente, y vela como un amor en la noche.<\/p>\n<h2><strong>Una hermen\u00e9utica inventiva<\/strong><\/h2>\n<p>El recurso a las realidades invisibles ilumina algo la agilidad desconcertante de la hermen\u00e9utica vicenciana. Catequista por naturaleza y por vocaci\u00f3n, el bueno del se\u00f1or Vicente tiene la preocupaci\u00f3n casi obsesiva de lograr que los pobres conozcan bien la buena nueva del Hijo de Dios<span id='easy-footnote-23-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-23-5388' title='Lc 4,18; Mt 5,3'><sup>23<\/sup><\/a><\/span>. Jes\u00fas mismo le suministra el m\u00e9todo mejor adaptado, y tambi\u00e9n el m\u00e1s f\u00e1cil. Adem\u00e1s de emplear el \u00abpeque\u00f1o m\u00e9todo\u00bb<span id='easy-footnote-24-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-24-5388' title='SVP, 164-187'><sup>24<\/sup><\/a><\/span>, el Salvador escogi\u00f3 las comparaciones m\u00e1s comunes: \u00ab\u00a1Qu\u00e9 maravillas podr\u00eda \u00e9l haberle ense\u00f1ado al pueblo! \u00a1Qu\u00e9 secretos no habr\u00eda podido descubrir de la divinidad y de sus admirables perfecciones, \u00e9l que era la sabidur\u00eda eterna de su Padre! Pero ya ve usted c\u00f3mo hablaba de forma inteligible y se serv\u00eda de comparaciones familiares: el labrador, el vi\u00f1ador<span id='easy-footnote-25-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-25-5388' title='Cfr. Mt 13, 21,40'><sup>25<\/sup><\/a><\/span>, el campo, la vi\u00f1a<span id='easy-footnote-26-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-26-5388' title='Cfr. Mt 13,31.38.44; Lc 12,16.28; Jn 15,1.5'><sup>26<\/sup><\/a><\/span>, el grano de mostaza<span id='easy-footnote-27-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-27-5388' title='Cfr. Mt 13,31'><sup>27<\/sup><\/a><\/span>. \u00abAs\u00ed es como tiene usted que hablar, si quiere que le entienda el pueblo, al que anuncia la palabra de Dios\u00bb<span id='easy-footnote-28-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-28-5388' title='SVP, XI, 239'><sup>28<\/sup><\/a><\/span>\n<p>Observ\u00e1ndole mejor, descubrimos que el pensamiento y la expresi\u00f3n de este catequista b\u00edblico explotan su reflexi\u00f3n y la fundamentan en una doble mediaci\u00f3n circundante.<\/p>\n<p>La primera, la de la gracia que parte del Padre, se manifiesta en el Hijo, se difunde en el Esp\u00edritu. Esta gracia, derramada por el Esp\u00edritu en los corazones, invita a unirse a Jesucristo para unirse al Padre. La segunda afianza y crea su lenguaje partiendo de los pobres. Los pobres constituyen el coraz\u00f3n de la Iglesia: \u00abEs entre ellos, entre esa pobre gente, donde se conserva la verdadera religi\u00f3n, la fe viva; creen sencillamente, sin hurgar; sumisi\u00f3n a las \u00f3rdenes, paciencia en las miserias que hay que sufrir mientras Dios quiera, unos por las guerras, otros por trabajar todo el d\u00eda bajo el ardor del sol; pobres vi\u00f1adores que nos dan su trabajo, que esperan que recemos por ellos, mientras que ellos se fatigan para alimentarnos&#8230; Vivimos del patrimonio de Jesucristo, del sudor de los pobres\u00bb<span id='easy-footnote-29-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-29-5388' title='SVP, XI, 120-121'><sup>29<\/sup><\/a><\/span>. Los pobres son los se\u00f1ores y los maestros<span id='easy-footnote-30-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-30-5388' title='SVP, IX, 42, 43, 95, 125, 211, 214, 634, 862, 863, 915, 916, 922, 1137, 1194; XI, 273, 324'><sup>30<\/sup><\/a><\/span>. No es s\u00f3lo que Nuestro Se\u00f1or considere como hecho a \u00c9l mismo lo que se hace a los pobres: es que adem\u00e1s est\u00e1 en los pobres: Cum ipso sum in tribulatione<span id='easy-footnote-31-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-31-5388' title='Sal 90,15'><sup>31<\/sup><\/a><\/span>. Hablando de los pobres: \u00abSi \u00e9l est\u00e1 enfermo, yo tambi\u00e9n lo estoy; si est\u00e1 en la c\u00e1rcel, yo tambi\u00e9n; si tiene grilletes en los pies, los tengo yo con \u00e9l\u00bb<span id='easy-footnote-32-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-32-5388' title='SVP, IX, 1194'><sup>32<\/sup><\/a><\/span>. J.-B. Bossuet expondr\u00e1 el origen, el sentido y la garant\u00eda de la eminente dignidad de los pobres, en el serm\u00f3n de fin de a\u00f1o, 1659, pronunciado en la capilla de las Hijas de la Providencia<span id='easy-footnote-33-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-33-5388' title='Oeuvres oratoires, ed. Le Barq, revisi\u00f3n de Ch. Urbain y E. Levesque, Par\u00eds 1927, t. III, pp. 119-138'><sup>33<\/sup><\/a><\/span>.<\/p>\n<p>Nadie escoge a su amo, como nadie escoge a los pobres, pues Dios ha dado a \u00e9stos el sobrenatural poder de integrarnos psicol\u00f3gicamente, por el coraz\u00f3n, el esp\u00edritu y la fe en la Iglesia de Jes\u00fas. Sin darnos lugar a duda, ellos nos asocian a la Redenci\u00f3n, que se perpet\u00faa en ellos m\u00e1s dolorosamente que en cualquier otra criatura. He ah\u00ed por qu\u00e9 \u00ablos pobres asistidos por ella ser\u00e1n sus intercesores delante de Dios; acudir\u00e1n en mont\u00f3n a su encuentro\u00bb y el abrir\u00e1n las puertas del para\u00edso<span id='easy-footnote-34-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-34-5388' title='SVP, IX, 241'><sup>34<\/sup><\/a><\/span>.<\/p>\n<p>En lo m\u00e1s hondo de su conciencia abriga Vicente algunas convicciones inconmovibles, que \u00e9l formula diversamente seg\u00fan las ocasiones. La primera es que el hombre nunca permanece en el mismo estado. Es algo que ha o\u00eddo decir a Job<span id='easy-footnote-35-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-35-5388' title='14,2'><sup>35<\/sup><\/a><\/span>, campe\u00f3n del debate, y de lo cual no cesar\u00e1 de servirse<span id='easy-footnote-36-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-36-5388' title='SVP, III, 571; IV, 270, 450;V, 297, 581,600; VI, 509; IX, 597; XI, 38; X, 397'><sup>36<\/sup><\/a><\/span>. La segunda es, algo expresado por la Escritura en diferentes libros<span id='easy-footnote-37-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-37-5388' title='Re 2,6; Dt 32,39; Tob 3,12; Sab 16,13'><sup>37<\/sup><\/a><\/span>, que Dios solo da la vida y la muerte. \u00c9l mortifica y vivifica<span id='easy-footnote-38-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-38-5388' title='SVP, VI, 119, 465, 472, 507; VII, 17; VIII, 200, 201, 2004, 208'><sup>38<\/sup><\/a><\/span>. La tercera es, que Dios \u00abha querido que todas las cosas del mundo sean inciertas y perecederas, a fin de que busc\u00e1semos s\u00f3lo en \u00e9l la solidez de nuestros deseos y de nuestros asuntos<span id='easy-footnote-39-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-39-5388' title='SVP, VI, 392'><sup>39<\/sup><\/a><\/span>. Las degradaciones de la humanidad, permitidas por Dios, est\u00e1n destinadas a ense\u00f1ar a nuestra d\u00e9bil conciencia, que Dios solo hace bien todo cuanto es hecho, y que a \u00c9l corresponde, a \u00c9l solo, el acabar aquello mismo que comenz\u00f3. La una y media de la ma\u00f1ana del 27 de septiembre de 1660, fue el momento de su muerte: al serle pedida en aquel trance la bendici\u00f3n para la familia, responde: \u00abDios la bendiga\u00bb, y dice alzando la mano, Qui coepit opus perficiet<span id='easy-footnote-40-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-40-5388' title='Flp 1, 6'><sup>40<\/sup><\/a><\/span>.<\/p>\n<p>Se dirige a auditorios muy diferentes: feligreses y ni\u00f1os de Clichy, y puede que tambi\u00e9n de Ch\u00e2tillon-les-Dombes; Damas de la Caridad o Hijas de la Caridad; sacerdotes o hermanos de la Misi\u00f3n, y Vicente entonces simplifica, actualiza su exposici\u00f3n. Evoca los personajes, les devuelve la vida y los hace hablar. Termina habitualmente sus pl\u00e1ticas con una oraci\u00f3n dirigida directamente a Jes\u00fas y a la Virgen Mar\u00eda. En Orar con el se\u00f1or Vicente<span id='easy-footnote-41-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-41-5388' title='Paris, 1982,, pp. 84-177'><sup>41<\/sup><\/a><\/span> hemos reunido 84 oraciones. Se extrae de un remoto pasado a algunos seres, tales Ad\u00e1n, No\u00e9, Abraham, Mois\u00e9s, que, para convencernos, nos son presentados llenos de vida. Vicente traduce con garbo 2 Sm 2,2: \u00abUn vistazo perdi\u00f3 a David\u00bb<span id='easy-footnote-42-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-42-5388' title='SVP, IX, 26'><sup>42<\/sup><\/a><\/span>. Nos sorprende y hace sonre\u00edr, cuando o\u00edmos que dice a las Hijas de la Caridad, Nuestro Se\u00f1or \u00abal ir a visitar a los pobres, pasaba delante de las tabernas, se re\u00edan de \u00e9l, se burlaban, y ten\u00eda que escuchar las canciones indecentes y las palabras groseras que se dec\u00edan en aquellos lugares\u00bb<span id='easy-footnote-43-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-43-5388' title='SVP, IX, 797'><sup>43<\/sup><\/a><\/span>. Afirma por las buenas que san Pedro lloraba continuamente<span id='easy-footnote-44-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-44-5388' title='SVP, IX, 257'><sup>44<\/sup><\/a><\/span> y que Margarita Ch\u00e9tif, molesta por llevar en Arras una toca propia de la Isla de Francia, debiera imitar a Nuestro Se\u00f1or, que no cambi\u00f3 de atuendo cuando fue a Egipto<span id='easy-footnote-45-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-45-5388' title='cfr. Mt 2,13ss'><sup>45<\/sup><\/a><\/span><span id='easy-footnote-46-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-46-5388' title='SVP, VI, 110'><sup>46<\/sup><\/a><\/span>. La raz\u00f3n por la cual han de ser sobrias las Hijas de la Caridad, es que Nuestro Se\u00f1or, fuera de la Pascua, cuando toma cordero, y otra ocasi\u00f3n en la que consume pescado, com\u00eda solo pan<span id='easy-footnote-47-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-47-5388' title='cfr., Mc 3,20'><sup>47<\/sup><\/a><\/span><span id='easy-footnote-48-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-48-5388' title='SVP, IX, 96'><sup>48<\/sup><\/a><\/span>. Cuando su memoria se hace lenta o le falla, invierte el orden de las palabras, o bien atribuye a san Pablo y texto del Apocalipsis<span id='easy-footnote-49-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-49-5388' title='Ap 14,13 atribuido a san Pablo cuando escribe a los Corintios, SVP, XI, 433'><sup>49<\/sup><\/a><\/span>. Al citar Sal 65,1 toma en \u00abpr\u00e9stamo\u00bb el texto masor\u00e9tico: \u00abEl silencio es una alabanza a Dios en Sion, dice el profeta, y san Jer\u00f3nimo lo repite\u00bb.<span id='easy-footnote-50-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-50-5388' title='SVP, V, 237'><sup>50<\/sup><\/a><\/span> Sorprendi\u00f3 tal vez al padre Carlos Ozenne, su corresponsal, semejante versi\u00f3n, pero el padre Bernardo Codoing, superior en la casa de Roma, buscar\u00eda vanamente en el Nuevo Testamento un pasaje aducido por su superior: \u00abNuestro Se\u00f1or sab\u00eda bien lo que dec\u00eda, cuando dijo que malum pecus inficit omne pecus<span id='easy-footnote-51-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-51-5388' title='SVP, II, 316'><sup>51<\/sup><\/a><\/span>, frase proveniente de las s\u00e1tiras de Juvenal. Cierto es que la sentencia se hab\u00eda hecho proverbial, y que la Regla de san Benito<span id='easy-footnote-52-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-52-5388' title='c. 8, \u00a7 78'><sup>52<\/sup><\/a><\/span> pide la separaci\u00f3n de la oveja infectada para que no contamine a todo el reba\u00f1o. Vicente no ignoraba la regla benedictina<span id='easy-footnote-53-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-53-5388' title='SVP, X, 425'><sup>53<\/sup><\/a><\/span>.<\/p>\n<h2><strong>Antiguo Testamento<\/strong><\/h2>\n<p>Vicente no ve ruptura alguna entre Antiguo y Nuevo Testamento. La continuidad es homog\u00e9nea, pues Dios va de comienzo en comienzo a trav\u00e9s de comienzos que no tienen fin. \u00abEn la sagrada escritura no hay ninguna palabra de la que no se pueda sacar alg\u00fan fruto, si se explica y se medita con cuidado<span id='easy-footnote-54-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-54-5388' title='SVP, XI, 432'><sup>54<\/sup><\/a><\/span>. En cualquier caso, ve diferentemente el Antiguo Testamento. Considera atentamente esa sucesi\u00f3n de personajes, de los que menciona a 35, y los cuales prepararon con sus palabras la venida y la revelaci\u00f3n del Hijo \u00fanico del Padre. La sucesi\u00f3n forma una procesi\u00f3n orante que camina en la penumbra hacia Cristo. Los salmos atribuidos a David suministran, no s\u00f3lo las expresiones mejores de la adoraci\u00f3n, sino que dan adem\u00e1s las reglas de la buena conducta religiosa. Buen conocedor suyo, Vicente hace frecuente uso de ellos, y hallamos en los escritos vicencianos citas de casi todo el salterio.<\/p>\n<p>Ahora bien, hay cuatro grandes figuras del Antiguo Testamento que retienen de manera particular la atenci\u00f3n de Vicente de Pa\u00fal: Ad\u00e1n, No\u00e9, Abraham y Mois\u00e9s.<\/p>\n<h3><strong>Ad\u00e1n <\/strong><\/h3>\n<p>11 veces hace Vicente menci\u00f3n, entre 1641 y 1659, de la vida y de la ca\u00edda de Ad\u00e1n: 11 veces a las Hijas de la Caridad y 12 veces a los misioneros<span id='easy-footnote-55-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-55-5388' title='SVP, IX, 62, 652, 663, 693, 713, 714, 716, 719, 835, 1006,1206; XI, 33, 128, 131, 447, 448, 512, 522, 523, 526, 743, 788'><sup>55<\/sup><\/a><\/span>. Acent\u00faa sobre todo su desobediencia y la secuelas que afectaron a todo el g\u00e9nero humano. \u00abAd\u00e1n hab\u00eda dado la muerte al cuerpo y hab\u00eda causado la del alma por el pecado\u00bb<span id='easy-footnote-56-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-56-5388' title='SVP, IX, 652'><sup>56<\/sup><\/a><\/span>. A Vicente le gusta las precisiones: \u00abAd\u00e1n desobedeci\u00f3 a Dios, mordiendo la manzana; de all\u00ed brotaron dos males\u00bb<span id='easy-footnote-57-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-57-5388' title='SVP, IX, 693'><sup>57<\/sup><\/a><\/span>. \u00abCuando Eva sinti\u00f3 la tentaci\u00f3n de comer la fruta prohibida, si se hubiera dirigido a Dios, seguramente no habr\u00eda pecado; pero, en vez de descubrirse a Dios, se fue a Ad\u00e1n, su marido, que tambi\u00e9n se puso a desearla y comieron los dos\u00bb<span id='easy-footnote-58-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-58-5388' title='SVP, IX, 1006'><sup>58<\/sup><\/a><\/span>. Haciendo esto, se sustrajo al amor de Dios y perdi\u00f3, para \u00e9l y sus descendientes, su propio dominio.<\/p>\n<p>El G\u00e9nesis afirma<span id='easy-footnote-59-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-59-5388' title='4,1'><sup>59<\/sup><\/a><\/span> que Ad\u00e1n muri\u00f3 a los 930 a\u00f1os, afirmaci\u00f3n que Vicente lleva a\u00fan m\u00e1s lejos: \u00abhizo penitencia y llor\u00f3 su pecado durante m\u00e1s novecientos a\u00f1os\u00bb<span id='easy-footnote-60-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-60-5388' title='SVP, IX, 663'><sup>60<\/sup><\/a><\/span>. Prosigue y glosa Sab 10, 1, seg\u00fan la ampliaci\u00f3n textual de muchos santos padres: \u00abDios tuvo piedad de \u00e9l. De Eva no nos dice nada la Escritura\u00bb<span id='easy-footnote-61-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-61-5388' title='Ib\u00eddem'><sup>61<\/sup><\/a><\/span>. \u00abDios le perdon\u00f3 su pecado, no por eso se vio libre de hacer una larga penitencia\u00bb<span id='easy-footnote-62-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-62-5388' title='SVP, IX, 835'><sup>62<\/sup><\/a><\/span>.<\/p>\n<p>Las consecuencias para la pobre naturaleza humana son que es pecado todo lo que pide: \u00ablas inclinaciones de la carne no son m\u00e1s que pecado; por eso hay que huir de ellas\u00bb<span id='easy-footnote-63-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-63-5388' title='SVP, IX, 1206'><sup>63<\/sup><\/a><\/span>.<\/p>\n<h3><strong>No\u00e9 <\/strong><\/h3>\n<p>La actividad de este patriarca antediluviano es evocada 6 veces por Vicente<span id='easy-footnote-64-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-64-5388' title='SVP, III, 165; VIII, 257; IX, 70, 624; XI, 263, 425'><sup>64<\/sup><\/a><\/span>. El G\u00e9nesis dice que era que era un var\u00f3n justo, y que construy\u00f3 un arca destinada a salvar del diluvio. La primera y segunda ep\u00edstolas de Pedro precisan que fueron ocho las personas salvadas<span id='easy-footnote-65-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-65-5388' title='1P 3,20; 2P 2,5'><sup>65<\/sup><\/a><\/span>.<\/p>\n<p>Vicente de Pa\u00fal atiende sobre todo a dos hechos: la construcci\u00f3n del arca y la actuaci\u00f3n de No\u00e9.<\/p>\n<p>Para la prudencia de Vicente es particularmente aleccionador lo que dur\u00f3 la construcci\u00f3n del arca. Se lo dice a Luisa de Marillac: \u00abCuando quiso salvar a No\u00e9 y a su familia, le mand\u00f3 que hiciese un arca que pod\u00eda haberse acabado en pocos meses, pero su construcci\u00f3n dur\u00f3 sin embargo cien a\u00f1os\u00bb<span id='easy-footnote-66-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-66-5388' title='SVP, VIII, 257'><sup>66<\/sup><\/a><\/span>. Se lo recuerda a las Hijas de la Caridad el 25 de marzo de 1654: \u00ab\u00bfSab\u00e9is cu\u00e1nto tiempo emple\u00f3 No\u00e9 en construir el arca y ponerla en debidas condiciones? Cien a\u00f1os. \u00a1Oh Salvador de nuestras almas! Si para hacer el arca, hermanas m\u00edas, en la que s\u00f3lo se salvaron del diluvio ocho personas, se necesit\u00f3 tanto tiempo, \u00bfcu\u00e1nto cre\u00e9is que se necesita para robustecer y conservar esta Compa\u00f1\u00eda, en donde se refugiar\u00e1n tantas almas y se salvar\u00e1n del diluvio del mundo?\u00bb<span id='easy-footnote-67-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-67-5388' title='SVP, IX, 624'><sup>67<\/sup><\/a><\/span>\n<p>Prolongando el texto del G\u00e9nesis, a\u00f1ade que No\u00e9 fue profeta y predicador de la penitencia, funciones que vemos aludidas en la carta de Clemente Romano a los Corintios: No\u00e9 predic\u00f3 la conversi\u00f3n, y los que le escucharon fueron salvos<span id='easy-footnote-68-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-68-5388' title='ed. Funk, 1901, p. 116'><sup>68<\/sup><\/a><\/span>. Esta actuaci\u00f3n, habitualmente ausente de los escritos patr\u00edsticos, es enunciada en cambio por Tirinius en la Biblia Magna de Estius<span id='easy-footnote-69-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-69-5388' title='Par\u00eds, 1643, t. IV, p. 1045'><sup>69<\/sup><\/a><\/span>, donde se dice que quienes sucumbieron en el diluvio, se salvaron aun as\u00ed, pero fueron relegados al limbo de los justos<span id='easy-footnote-70-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-70-5388' title='cfr., D. Sidersky, Les origines des l\u00e9gendes musulmanes dans le Coran et dans la vie des proph\u00e8tes, Paris, 1933'><sup>70<\/sup><\/a><\/span>. Piensa el Autor que Mahoma, quien menciona la predicaci\u00f3n penitencial de No\u00e9 en la sura 71, recurre al libro de Henoch y al libro de los Jubileos.<span id='easy-footnote-71-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-71-5388' title='Cfr., Ecrits intertestamentaires, 471-623, 635-810'><sup>71<\/sup><\/a><\/span>. La escenificaci\u00f3n de san Vicente es particularmente animada: \u00abDios quiere castigar a todo el mundo; env\u00eda el diluvio universal para castigar los horribles pecados que se comet\u00edan; pero \u00bfqu\u00e9 hace? Le inspira a No\u00e9 el pensamiento de construir un arca<span id='easy-footnote-72-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-72-5388' title='Gn 6, 14'><sup>72<\/sup><\/a><\/span>, y No\u00e9 estuvo construy\u00e9ndola durante cien a\u00f1os. \u00bfPor qu\u00e9 cre\u00e9is que quiso Dios que se tardara tanto tiempo en construir aquel arca, sino para ver si el mundo se convert\u00eda, si hac\u00eda penitencia y se aprovechaba de lo que No\u00e9 les dec\u00eda por la ventana de su arca, gritando a pleno pulm\u00f3n, seg\u00fan algunos autores: \u00abHaced penitencia, pedid perd\u00f3n a Dios\u00bb? Esto nos hace ver una vez m\u00e1s c\u00f3mo, aunque parec\u00eda que Dios deseaba que todo el mundo quedase ahogado bajo las aguas, sus designios eran distintos, ya que quiso que No\u00e9 y toda su familia quedasen libres del naufragio, a fin de repoblar el mundo y para que se llevase a cabo lo que \u00e9l hab\u00eda decidido desde toda la eternidad a prop\u00f3sito del nacimiento de su Hijo\u00bb<span id='easy-footnote-73-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-73-5388' title='SVP, XI, 263, 15 de noviembre de 1656'><sup>73<\/sup><\/a><\/span>.<\/p>\n<h3><strong>Abraham <\/strong><\/h3>\n<p>Para san Vicente Abraham es nada menos que el corifeo de los obedientes verdaderos, de los perfectamente desprendidos, aquellos que han presentido y respetado el misterio de esa trascendencia divina, que desconcierta las previsiones y desbanca los raciocinios. Esta obediencia incondicional sigue paso a paso a la Providencia adorable, lo mismo dejando la propia tierra, que disponi\u00e9ndose a sacrificar al hijo \u00fanico<span id='easy-footnote-74-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-74-5388' title='SVP, I, 350, 548; V, 195; XI, 89, 181, 262, 262, 436, 416, 534'><sup>74<\/sup><\/a><\/span>. Guiado por el autor de la Carta a los Hebreos<span id='easy-footnote-75-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-75-5388' title='11,8'><sup>75<\/sup><\/a><\/span> : \u00abPor la fe Abraham, obediente a la llamada divina, sali\u00f3 hacia una tierra que iba a recibir en posesi\u00f3n, y sali\u00f3 sin saber a donde iba\u00bb<span id='easy-footnote-76-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-76-5388' title='Heb 11, 8'><sup>76<\/sup><\/a><\/span>, Vicente le vuelve a vivir, y se conmueve reviviendo la escena del sacrificio de Isaac.<\/p>\n<p>\u00abA este prop\u00f3sito, acordaos de Abraham, a quien Dios le hab\u00eda prometido poblar toda la tierra por medio de un hijo que ten\u00eda. Pero Dios le pide que se lo sacrifique. Si Abraham hace morir a su hijo, \u00bfc\u00f3mo cumplir\u00e1 Dios su promesa? Sin embargo, Abraham, que ten\u00eda su esp\u00edritu acostumbrado a cumplir la voluntad de Dios, acepta la obligaci\u00f3n de ejecutar esta orden, sin preocuparse de nada m\u00e1s<span id='easy-footnote-77-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-77-5388' title='Gn 22'><sup>77<\/sup><\/a><\/span>. A Dios le toca pensar en ello, pod\u00eda decir; si yo cumplo su mandato, \u00e9l cumplir\u00e1 su promesa; pero \u00bfc\u00f3mo? No lo s\u00e9. S\u00f3lo s\u00e9 que es todopoderoso. Le voy a ofrecer lo m\u00e1s querido que tengo en el mundo, ya que as\u00ed lo quiere. \u00a1Pero es mi hijo \u00fanico! \u00a1No importa! \u00a1Pero, si le quito la vida a este ni\u00f1o, ya no habr\u00e1 medio de que Dios cumpla su palabra! \u00a1Es lo mismo! Si \u00e9l as\u00ed lo quiere, habr\u00e1 que hacerlo. Pero, si lo conservo, mi descendencia ser\u00e1 bendita: Dios lo ha dicho. S\u00ed, pero tambi\u00e9n ha dicho que le d\u00e9 muerte; me lo ha indicado; obedecer\u00e9, pase lo que pase, y esperar\u00e9 en sus palabras. Admirad esta confianza: no se preocupa para nada de lo que puede pasar; sin embargo, la cosa le tocaba muy de cerca; pero espera que todo saldr\u00e1 bien, ya que Dios se mete en ello. \u00bfPor qu\u00e9 no tendremos nosotros esa misma esperanza, si le dejamos a Dios el cuidado de todo lo que nos preocupa y preferimos lo que \u00e9l nos mande?\u00bb<span id='easy-footnote-78-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-78-5388' title='SVP, XI, 436-437'><sup>78<\/sup><\/a><\/span>.<\/p>\n<p>Luego, aclarando el Antiguo Testamento con el Nuevo, Vicente de Pa\u00fal recomienda: \u00abEncerr\u00e9monos, pues, dentro de ella como lo hizo Isaac con la voluntad de Abraham y Jesucristo con la voluntad de su Padre\u00bb<span id='easy-footnote-79-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-79-5388' title='SVP, I, 548'><sup>79<\/sup><\/a><\/span>.<\/p>\n<h3><strong>Mois\u00e9s <\/strong><\/h3>\n<p>San Vicente evoca m\u00e1s de 25 veces la existencia de Mois\u00e9s y su funci\u00f3n excepcional en la constituci\u00f3n y evoluci\u00f3n del pueblo de Dios. Detalle que Vicente ya no olvidar\u00e1 de 1638 en adelante, cuando se organiz\u00f3 la obra de los exp\u00f3sitos. Tambi\u00e9n Mois\u00e9s fue exp\u00f3sito, como R\u00f3mulo y Remo, como Melquisedec, que no tuvo padre, ni madre, ni genealog\u00eda<span id='easy-footnote-80-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-80-5388' title='Heb 7, 3'><sup>80<\/sup><\/a><\/span>. Mois\u00e9s ostentaba cierto parecido con Jes\u00fas, maestro de la nueva ley, que no tuvo padre carnal<span id='easy-footnote-81-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-81-5388' title='SVP, X, 919, 926'><sup>81<\/sup><\/a><\/span>. Pero sobre todo, habiendo sido Mois\u00e9s el mediador que Dios eligi\u00f3 para transmitir la ley<span id='easy-footnote-82-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-82-5388' title='cfr., Ex 19,24'><sup>82<\/sup><\/a><\/span>, son un modelo para los superiores su actitud, su conducta, su comportamiento: \u00abDespu\u00e9s de consultar con Dios, como un nuevo Mois\u00e9s, y de recibir de \u00e9l la ley para d\u00e1rsela a los que va a gobernar. Acu\u00e9rdese de que la forma de gobernar de aquel santo patriarca fue paciente, mansa, tolerante, humilde y caritativa, y que en Nuestro Se\u00f1or estas virtudes alcanzaron su mayor perfecci\u00f3n, a fin de que nosotros nos conform\u00e1semos a ellas\u00bb<span id='easy-footnote-83-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-83-5388' title='SVP, V, 401'><sup>83<\/sup><\/a><\/span>.<\/p>\n<p>A lo largo de todo su historial estuvo Mois\u00e9s sostenido por el poder de Dios, y era tan poderosa su oraci\u00f3n, que hac\u00eda triunfar a los israelitas<span id='easy-footnote-84-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-84-5388' title='Ex 17, 8-13; Jos 5,13; 8,22'><sup>84<\/sup><\/a><\/span> : \u00abUsted es su Mois\u00e9s, que levanta las manos al cielo mientras ellos combaten contra los enemigos de Dios, y tambi\u00e9n su Josu\u00e9 ya que combate junto a ellos con las armas, las ayudas, el entusiasmo y los consejos que les da\u00bb<span id='easy-footnote-85-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-85-5388' title='SVP, V, 473'><sup>85<\/sup><\/a><\/span>. Dios mismo se siente abrumado por la oraci\u00f3n mental de Mois\u00e9s<span id='easy-footnote-86-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-86-5388' title='Ex 32, 9\u00ad10'><sup>86<\/sup><\/a><\/span> : \u00ab\u00a1Gran fuerza la de la oraci\u00f3n mental, hijas m\u00edas, ya que era \u00e9se el ejercicio de Mois\u00e9s, cuando ten\u00eda las manos elevadas al cielo sin pronunciar una palabra; y ten\u00eda suficiente eficacia para hacer que ganaran la batalla aquellos por los que rezaba! La Sagrada Escritura nos refiere tambi\u00e9n que Mois\u00e9s estaba un d\u00eda delante de Dios sin pronunciar palabra. Y escuch\u00f3 la voz de Dios: \u00abMois\u00e9s, me est\u00e1s rompiendo la cabeza; me obligas a hacer lo que no quiero. Este pueblo es ingrato y rebelde a mi ley. Yo quiero castigarlo, pero t\u00fa quieres que lo salve. \u00bfPor qu\u00e9 me obligas? Ret\u00edrate y d\u00e9jame hacer mi voluntad \u00ab<span id='easy-footnote-87-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-87-5388' title='ex 32, 9.10'><sup>87<\/sup><\/a><\/span>, Fijaos, hijas m\u00edas, c\u00f3mo Dios se ve atado por la oraci\u00f3n, y por la oraci\u00f3n mental, ya que Mois\u00e9s no dec\u00eda ninguna palabra, pero su oraci\u00f3n era tan intensa que Dios le dec\u00eda: \u00abMe est\u00e1s rompiendo la cabeza; t\u00fa quieres que haga lo que yo no quiero hacer\u00bb<span id='easy-footnote-88-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-88-5388' title='SVP, IX, 383'><sup>88<\/sup><\/a><\/span>.<\/p>\n<p>En la historia de Israel, Mois\u00e9s figuraba como legislador irrecusable, y en su funci\u00f3n de tal, a \u00e9l encomendada por Dios, le ve siempre Vicente. Legislador tambi\u00e9n \u00e9l, Vicente se complace en recordar, que todos los que se opusieron a Mois\u00e9s fueron duramente castigados por Dios. Para mejor inculcarlo, Vicente aduce con energ\u00eda aquellos pasajes del libro de los N\u00fameros que registran los castigos particularmente disuasorios sobrevenidos a los oponentes. El libro de los N\u00fameros refiere c\u00f3mo, a Cor\u00e9, Dat\u00e1n y Abir\u00f3n, que reclamaban para s\u00ed, en contra de Aar\u00f3n, el ejercicio del sacerdocio, les fue rehusado \u00e9ste, que permaneci\u00f3 como privilegio de los descendientes de Aar\u00f3n<span id='easy-footnote-89-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-89-5388' title='17,5-14'><sup>89<\/sup><\/a><\/span>. Se abri\u00f3 la tierra y los engull\u00f3<span id='easy-footnote-90-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-90-5388' title='16,4-35'><sup>90<\/sup><\/a><\/span>. \u00abTenemos en la ley antigua el ejemplo de Cor\u00e9, Dath\u00e1n y Abir\u00f3n, que fueron tragados vivos por la tierra por haber murmurado contra Mois\u00e9s\u00bb<span id='easy-footnote-91-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-91-5388' title='SVP, X, 846, Consejo de las Hijas de la Caridad, 27 de julio de 1656'><sup>91<\/sup><\/a><\/span>. A\u00f1o y medio despu\u00e9s, cuando habla a los Hijas de la Caridad, san Vicente nos da una versi\u00f3n distinta y m\u00e1s pintoresca: \u00abCuando Mois\u00e9s, que gobernaba el pueblo de Dios, lo conduc\u00eda por el desierto, empezaron a criticar contra aquello Cor\u00e9, Dat\u00e1n y Abir\u00f3n, diciendo que Mois\u00e9s era un mago y murmurando as\u00ed contra \u00e9l y contra las reglas que Dios le hab\u00eda dictado. Pues bien, por permisi\u00f3n divina, la tierra se abri\u00f3 y se los trag\u00f3 el infierno, en castigo por haber murmurado delante del pueblo. Pero no pararon aqu\u00ed las cosas. Ellos fueron causa de que se perdiera la confianza en Mois\u00e9s\u00bb<span id='easy-footnote-92-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-92-5388' title='SVP, IX, 995-996, 30 de diciembre de 1657'><sup>92<\/sup><\/a><\/span>.<\/p>\n<p>De Mar\u00eda, hermana de Mois\u00e9s, sabemos que se irgui\u00f3 contra su hermano porque despos\u00f3 a una cusita. Pues bien, se vio contaminada de lepra, si bien luego san\u00f3, gracias a la oraci\u00f3n su hermano<span id='easy-footnote-93-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-93-5388' title='Nm 12,1-5; cfr., Dt 24,9'><sup>93<\/sup><\/a><\/span>. En julio de 1656, comienza Vicente a colorear algo el suceso: \u00abSu propia hermana se vio contagiada de lepra por haber criticado lo que hac\u00eda\u00bb<span id='easy-footnote-94-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-94-5388' title='SVP, X, 846'><sup>94<\/sup><\/a><\/span>. Dieciocho meses despu\u00e9s se ha enriquecido la psicolog\u00eda de Mar\u00eda: \u00abSucedi\u00f3 que la hermana de Mois\u00e9s, que se llamaba Mar\u00eda 4, habiendo o\u00eddo lo que se dec\u00eda de su hermano, al que hab\u00eda cuidado desde ni\u00f1o, empez\u00f3 a pensar lo mismo al ver las obras que hac\u00eda. Y tambi\u00e9n fue castigada por Dios; pero no quiso mandarla al abismo como a los otros, sino que le envi\u00f3 la lepra, de modo que tuvieron que enviarla al campo por culpa de aquella lepra, en donde ya no pod\u00eda ver a Mois\u00e9s ni o\u00edr hablar de \u00e9l. Aquel fue el castigo que recibi\u00f3\u00bb<span id='easy-footnote-95-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-95-5388' title='SVP, IX, 996'><sup>95<\/sup><\/a><\/span>. \u00abMois\u00e9s recibi\u00f3 \u00f3rdenes de Dios de hacer morir a todos los que recogiesen le\u00f1a en domingo; y esto se observ\u00f3 con toda exactitud\u00bb<span id='easy-footnote-96-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-96-5388' title='SVP, X, 846'><sup>96<\/sup><\/a><\/span><span id='easy-footnote-97-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-97-5388' title='Cfr. Nm 15, 35-38'><sup>97<\/sup><\/a><\/span>.<\/p>\n<p>El 6 de diciembre de 1658 Vicente de Pa\u00fal, que sent\u00eda acerc\u00e1rsele el fin, y deseaba asegurar la permanencia de la Reglas, como tambi\u00e9n su observancia \u2013 las hab\u00eda distribuido a sus disc\u00edpulos el 17 de mayo anterior -, nada mejor supo hacer, que tomar en pr\u00e9stamo las palabras de Mois\u00e9s<span id='easy-footnote-98-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-98-5388' title='Dt 31,29'><sup>98<\/sup><\/a><\/span> : \u00abOs advierto de ello, hermanos m\u00edos, antes de abandonaros, con el mismo esp\u00edritu con que Mois\u00e9s advert\u00eda a los hijos de Israel, seg\u00fan se dice en el Deuteronomio<span id='easy-footnote-99-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-99-5388' title='Dt 31, 29'><sup>99<\/sup><\/a><\/span>, Yo me voy, no me ver\u00e9is<span id='easy-footnote-100-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-100-5388' title='Jn 16, 16'><sup>100<\/sup><\/a><\/span> ; s\u00e9 que algunos de vosotros se levantar\u00e1n para seducir a los dem\u00e1s; har\u00e1n lo que os proh\u00edbo\u00bb<span id='easy-footnote-101-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-101-5388' title='SVP, XI, 396'><sup>101<\/sup><\/a><\/span>.<\/p>\n<p>Iluminado por Cristo Jes\u00fas, cuyo reino prepara, Mois\u00e9s, mediador y legislador, suministra al fundador y legislador de la Misi\u00f3n un modelo de oraci\u00f3n y de gobierno. \u00c9l le dicta discretamente su conducta y le inspira sus \u00faltimas recomendaciones.<\/p>\n<h2><strong>Nuevo Testamento<\/strong><\/h2>\n<p>Era f\u00e1cil de adivinar. M\u00e1s que sobre los 46 libros y 37.501 vers\u00edculos del Antiguo Testamento, se apoya san Vicente sobre los 261 cap\u00edtulos y 2.752 vers\u00edculos del Nuevo, que aplica tanto a su vida personal, como evangelizando a pobres de toda categor\u00eda: \u00abNo hay que desanimarse si, despu\u00e9s de haberlo le\u00eddo varias veces durante un mes, dos meses, seis meses, no se siente uno tocado. Llegar\u00e1 alguna ocasi\u00f3n en que tengamos una peque\u00f1a luz, otro d\u00eda tendremos otra mayor, y otra todav\u00eda mayor cuando la necesitemos. Una sola palabra es capaz de convertirnos: s\u00f3lo basta una, como s\u00f3lo una le bast\u00f3 a san Antonio\u00bb<span id='easy-footnote-102-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-102-5388' title='SVP, XI, 37\u00ad38'><sup>102<\/sup><\/a><\/span>.<\/p>\n<p>El contenido del Nuevo Testamento est\u00e1 bien definido: \u00abEsta doctrina o ley de Jesucristo est\u00e1 contenida en el Nuevo Testamento, bien en lo que nos ense\u00f1an los ap\u00f3stoles, por v\u00eda de inspiraci\u00f3n, o bien por s\u00ed mismo, en los evangelios, donde \u00e9l nos habla de viva voz. Para entenderlo mejor, hay que saber que el nuevo testamento se divide primero en la explicaci\u00f3n de la sagrada escritura y la ampliaci\u00f3n de la misma para instrucci\u00f3n y buena vida del pueblo; en segundo lugar se divide en la instituci\u00f3n del santo sacrificio, de los sacramentos y de las \u00f3rdenes que Jesucristo ha establecido; y en tercer lugar, en doctrina preceptiva, que manda, y directiva o de direcci\u00f3n, que aconseja, y que es lo que llamamos consejos evang\u00e9licos. De esta tercera clase de doctrina evang\u00e9lica, tanto preceptiva como directiva, es de la que queremos hablar en esta charla y de la que hace menci\u00f3n la regla. Tambi\u00e9n las llamamos m\u00e1ximas evang\u00e9licas\u00bb<span id='easy-footnote-103-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-103-5388' title='SVP, XI, 418'><sup>103<\/sup><\/a><\/span>.<\/p>\n<p>Pero Vicente hace una elecci\u00f3n: no es preciso practicar todas las m\u00e1ximas evang\u00e9licas, sino solamente \u00absi no son contrarias al instituto\u00bb<span id='easy-footnote-104-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-104-5388' title='SVP, XI, 428'><sup>104<\/sup><\/a><\/span>.<\/p>\n<p>\u00bfBasta con leer el Nuevo Testamento para comprenderlo y beneficiarse uno de su dinamismo? \u00a1Claro que no! Las m\u00e1ximas del mundo se conocen y comprueban por la experiencia, pero de las m\u00e1ximas de Nuestro Se\u00f1or \u00abconocemos su infalibilidad por su esp\u00edritu, que nos da su conocimiento y que nos hace ver cu\u00e1les son sus divinas consecuencias, ya que, como nos las ense\u00f1a la verdad eterna, son muy verdaderas y siempre alcanzan su efecto\u00bb<span id='easy-footnote-105-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-105-5388' title='SVP, XI, 421'><sup>105<\/sup><\/a><\/span>.<\/p>\n<p>Ser\u00eda un error leer la Escritura para enriquecer uno su arsenal de argumentos, o para ornar de flores el bancal de la ret\u00f3rica: \u00abSobre todo hay que evitar leerlo por estudio, diciendo: \u00abEste trozo me servir\u00e1 para tal predicaci\u00f3n\u00bb, sino leerlo s\u00f3lo para nuestro provecho espiritual\u00bb<span id='easy-footnote-106-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-106-5388' title='SVP, XI, 37'><sup>106<\/sup><\/a><\/span>.<\/p>\n<p>Esta intenci\u00f3n religiosa tiene una traducci\u00f3n concreta en tres disposiciones particulares que Vicente enuncia el 19 de enero de 1642: \u00ab1.\u00ba de adoraci\u00f3n, adorando la palabra de Dios y su verdad; 2.\u00ba entrar en los sentimientos con que las pronunci\u00f3 nuestro Se\u00f1or y aceptar esas verdades; 3.\u00ba resolverse a la pr\u00e1ctica de esas mismas verdades. Por ejemplo, cuando lea: \u00abBienaventurados los pobres de esp\u00edritu\u00bb<span id='easy-footnote-107-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-107-5388' title='Mt 5, 3s'><sup>107<\/sup><\/a><\/span> me resolver\u00e9 y me entregar\u00e9 a Dios para practicar esa verdad en tal y tal ocasi\u00f3n. Lo mismo cuando lea: \u00abBienaventurados los mansos\u00bb<span id='easy-footnote-108-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-108-5388' title='Mt 5, 4'><sup>108<\/sup><\/a><\/span>, me entregar\u00e9 a Dios para practicar la mansedumbre\u00bb<span id='easy-footnote-109-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-109-5388' title='XI, 37'><sup>109<\/sup><\/a><\/span>.<\/p>\n<p>Las Reglas o Constituciones que san Vicente elabor\u00f3 a lo largo de treinta a\u00f1os, y que distribuy\u00f3 a los misioneros el 17 de mayo de 1758, reafirman y precisan el modo de leer religiosamente el Nuevo Testamento, Todos los d\u00edas: \u00abLos sacerdotes y los cl\u00e9rigos leer\u00e1n adem\u00e1s un cap\u00edtulo del Nuevo Testamento. Venerar\u00e1n este libro como regla de la perfecci\u00f3n cristiana. Y para que m\u00e1s aproveche, lo leer\u00e1n de rodillas, con la cabeza descubierta, a\u00f1adiendo al final estos tres actos: 1\u00b0 adorar las verdades contenidas en el cap\u00edtulo le\u00eddo; 2\u00b0 animarse a revestirse del esp\u00edritu con que las dijeron Cristo y los Santos; 3\u00b0 proponerse imitar los consejos, normas y ejemplos de virtud que hayan encontrado en la lectura\u00bb<span id='easy-footnote-110-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-110-5388' title='RC, X, 5'><sup>110<\/sup><\/a><\/span>.<\/p>\n<p>Vicente ense\u00f1aba en especial este modo de entrar en el texto y de impregnarse de \u00e9l, por su modo de celebrar el santo sacrificio de la misa. Uno de los m\u00e1s antiguos en la Compa\u00f1\u00eda observ\u00f3 que, en la celebraci\u00f3n de la misa, la devoci\u00f3n de san Vicente era del todo singular, y esto se advert\u00eda particularmente en su manera de leer el santo evangelio. Otros observaron que, al topar con ciertas palabras pronunciadas por Nuestro Se\u00f1or, Vicente las recitaba en un tono de voz m\u00e1s tierno y afectuoso, lo cual infund\u00eda devoci\u00f3n en los asistentes que le escuchaban; y en varias ocasiones se oy\u00f3 a personas que no le conoc\u00edan de nada decirse unas a otras: \u00abDios m\u00edo, un sacerdote que dice bien la misa; tiene que ser un santo var\u00f3n\u00bb. Y hubo quienes dijeron, que les parec\u00eda ver a un \u00e1ngel en el altar. \u00abAlgunos han observado que, cuando le\u00eda en el Santo Evangelio algunos p\u00e1rrafos en los que Nuestro Se\u00f1or hab\u00eda dicho, Amen, amen dico vobis, es decir, en verdad, en verdad os digo, segu\u00eda con mucha atenci\u00f3n las palabras siguientes, como admirado de esa doble afirmaci\u00f3n que el mismo Dios de Verdad empleaba; y, al ver que all\u00ed se encerraba un doble misterio, y que la cosa era de gran importancia, manifestaba, con un tono de voz todav\u00eda m\u00e1s afectuoso y devoto, la pronta sumisi\u00f3n de su coraz\u00f3n. Parec\u00eda que mamaba el sentido de los pasajes de la Escritura como un ni\u00f1o la leche de su madre, y sacaba de ellos el meollo y la sustancia para sustentarse de ella y alimentar su alma. Eso hac\u00eda que en todas sus acciones y palabras apareciera lleno del Esp\u00edritu de Jesucristo\u00bb<span id='easy-footnote-111-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-111-5388' title='Abelly, p. 600'><sup>111<\/sup><\/a><\/span>.<\/p>\n<p>Mimetismo de algo que est\u00e1 en la Escritura<span id='easy-footnote-112-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-112-5388' title='Ap 10,9; Ez 3,3'><sup>112<\/sup><\/a><\/span> : \u00abcomer el libro\u00bb. Nuestro Se\u00f1or ten\u00eda por alimento la voluntad de su Padre<span id='easy-footnote-113-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-113-5388' title='Jn 4,34'><sup>113<\/sup><\/a><\/span>, y san Vicente dice \u00absu comida y sus delicias<span id='easy-footnote-114-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-114-5388' title='SVP,XI, 365'><sup>114<\/sup><\/a><\/span>. \u00abLo que me alimenta, me deleita y me robustece es hacer la voluntad de mi Padre\u00bb<span id='easy-footnote-115-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-115-5388' title='SVP, XI, 449'><sup>115<\/sup><\/a><\/span>.<\/p>\n<p>Se ve con facilidad que san Vicente capta la originalidad de cada evangelista: Mateo, contable de profesi\u00f3n, es quien mejores m\u00e1ximas evang\u00e9licas suministra. A \u00e9l acude Vicente para obtener formularios legislativos<span id='easy-footnote-116-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-116-5388' title='XI, 419'><sup>116<\/sup><\/a><\/span>. Lucas, cronista de la mansedumbre de Cristo, evoca la misericordia, la ternura, el servicio de la Virgen Mar\u00eda y de las mujeres que acompa\u00f1aban a Jes\u00fas: es una excelente autoridad, y el heraldo de la caridad logra que hable a las Damas y a las Hijas de la Caridad. Juan transmite el misterio del Hijo eterno de Dios. Unido a su padre, alimentado de su voluntad, sin ense\u00f1anza propia, est\u00e1 unido a su Padre de un modo tal, que ver al Hijo es ver al Padre. En cuanto a san Pablo, no tiene sustituto, \u00fanico como es, cuando precisa definir sin error la nueva condici\u00f3n del hombre regenerado. Reduciendo a dos rasgos el retrato de Cristo Jes\u00fas, escribe san Vicente: \u00abLas dos grandes virtudes de Jesucristo, a saber, la religi\u00f3n para con su Padre y la caridad para con los hombres\u00bb<span id='easy-footnote-117-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-117-5388' title='VI 370'><sup>117<\/sup><\/a><\/span>. \u00abEsa religi\u00f3n para con el Padre\u00bb se hac\u00eda visible de tres maneras: por la encarnaci\u00f3n, por una vida de pobre, por la dolorosa pasi\u00f3n. San Vicente nunca pierde de vista la existencia itinerante del \u00abPobre\u00bb y desconocido. Porque es rechazado<span id='easy-footnote-118-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-118-5388' title='I, 192; III, 25; XI, 555'><sup>118<\/sup><\/a><\/span>, amenazado e injuriado<span id='easy-footnote-119-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-119-5388' title='XI, 493; IX, 797'><sup>119<\/sup><\/a><\/span>; tratado de loco<span id='easy-footnote-120-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-120-5388' title='V, 135; VIII, 60'><sup>120<\/sup><\/a><\/span>, despreciado<span id='easy-footnote-121-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-121-5388' title='I, 160; IX, 25, 402, 420, 1189; XI, 486; X, 836'><sup>121<\/sup><\/a><\/span>, desprovisto de todo<span id='easy-footnote-122-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-122-5388' title=' I, 174, 256; II, 232, 281, 291, 397, III, 92-93, 101, 423, 493; VI, 76; VII, 151, 159, 165, 462, 524; VIII, 40, 196, 221, 414; IX, 77, 78, 98, 170, 397, 399, 405, 447, 748, 761, 813, 816, 819, 820, 821, 840, 841, 847, 882, 889, 947, 1119; XI, 29, 139, 140, 155, 171, 523, 645, 648, 650, 657'><sup>122<\/sup><\/a><\/span>. Tal la escandalosa manera, como el Hijo eterno de Dios revelaba su amor inefable hacia el Padre. La caridad del Hijo de Dios dimana directamente de su ser divino, que se entrega a la d\u00e9bil humanidad. Para no asustar a los hombres, para amansarlos y evangelizarles, el amor asume un semblante pobre: Jes\u00fas aborda a la enferma, an\u00e9mica humanidad con una humilde dulzura<span id='easy-footnote-123-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-123-5388' title='I, 231, 366, 408, 520, 528'><sup>123<\/sup><\/a><\/span>\n<p>No olvida tampoco san Vicente que las l\u00e1grimas velaban a veces el rostro grave de Jes\u00fas: \u00ab\u00a1Qu\u00e9 cari\u00f1oso era el Hijo de Dios! Le llaman para que vaya a ver a L\u00e1zaro; va; la Magdalena se levanta y acude a su encuentro llorando; la siguen los jud\u00edos llorando tambi\u00e9n; todos se ponen a llorar. \u00bfQu\u00e9 es lo que hace nuestro Se\u00f1or? Se pone a llorar con ellos 15, lleno de ternura y compasi\u00f3n. Ese cari\u00f1o es el que lo hizo venir del cielo; ve\u00eda a los hombres privados de su gloria 16 y se sinti\u00f3 afectado por su desgracia. Tambi\u00e9n nosotros hemos de sentir este cari\u00f1o por el pr\u00f3jimo afligido y tomar parte en su pena. \u00a1Oh, san Pablo, qu\u00e9 sensible eras t\u00fa en este punto! \u00a1Oh, Salvador, que llenaste a este ap\u00f3stol de tu esp\u00edritu y de tu cari\u00f1o, haznos decir como \u00e9l: Quis infirmatur, et ego non infirmor?<span id='easy-footnote-124-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-124-5388' title='2 Cor 2, 29'><sup>124<\/sup><\/a><\/span> : \u00bfhay alg\u00fan enfermo, con el que yo no me sienta enfermo?<span id='easy-footnote-125-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-125-5388' title='SVP, XI, 560'><sup>125<\/sup><\/a><\/span>.<\/p>\n<p>San Vicente capta la existencia y condici\u00f3n cristianas, las examina, y experimenta inquietud, pues aparecen exactamente descritas en las cartas de san Pablo: Vivimos en Jesucristo por la muerte en Jesucristo, y que hemos de morir en Jesucristo por la vida de Jesucristo, y que nuestra vida tiene que estar oculta en Jesucristo y llena de Jesucristo, y que, para morir como Jesucristo, hay que vivir como Jesucristo\u00bb<span id='easy-footnote-126-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-126-5388' title='I, 320'><sup>126<\/sup><\/a><\/span>. El 1 de mayo de 1635<span id='easy-footnote-127-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-127-5388' title=' I, 320'><sup>127<\/sup><\/a><\/span> quedan sentados los principios fundamentales. La existencia no puede concebirse de otro modo que como continuando la misi\u00f3n de Jes\u00fas; continuaci\u00f3n que, es evidente, se logra nada m\u00e1s empleando los medios que \u00c9l mismo emple\u00f3. Para continuar la misi\u00f3n de Jesucristo es preciso servirse del esp\u00edritu de Jesucristo<span id='easy-footnote-128-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-128-5388' title='SVP, XI, 410'><sup>128<\/sup><\/a><\/span>. Sin duda, el cristiano recibi\u00f3 el Esp\u00edritu de Jes\u00fas en el bautismo<span id='easy-footnote-129-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-129-5388' title='Gal 3,23s; Rom 6, 3s'><sup>129<\/sup><\/a><\/span> ; debe aun as\u00ed hacer ver\u00eddica y real en el tiempo la adopci\u00f3n divina, vaciarse de s\u00ed propio y unirse a Dios<span id='easy-footnote-130-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-130-5388' title='Rom 6,12'><sup>130<\/sup><\/a><\/span>, despojarse m\u00e1s y m\u00e1s del hombre viejo, para revestirse de Cristo Jes\u00fas<span id='easy-footnote-131-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-131-5388' title='Gal 3,27; Rom 13, 14; Ef 4,22'><sup>131<\/sup><\/a><\/span>. Seg\u00fan hace sus \u00faltimas recomendaciones al joven superior Antonio Durand, Vicente insiste: \u00abNo, padre, ni la filosof\u00eda, ni la teolog\u00eda, ni los discursos logran nada en las almas; es preciso que Jesucristo trabaje con nosotros, o nosotros con \u00e9l; que obremos en \u00e9l, y \u00e9l en nosotros; que hablemos como \u00e9l y con su esp\u00edritu, lo mismo que \u00e9l estaba en su Padre y predicaba la doctrina que le hab\u00eda ense\u00f1ado 4: tal es el lenguaje de la Escritura. Por consiguiente, padre, debe vaciarse de s\u00ed mismo para revestirse de Jesucristo\u00bb<span id='easy-footnote-132-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-132-5388' title='SVP, XI, 223'><sup>132<\/sup><\/a><\/span>.<\/p>\n<p>En el alma humana se han instalado, pues, la guerra y el combate. El esp\u00edritu de Jes\u00fas lucha efectivamente contra aquellas tres concupiscencias, que tres virtudes evang\u00e9licas, pobreza, castidad, y obediencia, intentan paralizar. Psicol\u00f3gicamente, hay que dirigir la lucha contra el esp\u00edritu propio por la sencillez, la pureza de intenci\u00f3n, la humildad; y contra la voluntad propia por la obediencia, la indiferencia, la pr\u00e1ctica de no pedir ni rehusar nada. De una manera que sorprendi\u00f3 a los contempor\u00e1neos, el Padre Vicente insist\u00eda en lo necesario de la humildad, que seg\u00fan dec\u00eda, \u00abel origen de todo el bien que hacemos\u00bb<span id='easy-footnote-133-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-133-5388' title='SVP, XI, 604'><sup>133<\/sup><\/a><\/span>. \u00abAqu\u00ed es donde est\u00e1 el fundamento de la perfecci\u00f3n evang\u00e9lica y el nudo de toda la vida espiritual. Quien tenga esta virtud obtendr\u00e1 f\u00e1cilmente todas las dem\u00e1s; y el que no la tenga, se ver\u00e1 tambi\u00e9n privado de las que parece que tiene y vivir\u00e1 en continuas preocupaciones\u00bb<span id='easy-footnote-134-5388' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#easy-footnote-bottom-134-5388' title='XI, 482-483'><sup>134<\/sup><\/a><\/span>. La caridad es hija de la humildad. La humildad es el centro que inspira toda la ascesis de Vicente de Pa\u00fal, al igual que el Cristo pobre ocupa el centro de sus perspectivas dogm\u00e1ticas.<\/p>\n<h2><strong>Conclusi\u00f3n <\/strong><\/h2>\n<p>En la experiencia religiosa y la ense\u00f1anza de Vicente de Pa\u00fal, la Escritura juega un doble papel y ejerce una doble funci\u00f3n.<\/p>\n<p>Es incontestablemente mediadora: a trav\u00e9s de ella es como san Vicente encuentra a Cristo vivo. Ella le cerciora de que est\u00e1 presente, y hace que disfrute apaciblemente su bondad. Se habr\u00eda degradado, de no haberle descubierto as\u00ed, se habr\u00eda hecho m\u00e1s y m\u00e1s opaco a s\u00ed mismo, indiferente a todo cuanto no pudiese poseer, extra\u00f1o a todos sus semejantes.<\/p>\n<p>Pero sobre todo, la Escritura es reveladora perpetua de otro mundo m\u00e1s veraz, m\u00e1s s\u00f3lido y m\u00e1s seguro que el mundo inconsistente conocido por los sentidos y la inteligencia, y jam\u00e1s pose\u00eddo de modo duradero. Aquel mundo invisible est\u00e1 habitado por Cristo Jes\u00fas, suavidad eterna de hombres y \u00e1ngeles; y es por esta misma virtud que tenemos nosotros la posibilidad de acceder a \u00e9l, de salvarnos y salvar a otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una triple constante determina el m\u00e9todo para mejor conocer las relaciones de san Vicente de Pa\u00fal con la Biblia. Las alternativas biogr\u00e1ficas Cuatro biograf\u00edas aseguraron, durante dos siglos y medio, el conocimiento de la vida, &#8230; <a href=\"http:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":402733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[186,218,173,148,142,193,145,119,227,172,139,143,188,120],"class_list":["post-5388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vicente-de-paul","tag-abadia-de-san-leonardo","tag-abelly","tag-chatillon-les-dombes","tag-clichy","tag-collet","tag-gamaches","tag-gannes","tag-gondi","tag-maynard","tag-pobreza","tag-san-benito","tag-san-lazaro","tag-san-leonardo","tag-senora-de-gondi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal y la Biblia - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal y la Biblia - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Una triple constante determina el m\u00e9todo para mejor conocer las relaciones de san Vicente de Pa\u00fal con la Biblia. Las alternativas biogr\u00e1ficas Cuatro biograf\u00edas aseguraron, durante dos siglos y medio, el conocimiento de la vida, ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-24T03:25:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-20T15:08:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"40 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vicente de Pa\u00fal y la Biblia\",\"datePublished\":\"2015-02-24T03:25:39+00:00\",\"dateModified\":\"2020-01-20T15:08:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/\"},\"wordCount\":7928,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630\",\"keywords\":[\"Abad\u00eda de San Leonardo\",\"Abelly\",\"Chatillon\",\"Clichy\",\"Collet\",\"Gamaches\",\"Gannes\",\"Gondi\",\"Maynard\",\"Pobreza\",\"San Benito\",\"San L\u00e1zaro\",\"San Leonardo\",\"Se\u00f1ora de Gondi\"],\"articleSection\":[\"Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/\",\"name\":\"Vicente de Pa\u00fal y la Biblia - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630\",\"datePublished\":\"2015-02-24T03:25:39+00:00\",\"dateModified\":\"2020-01-20T15:08:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/02\\\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-y-la-biblia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal y la Biblia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal y la Biblia - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal y la Biblia - Somos Vicencianos","og_description":"Una triple constante determina el m\u00e9todo para mejor conocer las relaciones de san Vicente de Pa\u00fal con la Biblia. Las alternativas biogr\u00e1ficas Cuatro biograf\u00edas aseguraron, durante dos siglos y medio, el conocimiento de la vida, ... Read More","og_url":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-02-24T03:25:39+00:00","article_modified_time":"2020-01-20T15:08:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"40 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vicente de Pa\u00fal y la Biblia","datePublished":"2015-02-24T03:25:39+00:00","dateModified":"2020-01-20T15:08:08+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/"},"wordCount":7928,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630","keywords":["Abad\u00eda de San Leonardo","Abelly","Chatillon","Clichy","Collet","Gamaches","Gannes","Gondi","Maynard","Pobreza","San Benito","San L\u00e1zaro","San Leonardo","Se\u00f1ora de Gondi"],"articleSection":["Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/","url":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/","name":"Vicente de Pa\u00fal y la Biblia - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630","datePublished":"2015-02-24T03:25:39+00:00","dateModified":"2020-01-20T15:08:08+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/vicente-de-paul-y-la-biblia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal y la Biblia"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2015\/02\/St_Vincent_De_Paul_-bible-1.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1oU","jetpack-related-posts":[{"id":121635,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-00-prefacio\/","url_meta":{"origin":5388,"position":0},"title":"San Vicente de Pa\u00fal y los Gondi: 00 Prefacio","author":"Francisco Javier Fern\u00e1ndez Chento","date":"31\/12\/2013","format":false,"excerpt":"Prefacio Los historiadores antiguos y modernos de san Vicente de Pa\u00fal. - Publicaci\u00f3n de su correspondencia - Documentos in\u00e9ditos del Oratorio y de los archivos del Ministerio de Asuntos exteriores. Dos siglos despu\u00e9s, ser\u00eda dif\u00edcil citar a un hombre ilustre, por grande que fuera su fama, cuya vida haya sido\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"Felipe-Manuel de Gondi","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/12\/Felipe-Manuel_de_Gondi-185x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":101815,"url":"http:\/\/vincentians.com\/es\/vida-del-senor-vicente-de-paul-nota-bibliografica-2\/","url_meta":{"origin":5388,"position":1},"title":"Vida del Se\u00f1or Vicente de Pa\u00fal: Nota bibliogr\u00e1fica","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/05\/2015","format":false,"excerpt":"Nota bibliogr\u00e1fica Esta biograf\u00eda de san Vicente de Pa\u00fal se dedica a la memoria de Pierre Coste, C.M. (1873-1935), sin cuyo trabajo previo no hubiera podido ser escrita. Coste recogi\u00f3 pacientemente y public\u00f3 en trece vol\u00famenes pr\u00e1cticamente todos los es\u00adcritos procedentes de Vicente de Pa\u00fal o que se refieren a\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"sanvibiblia","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/08\/sanvibiblia-300x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":121660,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-07\/","url_meta":{"origin":5388,"position":2},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 07","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/07\/2024","format":false,"excerpt":"Cap\u00edtulo VII Viaje de Vicente de Pa\u00fal a Marsella. \u2013 La leyenda del forzado. - Haza\u00f1as del general de las galeras ante La Rochelle. - Muerte de su segundo hijo y de su hermano, Henry de Gondi, obispo de Par\u00eds. Parecer\u00eda natural creer que Vicente de Pa\u00fal, una vez investido\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=1050%2C600 3x"},"classes":[]},{"id":121299,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-nacio-en-francia-ii-estudios\/","url_meta":{"origin":5388,"position":3},"title":"San Vicente de Pa\u00fal naci\u00f3 en Francia. II. Estudios","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/04\/2015","format":false,"excerpt":"II. Estudios En lo concerniente a los estudios teol\u00f3gicos de Vicente de Pa\u00fal, los detalles no ser\u00e1n abundantes, dado el cuidado del Santo por hacerse pasar por un estudiante de cuarto a\u00f1o. Sin embargo. despu\u00e9s de su muerte, se encuentran tres documentos, cuya existencia no se sospechaba, y que arrojan\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":121252,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-nacio-en-francia-i-nacimiento\/","url_meta":{"origin":5388,"position":4},"title":"San Vicente de Pa\u00fal naci\u00f3 en Francia. I. Nacimiento","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/04\/2015","format":false,"excerpt":"Vincentius a Pa\u00falo, natione Gallus, Podii non procul ab Aquis Tarbellis in Aquitania natus. (Breviario romano, 19 julio.) Primera parte Se public\u00f3 en Barcelona (Espa\u00f1a), como ap\u00e9ndice a la traducci\u00f3n de la obra del Sr. Arturo Loth: San Vicente de Pa\u00fal y su misi\u00f3n social, una tesis hist\u00f3rica en extremo\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"pemartin","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/pemartin-189x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":121425,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-nacio-en-francia-iv-primera-dificultad\/","url_meta":{"origin":5388,"position":5},"title":"San Vicente de Pa\u00fal naci\u00f3 en Francia. IV. Primera dificultad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/04\/2015","format":false,"excerpt":"Segunda Parte: Contestaci\u00f3n a las objeciones del traductor Nos proponemos seguir paso a paso al ilustrado traduc\u00adtor en su primer ap\u00e9ndice, y contestar a todos las objecio\u00adnes que revistan alguna importancia. Primera dificultad 1\u00ba Dice el Sr. Feli\u00fa y Perez: \"Entre los pueblos del mundo, pocos hay que puedan competir\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/5388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=5388"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/5388\/revisions"}],"predecessor-version":[{"id":402734,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/5388\/revisions\/402734"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/402733"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=5388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=5388"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=5388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}