{"id":45061,"date":"2017-02-01T08:13:51","date_gmt":"2017-02-01T07:13:51","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/07\/lucia-roge-las-martires-de-angers\/"},"modified":"2017-02-01T08:11:58","modified_gmt":"2017-02-01T07:11:58","slug":"lucia-roge-las-martires-de-angers","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/","title":{"rendered":"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers"},"content":{"rendered":"<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"399749\" data-permalink=\"http:\/\/vincentians.com\/es\/de-las-caridades-a-las-hijas-de-la-caridad\/hijas-caridad-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630\" data-orig-size=\"1200,630\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"hijas caridad\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=846%2C444\" class=\"alignnone size-medium wp-image-399749 alignleft\" src=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=300%2C158\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=300%2C158 300w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=768%2C403 768w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=1024%2C538 1024w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=100%2C53 100w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=846%2C444 846w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?resize=1004%2C527 1004w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/strong>Par\u00eds, diciembre de 1983<\/p>\n<p>Han transcurrido casi dos siglos desde que fueron martirizadas Sor Mar\u00eda Ana y Sor Odila. Pero el mensaje que nos dirigen es de una sin\u00adgular actualidad. Juntas, podemos descubrir en \u00e9l una luz y un apoyo para nuestra vida de Hijas de la Caridad hoy.<\/p>\n<p>San Vicente siempre pens\u00f3 que, como Hijas de la Caridad, nuestra entrega a Dios deb\u00eda llegar hasta la de la vida. Y as\u00ed le vemos proponer a las primeras Hermanas que no descarten de su pensamiento el marti\u00adrio como testimonio que se da de Cristo y de su doctrina hasta el sacri\u00adficio total. Al enviar a cuatro Hermanas a Calais para sustituir a las que all\u00ed acaban de morir, san Vicente les dijo, el 4 de agosto de 1658:<\/p>\n<p style=\"padding-left: 30px\">\u00abVais al martirio, si a Dios le place disponer de vosotras\u00bb.<span id='easy-footnote-1-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-1-45061' title='IX, 1089.'><sup>1<\/sup><\/a><\/span>\n<p>Para ellas se trataba de ponerse enteramente en manos de Dios, sin detenerse a pensar en las consecuencias de su fidelidad a las llamadas recibidas de \u00c9l.<\/p>\n<p>Penetradas de esta doctrina, Sor Mar\u00eda Ana y Sor Odila se muestran tan firmes en la fe que sus perseguidores: Vacheron, Br\u00e9maud, se ven, no sin furor, impotentes para hacerlas renunciar a ella. Hasta el final de su vida, demostrar\u00e1n con su actitud su fidelidad a Cristo y a la Iglesia. Alimentadas con el evangelio, que leen y meditan sin cesar, habr\u00edan de vivir en sus horas de c\u00e1rcel el texto mismo de san Lucas:<\/p>\n<p style=\"padding-left: 30px\">\u00ab&#8230; Os meter\u00e1n en prisi\u00f3n, os conducir\u00e1n ante los reyes y gobernadores por amor de mi nombre. Ser\u00e1 para vosotros ocasi\u00f3n de dar testimonio\u00bb.<span id='easy-footnote-2-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-2-45061' title='Lc 21, 12-13.'><sup>2<\/sup><\/a><\/span>\n<p>Es f\u00e1cil descubrir en el sobrio relato del interrogatorio, que las Her\u00admanas no hab\u00edan preparado nada para su defensa:<\/p>\n<p style=\"padding-left: 30px\">\u00abHaced prop\u00f3sito de no preocuparos de vuestra defensa\u00bb.<span id='easy-footnote-3-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-3-45061' title='Lc 21,14.'><sup>3<\/sup><\/a><\/span>\n<p>El \u00fanico argumento que una y otra presentan son los derechos de su conciencia.<\/p>\n<p>Repasando las Actas de los m\u00e1rtires de Angers y pensando en lo que viven tantas de nuestras Hermanas a trav\u00e9s del mundo, bueno es que entremos en sus mismos sentimientos de fe y de confianza. Como lo recordaba el Santo Padre en Lourdes, el 14 de agosto de este a\u00f1o:<\/p>\n<p style=\"padding-left: 30px\">\u00abLas persecuciones por la fe son a veces semejantes a las que el martiro\u00adlogio de la Iglesia tiene ya escritas en los pasados siglos. Toman diversas formas de discriminaci\u00f3n de los creyentes y de toda la comunidad de la Iglesia. Esas formas de discriminaci\u00f3n se aplican, a veces, al mismo tiempo que se insiste en reconocer el derecho a la libertad religiosa, a la libertad de conciencia&#8230; Existen hoy centenares y centenares de testigos de la fe&#8230;\u00bb.<span id='easy-footnote-4-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-4-45061' title='Juan Pablo II, Lourdes, 14.8.1983.'><sup>4<\/sup><\/a><\/span>\n<p>Y puede llegar nuestro turno. Basta con repasar los casos que el Papa evoca en ese discurso. \u00bfEstamos \u00edntimamente persuadidas de que el martirio forma parte de la vida de la Iglesia que<\/p>\n<p style=\"padding-left: 30px\">\u00abnaci\u00f3 en la Cruz de Cristo y creci\u00f3 en medio de las persecuciones?\u00bb<span id='easy-footnote-5-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-5-45061' title='Ib\u00eddem.'><sup>5<\/sup><\/a><\/span>\n<p>La persecuci\u00f3n se desencadena a partir del rechazo a transgredir un mandamiento o a negar la Palabra de Dios y la Revelaci\u00f3n, en su totalidad o en parte. Tambi\u00e9n surge la persecuci\u00f3n ante la adhesi\u00f3n firme a un dogma que los perseguidores rechazan. Pod\u00edamos nosotras, en comunidad, ilustrar con ejemplos esas causas de persecuci\u00f3n y bus\u00adcar en ellas un poderoso dinamismo para desarrollar nuestra fe.<\/p>\n<p style=\"padding-left: 30px\">\u00abNo teng\u00e1is miedo a los que matan el cuerpo, y no pueden matar el alma\u00bb.<span id='easy-footnote-6-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-6-45061' title='Mt 10, 28.'><sup>6<\/sup><\/a><\/span>\n<p>Estas palabras, el Se\u00f1or las firm\u00f3 con su sangre, y con toda humil\u00addad y sencillez, Sor Mar\u00eda Ana y Sor Odila siguieron sus huellas. Su esperanza permanece intacta y sostiene su penoso caminar a lo largo de los tres kil\u00f3metros de su \u00faltima marcha, \u00abpor un camino estrecho, pedregoso, poco transitable en cualquier estaci\u00f3n\u00bb.<span id='easy-footnote-7-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-7-45061' title='Monse\u00f1or MONTAULT, 17.3.1817.'><sup>7<\/sup><\/a><\/span> La amplia carre\u00adtera asfaltada de hoy no debe llevarnos a enga\u00f1o. La prueba de aquel largo caminar fue tremendamente dura bajo todos los aspectos. No es de extra\u00f1ar que Sor Odila se sintiera desfallecer. Las palabras de aliento de Sor Mar\u00eda Ana, en el lenguaje de la \u00e9poca, \u00abtenemos casi a la mano esta corona, no la dejemos escapar, unos instantes m\u00e1s y ser\u00e1 nuestra\u00bb, revelan hasta qu\u00e9 punto estaban sus corazones impregna\u00addos del evangelio:<\/p>\n<p style=\"padding-left: 30px\">\u00abCon vuestra paciencia comprar\u00e9is (la salvaci\u00f3n) de vuestras almas\u00bb.<span id='easy-footnote-8-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-8-45061' title='Lc 21,19.'><sup>8<\/sup><\/a><\/span>\n<p>Saben tambi\u00e9n que<\/p>\n<p style=\"padding-left: 30px\">\u00ab&#8230; Si el grano de trigo no cae en tierra y muere, quedar\u00e1 solo; pero si muere llevar\u00e1 mucho fruto\u00bb.<span id='easy-footnote-9-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-9-45061' title='Jn 12, 24.'><sup>9<\/sup><\/a><\/span>\n<p>El Concilio Vaticano II recuerda a la Iglesia de nuestro tiempo que, como cristianos, estamos llamados<\/p>\n<p style=\"padding-left: 30px\">`&#8230; a dar este supremo testimonio de amor ante todos\u00bb.<span id='easy-footnote-10-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-10-45061' title='LG, 42.'><sup>10<\/sup><\/a><\/span>\n<p>Hay un v\u00ednculo interno entre la fecundidad espiritual, el dinamismo de la Iglesia y el martirio.<\/p>\n<p>Ese testimonio de amor delante de todos, quisieron darlo Sor Mar\u00eda Ana y Sor Odila al rechazar taparse el rostro con un velo que les ofrec\u00ed\u00adan. Se sent\u00edan orgullosas de morir por Cristo y deseosas de que toda la ciudad contemplase y supiese c\u00f3mo se muere por la fe. Era la fuerza victoriosa del Esp\u00edritu de Jesucristo la que obraba en ellas y la que nos permite descubrir tambi\u00e9n los frutos de una vida teologal, vivida habi\u00adtualmente, de una vivencia m\u00edstica de uni\u00f3n con Jesucristo. Sin duda, hab\u00edan meditado profundamente la circular en que la Madre Dubois dec\u00eda a las Hermanas:<\/p>\n<p style=\"padding-left: 30px\">\u00abLa santificaci\u00f3n depende tambi\u00e9n de nuestra constante fidelidad en cum\u00adplir el doble voto del servicio espiritual y corporal a los pobres, confiados a nuestros cuidados, en cuyas personas hemos de ver la de Jesucristo\u00bb.<span id='easy-footnote-11-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-11-45061' title='Archivos de la Compa\u00f1\u00eda.'><sup>11<\/sup><\/a><\/span>\n<p>Estar en relaci\u00f3n constante con Jesucristo les comunica una con\u00adfianza extraordinaria. Est\u00e1n seguras del poder de Dios con quien no han cesado de estar en comuni\u00f3n.<\/p>\n<p>La espiritualidad de Sor Mar\u00eda Ana y Sor Odila abre ante nosotras perspectivas todav\u00eda v\u00e1lidas para la Iglesia y para nuestra vida de Hijas de la Caridad dentro de esa Iglesia. La fe es siempre la causa del mar\u00adtirio, \u00bfEs necesario recordar a Mons. Romero? \u00c9l tambi\u00e9n habl\u00f3 en pie, con el rostro descubierto. Anunciaba la Palabra de Dios y sus exigen\u00adcias. No es cuesti\u00f3n de que nos limitemos a limpiar un poco el polvo que en estos ciento noventa a\u00f1os haya podido depositarse sobre Sor Mar\u00eda Ana y Sor Odila, como im\u00e1genes de un pasado de la Compa\u00f1\u00eda. De lo que se trata es de que nos interroguemos, \u00bfpor qu\u00e9 pone el Se\u00f1or, ahora, sus vidas ante nuestros ojos? \u00bfNo ser\u00e1 acaso para que nos despertemos?<\/p>\n<p>\u00bfQu\u00e9 profesi\u00f3n de fe vivimos? \u00bfSon para nosotras las Bienaven\u00adturanzas una fuente de esperanza escatol\u00f3gica?<\/p>\n<p style=\"padding-left: 30px\">\u00abBienaventurados ser\u00e9is cuando os insulten y persigan&#8230;\u00bb.<span id='easy-footnote-12-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-12-45061' title='Mt 5,11.'><sup>12<\/sup><\/a><\/span>\n<p>\u00bfTendemos hacia su realizaci\u00f3n en nosotras y en torno nuestro? \u00bfNos atrevemos a \u00abanunciar\u00bb? \u00bfAnunciar la Buena Noticia del amor y de la fidelidad de Dios en un mundo en el que triunfa la injusticia, el odio, la violencia? Como Sor Mar\u00eda Ana y Sor Odila, \u00bftenemos el valor de rechazar las componendas? \u00abNo s\u00f3lo no queremos prestar el juramento, sino que tampoco queremos que parezca que lo hemos prestado\u00bb, dicen. \u00bfNuestro amor fraterno se convierte en apoyo, fortaleza, sost\u00e9n inquebrantable en las pruebas que compartimos?<\/p>\n<p>Esta actitud de confianza inalterable se apoya tambi\u00e9n en la inter\u00adcesi\u00f3n de la Reina de los M\u00e1rtires. La tradici\u00f3n refiere que despu\u00e9s del canto de los Salmos y de las Letan\u00edas de la Virgen, las Hermanas empe\u00adzaron la vieja tonada: \u00abPongo mi confianza, Virgen, en tu socorro&#8230;\u00bb. \u00bfC\u00f3mo dudar de que su \u00fanica Madre las haya sostenido en esos mo\u00admentos decisivos en que<\/p>\n<p style=\"padding-left: 30px\">\u00abnadie tiene amor mayor que el de dar la vida por sus amigos?\u00bb.<span id='easy-footnote-13-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-13-45061' title='Jn 15, 13.'><sup>13<\/sup><\/a><\/span>\n<p>Sor Mar\u00eda Ana y Sor Odila realizaron el mayor acto de amor siguien\u00addo a Cristo hasta el sacrificio voluntario de su vida. Como san Vicente lo quer\u00eda, \u00abreprodujeron de una manera natural la vida de Cristo\u00bb.<\/p>\n<p>El 15 de mayo pasado, dec\u00eda el Santo Padre:<\/p>\n<p style=\"padding-left: 30px\">\u00abCuando la Iglesia propone un modelo de vida a los fieles, lo hace tenien\u00addo en cuenta las necesidades particulares de la \u00e9poca en que hace tal pro\u00adclamaci\u00f3n\u00bb.<span id='easy-footnote-14-45061' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#easy-footnote-bottom-14-45061' title='Juan Pablo II, 15 de mayo de 1983.'><sup>14<\/sup><\/a><\/span>\n<p>Nos sentimos doblemente aludidas, como cristianas y como Hijas de la Caridad. Propong\u00e1monos meditar la vida de Sor Mar\u00eda Ana Vaillot y de Sor Odila Baumgarten; vida de siervas de Jesucristo en los pobres, de hijas de la Iglesia, de hermanas que se aman entre s\u00ed y se sostienen mutuamente.<\/p>\n<p>Con toda humildad, en proporci\u00f3n a nuestras fuerzas y a nuestras circunstancias, tratemos de imitarlas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00eds, diciembre de 1983 Han transcurrido casi dos siglos desde que fueron martirizadas Sor Mar\u00eda Ana y Sor Odila. Pero el mensaje que nos dirigen es de una sin\u00adgular actualidad. Juntas, podemos descubrir en \u00e9l &#8230; <a href=\"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[276],"tags":[],"class_list":["post-45061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-lucia-roge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Par\u00eds, diciembre de 1983 Han transcurrido casi dos siglos desde que fueron martirizadas Sor Mar\u00eda Ana y Sor Odila. Pero el mensaje que nos dirigen es de una sin\u00adgular actualidad. Juntas, podemos descubrir en \u00e9l ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-01T07:13:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers\",\"datePublished\":\"2017-02-01T07:13:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/\"},\"wordCount\":1536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Luc\u00eda Rog\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/\",\"name\":\"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"datePublished\":\"2017-02-01T07:13:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-las-martires-de-angers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/","og_locale":"es_ES","og_type":"article","og_title":"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers - Somos Vicencianos","og_description":"Par\u00eds, diciembre de 1983 Han transcurrido casi dos siglos desde que fueron martirizadas Sor Mar\u00eda Ana y Sor Odila. Pero el mensaje que nos dirigen es de una sin\u00adgular actualidad. Juntas, podemos descubrir en \u00e9l ... Read More","og_url":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2017-02-01T07:13:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers","datePublished":"2017-02-01T07:13:51+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/"},"wordCount":1536,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","articleSection":["Escritos de Luc\u00eda Rog\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/","url":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/","name":"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","datePublished":"2017-02-01T07:13:51+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/lucia-roge-las-martires-de-angers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Luc\u00eda Rog\u00e9: Las m\u00e1rtires de Angers"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-bIN","jetpack-related-posts":[{"id":143163,"url":"http:\/\/vincentians.com\/es\/vidas-que-cambian-vidas-los-martires-de-espana\/","url_meta":{"origin":45061,"position":0},"title":"Vidas que cambian vidas: los m\u00e1rtires de Espa\u00f1a","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/04\/2015","format":false,"excerpt":"Introducci\u00f3n \u201cDefender y custodiar la vida\u201d es el tema del a\u00f1o elegido para los Colegios de las Hijas de la Caridad en Espa\u00f1a. El lema que lo ilustra \u00a1Todo por la vida! La Comisi\u00f3n interprovincial de Hermanas ha elaborado para los alumnos y los profesores un material educativo, pedag\u00f3gico y\u2026","rel":"","context":"En \u00abTestigos vicencianos\u00bb","block_context":{"text":"Testigos vicencianos","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/testigos-vicencianos\/"},"img":{"alt_text":"martires hijas de la caridad 2013","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/04\/martires-hijas-de-la-caridad-2013-456x1024.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":131117,"url":"http:\/\/vincentians.com\/es\/las-hijas-de-la-caridad-en-china-1848-1948\/","url_meta":{"origin":45061,"position":1},"title":"Las Hijas de la Caridad en China (1848-1948)","author":"Mitxel Olabu\u00e9naga","date":"17\/08\/2014","format":false,"excerpt":"Un d\u00eda de 1655 \u201429 de septiembre\u2014 dec\u00eda. San Vicente de Pa\u00fal a las Hijas de la Caridad: \"Desde Madagascar nuestros Misioneros nos piden les mandemos Hijas de la Caridad para ayudarles a conquistar almas. Los Padres Mousnier y Bourdaise me dicen que creen ser \u00e9ste el \u00fanico medio para\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"Hijas2","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/03\/Hijas2.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":102587,"url":"http:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0631-al-senor-vicente\/","url_meta":{"origin":45061,"position":2},"title":"Luisa de Marillac, Carta 0631: Al se\u00f1or Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/09\/2012","format":false,"excerpt":"[mayo 1658] No sab\u00eda yo, mi muy Honorable Padre, que estuviera usted enfermo; por amor de Dios, \u00a1cu\u00eddese! Lo que me urge saber de su caridad es si le parecer\u00eda bien que di\u00e9ramos a Sor Ana, para hacer el viaje con la se\u00f1ora Duquesa de Ventadour, a la Hermanita que\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":118024,"url":"http:\/\/vincentians.com\/es\/estampa-en-el-dia-del-cambio-de-habito-1964\/","url_meta":{"origin":45061,"position":3},"title":"Estampa en el d\u00eda del cambio de h\u00e1bito (1964)","author":"Mitxel Olabu\u00e9naga","date":"28\/02\/2013","format":false,"excerpt":"El d\u00eda 20 de septiembre el M. R. P. General envi\u00f3 a todas y cada una de las Hijas de la Caridad una preciosa estampa-fotograf\u00eda de la fachada de la catedral de Estrasburgo y el lema \"Congregavit nos in unum Christi amor\", con un breve mensaje que, traducido al castellano,\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"sor_lorenza_diaz_bolanos","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/sor_lorenza_diaz_bolanos.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":120064,"url":"http:\/\/vincentians.com\/es\/luisa-de-marillac-carta-0690-a-sor-genoveva-doinel\/","url_meta":{"origin":45061,"position":4},"title":"Luisa de Marillac, Carta 0690: A Sor Genoveva Doinel","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/04\/2013","format":false,"excerpt":"Chantilly Hoy, 3 de septiembre de 1659 Mi querida Hermana: He sentido mucho dejarla tanto tiempo sola, y alabo a Dios que me proporciona el medio de poder enviarle a nuestra querida Sor Francisca, que es de car\u00e1cter bueno y apacible y tiene un gran deseo de pertenecer a Dios\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":130026,"url":"http:\/\/vincentians.com\/es\/ultimas-fundaciones-ii\/","url_meta":{"origin":45061,"position":5},"title":"\u00daltimas fundaciones (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/03\/2014","format":false,"excerpt":"St.-Fargeau Luisa de Marillac estaba convencida de que la Compa\u00f1\u00eda era noticia para la sociedad de Francia y para la Iglesia. Las ped\u00edan, a veces, suplicantes, obispos, nobles y la misma reina. Sin embargo, Luisa se sinti\u00f3 emocionada, casi halagada, cuando la Grande Demoi\u00adselle le pidi\u00f3 Hijas de la Caridad\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"cartel","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/02\/cartel.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/45061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=45061"}],"version-history":[{"count":2,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/45061\/revisions"}],"predecessor-version":[{"id":400578,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/45061\/revisions\/400578"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398623"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=45061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=45061"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=45061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}