{"id":42371,"date":"2014-12-19T02:59:51","date_gmt":"2014-12-19T01:59:51","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/06\/lucia-roge-la-pobreza\/"},"modified":"2014-12-19T02:59:51","modified_gmt":"2014-12-19T01:59:51","slug":"lucia-roge-la-pobreza","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/","title":{"rendered":"Luc\u00eda Rog\u00e9: La pobreza"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/Lucia_Roge.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34760\" title=\"Sor Luc\u00eda Rog\u00e9, H.C.\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/Lucia_Roge-249x300.jpg?resize=249%2C300\" alt=\"Sor Luc\u00eda Rog\u00e9, H.C.\" width=\"249\" height=\"300\" \/><\/a><\/p>\n<div>Par\u00eds, 24 de octubre de 1975.Dos acontecimientos han marcado recientemente a la familia vicen\u00adciana, las canonizaciones de Elizabeth Ann Seton y de Justino de Jaco-bis. El Se\u00f1or quiere por ese medio, atraer nuestra atenci\u00f3n hacia el ejemplo de sus vidas e impulsar nuestro coraz\u00f3n a imitarlos; as\u00ed nos vemos incitadas directa e indirectamente, a reconocer la acci\u00f3n de Dios en nuestra vida para serle fieles.En este sentido, me gustar\u00eda compartir con ustedes, algunas refle\u00adxiones sobre un mensaje especial, com\u00fan a los dos nuevos santos que nos aporta la historia de sus vidas, la pobreza.<\/p>\n<p>Para santa Isabel Ana, la decisi\u00f3n de seguir m\u00e1s \u00edntimamente a Jesucristo equivale a elegir la pobreza, el desprecio, el marginaci\u00f3n, todo lo que viven hoy tantos pobres. A Justino de Jacobis, la vida misio\u00adnera lo lleva a una pobreza radical. La fe permiti\u00f3 vivir a ambos en un estado de desprendimiento excepcional con la serenidad sorprendente de los santos. El amor a Dios hizo franquear a Isabel Ana sus \u00faltimas etapas de indecisi\u00f3n ante el realismo de la pobreza. Justino de Jacobis fue penetrado cada vez m\u00e1s en la vida de la pobreza para adherirse completamente a las exigencias del amor.<\/p>\n<p>\u00a1Qu\u00e9 invitaci\u00f3n para nosotras! \u00bfQui\u00e9n se atrever\u00e1 a discutir la fuerza de testimonios sellados por tales vidas? El hecho de la canonizaci\u00f3n los presenta ante nuestras mentes y corazones oblig\u00e1ndonos, como Familia Vicenciana y muy especialmente como Hijas de la Caridad, a revisar c\u00f3mo vivimos la pobreza.<\/p>\n<p>Tratemos de hacerlo, juntas, una vez m\u00e1s, teniendo el valor y la sen\u00adcillez de ver la realidad y de entrar en lo concreto. Porque, en efecto, ha de ser a trav\u00e9s de nuestra vida diaria y de la apreciaci\u00f3n del nivel econ\u00f3\u00admico de las personas que nos rodean como podremos conocer la realidad de nuestra holgura o nuestra pobreza. Es necesario que suscitemos un porqu\u00e9 y dejemos que se trasluzca la raz\u00f3n del renunciamiento volun\u00adtario a tener m\u00e1s y gozar m\u00e1s en los aspectos m\u00e1s sencillos de la vida.<\/p>\n<\/div>\n<div>\n<ul>\n<li>Fij\u00e9monos en el aspecto de alimentaci\u00f3n. \u00bfConservamos la fruga\u00adlidad de que nos habla san Vicente? \u00a1Cu\u00e1ntas razones encontramos para apartarnos de ella y olvidarnos de retornar a la misma: la salud, la cordialidad, las fiestas, etc.! Es verdad que es conveniente y deseable realzar las alegr\u00edas; pero no caigamos en la exageraci\u00f3n, tanto en la cali\u00addad como en la frecuencia, que han de verse restringidas si hemos de hacer posible un aut\u00e9ntico compartir con los pobres.<\/li>\n<li>En cuanto al vestuario, ya llevemos el h\u00e1bito de la comunidad, ya un traje seglar, la pobreza radica aqu\u00ed tambi\u00e9n en la cantidad y en la calidad. Pregunt\u00e9monos el n\u00famero de piezas que componen nuestro ajuar, sencillamente, empezando por los zapatos, medias, y compar\u00e9\u00admoslo con los pobres. Que se vea la calidad media de las telas y que todo sea modesto y sobrio.<\/li>\n<\/ul>\n<p>Podr\u00edamos detenernos aqu\u00ed, puesto que san Vicente nos dice: \u00abNo ten\u00e9is derecho m\u00e1s que para vivir y vestiros; el resto pertenece al ser\u00advicio de los pobres\u00bb.<span id='easy-footnote-1-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-1-42371' title='IX, 99.'><sup>1<\/sup><\/a><\/span> Sin embargo, conviene reflexionar sobre otros aspectos de nuestra vida en que se registra mayor apertura, bajo el impulso de una civilizaci\u00f3n cient\u00edficamente estudiada para motivarnos a comprar, as\u00ed como por el desarrollo, por la ampliaci\u00f3n de nuestro senti\u00addo de lo necesario, incluso de lo que juzgamos indispensable, y la res\u00adtricci\u00f3n de nuestra concepci\u00f3n sobre lo que es superfluo para los pobres. \u00abDesear tener comodidades y que no nos falte nada\u00bb<span id='easy-footnote-2-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-2-42371' title='IX,\u00a0 818.'><sup>2<\/sup><\/a><\/span> es contra la pobreza, nos dice san Vicente; es la actitud de los ricos que pueden procurarse todo con el dinero. El otro d\u00eda, unas Hermanas explicaban que hab\u00edan rehusado tener cuartos individuales, mientras los ni\u00f1os de los enfermos no tuvieran guarder\u00eda infantil. No pedir, est\u00e1 bien; pero rehusar, por amor a los pobres, es comprometerse con la pobreza.<\/p>\n<p>Las comodidades en las viviendas han aumentado considerablemen\u00adte entre las Hijas de la Caridad; tambi\u00e9n aqu\u00ed, son numerosos los casos que piden un examen leal. Como nos dice san Vicente, tratemos de \u00abver las manchas que tenemos sobre el rostro\u00bb, el aislamiento ac\u00fastico m\u00e1s perfec\u00adcionado, aislamiento visual, decoraci\u00f3n variada, grandes fotograf\u00edas, menu\u00addencias, flores, todos los elementos en uso entre los ricos. Qui\u00e9ralo yo o no, toda concesi\u00f3n hecha al dinero, incluso en cosas peque\u00f1as, modifica mi comportamiento. Compromisos f\u00fatiles llevan consigo cambios en el cora\u00adz\u00f3n y un desplazamiento en la escala de valores. La pobreza de esp\u00edritu, la de las Bienaventuranzas, se encuentra a trav\u00e9s de la austeridad.<\/p>\n<\/div>\n<div>\n<p>Los instrumentos de trabajo son tambi\u00e9n campo abundantemente provisto, donde se da con frecuencia el hecho de tener aparatos por duplicado, debido a que no estamos dispuestas a prestar las cosas, gesto propio y espont\u00e1neo en los pobres. Por ejemplo, \u00bfcu\u00e1ntos magne\u00adt\u00f3fonos, m\u00e1quinas fotogr\u00e1ficas hay por casa? Una comprobaci\u00f3n de esa multiplicidad en los aspectos m\u00e1s variados, como revistas, discos, etc., podr\u00eda permitir sin duda, un buen ahorro en beneficio de los pobres, y nos dar\u00eda ocasi\u00f3n de analizar nuestro esp\u00edritu de pobreza. Cuando se siente apego a algo hasta el punto de no querer prescindir de ello ni siquiera para prestarlo, no se es pobre. Es lo que dice san Vicente \u00abtener una afici\u00f3n desordenada e insistente a que no le falte nada\u00bb.<span id='easy-footnote-3-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-3-42371' title='IX, 405.'><sup>3<\/sup><\/a><\/span>\n<p>Otra cuenta viene a gravar nuestros presupuestos comunitarios, el de los descansos. Descansar es necesario; pero el descanso de una Hija de la Caridad no debe asemejarse a las vacaciones de las perso\u00adnas ricas, ni por el lugar, ni por la multiplicidad de viajes y gastos de litros y litros de gasolina. Estamos muy lejos de \u00abs\u00f3lo lo necesario para vivir y vestirse\u00bb. Y sin embargo, el querer permanecer en estado de ser\u00advicio en seguimiento de Cristo no puede aliarse con un nivel de vida visi\u00adblemente superior al de aqu\u00e9llos que pretendemos servir. La doctrina es clara, hay que amar a Dios con preferencia a toda otra cosa, es el cami\u00adno para servirle en los pobres.<\/p>\n<p>Evidentemente se me puede objetar diciendo: \u00abla frase que usted cita es una frase del siglo XVII. No vive usted en la realidad. Hoy san Vicente&#8230;\u00bb. Tambi\u00e9n en ese caso quiero responder con un hecho vivido, un acontecimiento que me interpela y me conmueve. Desde hace tiem\u00adpo me ha impresionado la intensa irradiaci\u00f3n de la Madre Teresa. Se mul\u00adtiplican las revistas, libros, discos, emisiones de TV sobre su persona, marcada tan intensamente por la pobreza, y sobre su acci\u00f3n con los pobres. Colaboradores seglares (20.000 seg\u00fan su fichero) y numerosas vocaciones surgen en torno suyo.<\/p>\n<\/div>\n<p>En octubre de 1974, una joven de Avranches, en Francia, hac\u00eda por pri\u00admera vez los votos en la comunidad de la Madre Teresa; otras varias la han seguido. Veamos lo que dijo aquella Hermana joven en una entrevista que concedi\u00f3 al peri\u00f3dico local La Manche Libre: \u00abDe todo lo que nos dan, s\u00f3lo guardamos lo m\u00ednimo para nosotras a fin de dejar todo lo posible para los pobres. Aprovechamos lo que los dem\u00e1s tiran. Personalmente, no posee\u00admos absolutamente nada, excepto dos saris de algod\u00f3n de rayas azules, uno puesto y otro para cambiarnos. Tenemos un dormitorio com\u00fan y come\u00admos lo mismo que los pobres, alimentaci\u00f3n rica en f\u00e9culas, pero muy pobre en lo dem\u00e1s. En Londres, donde hemos abierto uno de nuestros tres novi\u00adciados, nuestras Hermanas, indias y europeas mezcladas, viven como los pobres, sin calefacci\u00f3n; s\u00f3lo una habitaci\u00f3n de la casa la tiene\u00bb.<\/p>\n<div>\n<p>Esto es de actualidad, del a\u00f1o 1975, vivido por j\u00f3venes. Pero es tambi\u00e9n el programa propuesto por san Vicente a sus hijas. Admir\u00e9\u00admoslo y dig\u00e1monos que el Se\u00f1or puede multiplicar los mismos llama\u00admientos, y dej\u00e9monos interpelar por ello humildemente. Reconozcamos que hemos suavizado la rigurosidad de las exigencias primitivas de nuestros Fundadores. San Vicente nos hab\u00eda prevenido: \u00abDesear lo que a uno le gusta, desearlo ardientemente, exigirlo e impacientarse si no se le concede a uno enseguida, sentir mucho que se lo nieguen, mirad, todo eso va contra la santa pobreza&#8230; La pobreza pide una renuncia de todos los bienes y comodidades. En fin, consiste en no desear nada m\u00e1s que a Dios\u00bb.<span id='easy-footnote-4-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-4-42371' title='IX, 818.'><sup>4<\/sup><\/a><\/span> Cuando se es Hija de la Caridad, se practica una cierta manera de contentarse con poco, de no dejar ver lo que nos falta, de no granjearse regalos; en una palabra, una cierta ascesis de consumo que nos asemeje a los pobres, en verdad y amor. Tratemos seriamente con verdad y con amor de volver a la pobreza.<\/p>\n<p>La vitalidad espiritual de una comunidad radica ante todo, en el impulso personal y comunitario para reencontrar aut\u00e9nticamente a los Fundadores, impulso que se traduce obligatoriamente en un cambio de vida. No tengamos miedo a comprometernos en el camino de la verdad. Luchemos contra una anemia espiritual que, poco a poco, va borrando en nosotras los rasgos del verdadero rostro de la Compa\u00f1\u00eda.<\/p>\n<p>\u00abLa comunidad de vida establece entre las Hermanas una coparti\u00adcipaci\u00f3n que abarca desde las condiciones materiales de la existencia hasta los compromisos espirituales y apost\u00f3licos\u00bb.<span id='easy-footnote-5-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-5-42371' title='C. 23. Ed. de 1975.'><sup>5<\/sup><\/a><\/span>\n<p>Podr\u00edamos a\u00f1adir este otro pasaje de las Constituciones: \u00abLa pobre\u00adza esencial es la del coraz\u00f3n. Permite aceptar con paz las contradiccio\u00adnes y fracasos, las limitaciones propias y ajenas. La pobreza del cora\u00adz\u00f3n, que es acogida hecha al esp\u00edritu, abre al amor de todos\u00bb.<span id='easy-footnote-6-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-6-42371' title='C. 17. Ed. de 1975.'><sup>6<\/sup><\/a><\/span> De modo que las exigencias de nuestra vida fraterna en com\u00fan nos proporciona ocasiones de practicar la pobreza.<\/p>\n<\/div>\n<div>\n<p>Querr\u00eda destacar algunas:<\/p>\n<ul>\n<li>En primer lugar, el hecho de no escoger a nuestras compa\u00f1eras. Nos adherimos a este ensamblaje hecho por Dios, con su amor como v\u00ednculo de uni\u00f3n. No escoger entrar en un grupo, y asumir en la fe todas sus riquezas y deficiencias es ya hacer un acto de pobreza.<\/li>\n<li>\u00b7 Vivir la pobreza en esa comunidad en que Dios nos ha colocado es aceptar tambi\u00e9n, buscarle juntas, caminar juntas hacia \u00c9l, trabajar juntas en la Misi\u00f3n, con medios tan pobres como nuestras propias personas. En definitiva, es \u00c9l quien act\u00faa en las obras.<\/li>\n<li>Esta comunidad de vida fraterna, a trav\u00e9s de su proyecto comuni\u00adtario, puede centrar sus intercambios y retiros mensuales en el tema de la pobreza, partiendo de la vida actual y apoy\u00e1ndose sobre el Evange\u00adlio y profundizando en la doctrina de san Vicente.<\/li>\n<\/ul>\n<p>Partiendo de la vida actual, fij\u00e1ndose no solamente en la pobreza cl\u00e1sica, sino en las formas modernas que reviste en torno nuestro y que afectan al hombre en su ser profundo, en su actuaci\u00f3n y en su entorno.<\/p>\n<p>Tambi\u00e9n podemos buscar analog\u00edas entre las situaciones de los pobres y las de Cristo hombre a trav\u00e9s del evangelio, su infancia de emi\u00adgrante; su vida p\u00fablica, sin morada fija; su condena injusta y despojo radical del Calvario.<\/p>\n<p>Finalmente, tenemos la posibilidad de beber en las fuentes las importantes ense\u00f1anzas que nos dej\u00f3 san Vicente sobre la pobreza. Por una parte, nos explica qu\u00e9 es: \u00abrenunciamiento, abandono, confianza, abnegaci\u00f3n\u00bb;<span id='easy-footnote-7-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-7-42371' title='IX, 813-828.'><sup>7<\/sup><\/a><\/span> por otra parte, ya lo hemos visto, recuerda las faltas que la desnaturalizan: \u00abdesear que nada nos falte\u00bb.<\/p>\n<ul>\n<li>La revisi\u00f3n comunitaria es un acto de pobreza. Pienso en tantas comunidades que la descuidan y no la hacen ni siquiera una vez al mes. \u00bfPueden decir que son pobres? S\u00ed, lo repito, la revisi\u00f3n comunitaria es en s\u00ed misma un acto de pobreza. Significa que uno no cree poseer la perfecci\u00f3n (\u00abno tengo nada que reprocharme&#8230;\u00bb, es lo mismo que dijo el fariseo en el templo: \u00abno tengo nada que reprocharme\u00bb, lo leemos en el evangelio). Sino que, por el contrario, uno se reconoce pobre en virtud, se acepta la pobreza personal y, sobre todo, se acepta el ponerse uno mismo en tela de juicio ante la Palabra de Dios, ante las Constituciones y ante el juicio de las compa\u00f1eras.<\/li>\n<\/ul>\n<p>Podemos centrar esta revisi\u00f3n comunitaria, de com\u00fan acuerdo, sobre la pobreza. Una buena base inicial es, por ejemplo, la informaci\u00f3n sobre los gastos comunes en los que cada una tiene su parte de res\u00adponsabilidad, agua, luz, gas, calefacci\u00f3n, tel\u00e9fono, etc., compar\u00e1ndolos con el presupuesto de una familia pobre.<\/p>\n<\/div>\n<div>\n<p>De igual manera, la revisi\u00f3n debe hacerse no s\u00f3lo sobre lo mate\u00adrial, sino, como dicen las Constituciones, sobre la participaci\u00f3n de cada una en los intercambios espirituales, preparaci\u00f3n en la oraci\u00f3n, intercambio sobre el evangelio, etc.; si permanezco siempre en silen\u00adcio, debo interrogarme sobre mi pobreza, lo que Dios me da es para que lo comparta.<\/p>\n<p>Igualmente ha de informarse sobre lo que puede interesar al con\u00adjunto, claro est\u00e1; pero tambi\u00e9n hay que prestar atenci\u00f3n a cada una de las compa\u00f1eras, hay que estar disponible para los trabajos comunes.<\/p>\n<p>Es necesario que cada una se obligue a hacer un m\u00ednimo de traba\u00adjo dom\u00e9stico; constituye una parte del don de s\u00ed, de su tiempo. \u00abVuestro tiempo no os pertenece, &#8216;dice san Vicente&#8217;, es de Dios y de los pobres\u00bb.<span id='easy-footnote-8-42371' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#easy-footnote-bottom-8-42371' title='IX, 908.'><sup>8<\/sup><\/a><\/span> Los pobres s\u00ed que tienen el sentido de la coparticipaci\u00f3n, porque ellos tienen la experiencia de que les falte lo esencial.<\/p>\n<p>\u2022 Otra manera de practicar la pobreza, a trav\u00e9s de la vida fraterna, es la comunicaci\u00f3n con la Hermana Sirviente. Reconocer la necesidad de alguien que coordine la vida comunitaria, que sea conexi\u00f3n, el trans\u00admisor, en cierta manera, de la voluntad de Dios, eso es ya un acto de pobreza. Voy a la comunicaci\u00f3n como pobre, reconociendo que sola no puedo ver claro sobre m\u00ed misma. Espero ese servicio como pobre, y lo espero de quien me ve d\u00eda tras d\u00eda, con claridad y la verdad que revela la intimidad de vida.<\/p>\n<p>Con esa misma actitud, acojo a la que acude a m\u00ed para pedirme este servicio, consciente de la humildad que manifiesta ese gesto, dando gracias a Dios por todo lo que as\u00ed me hace comprender \u00c9l mismo y por descubrir la acci\u00f3n de la gracia de la Hermana que est\u00e1 ante m\u00ed.<\/p>\n<p>La comunicaci\u00f3n es esencial para una Hija de la Caridad, en parti\u00adcular para aqu\u00e9lla que quiere vivir en pobreza, porque la pobreza va unida al control y a la dependencia. Control, someti\u00e9ndose a dar cuen\u00adta; dependencia en la obediencia que refleja una actitud filial respecto a Dios. Es una pobreza-confianza. Eludir la comunicaci\u00f3n, tanto de un lado como del otro (ampar\u00e1ndose en lo que proponen las Constitucio\u00adnes, que trat\u00e1ndonos como adultas, dicen: \u00abLas Hermanas se presen\u00adtan espont\u00e1neamente a la comunicaci\u00f3n\u00bb), significa rechazar una cierta dimensi\u00f3n de pobreza. En efecto, es a lo largo de la comunicaci\u00f3n como, sostenidas fraternalmente, podemos entrar verdaderamente en la disponibilidad. Ese di\u00e1logo sencillo y confiado puede ayudarnos a descubrir el contenido de pobreza que se encierra en ciertos aconteci\u00admientos; ver c\u00f3mo languidece la obra de toda una vida, tener que abandonar un cargo, un empleo en el que se tiene \u00e9xito y en el que hemos adquirido lazos de amistad y tantos medios providenciales por los que Dios nos propone la pobreza y nos invita a volvernos a \u00c9l como a nuestro \u00fanico Bien.<\/p>\n<\/div>\n<div>\n<p>De manera m\u00e1s habitual, a lo largo de la comunicaci\u00f3n, podemos considerar juntas c\u00f3mo vivir el trabajo en pobreza. En efecto, querer ser pobre y llamarse sierva no va de acuerdo con el hecho de dispo\u00adner de su tiempo con m\u00e1s o menos rigor o fantas\u00eda (la fantas\u00eda, se quie\u00adra o no, es una actitud de rico), hacer el trabajo a su aire, repartirlo seg\u00fan su parecer, asumir responsabilidades o emprender iniciativas sin dar cuenta de ello. Las sencillas aldeanas de ayer, la gente humil\u00adde de hoy, saben cu\u00e1ntos problemas hay que afrontar en una vida de trabajo, c\u00f3mo deben doblegarse a las directivas de otras personas y encerrar bajo llave las propias iniciativas. En verdad, siempre resulta dif\u00edcil afrontar la comparaci\u00f3n con los pobres, y es \u00fanicamente juntas, en la vida comunitaria y muy especialmente en la comunicaci\u00f3n, como podremos ver claro.<\/p>\n<p>Seguir a Cristo en la pobreza, como lo hicieron nuestros dos nuevos santos es abandonar deliberadamente todo lo que poseemos personal\u00admente, o aceptar vernos privados de ello, incluso, de lo que m\u00e1s quere\u00admos, como lo hizo Isabel Ana; es tambi\u00e9n rechazar todo deseo de domi\u00adnio, toda ocasi\u00f3n de prestigio, como lo hizo Justino de Jacobis.<\/p>\n<p>Es apartar de nosotras todo deseo de influencia preferente, de con\u00adsideraci\u00f3n especial; rechazar toda complacencia en la popularidad y todo intento de buscarla, viviendo las exigencias del servicio de Dios con pureza de intenci\u00f3n. Es entrar en el camino del desprendimiento, que es el de la esperanza. Cuando el Se\u00f1or mir\u00f3 la bajeza de su sierva, hizo en ella y por ella maravillas. Como Mar\u00eda, acojamos la gracia de esta pobreza de coraz\u00f3n. Tenemos la seguridad de que Dios nos acom\u00adpa\u00f1ar\u00e1 en todos nuestros pasos por alcanzarla. Cuanto m\u00e1s nos des\u00adpojamos, m\u00e1s nos llenamos de Dios. Nuestra vida apost\u00f3lica necesita nuestro testimonio de pobreza.<\/p>\n<p>El Cardenal Marty, en una carta reciente a sus sacerdotes, les dice que la evangelizaci\u00f3n necesita fuertes personalidades; lo vemos a tra\u00adv\u00e9s de los dos santos de que acabamos de hablar. \u00abHacen falta fuertes personalidades, &#8216;dice el cardenal&#8217;, y hacen falta santos\u00bb. Y un poco m\u00e1s adelante les pide con insistencia: \u00abAtreveos a hablar de Cristo, el Hijo de Dios. Y lo har\u00e9is recordando la fragilidad y la limitaci\u00f3n de nuestras palabras, que son a la vez verdaderas e inadecuadas. No olvidar\u00e9is nunca que, cada vez que intentamos hablar de Jes\u00fas y de Dios en \u00e9l, nuestras palabras son insuficientes. Guardar\u00e9is viva vues\u00adtra com\u00fan responsabilidad del mensaje que se nos ha confiado. El mundo no necesita falsos profetas ni falsos mes\u00edas. Espera que le digamos en su lenguaje y seg\u00fan su nivel intelectual, la verdad sobre Cristo y su salvaci\u00f3n. Tenemos que profesar y presentar el rostro de quien amamos, y ense\u00f1ar aqu\u00e9l a quien la Iglesia canta y proclama como su maestro y su libertador. Es necesario que profesemos y pre\u00adsentemos el rostro de aqu\u00e9l a quien amamos\u00bb.<\/p>\n<\/div>\n<div>\n<p>Querr\u00eda comprometerme con ustedes y, siguiendo a san Vicente, presentar al mundo el rostro de Jesucristo pobre al servicio de los pobres, sus hermanos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00eds, 24 de octubre de 1975.Dos acontecimientos han marcado recientemente a la familia vicen\u00adciana, las canonizaciones de Elizabeth Ann Seton y de Justino de Jaco-bis. El Se\u00f1or quiere por ese medio, atraer nuestra atenci\u00f3n hacia &#8230; <a href=\"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[276],"tags":[172],"class_list":["post-42371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-lucia-roge","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luc\u00eda Rog\u00e9: La pobreza - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luc\u00eda Rog\u00e9: La pobreza - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Par\u00eds, 24 de octubre de 1975.Dos acontecimientos han marcado recientemente a la familia vicen\u00adciana, las canonizaciones de Elizabeth Ann Seton y de Justino de Jaco-bis. El Se\u00f1or quiere por ese medio, atraer nuestra atenci\u00f3n hacia ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-19T01:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Luc\u00eda Rog\u00e9: La pobreza\",\"datePublished\":\"2014-12-19T01:59:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/\"},\"wordCount\":3236,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Escritos de Luc\u00eda Rog\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/\",\"name\":\"Luc\u00eda Rog\u00e9: La pobreza - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"datePublished\":\"2014-12-19T01:59:51+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-lucia-roge.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/lucia-roge-la-pobreza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luc\u00eda Rog\u00e9: La pobreza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luc\u00eda Rog\u00e9: La pobreza - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/","og_locale":"es_ES","og_type":"article","og_title":"Luc\u00eda Rog\u00e9: La pobreza - Somos Vicencianos","og_description":"Par\u00eds, 24 de octubre de 1975.Dos acontecimientos han marcado recientemente a la familia vicen\u00adciana, las canonizaciones de Elizabeth Ann Seton y de Justino de Jaco-bis. El Se\u00f1or quiere por ese medio, atraer nuestra atenci\u00f3n hacia ... Read More","og_url":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2014-12-19T01:59:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Luc\u00eda Rog\u00e9: La pobreza","datePublished":"2014-12-19T01:59:51+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/"},"wordCount":3236,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","keywords":["Pobreza"],"articleSection":["Escritos de Luc\u00eda Rog\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/","url":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/","name":"Luc\u00eda Rog\u00e9: La pobreza - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","datePublished":"2014-12-19T01:59:51+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/lucia-roge-la-pobreza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Luc\u00eda Rog\u00e9: La pobreza"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-b1p","jetpack-related-posts":[{"id":42376,"url":"http:\/\/vincentians.com\/es\/lucia-roge-la-vida-de-la-hija-de-la-caridad\/","url_meta":{"origin":42371,"position":0},"title":"Luc\u00eda Rog\u00e9: La vida de la Hija de la Caridad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/03\/2021","format":false,"excerpt":"Sor Luc\u00eda Rog\u00e9, H.C.Tenerife, marzo de 1977 Veo el futuro de la Compa\u00f1\u00eda con gran esperanza misionera y coin\u00adcidente con el camino de la misi\u00f3n que nos ense\u00f1aron nuestros santos Fundadores, la misi\u00f3n que tenemos que emprender hoy. Para entrar por ese camino, san Vicente nos indica tres l\u00edneas espirituales:\u2026","rel":"","context":"En \u00abEscritos de Luc\u00eda Rog\u00e9\u00bb","block_context":{"text":"Escritos de Luc\u00eda Rog\u00e9","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-lucia-roge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":39200,"url":"http:\/\/vincentians.com\/es\/lucia-roge-renacer-a-una-nueva-vida-con-las-constituciones\/","url_meta":{"origin":42371,"position":1},"title":"Luc\u00eda Rog\u00e9: Renacer a una nueva vida con las Constituciones","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/09\/2020","format":false,"excerpt":"Par\u00eds, 19 de diciembre de 1983 Una vez m\u00e1s, el misterio de Navidad est\u00e1 ante nosotras. La venida de Jes\u00fas que nace, de Jes\u00fas Salvador, nos hace comprender cosas nuevas, en armon\u00eda con el designio de Dios sobre nosotras, del desig\u00adnio de Dios sobre la Compa\u00f1\u00eda, para el tiempo en\u2026","rel":"","context":"En \u00abEscritos de Luc\u00eda Rog\u00e9\u00bb","block_context":{"text":"Escritos de Luc\u00eda Rog\u00e9","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-lucia-roge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35316,"url":"http:\/\/vincentians.com\/es\/lucia-roge-clausura-de-la-asamblea-1974\/","url_meta":{"origin":42371,"position":2},"title":"Luc\u00eda Rog\u00e9: Clausura de la Asamblea (1974)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/04\/2011","format":false,"excerpt":"Roma, 30 julio de 1974 Al terminar esta Asamblea, parece conveniente que reflexionemos juntas sobre el camino recorrido durante estos dos meses, las realidades que han acompa\u00f1ado nuestra marcha y algunos puntos sobresalientes que descubrimos hoy, al t\u00e9rmino de este caminar, a veces doloroso. Marcadas por los s\u00edntomas de un\u2026","rel":"","context":"En \u00abEscritos de Luc\u00eda Rog\u00e9\u00bb","block_context":{"text":"Escritos de Luc\u00eda Rog\u00e9","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-lucia-roge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":45060,"url":"http:\/\/vincentians.com\/es\/lucia-roge-santa-catalina-laboure\/","url_meta":{"origin":42371,"position":3},"title":"Luc\u00eda Rog\u00e9: Santa Catalina Labour\u00e9","author":"Francisco Javier Fern\u00e1ndez Chento","date":"02\/02\/2020","format":false,"excerpt":"Fain-les-Moutiers, junio 1976 ... Al dar a santa Catalina, a la Compa\u00f1\u00eda y a la Iglesia, Dios nos propone un cierto modelo de vida misionera que es un poco el reflejo de Mar\u00eda. Si el centenario tiene lugar en este per\u00edodo de la vida de la Iglesia y de la\u2026","rel":"","context":"En \u00abEscritos de Luc\u00eda Rog\u00e9\u00bb","block_context":{"text":"Escritos de Luc\u00eda Rog\u00e9","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-lucia-roge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":41063,"url":"http:\/\/vincentians.com\/es\/lucia-roge-ser-siervas\/","url_meta":{"origin":42371,"position":4},"title":"Luc\u00eda Rog\u00e9: Ser siervas","author":"Francisco Javier Fern\u00e1ndez Chento","date":"18\/11\/2014","format":false,"excerpt":"Par\u00eds, marzo de 1979 La Asamblea General 1979-1980 marca una hora importante para la Compa\u00f1\u00eda, la de la afirmaci\u00f3n de nuestra fidelidad a san Vicente y a santa Luisa, es decir, al pensamiento de Dios sobre la Compa\u00f1\u00eda. Desde los or\u00edgenes, tenemos una identidad espiritual en la Iglesia, identidad dada\u2026","rel":"","context":"En \u00abEscritos de Luc\u00eda Rog\u00e9\u00bb","block_context":{"text":"Escritos de Luc\u00eda Rog\u00e9","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-lucia-roge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-lucia-roge.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":142210,"url":"http:\/\/vincentians.com\/es\/la-pobreza-baluarte-de-la-congregacion\/","url_meta":{"origin":42371,"position":5},"title":"La pobreza \u00abbaluarte\u00bb de la Congregaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/04\/2015","format":false,"excerpt":"\u00abTranquilizaos, reba\u00f1o pe\u00adque\u00f1o, que es decisi\u00f3n de vuestro Padre reinar de he\u00adcho sobre vosotros. Vended vuestros bienes y dadlo en limosna; haceos bolsas que no se estropeen, un tesoro inagotable en el cielo, adon\u00adde no se acercan los ladrones ni echa a perder la polilla. Porque donde teng\u00e1is vues\u00adtra riqueza\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"Reconc\u00edliate-con-tu-hermano","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/04\/Reconc--liate-con-tu-hermano-238x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/42371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=42371"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/42371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398623"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=42371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=42371"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=42371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}