{"id":40403,"date":"2017-04-20T08:43:11","date_gmt":"2017-04-20T06:43:11","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/05\/ano-1660\/"},"modified":"2017-01-06T19:15:33","modified_gmt":"2017-01-06T18:15:33","slug":"ano-1660","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/ano-1660\/","title":{"rendered":"A\u00f1o 1660"},"content":{"rendered":"<h2><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"400140\" data-permalink=\"http:\/\/vincentians.com\/es\/louis-debras-octavo-superior-general-de-la-congregacion-de-la-mision-y-de-las-hijas-de-la-caridad-1678-1761\/hijas-caridad-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886\" data-orig-size=\"1771,886\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"hijas-caridad\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=846%2C423\" class=\"alignnone size-medium wp-image-400140 alignleft\" src=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=300%2C150\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=768%2C384 768w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=1024%2C512 1024w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=100%2C50 100w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=846%2C423 846w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?resize=1004%2C502 1004w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?w=1771 1771w, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?w=1692 1692w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>El a\u00f1o 1660 en Francia:<\/h2>\n<p><strong>27 enero:<\/strong> Despu\u00e9s del Tratado de los Pirineos, Cond\u00e9 se entrevista humildemente con la Corte en Aix, que prosegu\u00eda su gira por el sur, mientras se ultimaban los preparativos de la Boda. Cond\u00e9 hab\u00eda recuperado sus posesiones de S. Mauro y de Chantilly y nombrado Gobernador de Borgo\u00f1a pero, dado su orgullo y su fuerte personalidad, no asistir\u00e1 a la Boda, aunque hab\u00eda sido invitado (M. 553).<\/p>\n<p><strong>2 febrero:<\/strong> Muere Gast\u00f3n de Orle\u00e1ns, hermano del Rey Luis XIII y t\u00edo de Luis XIV. Hubo que empe\u00f1ar hasta la vajilla para pagar los funerales que se tuvieron en los M\u00ednimos, el <strong>d\u00eda 14<\/strong> (LD. 303; M. 557).<\/p>\n<p><strong>13 mayo:<\/strong> Paz de la Oliva entre Polonia y Suecia (M. 561).<\/p>\n<p><strong>28 mayo:<\/strong> Moliere estrena \u00abSganarelle\u00bb y en Octubre deja el Petit-Bourbon que es derribado para hacer la columnata del Louvre y pasar\u00e1 en 1661 a tener sus representaciones en el Palacio Real.<\/p>\n<p><strong>3 junio:<\/strong> En Fuenterrab\u00eda se celebra \u00abpor poderes\u00bb el matrimonio real. Luis XIV estar\u00e1 representado por Luis de Haro (LD. 104-105; M. 556; Mz. 207).<\/p>\n<p>4 junio: Las familias reales se entrevistan en la isla de los Faisanes. Primero Felipe IV, Ana, Mazarino y Mar\u00eda Teresa; despu\u00e9s, de inc\u00f3gnito, Luis XIV. Se acaban los \u00faltimos puntos de las negociaciones y se firma definitivamente la Paz de los Pirineos. Por la noche Felipe IV y Mar\u00eda Teresa vuelven a Fuenterrab\u00eda (LD. 105; M. 557; Mz. 207-208).<\/p>\n<p>7 junio: Entrevista oficial entre Felipe IV y Luis XIV; juramentos de paz y amistad y entrega de Mar\u00eda Teresa a Francia, que se viste a la francesa (LD. 105; M. 557).<\/p>\n<p><strong>8 junio:<\/strong> D\u00eda dedicado a hacer los preparativos inmediatos para la boda en S. Juan de Luz (LD. 106)<\/p>\n<p><strong>9 junio:<\/strong> Boda en S. Juan de Luz por el Obispo de Bayona (LD. 106; A. 371; M. 558).<\/p>\n<p><strong>25 junio:<\/strong> La Corte se pone en camino hacia Par\u00eds. Luis XIV se escapa de la comitiva en Saintes para ir a Brouge y recordar en la playa rom\u00e1nticamente a su querida Mar\u00eda Manzini. Las sobrinas estaban ya en Par\u00eds; Mar\u00eda se casar\u00e1 despu\u00e9s con un Colonna (LD. 108-109 y M. 564; LD. 106-107; M. 554.558).<\/p>\n<p>&nbsp;<\/p>\n<p>26 agosto: Entrada de la Real Pareja en Par\u00eds: desde Vincennes se dirigen a la Puerta de S. Antonio (Mazarino y Ana mandan sus carrozas para el desfile pero ellos lo contemplan desde el Hotel de Beauvais), van luego a la plaza del Delf\u00edn y por \u00faltimo al Louvre (LD. 108; M. 558-559; Mz. 209).<\/p>\n<p><strong>27 agosto:<\/strong> \u00abTe Deum\u00bb en Notre Dame por el matrimonio de Luis XIV y Mar\u00eda Teresa.<\/p>\n<p><strong>&#8212;&#8212;&#8212;&#8212;&#8211;:<\/strong><\/p>\n<p>&#8211; Primeras \u00abS\u00e1tiras\u00bb de Boileau<\/p>\n<p>&#8211; Racine escribe la Oda de las \u00abNinfas del Sena\u00bb<\/p>\n<p>&#8211; Mansart hace la fachada de Val de Grace<\/p>\n<p>&#8211; Gran Asamblea del Clero, que despu\u00e9s de quemar p\u00fablicamente las Provinciales de Pascal en septiembre, los obispos condenar\u00e1n las Cinco Proposiciones y tendr\u00e1n que firmar un juramento antijansenista.<\/p>\n<p>&#8211; Fallece el pintor Vel\u00e1zquez.<\/p>\n<h2>El a\u00f1o 1660: Vicente de Pa\u00fal<\/h2>\n<div class=\"mceTemp\"><\/div>\n<p><strong>Enero: <\/strong>hace un invierno muy duro. La enfermedad de Vicente va en aumento, no puede bajar las escaleras ni decir misa (VIII, 218.259); en julio ya no puede estar de pie ni dormir (VIII, 326) y se le hace una capilla en la habitaci\u00f3n contigua para que pueda o\u00edr misa; en agosto acepta una silla de traslado (VIII, 206; SL, 644.645.650). El P.Portail est\u00e1 mejor, pero se ha retirado a una especie de ermita que hab\u00eda en el recinto de S. L\u00e1zaro para los ejercitantes (SL, 644.645). El Hno. Barreau manda desde Argel dos leones a Marsella; all\u00ed va a estar el Rey y Vicente ordena que se los regalen (VIII, 212).<\/p>\n<p><strong>18 enero: <\/strong>VI\u00aa-bis. Expedici\u00f3n a Madagascar. Salen de La Rochela despu\u00e9s del fracaso del a\u00f1o anterior. Llegaron solamente hasta el Cabo de Buena Esperanza, donde el 20 de mayo se rompi\u00f3 el barco, despu\u00e9s de seis meses de navegaci\u00f3n. En barcos holandeses regresaron a Amsterdan, luego por B\u00e9lgica llegaron a Par\u00eds en julio de 1661, muerto ya Vicente. La pr\u00f3xima expedici\u00f3n ser\u00e1 en 1663. Los misioneros permanecieron en Madagascar hasta 1674 para volver en 1896 (VIII, 237.481-536; SL, 653; Pastor, XXXI, 127).<\/p>\n<p><strong>4 Febrero: <\/strong>dificultades para atender a las Hermanas de Cahors. Vicente les recuerda que el Superior de la casa debe atender por \u00e9l o por otros a las Hermanas como a las dem\u00e1s obras: seminario&#8230;etc. es responsabilidad del superior (VIII, 220).<\/p>\n<p><strong>6 febrero: <\/strong>el obispo de Montpellier cierra el seminario. El P. Get debe volver a Marsella y asumir sus funciones (VIII, 222.248.266).&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>14 febrero: <\/strong>muere el P. Portail; el 20 se tuvo la conferencia sobre sus virtudes (VIII, 235.240.241.245; XI, 873).<\/p>\n<p><strong>23 febrero: <\/strong>Vicente pide a Roma que se nombre al P. Bourdaise Prefecto de la Misi\u00f3n de Madagascar&#8230; (VIII, 230).<\/p>\n<p><strong>Marzo: <\/strong>proyecto de fundaci\u00f3n en Plasencia (Espa\u00f1a) (VIII, 258.271.282.; ver a\u00f1os 1644.1658). El Rey da las cartas Patentes, ordenando al Parlamento, que registre la bula de Uni\u00f3n de la casa de S. L\u00e1zaro a la C.M. (X, 557). El Hno. Barreau \u00ab<em>ha vuelto a hacer una de las suyas&#8230;<\/em>\u00bb (VIII, 266. 267. 272).<\/p>\n<p><strong>15 marzo<\/strong>: muere Luisa de Marillac; el 17 el entierro. VIII, 2 59. Vicente exclam\u00f3: \u00ab<em>Hay que alabar a Dios por ello<\/em>\u00bb VIII, 263. \u00ab<em>Quiz\u00e1s no tenga necesidad de nuestra oraci\u00f3n<\/em>\u00bb (VIII, 268).<\/p>\n<p><strong>18 marzo: <\/strong>Vicente escribe al Sr. de S. Mart\u00edn, pidi\u00e9ndole \u00abesas miserables cartas\u00bb del cautiverio (VIII, 260). Presenta la dimisi\u00f3n como Superior de los conventos de la Visitaci\u00f3n de Par\u00eds, Chaillot y S.Denis. (VIII, 261).<\/p>\n<p><strong>Mayo: <\/strong>en Roma hay otras Congregaciones que quiere compartir la obra de los Ordenandos&#8230;.el Papa no (VIII, 288.300). Algunos Cardenales (Ludovisio, Durazzo, Bagni) escriben a Vicente interes\u00e1ndose por su salud y le dicen que se considere dispensado de rezar el Oficio Divino (VIII, 445. 472. 474).<\/p>\n<p><strong>2 mayo:<\/strong> muere el abad de Tournus, Luis de Rochechuart de Chandenier (IV, 59.n.430 y VIII, 297). Hab\u00eda salido de peregrinaci\u00f3n a Roma a finales del a\u00f1o anterior y cuando volv\u00eda, al llegar a Chambery el 29 de abril, cay\u00f3 enfermo. El P.Berthe que le acompa\u00f1aba lo admiti\u00f3 en la C.M. seg\u00fan sus deseos. Se hicieron cargo del cad\u00e1ver los Padres de Annecy; luego ser\u00eda tra\u00eddo y enterrado en S.L\u00e1zaro (VIII, 285.297.298.303.317).<\/p>\n<p><strong>13 mayo: <\/strong>se hace la paz de la Oliva entre polacos y suecos (VIII, 228.246.261 y 296).<\/p>\n<p><strong>18 junio: <\/strong>el P. Eudes da una misi\u00f3n en Par\u00eds, en los QuinzeVingts. Vicente la califica de una buena \u00abemulaci\u00f3n\u00bb (VIII, 310.314.350).<\/p>\n<p><strong>22 junio: <\/strong>el P. Almer\u00e1s sale para Richelieu, all\u00ed recibi\u00f3 a los Reyes el 7 de julio; luego cay\u00f3 enfermo y, llamado m\u00e1s tarde por Vicente, lleg\u00f3 a Par\u00eds en litera el 24 de Septiembre (VIII, 314.326.396.350.464).<\/p>\n<p><strong>12 julio: <\/strong>muere en Sed\u00e1n, el Hno. Sirven \u00ab<em>regla viviente de la Compa\u00f1\u00eda<\/em>\u00bb (VIII, 332-333-334).<\/p>\n<p><strong>25 julio: <\/strong>Fundaci\u00f3n del 3er. Monasterio de la Visitaci\u00f3n en la calle Montorgueil de Par\u00eds (VIII 38.41.n.371.458).<\/p>\n<p><strong>Julio-Agosto: <\/strong>el capit\u00e1n Pa\u00fal intenta liberar los esclavos de Argel por la fuerza; Vicente apoya la iniciativa. Fracas\u00f3. No pudo desembarcar y s\u00f3lo rescat\u00f3 a 40, que a nado pudieron llegar hasta los barcos del capit\u00e1n (VII, 73.143; VIII, 263. 456. 465. 466.483).<\/p>\n<p>Agosto: el Hno. Ducournau da las gracias al Sr de S.Mart\u00edn por haber enviado las cartas de la cautividad a Bons Enfants y no a S. L\u00e1zaro (VIII, 537).<\/p>\n<p><strong>15 agosto: <\/strong>Bossuet prepara en Metz una casa seminario para la Compa\u00f1\u00eda (VIII, 383.n.454).<\/p>\n<p><strong>26 agosto: <\/strong>entrada solemne de los nuevos reyes, Luis XIV y Mar\u00eda Teresa; el d\u00eda 27 hay Te Deum en Notre Dame (VIII, 398.403).<\/p>\n<p><strong>15-27 septiembre: <\/strong>diario de los \u00faltimos d\u00edas de Vicente (X, 223-233).<\/p>\n<p><strong>26 septiembre: <\/strong>recibe la Extrema-Unci\u00f3n de manos del P. Dehorgny (X, 218).<\/p>\n<p><strong>27 septiembre: <\/strong>muere Vicente de Pa\u00fal a las 4,45 de la ma\u00f1ana (X, 218).<\/p>\n<p>Durante este a\u00f1o Vicente ha recibido una gran cantidad de cartas. Se le piden consejos y mediaciones: Hijas de la Visitaci\u00f3n (VIII, 429.442.457), Carmelitas. (VIII, 57.406.428.436), Ursulinas (VIII, 446)&#8230; Los Marqueses de Pransac, para que admita a su hijo, un degenerado, en la prisi\u00f3n de S.L\u00e1zaro.(VIII,355) Un galeote dice que su firma seria su salvaci\u00f3n. (VIII, 475). Le piden que los ni\u00f1os de la Longueville le puedan ver (VIII, 428.). Le ofrecen fundaciones. (VIII, 448). Se ofrecen unas mujeres como cooperadoras activas en las Misiones. (VIII, 463-464). Se ofrecen personas y piden por favor ingresar en la C.M. (VIII, 451).<\/p>\n<p><strong>Ultima carta (25 septiembre): <\/strong>Hemos decidido<em>: <\/em><em>\u00abno recibir a nadie en la Compa\u00f1\u00eda por recomendaci\u00f3n&#8230;; son pocos los que resultan bien de aquellos que no lo piden por s\u00ed mismo y, que ni vienen por devoci\u00f3n, ni por deseo de entregarse a Dios\u00bb.<\/em><\/p>\n<p><strong>1 octubre: <\/strong>el Nuncio Piccolomini comunica a Roma: \u00abel martes muri\u00f3 el padre Vicente de Paul, superior de los sacerdotes de la Misi\u00f3n, hombre de grand\u00edsimo m\u00e9rito y estima por las se\u00f1aladas obras de piedad que ha hecho\u00bb (X, 236).<\/p>\n<p><strong>CARTAS DE VICENTE DE PA\u00daL<\/strong><\/p>\n<ul>\n<li><em> \u00abLas buenas obras, lo mismo que las malas, est\u00e1n sujetas a la censura y las que no son contrarias no (por eso) dejan de tener buena intenci\u00f3n\u00bb. (VIII, 213).<\/em><\/li>\n<li><em> \u00abLe pido a Nuestro Se\u00f1or le devuelva la salud o una gracia tan poderosa que pueda utilizar perfectamente la situaci\u00f3n en que se encuentra\u00bb. (VIII, 219).<\/em><\/li>\n<li><em> \u00abEl abandono total en manos de la Providencia vale m\u00e1s que cualquier otra fundaci\u00f3n\u00bb. (VIII, 221).<\/em><\/li>\n<li><em> \u00abServicio y relaciones con las Hijas de la Caridad\u00bb (VIII, 226-227).<\/em><\/li>\n<li><em> \u00abMuerte del P. Portail y de Luisa, Chandenier y Hno&#8230; Sirven\u00bb. (VIII, 236; 259; 263; 269; 297; 341; 332).<\/em><\/li>\n<li><em> \u00abLa gracia de la perseverancia es la m\u00e1s importante; es la que corona las dem\u00e1s\u00bb. (VIII, 239).<\/em><\/li>\n<li><em> \u00abTodo se transforma en bien para los que sirven a Dios\u00bb (VIII, 244).<\/em><\/li>\n<li><em> \u00abLas obras de Dios tienen sus comienzos y sus progresos: arca, Hijo, ni\u00f1o, hora\u00bb (VIII, 257).<\/em><\/li>\n<li><em> \u00abCartas de cautividad\u00bb. (VIII, 260; 537).<\/em><\/li>\n<li><em> \u00abA nosotros nos toca rogarles que env\u00ede buenos obreros a vivir tan bien que con nuestro ejemplo les demos m\u00e1s aliciente que desgana para que trabaje con nosotros\u00bb (VIII, 285).<\/em><\/li>\n<li><em> \u00abHay peligro de complacencia o de vanidad para todos los que encuentran en los dem\u00e1s testimonio de afecto o de precio particular\u00bb (VIII, 290).<\/em><\/li>\n<li><em> \u00abSalida de las Hermanas\u00bb (VIII, 294-295).<\/em><\/li>\n<li><em> \u00ab\u00a1Qu\u00e9 pocas personas hay en el mundo que quieran servir a Dios y a su Iglesia con pureza de fe, con despego de las criaturas y con abnegaci\u00f3n de s\u00ed mismas!\u00bb (VIII, 310).<\/em><\/li>\n<li><em> \u00abDios saca provecho en donde nosotros no encontramos nuestra satisfacci\u00f3n\u00bb (VIII, 324).<\/em><\/li>\n<li><em> \u00abNo se puede ver siempre la casa sin defectos&#8230; para las faltas generales no veo otro remedio mas que las advertencias en p\u00fablico y en particular, junto con la oraci\u00f3n y la paciencia\u00bb (VIII, 339).<\/em><\/li>\n<li><em> \u00abCre\u00eda haber hecho un buen negocio envi\u00e1ndole a Richelieu, pero nunca lo volver\u00e9 a hacer, aunque usted y yo vivamos quince o veinte a\u00f1os en la misma situaci\u00f3n\u00bb (VIII, 350; 326).<\/em><\/li>\n<li><em> \u00abNo es justo que ese descanso (un d\u00eda a la semana) se haga a costa de la acci\u00f3n m\u00e1s importante del d\u00eda (la oraci\u00f3n)\u00bb (VIII, 377).<\/em><\/li>\n<li><em> \u00abRegistros e historia de las casas\u00bb (VIII, 467).<\/em><\/li>\n<li><em> \u00abNormas para una fundaci\u00f3n\u00bb (VIII, 467).<\/em><\/li>\n<li><em> \u00abHemos decidido no recibir a nadie&#8230;que nos sea presentado por parientes o amigos si no vienen por devoci\u00f3n ni por deseo de entregarse a Dios\u00bb(VIII, 479.)<\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><em>\u00daLTIMA CARTA DE VICENTE<\/em><\/strong><\/p>\n<ul>\n<li>\u00ab<em>Viaje \u00faltimo de los misioneros a Madagascar (relato) (VIII, 481-536).<\/em><\/li>\n<\/ul>\n<h2>El a\u00f1o 1660: Luisa de Marillac<\/h2>\n<p>Enero: Luisa empieza el a\u00f1o mucho mejor. El p\u00e1rroco de S. Lorenzo ha escrito \u00abLa feligresa Caritativa\u00bb y Luisa env\u00eda ejemplares a algunas Hermanas (51,647). Como todos los a\u00f1os env\u00eda las estampas a las casas. Este a\u00f1o le manda tambi\u00e9n a Vicente una, con Jes\u00fas rodeado de espinas junto con una medalla que una enferma le ha tra\u00eddo del santuario de Notre Dame de Liesse, y adem\u00e1s varios remedios curativos (VIII, 197; SL 646).<\/p>\n<p><strong>4 febrero: <\/strong>Luisa sufre un flujo de sangre en el brazo derecho que le causa fiebre (VIII, 228.). La \u00faltima carta de Luisa es del 2 de febrero a Juana Delacrois en Chateaudun: \u00ab<em>No deje de darme noticias y que me diga sobre todo si, mientras trabajan en el servicio exterior, su interior se ocupa por amor a Nuestro Se\u00f1or, en velar sobre s\u00ed mismas, para vencer y dominar las pasiones<\/em>\u00bb (SL, 652).<\/p>\n<p><strong>7 febrero: <\/strong>Vicente escribe al P. de la Fosse sobre la obligaci\u00f3n de atender a las Hijas de la Caridad (VIII, 226).<\/p>\n<p><strong>12 marzo<\/strong>: recibe los Ultimos Sacramentos y luego tuvo un alivio durante unos d\u00edas (VIII, 236.243. 241).<\/p>\n<p><strong>15 marzo<\/strong>: muere Luisa de Marillac entre las once y las doce del Lunes de Pasi\u00f3n (VIII, 259).<\/p>\n<p>17 marzo: entierro de Luisa en la Capilla de la Visitaci\u00f3n de la parroquia de S.Lorenzo. Su deseo era que fuera enterrada en San L\u00e1zaro, pero lo dejaba a la voluntad de Vicente. Para los funerales <em>\u00abdeclaro que no quiero que se hagan otros gastos que los que se han hecho para nuestras Hermanas difuntas; y que si alguien quisiera ser causa de que se hiciera de otro modo, creo desde ahora que no habr\u00eda tenido nunca ning\u00fan afecto por m\u00ed<\/em>\u00bb (SL. 832).<\/p>\n<p><strong>Mayo: <\/strong>el P.Dehorgny (I, 111.n) es nombrado para sustituir al P. Portail, como Director de las Hermanas (VIII, 293 294.295).<\/p>\n<p><strong>24 mayo: <\/strong>Vicente manda venir a Sor Maturina desde La Fere para que vaya a la nueva fundaci\u00f3n en Breta\u00f1a, en Belle-Isleen-Mer (VIII, 284.293-294).<\/p>\n<p><strong>3 y 24 julio: <\/strong>Vicente tiene dos conferencias con las Hermanas sobre las virtudes de Santa Luisa (IX, 1218-1241).<\/p>\n<p><strong>27 agosto: <\/strong>Margarita Chetif es nombrada para suceder a Luisa de Marillac y son elegidas las oficialas (VIII, 321; IX, 1244-1246. \u00daltima Conferencia de San Vicente).<\/p>\n<p><strong>15 septiembre: <\/strong>el P. Dehorgny preside la toma de posesi\u00f3n de Sor Margarita Chetif, como Superiora de las Hijas de la Caridad (X.223). Vicente prepara la Obediencia para tres Hermanas que, junto con un Padre, dos Hnos. Cl\u00e9rigos y un Hermano Coadjutor, marchan a Polonia (VIII, 464.465; X, 730).<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;-: Fundaci\u00f3n de Gex y Moutiers-Saint Jean.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;-: Reglamento de las Damas del Hotel-Dieu (X, 964).<\/p>\n<p>CARTAS DE LUISA DE MARILLAC<\/p>\n<ul>\n<li><em> \u00abVuelvo sobre lo que ya le he dicho sobre el catecismo. Si ha llegado el tiempo de que lo que las Hijas de la Caridad han venido haciendo hasta ahora con sordina, resplandezca a plena luz, \u00a1bendito sea su santo Nombre!\u00bb (p. 646).<\/em><\/li>\n<li><em> \u00ab(Vocaciones) Lo que se necesitan son esp\u00edritus equilibrados y que deseen la perfecci\u00f3n de los verdaderos cristianos, que quieran morir a si mismas por la mortificaci\u00f3n y la verdadera renuncia, ya hecha en el santo bautismo, para que el esp\u00edritu de Jesucristo reine en ellas y les d\u00e9 la firmeza de la perseverancia en esta forma de vida, del todo espiritual, aunque se manifieste en continuas acciones exteriores que parecen bajas y despreciables a los ojos del mundo, pero que son grandes ante Dios y sus \u00e1ngeles\u00bb (p. 648).<\/em><\/li>\n<li>\u00ab<em>Parece que nuestras Hermanas no son ya ni tan apreciadas ni tan queridas, que se las trata con m\u00e1s dureza y en algunos lugares se las vigila por desconfianza&#8230; Esto me ha hecho pensar, mi muy Honorable Padre, en la necesidad de que las reglas obliguen siempre a la vida pobre, sencilla y humilde, por miedo a que, si se adoptara una forma de vida que requiera m\u00e1s gasto y con pr\u00e1cticas que atrajeran a la ostentaci\u00f3n y, en parte, a la a clausura, esto obligara a buscar medios para subsistir en esta forma, como ser\u00eda, por ejemplo, constituir un cuerpo o grupo interior y sin acci\u00f3n, que se alojar\u00eda por separado de las que entraran y salieran, mal vestidas; porque hay ya algunas que dicen que este tocado, este nombre de Hermana, no nos dan autoridad sino que atraen desprecio\u00bb.<\/em><\/li>\n<li><em> \u00abY s\u00e9 muy bien que no s\u00f3lo las Hermanas, sino otras personas que deber\u00edan considerarse obligadas a honrar los designios de Dios en cuanto al servicio espiritual y corporal de los pobres enfermos, est\u00e1n muy inclinadas a este modo de pensar tan peligroso para la continuaci\u00f3n de la obra de Dios, la que con tanta firmeza, mi muy Honorable Padre, ha sostenido su caridad contra todas las oposiciones&#8230; Si su caridad ve que Dios quiere otra cosa que lo que se ha hecho hasta ahora, en el nombre de Nuestro Se\u00f1or, sea ella quien lo ordene y lo declare; yo siempre ser\u00e9 la misma, sin r\u00e9plica, despu\u00e9s de haber tomado la libertad, como lo hago, de exponer las razones que se presenten a mi esp\u00edritu, no atrevi\u00e9ndome a decir que sean los pensamientos que Dios me inspira\u00bb. (pp. 651-652)(825-826).<\/em><\/li>\n<li><em> \u00abSin esto (a las acciones exteriores debe acompa\u00f1ar interiormente un domino sobre las pasiones y sentidos) sabe usted muy bien que las acciones exteriores, aun cuando sean para el servicio de los pobres, no pueden agradar mucho a Dios ni merecemos recompensa\u00bb (p. 652).<\/em><\/li>\n<\/ul>\n<p><strong><em>Cartas sin fecha<\/em><\/strong><\/p>\n<ul>\n<li><em> \u00abDios lo \u00fanico que quiere de nosotros es nuestro coraz\u00f3n; no ha puesto en nuestro poder m\u00e1s que el puro acto de voluntad y es lo que mira, junto con la acci\u00f3n que de \u00e9l procede&#8230; Aqu\u00ed tiene, pues, se\u00f1ora, sencillamente como Nuestro Se\u00f1or me lo inspira, lo que su humildad ha pedido a mi pobreza\u00bb (p. 653).<\/em><\/li>\n<li><em> \u00abHermana, tiene que haber tan grande igualdad, que cuando todo est\u00e9 bien establecido en la Compa\u00f1\u00eda pueda juzgarse conveniente que todas las Hermanas sean alternativamente Hermanas Sirvientes, cada una un a\u00f1o\u00bb (p. 655).<\/em><\/li>\n<li><em> \u00abHemos de acostumbrarnos a rogar y no a mandar; a ense\u00f1ar con el ejemplo y no dando \u00f3rdenes\u00bb (p. 656).<\/em><\/li>\n<li><em> \u00abHermana, \u00a1qu\u00e9 lamentable es la verdad!! \u00a1Cu\u00e1nto tiempo hace que le he rogado a usted que se deshiciera de esos animales! (gatos en la oraci\u00f3n) y no lo tiene usted en cuenta; en cambio, \u00a1si una Hermana deja de obedecerle con prontitud &#8230;!\u00bb (p. 656).<\/em><\/li>\n<li><em> \u00abPerm\u00edtame que me coloque ante usted como una pobre vergonzante que le pide, por amor de Dios, la caridad de darle la limosna de una breve visita, de la que tengo gran necesidad&#8230; \u00a1Si su caridad pudiese hoy!\u00bb (p. 659).<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El a\u00f1o 1660 en Francia: 27 enero: Despu\u00e9s del Tratado de los Pirineos, Cond\u00e9 se entrevista humildemente con la Corte en Aix, que prosegu\u00eda su gira por el sur, mientras se ultimaban los preparativos de &#8230; <a href=\"http:\/\/vincentians.com\/es\/ano-1660\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":400140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[230,168,130,163,126,127],"class_list":["post-40403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-tiempos-de-vicente-de-paul","tag-almeras","tag-argel","tag-beauvais","tag-bons-enfants","tag-dehorgny","tag-portail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A\u00f1o 1660 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/ano-1660\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00f1o 1660 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"El a\u00f1o 1660 en Francia: 27 enero: Despu\u00e9s del Tratado de los Pirineos, Cond\u00e9 se entrevista humildemente con la Corte en Aix, que prosegu\u00eda su gira por el sur, mientras se ultimaban los preparativos de ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/ano-1660\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-20T06:43:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886\" \/>\n\t<meta property=\"og:image:width\" content=\"1771\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"A\u00f1o 1660\",\"datePublished\":\"2017-04-20T06:43:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/\"},\"wordCount\":3034,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886\",\"keywords\":[\"Almer\u00e1s\",\"Argel\",\"Beauvais\",\"Bons Enfants\",\"Dehorgny\",\"Portail\"],\"articleSection\":[\"En tiempos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/\",\"name\":\"A\u00f1o 1660 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886\",\"datePublished\":\"2017-04-20T06:43:11+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2011\\\/11\\\/HIjas-Caridad.jpg?fit=1771%2C886\",\"width\":1771,\"height\":886},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/ano-1660\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00f1o 1660\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00f1o 1660 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/ano-1660\/","og_locale":"es_ES","og_type":"article","og_title":"A\u00f1o 1660 - Somos Vicencianos","og_description":"El a\u00f1o 1660 en Francia: 27 enero: Despu\u00e9s del Tratado de los Pirineos, Cond\u00e9 se entrevista humildemente con la Corte en Aix, que prosegu\u00eda su gira por el sur, mientras se ultimaban los preparativos de ... Read More","og_url":"http:\/\/vincentians.com\/es\/ano-1660\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2017-04-20T06:43:11+00:00","og_image":[{"width":1771,"height":886,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/ano-1660\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/ano-1660\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"A\u00f1o 1660","datePublished":"2017-04-20T06:43:11+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/ano-1660\/"},"wordCount":3034,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/ano-1660\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","keywords":["Almer\u00e1s","Argel","Beauvais","Bons Enfants","Dehorgny","Portail"],"articleSection":["En tiempos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/ano-1660\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/ano-1660\/","url":"http:\/\/vincentians.com\/es\/ano-1660\/","name":"A\u00f1o 1660 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/ano-1660\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/ano-1660\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","datePublished":"2017-04-20T06:43:11+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/ano-1660\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/ano-1660\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/ano-1660\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","width":1771,"height":886},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/ano-1660\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"A\u00f1o 1660"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/11\/HIjas-Caridad.jpg?fit=1771%2C886","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-avF","jetpack-related-posts":[{"id":38867,"url":"http:\/\/vincentians.com\/es\/ano-1649\/","url_meta":{"origin":40403,"position":0},"title":"A\u00f1o 1649","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/03\/2017","format":false,"excerpt":"El a\u00f1o 1649 en Francia: 6 enero: En la noche del 5 al 6 de enero (noche de Reyes), a las dos de la madrugada, la Corte sale de inc\u00f3gnito hacia S. German-en-Laye. Las sobrinas de Mazarino ya hab\u00edan salido para Sed\u00e1n con el Mariscal Fabert (LD. 63; A. 295;\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":398981,"url":"http:\/\/vincentians.com\/es\/vicente-paul-carta-1343-luisa-marillac-san-vicente\/","url_meta":{"origin":40403,"position":1},"title":"Vicente de Pa\u00fal, Carta 1343: Luisa De Marillac a San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/10\/2016","format":false,"excerpt":"[Entre 1647 y 1660] Mi muy venerado padre: Le ruego por amor de Dios que me reserve una hora y me la indique para ir a hablar con usted, para que as\u00ed pueda organizar mis cosas y buscar la ocasi\u00f3n para ir a tratar con usted el asunto del que\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":38851,"url":"http:\/\/vincentians.com\/es\/ano-1648\/","url_meta":{"origin":40403,"position":2},"title":"A\u00f1o 1648","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/03\/2017","format":false,"excerpt":"El a\u00f1o 1648 en Francia: 15 enero: Comienza el a\u00f1o con sublevaciones a causa de los Impuestos. De Emmery quiere un nuevo impuesto para los bienes de la Iglesia (la Santa Sede se opone) y otro a los que tienen el uso de los inmuebles del Dominio Real. Mazarino lleva\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/jesus-discipulos.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":115062,"url":"http:\/\/vincentians.com\/es\/casas-de-las-hijas-de-la-caridad-en-paris-en-tiempos-de-san-vicente-ii\/","url_meta":{"origin":40403,"position":3},"title":"Casas de las Hijas de la Caridad en Par\u00eds en tiempos de San Vicente (II)","author":"Mitxel Olabu\u00e9naga","date":"20\/02\/2019","format":false,"excerpt":"1) Parroquias (continuaci\u00f3n) m) Santiago de Alto Paso (II, 442) Para atender a los parroquianos alejados de las parroquias de S. Benito, de S. Medardo y de S. Hip\u00f3lito se habilit\u00f3 la capilla que la Comendadur\u00eda de Santiago de Alto Paso, (sucursal de la Orden Militar de Italia del Alto\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":405305,"url":"http:\/\/vincentians.com\/es\/origen-de-la-congregion-de-la-mision\/","url_meta":{"origin":40403,"position":4},"title":"ORIGEN DE LA CONGREGI\u00d3N DE LA MISI\u00d3N","author":"Mitxel Olabu\u00e9naga","date":"22\/08\/2024","format":false,"excerpt":"En la gran Historia de la Ciudad de Par\u00eds, de dom Filibien, completada por dom Lobineau, c\u00e9lebres benedictinos, se encuentra la narraci\u00f3n siguiente, relativa a la Congrega\u00adci\u00f3n de la Misi\u00f3n: \"El Instituto de los Sacerdotes de la Misi\u00f3n naci\u00f3 en el Colegio de los Buenos Hijos. hacia principios del a\u00f1o\u2026","rel":"","context":"En \u00abEn tiempos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"En tiempos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/en-tiempos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":387869,"url":"http:\/\/vincentians.com\/es\/amigo-de-los-pobres-anos-de-despedida-1654-1660\/","url_meta":{"origin":40403,"position":5},"title":"San Vicente: Amigo de los pobres: a\u00f1os de despedida (1654-1660)","author":"Mitxel Olabu\u00e9naga","date":"17\/10\/2016","format":false,"excerpt":"La vejez se parece a los atardeceres. Todos los d\u00edas, cuando concluye la tarde las nubes sacan sus vestidos de colores para celebrar la fiesta del sol que ha completado felizmente su jornada. Vicente de Pa\u00fal ha llegado al ocaso de su vida. Va a concluir una feliz jornada. Hab\u00eda\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/40403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=40403"}],"version-history":[{"count":2,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/40403\/revisions"}],"predecessor-version":[{"id":400504,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/40403\/revisions\/400504"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/400140"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=40403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=40403"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=40403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}