{"id":403564,"date":"2021-06-11T08:00:03","date_gmt":"2021-06-11T06:00:03","guid":{"rendered":"http:\/\/vincentians.com\/es\/?p=403564"},"modified":"2021-05-15T18:01:25","modified_gmt":"2021-05-15T16:01:25","slug":"la-cofradia-de-la-caridad-xiv","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/","title":{"rendered":"LA COFRAD\u00cdA DE LA CARIDAD (XIV)"},"content":{"rendered":"<p>LA M\u00cdSTICA DEL SERVICIO: CONTEMPLAR A CRISTO EN EL POBRE<\/p>\n<p>Al comienzo del reglamento san Vicente cita el evangelio de san Mateo: \u00abVenid, benditos de mi Padre, poseed el reino que se os tiene preparado desde el comienzo del mundo; porque tuve hambre y me disteis de comer; estuve enfermo y me visitasteis; pues todo lo que hicisteis con uno de esos peque\u00f1os, a m\u00ed me lo hicisteis\u00bb. M\u00e1s adelante, al indicar c\u00f3mo la sirvientas de los pobres debe darle de comer al pobre le dice que lo haga \u00abcomo si se tratase de su propio hijo <strong>o mejor dicho de Dios, que con\u00adsidera como hecho a s\u00ed mismo el bien que se le hace a los pobres\u00bb.<\/strong><\/p>\n<p>Encontramos aqu\u00ed una de las claves de la espiritualidad vicenciana, en la que muy poco se insiste, porque, en el fondo, le tenemos miedo o no nos atrevemos a practicar: se trata de la m\u00edstica vicenciana. Sin esa m\u00edstica o si queremos sin la dimen\u00adsi\u00f3n contemplativa, el servicio se asemejar\u00e1 al servicio de cual\u00adquier asalariado, le faltar\u00e1 la dimensi\u00f3n cristol\u00f3gica, en la que tanto insist\u00eda Vicente de Pa\u00fal a la sirvienta de los pobres.<\/p>\n<p>Meditando y reflexionando en este texto de san Mateo Vicen\u00adte de Pa\u00fal llega a esa luz clave de su vida que ilumina todo su caminar, a esa verdad fundamental, de todo cristiano, pero que en Vicente de Pa\u00fal tuvo relevancia particular: En el pobre est\u00e1 presente el mismo Cristo. Este es la verdad motriz de Vicente de Pa\u00fal. Es la verdad clave de toda su vida. Es una de esas verda\u00addes que configuran toda una vida y la lanzan por los caminos de la santidad. Con la vivencia radical de esta verdad san Vicente se ha convertido en un m\u00edstico. \u00bfEn d\u00f3nde encuentra Vicente a Cristo? En los pobres. \u00bfQui\u00e9n ilumina a Vicente en el camino de su fe? Cristo encarnado en los pobres. \u00bfPor qu\u00e9 para Vicente de Pa\u00fal los pobres son sus amos y se\u00f1ores? Porque en ellos visuali\u00adza, con los ojos de la fe, al mismo Cristo. \u00bfEn d\u00f3nde encuentra al verdadero Dios Vicente de Pa\u00fal? En todos aquellos que sufren. \u00bfPor qu\u00e9 los pobres son su peso y su dolor? Porque en ellos encuentra el rostro de Cristo que sufre en ellos. \u00bfPor qu\u00e9 cuando se deja la eucarist\u00eda o la oraci\u00f3n por el servicio de los pobres es dejar a Dios por Dios? Porque el servicio de los pobres es un encuentro con Cristo.<\/p>\n<p>Podemos afirmar sin ambig\u00fcedades que el centro de su cristo-centrismo est\u00e1 aqu\u00ed: Cristo se revela, se manifiesta, se encuentra en los m\u00e1s desfavorecidos de la sociedad. \u00abCuanto hicisteis a uno de mis estos hermanos m\u00edos m\u00e1s peque\u00f1os, a m\u00ed me lo hicisteis&#8217;.<\/p>\n<p>Sus palabras son expresi\u00f3n de sus vivencias y \u00e9stas son abun\u00addantes en este sentido. Aqu\u00ed centra todo el grueso de sus reflexiones cuando motiva tanto a las Hijas de la Caridad como a los misione\u00adros para entregarse sin reservas al servicio y a la evangelizaci\u00f3n de los pobres. Porque un servicio y una evangelizaci\u00f3n sin esta dimen\u00adsi\u00f3n m\u00edstica ser\u00edan simples actividades de funcionario, no de una verdadero espiritual, no de un vicenciano.<\/p>\n<p>A un enfermo hay que servirlo con el convencimiento de que \u00e9l representa a nuestro Se\u00f1or. Cuando encuentras un enfermo en tu casa en ella tienes un sagrario.<\/p>\n<p>Cuando serv\u00eds a los enfermos, ten\u00e9is que acordaron tambi\u00e9n de que es a Nuestro Se\u00f1or a quien representa ese pobre<sup>65<\/sup>.<\/p>\n<p>El glorificar y honrar a nuestro Se\u00f1or es un acto fundamental de la religi\u00f3n y de la fe cristiana. Cuando nos acercamos a los pobres honramos a Jesucristo y contemplamos en ellos la misma sabidur\u00eda encarnada de Dios.<\/p>\n<p>\u00abEs menester que sep\u00e1is que \u00e9l est\u00e1 en esos pobres privados de raz\u00f3n lo mismo que en todos los dem\u00e1s. Con esta creencia ten\u00e9is que ser\u00advirles y, cuando vay\u00e1is a verlos, alegraos y decid dentro de vosotras mismas: \u00abMe acerco a esos pobres para honrar en sus personas a la persona de Nuestro Se\u00f1or; voy a ver en ellos a la sabidur\u00eda encarna\u00adda de Dios que quiso pasar por tal, sin serlo efectivamente\u00bb.<\/p>\n<p>El acto de adoraci\u00f3n est\u00e1 en el mismo origen de nuestra fe y es una actitud b\u00e1sica de nuestro comportamiento como creyentes y cristianos. Est\u00e1 en el centro de nuestra vida cristiana.<\/p>\n<p>Pues bien, para hacer que vuestro viaje o lo que vay\u00e1is a hacer sea agradable a Dios, ten\u00e9is que proponeros adorar a Nuestro Se\u00f1or en las personas con las que vais a tratar&#8230; De esta forma, hijas m\u00edas, si os port\u00e1is como hemos dicho, os bendecir\u00e1 Nuestro Se\u00f1or por fuera, os bendecir\u00e1 por dentro, os bendecir\u00e1 en todo lo que hag\u00e1is.<\/p>\n<p>Los pobres son los miembros que poseen un honor supremo, porque ellos representan al mismo Hijo de Dios, encarnan la m\u00e1xima dignidad de Cristo, son los lugartenientes de Dios, son los vicarios de Cristo, son sus verdaderos iconos.<\/p>\n<p>\u00abEl primer motivo, dijo una hermana, es que los pobres tienen el honor de representar a los miembros de Jesucristo, que considera los servicios que se les hacen como hechos a \u00e9l mismo (Mt 25,40). El segundo, que las almas de los pobres tienen en s\u00ed la imagen de Dios, y por consiguiente tenemos que honrar en ellos a la Sant\u00edsima Trinidad. El tercero es la recomendaci\u00f3n que el Hijo de Dios nos ha hecho con sus palabras y ejemplos; para demostrarles a los dis\u00adc\u00edpulos de san Juan que era el Mes\u00edas, les dijo que los pobres eran evangelizados y los enfermos eran curados\u00bb.<\/p>\n<p>Servir a los pobres contemplando en ellos la imagen del Hijo de Dios es fuente de felicidad, porque se hace a Cristo, realidad invisible, los que se hace a sus miembros, los pobres, que son sus representantes.<\/p>\n<p>\u00a1Qu\u00e9 felicidad, hijas m\u00edas, servir a la persona de nuestro Se\u00f1or en sus pobres miembros! \u00c9l nos ha dicho que considerar\u00e1 este servicio como hecho a \u00c9l mismo. \u00a1Qu\u00e9 buena hermana, preferir ver a los pobres m\u00e1s que a sus parientes y mirar siempre en su persona a la de Jesucristo! \u00a1Bendito sea Dios por siempre!<\/p>\n<p>Para san Vicente Jesucristo se siente identificado con los que sufren, con los que est\u00e1n en la c\u00e1rcel, con los enfermos y \u00c9l sufre con su sufrimiento.<\/p>\n<p>Acordaos de que es Nuestro Se\u00f1or a quien hac\u00e9is ese servicio, ya que \u00c9l lo considera como hecho a s\u00ed mismo: <em>\u00abEstar\u00e9 a su lado en la desgracia\u00bb <\/em>(Sal, 90, 15) dice hablando de los pobres. Si \u00e9l est\u00e1 enfermo, yo tambi\u00e9n lo estoy; si est\u00e1 en la c\u00e1rcel, yo tambi\u00e9n; si tiene grilletes en los pies, los tengo yo con \u00e9l. Y otra raz\u00f3n es que ten\u00e9is que mirar a los pobres como si fueran vuestros amos.<\/p>\n<p>Y partir de aqu\u00ed Vicente saca una conclusi\u00f3n, profundamente querida por \u00e9l: \u00abAl servir a los pobres, se sirve a Jesucristo. Hijas m\u00edas, \u00a1cu\u00e1nta verdad es esto! Serv\u00eds a Jesucristo en la persona de los pobres\u00bb. Esta no es una verdad cualquiera. Es una verdad arraigada en lo m\u00e1s profundo de su ser, que constituye la misma esencia de su fe. Es una verdad palpable, verificable, experimenta\u00adda por \u00e9l mismo. \u00abY esto es tan verdad como que estamos aqu\u00ed\u00bb.<\/p>\n<p>Pero hay texto muy conocido, que ya es un cl\u00e1sico en este tema, que manifiesta con una fuerza inusitada la convicci\u00f3n de san Vicente, una convicci\u00f3n que trata de trasmitir a las Hijas de la Caridad, porque est\u00e1 convencido que es la \u00fanica manera de reali\u00adzar uno de los elementos fundamentales de su espiritualidad. De esa verdad no se puede dudar. Es una de esas certezas fuerza, es el mayor dinamismo espiritual de servidora de los pobres, es el la convicci\u00f3n motriz que libera energ\u00edas para la entrega sin reservas a Dios en el servicio de los pobres.<\/p>\n<p>Al servir a los pobres, se sirve a Jesucristo. Hijas m\u00edas, \u00a1cu\u00e1nta ver\u00addad es esto! Serv\u00eds a Jesucristo en la persona de los pobres. Y esto es tan verdad como que estamos aqu\u00ed. Una hermana ir\u00e1 diez veces cada d\u00eda a ver a los enfermos, y diez veces cada d\u00eda encontrar\u00e1 en ellos a Dios. Como dice san Agust\u00edn, lo que vemos no es tan segu\u00adro, porque nuestros sentidos pueden enga\u00f1arse; pero las verdades de Dios no enga\u00f1an jam\u00e1s. Id a ver a los pobres condenados a cadena perpetua, y en ellos encontrar\u00e9is a Dios; servid a esos ni\u00f1os, y en ellos encontrar\u00e9is a Dios. \u00a1Hijas m\u00edas, cu\u00e1n admirable es esto! Vais a unas casas muy pobres, pero all\u00ed encontr\u00e1is a Dios. Hijas m\u00edas, una vez m\u00e1s, \u00a1cu\u00e1n admirable es esto! S\u00ed, Dios acoge con agrado el servicio que hac\u00e9is a esos enfermos y lo considera, como hab\u00e9is dicho, hecho a \u00e9l mismo<sup>73<\/sup>.<\/p>\n<p>\u00bfCu\u00e1l es el camino para encontrar a Cristo, para descubrirlo, para llegar a \u00c9l? Son los pobres, los hombres que sufren, los que padecen. El Cristo de Vicente se encuentra en el enfermo, en el preso, en el galeote, en el ni\u00f1o abandonado, en las v\u00edctimas de las guerras religiosas de su tiempo.<\/p>\n<p>El pobre era para san Vicente la presencia cuasi sacramental de Cristo. Ah\u00ed radica la dignidad del pobre. San Vicente se encontr\u00f3 con Cristo encarnado y presente en el pobre, desde los primeros a\u00f1os de su transformaci\u00f3n espiritual, ya en el regla\u00admento de Ch\u00e1tillon. Era uno de esos dinamismos vitalizadores de la inmensa actividad desplegada a lo largo de su vida. Esta es la explicaci\u00f3n m\u00e1s l\u00f3gica de esa aplicaci\u00f3n genial de Vicente de que ellos son nuestros amos y se\u00f1ores.<\/p>\n<p>Jos\u00e9 Manuel S\u00e1nchez Mallo<\/p>\n<p>CEME, 2008<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA M\u00cdSTICA DEL SERVICIO: CONTEMPLAR A CRISTO EN EL POBRE Al comienzo del reglamento san Vicente cita el evangelio de san Mateo: \u00abVenid, benditos de mi Padre, poseed el reino que se os tiene preparado &#8230; <a href=\"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":5,"featured_media":399748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[307],"tags":[],"class_list":["post-403564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion-vicenciana-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA COFRAD\u00cdA DE LA CARIDAD (XIV) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA COFRAD\u00cdA DE LA CARIDAD (XIV) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"LA M\u00cdSTICA DEL SERVICIO: CONTEMPLAR A CRISTO EN EL POBRE Al comienzo del reglamento san Vicente cita el evangelio de san Mateo: \u00abVenid, benditos de mi Padre, poseed el reino que se os tiene preparado ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T06:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mitxel Olabu\u00e9naga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitxel Olabu\u00e9naga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/\"},\"author\":{\"name\":\"Mitxel Olabu\u00e9naga\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\"},\"headline\":\"LA COFRAD\u00cdA DE LA CARIDAD (XIV)\",\"datePublished\":\"2021-06-11T06:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/\"},\"wordCount\":1725,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/con-damas-de-la-caridad.jpg?fit=1200%2C630\",\"articleSection\":[\"Formaci\u00f3n Vicenciana sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/\",\"name\":\"LA COFRAD\u00cdA DE LA CARIDAD (XIV) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/con-damas-de-la-caridad.jpg?fit=1200%2C630\",\"datePublished\":\"2021-06-11T06:00:03+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/con-damas-de-la-caridad.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/con-damas-de-la-caridad.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-cofradia-de-la-caridad-xiv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA COFRAD\u00cdA DE LA CARIDAD (XIV)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/7c2670b4445a7ca9d164ea6acdb31859\",\"name\":\"Mitxel Olabu\u00e9naga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g\",\"caption\":\"Mitxel Olabu\u00e9naga\"},\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/mitxel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA COFRAD\u00cdA DE LA CARIDAD (XIV) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/","og_locale":"es_ES","og_type":"article","og_title":"LA COFRAD\u00cdA DE LA CARIDAD (XIV) - Somos Vicencianos","og_description":"LA M\u00cdSTICA DEL SERVICIO: CONTEMPLAR A CRISTO EN EL POBRE Al comienzo del reglamento san Vicente cita el evangelio de san Mateo: \u00abVenid, benditos de mi Padre, poseed el reino que se os tiene preparado ... Read More","og_url":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_published_time":"2021-06-11T06:00:03+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Mitxel Olabu\u00e9naga","twitter_card":"summary_large_image","twitter_creator":"@WeVincentians","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Mitxel Olabu\u00e9naga","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/"},"author":{"name":"Mitxel Olabu\u00e9naga","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859"},"headline":"LA COFRAD\u00cdA DE LA CARIDAD (XIV)","datePublished":"2021-06-11T06:00:03+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/"},"wordCount":1725,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630","articleSection":["Formaci\u00f3n Vicenciana sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/","url":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/","name":"LA COFRAD\u00cdA DE LA CARIDAD (XIV) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630","datePublished":"2021-06-11T06:00:03+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/la-cofradia-de-la-caridad-xiv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"LA COFRAD\u00cdA DE LA CARIDAD (XIV)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/7c2670b4445a7ca9d164ea6acdb31859","name":"Mitxel Olabu\u00e9naga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34137ec2e2b8939cbbed975731e71f3f4f1defc7266ded337a5ce0f925426877?s=96&d=mm&r=g","caption":"Mitxel Olabu\u00e9naga"},"url":"http:\/\/vincentians.com\/es\/author\/mitxel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/con-damas-de-la-caridad.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-1GZ6","jetpack-related-posts":[{"id":398641,"url":"http:\/\/vincentians.com\/es\/aportacion-del-carisma-vicenciano-la-mision-la-iglesia-4\/","url_meta":{"origin":403564,"position":0},"title":"Aportaci\u00f3n del carisma vicenciano a la Misi\u00f3n de la Iglesia (4)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/08\/2016","format":false,"excerpt":"4.- La salvaci\u00f3n de los pobres en el centro de la Misi\u00f3n de la Iglesia. San Vicente de Pa\u00fal y Santa Luisa de Marillac compartieron la misma experiencia: los pobres son los miembros de Cristo y, por tanto, de la Iglesia. En la Iglesia, Cuerpo de Cristo, los pobres ocupan\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":399992,"url":"http:\/\/vincentians.com\/es\/carisma-vicenciano-la-nueva-evangelizacion-algunas-claves-vicencianas-la-evangelizacion-actual\/","url_meta":{"origin":403564,"position":1},"title":"El Carisma Vicenciano y la Nueva Evangelizaci\u00f3n: algunas claves vicencianas para la evangelizaci\u00f3n actual","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/09\/2016","format":false,"excerpt":"Punto de partida: Confrontaci\u00f3n entre el Ser y el Quehacer Con frecuencia, en nuestros encuentros, convivencias, reuniones, asambleas... nos planteamos dos cuestiones relativas al ser y al quehacer vicencianos. Partimos de dos percepciones: por un lado, todos estamos de acuerdo en que el carisma, el ser, la identidad, el sello\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":118011,"url":"http:\/\/vincentians.com\/es\/la-iglesia-de-los-pobres-y-la-familia-vicenciana\/","url_meta":{"origin":403564,"position":2},"title":"La Iglesia de los pobres y la familia vicenciana","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/04\/2014","format":false,"excerpt":"El problema de los pobres y de la pobreza ocupa el primer plano en las preocupaciones de la Iglesia en nuestro tiempo, es\u00adpecialmente desde que Juan XXIII anunci\u00f3 al mundo, al abrir el Concilio Vaticano II (11 septiembre 1962) que la Iglesia era \"preferentemente de los pobres y para los\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"san-vicente-de-paul","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/01\/san-vicente-de-paul.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":132348,"url":"http:\/\/vincentians.com\/es\/carta-de-adviento-2014-a-la-familia-vicenciana-del-p-general\/","url_meta":{"origin":403564,"position":3},"title":"Carta de Adviento 2014 a la Familia Vicenciana, del P. General","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/12\/2014","format":false,"excerpt":"Adviento 2014, un tiempo de oraci\u00f3n, de paz y un lugar para los pobres Roma, 30 de Noviembre de 2014 Primer domingo de Adviento Queridos hermanos y queridas hermanas en Jes\u00fas y san Vicente, \u00a1Que la gracia y la paz de Nuestro Se\u00f1or Jesucristo est\u00e9n siempre en nuestros corazones! El\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"Altar mayor del santuario de Nuestra Se\u00f1ora Reina de la Paz, en Kazajist\u00e1n","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/12\/advent2014-300x195.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":398646,"url":"http:\/\/vincentians.com\/es\/aportacion-del-carisma-vicenciano-la-mision-la-iglesia-10-fin\/","url_meta":{"origin":403564,"position":4},"title":"Aportaci\u00f3n del carisma vicenciano a la Misi\u00f3n de la Iglesia (10 &#8211; Fin)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/08\/2016","format":false,"excerpt":"10.- La circularidad vicenciana: de Cristo a los pobres, de los pobres a Cristo. Para concluir esta reflexi\u00f3n sobre la aportaci\u00f3n del carisma vicenciano a la Misi\u00f3n de la Iglesia, me parece oportuno referirme a la \u201ccircularidad\u201d vicenciana: de Cristo a los pobres, de los pobres a Cristo. \u201cAmemos al\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":108324,"url":"http:\/\/vincentians.com\/es\/que-podemos-aportar-los-vicencianos-a-la-tarea-evangelizadora-de-la-iglesia\/","url_meta":{"origin":403564,"position":5},"title":"\u00bfQu\u00e9 podemos aportar los vicencianos a la tarea evangelizadora de la Iglesia?","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/09\/2018","format":false,"excerpt":"De entrada, quiero dejar muy claro que \u00e9ste no es un art\u00edculo completo y acabado. Se trata, m\u00e1s bien, de una especie de esbozo, de borrador, de \"lluvia de ideas\". Y, evidentemente, se trata tambi\u00e9n de mi propia opini\u00f3n que no es ni mejor ni peor que otras opiniones. Por\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/comnidad-vicenciana-para-la-mision.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/comnidad-vicenciana-para-la-mision.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/comnidad-vicenciana-para-la-mision.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/comnidad-vicenciana-para-la-mision.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/comnidad-vicenciana-para-la-mision.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=403564"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403564\/revisions"}],"predecessor-version":[{"id":403565,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/403564\/revisions\/403565"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/399748"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=403564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=403564"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=403564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}