{"id":35847,"date":"2022-01-29T08:10:35","date_gmt":"2022-01-29T07:10:35","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=35847"},"modified":"2022-01-05T11:23:45","modified_gmt":"2022-01-05T10:23:45","slug":"algunas-pistas-para-comprender-el-cambio-sistemico","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/","title":{"rendered":"Algunas pistas para comprender el Cambio Sist\u00e9mico"},"content":{"rendered":"<h2>\u00bfQu\u00e9 se nos quiere decir con la expresi\u00f3n \u00abCambio Sist\u00e9mico\u00bb?<\/h2>\n<p>Cambio sist\u00e9mico significa una nueva forma de comprender y vivir la atenci\u00f3n al necesitado.<\/p>\n<p>Modificar, cambiar el sistema, (nuestro sistema de pensamiento, y el sistema social, si ello es posible) la manera de ver, comprender y apoyar a las personas en situaci\u00f3n de pobreza.<\/p>\n<p>Cambiar no es modernizarse. No es estar m\u00e1s de acuerdo con las nuevas formas de filosof\u00eda, sociolog\u00eda o con los medios t\u00e9cnicos o de comunicaci\u00f3n que se nos brindan hoy. Se trata de un cambio desde y hacia el Evangelio y la tradici\u00f3n Vicenciana.<\/p>\n<p>Reformar no es dar otra forma, una mera innovaci\u00f3n en el ajuar eclesi\u00e1stico, sino que es volver de nuevo al origen, RE\u2011FORMAR hacia el coraz\u00f3n del Evangelio. Reformar es reconfigurar \u00abel programa\u00bb volviendo al n\u00facleo inicial. Tampoco reformar es transformar: hasta ahora esto era una escuela y la hemos transformado en un asilo de ancianos. Eso no es re\u2011formar sino transformar. Reforma es una vuelta al origen, a lo genuino, a la forma original. REFORMAR ES UN AGRADECIMIENTO Y UN HOMENAJE A LA<em> TRADITIO<\/em>; A LO QUE SE NOS HA ENTREGADO.<\/p>\n<p>No querer reformar es no querer reconocer la dimensi\u00f3n humana: limitada, caduca y, en ocasiones, pecaminosa de la Iglesia y nuestra. Una reforma bien hecha requiere una buena hermen\u00e9utica (interpretaci\u00f3n). Los fundamentalismos son la negaci\u00f3n de toda interpretaci\u00f3n y reforma.<\/p>\n<p>El criterio es que el Evangelio del Se\u00f1or llegue a nuestras gentes. \u00bfCu\u00e1l es el centro del evangelio? La Vida, resurrecci\u00f3n, la esperanza, el amor, el servicio, la paz, etc. D\u00e9mosle forma y cauce a todo ello y si las formas actuales en las que vivimos la caridad no llevan el evangelio del Se\u00f1or: REFORMA.<\/p>\n<h2><strong>\u00bfD\u00f3nde se vive y realiza el cambio?<\/strong><\/h2>\n<ul>\n<li>El cambio hemos de realizarlo \u2011ante todo\u2011 cada uno de nosotros en nuestro interior, en nuestra mentalidad y, como consecuencia, en nuestra vida.<\/li>\n<li>Para que se produzca en nosotros tal cambio hemos de contrastar nuestra vida, nuestro estilo de vivir, con el Evangelio y el carisma de san Vicente.<\/li>\n<li>Posiblemente sintamos que la necesidad de este cambio surja desde una nueva forma de comprender a la persona necesitada. Nuestro concepto antropol\u00f3gico (de persona) como ser biol\u00f3gico, ps\u00edquico, social, espiritual. Esta forma de concebir a la persona implicar\u00e1 un modo concreto de vivir la acci\u00f3n solidaria, una nueva forma de ver al que est\u00e1 en situaci\u00f3n dif\u00edcil en la vida, a nuestro grupo o asociaci\u00f3n y la propia Familia Vicenciana.<\/li>\n<li>Desde ah\u00ed cambiaremos por convicci\u00f3n y por coherencia con esta nueva y renovada manera de vivir en fuego de la Caridad.<\/li>\n<\/ul>\n<h2><strong>Bases para el cambio<\/strong><\/h2>\n<p>El fundamento de nuestro cambio cristiano est\u00e1:<\/p>\n<ol>\n<li>En la Palabra, en el Evangelio, la persona de Jes\u00fas y su forma de actuar y vivir.<\/li>\n<li>En la vida de Vicente de Pa\u00fal, su forma de seguir los criterios de Jes\u00fas y, por tanto, su modo de servir al pobre.<\/li>\n<li>La sabidur\u00eda de nuestra Familia Vicenciana; Luisa de Marillac, Federico Ozanan, Catalina Labour\u00e9&#8230; y su experiencia en el servicio a los m\u00e1s pobres.<\/li>\n<\/ol>\n<h2><strong>Forma de trabajo<\/strong><\/h2>\n<ol>\n<li>Hemos de<em> dejarnos preguntar<\/em>, primero individualmente, por los criterios que dimanan de estas tres fuentes: Evangelio, praxis de San Vicente y sabidur\u00eda de nuestra Familia.<\/li>\n<li>Profundizar en la<em> reflexi\u00f3n y orar<\/em>.<\/li>\n<li>En un segundo momento, en grupo,<em> compartiremos<\/em> las inquietudes, iniciativas y retos para nuestra vida concreta iluminando nuestra acci\u00f3n.<\/li>\n<\/ol>\n<p>Todo ello nos llevar\u00e1 a un cambio en nuestra forma de concebir, entender y realizar la ayuda a los necesitados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 se nos quiere decir con la expresi\u00f3n \u00abCambio Sist\u00e9mico\u00bb? Cambio sist\u00e9mico significa una nueva forma de comprender y vivir la atenci\u00f3n al necesitado. Modificar, cambiar el sistema, (nuestro sistema de pensamiento, y el sistema &#8230; <a href=\"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":404048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[102],"tags":[172],"class_list":["post-35847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cambio-sistemico","tag-pobreza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Algunas pistas para comprender el Cambio Sist\u00e9mico - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Algunas pistas para comprender el Cambio Sist\u00e9mico - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 se nos quiere decir con la expresi\u00f3n \u00abCambio Sist\u00e9mico\u00bb? Cambio sist\u00e9mico significa una nueva forma de comprender y vivir la atenci\u00f3n al necesitado. Modificar, cambiar el sistema, (nuestro sistema de pensamiento, y el sistema ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T07:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612\" \/>\n\t<meta property=\"og:image:width\" content=\"2432\" \/>\n\t<meta property=\"og:image:height\" content=\"1612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Algunas pistas para comprender el Cambio Sist\u00e9mico\",\"datePublished\":\"2022-01-29T07:10:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/\"},\"wordCount\":631,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/36.jpg?fit=2432%2C1612\",\"keywords\":[\"Pobreza\"],\"articleSection\":[\"Cambio sist\u00e9mico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/\",\"name\":\"Algunas pistas para comprender el Cambio Sist\u00e9mico - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/36.jpg?fit=2432%2C1612\",\"datePublished\":\"2022-01-29T07:10:35+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/36.jpg?fit=2432%2C1612\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2013\\\/04\\\/36.jpg?fit=2432%2C1612\",\"width\":2432,\"height\":1612},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/algunas-pistas-para-comprender-el-cambio-sistemico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Algunas pistas para comprender el Cambio Sist\u00e9mico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Algunas pistas para comprender el Cambio Sist\u00e9mico - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/","og_locale":"es_ES","og_type":"article","og_title":"Algunas pistas para comprender el Cambio Sist\u00e9mico - Somos Vicencianos","og_description":"\u00bfQu\u00e9 se nos quiere decir con la expresi\u00f3n \u00abCambio Sist\u00e9mico\u00bb? Cambio sist\u00e9mico significa una nueva forma de comprender y vivir la atenci\u00f3n al necesitado. Modificar, cambiar el sistema, (nuestro sistema de pensamiento, y el sistema ... Read More","og_url":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2022-01-29T07:10:35+00:00","og_image":[{"width":2432,"height":1612,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Algunas pistas para comprender el Cambio Sist\u00e9mico","datePublished":"2022-01-29T07:10:35+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/"},"wordCount":631,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612","keywords":["Pobreza"],"articleSection":["Cambio sist\u00e9mico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/","url":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/","name":"Algunas pistas para comprender el Cambio Sist\u00e9mico - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612","datePublished":"2022-01-29T07:10:35+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612","width":2432,"height":1612},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/algunas-pistas-para-comprender-el-cambio-sistemico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Algunas pistas para comprender el Cambio Sist\u00e9mico"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/36.jpg?fit=2432%2C1612","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-9kb","jetpack-related-posts":[{"id":126467,"url":"http:\/\/vincentians.com\/es\/aic-contra-las-pobrezas-actuar-juntos-i\/","url_meta":{"origin":35847,"position":0},"title":"AIC, Contra las pobrezas: \u00a1Actuar juntos! El cambio sist\u00e9mico (I)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/01\/2024","format":false,"excerpt":"Introducci\u00f3n Un objetivo com\u00fan: AIC, Contra las pobrezas, Actuar juntos! La AIC es una asociaci\u00f3n din\u00e1mica, que es parte y est\u00e1 compuesta por m\u00faltiples sistemas, que interact\u00faan constantemente, para lograr un objetivo com\u00fan: \"Contra las pobrezas, Actuar juntos\" La situaci\u00f3n actual del mundo, en la que la pobreza aumenta de\u2026","rel":"","context":"En \u00abCambio sist\u00e9mico\u00bb","block_context":{"text":"Cambio sist\u00e9mico","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/cambio-sistemico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=1050%2C600 3x"},"classes":[]},{"id":127015,"url":"http:\/\/vincentians.com\/es\/vias-hacia-el-cambio-sistemico\/","url_meta":{"origin":35847,"position":1},"title":"V\u00edas hacia el cambio sist\u00e9mico","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/08\/2019","format":false,"excerpt":"El creciente movimiento global de la innovaci\u00f3n social, que puede ser descrito simplemente como \"nuevas ideas que resuelvan problemas sociales\", est\u00e1 evolucionando a un ritmo inesperado. Somos testigos de un aumento no s\u00f3lo en el n\u00famero de innovaciones sociales sino tambi\u00e9n los tipos de enfoque. Este libro ha sido inspirado\u2026","rel":"","context":"En \u00abCambio sist\u00e9mico\u00bb","block_context":{"text":"Cambio sist\u00e9mico","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/cambio-sistemico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/chatillon_sur_chalaronne.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/chatillon_sur_chalaronne.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/chatillon_sur_chalaronne.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/chatillon_sur_chalaronne.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/10\/chatillon_sur_chalaronne.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":140312,"url":"http:\/\/vincentians.com\/es\/espiritualidad-y-cambio-sistemico\/","url_meta":{"origin":35847,"position":2},"title":"Espiritualidad y cambio sist\u00e9mico","author":"Francisco Javier Fern\u00e1ndez Chento","date":"21\/02\/2015","format":false,"excerpt":"1.- M\u00e1s que una relaci\u00f3n, quisiera proponerles una breve meditaci\u00f3n... El objetivo de esta meditaci\u00f3n es redescubrir la dimensi\u00f3n espiritual contenida en la metodolog\u00eda del cambio sist\u00e9mico, que no es una estrategia de trabajo, sino una dimen\u00adsi\u00f3n espiritual, un acto de fe, que est\u00e1 en la base, si queremos vivirla\u2026","rel":"","context":"En \u00abCambio sist\u00e9mico\u00bb","block_context":{"text":"Cambio sist\u00e9mico","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/cambio-sistemico\/"},"img":{"alt_text":"manzanas_union","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/02\/manzanas_union-244x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":126471,"url":"http:\/\/vincentians.com\/es\/aic-contra-las-pobrezas-actuar-juntos-ii\/","url_meta":{"origin":35847,"position":3},"title":"AIC, Contra las pobrezas: \u00a1Actuar juntos! El cambio sist\u00e9mico (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/01\/2024","format":false,"excerpt":"2. Actuar Estrategias para un Cambio Sist\u00e9mico Los miembros de la Comisi\u00f3n para el Cambio Sist\u00e9mico iniciaron el proceso de estudio y profundizaci\u00f3n partiendo de historias vividas o conocidas de cerca por cada uno de los miembros de la Comisi\u00f3n. El an\u00e1lisis de dichas historias nos llev\u00f3 a detectar aquellos\u2026","rel":"","context":"En \u00abCambio sist\u00e9mico\u00bb","block_context":{"text":"Cambio sist\u00e9mico","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/cambio-sistemico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=1050%2C600 3x"},"classes":[]},{"id":48436,"url":"http:\/\/vincentians.com\/es\/el-joven-vicenciano-ante-el-cambio-sistemico\/","url_meta":{"origin":35847,"position":4},"title":"El joven vicenciano ante el cambio sist\u00e9mico","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/03\/2015","format":false,"excerpt":"Analizamos nuestra realidad Esta catequesis tiene como objetivo ayudar a los j\u00f3venes vicencianos a reflexionar sobre los principios del cambio sist\u00e9mico practicados por San Vicente y reflejarlos en nuestro propio servicio, en nuestros propios proyectos. El Cambio Sist\u00e9mico para la Familia Vicenciana es un proceso que intenta transformar de manera\u2026","rel":"","context":"En \u00abCambio sist\u00e9mico\u00bb","block_context":{"text":"Cambio sist\u00e9mico","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/cambio-sistemico\/"},"img":{"alt_text":"cambio","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/11\/cambio-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":126473,"url":"http:\/\/vincentians.com\/es\/aic-contra-las-pobrezas-actuar-juntos-iii\/","url_meta":{"origin":35847,"position":5},"title":"AIC, Contra las pobrezas: \u00a1Actuar juntos! El cambio sist\u00e9mico (III)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/01\/2024","format":false,"excerpt":"III. Proyectos \" sist\u00e9micos \" a. A nivel individual: Mar\u00eda Es imprescindible tener en cuenta a la persona humana y respetar sus necesidades, sus aspiraciones y sus valores. Un profundo respeto y el deseo de buscar la promoci\u00f3n y el empoderamiento de las mujeres, llevaron a las participantes en la\u2026","rel":"","context":"En \u00abCambio sist\u00e9mico\u00bb","block_context":{"text":"Cambio sist\u00e9mico","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/cambio-sistemico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aa.jpeg?fit=1152%2C648&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=35847"}],"version-history":[{"count":2,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35847\/revisions"}],"predecessor-version":[{"id":404050,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35847\/revisions\/404050"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/404048"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=35847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=35847"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=35847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}