{"id":35039,"date":"2011-07-10T02:35:13","date_gmt":"2011-07-10T00:35:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/07\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/"},"modified":"2011-07-10T02:35:13","modified_gmt":"2011-07-10T00:35:13","slug":"introduccion-a-la-vida-devota-cuarta-parte-capitulo-13","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13"},"content":{"rendered":"<div id=\"attachment_32887\" style=\"width: 215px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32887\" class=\"size-medium wp-image-32887\" title=\"San Francisco de Sales\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales-205x300.jpg?resize=205%2C300\" alt=\"San Francisco de Sales\" width=\"205\" height=\"300\" \/><\/a><p id=\"caption-attachment-32887\" class=\"wp-caption-text\">San Francisco de Sales<\/p><\/div>\n<p><strong>CAP\u00cdTULO XIII<\/strong><\/p>\n<p><strong>DE LOS CONSUELOS ESPIRITUALES Y SENSIBLES Y C\u00d3MO HAY QUE CONDUCIRSE EN ELLOS<\/strong><\/p>\n<p>Dios conserva este gran mundo en una perpetua mudanza, por la cual el d\u00eda se cambia en noche, la primavera en verano, el verano en oto\u00f1o, el oto\u00f1o en invierno y el invierno en primavera, y nunca un d\u00eda es igual al anterior, pues los hay nublados, lluviosos, secos, ventosos, variedad que llena de hermosura el universo. Lo mismo puede decirse del hombre, el cual, seg\u00fan el dicho de los antiguos, es un compendio del mundo; porque nunca se halla en el mismo estado, y su vida se desliza sobre la tierra como las aguas, flotando y movi\u00e9ndose con perpetua variedad de movimientos, que ora lo elevan hacia la esperanza, ora lo hunden en el temor, ora lo inclinan hacia la derecha por el consuelo, ora hacia la izquierda por la aflicci\u00f3n, y jam\u00e1s uno solo de sus d\u00edas, ni siquiera una sola de sus horas, es igual a la que pas\u00f3.<\/p>\n<p>He aqu\u00ed una importante advertencia: hemos de procurar conservar una continua e inalterable igualdad de coraz\u00f3n, en medio de una desigualdad tan grande de acontecimientos, y, aunque todas las cosas den vueltas y cambien continuamente en torno nuestro, nosotros hemos de permanecer constantemente inm\u00f3viles, mirando, caminando y aspirando hacia nuestro Dios. Que la nave tome este o aquel rumbo, que navegue hacia levante o hacia poniente, hacia el septentri\u00f3n o hacia el mediod\u00eda, sea cual fuere el viento que la mueva, siempre su br\u00fajula mirar\u00e1 hacia su estrella favorita y hacia el polo. Que todo ande revuelto, no ya tan s\u00f3lo en torno nuestro, sino aun dentro de nosotros mismos, es decir, que nuestra alma est\u00e9 triste, alegre, en suavidad, en amargura, en luz y en tinieblas, en tentaci\u00f3n, en reposo, en placer, en displicencia, en sequedad, en ternura; que el sol la abrase o el roc\u00edo la refresque&#8230;. es menester que siempre y constantemente la punta de nuestro coraz\u00f3n, nuestro esp\u00edritu, nuestra voluntad superior, que es nuestra br\u00fajula, mire incesantemente y aspire perpetuamente al amor de Dios, a su Creador, a su Salvador, a su \u00fanico y soberano bien. \u00abYa vivamos, ya muramos, dice el Ap\u00f3stol, si permanecemos en Dios&#8230; \u00bfQui\u00e9n nos separar\u00e1 del amor y caridad de Dios?\u00bb No, jam\u00e1s cosa alguna nos separar\u00e1 de este amor: ni la tribulaci\u00f3n, ni la angustia, ni la muerte, ni la vida, ni el dolor presente, ni el temor de los accidentes futuros, ni los artificios del maligno esp\u00edritu, ni la elevaci\u00f3n de las consolaciones, ni el abismo de las aflicciones, ni la ternura, ni la sequedad, han de separarnos jam\u00e1s de esta santa caridad, que est\u00e1 fundada en Jesucristo.<\/p>\n<p>Esta resoluci\u00f3n tan absoluta de jam\u00e1s abandonar a Dios ni dejar su dulce amor, sirve de contrapeso a nuestras almas para mantenerlas en una santa igualdad, en medio de la desigual diversidad de movimientos que la condici\u00f3n de esta vida le acarrea. Porque, as\u00ed como las abejas, al sentirse sorprendidas por el viento en medio del campo, se cogen de las piedras para poderse balancear en el aire y no ser tan f\u00e1cilmente arrastradas a merced de la tempestad, de la misma manera nuestra alma, despu\u00e9s de haber abrazado con su resoluci\u00f3n el precioso amor de Dios, permanece constante en medio de la inconstancia y de las vicisitudes de los consuelos y aflicciones espirituales y temporales, exteriores e interiores.<\/p>\n<p>Mas, aparte de esta doctrina general, necesitamos algunos principios particulares, exteriores e interiores.<\/p>\n<p>1. Afirmo, pues, que la devoci\u00f3n no consiste en la dulzura, suavidad, consolaci\u00f3n y ternura sensible al coraz\u00f3n, que provoca en nosotros l\u00e1grimas y suspiros y nos causa una cierta satisfacci\u00f3n, agradable y sabrosa, en algunos ejercicios espirituales. No, Filotea, la devoci\u00f3n y esto no son, en manera alguna, una misma cosa, porque hay muchas almas que gozan de estas ternuras y consolaciones, y, a pesar de ello, no dejan de ser muy viciosas, y, por consiguiente, no tienen un verdadero amor de Dios ni, mucho menos, una verdadera devoci\u00f3n. Cuando Sa\u00fal persegu\u00eda a muerte a David, que hu\u00eda delante de \u00e9l hacia los desiertos de Engaddi, entr\u00f3 solo en una caverna, donde David se hab\u00eda ocultado, hubiera podido mil veces darle muerte, le perdon\u00f3 la vida, y, no s\u00f3lo no quiso infundirle temor, sino que, despu\u00e9s de haberle dejado salir libremente, le llam\u00f3 para probarle su inocencia y hacerle saber que lo hab\u00eda tenido a su arbitrio. Ahora bien, por este motivo, \u00bfqu\u00e9 cosas no hizo Sa\u00fal, para demostrar que su coraz\u00f3n se hab\u00eda ablandado con respecto a David? Llam\u00f3le hijo suyo, se ech\u00f3 a llorar en voz alta, comenz\u00f3 a alabarle, a reconocer su bondad, a rogar- a Dios por \u00e9l, a presagiar su grandeza, a encomendarle su posteridad para despu\u00e9s de su muerte. \u00bfQu\u00e9 mayor dulzura y ternura de coraz\u00f3n pod\u00eda manifestarle? Y no obstante, a pesar de esto, su alma no hab\u00eda cambiado y continu\u00f3 persiguiendo a David tan cruelmente como antes.<\/p>\n<p>Tambi\u00e9n se encuentran personas que, al considerar la bondad de Dios y la Pasi\u00f3n del Salvador, sienten gran ternura en su coraz\u00f3n, que les hace prorrumpir en suspiros, l\u00e1grimas, oraciones y acciones de gracias muy sensibles, de tal manera que podr\u00eda decirse que son presa de una gran devoci\u00f3n. Mas, cuando se llega a la pr\u00e1ctica, aparece que, como la lluvia pasajera de un verano caluroso, que, al caer a grandes chorros sobre la tierra, no la penetra y s\u00f3lo sirve para provocar la salida de las setas, de la misma manera estas l\u00e1grimas y estas ternuras, al caer sobre un coraz\u00f3n vicioso, no lo penetran, y son para \u00e9l completamente in\u00fatiles, porque, a pesar de ello, estos infelices no se desprenden ni de un c\u00e9ntimo de los bienes mal adquiridos, ni renuncian a uno solo de sus perversos afectos, ni quieren aceptar la menos incomodidad del mundo en el servicio de aquel Se\u00f1or sobre el cual tanto han llorado; de suerte que los buenos movimientos que han sentido no son otra cosa que ciertos hongos espirituales, que, no s\u00f3lo no constituyen la verdadera devoci\u00f3n, sino que, con frecuencia, son grandes artima\u00f1as del enemigo, el cual, mientras entretiene a las almas con estas peque\u00f1as consolaciones, hace que queden contentas y satisfechas con esto y que no busquen la verdadera y s\u00f3lida devoci\u00f3n, la cual consiste en una voluntad constante, resuelta, pronta y activa en ejecutar lo que es agradable a Dios.<\/p>\n<p>Un ni\u00f1o llorar\u00e1 amargamente si ve que sangran a su madre con una lanceta; pero si, al mismo tiempo, su madre le pide una manzana o un paquete de confites que tiene en la mano, no querr\u00e1, en manera alguna, soltarlo. Tales son, en su mayor parte, nuestras tiernas devociones: cuando vemos la lanzada que traspasa el coraz\u00f3n de Jesucristo crucificado, lloramos de ternura, \u00a1Ah! Filotea, est\u00e1 bien llorar la pasi\u00f3n dolorosa y la muerte de nuestro Padre y Redentor; mas, \u00bfpor qu\u00e9 no le damos de buen grado la manzana que tenemos en nuestras manos, y que \u00c9l nos pide constantemente, a saber, nuestro coraz\u00f3n, la \u00fanica manzana de amor que este Salvador desea de nosotros? \u00bfPor qu\u00e9, no le ofrecemos tantos peque\u00f1os afectos, goces, complacencias, que \u00c9l quiere arrebatarnos de las manos y no puede, porque son nuestras golosinas y las preferimos a la gracia celestial? \u00a1Ah! son amistades de ni\u00f1os peque\u00f1os, tiernas, s\u00ed, pero d\u00e9biles, ilusorias, y sin efecto. La devoci\u00f3n no consiste en estas ternezas y afectos sensibles, que unas veces proceden del propio natural que es tambi\u00e9n blando y susceptible de la impresi\u00f3n que se le quiera dar, y otras veces del enemigo, que, para distraernos con esto, excita nuestra imaginaci\u00f3n con ideas que producen estos efectos.<\/p>\n<p>2. Estas ternezas y afectuosas dulzuras son, empero, a veces, muy buenas y muy \u00fatiles, porque abren el apetito del alma, confortan el esp\u00edritu, y juntan a la prontitud de la devoci\u00f3n una santa alegr\u00eda, la cual hace que nuestros actos, aun exteriormente, sean bellos y simp\u00e1ticos. Es el gusto que se siente por las cosas divinas, el cual hacia exclamar a David: \u00ab\u00a1Oh, Se\u00f1or, qu\u00e9 dulces son a mi paladar tus palabras; m\u00e1s dulces que la miel en mi boca! \u00bb Y, ciertamente, el m\u00e1s insignificante consuelo de la devoci\u00f3n que sentimos vale m\u00e1s, bajo todos los conceptos, que las m\u00e1s excelentes virtudes del mundo. La leche que chupan los ni\u00f1os, es decir, las mercedes del divino Esposo, sabe mejor al alma que el vino sabroso de los placeres de la tierra; el que las ha gustado tiene todas las dem\u00e1s cosas de la tierra por hiel y ajenjo. Y as\u00ed como los que tienen regaliz en la boca reciben de ella una dulzura tan grande, que no sienten ni hambre ni sed, as\u00ed tambi\u00e9n aquellos a quienes Dios ha dado este man\u00e1 celestial de las suavidades y de las consolaciones exteriores, no pueden desear ni recibir los consuelos del mundo, a lo menos para entretenerse y complacerse en ellos. Estas suavidades son un peque\u00f1o anticipo de las suavidades inmortales, que Dios da a las almas que le buscan; son los confites que da a sus hijitos para atra\u00e9rselos; son aguas cordiales que les ofrece para confortarlos; y son tambi\u00e9n como ciertas arras de las recompensas eternas. Se dice que Alejandro Magno, navegando en alta mar, descubri\u00f3 antes que nadie la Arabia Feliz, por la suavidad de los aromas que el viento le llevaba, con lo que se animaron \u00e9l y sus compa\u00f1eros. De la misma manera nosotros recibimos, con frecuencia, en este mar de la vida mortal, dulzuras y suavidades que, sin duda, nos hacen presentir las delicias de la patria celestial, a la cual tendemos y aspiramos.<\/p>\n<p>3. Pero me dir\u00e1s: puesto que hay consuelos sensibles que son buenos y vienen de Dios, y tambi\u00e9n los hay in\u00fatiles, peligrosos y aun perniciosos, que provienen de la naturaleza o del enemigo, \u00bfc\u00f3mo podr\u00e9 discernir los unos de los otros y conocer los malos y los in\u00fatiles entre los que son buenos? Es doctrina general, amada Filotea, que, en cuanto a los afectos y pasiones, los hemos de conocer por los frutos. Nuestros corazones son los \u00e1rboles; los afectos y las pasiones son sus ramas, y sus obras y acciones son sus frutos. Es bueno el coraz\u00f3n que tiene buenos afectos, y son los afectos y las pasiones los que producen en nosotros buenas obras y santas acciones. Si las dulzuras, ternezas y consolaciones nos hacen m\u00e1s humildes, pacientes, tratables, caritativos y compasivos con el pr\u00f3jimo, m\u00e1s fervorosos en mortificar nuestras concupiscencias y nuestras inclinaciones, m\u00e1s constantes en nuestros ejercicios, m\u00e1s d\u00f3ciles y flexibles con respecto a aquellos a quienes debemos obedecer, m\u00e1s sencillos en nuestra manera de vivir, es indudable, Filotea, que son de Dios; mas, si estas dulzuras s\u00f3lo son dulces para nosotros, y nos hacen curiosos, \u00e1speros, puntillosos, impacientes, tercos, orgullosos, presuntuosos, duros para con el pr\u00f3jimo, y por creer que ya somos santos no queremos sujetarnos m\u00e1s a la direcci\u00f3n y a la correcci\u00f3n, es seguro que estos consuelos son falsos y perniciosos. \u00abEl buen \u00e1rbol solamente produce buenos frutos\u00bb.<\/p>\n<p>4. Cuando sintamos estas dulzuras y estos consuelos: a) Humill\u00e9monos mucho delante de Dios, y guard\u00e9monos bien de decir a causa de estas suavidades: \u00ab\u00a1Ah, qu\u00e9 bueno soy! \u00bb No, Filotea, estos bienes no nos hacen mejores, porque, como he dicho, la devoci\u00f3n no consiste en esto. Digamos m\u00e1s bien: \u00ab\u00a1Oh! \u00a1qu\u00e9 bueno es Dios para los que esperan en \u00c9l, para el alma que le busca! \u00bb El que tiene az\u00facar en la boca no puede decir que su boca es dulce, sino que es dulce el az\u00facar. De la misma manera, aunque esta dulzura espiritual es muy buena, y muy bueno el Dios que nos la da, no se sigue de aqu\u00ed que sea bueno el que la recibe. b) Reconozcamos que todav\u00eda somos ni\u00f1os peque\u00f1os, que necesitamos a\u00fan del pecho, y que estos confites se nos dan porque tenemos el esp\u00edritu tierno y delicado, el cual necesita cebos y golosinas para ser atra\u00eddo al amor de Dios. c) Mas, despu\u00e9s de esto, hablando en general y de ordinario, recibamos humildemente estas gracias y favores, y teng\u00e1moslos por muy grandes, no por lo que son en s\u00ed, sino porque es la mano de Dios la que los pone en nuestro coraz\u00f3n, como le ocurrir\u00eda a una madre, que para acariciar a su hijo, le pusiere ella misma los confites en la boca uno tras otro, pues, si el hijo fuese capaz de entenderlo, apreciar\u00eda m\u00e1s la dulzura de los halagos y de las caricias de su madre, que la dulzura de las mismas golosinas. As\u00ed tambi\u00e9n, Filotea, mucho es sentir estas dulzuras, pero la dulzura de las dulzuras est\u00e1 en considerar que Dios, con su mano amorosa y maternal, nos las pone en la boca, en el coraz\u00f3n, en el alma y en el esp\u00edritu. d) Una vez las hayamos recibido con humildad, emple\u00e9moslas con mucho cuidado, seg\u00fan las intenciones de Aquel que nos las da. \u00bfCon qu\u00e9 fin creemos que Dios nos da estas dulzuras? Para hacernos suaves con todos y amorosos con \u00c9l. La madre da el confite a su hijo para que la bese; besemos, pues, a este Salvador, que nos da tantas dulzuras. Ahora bien, besar al Salvador, es obedecerle, guardar sus mandamientos, hacer su voluntad, cumplir sus deseos: en una palabra, abrazarle tiernamente con obediencia y fidelidad. Por lo tanto, cuando recibimos alguna consolaci\u00f3n espiritual, es menester que, aquel d\u00eda, seamos m\u00e1s diligentes en el bien obrar, y que nos humillemos. e) Adem\u00e1s de eso, es necesario que, de vez en cuando, renunciemos a estas dulzuras, ternezas y consolaciones, que despeguemos nuestro coraz\u00f3n de ellas y que hagamos protestas de que, si bien las aceptamos humildemente y las amamos, porque Dios nos las env\u00eda y nos mueven a su amor, no son, empero, ellas lo que buscamos, sino Dios y su santo amor; no la consolaci\u00f3n, sino el Consolador; no la dulzura, sino el dulce Salvador; no la ternura, sino la suavidad del cielo y de la tierra, y, con estos afectos, nos hemos de disponer a perseverar firmes en el santo amor de Dios, aunque, durante toda nuestra vida, jam\u00e1s hubi\u00e9semos de sentir ning\u00fan consuelo, dici\u00e9ndole lo mismo en el monte Calvario y en el Tabor: \u00ab\u00a1Oh Se\u00f1or!, bueno es permanecer aqu\u00ed \u00ab, ya estemos en la cruz, ya en la gloria. f) Finalmente, te advierto que si recibes en notable abundancia estas consolaciones, ternuras, l\u00e1grimas y dulzuras, o te acontece en ellas alguna cosa extraordinaria, hables de ello sinceramente con tu director, para aprender la manera de moderarte y conducirte, pues est\u00e1 escrito: \u00ab\u00bfHas hallado la miel? Pues come la que es suficiente\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO XIII DE LOS CONSUELOS ESPIRITUALES Y SENSIBLES Y C\u00d3MO HAY QUE CONDUCIRSE EN ELLOS Dios conserva este gran mundo en una perpetua mudanza, por la cual el d\u00eda se cambia en noche, la primavera &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-35039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO XIII DE LOS CONSUELOS ESPIRITUALES Y SENSIBLES Y C\u00d3MO HAY QUE CONDUCIRSE EN ELLOS Dios conserva este gran mundo en una perpetua mudanza, por la cual el d\u00eda se cambia en noche, la primavera ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-10T00:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13\",\"datePublished\":\"2011-07-10T00:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/\"},\"wordCount\":2617,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2011-07-10T00:35:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13 - Somos Vicencianos","og_description":"CAP\u00cdTULO XIII DE LOS CONSUELOS ESPIRITUALES Y SENSIBLES Y C\u00d3MO HAY QUE CONDUCIRSE EN ELLOS Dios conserva este gran mundo en una perpetua mudanza, por la cual el d\u00eda se cambia en noche, la primavera ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2011-07-10T00:35:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13","datePublished":"2011-07-10T00:35:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/"},"wordCount":2617,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/","name":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2011-07-10T00:35:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 13"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-979","jetpack-related-posts":[{"id":120169,"url":"http:\/\/vincentians.com\/es\/la-primacia-de-la-caridad-en-el-carisma-vicenciano\/","url_meta":{"origin":35039,"position":0},"title":"La primac\u00eda de la caridad en el carisma vicenciano","author":"Francisco Javier Fern\u00e1ndez Chento","date":"20\/06\/2015","format":false,"excerpt":"Salir del peque\u00f1o mundo en el que vivimos e intentar vernos a trav\u00e9s de los ojos de los dem\u00e1s, es un ejercicio muy \u00fatil y un modo de practicar la humildad. El planeta tierra no es sino un peque\u00f1o lunar en el universo. Su inter\u00e9s para nosotros estriba en el\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"vicente","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/vicente-300x203.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":128643,"url":"http:\/\/vincentians.com\/es\/federico-ozanam-por-mons-baunard-capitulo-25\/","url_meta":{"origin":35039,"position":1},"title":"Federico Ozanam (por Mons. Baunard): Cap\u00edtulo 25","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/09\/2016","format":false,"excerpt":"Cap\u00edtulo XXV: Breta\u00f1a. Inglaterra. La obra de publicaci\u00f3n Breta\u00f1a.\u2014La obra de publicaci\u00f3n.\u2014Las f ioretti de San Francisco.\u2014El siglo V.\u2014Sceaux.\u2014Londres y Dieppe. 1850-1851 El fr\u00e1gil organismo de Ozanam no se hab\u00eda restablecido por completo de su crisis de 1846. El trabajo, la lucha, las heridas aca\u00adban de consumar su ruina. Los\u2026","rel":"","context":"En \u00abFederico Ozanam\u00bb","block_context":{"text":"Federico Ozanam","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/federico-ozanam\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/frederic-ozanam-layman-for-now.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/frederic-ozanam-layman-for-now.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/frederic-ozanam-layman-for-now.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/frederic-ozanam-layman-for-now.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/frederic-ozanam-layman-for-now.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":114953,"url":"http:\/\/vincentians.com\/es\/como-rezar-el-rosario\/","url_meta":{"origin":35039,"position":2},"title":"C\u00f3mo rezar el Rosario","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/02\/2019","format":false,"excerpt":"Modo de rezarlo Hacer el signo de la cruz y rezar el s\u00edmbolo de los ap\u00f3stoles o el acto de contrici\u00f3n. Rezar el Padrenuestro. Rezar 3 Avemar\u00edas y Gloria. Anunciar el primer misterio. Rezar el Padrenuestro. Rezar 10 Avemar\u00edas, Gloria y Jaculatoria. Anunciar el segundo misterio. Rezar el Padrenuestro. Rezar\u2026","rel":"","context":"En \u00abOraci\u00f3n\u00bb","block_context":{"text":"Oraci\u00f3n","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/oracion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35069,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-quinta-parte-capitulo-14\/","url_meta":{"origin":35039,"position":3},"title":"Introducci\u00f3n a la vida devota. Quinta parte, cap\u00edtulo 14","author":"Francisco Javier Fern\u00e1ndez Chento","date":"26\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO XIV QUINTA CONSIDERACI\u00d3N: DEL AMOR ETERNO DE DIOS A NOSOTROS Considera el amor eterno que Dios te ha tenido; porque ya antes de que Nuestro Se\u00f1or Jesucristo, en cuanto hombre, sufriese en la cruz por ti, su divina Majestad te conceb\u00eda en su soberana bondad, y te amaba en\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":54305,"url":"http:\/\/vincentians.com\/es\/las-sagradas-escrituras-nos-manifiestan-los-misterios-de-dios-san-hipolito\/","url_meta":{"origin":35039,"position":4},"title":"Las Sagradas Escrituras nos manifiestan los misterios de Dios (San Hip\u00f3lito)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/06\/2019","format":false,"excerpt":"Las Sagradas Escrituras nos manifiestan los misterios de Dios Del Tratado de San Hip\u00f3lito, presb\u00edtero, Contra la herej\u00eda de Noeto. Lectura b\u00edblica: Jn 1, 1-18 San Hip\u00f3lito (\u00bf-235) Desconocemos lugar y fecha de su nacimiento, aunque sabemos que fue disc\u00edpulo de San Ireneo y compuso sus escritos entre los a\u00f1os\u2026","rel":"","context":"En \u00abPadres de la Iglesia\u00bb","block_context":{"text":"Padres de la Iglesia","link":"http:\/\/vincentians.com\/es\/category\/formacion-cristiana\/padres-de-la-iglesia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34985,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-37\/","url_meta":{"origin":35039,"position":5},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 37","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/04\/2021","format":false,"excerpt":"CAP\u00cdTULO XXXVII LOS DESEOS Todos saben que se han de guardar de los deseos de cosas viciosas, porque el deseo del mal nos hace malos. Pero digo ir\u00e1s, Filotea: no desees en manera alguna las cosas peligrosas para el alma, como los bailes, los juegos y ciertos pasatiempos; ni los\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=35039"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=35039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=35039"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=35039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}