{"id":35038,"date":"2011-07-09T02:35:13","date_gmt":"2011-07-09T00:35:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/07\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/"},"modified":"2011-07-09T02:35:13","modified_gmt":"2011-07-09T00:35:13","slug":"introduccion-a-la-vida-devota-cuarta-parte-capitulo-12","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12"},"content":{"rendered":"<div id=\"attachment_32887\" style=\"width: 215px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32887\" class=\"size-medium wp-image-32887\" title=\"San Francisco de Sales\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales-205x300.jpg?resize=205%2C300\" alt=\"San Francisco de Sales\" width=\"205\" height=\"300\" \/><\/a><p id=\"caption-attachment-32887\" class=\"wp-caption-text\">San Francisco de Sales<\/p><\/div>\n<p><strong>CAP\u00cdTULO XII<\/strong><\/p>\n<p><strong>DE LA TRISTEZA<\/strong><\/p>\n<p>Dice San Pablo: \u00abLa tristeza que es seg\u00fan Dios, obra la penitencia para la salvaci\u00f3n; la tristeza del mundo obra la muerte\u00bb. Luego, la tristeza puede ser buena o mala, seg\u00fan sean los diversos frutos que causa en nosotros. Es cierto que son m\u00e1s los frutos malos que los buenos, porque los buenos s\u00f3lo son dos: misericordia y penitencia, y los malos, en cambio, son seis: angustia, pereza, indignaci\u00f3n, celos, envidia e impaciencia; lo cual hace decir al Sabio: \u00abLa tristeza es la muerte de muchos y, en ella, no hay provecho alguno\u00bb, porque, por dos buenos riachuelos que manan de la fuente de la tristeza, hay seis que son muy malos.<\/p>\n<p>El enemigo se vale de la tristeza para ocasionar tentaciones a los buenos; porque, as\u00ed como procura que los malos se alegren en sus pecados, as\u00ed tambi\u00e9n procura que los buenos se entristezcan en sus buenas obras; y as\u00ed como no puede inducir al mal si no es haci\u00e9ndolo agradable, de la misma manera no puede apartar del bien si no es haci\u00e9ndolo desagradable. El maligno se complace en la tristeza y en la melancol\u00eda, porque \u00e9l est\u00e1 triste y melanc\u00f3lico, y lo estar\u00e1 eternamente; por lo que quiere que todos est\u00e9n como \u00e9l.<\/p>\n<p>La tristeza mala perturba el alma, la inquieta, infunde temores excesivos, hace perder el gusto por la oraci\u00f3n, adormece y agota el cerebro, priva al alma del consejo, de la resoluci\u00f3n, del juicio, del valor, y abate las fuerzas; en una palabra, es como un invierno crudo que priva a la tierra de toda su belleza y acobarda a los animales, porque quita toda suavidad al alma y la paraliza y hace impotente en todas facultades.<\/p>\n<p>Filotea, si alguna vez te acontece que te sientes atacada de esta tristeza, practica los siguientes remedios: \u00abSi alguno est\u00e1 triste -dice Santiago-, que ore\u00bb: la oraci\u00f3n es el m\u00e1s excelente remedio, porque eleva el esp\u00edritu a Dios, que es nuestro \u00fanico gozo y consuelo. Mas, al orar, hemos de excitar afectos y pronunciar palabras, ya interiores ya exteriores, que muevan a la confianza y al amor de Dios, como: \u00ab\u00a1Oh Dios de misericordia! \u00a1Dios m\u00edo bondados\u00edsimol \u00a1Salvador de bondad! \u00a1Dios de mi coraz\u00f3n! \u00a1Mi gozo, mi esperanza, mi amado esposo, bienamado de mi alma!\u00bb y otras semejantes.<\/p>\n<p>Esfu\u00e9rzate en contrariar vivamente las inclinaciones de la tristeza, y, aunque te parezca que en este estado, todo lo haces con frialdad, pena y cansancio, no dejes, empero, de hacerlo; porque el enemigo, que pretende hacernos aflojar en nuestras buenas obras mediante la tristeza, al ver que, a pesar de ella, no dejamos de hacerlas, y que, haci\u00e9ndolas con resistencia, tienen m\u00e1s valor, cesa entonces de afligirnos.<\/p>\n<p>Canta himnos espirituales, porque el maligno ha desistido, a veces, de sus ataques, merced a este medio, como lo atestigua el esp\u00edritu que asaltaba o se apoderaba de Sa\u00fal, cuya vehemencia ced\u00eda ante la salmodia.<\/p>\n<p>Es muy buena cosa ocuparse en obras exteriores, y variarlas cuanto sea posible, para distraer el alma del objeto triste, purificar y enfervorizar el coraz\u00f3n, pues la tristeza es una pasi\u00f3n de suyo fr\u00eda y \u00e1rida.<\/p>\n<p>Haz actos exteriores de fervor, aunque sea sin gusto, como abrazar el crucifijo, estrecharlo contra el pecho, besarle las manos y los pies, levantar los ojos al cielo, elevar la voz hac\u00eda Dios con palabras de amor y de confianza, como \u00e9sta: \u00abMi amado para m\u00ed y yo para \u00c9l. Corno manojito de mirra es mi Amado para m\u00ed. \u00c9l reposar\u00e1 sobre mi pecho. Mis ojos se derriten por Ti, \u00a1oh Dios m\u00edo!, diciendo: \u00bfCu\u00e1ndo me consolar\u00e1s? \u00a1Oh Jes\u00fas!, seas para m\u00ed Jes\u00fas; viva Jes\u00fas, y vivir\u00e1 mi alma. \u00bfQui\u00e9n me separar\u00e1 del amor de mi Dios?\u00bb, y otras semejantes.<\/p>\n<p>La disciplina moderada es buen remedio contra la tristeza, porque esta voluntaria aflicci\u00f3n exterior impetra el consuelo interior, y el alma al sentir los dolores de fuera, se distrae de los de dentro. La frecuencia de la Sagrada Comuni\u00f3n es excelente, porque este pan celestial robustece el coraz\u00f3n y regocija el esp\u00edritu.<\/p>\n<p>Descubre todos los sentimientos, afectos y sugestiones que nacen de la tristeza a tu director y a tu confesor, con humildad y fidelidad; busca el trato de personas espirituales, y conversa con ellas, cuanto puedas, durante este tiempo. Y, principalmente, res\u00edgnate en las manos de Dios, disponi\u00e9ndote a padecer esta enojosa tristeza con paciencia, como un justo castigo a tus vanas alegr\u00edas, y no dudes de que Dios, despu\u00e9s de haberte probado, te librar\u00e1 de este mal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO XII DE LA TRISTEZA Dice San Pablo: \u00abLa tristeza que es seg\u00fan Dios, obra la penitencia para la salvaci\u00f3n; la tristeza del mundo obra la muerte\u00bb. Luego, la tristeza puede ser buena o mala, &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-35038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO XII DE LA TRISTEZA Dice San Pablo: \u00abLa tristeza que es seg\u00fan Dios, obra la penitencia para la salvaci\u00f3n; la tristeza del mundo obra la muerte\u00bb. Luego, la tristeza puede ser buena o mala, ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-09T00:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12\",\"datePublished\":\"2011-07-09T00:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/\"},\"wordCount\":820,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2011-07-09T00:35:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12 - Somos Vicencianos","og_description":"CAP\u00cdTULO XII DE LA TRISTEZA Dice San Pablo: \u00abLa tristeza que es seg\u00fan Dios, obra la penitencia para la salvaci\u00f3n; la tristeza del mundo obra la muerte\u00bb. Luego, la tristeza puede ser buena o mala, ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2011-07-09T00:35:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12","datePublished":"2011-07-09T00:35:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/"},"wordCount":820,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/","name":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2011-07-09T00:35:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 12"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-978","jetpack-related-posts":[{"id":35037,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-11\/","url_meta":{"origin":35038,"position":0},"title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 11","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO XI DE LA INQUIETUD La inquietud no es una simple tentaci\u00f3n, sino una fuente de la cual y por la cual vienen muchas tentaciones: diremos, pues, algo acerca de ella. La tristeza no es otra cosa que el dolor del esp\u00edritu a causa del mal que se encuentra en\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":114953,"url":"http:\/\/vincentians.com\/es\/como-rezar-el-rosario\/","url_meta":{"origin":35038,"position":1},"title":"C\u00f3mo rezar el Rosario","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/02\/2019","format":false,"excerpt":"Modo de rezarlo Hacer el signo de la cruz y rezar el s\u00edmbolo de los ap\u00f3stoles o el acto de contrici\u00f3n. Rezar el Padrenuestro. Rezar 3 Avemar\u00edas y Gloria. Anunciar el primer misterio. Rezar el Padrenuestro. Rezar 10 Avemar\u00edas, Gloria y Jaculatoria. Anunciar el segundo misterio. Rezar el Padrenuestro. Rezar\u2026","rel":"","context":"En \u00abOraci\u00f3n\u00bb","block_context":{"text":"Oraci\u00f3n","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/oracion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/ojos-jesucristo.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34971,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-25\/","url_meta":{"origin":35038,"position":2},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 25","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/06\/2011","format":false,"excerpt":"CAPITULO XXV DE LA DECENCIA EN LOS VESTIDOS Quiere San Pablo que las mujeres devotas (lo mismo se diga de los hombres) vistan con decoro y se adornen con decencia y sobriedad. Ahora bien, la decencia en el vestir y en el ornato depende de la materia de la forma\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35029,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-04\/","url_meta":{"origin":35038,"position":3},"title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 04","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO IV EL SENTIR Y EL CONSENTIR DOS BELLOS EJEMPLOS ACERCA DE ESTE PUNTO Es tan importante entender esto, que no tengo inconveniente en insistir en ello para explicarlo mejor. El joven de quien nos habla San Jer\u00f3nimo, que, tendido y atado con cintas de seda y con toda delicadeza\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34211,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-primera-parte-capitulo-24\/","url_meta":{"origin":35038,"position":4},"title":"Introducci\u00f3n a la vida devota. Primera parte, cap\u00edtulo 24","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/07\/2020","format":false,"excerpt":"CAP\u00cdTULO XXIV QUE HEMOS DE PURIFICARNOS DE LAS MALAS INCLINACIONES Tenemos tambi\u00e9n, Filotea, ciertas inclinaciones naturales, las cuales, porque no tienen su origen en nuestros pecados particulares, no son propiamente pecado, ni mortal ni venial, pero se llaman imperfecciones, y sus actos se llaman efectos o faltas. Por ejemplo, Santa\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":404577,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-un-hombre-evangelico-iii\/","url_meta":{"origin":35038,"position":5},"title":"San Vicente de Pa\u00fal, un hombre evang\u00e9lico (III)","author":"Mitxel Olabu\u00e9naga","date":"12\/02\/2023","format":false,"excerpt":"LOS SENTIMIENTOS DE VICENTE DE PA\u00daL SON SEMEJANTES A LOS DE JESUCRISTO San Vicente medit\u00f3 y coment\u00f3 con frecuencia la recomenda\u00adci\u00f3n de Pablo: \u00abTened los mismos sentimientos que Cristo Jes\u00fas\u00bb y el contenido del himno cristol\u00f3gico que nos ha dejado el ap\u00f3s\u00adtol de los gentiles en su carta a los\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/05\/d.jpg?fit=1200%2C799&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=35038"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/35038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=35038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=35038"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=35038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}