{"id":34980,"date":"2011-06-18T02:35:13","date_gmt":"2011-06-18T00:35:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/06\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/"},"modified":"2011-06-18T02:35:13","modified_gmt":"2011-06-18T00:35:13","slug":"introduccion-a-la-vida-devota-tercera-parte-capitulo-32","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32"},"content":{"rendered":"<div id=\"attachment_32887\" style=\"width: 215px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32887\" class=\"size-medium wp-image-32887\" title=\"San Francisco de Sales\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales-205x300.jpg?resize=205%2C300\" alt=\"San Francisco de Sales\" width=\"205\" height=\"300\" \/><\/a><p id=\"caption-attachment-32887\" class=\"wp-caption-text\">San Francisco de Sales<\/p><\/div>\n<p><strong>CAP\u00cdTULO XXXII<\/strong><\/p>\n<p><strong>DE LOS JUEGOS PROHIBIDOS<\/strong><\/p>\n<p>Los juegos de los dados, de los naipes y otros semejantes, en los cuales la ganancia depende \u00fanicamente del azar, no s\u00f3lo son recreaciones peligrosas, como los bailes, sino tambi\u00e9n sencillamente y naturalmente malas y vituperables; por esto est\u00e1n prohibidos por las leyes, as\u00ed civiles como eclesi\u00e1sticas. Pero dir\u00e1s: \u00ab\u00bfQu\u00e9 mal hay en ellos?\u00bb En estos juegos la ganancia no es fruto de la inteligencia, sino de la suerte, que muchas veces favorece al que no lo merece ni por su habilidad ni por su ingenio: en esto, pues, la raz\u00f3n sale ofendida. \u00abPero nosotros ya hemos convenido en ello&gt;&gt;, replicar\u00e1s. Esto sirve para demostrar que el que gana no hace injuria a los dem\u00e1s, pero de aqu\u00ed no se sigue que el pacto no est\u00e9 fuera de raz\u00f3n, y tambi\u00e9n el juego; porque el lucro, que ha de ser el precio de la habilidad, se convierte en el precio de la suerte, la cual no vale nada, pues, de ninguna manera, depende de nosotros.<\/p>\n<p>Adem\u00e1s, estos juegos llevan el nombre de recreaci\u00f3n, y para esto se han inventado; sin embargo, no lo son, sino m\u00e1s bien ocupaciones violentas. Porque, \u00bfno es, acaso, ocupaci\u00f3n, tener el esp\u00edritu oprimido y tenso por una continua atenci\u00f3n, y agitado por constantes inquietudes, aprensiones y zozobras? \u00bfExiste una atenci\u00f3n m\u00e1s triste, m\u00e1s sombr\u00eda y m\u00e1s melanc\u00f3lica que la de los jugadores? Por esto, durante el juego, no se puede hablar, ni re\u00edr, ni toser, pues enseguida se encolerizan.<\/p>\n<p>Finalmente, en el juego, no hay m\u00e1s goce que el del lucro, y \u00bfno es inicuo un goce que no se puede lograr de otra manera, sino a costa de la p\u00e9rdida y del disgusto del compa\u00f1ero? Esta alegr\u00eda es, en verdad, infame. Por estos tres motivos est\u00e1n prohibidos estos juegos. El gran rey San Luis, al enterarse de que su hermano el conde de Anjou y Don Gautier de Nemours estaban jugando, se levant\u00f3 de la cama a pesar de que estaba enfermo, y, con paso vacilante, se dirigi\u00f3 a su estancia, y cogi\u00f3 las mesas, los dados y parte del dinero, y lo arroj\u00f3 al mar por la ventana mostr\u00e1ndose muy enojado. La santa y casta doncella Sara, hablando a Dios de su inocencia, le dijo: \u00abT\u00fa sabes, \u00a1oh Se\u00f1or!, que nunca he tenido trato con jugadores\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO XXXII DE LOS JUEGOS PROHIBIDOS Los juegos de los dados, de los naipes y otros semejantes, en los cuales la ganancia depende \u00fanicamente del azar, no s\u00f3lo son recreaciones peligrosas, como los bailes, sino &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-34980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO XXXII DE LOS JUEGOS PROHIBIDOS Los juegos de los dados, de los naipes y otros semejantes, en los cuales la ganancia depende \u00fanicamente del azar, no s\u00f3lo son recreaciones peligrosas, como los bailes, sino ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-18T00:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32\",\"datePublished\":\"2011-06-18T00:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/\"},\"wordCount\":444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2011-06-18T00:35:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32 - Somos Vicencianos","og_description":"CAP\u00cdTULO XXXII DE LOS JUEGOS PROHIBIDOS Los juegos de los dados, de los naipes y otros semejantes, en los cuales la ganancia depende \u00fanicamente del azar, no s\u00f3lo son recreaciones peligrosas, como los bailes, sino ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2011-06-18T00:35:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32","datePublished":"2011-06-18T00:35:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/"},"wordCount":444,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/","name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2011-06-18T00:35:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-32\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 32"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-96c","jetpack-related-posts":[{"id":34978,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-31\/","url_meta":{"origin":34980,"position":0},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 31","author":"Francisco Javier Fern\u00e1ndez Chento","date":"20\/03\/2021","format":false,"excerpt":"CAP\u00cdTULO XXXI DE LOS PASATIEMPOS Y RECREACIONES, Y, EN PRIMER LUGAR, DE LAS QUE SON L\u00cdCITAS Y LAUDABLES Es necesario dar, de vez en cuando, cierta expansi\u00f3n a nuestro esp\u00edritu y tambi\u00e9n a nuestro cuerpo, con alguna clase de recreaci\u00f3n. Como dice Casiano, un d\u00eda un cazador encontr\u00f3 a San\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34982,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-34\/","url_meta":{"origin":34980,"position":1},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 34","author":"Francisco Javier Fern\u00e1ndez Chento","date":"04\/04\/2021","format":false,"excerpt":"CAP\u00cdTULO XXXIV CU\u00c1NDO SE PUEDE JUGAR Y BAILAR Para jugar y bailar l\u00edcitamente, es menester hacerlo por recreaci\u00f3n y no por afici\u00f3n, durante poco tiempo, sin cansarse ni rendirse, y muy de tarde en tarde; porque el que hace de ello una cosa ordinaria, convierte el recreo en ocupaci\u00f3n. Mas,\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34208,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-primera-parte-capitulo-23\/","url_meta":{"origin":34980,"position":2},"title":"Introducci\u00f3n a la vida devota. Primera parte, cap\u00edtulo 23","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/07\/2020","format":false,"excerpt":"CAP\u00cdTULO XXIII QUE HEMOS DE PURIFICARNOS DEL AFECTO A LAS COSAS IN\u00daTILES Y PELIGROSAS Los juegos, los bailes, los festines, las pompas, las comedias no son esencialmente cosas malas, sino indiferentes, y pueden ejecutarse bien o mal; pero siempre son peligrosas, y aficionarse a ellas todav\u00eda lo es m\u00e1s. Por\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":54305,"url":"http:\/\/vincentians.com\/es\/las-sagradas-escrituras-nos-manifiestan-los-misterios-de-dios-san-hipolito\/","url_meta":{"origin":34980,"position":3},"title":"Las Sagradas Escrituras nos manifiestan los misterios de Dios (San Hip\u00f3lito)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/06\/2019","format":false,"excerpt":"Las Sagradas Escrituras nos manifiestan los misterios de Dios Del Tratado de San Hip\u00f3lito, presb\u00edtero, Contra la herej\u00eda de Noeto. Lectura b\u00edblica: Jn 1, 1-18 San Hip\u00f3lito (\u00bf-235) Desconocemos lugar y fecha de su nacimiento, aunque sabemos que fue disc\u00edpulo de San Ireneo y compuso sus escritos entre los a\u00f1os\u2026","rel":"","context":"En \u00abPadres de la Iglesia\u00bb","block_context":{"text":"Padres de la Iglesia","link":"http:\/\/vincentians.com\/es\/category\/formacion-cristiana\/padres-de-la-iglesia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35032,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-06\/","url_meta":{"origin":34980,"position":4},"title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 06","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO VI DE QU\u00c9 MANERA LA TENTACI\u00d3N Y LA DELECTACI\u00d3N PUEDEN SER PECADO La princesa de la cual hemos hablado, no es responsable de la propuesta deshonesta que le ha sido hecha, porque, como hemos supuesto, todo ha ocurrido contra su voluntad; mas, si, por el contrario, hubiese dado motivo\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34963,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-17\/","url_meta":{"origin":34980,"position":5},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 17","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/06\/2011","format":false,"excerpt":"CAP\u00cdTULO XVII DE LA AMISTAD Y, EN PRIMER LUGAR, DE LA QUE ES MALA Y FR\u00cdVOLA El amor ocupa el primer lugar entre las pasiones del alma; es el rey de todos los movimientos del coraz\u00f3n; transforma en s\u00ed mismo todas las dem\u00e1s cosas y nos hace tales cuales son\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=34980"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=34980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=34980"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=34980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}