{"id":34977,"date":"2021-03-06T08:35:13","date_gmt":"2021-03-06T07:35:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/06\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/"},"modified":"2020-12-13T11:56:02","modified_gmt":"2020-12-13T10:56:02","slug":"introduccion-a-la-vida-devota-tercera-parte-capitulo-30","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30"},"content":{"rendered":"<p><strong>CAP\u00cdTULO XXX<\/strong><\/p>\n<p><strong>ALGUNOS OTROS AVISOS ACERCA DEL HABLAR<\/strong><\/p>\n<p>Que tu manera de hablar sea dulce, franca, sincera, espont\u00e1nea, ingenua y fiel. Gu\u00e1rdate de la doblez, del artificio y de la ficci\u00f3n; aunque no siempre es oportuno decir toda clase de verdades, nunca, empero, est\u00e1 permitido faltar a la verdad. Acost\u00fambrate a no mentir nunca a sabiendas, ni para excusarte, ni por otro cualquier motivo, y acu\u00e9rdate de que Dios es el Dios de la verdad. Si dices mentiras por descuido, y puedes retractarlas al momento, mediante alguna explicaci\u00f3n o reparaci\u00f3n, retr\u00e1ctalas; una raz\u00f3n verdadera tiene m\u00e1s gracia y fuerza, para excusar, que una mentira.<\/p>\n<p>Aunque, en alguna ocasi\u00f3n, se puede, con discreci\u00f3n y prudencia, disimular y encubrir la verdad con alg\u00fan artificio de palabras, \u00fanicamente se ha de hacer en cosas de importancia y cuando claramente lo exigen la gloria y el servicio de Dios; fuera de este caso, los artificios son muy peligrosos, porque, como dice la Sagrada Escritura, el Esp\u00edritu Santo no habita en un esp\u00edritu fingido y doble. No existe delicadeza tan buena y tan deseable como la simplicidad. La prudencia mundana y los artificios carnales pertenecen a los hijos de este siglo; pero los hijos de Dios caminan rectamente y tienen el coraz\u00f3n sin dobleces. \u00abQuien anda con simplicidad -dice el Sabio- anda seguro\u00bb. La mentira, la doblez y el disimulo suponen siempre un esp\u00edritu flaco y envilecido.<\/p>\n<p>San Agust\u00edn hab\u00eda dicho en el libro de sus Confesiones, que su alma y la de su amigo no eran m\u00e1s que una sola alma, y que esta vida era para \u00e9l horrible despu\u00e9s de la muerte de aqu\u00e9l, porque no quer\u00eda vivir a medias, pero que, por este motivo no quer\u00eda morir, a saber, por temor de que su amigo muriese del todo. Estas palabras le parecieron despu\u00e9s demasiado artificiosas y afectadas, por lo que se desdice de ellas en el libro de sus Retractaciones, llam\u00e1ndolas necedad. \u00bfNo ves, amada Filotea, cu\u00e1n delicada es esta hermosa alma, en lo que ata\u00f1e a la afectaci\u00f3n en las palabras? Ciertamente, es un gran adorno de la vida cristiana la fidelidad, la franqueza y la sinceridad en el hablar. \u00abYo dije: tendr\u00e9 cuidado en mis caminos, para no pecar con mi lengua&#8230; \u00a1Ah Se\u00f1or!, pon guardia en mi boca, y una puerta que cierre mis labios\u00bb, dec\u00eda David.<\/p>\n<p>Es una advertencia del rey San Luis, que a nadie se contradiga, fuera del caso en que el consentir sea pecado o acarree un gran mal, con el fin de evitar disputas y discordias. Ahora bien, cuando conviene contradecir a alguno y oponer la propia opini\u00f3n a la de otro, es menester emplear mucha dulzura y flexibilidad, y no querer violentar el \u00e1nimo del contrario, pues nada se gana tomando las cosas con aspereza. El hablar poco, tan recomendado por los sabios antiguos, no significa que se hayan de decir pocas palabras, sino que no hay que decir muchas in\u00fatiles; porque, en cuanto al hablar, no se mira la cantidad, sino la calidad. Y me parece que se han de evitar los dos extremos, ya que el querer sentar plaza de sabio y de severo, neg\u00e1ndose, al efecto a tomar parte en los pasatiempos familiares, como son las conversaciones, parece que arguye falta de confianza o desd\u00e9n; como el hablar y el bromear continuamente, sin dar a los dem\u00e1s tiempo y oportunidad de hablar cuando quieren, es propio de personas livianas y ligeras.<\/p>\n<p>A San Luis no le parec\u00eda bien que, en presencia de los dem\u00e1s, se hablase secretamente y con misterio, particularmente en la mesa, para no dar motivo de sospecha de que se hablaba mal de alguno. \u00abAquel -dec\u00eda&#8211;que est\u00e1 en la mesa con buena compa\u00f1\u00eda, y quiere decir alguna cosa jocosa y divertida, debe decirla de manera que la oiga todo el mundo, si es cosa de importancia, debe callarla, sin hablar de ella\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO XXX ALGUNOS OTROS AVISOS ACERCA DEL HABLAR Que tu manera de hablar sea dulce, franca, sincera, espont\u00e1nea, ingenua y fiel. Gu\u00e1rdate de la doblez, del artificio y de la ficci\u00f3n; aunque no siempre es &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"#ffffff","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-34977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO XXX ALGUNOS OTROS AVISOS ACERCA DEL HABLAR Que tu manera de hablar sea dulce, franca, sincera, espont\u00e1nea, ingenua y fiel. Gu\u00e1rdate de la doblez, del artificio y de la ficci\u00f3n; aunque no siempre es ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-06T07:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30\",\"datePublished\":\"2021-03-06T07:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/\"},\"wordCount\":696,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2021-03-06T07:35:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30 - Somos Vicencianos","og_description":"CAP\u00cdTULO XXX ALGUNOS OTROS AVISOS ACERCA DEL HABLAR Que tu manera de hablar sea dulce, franca, sincera, espont\u00e1nea, ingenua y fiel. Gu\u00e1rdate de la doblez, del artificio y de la ficci\u00f3n; aunque no siempre es ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2021-03-06T07:35:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30","datePublished":"2021-03-06T07:35:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/"},"wordCount":696,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/","name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2021-03-06T07:35:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 30"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-969","jetpack-related-posts":[{"id":130883,"url":"http:\/\/vincentians.com\/es\/el-camino-de-san-vicente-sencillez\/","url_meta":{"origin":34977,"position":0},"title":"El camino de San Vicente: Sencillez","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/02\/2015","format":false,"excerpt":"Esta es la virtud que m\u00e1s amaba san Vicente. \"Es mi evangelio\", sol\u00eda decir. Escucha, hermano m\u00edo, c\u00f3mo san Vicente describe la sencillez: Nuestro Se\u00f1or Jesucristo nos pide la sencillez de la paloma, que consiste en decir las cosas llanamente como est\u00e1n en nuestro coraz\u00f3n, sin elucubraciones in\u00fatiles, y en\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"la-sencillez","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/la-sencillez-300x216.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":387820,"url":"http:\/\/vincentians.com\/es\/sencillos-como-palomas-y-prudentes-como-serpientes\/","url_meta":{"origin":34977,"position":1},"title":"Sencillos como palomas y prudentes como serpientes","author":"Mitxel Olabu\u00e9naga","date":"17\/09\/2016","format":false,"excerpt":"La virtud amable de la sencillez es la primera biena\u00adventuranza de los seguidores de Jes\u00fas, seg\u00fan el programa \u00abut\u00f3pi\u00adco\u00bb de Vicente de Pa\u00fal. Hacia esta virtud encantadora experimen\u00adta el Santo una atracci\u00f3n y simpat\u00eda admirables. El 6 de noviem\u00adbre de 1634 le comunica a E. du Coudray: \u00abLa sencillez es\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana sin categorizar\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana sin categorizar","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/formacion-vicenciana-sin-categorizar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":133542,"url":"http:\/\/vincentians.com\/es\/sencillez-la-virtud-de-la-transparencia\/","url_meta":{"origin":34977,"position":2},"title":"Sencillez: la virtud de la transparencia","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/01\/2015","format":false,"excerpt":"Al enumerar las virtudes que los Vicentinos han de imitar de San Vicente de Pa\u00fal para fomentar el amor y el respeto por los pobres, la Regla empieza por la virtud de la sencillez, que \"incluye franqueza, integridad, generosidad\" (2.5.1) La sencillez, a decir del Diccionario de la Real Academia\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"esp_08","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/12\/esp_08-300x167.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":48764,"url":"http:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-de-fray-juan-del-santisimo-sacramento-libro-primero-capitulo-22\/","url_meta":{"origin":34977,"position":3},"title":"Vida de San Vicente de Pa\u00fal, de Fray Juan del Sant\u00edsimo Sacramento. Libro primero, cap\u00edtulo 22","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/08\/2011","format":false,"excerpt":"Cap\u00edtulo XXII: Se ha opuesto siempre Vicente con mucha fuerza a los errores del Jansenismo. Siempre \u00a0los santos han tenido por grande honor permanecer en una humilde dependencia, no solo a las \u00f3rdenes de la voluntad de Dios, sino tambi\u00e9n a la conducta de su Iglesia, pues han hecho profesi\u00f3n\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/san-vicente-de-fray-juan-del-santisimo-sacramento.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/san-vicente-de-fray-juan-del-santisimo-sacramento.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/san-vicente-de-fray-juan-del-santisimo-sacramento.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/san-vicente-de-fray-juan-del-santisimo-sacramento.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/san-vicente-de-fray-juan-del-santisimo-sacramento.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":30462,"url":"http:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-primero-capitulo-44\/","url_meta":{"origin":34977,"position":4},"title":"Vida de san Vicente de Pa\u00fal: Libro Primero, Cap\u00edtulo 44","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/03\/2020","format":false,"excerpt":"Los Santos siempre han considerado como un gran honor mantenerse en humilde dependencia no solamente a las \u00f3rdenes de la voluntad de Dios, sino tambi\u00e9n a las directrices de la Iglesia, pues profesaron someterle a ella su libertad con una obediencia exacta a las leyes prescritas por ella, y tambi\u00e9n\u2026","rel":"","context":"En \u00abEscritos de Luis Abelly\u00bb","block_context":{"text":"Escritos de Luis Abelly","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luis-abelly\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":131681,"url":"http:\/\/vincentians.com\/es\/sencillos-como-las-palomas-y-prudentes-como-las-serpientes\/","url_meta":{"origin":34977,"position":5},"title":"\u00abSencillos como las palomas y prudentes como las serpientes\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"16\/11\/2014","format":false,"excerpt":"Que vuestro s\u00ed sea un s\u00ed y vuestro no un no; lo que pasa de ah\u00ed es cosa del Malo. (Mt 5,37). \"La Congregaci\u00f3n intenta expresar su esp\u00edritu tambi\u00e9n con las cinco virtudes sacadas de su peculiar visi\u00f3n de Cristo, a saber: la sencillez, la humildad, la mansedumbre, la mortificaci\u00f3n\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"mateo_10_16","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/11\/mateo_10_16-300x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=34977"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34977\/revisions"}],"predecessor-version":[{"id":403368,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34977\/revisions\/403368"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=34977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=34977"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=34977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}