{"id":34965,"date":"2011-06-05T08:35:13","date_gmt":"2011-06-05T06:35:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/06\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/"},"modified":"2011-06-05T08:35:13","modified_gmt":"2011-06-05T06:35:13","slug":"introduccion-a-la-vida-devota-tercera-parte-capitulo-19","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19"},"content":{"rendered":"<div id=\"attachment_32887\" style=\"width: 215px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-32887\" class=\"size-medium wp-image-32887\" title=\"San Francisco de Sales\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/04\/francisco-de-sales-205x300.jpg?resize=205%2C300\" alt=\"San Francisco de Sales\" width=\"205\" height=\"300\" \/><\/a><p id=\"caption-attachment-32887\" class=\"wp-caption-text\">San Francisco de Sales<\/p><\/div>\n<p><strong>CAP\u00cdTULO XIX<\/strong><\/p>\n<p><strong>DE LA VERDADERA AMISTAD<\/strong><\/p>\n<p>\u00a1Oh, Filotea!, ama a todo el mundo con amor de caridad, pero no tengas amistad sino con aquellos que pueden comunicar contigo cosas virtuosas; y cuanto m\u00e1s exquisitas sean las virtudes, m\u00e1s perfecta ser\u00e1 la amistad. Si la comunicaci\u00f3n tiene por objeto las ciencias, tu amistad es, ciertamente, muy loable; y lo es todav\u00eda m\u00e1s, si la comunicaci\u00f3n se refiere a las virtudes de la prudencia, discreci\u00f3n, fortaleza y justicia. Pero, si vuestra mutua y rec\u00edproca comunicaci\u00f3n es acerca de la caridad, de la devoci\u00f3n, de la perfecci\u00f3n cristiana, \u00a1oh Dios m\u00edo!, qu\u00e9 preciosa ser\u00e1 esta amistad. Ser\u00e1 excelente, porque vendr\u00e1 de Dios; excelente, porque tender\u00e1 a Dios; excelente, porque durar\u00e1 eternamente en Dios. \u00a1Qu\u00e9 bueno es amar en la tierra como se ama en el cielo y aprender a amarse los unos a los otros, en este mundo, de la misma manera que nos amaremos eternamente en el otro!<\/p>\n<p>No hablo ahora del simple amor de caridad, porque esta virtud hemos de tenerla con respecto a todos los hombres; sino que hablo de la amistad espiritual, por la que dos, o tres o m\u00e1s almas se comunican su devoci\u00f3n, sus afectos espirituales, y forman como un solo esp\u00edritu. Con cu\u00e1nta raz\u00f3n pueden cantar estas bienaventuradas almas: \u00abi Oh, cu\u00e1n bueno y agradable es el que los hermanos vivan unidos!\u00bb S\u00ed, porque el b\u00e1lsamo delicioso de la devoci\u00f3n destila de un coraz\u00f3n a otro por una continua participaci\u00f3n, de suerte que se puede afirmar que Dios hace mover-sobre esta amistad su bendici\u00f3n y la vida por los siglos de los siglos.<\/p>\n<p>Me parece que todas las dem\u00e1s amistades no son sino sombras, en comparaci\u00f3n de aqu\u00e9lla, y que sus lazos no son m\u00e1s que cadenas de vidrio, en comparaci\u00f3n con este gran v\u00ednculo de la santa devoci\u00f3n, todo \u00e9l de oro.<\/p>\n<p>No quieras trabar otra clase de amistades, se entiende de las amistades buscadas por ti; porque claro est\u00e1 que no se pueden dejar ni despreciar las amistades que la naturaleza y los deberes preexistentes nos obligan a cultivar: con los padres, los parientes, los bienhechores, los vecinos y otros; hablo de las que t\u00fa misma escoges.<\/p>\n<p>Quiz\u00e1s muchos te dir\u00e1n que no hay que tener ninguna clase de particular afecto y amistad, porque esto ocupa el coraz\u00f3n, distrae el esp\u00edritu y engendra envidias; pero se equivocan en sus consejos. Por haber le\u00eddo en los escritos de muchos santos y en devotos autores, que las amistades particulares y los afectos extraordinarios son infinitamente perjudiciales a los religiosos, creen que lo mismo se ha de entender con respecto a todo el mundo; pero, acerca de esto, hay mucho que decir. Porque, considerando que, en un monasterio bien ordenado, el fin com\u00fan a todos es encaminarse a la verdadera devoci\u00f3n, ser\u00e1 f\u00e1cil de entender que no son necesarias estas particulares comunicaciones, por temor de que, al buscar en particular lo que es com\u00fan, no se pase de las particularidades a las parcialidades; pero, en lo que ata\u00f1e a los que viven entre los mundanos y abrazan la verdadera virtud, necesitan unirse unos con otros con una santa y sagrada amistad, ya que, merced a \u00e9sta, se alientan, ayudan y estimulan mutuamente a obrar bien. Y, as\u00ed como los que andan por la llanura no necesitan darse la mano, pero los que andan por caminos escabrosos y resbaladizos se cogen los unos a los otros, para caminar con m\u00e1s seguridad; de la misma manera, los que viven en las comunidades religiosas no tienen necesidad de amistades particulares, pero los que est\u00e1n en el mundo necesitan de ellas para apoyarse y socorrerse los unos a los otros, en medio de los parajes dif\u00edciles que han de atravesar. En el mundo, no todos conspiran al mismo fin, ni todos tienen el mismo esp\u00edritu; se impone, pues, la separaci\u00f3n y la amistad, seg\u00fan las aspiraciones de cada uno; y esta separaci\u00f3n crea, ciertamente, una parcialidad, pero una parcialidad santa, que no produce otra divisi\u00f3n que la del bien y el mal, la de los corderos y los cabritos, la de las abejas y los moscardones, separaciones de todo punto necesarias.,<\/p>\n<p>A la verdad, no me atrever\u00eda a negar que Nuestro Se\u00f1or am\u00f3 con m\u00e1s particular y m\u00e1s dulce amistad a San Juan, a L\u00e1zaro, a Marta y a Magdalena, pues la Escritura da testimonio de ello. Sabemos que San Pedro am\u00f3 tiernamente a San Marcos y a Santa Petronila; como San Pablo, a Timoteo y a Santa Tecla. San Gregorio Nacianceno se gloria cien veces de la amistad incomparable que profes\u00f3 al gran San Basilio, y la describe de esta manera: \u00abParec\u00eda que en nosotros no hab\u00eda m\u00e1s que una sola alma en dos cuerpos\u00bb. Y, aunque no hemos de creer a los que afirman que todas las cosas est\u00e1n en todas las cosas, hemos de creer, empero, que nosotros \u00e9ramos dos en cada uno de nosotros, el uno en el otro; los dos ten\u00edamos una sola aspiraci\u00f3n: cultivar la virtud y ajustar los designios de nuestra vida a las esperanzas venideras, saliendo as\u00ed de esta tierra mortal antes de morir en ella. San Agust\u00edn atestigua que San Ambrosio amaba a Santa M\u00f3nica \u00fanicamente por las virtudes que ve\u00eda en ella, y que ella, rec\u00edprocamente, le amaba como a un \u00e1ngel de Dios.<\/p>\n<p>Pero me equivoco al entretenerte en una cosa tan clara. San Jer\u00f3nimo, San Agust\u00edn, San Gregorio, San Bernardo y todos los m\u00e1s grandes siervos de Dios, han tenido amistades muy particulares, sin menoscabo de su perfecci\u00f3n. San Pablo, al censurar los vicios de los gentiles, les acusa de que son personas sin afecto; es decir, que no tienen ninguna amistad. Y Santo Tom\u00e1s, como todos los buenos fil\u00f3sofos, afirma que la amistad es una virtud: y n\u00f3tese que habla de la amistad particular, pues, como \u00e9l mismo dice, la verdadera amistad no puede extenderse a muchas personas. Luego la perfecci\u00f3n no consiste en no tener amistades, sino en tenerlas \u00fanicamente buenas, santas y sagradas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO XIX DE LA VERDADERA AMISTAD \u00a1Oh, Filotea!, ama a todo el mundo con amor de caridad, pero no tengas amistad sino con aquellos que pueden comunicar contigo cosas virtuosas; y cuanto m\u00e1s exquisitas sean &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-34965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO XIX DE LA VERDADERA AMISTAD \u00a1Oh, Filotea!, ama a todo el mundo con amor de caridad, pero no tengas amistad sino con aquellos que pueden comunicar contigo cosas virtuosas; y cuanto m\u00e1s exquisitas sean ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-05T06:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19\",\"datePublished\":\"2011-06-05T06:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/\"},\"wordCount\":1090,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2011-06-05T06:35:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19 - Somos Vicencianos","og_description":"CAP\u00cdTULO XIX DE LA VERDADERA AMISTAD \u00a1Oh, Filotea!, ama a todo el mundo con amor de caridad, pero no tengas amistad sino con aquellos que pueden comunicar contigo cosas virtuosas; y cuanto m\u00e1s exquisitas sean ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2011-06-05T06:35:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19","datePublished":"2011-06-05T06:35:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/"},"wordCount":1090,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/","name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2011-06-05T06:35:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 19"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-95X","jetpack-related-posts":[{"id":34963,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-17\/","url_meta":{"origin":34965,"position":0},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 17","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/06\/2011","format":false,"excerpt":"CAP\u00cdTULO XVII DE LA AMISTAD Y, EN PRIMER LUGAR, DE LA QUE ES MALA Y FR\u00cdVOLA El amor ocupa el primer lugar entre las pasiones del alma; es el rey de todos los movimientos del coraz\u00f3n; transforma en s\u00ed mismo todas las dem\u00e1s cosas y nos hace tales cuales son\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":118752,"url":"http:\/\/vincentians.com\/es\/teologia-de-la-caridad-perspectivas-tomistas\/","url_meta":{"origin":34965,"position":1},"title":"Teolog\u00eda de la Caridad. Perspectivas Tomistas","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/10\/2021","format":false,"excerpt":"Introducci\u00f3n Por la fe conoce el hombre a Dios, verdad primera y fin \u00faltimo de su vida, con esperanza tiende a poseerlo como objeto de su felicidad, en la caridad se une afectivamente a \u00e9l como amigo; se transforma de alguna manera en \u00e9l y comienza a amar como es\u2026","rel":"","context":"En \u00abFormaci\u00f3n Cristiana\u00bb","block_context":{"text":"Formaci\u00f3n Cristiana","link":"http:\/\/vincentians.com\/es\/category\/formacion-cristiana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34968,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-22\/","url_meta":{"origin":34965,"position":2},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 22","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/01\/2021","format":false,"excerpt":"CAP\u00cdTULO XXII ALGUNAS OTRAS ADVERTENCIAS SOBRE LAS AMISTADES La amistad requiere una gran comunicaci\u00f3n entre los amigos; de lo contrario, no puede nacer ni subsistir. Por esta causa, ocurre que, con la comunicaci\u00f3n propia de la amistad, se deslizan y pasan insensiblemente de coraz\u00f3n a coraz\u00f3n otras comunicaciones, por una\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":141151,"url":"http:\/\/vincentians.com\/es\/amigos-que-se-quieren-bien\/","url_meta":{"origin":34965,"position":3},"title":"Amigos que se quieren bien","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/03\/2015","format":false,"excerpt":"\u00abSer\u00e9is amigos m\u00edos si ha\u00adc\u00e9is lo que os mando. Ya no os llamar\u00e9 m\u00e1s siervos, porque un siervo no est\u00e1 al corriente de lo que hace su amo; os llamo amigos por\u00adque os he comunicado todo lo que he o\u00eddo a mi Padre\u00bb. (In 15,14-15). \u201cLa comunidad se crea constantemente\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"\u20ac~}","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/03\/cooperacion-300x198.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":133546,"url":"http:\/\/vincentians.com\/es\/afabilidad-virtud-del-buen-trato\/","url_meta":{"origin":34965,"position":4},"title":"Afabilidad: Virtud del buen trato","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/01\/2015","format":false,"excerpt":"Llama la atenci\u00f3n en \"Wikipedia\" que, al hablar sobre la afabilidad, dice que es \"una virtud de los antiguos tiempos, aunque se encuentra todav\u00eda en personas que han conservado las tradiciones de noble sencillez y de generosa franqueza\". Desde luego, se conserva la afabilidad en los miembros de la Sociedad\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"afable_1","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/01\/afable_1-300x224.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":34966,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-20\/","url_meta":{"origin":34965,"position":5},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 20","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/06\/2011","format":false,"excerpt":"CAP\u00cdTULO XX DE LA DIFERENCIA ENTRE LA AMISTAD VERDADERA Y LAS AMISTADES FALSAS He aqu\u00ed, pues, la gran advertencia, Filotea. La miel de Heraelea, que es tan venenosa, es parecida a la otra ' que es tan saludable: es un gran peligro tomar la una por la otra, o tomarlas\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=34965"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=34965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=34965"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=34965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}