{"id":34935,"date":"2020-10-26T08:20:13","date_gmt":"2020-10-26T07:20:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/05\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/"},"modified":"2020-10-03T19:33:17","modified_gmt":"2020-10-03T17:33:17","slug":"introduccion-a-la-vida-devota-tercera-parte-capitulo-06","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06"},"content":{"rendered":"<p><strong>CAP\u00cdTULO VI<\/strong><\/p>\n<p><strong>QUE LA HUMILDAD HACE QUE AMEMOS NUESTRA PROPIA ABYECCI\u00d3N<\/strong><\/p>\n<p>Voy m\u00e1s lejos, Filotea, y te digo que, en todo y por todo, ames tu propia abyecci\u00f3n. Pero me dir\u00e1s: \u00bfqu\u00e9 significa esto: ama tu propia abyecci\u00f3n? En lat\u00edn, abyecci\u00f3n quiere decir humildad, y humildad quiere decir abyecci\u00f3n, de manera que, cuando Nuestra Se\u00f1ora, en su sagrado c\u00e1ntico, dice: \u00abporque el Se\u00f1or ha visto la humildad de su sierva, todas las generaciones me llamar\u00e1n bienaventurada \u00ab, quiere decir que el Se\u00f1or ha visto de buen grado su abyecci\u00f3n, vileza y bajeza, para colmarla de gracias y favores. Con todo hay mucha diferencia entre la virtud de la humildad y la abyecci\u00f3n, porque la abyecci\u00f3n es la peque\u00f1ez, la bajeza y la vileza que hay entre nosotros, sin que nosotros pensemos en ello; pero la virtud de la humildad es el verdadero conocimiento y voluntario reconocimiento de nuestra abyecci\u00f3n. Ahora bien, el punto m\u00e1s encumbrado de esta humildad consiste, no s\u00f3lo en reconocer voluntariamente nuestra abyecci\u00f3n, sino en amarla y en complacernos en ella, y no por falta de \u00e1nimos y de generosidad, sino para m\u00e1s ensalzar a la divina Majestad y m\u00e1s amar al pr\u00f3jimo en comparaci\u00f3n con nosotros mismos. Esta es la cosa a la cual te exhorto, y, para que lo entiendas mejor, sepas que entre los males que padecemos unos son abyectos y otros honrosos. Muchos se conforman con los honrosos, pero nadie quiere acomodarse a los abyectos. He aqu\u00ed un devoto ermita\u00f1o harapiento y tiritando de fr\u00edo: todos honran su h\u00e1bito deshecho y compadecen su austeridad; pero si se trata de un pobre obrero, de un pobre joven, de una pobre muchacha, son despreciados, objeto de burla; su pobreza es abyecta. Un religioso recibe resignadamente una \u00e1spera reprensi\u00f3n de su superior, o un hijo la recibe de su padre: todo el mundo llamar\u00e1 a esto mortificaci\u00f3n, obediencia y prudencia; un caballero o una dama sufrir\u00e1n lo mismo de parte de otra persona, y, aunque la soporten por amor de Dios, todos les motejar\u00e1n de cobard\u00eda y poquedad de esp\u00edritu. Una persona tiene un c\u00e1ncer en un brazo y otra en la cara: aqu\u00e9lla s\u00f3lo tiene el mal, pero \u00e9sta, adem\u00e1s del mal, padece el menosprecio, el desd\u00e9n y la abyecci\u00f3n. Pues bien, te digo ahora que no s\u00f3lo hemos de apreciar el mal, lo cual se hace con la virtud de la paciencia, sino tambi\u00e9n la abyecci\u00f3n, lo cual se hace con la virtud de la humildad.<\/p>\n<p>Tambi\u00e9n hay virtudes abyectas y virtudes honrosas: la paciencia, la mansedumbre, la simplicidad y la humildad son virtudes que los mundanos tienen por viles y abyectas; al contrario, tienen en mucha estima la prudencia, el valor, la liberalidad. Y, aun entre los actos de una misma virtud, unos son objeto de desprecio y otros de honra: dar limosna y perdonar las injurias son actos de caridad; el primero es honrado por todos, y el segundo despreciable a los ojos del mundo. Un joven noble o una doncella que no se entreguen al desorden de una pandilla desenfrenada en el hablar, en el jugar, en el bailar, en el beber, en el vestir, ser\u00e1n criticados o censurados por los dem\u00e1s y su modestia ser\u00e1 calificada de hipocres\u00eda o afectaci\u00f3n: pues bien, amar esto es amar la propia abyecci\u00f3n. He aqu\u00ed otra manera de amarla: vamos a visitar a los enfermos; si soy enviado al m\u00e1s miserable, esto ser\u00e1 para mi un motivo de abyecci\u00f3n, seg\u00fan el mundo, y, por esto mismo la amar\u00e9; si me env\u00edan a visitar a los de categor\u00eda, ser\u00e1 una abyecci\u00f3n seg\u00fan el esp\u00edritu, porque en ello no hay tanta virtud ni m\u00e9rito &#8216; y por lo tanto, amar\u00e9 esta abyecci\u00f3n. El que cae en medio de la calle, adem\u00e1s del da\u00f1o que se hace, es objeto de burla; es menester querer esta abyecci\u00f3n. Hay faltas en las cuales no se encuentra otro mal que la abyecci\u00f3n; la humildad no nos exige que las cometamos expresamente, pero exige que no nos inquietemos cuando las hayamos cometido: tales son ciertas ligerezas, faltas de educaci\u00f3n, descuidos, las cuales hay que evitar, por razones de buena educaci\u00f3n y de prudencia, antes de que se cometan; pero una vez cometidas, hay que aceptar la abyecci\u00f3n que de ellas proviene, y hay que aceptarla de buen grado, para practicar la santa virtud de la humildad. M\u00e1s a\u00fan: si me he dejado llevar de la ira o de la disoluci\u00f3n, hasta decir palabras inconvenientes, que han redundado en ofensa de Dios o del pr\u00f3jimo, me arrepentir\u00e9 vivamente y estar\u00e9 afligido de la ofensa, la cual procurar\u00e9 reparar de la mejor manera que me sea posible; pero no dejar\u00e9 de aceptar la abyecci\u00f3n y el desprecio que de ello me sobrevengan, y, si una cosa pudiese separarse de la otra, rechazar\u00eda en\u00e9rgicamente el pecado y me quedar\u00eda humildemente con la abyecci\u00f3n.<\/p>\n<p>Pero, aunque amemos la abyecci\u00f3n que proviene del mal, es menester que, con recursos apropiados y leg\u00edtimos, pongamos remedio al mal que la ha causado, sobre todo cuando el mal acarrea consecuencias. Si tengo en el rostro alg\u00fan mal repugnante, procurar\u00e9 su curaci\u00f3n, pero sin olvidar la abyecci\u00f3n que trae consigo. Si he hecho alguna cosa que no of ende a nadie, no me disculpar\u00e9 de ella, porque, aunque esta cosa sea alg\u00fan defecto, no es permanente, y no podr\u00eda excusarme de ella sino por la abyecci\u00f3n que de la misma procede y esto es lo que la humildad no puede permitir; mas, si, por descuido o por dejadez, he ofendido o escandalizado a alguno, reparar\u00e9 la ofensa con alguna excusa, verdadera, porque el mal es permanente y la caridad obliga a borrarlo. Por lo dem\u00e1s, suele ocurrir, alguna vez, que la caridad exija que pongamos remedio a la abyecci\u00f3n, por el bien del pr\u00f3jimo, al cual es necesaria nuestra reputaci\u00f3n; mas en este caso, una vez quitada nuestra abyecci\u00f3n de los ojos del pr\u00f3jimo para evitar el esc\u00e1ndalo, conviene guardarla y ocultarla dentro del coraz\u00f3n, para que se edifique de ello.<\/p>\n<p>Pero t\u00fa, Filotea, quieres saber cu\u00e1les son las mejores abyecciones. Te digo claramente que las m\u00e1s provechosas al alma y las m\u00e1s agradables a Dios son las que nos vienen al azar o por la condici\u00f3n de nuestra vida, porque \u00e9stas no son escogidas por nosotros, sino que se reciben tal como las env\u00eda Dios, cuya elecci\u00f3n siempre es mejor que la nuestra. Y, si hay que escoger, las m\u00e1s grandes son las mejores, y son m\u00e1s grandes las contrar\u00edas a nuestras inclinaciones, con tal que cuadren con nuestra profesi\u00f3n, porque, dig\u00e1moslo de una vez para siempre, nuestra elecci\u00f3n echa a perder y disminuye casi todas nuestras virtudes. \u00a1Ah! \u00bfQui\u00e9n nos har\u00e1 la gracia de que podamos decir con aquel gran rey: \u00abHe preferido ser abyecto en la casa del Se\u00f1or a habitar en los palacios de los pecadores?\u00bb. Nadie puede decirlo, amada Filotea, fuera de Aquel que, para ensalzarnos, vivi\u00f3 y muri\u00f3 de manera que fue \u00abel oprob\u00edo de los hombres y la abyecci\u00f3n de la plebe\u00bb.<\/p>\n<p>Te he dicho muchas cosas que te parecer\u00e1n duras cuando las consideres; pero, cr\u00e9eme: cuando las practiques, ser\u00e1n para ti m\u00e1s agradables que el az\u00facar y la miel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO VI QUE LA HUMILDAD HACE QUE AMEMOS NUESTRA PROPIA ABYECCI\u00d3N Voy m\u00e1s lejos, Filotea, y te digo que, en todo y por todo, ames tu propia abyecci\u00f3n. Pero me dir\u00e1s: \u00bfqu\u00e9 significa esto: ama &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"#ffffff","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-34935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO VI QUE LA HUMILDAD HACE QUE AMEMOS NUESTRA PROPIA ABYECCI\u00d3N Voy m\u00e1s lejos, Filotea, y te digo que, en todo y por todo, ames tu propia abyecci\u00f3n. Pero me dir\u00e1s: \u00bfqu\u00e9 significa esto: ama ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-26T07:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06\",\"datePublished\":\"2020-10-26T07:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/\"},\"wordCount\":1318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2020-10-26T07:20:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06 - Somos Vicencianos","og_description":"CAP\u00cdTULO VI QUE LA HUMILDAD HACE QUE AMEMOS NUESTRA PROPIA ABYECCI\u00d3N Voy m\u00e1s lejos, Filotea, y te digo que, en todo y por todo, ames tu propia abyecci\u00f3n. Pero me dir\u00e1s: \u00bfqu\u00e9 significa esto: ama ... Read More","og_url":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2020-10-26T07:20:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06","datePublished":"2020-10-26T07:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/"},"wordCount":1318,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/","url":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/","name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2020-10-26T07:20:13+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 06"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-95t","jetpack-related-posts":[{"id":130885,"url":"http:\/\/vincentians.com\/es\/el-camino-de-san-vicente-humildad\/","url_meta":{"origin":34935,"position":0},"title":"El camino de San Vicente: Humildad","author":"Francisco Javier Fern\u00e1ndez Chento","date":"22\/02\/2015","format":false,"excerpt":"Hermano, medita de coraz\u00f3n estas palabras de san Vicente: Todos nos aplicaremos con diligencia a aprender esta lecci\u00f3n de Jesucristo: Aprended de m\u00ed, porque soy manso y humilde de coraz\u00f3n. Pensemos que, como \u00e9l mismo afirma, con la mansedumbre se llega a poseer la tierra, pues con esta virtud se\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"humildad","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/07\/humildad-300x188.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6491,"url":"http:\/\/vincentians.com\/es\/luisa-de-marillac-pensamiento-013-temor-y-consuelo-experimentados-con-relacion-a-la-sagrada-comunion\/","url_meta":{"origin":34935,"position":1},"title":"Luisa de Marillac, Pensamiento 013: Temor y consuelo experimentados con relaci\u00f3n a la Sagrada Comuni\u00f3n:","author":"Francisco Javier Fern\u00e1ndez Chento","date":"13\/01\/2009","format":false,"excerpt":"38. De tiempo en tiempo, especialmente en las grandes solemnidades, la vista de mi abyecci\u00f3n con el recuerdo de mis faltas e infidelidades a Dios me hace temer el acercarme a la Sagrada Comuni\u00f3n; unas veces por un sentimiento de desagrado de que un Dios tan bueno venga a lugar\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35036,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-cuarta-parte-capitulo-10\/","url_meta":{"origin":34935,"position":2},"title":"Introducci\u00f3n a la vida devota. Cuarta parte, cap\u00edtulo 10","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO X C\u00d3MO SE HA DE ROBUSTECER EL CORAZ\u00d3N CONTRA LAS TENTACIONES De vez en cuando, considera qu\u00e9 pasiones son m\u00e1s dominantes en tu alma, y, una vez descubiertas, emprende una manera de vivir que les sea totalmente contraria, en pensamientos, palabras y obras. Por ejemplo, si te sientes inclinada\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":28844,"url":"http:\/\/vincentians.com\/es\/vida-de-san-vicente-de-paul-libro-primero-capitulo-2\/","url_meta":{"origin":34935,"position":3},"title":"Vida de san Vicente de Pa\u00fal: Libro Primero, Cap\u00edtulo 2","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/02\/2020","format":false,"excerpt":"Fue el a\u00f1o 1576, martes despu\u00e9s de Pascua, cuando Vicente de Pa\u00fal naci\u00f3 en la peque\u00f1a aldea de Pouy, cerca de Dax, ciudad episcopal situada en los confines de las Landas de Burdeos, cerca de los Pirineos. Hay en el territorio de esa parroquia una capilla dedicada la Sant\u00edsima Virgen,\u2026","rel":"","context":"En \u00abEscritos de Luis Abelly\u00bb","block_context":{"text":"Escritos de Luis Abelly","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luis-abelly\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/abelly-feat.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":6471,"url":"http:\/\/vincentians.com\/es\/luisa-de-marillac-pensamiento-001-sobre-una-pena-interior\/","url_meta":{"origin":34935,"position":4},"title":"Luisa de Marillac, Pensamiento 001: Sobre una pena interior","author":"Francisco Javier Fern\u00e1ndez Chento","date":"01\/01\/2009","format":false,"excerpt":"(hacia 1621) 1. El d\u00eda de Santo Tom\u00e1s, a lo largo de todo el d\u00eda (tuve) grandes decaimientos de esp\u00edritu por los sentimientos de mi propia abyecci\u00f3n, que me hacen aparecer como una cloaca de orgullo y fuente de amor propio; de desamparo, anonadamiento de m\u00ed misma, abandono de Dios\u2026","rel":"","context":"En \u00abEscritos de Luisa de Marillac\u00bb","block_context":{"text":"Escritos de Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-luisa-de-marillac\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-luisa-de-marillac.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34983,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-35\/","url_meta":{"origin":34935,"position":5},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 35","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/04\/2021","format":false,"excerpt":"CAP\u00cdTULO XXXV QUE ES NECESARIO SER FIEL EN LAS OCASIONES GRANDES Y EN LAS PEQUE\u00d1AS El sagrado Esposo del Cantar de los Cantares dice que la Esposa le ha robado el coraz\u00f3n con uno de sus ojos y con uno de sus cabellos. Ahora bien, de todas las partes exteriores\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=34935"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34935\/revisions"}],"predecessor-version":[{"id":403093,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34935\/revisions\/403093"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=34935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=34935"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=34935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}