{"id":34265,"date":"2020-09-14T08:35:13","date_gmt":"2020-09-14T06:35:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/05\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/"},"modified":"2020-09-02T10:21:06","modified_gmt":"2020-09-02T08:21:06","slug":"introduccion-a-la-vida-devota-segunda-parte-capitulo-18","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18"},"content":{"rendered":"<p><strong>CAP\u00cdTULO XVIII<\/strong><\/p>\n<p><strong>COMO SE HAN DE RECIBIR LAS INSPIRACIONES<\/strong><\/p>\n<p>Entendemos por inspiraciones todos los atractivos, movimientos, reconvenciones y remordimientos interiores, luces y conocimientos que recibimos de Dios, el cual previene nuestro coraz\u00f3n con sus bendiciones, con cuidado y amor paternal, para despertarnos, excitarnos, empujarnos y atraernos a las santas virtudes, al amor celestial, a los buenos prop\u00f3sitos, en una palabra, a todo lo que nos encamina hacia nuestro bien eterno. Es lo que el Esposo entiende por llamar a la puerta y hablar al coraz\u00f3n de la Esposa, despertarla cuando duerme, llamarla y reclamarla cuando est\u00e1 ausente, invitarla a gustar la miel y a coger las manzanas y las flores de su jard\u00edn y a cantar y hacer resonar su dulce voz en sus o\u00eddos.<\/p>\n<p>Para ajustar perfectamente un casamiento, se requieren tres actos de parte de la doncella que quiere casarse: porque, primeramente, se le propone el partido; en segundo lugar acepta la propuesta, y finalmente, consiente. Asimismo, Dios, cuando quiere hacer en nosotros, por nosotros y con nosotros un acto de gran caridad, primero nos lo propone por medio de sus inspiraciones; despu\u00e9s nosotros lo aceptamos, y, por \u00faltimo, consentimos en \u00e9l; porque, as\u00ed como para descender hasta el pecado, hay que pasar por tres grados; la tentaci\u00f3n, la delectaci\u00f3n y el consentimiento, de la misma manera, hay tres para subir hasta la virtud: la inspiraci\u00f3n, que es contraria a la tentaci\u00f3n; la delectaci\u00f3n en la inspiraci\u00f3n, que es contraria al deleite en la tentaci\u00f3n, y el consentimiento en la inspiraci\u00f3n, que es contrario al consentimiento en la tentaci\u00f3n.<\/p>\n<p>Aunque la inspiraci\u00f3n se prolongase durante todo el tiempo de nuestra vida no ser\u00edamos, sin embargo, agradables a Dios, si no nos deleit\u00e1semos en ella; al contrario: su divina Majestad se ofender\u00eda, como se ofendi\u00f3 contra los israelitas, con los cuales, como \u00c9l mismo nos lo dice, estuvo por espacio de cuarenta a\u00f1os exhort\u00e1ndoles a que se convirtiesen, sin que jam\u00e1s hubiesen querido saber nada de ello, por lo que jur\u00f3, en su ira, que no entrar\u00edan en el lugar de su reposo. As\u00ed, el gal\u00e1n que hubiese estado, durante mucho tiempo, haciendo la corte a una doncella, quedar\u00eda despu\u00e9s muy ofendido, si ella no quisiera saber nada del casamiento.<\/p>\n<p>El placer que encontramos en las inspiraciones nos acerca mucho a la gloria de Dios, con lo que ya comenzamos a ser agradables a la divina Majestad, pues, aunque esta complacencia no sea un verdadero consentimiento, es una cierta disposici\u00f3n. Y, si es muy buena se\u00f1al y cosa muy \u00fatil complacerse en o\u00edr la palabra de Dios, que es como una inspiraci\u00f3n interior, es tambi\u00e9n cosa buena y agradable a Dios complacerse en la inspiraci\u00f3n interior; \u00e9sta es aquella complacencia de la cual habla la Esposa, cuando dice: \u00abMi alma se ha derretido de gozo, cuando ha hallado a mi muy amado\u00bb. As\u00ed, el gal\u00e1n est\u00e1 muy contento de la damisela a quien sirve, cuando ve que es correspondido y que ella se complace en su servicio.<\/p>\n<p>Finalmente, es el consentimiento el que perfecciona el acto virtuoso, porque, si estando inspirados y habi\u00e9ndonos complacido en la inspiraci\u00f3n, no obstante negamos a Dios el consentimiento, somos en gran manera desagradecidos y hacemos gran agravio a su divina Majestad, pues entonces parece que es mayor el desprecio. Esto es lo que ocurri\u00f3 a la Esposa, pues, aunque la voz del amado estremeci\u00f3 su coraz\u00f3n de santa alegr\u00eda, no obstante no le abri\u00f3 la puerta, sino que se excus\u00f3 con un fr\u00edvolo pretexto, lo cual dio lugar a que el Esposo se indignase justamente y, pasando de largo, la dejase. As\u00ed el gal\u00e1n, que, despu\u00e9s de haber suspirado mucho por una joven y de haberle prestado agradables servicios, se viese al fin rechazado y despreciado, tendr\u00eda muchos m\u00e1s motivos de disgusto que si su requerimiento no hubiese sido aceptado y correspondido. Resu\u00e9lvete, pues, Filotea, a aceptar con todo el afecto todas las inspiraciones que a Dios pluguiere enviarte, y, cuando las sientas, rec\u00edbelas como mensajeras del Rey celestial, que desea desposarse contigo. Escucha de buen grado sus propuestas; considera el amor con que te las ha inspirado y fomenta la santa inspiraci\u00f3n. Consiente, pero con un consentimiento pleno, amoroso y constante, a la santa inspiraci\u00f3n, porque, de esta manera, Dios, a quien no puedes obligar, se tendr\u00e1 por muy obligado a tu afecto. Pero antes de consentir en las inspiraciones de cosas importantes y extraordinarias, acons\u00e9jate, para no ser enga\u00f1ada, con tu confesor, a fin de que 61 examine si la inspiraci\u00f3n es falsa o verdadera; pues ocurre que el enemigo, cuando ve un alma pronta en dar consentimiento a las inspiraciones, le sugiere, con frecuencia, cosas falsas, para enga\u00f1arla, lo cual nunca podr\u00e1 lograr mientras ella obedezca con humildad al director.<\/p>\n<p>Una vez dado el consentimiento, es menester procurar, con mucha diligencia, llevar a la pr\u00e1ctica y ejecutar la inspiraci\u00f3n, en lo cual consiste la perfecci\u00f3n de la verdadera virtud; porque tener el consentimiento en el coraz\u00f3n sin realizarlo, ser\u00eda lo mismo que plantar una vi\u00f1a sin querer que diese fruto.<\/p>\n<p>Ahora bien, para ello es muy \u00fatil el \u00abejercicio del cristiano\u00bb de la ma\u00f1ana y el retiro espiritual, de que hemos hablado m\u00e1s arriba, pues, de esta manera, nos preparamos para hacer el bien, con una preparaci\u00f3n, no s\u00f3lo general, sino, adem\u00e1s, particular.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO XVIII COMO SE HAN DE RECIBIR LAS INSPIRACIONES Entendemos por inspiraciones todos los atractivos, movimientos, reconvenciones y remordimientos interiores, luces y conocimientos que recibimos de Dios, el cual previene nuestro coraz\u00f3n con sus bendiciones, &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"#ffffff","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-34265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO XVIII COMO SE HAN DE RECIBIR LAS INSPIRACIONES Entendemos por inspiraciones todos los atractivos, movimientos, reconvenciones y remordimientos interiores, luces y conocimientos que recibimos de Dios, el cual previene nuestro coraz\u00f3n con sus bendiciones, ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-14T06:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18\",\"datePublished\":\"2020-09-14T06:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/\"},\"wordCount\":955,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2020-09-14T06:35:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18 - Somos Vicencianos","og_description":"CAP\u00cdTULO XVIII COMO SE HAN DE RECIBIR LAS INSPIRACIONES Entendemos por inspiraciones todos los atractivos, movimientos, reconvenciones y remordimientos interiores, luces y conocimientos que recibimos de Dios, el cual previene nuestro coraz\u00f3n con sus bendiciones, ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2020-09-14T06:35:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18","datePublished":"2020-09-14T06:35:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/"},"wordCount":955,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/","name":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2020-09-14T06:35:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 18"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-8UF","jetpack-related-posts":[{"id":34983,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-35\/","url_meta":{"origin":34265,"position":0},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 35","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/04\/2021","format":false,"excerpt":"CAP\u00cdTULO XXXV QUE ES NECESARIO SER FIEL EN LAS OCASIONES GRANDES Y EN LAS PEQUE\u00d1AS El sagrado Esposo del Cantar de los Cantares dice que la Esposa le ha robado el coraz\u00f3n con uno de sus ojos y con uno de sus cabellos. Ahora bien, de todas las partes exteriores\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":116599,"url":"http:\/\/vincentians.com\/es\/dei-verbum\/","url_meta":{"origin":34265,"position":1},"title":"Dei Verbum","author":"Francisco Javier Fern\u00e1ndez Chento","date":"18\/10\/2018","format":false,"excerpt":"Comentario a \"Dei Verbum\" Autor: Jos\u00e9 Miguel Arr\u00e1iz La Dei Verbum o Constituci\u00f3n dogm\u00e1tica de la divina revelaci\u00f3n es otro de los documentos fundamentales del Concilio Vaticano II. Su valor doctrinal fue objeto de una notificaci\u00f3n el 15 de Noviembre de 1965 que reitera una dada el a\u00f1o anterior el\u2026","rel":"","context":"En \u00abConcilio Vaticano II\u00bb","block_context":{"text":"Concilio Vaticano II","link":"http:\/\/vincentians.com\/es\/category\/formacion-cristiana\/concilios-ecumenicos\/concilio-vaticano-ii\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/sencillos-como-palomas.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34989,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-41\/","url_meta":{"origin":34265,"position":2},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 41","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/06\/2011","format":false,"excerpt":"CAP\u00cdTULO XLI UNA PALABRA A LAS V\u00cdRGENES \u00a1Oh v\u00edrgenes!, si aspir\u00e1is al matrimonio temporal, guardad celosamente vuestro primer amor para vuestro primer marido. Creo que es un gran enga\u00f1o presentar, en lugar de un coraz\u00f3n \u00edntegro y sincero, un coraz\u00f3n gastado, marchito y agitado por el amor. Pero, si por\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34968,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-22\/","url_meta":{"origin":34265,"position":3},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 22","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/01\/2021","format":false,"excerpt":"CAP\u00cdTULO XXII ALGUNAS OTRAS ADVERTENCIAS SOBRE LAS AMISTADES La amistad requiere una gran comunicaci\u00f3n entre los amigos; de lo contrario, no puede nacer ni subsistir. Por esta causa, ocurre que, con la comunicaci\u00f3n propia de la amistad, se deslizan y pasan insensiblemente de coraz\u00f3n a coraz\u00f3n otras comunicaciones, por una\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":130265,"url":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-09\/","url_meta":{"origin":34265,"position":4},"title":"Un perfil heroico: santa Luisa de Marillac (09)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/03\/2015","format":false,"excerpt":"EL Se\u00f1or echar\u00e1 la bendici\u00f3n sobre todas las obras de tus manos. (Deuteronomio, XXVIII.) LOS territorios que primero visit\u00f3 Santa Luisa en sus funcio\u00adnes de caridad fueron los establecidos en los dominios de la casa de Gondi, en Montmirail. En su porte distinguido podr\u00eda adivinarse algo de la belleza delicada\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":34986,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-tercera-parte-capitulo-38\/","url_meta":{"origin":34265,"position":5},"title":"Introducci\u00f3n a la vida devota. Tercera parte, cap\u00edtulo 38","author":"Francisco Javier Fern\u00e1ndez Chento","date":"24\/06\/2011","format":false,"excerpt":"CAP\u00cdTULO XXXVIII AVISO A LAS PERSONAS CASADAS \"El matrimonio es un gran sacramento, lo digo en Jesucristo y en su Iglesia\"; \"es honorable para todos\", en todos y en todo, es decir, en todas sus partes: para todos, porque aun las mismas v\u00edrgenes han de honrarlo con humildad; en todos,\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=34265"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34265\/revisions"}],"predecessor-version":[{"id":403038,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34265\/revisions\/403038"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=34265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=34265"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=34265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}