{"id":34235,"date":"2020-08-12T08:45:13","date_gmt":"2020-08-12T06:45:13","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2011\/05\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/"},"modified":"2020-08-01T09:48:46","modified_gmt":"2020-08-01T07:48:46","slug":"introduccion-a-la-vida-devota-segunda-parte-capitulo-08","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/","title":{"rendered":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08"},"content":{"rendered":"<p><strong>CAP\u00cdTULO VIII<\/strong><\/p>\n<p><strong>ALGUNOS AVISOS \u00daTILES SOBRE LA MEDITACI\u00d3N<\/strong><\/p>\n<p>Conviene, sobre todo, F\u00edlotea, que, al salir de la meditaci\u00f3n conserves las resoluciones y los prop\u00f3sitos que hubieres hecho para practicarlos con diligencia durante el d\u00eda. Este es el gran fruto de la meditaci\u00f3n, sin el cual, \u00e9sta es, con frecuencia, no s\u00f3lo in\u00fatil sino perjudicial, porque las virtudes meditadas y no practicadas hinchan y envalentonan el esp\u00edritu, pues nos hacen creer que somos en realidad, lo que hemos resuelto ser, lo cual es, ciertamente, verdad cuando las resoluciones son vivas y s\u00f3lidas; pero no lo son, sino que, al contrario, son vanas y peligrosas, cuando no se practican. Conviene, pues, por todos los medios, esforzarse en practicarlas y buscar las ocasiones de ello, grandes o peque\u00f1as. Por ejemplo, si he resuelto ganar con la dulzura a los que me han ofendido, procurar\u00e9, durante el d\u00eda, encontrarlos, para saludarlos con amabilidad, y, si no puedo encontrarlos, hablar\u00e9 bien de ellos y los encomendar\u00e9 a Dios.<\/p>\n<p>Al salir de esta oraci\u00f3n afectiva, has de tener cuidado de no sacudir tu coraz\u00f3n, para que no derrame el b\u00e1lsamo que la oraci\u00f3n ha vertido en \u00e9l; quiero decir que hay que guardar, por espacio de alg\u00fan tiempo, el silencio y transportar suavemente el coraz\u00f3n, de la oraci\u00f3n a las ocupaciones, conservando, todo el tiempo que sea posible, el sentimiento y los afectos concebidos. El hombre que recibe en un recipiente de hermosa porcelana un licor de mucho precio, para llevarlo a su casa, anda con mucho tiento, sin mirar a los lados, sino que ora mira enfrente, para no tropezar contra alguna piedra, ora el recipiente, para evitar que se derrame. Lo mismo has de hacer t\u00fa, al salir de la meditaci\u00f3n: no te distraigas enseguida, sino mira sencillamente delante de ti, pero, si encuentras alguno, con el cual hayas de hablar o al que hayas de escuchar, hazlo, pues no queda otro remedio, pero de manera que tengas siempre la mirada puesta en tu coraz\u00f3n, para que el licor de la santa oraci\u00f3n no se derrame m\u00e1s de lo que sea imprescindible.<\/p>\n<p>Tambi\u00e9n conviene que te acostumbres a saber pasar de la oraci\u00f3n a toda clase de acciones, que tu oficio o profesi\u00f3n, justa y leg\u00edtimamente, requieran, por m\u00e1s que parezcan muy ajenas a los afectos que hemos concebido en la oraci\u00f3n. Por ejemplo: un abogado ha de saber pasar de la oraci\u00f3n a los pleitos; un comerciante, al tr\u00e1fico; la mujer casada, a las obligaciones de su estado y a las ocupaciones del hogar, con tanta dulzura y tranquilidad, que no, por ello, se turbe su esp\u00edritu, pues ambas cosas son seg\u00fan la voluntad de Dios y en ambas hay que pensar con esp\u00edritu de humildad y devoci\u00f3n.<\/p>\n<p>Te ocurrir\u00e1, alguna vez, que, inmediatamente despu\u00e9s de la preparaci\u00f3n, tu afecto se sentir\u00e1 en seguida movido hacia Dios. Entonces, Filotea, conviene darle rienda suelta, sin empe\u00f1arte en querer seguir el m\u00e9todo que te he dado; porque, si bien, por lo regular, la consideraci\u00f3n ha de preceder a los afectos y a las resoluciones, cuando, empero, el Esp\u00edritu Santo te da los afectos antes de la consideraci\u00f3n, no has de detenerte en \u00e9sta quieras o no, pues su fin no es otro que mover los afectos. En una palabra, siempre que se despierten en ti los afectos, debes admitirlos y hacerles lugar, ya sea antes ya despu\u00e9s de todas las consideraciones. Y, aunque yo he puesto los afectos despu\u00e9s de todas las consideraciones, lo he hecho \u00fanicamente para distinguir bien las diferentes partes de la oraci\u00f3n; por otra parte, es una regla general que nunca hay que cohibir los afectos, sino que es menester dejar que se expansionen los que se presentan. Digo esto no s\u00f3lo con respecto a los dem\u00e1s afectos, sino tambi\u00e9n con respecto a la acci\u00f3n de gracias, al ofrecimiento ya la plegaria, que pueden hacerse entre las consideraciones, y que no se han de contener m\u00e1s que los otros afectos, si bien, despu\u00e9s, al terminar la meditaci\u00f3n, conviene repetirlos y continuarlos. Pero, en cuanto a las resoluciones es menester hacerlas despu\u00e9s de los afectos y al fin de toda la meditaci\u00f3n, antes de la conclusi\u00f3n, pues, como quiera que las resoluciones traen a nuestra imaginaci\u00f3n objetos concretos y de orden familiar, nos pondr\u00edan en el peligro de distraernos, si se hiciesen en medio de los afectos.<\/p>\n<p>Entre los afectos y las resoluciones, es bueno emplear el coloquio, y hablar ora a Dios, ora a los \u00e1ngeles, ora a las personas que aparecen en los misterios, a los santos y a s\u00ed mismo, al propio coraz\u00f3n, a los pecadores, como vemos que lo hizo David en los Salmos, y otros santos, en sus meditaciones y oraciones.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAP\u00cdTULO VIII ALGUNOS AVISOS \u00daTILES SOBRE LA MEDITACI\u00d3N Conviene, sobre todo, F\u00edlotea, que, al salir de la meditaci\u00f3n conserves las resoluciones y los prop\u00f3sitos que hubieres hecho para practicarlos con diligencia durante el d\u00eda. Este &#8230; <a href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":398698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"#ffffff","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[272],"tags":[],"class_list":["post-34235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-francisco-de-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"CAP\u00cdTULO VIII ALGUNOS AVISOS \u00daTILES SOBRE LA MEDITACI\u00d3N Conviene, sobre todo, F\u00edlotea, que, al salir de la meditaci\u00f3n conserves las resoluciones y los prop\u00f3sitos que hubieres hecho para practicarlos con diligencia durante el d\u00eda. Este ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T06:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08\",\"datePublished\":\"2020-08-12T06:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"articleSection\":[\"Escritos de Francisco de Sales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/\",\"name\":\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"datePublished\":\"2020-08-12T06:45:13+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/08\\\/escritos-francisco-de-sales.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/","og_locale":"es_ES","og_type":"article","og_title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08 - Somos Vicencianos","og_description":"CAP\u00cdTULO VIII ALGUNOS AVISOS \u00daTILES SOBRE LA MEDITACI\u00d3N Conviene, sobre todo, F\u00edlotea, que, al salir de la meditaci\u00f3n conserves las resoluciones y los prop\u00f3sitos que hubieres hecho para practicarlos con diligencia durante el d\u00eda. Este ... Read More","og_url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2020-08-12T06:45:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08","datePublished":"2020-08-12T06:45:13+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","articleSection":["Escritos de Francisco de Sales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/","url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/","name":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","datePublished":"2020-08-12T06:45:13+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 08"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-8Ub","jetpack-related-posts":[{"id":34232,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-07\/","url_meta":{"origin":34235,"position":0},"title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 07","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/08\/2020","format":false,"excerpt":"CAP\u00cdTULO VII DE LA CONCLUSI\u00d3N Y RAMILLETE ESPIRITUAL Finalmente, la meditaci\u00f3n se ha de acabar con tres cosas, que se han de hacer con toda la humildad posible. La primera es la acci\u00f3n de gracias a Dios por los afectos y prop\u00f3sitos que nos ha inspirado, y por su bondad\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35071,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-quinta-parte-capitulo-16\/","url_meta":{"origin":34235,"position":1},"title":"Introducci\u00f3n a la vida devota. Quinta parte, cap\u00edtulo 16","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO XVI DE LOS SENTIMIENTOS QUE ES MENESTER CONSERVAR DESPU\u00c9S DE ESTE EJERCICIO Este d\u00eda, en que habr\u00e1s hecho esta renovaci\u00f3n, y los d\u00edas siguientes, has de repetir con frecuencia, con el coraz\u00f3n y con la boca, estas ardientes palabras de San Pablo, de San Agust\u00edn, de Santa Catalina de\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34214,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-01\/","url_meta":{"origin":34235,"position":2},"title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 01","author":"Francisco Javier Fern\u00e1ndez Chento","date":"19\/07\/2020","format":false,"excerpt":"Introducci\u00f3n a la vida devota (Segunda parte) SEGUNDA PARTE DE LA INTRODUCCI\u00d3N Diferentes avisos para elevaci\u00f3n del alma a Dios, mediante la oraci\u00f3n y los sacramentos CAPITULO I DE LA NECESIDAD DE LA ORACI\u00d3N 1. La oraci\u00f3n al llevar nuestro entendimiento hacia las claridades de la luz divina y al\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":35072,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-quinta-parte-capitulo-17\/","url_meta":{"origin":34235,"position":3},"title":"Introducci\u00f3n a la vida devota. Quinta parte, cap\u00edtulo 17","author":"Francisco Javier Fern\u00e1ndez Chento","date":"29\/07\/2011","format":false,"excerpt":"CAP\u00cdTULO XVII RESPUESTA A DOS OBJECIONES QUE PUEDEN HACERSE ACERCA DE ESTA \"INTRODUCCI\u00d3N\" Filotea, el mundo te dir\u00e1 que estos ejercicios y estas advertencias son tan numerosos, que el que quiera observarlos no podr\u00e1 hacer otra cosa. \u00a1Ah, amada Filotea!, aunque no hici\u00e9semos otra cosa, mucho har\u00edamos, pues har\u00edamos lo\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":34226,"url":"http:\/\/vincentians.com\/es\/introduccion-a-la-vida-devota-segunda-parte-capitulo-05\/","url_meta":{"origin":34235,"position":4},"title":"Introducci\u00f3n a la vida devota. Segunda parte, cap\u00edtulo 05","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/08\/2020","format":false,"excerpt":"CAPITULO V DE LAS CONSIDERACIONES, SEGUNDA PARTE DE LA MEDITACI\u00d3N Despu\u00e9s. del acto de la imaginaci\u00f3n, sigue el acto del entendimiento, que llamamos meditaci\u00f3n, la cual no es otra cosa que una o varias consideraciones hechas con el fin de mover los afectos hacia Dios y las cosas divinas: y,\u2026","rel":"","context":"En \u00abEscritos de Francisco de Sales\u00bb","block_context":{"text":"Escritos de Francisco de Sales","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-francisco-de-sales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/escritos-francisco-de-sales.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":55102,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-maestro-de-oracion-01\/","url_meta":{"origin":34235,"position":5},"title":"San Vicente de Pa\u00fal, maestro de oraci\u00f3n (01)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"15\/06\/2015","format":false,"excerpt":"Presentaci\u00f3n Paris, 7 octubre 1928 MI QUERIDO PADRE, Escribiendo el 8 de abril de 1933 al Sr Coste, sacerdote de la Misi\u00f3n, editor de las conferencias de san Vicente, se ha de saber\u00a0: las conferencias a los misioneros y a las Hijas de la Caridad, las repeticiones de oraci\u00f3n, los\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"vincent Croatia Zagreb 2","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2015\/06\/vincent-Croatia-Zagreb-2-300x208.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=34235"}],"version-history":[{"count":1,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34235\/revisions"}],"predecessor-version":[{"id":402993,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/34235\/revisions\/402993"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/398698"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=34235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=34235"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=34235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}